{"id":279065,"date":"2025-05-13T11:41:58","date_gmt":"2025-05-13T09:41:58","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=279065"},"modified":"2025-05-22T10:34:47","modified_gmt":"2025-05-22T08:34:47","slug":"grande-guerre-chine-etats-unis-2","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/","title":{"rendered":"Des terres rares au fentanyl&#160;: vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie)"},"content":{"rendered":"\n<p><em><a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/23\/grande-guerre-chine-etats-unis-1\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lire l&rsquo;\u00e9pisode 1<\/a><\/em><\/p>\n\n\n\n<p class=\"non-subscribers-only\"><em>[bloc conditionn\u00e9] Cet article est le deuxi\u00e8me \u00e9pisode d\u2019<\/em><a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/23\/grande-guerre-chine-etats-unis-1\/\"><em>une vaste enqu\u00eate sur les formes que pourrait prendre un affrontement total et multidimensionnel entre la guerre entre la R\u00e9publique populaire de Chine et les \u00c9tats-Unis d\u2019Am\u00e9rique<\/em><\/a><em>. Pour recevoir en exclusivit\u00e9 le troisi\u00e8me, <\/em><a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc-x\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>pensez \u00e0 vous abonner au Grand Continent<\/em><\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">La \u00ab&#160;guerre commerciale&#160;\u00bb, c\u2019est la guerre<\/h4>\n\n\n\n<p>En avril 2025, un tournant brutal s\u2019op\u00e8re dans la politique commerciale et s\u00e9curitaire des \u00c9tats-Unis&#160;: l\u2019administration Trump annonce une hausse spectaculaire de 145&#160;% des droits de douane sur les importations chinoises&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-1-279065' title='Maggie Bannerman, Eric Shmitt et Hamed Aleaziz, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.nytimes.com\/2025\/04\/11\/us\/politics\/trump-military-border.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Trump directive calls for turning border strip into \u201cmilitary installation\u201d&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The New York Times&lt;\/em&gt;, 11 avril 2025.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Cette d\u00e9cision marque bien plus qu\u2019un simple durcissement \u00e9conomique. Elle s\u2019inscrit dans <a href=\"https:\/\/legrandcontinent.eu\/fr\/trump-et-la-guerre-commerciale-x\/\">un vaste retour du protectionnisme, \u00e9tendu au Canada et au Mexique<\/a>, et doubl\u00e9 d\u2019une offensive s\u00e9curitaire in\u00e9dite.<\/p>\n\n\n\n<p>Les fronti\u00e8res am\u00e9ricaines ne sont plus seulement des lignes \u00e0 d\u00e9fendre, mais des fronts actifs&#160;: d\u00e9ploiement des forces de s\u00e9curit\u00e9, militarisation des points de passage, traque des flux migratoires et des trafics illicites. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/23\/grande-guerre-chine-etats-unis-1\/\">\u00c0 l\u2019arri\u00e8re-plan, l\u2019intelligence artificielle devient un outil strat\u00e9gique<\/a>. Des entreprises comme Palantir, en partenariat avec l\u2019agence Immigration and Customs Enforcement (ICE), mettent leur technologie au service de cette nouvelle doctrine de contr\u00f4le, m\u00ealant surveillance algorithmique et automatisation du tri humain&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-2-279065' title='Alayna Alvarez, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.axios.com\/local\/denver\/2025\/05\/01\/palantir-deportations-ice-immigration-trump&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Palantir\u2019s partnership with ICE deepens&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Axios&lt;\/em&gt;, 1 mai 2025.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Le territoire se ferme \u2014 et tout un syst\u00e8me technique et politique s\u2019active pour en verrouiller les acc\u00e8s.<\/p>\n\n\n\n<p>La riposte de P\u00e9kin ne se fait pas attendre.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La rivalit\u00e9 sino-am\u00e9ricaine n\u2019est plus seulement commerciale ou diplomatique&#160;: elle devient militaire, distribu\u00e9e, technologique.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Face aux sanctions am\u00e9ricaines, la Chine annonce une surtaxe de 125&#160;% sur les produits am\u00e9ricains, mais surtout un coup strat\u00e9gique majeur \u2014 le blocage des exportations de terres rares vers les \u00c9tats-Unis. Or ces ressources, discr\u00e8tes mais d\u00e9cisives, sont le carburant silencieux de l\u2019innovation num\u00e9rique et de l\u2019intelligence artificielle.<\/p>\n\n\n\n<p>Sans elles, pas de semi-conducteurs avanc\u00e9s, pas de batteries performantes, pas d\u2019IA de pointe.<\/p>\n\n\n\n<p>Cette mesure met en p\u00e9ril le c\u0153ur m\u00eame de l\u2019\u00e9cosyst\u00e8me technologique am\u00e9ricain, dont la supr\u00e9matie scientifique, militaire et \u00e9conomique repose d\u00e9sormais largement sur la ma\u00eetrise de ces technologies&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-3-279065' title='Jean-Michel Valantin, &lt;a href=&quot;https:\/\/www.nouveau-monde.net\/catalogue\/hyperguerre\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;Hyperguerre. Comment l\u2019IA r\u00e9volutionne la Guerre&lt;\/em&gt;&lt;\/a&gt;, Paris, \u00c9ditions Nouveau Monde, 2024.'><sup>3<\/sup><\/a><\/span><\/span>. Plus encore, l\u2019intelligence artificielle n\u2019est plus seulement un outil&#160;: <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/07\/lia-aux-racines-de-la-guerre\/\">elle est devenue un vecteur d\u2019influence mondiale, une arme douce d\u2019expansion strat\u00e9gique<\/a>.<\/p>\n\n\n\n<p>\u00c0 Washington, les g\u00e9ants du num\u00e9rique si\u00e8gent d\u00e9sormais au plus pr\u00e8s du pouvoir ex\u00e9cutif, r\u00e9v\u00e9lant \u00e0 quel point les int\u00e9r\u00eats industriels et g\u00e9opolitiques de l\u2019IA sont d\u00e9sormais \u00e9troitement entrem\u00eal\u00e9s&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-4-279065' title='Jean-Michel Valantin, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/redanalysis.org\/2025\/01\/20\/trump-geopolitics-ai-power-president\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Trump Geopolitics \u2013 Trump as the AI Power President&amp;#160;\u00bb&lt;\/a&gt;, &lt;em&gt;The Red Team Analysis Society&lt;\/em&gt;, 20 janvier 2025.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/o8dyn\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Le tournant militaire de l\u2019IA repr\u00e9sente un virage strat\u00e9gique majeur dans la doctrine am\u00e9ricaine.<\/p>\n\n\n\n<p>Non seulement il red\u00e9finit en profondeur les capacit\u00e9s op\u00e9rationnelles de l\u2019arm\u00e9e, mais il l\u2019inscrit de mani\u00e8re frontale dans une nouvelle course aux armements avec la Chine.&nbsp;<\/p>\n\n\n\n<p>Ce n\u2019est plus une simple comp\u00e9tition technologique mais un affrontement syst\u00e9mique o\u00f9 les algorithmes deviennent des armes, et o\u00f9 les lignes de code s\u2019\u00e9crivent dans les logiques de guerre.<\/p>\n\n\n\n<p>Dans ce contexte, les fronti\u00e8res entre le secteur public de la d\u00e9fense et les entreprises de l\u2019IA ou du spatial s\u2019estompent.<\/p>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/02\/03\/techno-droite-et-securite-imperiale-aux-racines-du-lebensraum-algorithmique-dans-lamerique-de-trump\/\">Les partenariats se multiplient, les interd\u00e9pendances se renforcent, les int\u00e9r\u00eats convergent<\/a>.&nbsp;<\/p>\n\n\n\n<p>\u00c0 cela s\u2019ajoute un contexte de plus en plus dangereux&#160;: sur plusieurs th\u00e9\u00e2tres d\u2019op\u00e9rations plan\u00e9taires, les forces am\u00e9ricaines se trouvent confront\u00e9es, directement ou indirectement, \u00e0 des adversaires soutenus \u2014 souvent discr\u00e8tement mais efficacement \u2014 par P\u00e9kin. La rivalit\u00e9 sino-am\u00e9ricaine n\u2019est plus seulement commerciale ou diplomatique&#160;: elle devient militaire, distribu\u00e9e, technologique.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000012-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000012-scaled.jpg\" alt=\"\u00abLes fronti\u00e8res am\u00e9ricaines ne sont plus seulement des lignes \u00e0 d\u00e9fendre, mais des fronts actifs : d\u00e9ploiement des forces de s\u00e9curit\u00e9, militarisation des points de passage, traque des flux migratoires et des trafics illicites. \u00c0 l\u2019arri\u00e8re-plan, l\u2019intelligence artificielle devient un outil strat\u00e9gique.\u00bb\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;Les fronti\u00e8res am\u00e9ricaines ne sont plus seulement des lignes \u00e0 d\u00e9fendre, mais des fronts actifs&#160;: d\u00e9ploiement des forces de s\u00e9curit\u00e9, militarisation des points de passage, traque des flux migratoires et des trafics illicites. \u00c0 l\u2019arri\u00e8re-plan, l\u2019intelligence artificielle devient un outil strat\u00e9gique.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22935800_000001-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22935800_000001-scaled.jpg\" alt=\"\u00abC\u00f4t\u00e9 mexicain, plus de 10 000 soldats d\u00e9ploy\u00e9s contre les narcotrafiquants, en coordination avec les agences am\u00e9ricaines. Cet engagement sert aussi d\u2019argument dans les n\u00e9gociations visant \u00e0 all\u00e9ger les surtaxes douani\u00e8res. Entre f\u00e9vrier et avril 2025, le Mexique annonce l\u2019arrestation de plus de 6 000 personnes li\u00e9es au narcotrafic.\u00bb\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;C\u00f4t\u00e9 mexicain, plus de 10 000 soldats d\u00e9ploy\u00e9s contre les narcotrafiquants, en coordination avec les agences am\u00e9ricaines. Cet engagement sert aussi d\u2019argument dans les n\u00e9gociations visant \u00e0 all\u00e9ger les surtaxes douani\u00e8res. Entre f\u00e9vrier et avril 2025, le Mexique annonce l\u2019arrestation de plus de 6 000 personnes li\u00e9es au narcotrafic.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>\u00ab&#160;Les fronti\u00e8res am\u00e9ricaines ne sont plus seulement des lignes \u00e0 d\u00e9fendre, mais des fronts actifs&#160;: d\u00e9ploiement des forces de s\u00e9curit\u00e9, militarisation des points de passage, traque des flux migratoires et des trafics illicites. \u00c0 l\u2019arri\u00e8re-plan, l\u2019intelligence artificielle devient un outil strat\u00e9gique.&#160;\u00bb<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>\u00ab&#160;C\u00f4t\u00e9 mexicain, plus de 10 000 soldats d\u00e9ploy\u00e9s contre les narcotrafiquants, en coordination avec les agences am\u00e9ricaines. Cet engagement sert aussi d\u2019argument dans les n\u00e9gociations visant \u00e0 all\u00e9ger les surtaxes douani\u00e8res. Entre f\u00e9vrier et avril 2025, le Mexique annonce l\u2019arrestation de plus de 6 000 personnes li\u00e9es au narcotrafic.&#160;\u00bb<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\">L\u2019essor du n\u00e9o-mercantilisme am\u00e9ricain<\/h4>\n\n\n\n<p>L\u2019administration Trump affirme ainsi sa singularit\u00e9 en orchestrant une mobilisation simultan\u00e9e \u2014 mais surtout int\u00e9gr\u00e9e \u2014 des leviers commercial, s\u00e9curitaire et militaire.&nbsp;<\/p>\n\n\n\n<p>Ce qui distingue cette nouvelle doctrine n\u2019est pas tant l\u2019usage d\u2019instruments d\u00e9j\u00e0 \u00e9prouv\u00e9s par le pass\u00e9 que leur fusion strat\u00e9gique dans une architecture coh\u00e9rente&#160;: une grande strat\u00e9gie au sens plein du terme.<\/p>\n\n\n\n<p>Comme l\u2019avait bien montr\u00e9 Klaus Dodds dans ces pages, le politique, l\u2019\u00e9conomique, le militaire, le technologique et m\u00eame le culturel ne sont plus des sph\u00e8res s\u00e9par\u00e9es, mais <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/03\/trump-et-la-terre-matrice-geopolitique-dune-presidence-imperiale\/\">des vecteurs interd\u00e9pendants d\u2019une m\u00eame ambition&#160;: s\u00e9curiser l\u2019acc\u00e8s aux ressources critiques et aux march\u00e9s clefs<\/a>, dans un monde structur\u00e9 par la rivalit\u00e9 avec la Chine.<\/p>\n\n\n\n<p>Cette intrication s\u2019incarne particuli\u00e8rement dans l\u2019industrie de l\u2019IA, devenue \u00e0 la fois enjeu de puissance, outil diplomatique et bras arm\u00e9 du <em>soft power<\/em>, mais elle se manifeste \u00e9galement dans la transformation des relations entre les acteurs priv\u00e9s et l\u2019\u00c9tat f\u00e9d\u00e9ral&#160;: de simples prestataires, certaines entreprises technologiques se muent en extensions quasi-souveraines de la puissance publique.<\/p>\n\n\n\n<p>V\u00e9ritables compagnies priv\u00e9es pour l\u2019\u00c9tat&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-5-279065' title='Arnaud Orain, &lt;a href=&quot;https:\/\/editions.flammarion.com\/le-monde-confisque\/9782080466570&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;Le Monde confisqu\u00e9. Essai sur le capitalisme de la finitude&lt;\/em&gt;&lt;\/a&gt;, Paris, Flammarion, 2025.'><sup>5<\/sup><\/a><\/span><\/span>, sortes de nouvelles Compagnies des Indes, elles op\u00e8rent d\u00e9sormais dans le champ r\u00e9galien, brouillant les fronti\u00e8res entre initiative priv\u00e9e et imp\u00e9ratif national.<\/p>\n\n\n\n<p>En d\u2019autres termes, la promotion et la protection de la mondialisation centr\u00e9e sur les \u00c9tats-Unis est en train de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/20\/mercantilisme-et-capitalisme-de-la-finitude-aux-origines-de-lempire-trump\/\">c\u00e9der la place \u00e0 une grande strat\u00e9gie que nous qualifions ici de n\u00e9o-mercantilisme<\/a>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-6-279065' title='Jean-Michel Valantin, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/redanalysis.org\/2018\/11\/12\/militarizing-the-warming-arctic-the-race-to-neo-mercantilisms\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Militarizing the Warming Arctic \u2013 The Road to Neo-Mercantilism(s)&lt;\/a&gt;&amp;#160;\u00bb,&amp;nbsp;&lt;em&gt;The Red Team Analysis Society&lt;\/em&gt;, 12 novembre 2018.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">La Chine, adversaire et comp\u00e9titeur strat\u00e9gique de l\u2019administration Trump<\/h4>\n\n\n\n<p>Le recours au concept de mercantilisme s\u2019impose ici naturellement tant la coercition \u2014 commerciale, politique, strat\u00e9gique \u2014 est mobilis\u00e9e de mani\u00e8re explicite et syst\u00e9matique dans les strat\u00e9gies d\u2019acc\u00e8s aux march\u00e9s et aux ressources. Ce n\u00e9o-mercantilisme am\u00e9ricain, profond\u00e9ment teint\u00e9 de protectionnisme, s\u2019ancre dans une logique de puissance assum\u00e9e, o\u00f9 la pression \u00e9conomique devient un outil central de la politique ext\u00e9rieure. Partout, la Chine s\u2019impose comme l\u2019horizon structurant de cette doctrine&#160;: sa pr\u00e9sence est constante dans les discours, les justifications et les m\u00e9canismes de formalisation de cette strat\u00e9gie \u00e9conomique militaris\u00e9e.<\/p>\n\n\n\n<p>R\u00e9ciproquement, apr\u00e8s une phase d\u2019escalade entre avril et mai 2025, les deux puissances s\u2019engagent dans une s\u00e9quence de n\u00e9gociations qui d\u00e9bouchent sur un premier compromis&#160;: les tarifs douaniers am\u00e9ricains doivent \u00eatre abaiss\u00e9s, temporairement, de 145&#160;% \u00e0 30&#160;%, tandis que les droits chinois passent de 125&#160;% \u00e0 10&#160;%.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00c0 Moscou le 9 mai, le message est clair&#160;: la Chine et la Russie s\u2019affichent d\u00e9sormais comme une <em>co-puissance<\/em>.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Mais cette d\u00e9sescalade tarifaire ne doit pas masquer la r\u00e9alit\u00e9 plus profonde&#160;: la tension g\u00e9opolitique ne faiblit pas.<\/p>\n\n\n\n<p>Elle se prolonge, se transforme, se d\u00e9place.<\/p>\n\n\n\n<p>De plus en plus, elle s\u2019incarne dans des affrontements indirects, hybrides, dissimul\u00e9s dans les marges des conflits r\u00e9gionaux, o\u00f9 les deux g\u00e9ants s\u2019opposent par acteurs interpos\u00e9s.<\/p>\n\n\n\n<p>L\u2019affrontement sino-am\u00e9ricain, bien que de basse intensit\u00e9, tend ainsi \u00e0 devenir une forme de guerre prolong\u00e9e \u2014 implacable, diffuse, structurelle.<\/p>\n\n\n\n<p>Le 9 mai 2025, \u00e0 l\u2019occasion du d\u00e9fil\u00e9 militaire c\u00e9l\u00e9brant les 80 ans de la fin de la Seconde Guerre mondiale, un signal g\u00e9opolitique puissant est envoy\u00e9 depuis Moscou. Aux c\u00f4t\u00e9s de Vladimir Poutine, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/09\/geopolitique-du-9-mai-les-prises-de-parole-des-dirigeants-invites-au-defile-de-poutine\/\">Xi Jinping tr\u00f4ne au premier rang, entour\u00e9 d\u2019une vingtaine de chefs d\u2019\u00c9tat, de gouvernement et de hauts repr\u00e9sentants internationaux<\/a>. Sur la place Rouge, les images parlent d\u2019elles-m\u00eames&#160;: des unit\u00e9s chinoises et russes d\u00e9filent ensemble, des syst\u00e8mes d\u2019armes russes exhibent fi\u00e8rement des composants chinois. Ce n\u2019est pas un simple exercice de protocole militaire \u2014 c\u2019est une d\u00e9monstration de force symbolique, une chor\u00e9graphie de l\u2019alliance. Le message est clair&#160;: la Chine et la Russie s\u2019affichent d\u00e9sormais comme une <em>co-puissance<\/em>, soud\u00e9e par un partenariat strat\u00e9gique de plus en plus \u00e9troit.<\/p>\n\n\n\n<p>Dans ce contexte, la tribune de Xi Jinping, publi\u00e9e le 7 mai, prend tout son sens. En exprimant la reconnaissance de P\u00e9kin pour le soutien de Moscou \u00e0 sa politique d\u2019\u00ab&#160;unit\u00e9 territoriale&#160;\u00bb, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/07\/dans-une-tribune-publiee-en-russe-xi-jinping-affirme-avoir-le-soutien-total-de-vladimir-poutine-pour-annexer-taiwan-traduction-inedite\/\">le pr\u00e9sident chinois formule une allusion claire \u00e0 la r\u00e9int\u00e9gration de Ta\u00efwan dans le giron de la R\u00e9publique populaire de Chine<\/a>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/o46Th\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Mais derri\u00e8re les gestes diplomatiques et les symboles militaires, une autre r\u00e9alit\u00e9 se dessine&#160;: celle d\u2019un potentiel d\u2019escalade, r\u00e9el, palpable, d\u00e9j\u00e0 en cours. La mont\u00e9e aux extr\u00eames n\u2019est plus une hypoth\u00e8se th\u00e9orique&#160;; elle s\u2019insinue dans les dynamiques d\u2019alliances, dans les conflits p\u00e9riph\u00e9riques, dans la reconfiguration des \u00e9quilibres mondiaux.<\/p>\n\n\n\n<p>C\u2019est dans ce climat tendu, o\u00f9 les lignes de fracture se cristallisent, que s\u2019inscrit <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/23\/grande-guerre-chine-etats-unis-1\/\">ce nouvel article de notre s\u00e9rie consacr\u00e9e \u00e0 la guerre \u00e0 venir entre les \u00c9tats-Unis et la Chine<\/a>.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000013-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1703\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000013-scaled.jpg\" alt=\"\u00abProtectionnisme \u00e9conomique et s\u00e9curisation territoriale forment les deux faces d\u2019une m\u00eame strat\u00e9gie : r\u00e9ancrer la puissance am\u00e9ricaine dans ses fondations nationales, mat\u00e9rielles et symboliques.\u00bb\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;Protectionnisme \u00e9conomique et s\u00e9curisation territoriale forment les deux faces d\u2019une m\u00eame strat\u00e9gie&#160;: r\u00e9ancrer la puissance am\u00e9ricaine dans ses fondations nationales, mat\u00e9rielles et symboliques.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000004-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000004-scaled.jpg\" alt=\"\u00abLa mont\u00e9e aux extr\u00eames n\u2019est plus une hypoth\u00e8se th\u00e9orique ; elle s\u2019insinue dans les dynamiques d\u2019alliances, dans les conflits p\u00e9riph\u00e9riques, dans la reconfiguration des \u00e9quilibres mondiaux.\u00bb\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;La mont\u00e9e aux extr\u00eames n\u2019est plus une hypoth\u00e8se th\u00e9orique&#160;; elle s\u2019insinue dans les dynamiques d\u2019alliances, dans les conflits p\u00e9riph\u00e9riques, dans la reconfiguration des \u00e9quilibres mondiaux.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>\u00ab&#160;Protectionnisme \u00e9conomique et s\u00e9curisation territoriale forment les deux faces d\u2019une m\u00eame strat\u00e9gie&#160;: r\u00e9ancrer la puissance am\u00e9ricaine dans ses fondations nationales, mat\u00e9rielles et symboliques.&#160;\u00bb<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>\u00ab&#160;La mont\u00e9e aux extr\u00eames n\u2019est plus une hypoth\u00e8se th\u00e9orique&#160;; elle s\u2019insinue dans les dynamiques d\u2019alliances, dans les conflits p\u00e9riph\u00e9riques, dans la reconfiguration des \u00e9quilibres mondiaux.&#160;\u00bb<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>Nous analyserons d\u2019abord en quoi la guerre commerciale d\u00e9clench\u00e9e par Washington constitue l\u2019acte fondateur d\u2019un n\u00e9o-mercantilisme assum\u00e9.<\/p>\n\n\n\n<p>Puis, nous verrons comment l\u2019IA devient l\u2019un de ses piliers essentiels.<\/p>\n\n\n\n<p>Enfin, nous \u00e9tudierons comment ce n\u00e9o-mercantilisme cherche \u00e0 s\u2019\u00e9tendre au Groenland et \u00e0 l\u2019Ukraine \u2014 deux territoires riches en ressources strat\u00e9giques, au c\u0153ur de la comp\u00e9tition technologique mondiale avec la Chine.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Au-del\u00e0 de l\u2019affrontement tarifaire, l\u2019administration am\u00e9ricaine engage ici bien plus qu\u2019un simple bras de fer commercial&#160;: elle r\u00e9active le r\u00f4le de la fronti\u00e8re comme outil central de souverainet\u00e9.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La guerre commerciale et la strat\u00e9gie du verrouillage territorial&#160;: formes du n\u00e9o-mercantilisme am\u00e9ricain<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><em>Make Mercantilism Great Again<\/em>&#160;: faire de la politique avec les fronti\u00e8res<\/h4>\n\n\n\n<p>Depuis le 4 avril 2025, la guerre commerciale ouverte entre Washington et P\u00e9kin expose au grand jour une reconfiguration profonde de l\u2019ordre mondial.<\/p>\n\n\n\n<p>Cette rupture brutale avec les principes du libre-\u00e9change \u2014 piliers de la mondialisation depuis les ann\u00e9es 1980&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-7-279065' title='Jean-Michel Valantin, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/redanalysis.org\/2025\/05\/05\/trump-china-geoeconomic-war\/?utm_source=mailpoet&amp;amp;utm_medium=email&amp;amp;utm_source_platform=mailpoet&amp;amp;utm_campaign=the-red-team-analysis-society-newsletter-post-title_6&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Trump Geopolitics (2) \u2013 The US vs China geoeconomic War&amp;#160;\u00bb&lt;\/a&gt;, &lt;em&gt;The Red Team Analysis Society&lt;\/em&gt;, 5 mai 2025 et Benjamin B\u00fcrbaumer, &lt;a href=&quot;https:\/\/www.editionsladecouverte.fr\/chine_etats_unis_le_capitalisme_contre_la_mondialisation-9782348078347&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;Chine\/\u00c9tats-Unis, le capitalisme contre la mondialisation&lt;\/em&gt;&lt;\/a&gt;, Paris, La D\u00e9couverte, 2024.'><sup>7<\/sup><\/a><\/span><\/span> \u2014 marque le retour en force de pratiques n\u00e9o-mercantilistes.<\/p>\n\n\n\n<p>L\u2019administration Trump incarne ce virage en concentrant un ensemble de mesures visant \u00e0 garantir l\u2019acc\u00e8s des entreprises et de l\u2019\u00c9tat am\u00e9ricains aux ressources et aux march\u00e9s jug\u00e9s strat\u00e9giques. Ces objectifs sont d\u00e9sormais poursuivis non plus par la n\u00e9gociation multilat\u00e9rale, mais par des moyens coercitifs, assum\u00e9s et revendiqu\u00e9s.&nbsp;<\/p>\n\n\n\n<p>La doctrine du \u00ab&#160;Make America Great Again&#160;\u00bb prend ici une forme concr\u00e8te&#160;: une politique offensive, o\u00f9 l\u2019\u00e9conomie est instrumentalis\u00e9e au service de la puissance.<\/p>\n\n\n\n<p>C\u2019est dans le m\u00eame mouvement que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/18\/trump-tertrais\/\">la Maison-Blanche r\u00e9affirme la centralit\u00e9 des fronti\u00e8res<\/a> \u2014 non comme simples lignes g\u00e9ographiques, mais comme espaces \u00e0 d\u00e9fendre et \u00e0 verrouiller. Protectionnisme \u00e9conomique et s\u00e9curisation territoriale forment les deux faces d\u2019une m\u00eame strat\u00e9gie&#160;: r\u00e9ancrer la puissance am\u00e9ricaine dans ses fondations nationales, mat\u00e9rielles et symboliques.<\/p>\n\n\n\n<p>Remise en perspective historique, cette articulation entre pouvoir politique, int\u00e9r\u00eats \u00e9conomiques et projection de la force s\u2019inscrit dans une longue tradition&#160;: celle du mercantilisme.<\/p>\n\n\n\n<p>Du XVIe au XVIIIe si\u00e8cle, ce mode d\u2019organisation strat\u00e9gique a domin\u00e9 les relations internationales, notamment au c\u0153ur des rivalit\u00e9s entre puissances europ\u00e9ennes en qu\u00eate de ressources, de routes maritimes et de march\u00e9s sur les continents am\u00e9ricain et asiatique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-8-279065' title='Fran\u00e7ois Crouzet, &lt;a href=&quot;https:\/\/www.fayard.fr\/livre\/la-guerre-economique-franco-anglaise-au-xviiie-siecle-9782213636016\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;La Guerre \u00e9conomique franco-anglaise au XVIII\u00b0 si\u00e8cle&lt;\/em&gt;&lt;\/a&gt;, Paris, Fayard, 2008.'><sup>8<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Loin d\u2019\u00eatre une anomalie, le n\u00e9o-mercantilisme contemporain r\u00e9active donc des logiques anciennes, dans un contexte technologique et g\u00e9opolitique profond\u00e9ment transform\u00e9.<\/p>\n\n\n\n<p>Ce mercantilisme historique avait vu na\u00eetre un acteur hybride, embl\u00e9matique de cette imbrication entre int\u00e9r\u00eats priv\u00e9s et puissance publique&#160;: les grandes compagnies commerciales. Parmi elles, la Compagnie britannique des Indes orientales est officiellement une entreprise priv\u00e9e&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-9-279065' title='Willliam Dalrymple, &lt;a href=&quot;https:\/\/www.bloomsbury.com\/uk\/anarchy-9781408864395\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;The Anarchy. The relentless rise of the East Indian company&lt;\/em&gt;&lt;\/a&gt;, Londres, Bloosmbury, 2019.'><sup>9<\/sup><\/a><\/span><\/span>. Pourtant, elle exerce des op\u00e9rations militaires, pratique la guerre de course, assure le commerce de mati\u00e8res premi\u00e8res strat\u00e9giques, et administre m\u00eame des territoires. \u00c0 la crois\u00e9e du march\u00e9 et de l\u2019Empire, elle agit comme un prolongement arm\u00e9 de la Couronne britannique \u2014 sans en \u00eatre une \u00e9manation directe. Cette ambivalence fonde son efficacit\u00e9 strat\u00e9gique&#160;: tout en affichant l\u2019apparence d\u2019une initiative marchande, elle participe pleinement \u00e0 la politique de domination globale de la Couronne britannique. Le mercantilisme n\u2019opposait pas l\u2019\u00c9tat et l\u2019entreprise&#160;: il les articulait dans une synergie imp\u00e9riale.<\/p>\n\n\n\n<p>Dans les \u00c9tats-Unis de nos ann\u00e9es Vingt, la fusion n\u00e9o-mercantiliste du politique, de l\u2019\u00e9conomique, du commercial et du militaire prend une forme singuli\u00e8re et une expression g\u00e9ographique pr\u00e9cise sous l\u2019administration Trump&#160;: elle passe par la r\u00e9affirmation brutale des fronti\u00e8res comme principe structurant de l\u2019action publique.<\/p>\n\n\n\n<p>Ce recentrage territorial de l\u2019int\u00e9r\u00eat national repose sur une articulation \u00e9troite entre diplomatie, coercition s\u00e9curitaire et usage strat\u00e9gique de la force. Les fronti\u00e8res ne sont plus seulement des lignes de d\u00e9fense&#160;: elles deviennent des instruments actifs de projection de puissance. En retour, plusieurs secteurs clefs de l\u2019\u00e9conomie am\u00e9ricaine \u2014 les industries traditionnelles comme l\u2019\u00e9nergie, mais aussi les fili\u00e8res \u00e9mergentes du num\u00e9rique et de l\u2019intelligence artificielle \u2014 se mobilisent pleinement pour soutenir cette red\u00e9finition offensive de l\u2019int\u00e9r\u00eat national. L\u2019\u00e9conomie ne r\u00e9siste pas \u00e0 cette logique&#160;: elle s\u2019y aligne, s\u2019y adapte, et parfois m\u00eame, la pr\u00e9c\u00e8de&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-10-279065' title='Alexander Karp et Nicholas W. Zamiska, &lt;a href=&quot;https:\/\/techrepublicbook.com\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;The Technological Republic, hard power, soft belief and the future of the West&lt;\/a&gt;, Londres, Penguin, 2025. &lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2025\/04\/15\/transformer-la-nation-americaine-en-republique-technologique-une-lecture-dalex-karp\/&quot;&gt;Voir ici une recension parue dans la revue&lt;\/a&gt;.'><sup>10<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le mercantilisme n\u2019opposait pas l\u2019\u00c9tat et l\u2019entreprise&#160;: il les articulait dans une synergie imp\u00e9riale.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Au-del\u00e0 de l\u2019affrontement tarifaire, l\u2019administration am\u00e9ricaine engage bien plus qu\u2019un simple bras de fer commercial&#160;: elle r\u00e9active le r\u00f4le de la fronti\u00e8re comme outil central de souverainet\u00e9, redonnant au pouvoir d\u2019\u00c9tat une intensit\u00e9 d\u2019action in\u00e9dite depuis la fin de la Seconde Guerre mondiale.<\/p>\n\n\n\n<p>Cette guerre commerciale est donc aussi une guerre des formes de mondialisation&#160;: elle remet frontalement en cause les principes du libre-\u00e9change, ainsi que l\u2019ensemble des accords internationaux qui ont structur\u00e9 l\u2019ordre \u00e9conomique global depuis les ann\u00e9es 1990.&nbsp;<\/p>\n\n\n\n<p>Le repli protectionniste n\u2019est pas conjoncturel \u2014 il est doctrinal, strat\u00e9gique, assum\u00e9.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Donald Trump, l\u2019anti-Bill Clinton<\/h4>\n\n\n\n<p>L\u2019exemple le plus spectaculaire de cette offensive protectionniste demeure l\u2019imposition de surtaxes sur les importations en provenance du Canada et du Mexique.<\/p>\n\n\n\n<p>D\u00e8s f\u00e9vrier 2025, Washington frappe ses deux principaux partenaires frontaliers de hausses tarifaires significatives.<\/p>\n\n\n\n<p>Apr\u00e8s plusieurs cycles de n\u00e9gociation, 50&#160;% des produits mexicains et 38&#160;% des produits canadiens sont soumis \u00e0 des taxes douani\u00e8res punitives. \u00c0 ces mesures s\u2019ajoutent des surtaxes sp\u00e9cifiques sur des secteurs strat\u00e9giques comme l\u2019acier et l\u2019\u00e9nergie \u2014 des piliers de l\u2019\u00e9conomie nord-am\u00e9ricaine.<\/p>\n\n\n\n<p>Et cela, malgr\u00e9 le fait que le Canada, le Mexique et le Br\u00e9sil constituent les trois principaux fournisseurs de l\u2019industrie automobile am\u00e9ricaine en acier et en pi\u00e8ces d\u00e9tach\u00e9es.<\/p>\n\n\n\n<p>Cette politique tarifaire ne rel\u00e8ve donc pas d\u2019un simple r\u00e9ajustement \u00e9conomique&#160;: elle constitue une remise en cause directe de plusieurs trait\u00e9s fondateurs de la mondialisation, au premier rang desquels l\u2019ALENA. Sign\u00e9 en 1994, sous la pr\u00e9sidence de Bill Clinton&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-11-279065' title='Andrew Chatzky, James McBride et Mohamed Aly Sergie, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.cfr.org\/backgrounder\/naftas-economic-impact&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;NAFTA and USMCA&amp;nbsp;&amp;#160;:&amp;nbsp;Weighing the impact of the North american trade&amp;#160;\u00bb&lt;\/a&gt;, Council on Foreign Relations, 1er juillet 2020.'><sup>11<\/sup><\/a><\/span><\/span><sup> <\/sup>\u2014 premier pr\u00e9sident \u00e0 incarner pleinement la vision globalisatrice de la puissance am\u00e9ricaine \u2014 cet accord de libre-\u00e9change symbolisait l\u2019int\u00e9gration \u00e9conomique continentale.<\/p>\n\n\n\n<p>Le tournant n\u00e9o-mercantiliste de l\u2019administration Trump s\u2019affirme \u00e9galement par une strat\u00e9gie de fusion des fronts&#160;: les tarifs douaniers, la militarisation des fronti\u00e8res et la lutte contre le narcotrafic ne sont plus trait\u00e9s comme des enjeux s\u00e9par\u00e9s, mais int\u00e9gr\u00e9s dans une m\u00eame logique de s\u00e9curisation territoriale et \u00e9conomique. D\u00e8s f\u00e9vrier 2025, Washington intime au gouvernement canadien de renforcer le contr\u00f4le de ses fronti\u00e8res.<\/p>\n\n\n\n<p>Derri\u00e8re cette exigence, une justification s\u00e9curitaire&#160;: appuyer l\u2019effort am\u00e9ricain contre le trafic de fentanyl&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-12-279065' title='Marielle Ferragamo et Claire Kobuscista, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.cfr.org\/backgrounder\/fentanyl-and-us-opioid-epidemic&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Fentanyl and the U.S opioid epidemic&lt;\/a&gt;&amp;#160;\u00bb, Council on Foreign Relations, 28 mars 2025.'><sup>12<\/sup><\/a><\/span><\/span>, fl\u00e9au sanitaire devenu un sujet g\u00e9opolitique \u00e0 part enti\u00e8re. Ce narcotique synth\u00e9tique, au c\u0153ur d\u2019un r\u00e9seau d\u2019approvisionnement transnational, cristallise les tensions entre les \u00c9tats-Unis, la Chine \u2014 principal fournisseur des pr\u00e9curseurs chimiques \u2014, le Mexique \u2014 plateforme de transformation et d\u2019acheminement \u2014 et le Canada \u2014 point d\u2019entr\u00e9e secondaire mais strat\u00e9gique. Ainsi, la fronti\u00e8re nord-am\u00e9ricaine devient, \u00e0 son tour, un th\u00e9\u00e2tre de cette nouvelle doctrine de puissance o\u00f9 commerce, s\u00e9curit\u00e9 et coercition s\u2019entrelacent.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Au-del\u00e0 de l\u2019affrontement tarifaire, l\u2019administration am\u00e9ricaine engage bien plus qu\u2019un simple bras de fer commercial&#160;: elle r\u00e9active le r\u00f4le de la fronti\u00e8re comme outil central de souverainet\u00e9, redonnant au pouvoir d\u2019\u00c9tat une intensit\u00e9 d\u2019action in\u00e9dite depuis la fin de la Seconde Guerre mondiale.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">G\u00e9opolitique du fentanyl<\/h4>\n\n\n\n<p>Au c\u0153ur de la crise des opio\u00efdes qui ravage les \u00c9tats-Unis depuis le d\u00e9but des ann\u00e9es 2000, le fentanyl s\u2019impose comme la substance la plus meurtri\u00e8re.<\/p>\n\n\n\n<p>Opio\u00efde de synth\u00e8se d\u2019une extr\u00eame puissance, il peut provoquer une overdose fatale \u00e0 partir de seulement 2 milligrammes. Depuis 2000, plus d\u2019un million d\u2019Am\u00e9ricains ont perdu la vie \u00e0 cause de la consommation d&rsquo;opio\u00efdes \u2014 dont une large part est li\u00e9e au fentanyl.<\/p>\n\n\n\n<p>Cette drogue circule selon deux grands modes op\u00e9ratoires.<\/p>\n\n\n\n<p>Soit elle est directement produite en Chine, puis exp\u00e9di\u00e9e vers le Mexique ou le Canada avant d\u2019\u00eatre achemin\u00e9e clandestinement aux \u00c9tats-Unis par les r\u00e9seaux de narcotrafiquants.<\/p>\n\n\n\n<p>Soit elle est fabriqu\u00e9e localement par les cartels mexicains \u2014 et, plus marginalement, par certains groupes criminels canadiens \u2014 \u00e0 partir de pr\u00e9curseurs chimiques import\u00e9s de Chine, <em>via<\/em> les circuits mafieux chinois&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-13-279065' title='Ferragamo, &lt;em&gt;Ibid&lt;\/em&gt;.'><sup>13<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/vCYyA\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Conscient de l\u2019ampleur du fl\u00e9au, le pr\u00e9sident Joe Biden avait, d\u00e8s 2023, initi\u00e9 une coop\u00e9ration trilat\u00e9rale avec la Chine et le Mexique, obtenant un accord de principe de leurs pr\u00e9sidents respectifs pour une coordination renforc\u00e9e dans la lutte contre la production et le trafic de fentanyl. Mais cette tentative de coop\u00e9ration peine \u00e0 enrayer des dynamiques transnationales ancr\u00e9es, o\u00f9 les logiques criminelles, industrielles et g\u00e9opolitiques s\u2019entrecroisent.<\/p>\n\n\n\n<p>Depuis l\u2019investiture de Donald Trump en 2025, la lutte contre la production et le trafic de fentanyl est pr\u00e9sent\u00e9e comme l\u2019un des fondements de la nouvelle doctrine s\u00e9curitaire am\u00e9ricaine.<\/p>\n\n\n\n<p>Cette crise sanitaire justifie non seulement l\u2019instauration de barri\u00e8res douani\u00e8res vis-\u00e0-vis du Mexique, du Canada et de la Chine, mais aussi le durcissement spectaculaire du contr\u00f4le physique des fronti\u00e8res. Le narcotrafiquant devient ainsi une figure centrale dans le r\u00e9cit de la menace, au m\u00eame titre que le concurrent strat\u00e9gique ou le terroriste.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000003-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000003-scaled.jpg\" alt=\"\u00abLes tarifs douaniers, la militarisation des fronti\u00e8res et la lutte contre le narcotrafic ne sont plus trait\u00e9s comme des enjeux s\u00e9par\u00e9s, mais int\u00e9gr\u00e9s dans une m\u00eame logique de s\u00e9curisation territoriale et \u00e9conomique.\u00bb\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;Les tarifs douaniers, la militarisation des fronti\u00e8res et la lutte contre le narcotrafic ne sont plus trait\u00e9s comme des enjeux s\u00e9par\u00e9s, mais int\u00e9gr\u00e9s dans une m\u00eame logique de s\u00e9curisation territoriale et \u00e9conomique.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000001-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000001-scaled.jpg\" alt=\"\u00abEn classant le fentanyl comme arme de destruction massive, les \u00c9tats-Unis ouvriraient la voie \u00e0 une mobilisation accrue, voire exceptionnelle, de leurs instruments de puissance : agences de renseignement, forces sp\u00e9ciales, arm\u00e9e r\u00e9guli\u00e8re.\u00bb\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;En classant le fentanyl comme arme de destruction massive, les \u00c9tats-Unis ouvriraient la voie \u00e0 une mobilisation accrue, voire exceptionnelle, de leurs instruments de puissance&#160;: agences de renseignement, forces sp\u00e9ciales, arm\u00e9e r\u00e9guli\u00e8re.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>\u00ab&#160;Les tarifs douaniers, la militarisation des fronti\u00e8res et la lutte contre le narcotrafic ne sont plus trait\u00e9s comme des enjeux s\u00e9par\u00e9s, mais int\u00e9gr\u00e9s dans une m\u00eame logique de s\u00e9curisation territoriale et \u00e9conomique.&#160;\u00bb<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>\u00ab&#160;En classant le fentanyl comme arme de destruction massive, les \u00c9tats-Unis ouvriraient la voie \u00e0 une mobilisation accrue, voire exceptionnelle, de leurs instruments de puissance&#160;: agences de renseignement, forces sp\u00e9ciales, arm\u00e9e r\u00e9guli\u00e8re.&#160;\u00bb<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>En mars 2025, Tulsi Gabbard, tout juste nomm\u00e9e directrice f\u00e9d\u00e9rale du renseignement et charg\u00e9e de coordonner l\u2019ensemble des agences de renseignement am\u00e9ricaines, a officialis\u00e9 cette orientation&#160;: le fentanyl est d\u00e9sormais inscrit parmi les menaces prioritaires dans le rapport annuel sur la s\u00e9curit\u00e9 nationale des \u00c9tats-Unis.&nbsp;<\/p>\n\n\n\n<p>Cette classification acte un tournant&#160;: la crise des opio\u00efdes n\u2019est plus seulement un probl\u00e8me de sant\u00e9 publique, elle devient un facteur structurant de la politique \u00e9trang\u00e8re, commerciale et de d\u00e9fense&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-14-279065' title='&lt;em&gt;Ibid&lt;\/em&gt;.'><sup>14<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>L\u2019annonce de l\u2019<em>Office of the Director of National Intelligence<\/em> s\u2019inscrit dans un contexte de d\u00e9bat intense au sein de la communaut\u00e9 de s\u00e9curit\u00e9 nationale am\u00e9ricaine.<\/p>\n\n\n\n<p>Au c\u0153ur de ce d\u00e9bat, il y a la question de savoir si les organisations criminelles transnationales impliqu\u00e9es dans le trafic de fentanyl \u2014 en grande partie issues d\u2019Am\u00e9rique latine \u2014, ainsi que la substance elle-m\u00eame, doivent \u00eatre officiellement d\u00e9sign\u00e9es comme des <em>armes de destruction massive<\/em> par le D\u00e9partement de la D\u00e9fense&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-15-279065' title='&lt;em&gt;Ibid&lt;\/em&gt;.'><sup>15<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Un tel basculement conceptuel aurait des implications politiques et militaires consid\u00e9rables.<\/p>\n\n\n\n<p>En classant le fentanyl comme arme de destruction massive, les \u00c9tats-Unis ouvriraient la voie \u00e0 une mobilisation accrue, voire exceptionnelle, de leurs instruments de puissance&#160;: agences de renseignement, forces sp\u00e9ciales, arm\u00e9e r\u00e9guli\u00e8re. Le narcotrafic ne serait plus trait\u00e9 comme un probl\u00e8me de s\u00e9curit\u00e9 int\u00e9rieure, mais comme une menace strat\u00e9gique de niveau \u00e9tatique.<\/p>\n\n\n\n<p>Ce changement de statut transformerait en profondeur la doctrine d\u2019intervention am\u00e9ricaine, brouillant encore un peu plus les fronti\u00e8res entre guerre, police et politique \u00e9trang\u00e8re.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La crise des opio\u00efdes n\u2019est plus seulement un probl\u00e8me de sant\u00e9 publique, elle devient un facteur structurant de la politique \u00e9trang\u00e8re, commerciale et de d\u00e9fense.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ainsi, durant les d\u00e9buts la \u00ab&#160;<em>war on terror<\/em>&#160;\u00bb qui s\u2019\u00e9tendent des attentats du 11 septembre 2001 l\u2019\u00e9vacuation de l\u2019Afghanistan en 2021, la communaut\u00e9 de s\u00e9curit\u00e9 nationale am\u00e9ricaine accusait l\u2019Iran, l\u2019Irak et la Cor\u00e9e du Nord de se livrer \u00e0 la prolif\u00e9ration d\u2019armes de destruction massive.<\/p>\n\n\n\n<p>Face \u00e0 cet \u00ab&#160;axe du mal&#160;\u00bb, la communaut\u00e9 de s\u00e9curit\u00e9 nationale et de d\u00e9fense am\u00e9ricaine s\u2019\u00e9tait lourdement mobilis\u00e9e pour contrer cette menace. Il en a r\u00e9sult\u00e9, entre autres, l\u2019invasion de l\u2019Irak, de m\u00eame que la \u00ab&#160;guerre secr\u00e8te&#160;\u00bb men\u00e9e par des cyberattaques et des op\u00e9rations sp\u00e9ciales contre le programme nucl\u00e9aire iranien&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-16-279065' title='ason Burke, &lt;a href=&quot;https:\/\/www.penguin.co.uk\/books\/175968\/the-911-wars-by-burke-jason\/9780141044590&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;The 9\/11 Wars&lt;\/em&gt;&lt;\/a&gt;, Londres, Penguin, 2011 et Paul Scharre, &lt;a href=&quot;https:\/\/wwnorton.com\/books\/9780393866865&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;Four Battlegrounds, Power in the age of Artificial Intelligence&lt;\/em&gt;&lt;\/a&gt;, New-York, W. W. Norton, 2023.'><sup>16<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>D\u00e9finir, ou non, le fentanyl comme \u00ab&#160;arme de destruction massive&#160;\u00bb appara\u00eet donc comme un d\u00e9bat dont les conclusions, quelles qu\u2019elles soient, auront une importance potentiellement strat\u00e9gique.<\/p>\n\n\n\n<p>Cela reviendrait potentiellement \u00e0 d\u00e9clencher une logique d\u2019engagement militaire et s\u00e9curitaire semblable \u00e0 celle qui a structur\u00e9 deux d\u00e9cennies d\u2019interventionnisme am\u00e9ricain. Le d\u00e9bat n\u2019est donc pas simplement s\u00e9mantique&#160;: il est strat\u00e9gique, et possiblement d\u00e9terminant pour l\u2019architecture future de la puissance am\u00e9ricaine.<\/p>\n\n\n\n<p>Dans cette m\u00eame logique, les forces des douanes, du <em>Department of Homeland Security<\/em>, du FBI et de la CIA sont mobilis\u00e9es pour renforcer le contr\u00f4le de la fronti\u00e8re sud. En retour, le Mexique et le Canada engagent des moyens consid\u00e9rables&#160;: plusieurs centaines de millions de dollars, et, c\u00f4t\u00e9 mexicain, plus de 10 000 soldats d\u00e9ploy\u00e9s contre les narcotrafiquants, en coordination avec les agences am\u00e9ricaines. Cet engagement sert aussi d\u2019argument dans les n\u00e9gociations visant \u00e0 all\u00e9ger les surtaxes douani\u00e8res. Entre f\u00e9vrier et avril 2025, le Mexique annonce l\u2019arrestation de plus de 6 000 personnes li\u00e9es au narcotrafic.<\/p>\n\n\n\n<p>Pour l\u2019administration Trump, les fronti\u00e8res am\u00e9ricaines ne sont pas seulement des instruments de politique commerciale et s\u00e9curitaire&#160;: elles sont aussi centrales dans le contr\u00f4le des flux migratoires.<\/p>\n\n\n\n<p>Ces derniers, en particulier les passages clandestins, sont en grande partie orchestr\u00e9s par les m\u00eames r\u00e9seaux mafieux que ceux du narcotrafic, tant ils repr\u00e9sentent une source de revenus massive. La crise migratoire, quant \u00e0 elle, s\u2019aggrave depuis la fin des ann\u00e9es 2010. D\u00e8s 2017, lors de son premier mandat, Donald Trump promet la construction d\u2019un mur \u00e0 la fronti\u00e8re mexicaine \u2014 une promesse r\u00e9affirm\u00e9e au c\u0153ur de son second mandat.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/iF0UQ\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La crise migratoire \u00e0 la fronti\u00e8re sud atteint une ampleur in\u00e9dite&#160;: entre 2021 et 2024, pr\u00e8s de 7,2 millions de personnes ont tent\u00e9 de franchir ill\u00e9galement la fronti\u00e8re am\u00e9ricaine \u2014 un chiffre qui ne tient pas compte des entr\u00e9es non d\u00e9tect\u00e9es&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-17-279065' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/usafacts.org\/answers\/how-many-migrant-encounters-are-there-along-the-us-mexico-border\/country\/united-states\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;How many illegal crossings are attempted at the U.S Mexico border each month&amp;#160;?&lt;\/a&gt;&amp;#160;\u00bb, USA Facts.'><sup>17<\/sup><\/a><\/span><\/span>. La majorit\u00e9 de ces migrants viennent d\u2019Am\u00e9rique centrale, notamment du Honduras, du Nicaragua et du Salvador, pouss\u00e9s par la mis\u00e8re, les effets du changement climatique et la d\u00e9gradation des conditions de vie dans des m\u00e9gapoles devenues invivables&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-18-279065' title='Laurent Testot et Jean-Michel Valantin, &lt;a href=&quot;https:\/\/www.nouveau-monde.net\/catalogue\/el-nino-histoire-et-geopolitique-dune-bombe-climatique\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;El Ni\u00f1o, Histoire et G\u00e9opolitique d\u2019une Bombe Climatique&lt;\/em&gt;&lt;\/a&gt;, Paris, \u00c9ditions Nouveau Monde, 2023.'><sup>18<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>D\u00e9finir le fentanyl comme \u00ab&#160;arme de destruction massive&#160;\u00bb reviendrait potentiellement \u00e0 d\u00e9clencher une logique d\u2019engagement militaire et s\u00e9curitaire semblable \u00e0 celle qui a structur\u00e9 deux d\u00e9cennies d\u2019interventionnisme am\u00e9ricain.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La militarisation de l\u2019IA, et la co-p\u00e9n\u00e9tration \u00ab&#160;public-priv\u00e9&#160;\u00bb de l\u2019\u00c9tat et de la Silicon Valley<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L\u2019IA aux fronti\u00e8res<\/h4>\n\n\n\n<p>Face \u00e0 l\u2019ampleur de cette crise, l\u2019administration r\u00e9tablit largement les contr\u00f4les aux fronti\u00e8res, tout en soutenant la signature d\u2019un partenariat entre l\u2019agence de contr\u00f4le des fronti\u00e8res et Palantir, le g\u00e9ant de l\u2019analyse de donn\u00e9es sociales \u2014 parfois surnomm\u00e9e le \u00ab&#160;Google des espions&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-19-279065' title='Jean-Michel Valantin, &lt;em&gt;Hyperguerre&lt;\/em&gt;,&lt;em&gt; ibid&lt;\/em&gt;.'><sup>19<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Les capacit\u00e9s de Palantir \u00e0 croiser et \u00e0 traiter par intelligence artificielle les flux d\u2019information provenant de tous capteurs et \u00e0 l\u2019observation et \u00e0 la surveillance satellitaire devraient permettre d&rsquo;accro\u00eetre la qualit\u00e9 de la surveillance de la fronti\u00e8re, tout en devenant une partie prenante du \u00ab&#160;mur digital&#160;\u00bb que les autorit\u00e9s am\u00e9ricaines sont en train d\u2019\u00e9tablir&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-20-279065' title='Alayna Alvarez, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.axios.com\/local\/denver\/2025\/05\/01\/palantir-deportations-ice-immigration-trump&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Palantir\u2019s partnership with ICE deepens&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Axios&lt;\/em&gt;, 1er mai 2025.'><sup>20<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Or Palantir et ses dirigeants sont profond\u00e9ment impliqu\u00e9s dans la dynamique actuelle de militarisation de l\u2019intelligence artificielle.<\/p>\n\n\n\n<p>Celle-ci s\u2019inscrit dans une \u00e9volution profonde de l\u2019industrie militaire et de la course aux armements.<\/p>\n\n\n\n<p>Ce processus se d\u00e9ploie du fait de l\u2019int\u00e9gration des capacit\u00e9s d\u2019intelligence artificielle aux syst\u00e8mes d\u2019armes, et r\u00e9ciproquement \u00e0 la mise au point d\u2019architectures IA qui traitent les flux de donn\u00e9es g\u00e9n\u00e9r\u00e9s par des services arm\u00e9s am\u00e9ricains et par les th\u00e9\u00e2tres d\u2019op\u00e9rations&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-21-279065' title='Jean-Michel Valantin, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2025\/04\/23\/grande-guerre-chine-etats-unis-1\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Vers la Grande guerre entre les \u00c9tats-Unis et la Chine (Premi\u00e8re partie&lt;\/a&gt;)&amp;#160;\u00bb, &lt;em&gt;Le Grand Continent&lt;\/em&gt;, 23 avril 2025.&lt;br&gt;'><sup>21<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Militarisation de l\u2019IA et strat\u00e9gie n\u00e9o-mercantiliste<\/h4>\n\n\n\n<p>Les forces arm\u00e9es am\u00e9ricaines sont d\u00e9sormais renforc\u00e9es et \u00ab&#160;augment\u00e9es&#160;\u00bb par des capacit\u00e9s d\u2019intelligence artificielle toujours plus autonomes, rapides et interconnect\u00e9es.<\/p>\n\n\n\n<p>Les diff\u00e9rents \u00e9chelons du commandement acc\u00e8dent plus vite \u00e0 des options tactiques et strat\u00e9giques fond\u00e9es sur une analyse en temps r\u00e9el des situations op\u00e9rationnelles&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-22-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-22-279065' title='Paul Scharre, &lt;em&gt;Ibid&lt;\/em&gt;.'><sup>22<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Cette militarisation de l\u2019IA est soutenue par une hausse continue du budget de la d\u00e9fense&#160;: de 770 milliards de dollars en 2023, il grimpe \u00e0 840 milliards en 2024, puis \u00e0 850 milliards en 2025.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000005-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1706\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000005-scaled.jpg\" alt=\"\u00abL\u2019administration r\u00e9tablit largement les contr\u00f4les aux fronti\u00e8res, tout en soutenant la signature d\u2019un partenariat entre l\u2019agence de contr\u00f4le des fronti\u00e8res et Palantir, le g\u00e9ant de l\u2019analyse de donn\u00e9es sociales \u2014 parfois surnomm\u00e9e le Google des espions.\u00bb\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;L\u2019administration r\u00e9tablit largement les contr\u00f4les aux fronti\u00e8res, tout en soutenant la signature d\u2019un partenariat entre l\u2019agence de contr\u00f4le des fronti\u00e8res et Palantir, le g\u00e9ant de l\u2019analyse de donn\u00e9es sociales \u2014 parfois surnomm\u00e9e le Google des espions.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000008-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000008-scaled.jpg\" alt=\"\u00abEn d\u00e9signant l\u2019acc\u00e8s au territoire comme une priorit\u00e9, en d\u00e9non\u00e7ant l\u2019impuissance europ\u00e9enne, et en rappelant sa capacit\u00e9 \u00e0 recourir \u00e0 la force, Washington articule diplomatie, pression strat\u00e9gique et volont\u00e9 d\u2019appropriation.\u00bb\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;En d\u00e9signant l\u2019acc\u00e8s au territoire comme une priorit\u00e9, en d\u00e9non\u00e7ant l\u2019impuissance europ\u00e9enne, et en rappelant sa capacit\u00e9 \u00e0 recourir \u00e0 la force, Washington articule diplomatie, pression strat\u00e9gique et volont\u00e9 d\u2019appropriation.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>\u00ab&#160;L\u2019administration r\u00e9tablit largement les contr\u00f4les aux fronti\u00e8res, tout en soutenant la signature d\u2019un partenariat entre l\u2019agence de contr\u00f4le des fronti\u00e8res et Palantir, le g\u00e9ant de l\u2019analyse de donn\u00e9es sociales \u2014 parfois surnomm\u00e9e le Google des espions.&#160;\u00bb<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>\u00ab&#160;En d\u00e9signant l\u2019acc\u00e8s au territoire comme une priorit\u00e9, en d\u00e9non\u00e7ant l\u2019impuissance europ\u00e9enne, et en rappelant sa capacit\u00e9 \u00e0 recourir \u00e0 la force, Washington articule diplomatie, pression strat\u00e9gique et volont\u00e9 d\u2019appropriation.&#160;\u00bb<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>L\u2019objectif est clair&#160;: acc\u00e9l\u00e9rer l\u2019int\u00e9gration des technologies d\u2019innovation et d\u2019intelligence artificielle au c\u0153ur de l\u2019appareil militaire.<\/p>\n\n\n\n<p>Selon le pr\u00e9sident Trump et le Secr\u00e9taire \u00e0 la D\u00e9fense Pete Hegseth, le budget militaire am\u00e9ricain devrait atteindre le seuil historique de 1 000 milliards de dollars en 2026&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-23-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-23-279065' title='Valerie Insinna, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/breakingdefense.com\/2025\/05\/trump-administration-to-request-1t-defense-budget-using-reconciliation-funds\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Trump administration to request 1T defense budget using reconciliation funds&lt;\/a&gt;&amp;#160;\u00bb, 2 mai 2025.'><sup>23<\/sup><\/a><\/span><\/span>. Or cette hausse massive vise principalement \u00e0 int\u00e9grer les innovations technologiques, en particulier dans le domaine de l\u2019intelligence artificielle. Elle s\u2019appuie sur des partenariats \u00e9troits avec des entreprises de la Silicon Valley, parmi lesquelles Palantir, Anduril (sp\u00e9cialiste du drone de combat), SpaceX, Starlink ou encore Scale AI&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-24-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-24-279065' title='Jean-Michel Valantin, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/redanalysis.org\/2025\/03\/24\/ai-at-war-us-china-drone-and-robot-race\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;AI at War (4) \u2013 The US-China drone and robot race&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Red Team Analysis Society&lt;\/em&gt;, 24 mars 2025 et Michael Klare, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/tomdispatch.com\/a-new-military-industrial-complex-arises\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;A new military-industrial complex arises&lt;\/a&gt;&amp;#160;\u00bb,&amp;nbsp;&lt;em&gt;TomDispatch&lt;\/em&gt;, 9 f\u00e9vrier 2025.'><sup>24<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Cette dynamique alimente directement l\u2019\u00e9mergence du n\u00e9o-mercantilisme am\u00e9ricain.&nbsp;<\/p>\n\n\n\n<p>Les budgets militaires et les projets associ\u00e9s renforcent l\u2019int\u00e9gration de la Silicon Valley \u00e0 la sph\u00e8re de la d\u00e9fense, tant sur le plan industriel que strat\u00e9gique. Il en r\u00e9sulte un effacement progressif des fronti\u00e8res entre le Pentagone et les grandes entreprises priv\u00e9es de la tech et de l\u2019IA. De 2022 \u00e0 2025, ces acteurs ont jou\u00e9 un r\u00f4le crucial dans la r\u00e9silience de l\u2019\u00c9tat et des forces arm\u00e9es ukrainiennes. Les constellations satellitaires de Starlink et les antennes fournies par l\u2019entreprise d\u2019Elon Musk ont permis de maintenir les communications internet de l\u2019Ukraine, assurant la continuit\u00e9 des services \u00e9tatiques et militaires&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-25-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-25-279065' title='Jean-Michel Valantin, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/redanalysis.org\/2024\/04\/08\/ai-at-war-1-ukraine\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;AI at War (I) \u2013 Ukraine&lt;\/a&gt;&amp;#160;\u00bb,&amp;nbsp;&lt;em&gt;The Red Team Analysis Society&lt;\/em&gt;, 8 avril 2024.'><sup>25<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Ce service strat\u00e9gique, assur\u00e9 par Starlink, est financ\u00e9 \u00e0 hauteur de 400 millions de dollars par an depuis septembre 2022. Elon Musk a toutefois bri\u00e8vement interrompu l\u2019acc\u00e8s internet de l\u2019arm\u00e9e ukrainienne lors d\u2019une offensive, soulevant des doutes sur les usages militaires de son r\u00e9seau. Cet incident co\u00efncidait avec des n\u00e9gociations en cours entre SpaceX et le Pentagone&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-26-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-26-279065' title='&lt;em&gt;Ibid&lt;\/em&gt;.'><sup>26<\/sup><\/a><\/span><\/span>. Aujourd\u2019hui, Starlink, \u00e0 l\u2019instar de Palantir, Amazon, Anduril et d\u2019autres, s\u2019impose comme un acteur priv\u00e9 de l\u2019influence am\u00e9ricaine, \u00e9troitement int\u00e9gr\u00e9 aux fonctions de d\u00e9fense, de s\u00e9curit\u00e9 et de projection strat\u00e9gique de l\u2019\u00c9tat f\u00e9d\u00e9ral&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-27-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-27-279065' title='Michael Klare, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/tomdispatch.com\/a-new-military-industrial-complex-arises\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;A New Military-Industrial Complex Arises, the secret war within the Pentagon&amp;#160;\u00bb&lt;\/a&gt;, TomDispatch, 9 f\u00e9vrier 2025.'><sup>27<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>R\u00e9ciproquement, l\u2019ex\u00e9cutif am\u00e9ricain soutient activement la mont\u00e9e en puissance de ces entreprises, qu\u2019il mobilise sur le territoire, aux fronti\u00e8res et \u00e0 l\u2019\u00e9tranger. La militarisation de l\u2019IA devient ainsi une composante centrale du n\u00e9o-mercantilisme am\u00e9ricain, dans le cadre de l\u2019affrontement strat\u00e9gique global avec la R\u00e9publique populaire de Chine.<\/p>\n\n\n\n<p><strong><em>[<\/em><\/strong><a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/23\/grande-guerre-chine-etats-unis-1\/\"><strong><em>Sur la militarisation de l\u2019IA au c\u0153ur de l\u2019affrontement entre P\u00e9kin et Washington, lire le premier volet de cette enqu\u00eate<\/em><\/strong><\/a><strong><em>]<\/em><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De l\u2019Ukraine au Groenland, la guerre hybride entre les \u00c9tats-Unis et la Chine a commenc\u00e9<\/h2>\n\n\n\n<p>Les m\u00e9thodes et les dimensions de la strat\u00e9gie n\u00e9o-mercantiliste se cristallisent dans l\u2019attention strat\u00e9gique port\u00e9e par l\u2019ex\u00e9cutif am\u00e9ricain aux ressources min\u00e9rales du Groenland et de l\u2019Ukraine.<\/p>\n\n\n\n<p>Ces terres semblent en effet \u00eatre devenues centrales pour alimenter l\u2019industrie nationale de l\u2019intelligence artificielle, mais aussi pour contrer le quasi-monopole chinois sur leur extraction.<\/p>\n\n\n\n<p>Depuis la r\u00e9\u00e9lection de Donald Trump en novembre 2024, les propositions am\u00e9ricaines visant \u00e0 annexer le Groenland sont une constante.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Le Groenland, terre de conqu\u00eate<\/h4>\n\n\n\n<p>Cette orientation politique est mise en sc\u00e8ne le 28 mars 2025, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/28\/j-d-vance-se-rend-au-groenland-dans-le-cadre-dune-visite-hautement-controversee\/\">lors de la visite du vice-pr\u00e9sident J. D. Vance et de son \u00e9pouse \u00e0 la base de l\u2019U.S. Air Force au Groenland<\/a>.<\/p>\n\n\n\n<p>\u00c0 cette occasion, il d\u00e9clare que la situation du territoire \u00e9volue face aux ambitions chinoises, aux transformations environnementales et \u00e0 \u00ab&#160;l\u2019incapacit\u00e9 du Danemark&#160;\u00bb \u00e0 en assurer la s\u00e9curit\u00e9. Il pr\u00e9cise penser que \u00ab&#160;le recours \u00e0 la force militaire ne sera pas n\u00e9cessaire&#160;\u00bb \u2014 tout en s\u2019exprimant depuis une base install\u00e9e sur place depuis 1942&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-28-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-28-279065' title='Andrew Harding, Adrienne Murray et Bernd Debussman, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bbc.com\/news\/articles\/cr525e49m2do&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Vance Scolds Denmark during Greenland trip&lt;\/a&gt;&amp;#160;\u00bb, BBC, 29 mars 2025.'><sup>28<\/sup><\/a><\/span><\/span>. Le 2 mai, Donald Trump affirme sur NBC qu\u2019il \u00ab&#160;n\u2019exclut pas de recourir \u00e0 la force&#160;\u00bb pour \u00ab&#160;r\u00e9cup\u00e9rer&#160;\u00bb le Groenland&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-29-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-29-279065' title='Andrew Harding, Adrienne Murray et Bernd Debussman, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bbc.com\/news\/articles\/cr525e49m2do&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Vance Scolds Denmark during Greenland trip&lt;\/a&gt;&amp;#160;\u00bb, BBC, 29 mars 2025.'><sup>29<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Le Groenland, situ\u00e9 \u00e0 la sortie du passage du Nord-Ouest et clef pour la s\u00e9curit\u00e9 de l\u2019Atlantique Nord, poss\u00e8de aussi d\u2019importants gisements de terres rares&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-30-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-30-279065' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.innovationnewsnetwork.com\/why-world-turning-to-greenlands-rare-earth-metals\/32694\/#:~:text=As%20the%20demand%20for%20rare,this%20type%20of%20resource%20extraction.&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Why the world is turning to Greenland rare earth metals&amp;#160;?&lt;\/a&gt;&amp;#160;\u00bb,&amp;nbsp;&lt;em&gt;Innovation News Network&lt;\/em&gt;, Innovation News Network, 3 ao\u00fbt 2023 et Gracelin Baskaran, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.csis.org\/analysis\/what-chinas-ban-rare-earths-processing-technology-exports-means&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;What China\u2019s ban on rare earth processing technology means&lt;\/a&gt;&amp;#160;\u00bb,&lt;em&gt;&amp;nbsp;CSIS&lt;\/em&gt;, January 8, 2024. Eduardo Baptista, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/technology\/how-china-could-retaliate-against-new-us-chip-curbs-2024-12-03\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;After China\u2019s ban on mineral exports, how else could it respond to U.S chips curb&amp;#160;?&lt;\/a&gt;&amp;#160;\u00bb,&amp;nbsp;&lt;em&gt;Reuters&lt;\/em&gt;, 3 d\u00e9cembre 2024.'><sup>30<\/sup><\/a><\/span><\/span>. Cette richesse en fait une cible strat\u00e9gique centrale pour Washington, d\u2019autant plus depuis l\u2019embargo chinois sur l\u2019exportation de terres rares vers les \u00c9tats-Unis, instaur\u00e9 en 2024 et renforc\u00e9 apr\u00e8s l\u2019imposition des barri\u00e8res douani\u00e8res par l\u2019administration Trump en avril 2025&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-31-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-31-279065' title='Gracelin Baskaran et Meredith Shwartz, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.csis.org\/analysis\/consequences-chinas-new-rare-earths-export-restrictions#:~:text=In%20December%202023%2C%20China%20imposed,that%20other%20countries%20do%20not.&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;The consequences of New China\u2019s Rare Earth Export Restrictions&lt;\/a&gt;&amp;#160;\u00bb, CSIS, 14 avril 2025.'><sup>31<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>La m\u00e9thode employ\u00e9e par l\u2019ex\u00e9cutif am\u00e9ricain au Groenland illustre parfaitement l\u2019intrication des dimensions s\u00e9curitaire, commerciale et militaire.&nbsp;<\/p>\n\n\n\n<p>En d\u00e9signant l\u2019acc\u00e8s au territoire comme une priorit\u00e9, en d\u00e9non\u00e7ant l\u2019impuissance europ\u00e9enne, et en rappelant sa capacit\u00e9 \u00e0 recourir \u00e0 la force, Washington articule diplomatie, pression strat\u00e9gique et volont\u00e9 d\u2019appropriation.<\/p>\n\n\n\n<p>Cette approche r\u00e9v\u00e8le combien le d\u00e9veloppement et la militarisation de l\u2019intelligence artificielle sont li\u00e9s \u00e0 la ma\u00eetrise des ressources, dans un cadre o\u00f9 politique, industrie et puissance militaire ne peuvent plus \u00eatre dissoci\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La m\u00e9thode employ\u00e9e par l\u2019ex\u00e9cutif am\u00e9ricain au Groenland illustre parfaitement l\u2019intrication des dimensions s\u00e9curitaire, commerciale et militaire.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le caract\u00e8re n\u00e9o-mercantiliste de la nouvelle grande strat\u00e9gie am\u00e9ricaine se manifeste aussi dans l\u2019accord impos\u00e9 \u00e0 l\u2019Ukraine, visant \u00e0 garantir l\u2019acc\u00e8s des \u00c9tats-Unis aux gisements de min\u00e9raux, notamment de terres rares, comme au Groenland. Le 28 f\u00e9vrier 2025, lors de la visite de Volodymyr Zelensky \u00e0 la Maison-Blanche, ce volet <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/02\/28\/lechange-entre-trump-et-zelensky-transcription-integrale\/\">est exprim\u00e9 avec une rare brutalit\u00e9<\/a>. Face au refus du pr\u00e9sident ukrainien de signer un accord incluant l\u2019uranium, le lithium et les terres rares, Donald Trump et J. D. Vance exercent une pression politique et m\u00e9diatique publique.<\/p>\n\n\n\n<p>Leur position est claire&#160;: l\u2019aide am\u00e9ricaine, estim\u00e9e \u00e0 500 milliards de dollars depuis 2022, devrait \u00eatre \u00ab&#160;rembours\u00e9e&#160;\u00bb par un acc\u00e8s privil\u00e9gi\u00e9 aux ressources du sous-sol ukrainien.<\/p>\n\n\n\n<p>\u00c0 la suite du refus initial du pr\u00e9sident Zelensky, les \u00c9tats-Unis suspendent brutalement leur soutien&#160;: livraisons de munitions, d\u2019armement et de renseignement, notamment \u00e9lectronique et spatial, sont interrompues. La reprise des n\u00e9gociations entra\u00eene toutefois le r\u00e9tablissement progressif de l\u2019aide.<\/p>\n\n\n\n<p>Les n\u00e9gociations entre Washington et Kiev aboutissent le 30 avril 2025, \u00e0 l\u2019occasion des 100 premiers jours du second mandat de Donald Trump. L\u2019accord pr\u00e9voit la cr\u00e9ation d\u2019un fonds d\u2019investissement bilat\u00e9ral destin\u00e9 \u00e0 la reconstruction de l\u2019Ukraine. Ce fonds sera partiellement aliment\u00e9 par les revenus issus de l\u2019exploitation conjointe des gisements ukrainiens de min\u00e9raux \u2014 uranium, lithium, terres rares \u2014 ainsi que de p\u00e9trole et de gaz. En contrepartie, l\u2019Ukraine est dispens\u00e9e de rembourser l\u2019aide civile et militaire fournie par les \u00c9tats-Unis depuis 2022&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-32-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-32-279065' title='Gracelin Baskaran et Meredith Schwarz, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.csis.org\/analysis\/what-know-about-signed-us-ukraine-minerals-deal&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;What to know about the signed U.S-Ukraine minerals deal&lt;\/a&gt;&amp;#160;\u00bb, CSIS, 1er mai 2025.'><sup>32<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Comme pour le Groenland, l\u2019administration Trump manifeste un int\u00e9r\u00eat actif, voire offensif, pour les ressources min\u00e9rales ukrainiennes, notamment le lithium et les terres rares. Ces mat\u00e9riaux sont essentiels aux technologies num\u00e9riques, \u00e0 l\u2019intelligence artificielle, aux syst\u00e8mes d\u2019armes, aux applications spatiales et aux nouvelles g\u00e9n\u00e9rations de batteries. L\u2019acc\u00e8s au sous-sol ukrainien permettrait aux \u00c9tats-Unis de diversifier leurs sources d\u2019approvisionnement et de r\u00e9duire leur d\u00e9pendance vis-\u00e0-vis de la Chine.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Comme pour le Groenland, l\u2019administration Trump manifeste un int\u00e9r\u00eat actif, voire offensif, pour les ressources min\u00e9rales ukrainiennes, notamment le lithium et les terres rares.<\/p><cite>Jean-Michel Valantin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Toutefois, la mise en \u0153uvre de cet accord d\u00e9pend d\u2019une condition majeure&#160;: l\u2019\u00e9tablissement d\u2019une paix durable et la r\u00e9habilitation des r\u00e9seaux de transport et d\u2019\u00e9nergie. Cette exigence est d\u2019autant plus cruciale que l\u2019ouverture d\u2019une mine n\u00e9cessite un d\u00e9lai de 12 \u00e0 18 ans&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-33-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-33-279065' title='H\u00e9l\u00e8ne Lavoix, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/redanalysis.org\/2025\/01\/17\/uranium-us-nuclear-renaissance-global-geopolitical-race\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Uranium for the U.S Nuclear Renaissance&amp;nbsp;&amp;#160;: Towards a Global Geopolitical Race&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Red Team Analysis Society&lt;\/em&gt;, 17 janvier 2025.'><sup>33<\/sup><\/a><\/span><\/span>. \u00c0 cela s\u2019ajoute une contrainte g\u00e9ostrat\u00e9gique&#160;: deux des quatre gisements de lithium identifi\u00e9s se trouvent en Ukraine orientale, dans des zones actuellement occup\u00e9es par les forces russes \u2014 comme de nombreux autres sites miniers. Le communiqu\u00e9 de la Maison-Blanche se conclut d\u2019ailleurs sans ambigu\u00eft\u00e9&#160;: \u00ab&#160;Aucun \u00c9tat ni aucune personne ayant financ\u00e9 ou approvisionn\u00e9 la machine de guerre russe ne sera autoris\u00e9 \u00e0 b\u00e9n\u00e9ficier de la reconstruction de l\u2019Ukraine.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-34-279065' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#easy-footnote-bottom-34-279065' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.whitehouse.gov\/fact-sheets\/2025\/05\/fact-sheet-president-donald-j-trump-secures-agreement-to-establish-united-states-ukraine-reconstruction-investment-fund\/#:~:text=No%20state%2C%20company%2C%20or%20person,projects%20supported%20by%20fund%20resources.&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Fact sheet&amp;nbsp;&amp;#160;: President Donald J. Trump Secures Agreement to Establish United States-Ukraine Reconstruction Investment Fund&amp;#160;\u00bb&lt;\/a&gt;, Maison-Blanche, 1er mai 2025.'><sup>34<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/aEnQT\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Depuis 2022, la Chine apporte un soutien multidimensionnel \u00e0 la Russie. Lors du sommet marquant les 10 ans de la \u00ab&#160;Nouvelle Route de la Soie&#160;\u00bb, tenu \u00e0 P\u00e9kin du 16 au 18 octobre 2023, des accords commerciaux majeurs sont conclus entre les deux pays, dont, pour la premi\u00e8re fois, un accord d\u2019importation de produits agricoles russes.<\/p>\n\n\n\n<p>Les mesures prises par P\u00e9kin permettent \u00e0 Moscou de compenser partiellement les effets des sanctions impos\u00e9es par l\u2019Union europ\u00e9enne et les \u00c9tats-Unis. La mise en service du gazoduc <em>Power of Siberia<\/em>, qui transporte du gaz naturel russe vers la Chine, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/05\/chine-russie-energie-le-fragile-alignement\/\">s\u2019accompagne de n\u00e9gociations en vue de la construction d\u2019un second<\/a>. Ces accords pr\u00e9parent la signature, \u00e0 Moscou, d\u2019un \u00ab&#160;partenariat strat\u00e9gique sans limites&#160;\u00bb entre les deux pays, en gestation depuis 2022. Ce partenariat couvre le commerce, l\u2019\u00e9nergie, l\u2019\u00e9lectrom\u00e9canique \u2014 y compris la robotique et l\u2019IA \u2014, les ressources, l\u2019industrie, les infrastructures et la coop\u00e9ration militaire. Cette alliance renforce l\u2019\u00e9conomie russe et soutient son effort de guerre. L\u2019interdiction am\u00e9ricaine visant tout acteur ayant soutenu la machine de guerre russe dans la reconstruction de l\u2019Ukraine vise donc \u2014 implicitement \u2014 la Chine.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000010-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000010-scaled.jpg\" alt=\"\u00abLoin d\u2019\u00eatre une anomalie, le n\u00e9o-mercantilisme contemporain r\u00e9active donc des logiques anciennes, dans un contexte technologique et g\u00e9opolitique profond\u00e9ment transform\u00e9.\u00bb\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;Loin d\u2019\u00eatre une anomalie, le n\u00e9o-mercantilisme contemporain r\u00e9active donc des logiques anciennes, dans un contexte technologique et g\u00e9opolitique profond\u00e9ment transform\u00e9.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000007-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000007-scaled.jpg\" alt=\"\u00abCette confrontation commerciale et politique s\u2019\u00e9tire d\u00e9sormais jusque dans le domaine militaire \u00e0 travers l\u2019implication indirecte de leurs forces arm\u00e9es dans plusieurs conflits en cours.\u00bb\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00ab&#160;Cette confrontation commerciale et politique s\u2019\u00e9tire d\u00e9sormais jusque dans le domaine militaire \u00e0 travers l\u2019implication indirecte de leurs forces arm\u00e9es dans plusieurs conflits en cours.&#160;\u00bb<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>\u00ab&#160;Loin d\u2019\u00eatre une anomalie, le n\u00e9o-mercantilisme contemporain r\u00e9active donc des logiques anciennes, dans un contexte technologique et g\u00e9opolitique profond\u00e9ment transform\u00e9.&#160;\u00bb<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>\u00ab&#160;Cette confrontation commerciale et politique s\u2019\u00e9tire d\u00e9sormais jusque dans le domaine militaire \u00e0 travers l\u2019implication indirecte de leurs forces arm\u00e9es dans plusieurs conflits en cours.&#160;\u00bb<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>Les barri\u00e8res douani\u00e8res impos\u00e9es par l\u2019administration Trump d\u00e9signent clairement la Chine comme un rival strat\u00e9gique de premier plan \u2014 un concurrent direct dans la logique n\u00e9o-mercantiliste qui structure d\u00e9sormais la politique am\u00e9ricaine.<\/p>\n\n\n\n<p>Pour contenir l\u2019escalade, Washington et P\u00e9kin ont entam\u00e9 des n\u00e9gociations qui ont abouti \u00e0 Gen\u00e8ve le lundi 12 mai \u00e0 une r\u00e9duction provisoire des droits de douane&#160;: de 145&#160;% \u00e0 30&#160;% c\u00f4t\u00e9 am\u00e9ricain, de 125&#160;% \u00e0 10&#160;% c\u00f4t\u00e9 chinois, pour une p\u00e9riode de 90 jours.<\/p>\n\n\n\n<p>L\u2019enjeu imm\u00e9diat est d\u00e9sormais la gestion de l\u2019apr\u00e8s \u2014 la sortie de cette tr\u00eave tarifaire temporaire \u2014 alors m\u00eame que la rivalit\u00e9 entre les deux puissances s\u2019\u00e9tend \u00e0 d\u2019autres champs.<\/p>\n\n\n\n<p>Car cette confrontation commerciale et politique s\u2019\u00e9tire d\u00e9sormais jusque dans le domaine militaire \u00e0 travers l\u2019implication indirecte de leurs forces arm\u00e9es dans plusieurs conflits en cours.<\/p>\n\n\n\n<p><em>Ce sera l\u2019objet du troisi\u00e8me article de cette s\u00e9rie.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des hommes en armes patrouillent en rangs serr\u00e9s \u00e0 la fronti\u00e8re.<\/p>\n<p>Des navires bloqu\u00e9s dans des ports.<\/p>\n<p>Un opio\u00efde l\u00e9tal qui pourrait devenir une arme de destruction massive.<\/p>\n<p>Entre le Pentagone et la Californie, des contrats de plus en plus en gros, de plus en plus profitables.<\/p>\n<p>Deuxi\u00e8me volet de notre vaste enqu\u00eate sur les formes de la guerre qui vient.<\/p>\n","protected":false},"author":10,"featured_media":279010,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":28,"footnotes":""},"categories":[1732],"tags":[],"staff":[3366],"editorial_format":[4849],"serie":[],"audience":[],"geo":[525],"class_list":["post-279065","post","type-post","status-publish","format-standard","hentry","category-guerre","staff-jean-michel-valantin","editorial_format-etudes","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":279010,"excerpt":"Des hommes en armes patrouillent en rangs serr\u00e9s \u00e0 la fronti\u00e8re.\r\n\r\nDes navires bloqu\u00e9s dans des ports.\r\n\r\nUn opio\u00efde l\u00e9tal qui pourrait devenir une arme de destruction massive.\r\n\r\nEntre le Pentagone et la Californie, des contrats de plus en plus en gros, de plus en plus profitables.\r\n\r\nDeuxi\u00e8me volet de notre vaste enqu\u00eate sur les formes de la guerre qui vient.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Des terres rares au fentanyl : vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie) | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des terres rares au fentanyl : vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie) | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Des hommes en armes patrouillent en rangs serr\u00e9s \u00e0 la fronti\u00e8re.  Des navires bloqu\u00e9s dans des ports.  Un opio\u00efde l\u00e9tal qui pourrait devenir une arme de destruction massive.  Entre le Pentagone et la Californie, des contrats de plus en plus en gros, de plus en plus profitables.  Deuxi\u00e8me volet de notre vaste enqu\u00eate sur les formes de la guerre qui vient.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-13T09:41:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T08:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-valantin-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-valantin-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/\",\"name\":\"Des terres rares au fentanyl : vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie) | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg\",\"datePublished\":\"2025-05-13T09:41:58+00:00\",\"dateModified\":\"2025-05-22T08:34:47+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Un cadre bris\u00e9 repr\u00e9sentant le drapeau am\u00e9ricain montre un membre du Corps des Marines des \u00c9tats-Unis en train d'installer des barbel\u00e9s le long du mur entre les \u00c9tats-Unis et le Mexique \u00e0 San Diego, en Californie, vu depuis Tijuana, au Mexique. \u00a9 Carlos Moreno\/Sipa USA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des terres rares au fentanyl&#160;: vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des terres rares au fentanyl : vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie) | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Des terres rares au fentanyl : vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie) | Le Grand Continent","og_description":"Des hommes en armes patrouillent en rangs serr\u00e9s \u00e0 la fronti\u00e8re.  Des navires bloqu\u00e9s dans des ports.  Un opio\u00efde l\u00e9tal qui pourrait devenir une arme de destruction massive.  Entre le Pentagone et la Californie, des contrats de plus en plus en gros, de plus en plus profitables.  Deuxi\u00e8me volet de notre vaste enqu\u00eate sur les formes de la guerre qui vient.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/","og_site_name":"Le Grand Continent","article_published_time":"2025-05-13T09:41:58+00:00","article_modified_time":"2025-05-22T08:34:47+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-valantin-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-valantin-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"28 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/","name":"Des terres rares au fentanyl : vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie) | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg","datePublished":"2025-05-13T09:41:58+00:00","dateModified":"2025-05-22T08:34:47+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg","width":2560,"height":1706,"caption":"Un cadre bris\u00e9 repr\u00e9sentant le drapeau am\u00e9ricain montre un membre du Corps des Marines des \u00c9tats-Unis en train d'installer des barbel\u00e9s le long du mur entre les \u00c9tats-Unis et le Mexique \u00e0 San Diego, en Californie, vu depuis Tijuana, au Mexique. \u00a9 Carlos Moreno\/Sipa USA"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/13\/grande-guerre-chine-etats-unis-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Des terres rares au fentanyl&#160;: vers la Grande Guerre entre la Chine et les \u00c9tats-Unis (deuxi\u00e8me partie)"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1732,"name":"Guerre","slug":"guerre"}],"lgc_author":{"id":3366,"name":"Jean-Michel Valantin","slug":"jean-michel-valantin","description":"Jean-Michel Valantin est docteur et chercheur en \u00e9tudes strat\u00e9giques qui se concentre sur la fa\u00e7on dont la comp\u00e9tition internationale entre les \u00c9tats-Unis, la Russie et la Chine est de plus en plus modifi\u00e9e par le changement climatique, les conflits pour les ressources et la course \u00e0 l'intelligence artificielle.","first_name":"Jean-Michel ","last_name":"Valantin","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/02\/1517224628179-1.jpeg","width":326,"height":326,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg","width":2560,"height":1706,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_sipausa30465727_000002-scaled.jpg","width":2560,"height":1706,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/279065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=279065"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/279065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/279010"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=279065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=279065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=279065"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=279065"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=279065"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=279065"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=279065"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=279065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}