{"id":267756,"date":"2025-03-15T18:38:15","date_gmt":"2025-03-15T17:38:15","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=267756"},"modified":"2025-03-15T18:38:17","modified_gmt":"2025-03-15T17:38:17","slug":"starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/","title":{"rendered":"Starmer organise une r\u00e9union virtuelle pour aider l&rsquo;Ukraine en cas de tr\u00eave&#160;: que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres&#160;?"},"content":{"rendered":"\n<p>Le sommet virtuel qui a r\u00e9uni environ 25 pays s\u2019inscrit dans le cadre de la \u00ab&#160;coalition des volontaires&#160;\u00bb, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/03\/securite-de-lukraine-qui-etait-present-et-que-faut-il-retenir-du-sommet-de-londres\/\">dans un format similaire \u00e0 Londres le 3 mars<\/a>. Parmi les participants, on comptait notamment&#160;: le pr\u00e9sident fran\u00e7ais Emmanuel Macron, le pr\u00e9sident ukrainien Volodymyr Zelensky, le nouveau Premier ministre canadien Mark Carney, le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019OTAN Mark Rutte ainsi que la pr\u00e9sidente du Conseil italien Giorgia Meloni.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le sujet central de discussion a \u00e9t\u00e9 le soutien \u00e0 l\u2019Ukraine. Starmer a r\u00e9it\u00e9r\u00e9 la n\u00e9cessit\u00e9 de maintenir l\u2019aide militaire et la pression \u00e9conomique sur la Russie en d\u00e9clarant&#160;: \u00ab&#160;C\u2019est le moment o\u00f9 les armes doivent se taire&#160;\u00bb. Il a ajout\u00e9 que les pays doivent maintenir le flux d\u2019aide militaire et continuer les sanctions pour affaiblir la \u00ab&#160;machine de guerre de Poutine et le forcer \u00e0 n\u00e9gocier&#160;\u00bb.<\/li>\n\n\n\n<li>\u00ab&#160;Le \u2018oui, mais\u2019 de la Russie ne suffit pas, et tous les participants de la r\u00e9union de ce matin sont convenus d\u2019exercer une pression collective sur la Russie&#160;\u00bb.\u00a0\u00a0<\/li>\n\n\n\n<li>Starmer a \u00e9galement d\u00e9clar\u00e9 que la \u00ab&#160;coalition des volontaires&#160;\u00bb passait maintenant \u00e0 une \u00ab&#160;phase op\u00e9rationnelle&#160;\u00bb de planification pratique et que les efforts visant \u00e0 garantir une \u00ab&#160;paix juste et durable&#160;\u00bb rassemblent des pays europ\u00e9ens, le Canada, l&rsquo;Australie et la Nouvelle-Z\u00e9lande, avec le soutien d&rsquo;autres pays, dont le Japon.<\/li>\n\n\n\n<li>Les responsables militaires des pays alli\u00e9s de l\u2019Ukraine devraient se r\u00e9unir le jeudi 20 mars au Royaume-Uni pour concr\u00e9tiser les plans de maintien de la paix en cas de cessez-le-feu avec Moscou.<\/li>\n\n\n\n<li>Giorgia Meloni a d\u00e9clar\u00e9 explicitement que l&rsquo;Italie n&rsquo;avait pas l&rsquo;intention de participer \u00e0 une pr\u00e9sence militaire en Ukraine.<\/li>\n\n\n\n<li>Le pr\u00e9sident finlandais Alexander Stubb a exprim\u00e9 des r\u00e9serves quant au d\u00e9ploiement de troupes au sol, d\u00e9clarant&#160;: \u00ab&#160;Il est encore trop t\u00f4t pour parler de forces de maintien de la paix en Ukraine. Une fois que nous aurons un plan clair, nous commencerons \u00e0 prendre des engagements. Il y a entre z\u00e9ro et cinquante fa\u00e7ons d\u2019aider \u2014 avoir des troupes sur le terrain n\u2019en est qu\u2019une parmi d\u2019autres&#160;\u00bb.\u00a0<\/li>\n\n\n\n<li>Le Premier ministre australien Anthony Albanese a promis que son pays \u00ab&#160;soutiendrait l\u2019Ukraine aussi longtemps qu\u2019il le faudra, car c\u2019est la bonne chose \u00e0 faire&#160;\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>Les d\u00e9bats sur un cessez-le-feu s\u2019intensifient apr\u00e8s la r\u00e9union entre Steve Witkoff, l\u2019envoy\u00e9 sp\u00e9cial am\u00e9ricain pour le Moyen-Orient et Poutine \u00e0 Moscou de jeudi 13 mars. Donald Trump a d\u00e9clar\u00e9 qu\u2019il allait pr\u00e9senter des d\u00e9tails sur sa proposition d\u2019un cessez-le-feu ce lundi, 17 mars.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mais si le pr\u00e9sident am\u00e9ricain a qualifi\u00e9 les discussions avec la partie russe de \u00ab&#160;bonnes et productives&#160;\u00bb, Poutine\u00a0 a exprim\u00e9 des doutes sur la faisabilit\u00e9 d\u2019une tr\u00eave et continue \u00e0 maintenir des demandes maximalistes pour l&rsquo;arr\u00eat des combats.<\/li>\n\n\n\n<li>Dans une d\u00e9claration apr\u00e8s le sommet virtuel de Starmer, Zelensky a d\u00e9clar\u00e9 qu\u2019un \u00ab&#160;cessez-le-feu aurait d\u00e9j\u00e0 pu avoir lieu, mais [que] la Russie fait tout pour l\u2019emp\u00eacher. C\u2019est la guerre de la Russie \u2013 plus de trois ans de combats et de destructions \u00e0 grande \u00e9chelle. Pour y mettre fin, il faut une pression active, pas seulement des discussions&#160;\u00bb.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Sur le terrain, selon l&rsquo;Institut pour l&rsquo;\u00e9tude de la guerre (Institute for the Study of War), malgr\u00e9 les d\u00e9clarations russes et am\u00e9ricaines&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-267756' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#easy-footnote-bottom-1-267756' title='Post de &lt;a href=&quot;https:\/\/truthsocial.com\/@realDonaldTrump\/114161039436456514&quot;&gt;Donald Trump sur TruthSocial&lt;\/a&gt;.'><sup>1<\/sup><\/a><\/span><\/span>, aucune preuve g\u00e9olocalis\u00e9e n\u2019indique que les forces russes ont encercl\u00e9 un nombre significatif de forces ukrainiennes dans l\u2019oblast de Koursk ou les forces ukrainiennes conservent encore des positions limit\u00e9es&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-267756' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#easy-footnote-bottom-2-267756' title='Institute for the Study of War, &lt;a href=&quot;https:\/\/www.understandingwar.org\/backgrounder\/russian-offensive-campaign-assessment-march-14-2025&quot;&gt;Russian Offensive Campaign Assessment&lt;\/a&gt;, 14 mars 2025.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Premier ministre britannique, Keir Starmer, a organis\u00e9 aujourd\u2019hui, le 15 mars, un sommet virtuel r\u00e9unissant des dirigeants d\u2019environ 25 pays alli\u00e9s de l\u2019Ukraine, une coalition de pays \u00ab&#160;volontaires&#160;\u00bb qui devrait \u00eatre en premi\u00e8re ligne pour aider au respect d\u2019un \u00e9ventuel cessez-le-feu en Ukraine. <\/p>\n<p>Alors que Donald Trump promet des \u00e9l\u00e9ments sur sa proposition de tr\u00eave le lundi 17 mars, Starmer a d\u00e9clar\u00e9&#160;: \u00ab&#160;Nous ne pouvons pas simplement attendre (&#8230;), nous devons continuer \u00e0 pousser et pr\u00e9parer une paix qui doit \u00eatre juste et durable (&#8230;). Si Poutine veut vraiment la paix, c\u2019est tr\u00e8s simple&#160;: il doit cesser ses attaques barbares contre l\u2019Ukraine et accepter un cessez-le-feu&#160;\u00bb.<\/p>\n","protected":false},"author":40,"featured_media":267757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-267756","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":267757,"excerpt":"Le Premier ministre britannique, Keir Starmer, a organis\u00e9 aujourd\u2019hui, le 15 mars, un sommet virtuel r\u00e9unissant des dirigeants d\u2019environ 25 pays alli\u00e9s de l\u2019Ukraine, une coalition de pays \u00ab volontaires \u00bb qui devrait \u00eatre en premi\u00e8re ligne pour aider au respect d\u2019un \u00e9ventuel cessez-le-feu en Ukraine. \r\n\r\nAlors que Donald Trump promet des \u00e9l\u00e9ments sur sa proposition de tr\u00eave le lundi 17 mars, Starmer a d\u00e9clar\u00e9 : \u00abNous ne pouvons pas simplement attendre (...), nous devons continuer \u00e0 pousser et pr\u00e9parer une paix qui doit \u00eatre juste et durable (...). Si Poutine veut vraiment la paix, c\u2019est tr\u00e8s simple : il doit cesser ses attaques barbares contre l\u2019Ukraine et accepter un cessez-le-feu\u00bb.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Starmer organise une r\u00e9union virtuelle pour aider l&#039;Ukraine en cas de tr\u00eave : que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres ? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Starmer organise une r\u00e9union virtuelle pour aider l&#039;Ukraine en cas de tr\u00eave : que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres ? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le Premier ministre britannique, Keir Starmer, a organis\u00e9 aujourd\u2019hui, le 15 mars, un sommet virtuel r\u00e9unissant des dirigeants d\u2019environ 25 pays alli\u00e9s de l\u2019Ukraine, une coalition de pays \u00ab&#160;volontaires&#160;\u00bb qui devrait \u00eatre en premi\u00e8re ligne pour aider au respect d\u2019un \u00e9ventuel cessez-le-feu en Ukraine.   Alors que Donald Trump promet des \u00e9l\u00e9ments sur sa proposition de tr\u00eave le lundi 17 mars, Starmer a d\u00e9clar\u00e9&#160;: \u00ab&#160;Nous ne pouvons pas simplement attendre (...), nous devons continuer \u00e0 pousser et pr\u00e9parer une paix qui doit \u00eatre juste et durable (...). Si Poutine veut vraiment la paix, c\u2019est tr\u00e8s simple&#160;: il doit cesser ses attaques barbares contre l\u2019Ukraine et accepter un cessez-le-feu&#160;\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T17:38:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-15T17:38:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/gc-visio-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ramona Bloj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/gc-visio-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ramona Bloj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/\",\"name\":\"Starmer organise une r\u00e9union virtuelle pour aider l'Ukraine en cas de tr\u00eave : que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres ? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_sipausa31651161_000001.jpg\",\"datePublished\":\"2025-03-15T17:38:15+00:00\",\"dateModified\":\"2025-03-15T17:38:17+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_sipausa31651161_000001.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_sipausa31651161_000001.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Starmer organise une r\u00e9union virtuelle pour aider l&rsquo;Ukraine en cas de tr\u00eave&#160;: que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\",\"name\":\"Ramona Bloj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"caption\":\"Ramona Bloj\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Starmer organise une r\u00e9union virtuelle pour aider l'Ukraine en cas de tr\u00eave : que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres ? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/","og_locale":"fr_FR","og_type":"article","og_title":"Starmer organise une r\u00e9union virtuelle pour aider l'Ukraine en cas de tr\u00eave : que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres ? | Le Grand Continent","og_description":"Le Premier ministre britannique, Keir Starmer, a organis\u00e9 aujourd\u2019hui, le 15 mars, un sommet virtuel r\u00e9unissant des dirigeants d\u2019environ 25 pays alli\u00e9s de l\u2019Ukraine, une coalition de pays \u00ab&#160;volontaires&#160;\u00bb qui devrait \u00eatre en premi\u00e8re ligne pour aider au respect d\u2019un \u00e9ventuel cessez-le-feu en Ukraine.   Alors que Donald Trump promet des \u00e9l\u00e9ments sur sa proposition de tr\u00eave le lundi 17 mars, Starmer a d\u00e9clar\u00e9&#160;: \u00ab&#160;Nous ne pouvons pas simplement attendre (...), nous devons continuer \u00e0 pousser et pr\u00e9parer une paix qui doit \u00eatre juste et durable (...). Si Poutine veut vraiment la paix, c\u2019est tr\u00e8s simple&#160;: il doit cesser ses attaques barbares contre l\u2019Ukraine et accepter un cessez-le-feu&#160;\u00bb.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/","og_site_name":"Le Grand Continent","article_published_time":"2025-03-15T17:38:15+00:00","article_modified_time":"2025-03-15T17:38:17+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/gc-visio-scaled.jpg","type":"image\/jpeg"}],"author":"Ramona Bloj","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/gc-visio-scaled.jpg","twitter_misc":{"\u00c9crit par":"Ramona Bloj","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/","name":"Starmer organise une r\u00e9union virtuelle pour aider l'Ukraine en cas de tr\u00eave : que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres ? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_sipausa31651161_000001.jpg","datePublished":"2025-03-15T17:38:15+00:00","dateModified":"2025-03-15T17:38:17+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_sipausa31651161_000001.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_sipausa31651161_000001.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/15\/starmer-organise-une-reunion-virtuelle-pour-aider-lukraine-en-cas-de-treve-que-sest-il-passe-aujourdhui-a-londres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Starmer organise une r\u00e9union virtuelle pour aider l&rsquo;Ukraine en cas de tr\u00eave&#160;: que s\u2019est-il pass\u00e9 aujourd\u2019hui \u00e0 Londres&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697","name":"Ramona Bloj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","caption":"Ramona Bloj"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_sipausa31651161_000001.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/267756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=267756"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/267756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/267757"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=267756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=267756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=267756"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=267756"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=267756"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=267756"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=267756"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=267756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}