{"id":257118,"date":"2025-01-05T22:29:21","date_gmt":"2025-01-05T21:29:21","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=257118"},"modified":"2025-01-06T09:34:45","modified_gmt":"2025-01-06T08:34:45","slug":"en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/","title":{"rendered":"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale"},"content":{"rendered":"\n<p class=\"intro\">Ce dimanche 5 janvier en d\u00e9but d\u2019apr\u00e8s-midi, le pr\u00e9sident autrichien Alexander van der Bellen (Verts) a prononc\u00e9 un discours annon\u00e7ant qu\u2019il allait convier Herbert Kickl, chef du Parti de la libert\u00e9 d\u2019Autriche (FP\u00d6, PfE), \u00e0 un entretien le lundi 6 janvier. Apr\u00e8s l\u2019\u00e9chec d\u2019une formation gouvernementale au centre et la d\u00e9mission du <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/08\/la-neutralite-strategique-de-lautriche-une-conversation-avec-le-chancelier-federal-karl-nehammer\/\">chancelier Nehammer<\/a>, le pr\u00e9sident semble sur le point de confier \u00e0 l\u2019extr\u00eame droite la t\u00e2che de former le prochain gouvernement. En septembre dernier, l&rsquo;homme qui vient de prendre la t\u00eate des conservateurs autrichiens \u00e9crivait ceci \u00e0 propos du chef du parti d&rsquo;extr\u00eame droite FP\u00d6&#160;: \u00ab&#160;Il serait fatal pour l&rsquo;Autriche que Kickl assume \u00e0 nouveau des responsabilit\u00e9s gouvernementales&#160;\u00bb.<\/p>\n\n\n\n<p class=\"intro\">Ce ne serait pas la premi\u00e8re fois que l\u2019extr\u00eame droite se trouve dans une coalition au gouvernement de l\u2019Autriche \u2014 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/09\/30\/autriche-quest-ce-que-le-fpo-histoire-et-perspectives-du-parti-dextreme-droite-qui-vient-de-remporter-les-legislatives\/\">la premi\u00e8re fois remonte d\u00e9j\u00e0 \u00e0 2000<\/a>&nbsp;\u2014, mais ce serait bien la premi\u00e8re fois qu\u2019un chancelier serait issu de ce parti.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Parmi les \u00e9ditorialistes les plus conservateurs de la presse allemande, on voit dans cette possible nomination un signe&#160;: \u00ab&#160;l&rsquo;Allemagne devrait jeter un regard sur son voisin du sud&#160;\u00bb.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Kickl deviendrait chancelier dans un contexte europ\u00e9en particulier&#160;: avec Giorgia Meloni, pr\u00e9sidente du Conseil italien, et le premier ministre tch\u00e8que Petr Fiala, il serait le troisi\u00e8me chef d&rsquo;\u00c9tat ou de gouvernement directement issu d\u2019une famille \u00e0 la droite du PPE, sans compter le gouvernement de coalition aux Pays-Bas soutenu par Geert Wilders. <br>Dans le m\u00eame temps, une partie de l&rsquo;\u00e9lite trumpiste et Elon Musk semblent appuyer l&rsquo;ascension de l&rsquo;AfD, le parti d&rsquo;extr\u00eame droite allemand.<\/p>\n\n\n\n<p class=\"intro\">Nous traduisons et commentons ce discours historique.<\/p>\n\n\n\n<p>Chers Autrichiens et ch\u00e8res Autrichiennes, chers toutes et tous qui vivez ici&#160;!<\/p>\n\n\n\n<p class=\"comment\">D\u00e8s les premiers mots de son discours, le pr\u00e9sident van der Bellen a le souci d\u2019y inclure tous les r\u00e9sidents ne disposant pas de la nationalit\u00e9 autrichienne (\u00ab&#160;chers toutes et tous qui vivez ici&#160;\u00bb). Si la formule est courante dans sa rh\u00e9torique, elle n\u2019en est pas moins notable alors que le chef de l\u2019\u00c9tat s\u2019appr\u00eate \u00e0 remettre les clefs des n\u00e9gociations gouvernementales \u00e0 un parti connu pour sa x\u00e9nophobie. Dans son programme pour l\u2019\u00e9lection l\u00e9gislative de 2024, le FP\u00d6 qualifiait les \u00e9trangers de \u00ab&#160;<em>V\u00f6lkerwanderer<\/em>&#160;\u00bb, terme qui fait \u00e9cho aux \u00ab&#160;grandes invasions&#160;\u00bb de l\u2019Antiquit\u00e9 tardive.<\/p>\n\n\n\n<p>Si j&rsquo;ai appris quelque chose durant mon mandat de pr\u00e9sident de la R\u00e9publique d&rsquo;Autriche, c&rsquo;est que des situations nouvelles peuvent toujours survenir. M\u00eame lorsque la situation semble famili\u00e8re, m\u00eame apr\u00e8s avoir accumul\u00e9 une longue exp\u00e9rience, on peut soudain faire face \u00e0 une situation nouvelle.<\/p>\n\n\n\n<p class=\"comment\">Depuis sa prise de fonctions en janvier 2017, van der Bellen a d\u00e9j\u00e0 connu de nombreuses crises gouvernementales&#160;: sept cabinets diff\u00e9rents se sont succ\u00e9d\u00e9 depuis cette date, soit environ un par an. Le gouvernement Kurz I (2017-2019) associant le Parti populaire d\u2019Autriche (\u00d6VP, PPE) et le FP\u00d6 est tomb\u00e9 en 2019 suite \u00e0 l\u2019affaire dite \u00ab&#160;d\u2019Ibiza&#160;\u00bb qui a vu tomber Heinz-Christian Strache, vice-chancelier et chef de file du FP\u00d6, mais aussi son ministre de l\u2019Int\u00e9rieur de l\u2019\u00e9poque, Herbert Kickl. Apr\u00e8s un an de gouvernement technocratique, Sebastian Kurz est revenu aux affaires en coalition avec les Verts (2020-2021). Touch\u00e9 \u00e0 son tour par des accusations de corruption, Kurz a d\u00e9missionn\u00e9 \u00e0 l\u2019automne 2021 pour c\u00e9der sa place \u00e0 Alexander Schallenberg (2021) puis \u00e0 Karl Nehammer (2021-2024), ancien ministre de l\u2019Int\u00e9rieur et nouveau pr\u00e9sident de l\u2019\u00d6VP. Kurz a dans un premier temps quitt\u00e9 la politique pour les affaires, occupant notamment un poste dans le fonds d\u2019investissement du milliardaire trumpiste Peter Thiel. En f\u00e9vrier 2024, il a \u00e9t\u00e9 condamn\u00e9 \u00e0 six mois de prison avec sursis en premi\u00e8re instance, condamnation dont il a fait appel.<\/p>\n\n\n\n<p>Comme vous le savez, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/08\/la-neutralite-strategique-de-lautriche-une-conversation-avec-le-chancelier-federal-karl-nehammer\/\">Karl Nehammer<\/a> a annonc\u00e9 hier soir qu&rsquo;il se retirait de la chancellerie f\u00e9d\u00e9rale et de la pr\u00e9sidence de l\u2019\u00d6VP suite \u00e0 l&rsquo;\u00e9chec des discussions pour la formation d&rsquo;un gouvernement avec le SP\u00d6. Karl Nehammer m&rsquo;a assur\u00e9 aujourd&rsquo;hui lors de notre entretien que la transition se ferait dans le calme et de mani\u00e8re ordonn\u00e9e. Concr\u00e8tement, cela signifie que M. Nehammer et son gouvernement continueront, dans un premier temps, \u00e0 assurer la gestion des affaires courantes. Un nouveau chancelier de transition sera ensuite d\u00e9sign\u00e9 par mes soins au cours de la semaine \u00e0 venir. De cette mani\u00e8re, la bonne administration et la poursuite des affaires de la R\u00e9publique d&rsquo;Autriche seront garanties.<\/p>\n\n\n\n<p>Je tiens \u00e0 remercier chaleureusement M. Nehammer pour les services rendus en tant que chancelier de la R\u00e9publique d&rsquo;Autriche. Les temps qu&rsquo;il a pass\u00e9s \u00e0 la t\u00eate de notre pays n&rsquo;ont vraiment pas \u00e9t\u00e9 faciles. Il m\u2019importe de le souligner et de lui rendre hommage.<\/p>\n\n\n\n<p class=\"comment\">Karl Nehammer a annonc\u00e9 le 4 janvier qu\u2019il se retirait \u00e0 la fois de la pr\u00e9sidence de l\u2019\u00d6VP et de la chancellerie. Ce retrait fait suite \u00e0 l\u2019\u00e9chec des n\u00e9gociations de coalitions entre l\u2019\u00d6VP, arriv\u00e9 second aux \u00e9lections l\u00e9gislatives de septembre derri\u00e8re le FP\u00d6, avec les sociaux-d\u00e9mocrates du SP\u00d6 (S&amp;D) et les lib\u00e9raux de Neos (RE), qui ont termin\u00e9 en troisi\u00e8me et quatri\u00e8me position. Pendant la campagne comme au lendemain de l\u2019\u00e9lection, Nehammer avait indiqu\u00e9 son opposition franche \u00e0 toute coalition impliquant le chef du FP\u00d6 Herbert Kickl. En octobre 2024, il justifiait cette d\u00e9cision, relativement surprenante au vu de l\u2019absence de cordon sanitaire en Autriche, par la personnalit\u00e9 clivante\u00a0 de son adversaire politique. Kickl est connu pour sa proximit\u00e9 avec les milieux identitaires, son rejet du consensus scientifique dans la pand\u00e9mie de Covid-19, ses positions anti-ukrainiennes et ses liens avec le parti poutinien Russie Unie. Il convient de noter que le refus de Nehammer portait davantage sur les positions de Kickl lui-m\u00eame que sur celles de son parti, avec lequel l\u2019\u00d6VP pouvait envisager des accords. Ce refus peut \u00e9galement se lire dans une perspective plus opportuniste&#160;: arriv\u00e9 second, l\u2019\u00d6VP pouvait conserver la chancellerie en formant une coalition avec des partenaires plus faibles&#160;; collaborant avec le FP\u00d6, il aurait sans doute d\u00fb accepter un chancelier Kickl.<\/p>\n\n\n\n<p>Mais revenons \u00e0 la <em>causa prima<\/em>, \u00e0 la nouvelle situation \u00e0 laquelle nous faisons face. Pendant un long moment, il a sembl\u00e9 exister entre les trois partenaires de n\u00e9gociation &#8211; l&rsquo;\u00d6VP, le SP\u00d6 et les Neos &#8211; une base de travail favorable. M\u00eame apr\u00e8s le retrait des Neos, on m&rsquo;a dans un premier temps indiqu\u00e9 qu&rsquo;un accord \u00e9tait encore envisageable.<\/p>\n\n\n\n<p>Pour beaucoup d&rsquo;entre vous, Mesdames et Messieurs, l&rsquo;\u00e9chec d\u00e9finitif de ces discussions est une grande d\u00e9ception. Je ne m\u2019en cacherai pas&#160;: pour moi aussi, leur \u00e9chec a \u00e9t\u00e9 une surprise, et vous savez tous que cette issue n\u2019\u00e9tait pas celle que je souhaitais.<\/p>\n\n\n\n<p class=\"comment\">Le 3 janvier, la chef des Neos, Beate Meinl-Reisinger, a indiqu\u00e9 que son parti quittait les discussions de coalition. La dirigeante lib\u00e9rale a mis en cause les positions de ses partenaires sur le plan budg\u00e9taire, leur manque d\u2019une \u00ab&#160;volont\u00e9 de r\u00e9forme&#160;\u00bb et l\u2019absence d\u2019une vision commune apr\u00e8s presque deux mois de n\u00e9gociations. Le SP\u00d6 a aussit\u00f4t rejet\u00e9 l\u2019\u00e9chec de la n\u00e9gociation sur les Neos, les accusant d\u2019avoir voulu imposer des pr\u00e9tentions programmatiques d\u00e9mesur\u00e9es au vu de leur poids \u00e9lectoral limit\u00e9 (9&#160;%). Sans les Neos, l\u2019\u00d6VP et le SP\u00d6 ne disposeraient que d\u2019une majorit\u00e9 d\u2019un si\u00e8ge au Conseil national, ce qui rend la formation d\u2019un ex\u00e9cutif stable d\u00e9licat. Au jour de l\u2019\u00e9chec des n\u00e9gociations, la critique des Neos, qui visait principalement les sociaux-d\u00e9mocrates, a \u00e9t\u00e9 reprise par le Parti populaire, rendant l\u2019hypoth\u00e8se d\u2019une Grande coalition peu probable.<\/p>\n\n\n\n<p>Mais ce n&rsquo;est plus de cela qu&rsquo;il s&rsquo;agit maintenant. Il s&rsquo;agit de doter l&rsquo;Autriche d&rsquo;un gouvernement capable d&rsquo;agir. Il s&rsquo;agit de formuler une vision commune de l&rsquo;Autriche dans laquelle nous voulons vivre. Pour ce faire, nous avons besoin d&rsquo;un gouvernement f\u00e9d\u00e9ral disposant d\u2019une majorit\u00e9 stable, d\u00e9tenant plus de 50&#160;% des si\u00e8ges au Conseil national. Comme vous le savez, j&rsquo;ai d\u00e9j\u00e0 soulign\u00e9 \u00e0 plusieurs reprises cette n\u00e9cessit\u00e9. Vous savez \u00e9galement qu\u2019en octobre dernier, pour \u00e9viter \u00e0 notre pays des d\u00e9lais inutiles, je n&rsquo;avais pas charg\u00e9 Herbert Kickl de former un gouvernement. Karl Nehammer et Andreas Babler avaient en effet exclu \u00e0 plusieurs reprises toute formation d\u2019une coalition avec le FP\u00d6 sous la direction d\u2019Herbert Kickl.<\/p>\n\n\n\n<p>Depuis hier, la situation a chang\u00e9. Karl Nehammer s&rsquo;est retir\u00e9 et a renonc\u00e9 \u00e0 la mission de former un gouvernement.<\/p>\n\n\n\n<p>J&rsquo;ai, chers Autrichiens, mis \u00e0 profit ces derni\u00e8res heures pour m&rsquo;entretenir avec de nombreux responsables politiques. Il ressort de ces entretiens que les voix qui, au sein du Parti populaire, excluaient toute collaboration avec un FP\u00d6 dirig\u00e9 par Herbert Kickl sont devenues moins fortes. Cette \u00e9volution signifie qu&rsquo;une nouvelle voie s&rsquo;ouvre peut-\u00eatre pour la formation d\u2019un gouvernement.<\/p>\n\n\n\n<p class=\"comment\">Alexander van der Bellen prend acte de l\u2019\u00e9chec des n\u00e9gociations et du changement de ton au sein de l\u2019\u00d6VP qui l\u2019a suivi. Dimanche 5 janvier, Christian Stocker, dirigeant par int\u00e9rim du Parti populaire, a en effet indiqu\u00e9 qu\u2019il \u00ab&#160;accepterait l\u2019invitation&#160;\u00bb \u00e9ventuelle du FP\u00d6 \u00e0 participer \u00e0 de futures n\u00e9gociations gouvernementales. Stocker, alors secr\u00e9taire g\u00e9n\u00e9ral du parti, avait pourtant soutenu en octobre dernier la ligne de Karl Nehammer. Au plan d\u00e9moscopique, l\u2019\u00d6VP est le grand perdant de la s\u00e9quence pass\u00e9e&#160;: il a perdu 5 points dans les intentions de vote depuis l\u2019\u00e9lection de septembre, passant de 26 \u00e0 21&#160;% tandis que le FP\u00d6 accroissait ses parts de voix de 29 \u00e0 36&#160;%.&nbsp; En octobre 2024, un sondage Gallup avait plac\u00e9 en t\u00eate, parmi les coalitions pr\u00e9f\u00e9r\u00e9es des \u00e9lecteurs, l\u2019option d\u2019un trio \u00d6VP-SP\u00d6-Neos&nbsp; (26&#160;%)&#160;; l\u2019hypoth\u00e8se d\u2019un accord FP\u00d6-\u00d6VP avec participation d\u2019Herbert Kickl arrivait en deuxi\u00e8me position avec 24&#160;%, tandis qu\u2019une coalition FP\u00d6-\u00d6VP sans participation du <em>leader<\/em> d\u2019extr\u00eame droite obtenait 12&#160;% des pr\u00e9f\u00e9rences. Au total, la coalition droite-extr\u00eame droite \u00e9tait donc plus populaire que celle d\u2019un accord de trois partis centristes. En c\u00e9dant aux exigences du FP\u00d6, il est probable que l\u2019\u00d6VP esp\u00e8re convaincre une partie de son \u00e9lectorat d\u00e9sireux d\u2019une ligne plus dure.<\/p>\n\n\n\n<p>C&rsquo;est la raison pour laquelle j&rsquo;ai appel\u00e9 aujourd\u2019hui le chef du Parti de la libert\u00e9, M. Herbert Kickl, avec lequel j\u2019ai convenu d\u2019une rencontre demain \u00e0 11 heures ici, \u00e0 la Hofburg, pour \u00e9voquer cette nouvelle situation.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Herbert Kickl a manifestement r\u00e9ussi son pari&#160;: celui de se rendre indispensable dans une politique autrichienne fragment\u00e9e, alors m\u00eame qu\u2019il n\u2019a jamais abandonn\u00e9 sa ligne dure et affrontait un chancelier sortant et un pr\u00e9sident qui lui \u00e9taient ouvertement hostiles. Le pr\u00e9sident van der Bellen, \u00e0 qui revient constitutionnellement la nomination du chef du gouvernement, avait en effet d\u00e9clar\u00e9 de mani\u00e8re constante depuis 2017 son rejet de l\u2019hypoth\u00e8se d\u2019un chancelier FP\u00d6.&nbsp; Face \u00e0 l\u2019absence d\u2019alternative d\u00e9sign\u00e9e par les chefs de partis, sans doute convaincu d\u2019une victoire \u00e9crasante du FP\u00d6 en cas de potentielles \u00e9lections l\u00e9gislatives, il semble s\u2019\u00eatre ravis\u00e9. Il reste \u00e0 voir si van der Bellen pourrait poser des conditions inhabituelles \u00e0 la nomination du prochain chancelier, qu\u2019il est seul \u00e0 pouvoir nommer \u00e0 ce poste.<\/p>\n\n\n\n<p>Mesdames et Messieurs, en d\u00e9mocratie, il nous incombe de trouver des solutions et de faire des compromis. Et ce, en toute sinc\u00e9rit\u00e9. Sans ces compromis et cette sinc\u00e9rit\u00e9, la d\u00e9mocratie ne fonctionne pas. La d\u00e9mocratie lib\u00e9rale ne peut pas non plus ignorer les conditions ancr\u00e9es dans notre Constitution f\u00e9d\u00e9rale&#160;: l&rsquo;\u00c9tat de droit, la s\u00e9paration des pouvoirs, les droits de l&rsquo;homme et les droits des minorit\u00e9s, des m\u00e9dias libres et ind\u00e9pendants et l&rsquo;appartenance \u00e0 l&rsquo;Union europ\u00e9enne.&nbsp;<\/p>\n\n\n\n<p>Je continuerai dans tous les cas \u00e0 veiller de mon mieux \u00e0 ce que ces piliers fondamentaux de notre d\u00e9mocratie soient respect\u00e9s. Ils sont le fondement sur lequel notre prosp\u00e9rit\u00e9 et notre s\u00e9curit\u00e9 sont b\u00e2ties.<\/p>\n\n\n\n<p class=\"comment\">Van der Bellen conclut sur les principes de la d\u00e9mocratie lib\u00e9rale, des droits humains et de l\u2019int\u00e9gration europ\u00e9enne que le FP\u00d6, malgr\u00e9 un <em>credo<\/em> libertarien symbolique, semble bien dispos\u00e9 \u00e0 combattre. Son programme \u00e9lectoral pr\u00f4nait ouvertement l\u2019\u00ab&#160;homog\u00e9n\u00e9it\u00e9&#160;\u00bb autrichienne vis-\u00e0-vis des instances supranationales comme des migrations, appelait \u00e0 la \u00ab&#160;remigration des \u00e9trangers non-d\u00e9sir\u00e9s&#160;\u00bb et \u00e0 la construction d\u2019une \u00ab&#160;forteresse Autriche&#160;\u00bb.<\/p>\n\n\n\n<p>Je vous remercie de votre attention et continuerai \u00e0 vous informer directement et imm\u00e9diatement d\u00e8s qu\u2019il y aura du nouveau.<\/p>\n\n\n\n<p>Merci beaucoup.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019extr\u00eame droite vient-elle d\u2019emporter une nouvelle victoire en Autriche&#160;? Ce dimanche 5 janvier, le pr\u00e9sident autrichien Alexander van der Bellen a annonc\u00e9 convier le leader d\u2019extr\u00eame droite Herbert Kickl \u00e0 un entretien. Kickl, connu pour ses positions pro-Kremlin, pourrait recevoir d\u00e8s demain la t\u00e2che de former une coalition avec les conservateurs.<\/p>\n","protected":false},"author":7,"featured_media":257121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":11,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1731],"tags":[],"staff":[1637],"editorial_format":[4943],"serie":[],"audience":[],"geo":[3025],"class_list":["post-257118","post","type-post","status-publish","format-standard","hentry","category-politique","staff-francois-hublet","editorial_format-discours","geo-vienne"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":257121,"excerpt":"L\u2019extr\u00eame droite vient-elle d\u2019emporter une nouvelle victoire en Autriche ? Ce dimanche 5 janvier, le pr\u00e9sident autrichien Alexander van der Bellen a annonc\u00e9 convier le leader d\u2019extr\u00eame droite Herbert Kickl \u00e0 un entretien. Kickl, connu pour ses positions pro-Kremlin, pourrait recevoir d\u00e8s demain la t\u00e2che de former une coalition avec les conservateurs.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"L\u2019extr\u00eame droite vient-elle d\u2019emporter une nouvelle victoire en Autriche&#160;? Ce dimanche 5 janvier, le pr\u00e9sident autrichien Alexander van der Bellen a annonc\u00e9 convier le leader d\u2019extr\u00eame droite Herbert Kickl \u00e0 un entretien. Kickl, connu pour ses positions pro-Kremlin, pourrait recevoir d\u00e8s demain la t\u00e2che de former une coalition avec les conservateurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-05T21:29:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-06T08:34:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Grand-Continent-le-president-autrichien-Alexander-van-der-Bellen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1206\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gilles Gressani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Grand-Continent-le-president-autrichien-Alexander-van-der-Bellen.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Gressani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/\",\"name\":\"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg\",\"datePublished\":\"2025-01-05T21:29:21+00:00\",\"dateModified\":\"2025-01-06T08:34:45+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg\",\"width\":2560,\"height\":1634,\"caption\":\"Cr\u00e9dit obligatoire : Photo par dts News Agency Germany\/Shutterstock (14747051b) Soir\u00e9e \u00e9lectorale au Parlement : Des journalistes regardent une t\u00e9l\u00e9vision dans le centre des m\u00e9dias, sur laquelle un bref discours du pr\u00e9sident f\u00e9d\u00e9ral Alexander Van der Bellen est diffus\u00e9 en direct. Soir\u00e9e \u00e9lectorale au Parlement, Parlamentsgeb\u00e4ude, Vienne, Autriche - 29 Sep 2024\/shutterstock_editorial_Election_evening_in_parliament_14747051b\/\/2409292033\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\",\"name\":\"Gilles Gressani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"caption\":\"Gilles Gressani\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/","og_locale":"fr_FR","og_type":"article","og_title":"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale | Le Grand Continent","og_description":"L\u2019extr\u00eame droite vient-elle d\u2019emporter une nouvelle victoire en Autriche&#160;? Ce dimanche 5 janvier, le pr\u00e9sident autrichien Alexander van der Bellen a annonc\u00e9 convier le leader d\u2019extr\u00eame droite Herbert Kickl \u00e0 un entretien. Kickl, connu pour ses positions pro-Kremlin, pourrait recevoir d\u00e8s demain la t\u00e2che de former une coalition avec les conservateurs.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/","og_site_name":"Le Grand Continent","article_published_time":"2025-01-05T21:29:21+00:00","article_modified_time":"2025-01-06T08:34:45+00:00","og_image":[{"width":1206,"height":676,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Grand-Continent-le-president-autrichien-Alexander-van-der-Bellen.png","type":"image\/png"}],"author":"Gilles Gressani","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Grand-Continent-le-president-autrichien-Alexander-van-der-Bellen.png","twitter_misc":{"\u00c9crit par":"Gilles Gressani","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/","name":"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg","datePublished":"2025-01-05T21:29:21+00:00","dateModified":"2025-01-06T08:34:45+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg","width":2560,"height":1634,"caption":"Cr\u00e9dit obligatoire : Photo par dts News Agency Germany\/Shutterstock (14747051b) Soir\u00e9e \u00e9lectorale au Parlement : Des journalistes regardent une t\u00e9l\u00e9vision dans le centre des m\u00e9dias, sur laquelle un bref discours du pr\u00e9sident f\u00e9d\u00e9ral Alexander Van der Bellen est diffus\u00e9 en direct. Soir\u00e9e \u00e9lectorale au Parlement, Parlamentsgeb\u00e4ude, Vienne, Autriche - 29 Sep 2024\/shutterstock_editorial_Election_evening_in_parliament_14747051b\/\/2409292033"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/05\/en-autriche-le-president-van-der-bellen-ouvre-la-porte-au-premier-chancelier-dextreme-droite-depuis-la-seconde-guerre-mondiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"En Autriche le pr\u00e9sident Van der Bellen ouvre la porte au premier chancelier d\u2019extr\u00eame droite depuis la Seconde Guerre mondiale"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b","name":"Gilles Gressani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","caption":"Gilles Gressani"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1637,"name":"Fran\u00e7ois Hublet","slug":"francois-hublet","description":"Fran\u00e7ois Hublet est r\u00e9dacteur-en-chef des <em>Bulletins des \u00e9lections de l'Union Europ\u00e9enne<\/em> (BLUE), publication du Groupe d'\u00e9tudes g\u00e9opolitiques. Il est dipl\u00f4m\u00e9 de l'\u00c9cole polytechnique (Palaiseau) et de l'\u00c9cole polytechnique f\u00e9d\u00e9rale de Zurich.","first_name":"Fran\u00e7ois","last_name":"Hublet","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/GC_Hublet.png","width":333,"height":331,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg","width":2560,"height":1634,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/SIPA_shutterstock41209737_000002-2-scaled.jpg","width":2560,"height":1634,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/257118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=257118"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/257118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/257121"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=257118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=257118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=257118"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=257118"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=257118"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=257118"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=257118"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=257118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}