{"id":256913,"date":"2025-01-03T18:00:00","date_gmt":"2025-01-03T17:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=256913"},"modified":"2025-01-03T17:32:26","modified_gmt":"2025-01-03T16:32:26","slug":"tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/","title":{"rendered":"\u00ab&#160;Tel est le si\u00e8cle&#160;\u00bb&#160;: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab&#160;\u00e8re des tyrannies&#160;\u00bb"},"content":{"rendered":"\n<p class=\"intro\">N\u00e9 le 6 septembre 1870, \u00c9lie Hal\u00e9vy d\u00e9c\u00e8de soudainement le 21 ao\u00fbt 1937 dans sa demeure de Sucy-en-Brie, la Maison Blanche. \u00c0 l\u2019heure de menaces massives mais inconnues contre les d\u00e9mocraties, cette disparition soudaine est un drame pour sa famille, ses amis, ses \u00e9l\u00e8ves et ses coll\u00e8gues de la philosophie et de l\u2019histoire. Mais il a eu le temps de l\u00e9guer \u00e0 ses contemporains, \u00e0 peine un an plus t\u00f4t, une analyse d\u00e9cisive sur \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb qui recouvre l\u2019Europe et bient\u00f4t le monde, une analyse qui r\u00e9v\u00e8le en contrepoint le pouvoir de la raison critique, la puissance d\u2019une pens\u00e9e politique, et l\u2019affirmation \u00e9clatante du choix de libert\u00e9 qui a toujours \u00e9t\u00e9 la sienne. Ses proches eurent imm\u00e9diatement conscience de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/12\/28\/sur-les-origines-du-totalitarisme-le-message-dhannah-arendt\/\">l\u2019importance de la th\u00e8se de \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb qui posait des identit\u00e9s de nature entre les r\u00e9gimes d\u2019Italie, d\u2019Allemagne et de Russie<\/a>. \u00c9lie Hal\u00e9vy l\u2019exposa, pour la premi\u00e8re et unique fois, le 28 novembre 1936 \u00e0 Paris, devant la Soci\u00e9t\u00e9 fran\u00e7aise de philosophie&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-1-256913' title='La SFP compl\u00e9tait le dispositif cr\u00e9\u00e9 en 1893 avec la &lt;em&gt;Revue de m\u00e9taphysique et de morale&lt;\/em&gt;.\u00a0(Cf. Christophe Prochasson, \u00ab&amp;#160;Philosopher au xx&lt;sup&gt;e&lt;\/sup&gt; si\u00e8cle&amp;#160;: Xavier L\u00e9on et l\u2019invention du \u2018\u2018syst\u00e8me R2M\u2019\u2019 (1891-1902)&amp;#160;\u00bb, &lt;em&gt;Revue de m\u00e9taphysique et de morale&lt;\/em&gt;, n&lt;sup&gt;o&lt;\/sup&gt;\u00b01-2, 1993, p. 109-140&amp;#160;; Stephan Souli\u00e9, &lt;em&gt;Les philosophes en R\u00e9publique. L\u2019aventure intellectuelle de la &lt;\/em&gt;Revue de M\u00e9taphysique et de Morale&lt;em&gt; et de la Soci\u00e9t\u00e9 fran\u00e7aise de philosophie (1891-1914)&lt;\/em&gt;, pr\u00e9face de Christophe Prochasson, Rennes, PUR, 2009.) \u00c9lie Hal\u00e9vy dirigeait cette derni\u00e8re depuis la mort le 21 octobre 1935 de son ami Xavier L\u00e9on qui en \u00e9tait le directeur en titre. Sans avoir le titre de co-directeur de la &lt;em&gt;Revue de m\u00e9taphysique et de morale&lt;\/em&gt;, \u00c9lie Hal\u00e9vy l\u2019\u00e9tait en r\u00e9alit\u00e9. Voir \u00e0 ce sujet deux tomes de la s\u00e9rie \u00ab&amp;#160;\u00c9lie Hal\u00e9vy philosophe&amp;#160;\u00bb des &lt;em&gt;\u0152uvres compl\u00e8tes\u00a0&lt;\/em&gt;&amp;#160;: &lt;em&gt;M\u00e9taphysique et morale &lt;\/em&gt;(\u00e9dition critique i&lt;em&gt;n extenso&lt;\/em&gt;, par Vincent Duclert et Stephan Souli\u00e9, avec introduction, documents et notes). Pr\u00e9face de Fr\u00e9d\u00e9ric Worms, Paris, Les Belles Lettres, 2023&amp;#160;; &lt;em&gt;Correspondance philosophique &lt;\/em&gt;(\u00e9dition critique &lt;em&gt;in extenso&lt;\/em&gt;, par Vincent Duclert et Stephan Souli\u00e9, avec introduction, documents et notes\u00a0), pr\u00e9face de Jean-Louis Fabiani, Paris, Les Belles Lettres, 2023.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p class=\"intro\">S\u2019ajoutait ainsi une nouvelle \u00e9tude \u00e0 l\u2019<em>Histoire du\u00a0peuple anglais au XIXe si\u00e8cle<\/em> et \u00e0 l\u2019<em>Histoire du socialisme europ\u00e9en<\/em>, soit les deux recherches au long cours d\u2019\u00c9lie Hal\u00e9vy et ses cours \u00e0 l\u2019\u00c9cole\u00a0libre des sciences politiques depuis 1898 pour l\u2019une, 1902 pour l\u2019autre. Elle commen\u00e7ait avec l\u2019analyse des cons\u00e9quences de la guerre elle-m\u00eame en ce qu\u2019elle bouleversait profond\u00e9ment les soci\u00e9t\u00e9s europ\u00e9ennes et l\u2019\u00e9quilibre du monde. La guerre mondiale ne s\u2019\u00e9tait pas arr\u00eat\u00e9e aux armistices de 1918 ni aux trait\u00e9s de la conf\u00e9rence de la paix. Elle avait engendr\u00e9 de nouvelles formes d\u2019\u00c9tat, d\u2019id\u00e9ologies et de r\u00e9volution qui constituaient la matrice de \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb, comme \u00c9lie Hal\u00e9vy l\u2019exposa dans la conf\u00e9rence du 28 novembre 1936. Une telle lucidit\u00e9, tr\u00e8s en avance sur ses contemporains, portait en elle les r\u00e9sistances d\u00e9cisives aux \u00c9tats totalitaires. Les proches d\u2019\u00c9lie Hal\u00e9vy furent aux avant-postes d\u2019un tel combat, de C\u00e9lestin Bougl\u00e9 \u00e0 Raymond Aron, d\u2019\u00c9tienne Mantoux, de Jean Cavaill\u00e8s, de sa femme Florence comme de sa ni\u00e8ce Henriette, cette derni\u00e8re contribuant durant tout le second XXe si\u00e8cle \u00e0 faire conna\u00eetre l\u2019\u0153uvre et la vie de son oncle mort trop t\u00f4t, restituant le courage de la v\u00e9rit\u00e9 et l\u2019esprit de libert\u00e9 qui les inspiraient si profond\u00e9ment.\u00a0<\/p>\n\n\n\n<p class=\"intro\">Cette troisi\u00e8me \u00e9tude sur \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb, qu\u2019\u00c9lie Hal\u00e9vy assuma avec un sentiment d\u2019urgence \u00e0 mesure que grandissait le tragique de l\u2019histoire pr\u00e9sente, se liait \u00e0 ses deux recherches initiales. La transformation du socialisme europ\u00e9en se muant en id\u00e9ologie illib\u00e9rale justifiait toutes les violences r\u00e9volutionnaires et devenait partie prenante des \u00c9tats liberticides. Le d\u00e9fi lanc\u00e9 \u00e0 la d\u00e9mocratie \u2014 et d\u2019abord celle du peuple anglais \u2014 apparaissait alors d\u2019une gravit\u00e9 extr\u00eame. C\u2019est \u00e0 l\u2019universit\u00e9&nbsp;d\u2019Oxford, dont il avait \u00e9t\u00e9 fait docteur <em>honoris causa<\/em> en 1926, qu\u2019\u00c9lie Hal\u00e9vy communiqua trois ans plus tard, invit\u00e9 aux prestigieuses Rhodes Lectures, l\u2019\u00e9tat le plus avanc\u00e9 de sa r\u00e9flexion sur la crise mondiale, le fanatisme de nationalit\u00e9 et la r\u00e9ponse encore possible de l\u2019humanit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">L\u2019urgence de penser l\u2019histoire r\u00e9sultait aussi,&nbsp;pour Hal\u00e9vy, de l\u2019exp\u00e9rience personnelle qu\u2019il en avait, par ses voyages en Europe dont, en premier lieu l\u2019Italie. Sa femme, Florence, \u00e9tait n\u00e9e en Italie et une partie de sa famille, dont sa m\u00e8re, r\u00e9sidait toujours \u00e0 Florence. Apr\u00e8s l\u2019Angleterre, l\u2019Italie \u00e9tait le lieu de leurs s\u00e9jours \u00e0 \u00ab&#160;l\u2019\u00e9tranger&#160;\u00bb bien que cette notion \u00e9chappait largement au couple. En Italie, \u00c9lie et Florence furent les t\u00e9moins de la r\u00e9volution fasciste et de l\u2019instauration de la dictature de Mussolini.<\/p>\n\n\n\n<p class=\"intro\">Enfin, le caract\u00e8re tr\u00e8s pr\u00e9curseur de \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb et la puissance de la pens\u00e9e d\u2019Hal\u00e9vy s\u2019expliquent sans conteste par la grande alliance de la philosophie et de l\u2019histoire. Durant la conf\u00e9rence du 28 novembre 1936, \u00c9lie Hal\u00e9vy allait se d\u00e9finir comme philosophe et historien. Depuis l\u2019affaire Dreyfus, il avait ajout\u00e9 l\u2019histoire \u00e0 la philosophie. Ses travaux historiques prenaient le pas sur les travaux philosophiques. Mais il ne renon\u00e7ait ni \u00e0 la philosophie, ni \u00e0 la codirection de la <em>Revue de m\u00e9taphysique et de morale<\/em>, ni aux discussions de la Soci\u00e9t\u00e9 fran\u00e7aise de philosophie.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Bref et saisissant, l\u2019expos\u00e9 d\u2019\u00c9lie Hal\u00e9vy le 28 novembre 1936 est suivi d\u2019une longue discussion reproduite dans le volume des <em>\u0152uvres compl\u00e8tes <\/em>publi\u00e9es en 2016 aux \u00e9ditions des Belles Lettres&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-2-256913' title='\u00c9lie Hal\u00e9vy, &lt;em&gt;L\u2019\u00e8re des tyrannies. \u00c9tudes sur le socialisme et la guerre &lt;\/em&gt;[1938], \u00e9dition critique in extenso, avec introduction, documents et notes par Vincent Duclert, pr\u00e9face de Nicolas Baverez, Paris, Les Belles Lettres, 2016.'><sup>2<\/sup><\/a><\/span><\/span>, et dans l\u2019ouvrage <em>L\u2019\u00e8re des tyrannies. Penser en r\u00e9sistance<\/em>, paru en novembre 2024 aux m\u00eames \u00e9ditions, dans la collection \u00ab&#160;Le go\u00fbt des id\u00e9es&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-3-256913' title='\u00c9lie Hal\u00e9vy, &lt;em&gt;L\u2019\u00e8re des tyrannies. Penser en r\u00e9sistance&lt;\/em&gt;, pr\u00e9face de Perrine Simon-Nahum, Paris, Les Belles Lettres, coll. \u00ab&amp;#160;Le go\u00fbt des id\u00e9es&amp;#160;\u00bb, 2024, XVIII-217 p.'><sup>3<\/sup><\/a><\/span><\/span>. Nos commentaires sont tr\u00e8s largement inspir\u00e9s et repris des analyses qui y sont pr\u00e9sent\u00e9es.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;\u00e8re des tyrannies<\/h2>\n\n\n\n<p>Le socialisme, depuis sa naissance, au d\u00e9but du XIXe si\u00e8cle, souffre d\u2019une contradiction interne. D\u2019une part, il est souvent pr\u00e9sent\u00e9, par ceux qui sont les adeptes de cette doctrine, comme l\u2019aboutissement et l\u2019ach\u00e8vement de la R\u00e9volution de 1789, qui fut une r\u00e9volution de la libert\u00e9, comme une lib\u00e9ration du dernier asservissement qui subsiste apr\u00e8s que tous les autres ont \u00e9t\u00e9 d\u00e9truits&nbsp;&#160;: l\u2019asservissement du travail par le capital. Mais il est aussi, d\u2019autre part, r\u00e9action contre l\u2019individualisme et le lib\u00e9ralisme&nbsp;&#160;; il nous propose une nouvelle organisation par contrainte \u00e0 la place des organisations p\u00e9rim\u00e9es que la R\u00e9volution a d\u00e9truites&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p>a) Le socialisme, sous sa forme primitive, n\u2019est ni lib\u00e9ral, ni d\u00e9mocratique, il est organisateur et hi\u00e9rarchique. Voir en particulier le socialisme saint-simonien.&nbsp;<\/p>\n\n\n\n<p>b) La r\u00e9volution socialiste de 1848 aboutit, par un double mouvement de r\u00e9action contre l\u2019anarchie socialiste et de d\u00e9veloppement du principe organisateur que rec\u00e8le le socialisme, au c\u00e9sarisme de 1851 (tr\u00e8s influenc\u00e9 par le saint-simonisme).&nbsp;<\/p>\n\n\n\n<p>c) \u00c0 l\u2019origine du socialisme d\u00e9mocratique allemand, il y a Karl Marx, internationaliste, fondateur de l\u2019Internationale, et qui aspire \u00e0 un \u00e9tat d\u00e9finitif du genre humain qui sera d\u2019anarchie en m\u00eame temps que de communisme. Mais il y a aussi Ferdinand Lassalle, nationaliste en m\u00eame temps que socialiste, inspirateur direct de la \u00ab&#160;monarchie sociale&#160;\u00bb de Bismarck.&nbsp;<\/p>\n\n\n\n<p>Ces remarques nous semblent trouver une confirmation sensationnelle dans l\u2019\u00e9volution g\u00e9n\u00e9rale de la soci\u00e9t\u00e9 europ\u00e9enne, depuis le d\u00e9but de la Grande Guerre et l\u2019ouverture de ce que nous proposons d\u2019appeler l\u2019\u00e8re des tyrannies&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-4-256913' title='Je me bornerai \u00e0 dire deux mots sur les raisons qui m\u2019ont amen\u00e9 \u00e0 pr\u00e9f\u00e9rer le vocable \u00ab&amp;#160;tyrannie&amp;#160;\u00bb au vocable \u00ab&amp;#160;dictature&amp;#160;\u00bb. C\u2019est que le mot latin de dictature implique l\u2019id\u00e9e d\u2019un r\u00e9gime provisoire, qui laisse intact, \u00e0 la longue, un r\u00e9gime de libert\u00e9, consid\u00e9r\u00e9, malgr\u00e9 tout, comme normal. Tandis que le mot grec de tyrannie exprime l\u2019id\u00e9e d\u2019une forme normale de gouvernement, que l\u2019observateur scientifique des soci\u00e9t\u00e9s doit ranger \u00e0 c\u00f4t\u00e9 des autres formes normales&amp;#160;: royaut\u00e9, aristocratie, et d\u00e9mocratie. On ne saurait donc parler d\u2019une \u00ab&amp;#160;\u00e8re des dictatures&amp;#160;\u00bb. Il m\u2019est apparu d\u2019ailleurs \u2013\u00a0sans conna\u00eetre suffisamment, je l\u2019avoue, l\u2019histoire du monde antique, mais je suis heureux d\u2019avoir re\u00e7u, sur ce point, l\u2019approbation sans r\u00e9serve de Marcel Mauss\u00a0\u2013 que les analyses compl\u00e9mentaires de Platon et d\u2019Aristote sur la mani\u00e8re dont s\u2019op\u00e9ra dans le monde antique le passage de la d\u00e9mocratie \u00e0 la tyrannie trouvent une application profonde aux ph\u00e9nom\u00e8nes historiques dont nous sommes aujourd\u2019hui les spectateurs.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>L\u2019\u00e8re des tyrannies date du mois d\u2019ao\u00fbt 1914, en d\u2019autres termes du moment o\u00f9 les nations bellig\u00e9rantes adopt\u00e8rent un r\u00e9gime qu\u2019on peut d\u00e9finir de la fa\u00e7on suivante&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p>a) Au point de vue \u00e9conomique, \u00e9tatisation extr\u00eamement \u00e9tendue de tous les moyens de production, de distribution et d\u2019\u00e9change&nbsp;&#160;; et, d\u2019autre part, appel des gouvernements aux chefs des organisations ouvri\u00e8res pour les aider dans ce travail d\u2019\u00e9tatisation \u2013&nbsp;donc syndicalisme, corporatisme, en m\u00eame temps qu\u2019\u00e9tatisme.&nbsp;<\/p>\n\n\n\n<p>b) Au point de vue intellectuel, \u00e9tatisation de la pens\u00e9e, cette \u00e9tatisation prenant elle-m\u00eame deux formes&nbsp;&#160;: l\u2019une n\u00e9gative, par la suppression de toutes les expressions d\u2019une opinion jug\u00e9e d\u00e9favorable \u00e0 l\u2019int\u00e9r\u00eat national&nbsp;&#160;; l\u2019autre positive, par ce que nous appellerons l\u2019organisation de l\u2019enthousiasme.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>C\u2019est de ce r\u00e9gime de guerre, beaucoup plus que de la doctrine marxiste, que d\u00e9rive tout le socialisme d\u2019apr\u00e8s-guerre. Le paradoxe du socialisme d\u2019apr\u00e8s-guerre c\u2019est qu\u2019il recrute des adeptes qui viennent \u00e0 lui par haine et d\u00e9go\u00fbt de la guerre, et qu\u2019il leur propose un programme qui consiste dans la prolongation du r\u00e9gime de guerre en temps de paix. Le bolchevisme russe a pr\u00e9sent\u00e9, pour commencer, les caract\u00e8res que nous disons. La R\u00e9volution russe, n\u00e9e d\u2019un mouvement de r\u00e9volte contre la guerre, s\u2019est consolid\u00e9e, organis\u00e9e, sous la forme du \u00ab&#160;communisme de guerre&#160;\u00bb pendant les deux ann\u00e9es de guerre avec les arm\u00e9es alli\u00e9es, qui vont de la paix de Brest-Litowsk \u00e0 la victoire d\u00e9finitive des arm\u00e9es communistes en 1920. Un trait nouveau s\u2019ajoute ici \u00e0 ceux que nous avons d\u00e9finis plus haut. En raison de l\u2019effondrement anarchique, de la disparition totale de l\u2019\u00c9tat, un groupe d\u2019hommes arm\u00e9s, anim\u00e9s par une foi commune, a d\u00e9cr\u00e9t\u00e9 qu\u2019il \u00e9tait l\u2019\u00c9tat&nbsp;&#160;: le sovi\u00e9tisme, sous cette forme, est, \u00e0 la lettre, un \u00ab&#160;fascisme&#160;\u00bb.<\/p>\n\n\n\n<p class=\"comment\">Le trait\u00e9 de Brest-Litowsk (ou Brest-Litovsk) a \u00e9t\u00e9 sign\u00e9 le 3 mars 1918 entre la R\u00e9publique bolchevique de Russie et les Empires centraux, dans la ville du m\u00eame nom. \u00c0 la suite de cet accord, le conflit cesse temporairement sur le front de l\u2019Est.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>Dans l\u2019Europe centrale, c\u2019est pr\u00e9cis\u00e9ment le \u00ab&#160;fascisme&#160;\u00bb, imitation directe des m\u00e9thodes russes de gouvernement, qui a r\u00e9agi contre l\u2019\u00ab&#160;anarchie&#160;\u00bb socialiste. Mais il s\u2019est trouv\u00e9 amen\u00e9 \u00e0 constituer, sous le nom de \u00ab&#160;corporatisme&#160;\u00bb, une sorte de contre-socialisme, que nous sommes dispos\u00e9 \u00e0 prendre plus au s\u00e9rieux qu\u2019on ne fait g\u00e9n\u00e9ralement dans les milieux antifascistes, et qui consiste dans une \u00e9tatisation croissante, avec collaboration de certains \u00e9l\u00e9ments ouvriers, de la soci\u00e9t\u00e9 \u00e9conomique. Nous d\u00e9finirons de la mani\u00e8re suivante la contradiction interne dont souffre la soci\u00e9t\u00e9 europ\u00e9enne. Les partis conservateurs demandent le renforcement presque ind\u00e9fini de l\u2019\u00c9tat avec la r\u00e9duction presque ind\u00e9finie de ses fonctions \u00e9conomiques. Les partis socialistes demandent l\u2019extension ind\u00e9finie des fonctions de l\u2019\u00c9tat et, en m\u00eame temps, l\u2019affaiblissement ind\u00e9fini de son autorit\u00e9. La solution par conciliation, c\u2019est le \u00ab&#160;socialisme national&#160;\u00bb.&nbsp;<\/p>\n\n\n\n<p>Quelles sont, pour les nouveaux r\u00e9gimes, les chances de propagation ult\u00e9rieures&nbsp;&#160;? Quelles sont les possibilit\u00e9s de d\u00e9composition interne&nbsp;&#160;? Mais surtout, l\u2019explication que nous avons tent\u00e9 de donner \u00e0 leur gen\u00e8se, par la nature contradictoire de l\u2019essence du socialisme, est-elle valable&nbsp;&#160;? Voil\u00e0 les questions que nous soumettons \u00e0 l\u2019examen de la <em>Soci\u00e9t\u00e9 de Philosophie<\/em>. [\u2026]&nbsp;<\/p>\n\n\n\n<p>Je n\u2019ai pas l\u2019intention de r\u00e9p\u00e9ter, encore moins de d\u00e9velopper, le texte imprim\u00e9 qui a \u00e9t\u00e9 adress\u00e9 \u00e0 tous les membres de la <em>Soci\u00e9t\u00e9<\/em>. Je me bornerai, pour ouvrir le d\u00e9bat, \u00e0 pr\u00e9senter quelques observations personnelles. Non que j\u2019attache une importance sp\u00e9ciale \u00e0 ma personnalit\u00e9&nbsp;&#160;; mais pour encourager ceux qui parleront apr\u00e8s moi \u00e0 suivre mon exemple. De la confrontation de nos \u00ab&#160;exp\u00e9riences&#160;\u00bb, il jaillira peut-\u00eatre quelque lumi\u00e8re sur le gros probl\u00e8me qui ne peut manquer de passionner, ou tout au moins de troubler, les consciences de tous ceux qui sont ici.&nbsp;<\/p>\n\n\n\n<p>Je vous rappellerai donc qu\u2019en mars 1902, lorsqu\u2019eut lieu la s\u00e9ance \u00e0 laquelle Brunschvicg faisait allusion, il y avait quelques mois que j\u2019avais commenc\u00e9 d\u2019enseigner, \u00e0 l\u2019\u00c9cole des Sciences Politiques, l\u2019histoire du socialisme europ\u00e9en au xix<sup>e<\/sup> si\u00e8cle. Depuis le mois de novembre 1901, tous les deux ans, j\u2019ai enseign\u00e9 cette histoire.<\/p>\n\n\n\n<p class=\"comment\">Le cours sur l\u2019histoire du socialisme europ\u00e9en est dispens\u00e9 \u00e0 l\u2019\u00c9cole libre des sciences politiques, en alternance avec celui consacr\u00e9 \u00e0 l\u2019histoire de l\u2019Angleterre, depuis janvier 1902.<\/p>\n\n\n\n<p>J\u2019ai donc, pour parler de socialisme, non pas en partisan, mais en historien, une certaine comp\u00e9tence. Max Lazard, que je vois ici, et qui n\u2019est plus un tr\u00e8s jeune homme, a suivi ce cours voil\u00e0 bien une trentaine d\u2019ann\u00e9es.<\/p>\n\n\n\n<p class=\"comment\">Max Lazard (1875-1953) est le fils de Simon Lazard, associ\u00e9-fondateur de la banque du m\u00eame nom, un ami d\u2019\u00c9lie Hal\u00e9vy. Apr\u00e8s sa mort, sa femme cr\u00e9e en 1954, \u00e0 l\u2019Institut politique de Paris, une bourse qui porte son nom, \u00ab&#160;destin\u00e9e \u00e0 faciliter \u00e0 des \u00e9tudiants, ou \u00e9tudiantes, ou \u00e0 des chercheurs en sciences politiques, \u00e9conomiques ou sociales des recherches et des travaux, notamment \u00e0 l\u2019\u00e9tranger&#160;\u00bb. Il est l\u2019oncle de Jean-Pierre Lazard (cf. \u00ab&#160;Discours prononc\u00e9 par \u00c9lie Hal\u00e9vy au cimeti\u00e8re d\u2019Ablon, le 17 ao\u00fbt 1926, sur le cercueil de Jean-Pierre Lazard, mort le 13 ao\u00fbt \u00e0 Tr\u00eaves, \u00e0 l\u2019\u00e2ge de 21 ans&#160;\u00bb.<\/p>\n\n\n\n<p>Or, quelle \u00e9tait, en ce qui concerne le socialisme, mon attitude intellectuelle, lorsque j\u2019acceptai d\u2019entreprendre ce cours&#160;? Autant qu\u2019il me souvient, voici&#160;:\u00a0<\/p>\n\n\n\n<p>Je n\u2019\u00e9tais pas socialiste. J\u2019\u00e9tais \u00ab&#160;lib\u00e9ral&#160;\u00bb en ce sens que j\u2019\u00e9tais anticl\u00e9rical, d\u00e9mocrate, r\u00e9publicain, disons d\u2019un seul mot qui \u00e9tait alors lourd de sens&nbsp;&#160;: un \u00ab&#160;dreyfusard&#160;\u00bb. Mais je n\u2019\u00e9tais pas socialiste. Et pourquoi&nbsp;&#160;? C\u2019est, j\u2019en suis persuad\u00e9, pour un motif dont je n\u2019ai aucune raison d\u2019\u00eatre fier. C\u2019est que je suis n\u00e9 cinq ou six ans trop t\u00f4t. Mes ann\u00e9es d\u2019\u00c9cole Normale vont de l\u2019automne 1889, juste apr\u00e8s l\u2019effondrement du boulangisme, \u00e0 l\u2019\u00e9t\u00e9 de 1892, juste avant le d\u00e9but de la crise du Panama. Ann\u00e9es de calme plat&nbsp;&#160;: au cours de ces trois ann\u00e9es, je n\u2019ai pas connu \u00e0 l\u2019\u00c9cole Normale un seul socialiste. Si j\u2019avais eu cinq ans de moins, si j\u2019avais \u00e9t\u00e9 \u00e0 l\u2019\u00c9cole Normale au cours des ann\u00e9es qui vont des environs de 1895 aux environs de 1900&nbsp;&#160;; si j\u2019avais \u00e9t\u00e9 le camarade de Mathiez, de P\u00e9guy, d\u2019Albert Thomas, il est extr\u00eamement probable qu\u2019\u00e0 vingt-et-un ans j\u2019aurais \u00e9t\u00e9 socialiste, quitte \u00e0 \u00e9voluer ensuite, il m\u2019est impossible de deviner en quel sens. Lorsque, appliquant \u00e0 nous-m\u00eames les m\u00e9thodes de la recherche historique, nous sommes amen\u00e9s \u00e0 d\u00e9couvrir les raisons de nos convictions, nous constatons souvent qu\u2019elles sont accidentelles, qu\u2019elles tiennent \u00e0 des circonstances dont nous n\u2019avons pas \u00e9t\u00e9 les ma\u00eetres. Et peut-\u00eatre y a-t-il l\u00e0 une le\u00e7on de tol\u00e9rance. Si on a bien compris cela, on est conduit \u00e0 se demander s\u2019il vaut la peine de se massacrer les uns les autres pour des convictions dont l\u2019origine est si fragile.&nbsp;<\/p>\n\n\n\n<p>Je n\u2019\u00e9tais pas socialiste, et cependant j\u2019avais d\u00e9j\u00e0 une connaissance assez approfondie du socialisme, tant par ce que je pouvais d\u00e9j\u00e0 observer en France que par ce que j\u2019apprenais par mon exp\u00e9rience des choses anglaises. Il y avait d\u00e9j\u00e0, \u00e0 cette \u00e9poque, trois ou quatre ans que je faisais en Angleterre des s\u00e9jours prolong\u00e9s et fr\u00e9quents&nbsp;&#160;: et d\u00e9j\u00e0 je m\u2019\u00e9tais li\u00e9 avec les deux personnalit\u00e9s \u00e9minentes que sont M. et Mme Sidney Webb, inspirateurs de la <em>Soci\u00e9t\u00e9 Fabienne<\/em>. Je suis rest\u00e9 leur ami&nbsp;&#160;; et aujourd\u2019hui, j\u2019ai l\u2019impression d\u2019\u00eatre leur contemporain&nbsp;&#160;; mais, dans ce temps-l\u00e0, les dix ann\u00e9es qui nous s\u00e9parent comptaient beaucoup. J\u2019\u00e9tais un jeune homme de vingt-cinq, de trente ans, qui s\u2019entretenait avec deux a\u00een\u00e9s \u00e2g\u00e9s de trente-cinq, de quarante ans, ayant d\u00e9j\u00e0 \u00e9crit des ouvrages qui sont rest\u00e9s classiques. Je les \u00e9coutais donc avec respect&nbsp;&#160;; et ils m\u2019expliquaient les principes de leur socialisme, qui \u00e9tait essentiellement antilib\u00e9ral. Ils poursuivaient de leur haine non pas le conservatisme, le torysme, pour lequel leur indulgence \u00e9tait extr\u00eame, mais le lib\u00e9ralisme gladstonien. On \u00e9tait au temps de la guerre des Boers&nbsp;&#160;; et les lib\u00e9raux avanc\u00e9s, les travaillistes, qui commen\u00e7aient \u00e0 s\u2019organiser en parti, prenaient tous, par g\u00e9n\u00e9rosit\u00e9, par amour de la libert\u00e9 et du genre humain, la d\u00e9fense des Boers contre l\u2019imp\u00e9rialisme britannique. Mais les deux Webb, ainsi que leur ami Bernard Shaw, faisaient bande \u00e0 part. Ils \u00e9taient imp\u00e9rialistes avec ostentation. L\u2019ind\u00e9pendance des petites nations pouvait bien avoir du prix pour les tenants de l\u2019individualisme lib\u00e9ral, mais non pour eux, pr\u00e9cis\u00e9ment parce qu\u2019ils \u00e9taient collectivistes. J\u2019entends encore Sidney Webb m\u2019expliquant que l\u2019avenir \u00e9tait aux grandes nations administratives, gouvern\u00e9es par des bureaux, et o\u00f9 l\u2019ordre \u00e9tait maintenu par des gendarmes.&nbsp;<\/p>\n\n\n\n<p>C\u2019est peut-\u00eatre leur faute si j\u2019ai toujours \u00e9t\u00e9 frapp\u00e9 par ce qu\u2019il y avait d\u2019illib\u00e9ral dans l\u2019id\u00e9e socialiste. Deuxi\u00e8me accident dans l\u2019histoire de la formation de mon esprit&nbsp;&#160;: tenez-en-compte si vous voulez comprendre, par leur origine, la nature de mes pr\u00e9jug\u00e9s. Je fus donc amen\u00e9, dans mon cours de l\u2019\u00c9cole des Sciences Politiques, \u00e0 insister sur certains aspects conservateurs qu\u2019a pr\u00e9sent\u00e9s le socialisme europ\u00e9en au cours du dernier si\u00e8cle&nbsp;&#160;; sur le socialisme autoritaire, monarchique ou chr\u00e9tien&#160;; sur Napol\u00e9on III, subissant l\u2019influence des saint-simoniens&nbsp;&#160;; sur Bismarck, subissant celle de Lassalle. Je n\u2019insiste pas&nbsp;&#160;: je vous renvoie au texte qui est sous vos yeux.&nbsp;<\/p>\n\n\n\n<p>Je reconnais, d\u2019ailleurs, qu\u2019aux environs de 1910 je fus troubl\u00e9 par le fait qu\u2019en Angleterre les Webb semblaient s\u2019\u00eatre tromp\u00e9s, et se trompant, m\u2019avaient tromp\u00e9. Il s\u2019\u00e9tait produit une violente r\u00e9vulsion lib\u00e9rale, qu\u2019ils n\u2019avaient point pr\u00e9vue&nbsp;&#160;; le nouveau lib\u00e9ralisme \u00e9tait fortement teint\u00e9 de socialisme&nbsp;&#160;: et l\u2019exp\u00e9rience Lloyd George, comme on dirait aujourd\u2019hui, prouvait qu\u2019on pourrait concevoir un radicalisme socialisant dou\u00e9 d\u2019une vitalit\u00e9 tr\u00e8s grande&nbsp;&#160;; bref, cette conciliation entre socialisme et lib\u00e9ralisme, que les Webb tenaient pour impossible, devenait une r\u00e9alit\u00e9.&nbsp;<\/p>\n\n\n\n<p>Mais la guerre est venue. \u00c0 sa suite s\u2019est ouvert ce que j\u2019appelle l\u2019\u00e8re des tyrannies. Les Webb et Bernard Shaw n\u2019ont pas trahi les convictions de leur jeunesse&nbsp;&#160;; ils les trouvent v\u00e9rifi\u00e9es par les faits, et partagent leurs sympathies entre le sovi\u00e9tisme russe et le fascisme italien.&nbsp;<\/p>\n\n\n\n<p>Voil\u00e0 ce que je voulais vous dire, non pour justifier ma position, mais pour l\u2019expliquer. J\u2019ai proc\u00e9d\u00e9, pour vous la faire comprendre, non pas en doctrinaire, mais en historien. C\u2019est de m\u00eame en historien \u2013\u00a0en historien philosophe, si vous voulez, et en me tenant autant que possible, et j\u2019esp\u00e8re que vous suivrez mon exemple, au-dessus du niveau de la politique\u00a0\u2013 que j\u2019ai proc\u00e9d\u00e9 pour d\u00e9finir cette \u00ab&#160;\u00e8re des tyrannies&#160;\u00bb. \u00cates-vous d\u2019accord, premi\u00e8rement, apr\u00e8s avoir lu le texte de ma communication, sur la r\u00e9alit\u00e9 du ph\u00e9nom\u00e8ne historique qui en est l\u2019objet&#160;? Et, deuxi\u00e8mement, croyez-vous que mon explication de ce ph\u00e9nom\u00e8ne soit plausible&#160;? Je vous laisse la parole.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-5-256913' title='Cit\u00e9 in \u00c9lie Hal\u00e9vy, &lt;em&gt;L\u2019\u00e8re des tyrannies. Penser en r\u00e9sistance&lt;\/em&gt;, &lt;em&gt;op. cit.&lt;\/em&gt;, p. 125-128.'><sup>5<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Au terme de la conf\u00e9rence de \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb \u00e0 la Soci\u00e9t\u00e9 fran\u00e7aise de philosophie, il avait \u00e9t\u00e9 pr\u00e9vu de reprendre le fil de la discussion d\u00e8s que possible, tant \u00ab&#160;un monde de questions\u00a0\u00e9tait soulev\u00e9&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-6-256913' title='C\u00e9lestin Bougl\u00e9 l\u2019affirme dans la pr\u00e9face de &lt;em&gt;L\u2019\u00c8re des tyrannies&lt;\/em&gt; paru en octobre 1938 (Paris, Gallimard, coll. \u00ab&amp;#160;Biblioth\u00e8que des id\u00e9es&amp;#160;\u00bb, r\u00e9\u00e9d. princeps 2016, par Vincent Duclert, pr\u00e9face de Nicolas Baverez, Paris, &lt;em&gt;op. cit.&lt;\/em&gt;).'><sup>6<\/sup><\/a><\/span><\/span>. La brusque disparition d\u2019\u00c9lie Hal\u00e9vy enterra cette promesse. Mais la poursuite de la r\u00e9flexion n\u2019allait pas s\u2019arr\u00eater pour autant. Tr\u00e8s vite, l\u2019ami de l\u2019\u00c9cole normale sup\u00e9rieure C\u00e9lestin Bougl\u00e9, son cadet Raymond Aron et son \u00e9l\u00e8ve \u00c9tienne Mantoux s\u2019emploient \u00e0 r\u00e9unir les textes majeurs d\u2019\u00c9lie Hal\u00e9vy afin de composer un livre pour le temps pr\u00e9sent. Son titre s\u2019impose, <em>L\u2019\u00c8re des tyrannies<\/em>. Il para\u00eet un an apr\u00e8s la mort de son auteur, le 18 octobre 1938, dans la prestigieuse \u00ab&#160;Biblioth\u00e8que des id\u00e9es&#160;\u00bb qui vient d\u2019\u00eatre cr\u00e9\u00e9e aux \u00e9ditions Gallimard.\u00a0<\/p>\n\n\n\n<p class=\"comment\">Dans la pr\u00e9face qu\u2019il donne au livre posthume de son ami, C\u00e9lestin Bougl\u00e9 s\u2019attache \u00e0 l\u2019importance cruciale de sa th\u00e8se de \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb de 1936. Il souligne, comme nous l\u2019avons relev\u00e9 en 2016 dans l\u2019\u00e9dition princeps pour les <em>\u0152uvres compl\u00e8tes <\/em>(Belles Lettres-Sciences Po), \u00ab&#160;la signification d\u2019une proposition de lecture du monde pr\u00e9sent et son impact sur la pens\u00e9e philosophique confront\u00e9e \u00e0 la toute-puissance de l\u2019histoire&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-7-256913' title='&lt;em&gt;Ibid.&lt;\/em&gt;, p.&lt;em&gt; &lt;\/em&gt;57.'><sup>7<\/sup><\/a><\/span><\/span>. C\u00e9lestin Bougl\u00e9 y voit la marque de la \u00ab&#160;r\u00e9flexion la plus libre, la plus m\u00e9thodique, la mieux inform\u00e9e qui soit&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-8-256913' title='&lt;em&gt;Ibid.&lt;\/em&gt;, p.&lt;em&gt; &lt;\/em&gt;65 et pour les deux citations suivantes.'><sup>8<\/sup><\/a><\/span><\/span>.\u00a0<\/p>\n\n\n\n<p class=\"comment\">Un tel exemple de courage intellectuel et de v\u00e9rit\u00e9 humaine, tel qu\u2019il \u00e9mane d\u2019\u00c9lie Hal\u00e9vy, se doit d\u2019\u00eatre communiqu\u00e9 \u00e0 tous. Il est \u00ab&#160;un de ceux dont personne aux heures que nous traversons ne m\u00e9conna\u00eetra le prix&#160;\u00bb. Avec lui et cet h\u00e9ritage sans \u00e9quivalent, \u00ab&#160;les d\u00e9mocraties, ni en Am\u00e9rique, ni en Angleterre, n\u2019ont encore dit leur dernier mot&#160;\u00bb.<\/p>\n\n\n\n<p class=\"comment\">Sa vie durant, \u00c9lie Hal\u00e9vy fit le choix de la libert\u00e9. Libert\u00e9 au regard d\u2019une famille artiste entre son p\u00e8re Ludovic et son fr\u00e8re Daniel, avec son choix d\u2019une carri\u00e8re savante, fid\u00e8le en cela \u00e0 l\u2019enseignement de sa m\u00e8re Louis Breguet et de ses anc\u00eatres Hal\u00e9vy&#160;; libert\u00e9 du professeur renon\u00e7ant \u00e0 la Sorbonne au profit d\u2019une moindre carri\u00e8re acad\u00e9mique mais plus \u00e0 m\u00eame de favoriser sa vie d\u2019\u00e9tude\u00a0et de recherche&#160;; libert\u00e9 du chercheur posant sur le monde un jugement ind\u00e9pendant des modes et des contraintes&#160;; libert\u00e9 du philosophe allant vers l\u2019histoire mais demeurant philosophe jusqu\u2019\u00e0 la fin, face \u00e0 \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb et devant la mort&#160;; libert\u00e9 d\u2019un d\u00e9mocrate r\u00e9publicain exigeant pour la R\u00e9publique dont il avait compris \u00e0 la fois les vertus et les pathologies, tr\u00e8s jeune, pendant l\u2019affaire Dreyfus&#160;; libert\u00e9 d\u2019un citoyen europ\u00e9en \u00e9pris des nations et des peuples du vieux continent vers lesquels il voyageait souvent avec son \u00e9pouse Florence, n\u00e9e en Italie&#160;; libert\u00e9 d\u2019un penseur politique, adversaire du colonialisme et de l\u2019imp\u00e9rialisme, d\u00e9fenseur d\u2019un \u00ab&#160;fanatisme de l\u2019humanit\u00e9&#160;\u00bb capable de repousser le fanatisme mortel \u00ab&#160;de nationalit\u00e9&#160;\u00bb&#160;; libert\u00e9 de l\u2019intellectuel d\u00e9mocratique tel qu\u2019il s\u2019\u00e9tait affirm\u00e9 d\u00e8s l\u2019affaire Dreyfus \u2014 et \u00e0 laquelle il se r\u00e9f\u00e8re durant la conf\u00e9rence de \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb, s\u2019y pr\u00e9sentant comme \u00ab&#160;&rsquo;lib\u00e9ral&rsquo; en ce sens que j\u2019\u00e9tais anticl\u00e9rical, d\u00e9mocrate, r\u00e9publicain, disons d\u2019un seul mot qui \u00e9tait alors lourd de sens&#160;: un &lsquo;dreyfusard&rsquo;&#160;\u00bb.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00ab&#160;Tel est le si\u00e8cle&#160;\u00bb<\/h2>\n\n\n\n<p>Mon cher ami&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-9-256913' title='Le 13 juin 1937.'><sup>9<\/sup><\/a><\/span><\/span>,\u00a0<\/p>\n\n\n\n<p class=\"comment\">Pour suivre le cheminement de la pens\u00e9e hal\u00e9vyenne, l\u2019\u00e9criture \u00e9pistolaire est tout \u00e0 fait essentielle. \u00c9lie Hal\u00e9vy y \u00e9labore ses hypoth\u00e8ses, les soumet \u00e0 ses proches, dialogue avec lui-m\u00eame. En cela, il s\u2019autorise \u00e0 poursuivre l\u2019exploration d\u2019un monde plong\u00e9 dans l\u2019inconnu et l\u2019inconnaissable depuis le d\u00e9clenchement de la guerre mondiale. \u00ab&#160;Il vit d\u00e9sormais dans un autre monde qu\u2019avant la guerre, et personne ne le sait plus que lui. Il l\u2019a compris d\u00e8s apr\u00e8s la bataille de la Marne. Depuis lors, il n\u2019a cess\u00e9 d\u2019\u00e9crire \u00e0 ses amis qu\u2019un nouveau si\u00e8cle venait de commencer&#160;\u00bb, rel\u00e8ve l\u2019historien Fran\u00e7ois Furet dans sa pr\u00e9face \u00e0 l\u2019\u00e9dition de la <em>Correspondance<\/em> de 1996. Ce \u00ab&#160;nouveau si\u00e8cle risque d\u2019\u00eatre aussi tragique que les circonstances qui en ont form\u00e9 le berceau&#160;: l\u2019esprit nationaliste et l\u2019esprit r\u00e9volutionnaire joignant leurs efforts inverses pour faire dispara\u00eetre la libert\u00e9. Tel est d\u00e9sormais le grand souci de sa vie, qui donne \u00e0 sa pens\u00e9e une inqui\u00e9tude proph\u00e9tique&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-10-256913' title='Fran\u00e7ois Furet, Pr\u00e9face \u00e0 \u00c9lie Hal\u00e9vy, &lt;em&gt;Correspondance (1891-1937), &lt;\/em&gt;textes r\u00e9unis et pr\u00e9sent\u00e9s par Henriette Guy-Lo\u00eb et annot\u00e9s par Monique Canto-Sperber, Vincent Duclert et Henriette Guy-Lo\u00eb, Paris, Bernard de Fallois, 1996, p. 49.'><sup>10<\/sup><\/a><\/span><\/span>. \u00c0 l\u2019heure o\u00f9 la tentation illib\u00e9rale du monde et de l\u2019Europe est si prononc\u00e9e, il est sage de relire Hal\u00e9vy, d\u2019apprendre de lui que l\u2019illib\u00e9ralisme est le berceau de la tyrannie, et que la libert\u00e9 ne se n\u00e9gocie jamais.\u00a0<\/p>\n\n\n\n<p class=\"comment\">\u00ab&#160;Nous sommes rentr\u00e9s depuis 1914 en pleine histoire, autrement dit en pleine temp\u00eate&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-11-256913' title='\u00c9lie Hal\u00e9vy, Lettre \u00e0 Daniel Hal\u00e9vy, 5 mars 1933'><sup>11<\/sup><\/a><\/span><\/span>, expose-t-il \u00e0 son fr\u00e8re Daniel dans une lettre de 1933. Voil\u00e0 selon lui le changement majeur provoqu\u00e9 par la guerre. \u00ab&#160;De 1870 \u00e0 1914, nous avons v\u00e9cu \u00e0 l\u2019abri de l\u2019histoire&#160;\u00bb, pr\u00e9cise-t-il. Cette correspondance active \u2014 \u00e0 tous les sens du terme \u2014 ressemble \u00e0 un carnet d\u2019esquisses pour l\u2019analyse de l\u2019accumulation des conflits internationaux comme de l\u2019impuissance des d\u00e9mocraties \u00e0 gouverner leur propre destin. Malgr\u00e9 le pessimisme qui domine ses analyses, \u00c9lie Hal\u00e9vy ne c\u00e8de rien \u00e0 l\u2019exigence de penser en historien et philosophe l\u2019histoire en train de se faire, la plus tragique. L\u2019admettre, la comprendre, c\u2019est d\u00e9j\u00e0 y r\u00e9sister. Deux derni\u00e8res lettres connues d\u2019\u00c9lie Hal\u00e9vy en t\u00e9moignent. Elles sont adress\u00e9es depuis Londres \u00e0 son ami le baron de Meyendorff, et \u00e0 Gabrielle L\u00e9on, la veuve de Xavier L\u00e9on avec lequel il avait cr\u00e9\u00e9 en 1893 <em>La Revue de m\u00e9taphysique et de morale<\/em>.<\/p>\n\n\n\n<p>Je ne voudrais pas avoir quitt\u00e9 Londres sans vous avoir envoy\u00e9 d\u2019ici un mot de souvenir. Dans huit jours, nous serons de retour, sur cet infernal continent. La mort des deux fr\u00e8res Rosselli, tous deux mes amis \u2014\u00a0l\u2019un ennemi redoutable autant qu\u2019acharn\u00e9 de Mussolini, l\u2019autre un antifasciste des plus mod\u00e9r\u00e9s et qui \u00e9tait un historien de valeur\u00a0\u2014, nous plonge dans le deuil. <\/p>\n\n\n\n<p class=\"comment\">Carlo Rosselli (1899-1937), homme politique et historien italien antifasciste, assassin\u00e9 le 9 juin 1937 \u00e0 Bagnoles-de-l\u2019Orne par les activistes d\u2019extr\u00eame-droite de l\u2019organisation de \u00ab&#160;La Cagoule&#160;\u00bb pour le compte du r\u00e9gime fasciste italien. Carlo Rosselli, condamn\u00e9 par le Tribunal sp\u00e9cial fasciste pour avoir organis\u00e9 la fuite en Corse du vieux chef socialiste Filippo Turati, s\u2019\u00e9tait \u00e9vad\u00e9 en 1929 de l\u2019\u00eele de Lipari et avait fond\u00e9 \u00e0 Paris le mouvement <em>Giustizia e Libert\u00e0<\/em>. Quand la guerre civile \u00e9clate en Espagne, il cr\u00e9e en 1936 le premier contingent italien pro-r\u00e9publicain et va lui-m\u00eame se battre en Espagne, d\u2019o\u00f9 il revient bless\u00e9. Ses \u0153uvres principales comprennent <em>Socialisme lib\u00e9ral<\/em> (Paris, Librairie Valois, 1930) et <em>Scritti dell\u2019esilio<\/em> (2 vol. Turin, Einaudi, 1988 et 1992).<\/p>\n\n\n\n<p class=\"comment\">Nello Rosselli (1901-1937), le fr\u00e8re de Carlo, historien lui aussi, avait publi\u00e9 des ouvrages sur Mazzini et Bakounine (1927) et Carlo Pisacane (1932). Il \u00e9tait rest\u00e9 en Italie, bien qu\u2019il ait \u00e9t\u00e9 envoy\u00e9 par deux fois, \u00e0 cause de l\u2019activit\u00e9 de son fr\u00e8re, en r\u00e9sidence forc\u00e9e dans les \u00eeles d\u2019Ustica et de Ponza. Pour ne pas devoir pr\u00eater serment de fid\u00e9lit\u00e9 au r\u00e9gime fasciste, il n\u2019enseigna jamais \u00e0 l\u2019Universit\u00e9. De longues recherches sur les relations entre la Grande-Bretagne et le royaume de Sardaigne de 1815 \u00e0 1847 lui donnent l\u2019occasion de se rendre \u00e0 l\u2019\u00e9tranger et de voir ainsi son fr\u00e8re, g\u00e9n\u00e9ralement dans la province fran\u00e7aise&#160;; c\u2019est ainsi qu\u2019il tombe victime de l\u2019assassinat qui vise surtout Carlo. Ses derni\u00e8res recherches feront l\u2019objet d\u2019une \u00e9dition posthume, en 1954.<\/p>\n\n\n\n<p>Pendant ce temps-l\u00e0, du c\u00f4t\u00e9 (si je puis dire) de chez vous, Staline poursuit le cours de ses sinistres exploits. Apr\u00e8s tout, le Moyen \u00c2ge avait raison. <em>Angli Angeli<\/em>. [\u2026]\u00a0<\/p>\n\n\n\n<p class=\"comment\">\u00c9lie Hal\u00e9vy \u00e9voque ici les grands proc\u00e8s de Moscou qui d\u00e9butent en ao\u00fbt 1936 et qui s\u2019inscrivent dans une politique de terreur et de purge syst\u00e9matique des \u00e9lites sovi\u00e9tiques et russes. Cette fois, Staline s\u2019attaque \u00e0 la veille garde du Parti communiste et aux principaux officiers g\u00e9n\u00e9raux. Ainsi, les chefs de l\u2019Arm\u00e9e rouge, Toukhatchevski, Iakir, Ouborevitch, sont jug\u00e9s et ex\u00e9cut\u00e9s, et un communiqu\u00e9 laconique annonce leur disparition le 11 juin 1937. D\u2019autres se suicident tel Gamarnik, recherch\u00e9 comme \u00ab&#160;complice&#160;\u00bb, qui se donne la mort en mai 1937. Staline d\u00e9capite ainsi la direction de l\u2019Arm\u00e9e rouge, ce qui aura de graves cons\u00e9quences lors de l\u2019attaque allemande de juin 1941 \u00e0 laquelle les Russes seront incapables de s\u2019opposer efficacement.<\/p>\n\n\n\n<p>Des tas d\u2019auteurs viennent d\u2019Europe Centrale parler \u00e0 <em>Chatham House<\/em>, et essayer de secouer les Anges Incarn\u00e9s. \u00ab&#160;Pour l\u2019amour du ciel, si vous voulez laisser l\u2019Allemagne libre de faire tout ce qu\u2019elle veut sur le continent, dites-le explicitement. Ou bien si vous voulez vous opposer \u00e0 ses ambitions, dites-lui non, franchement.&#160;\u00bb Mais les anges ne savent dire ni oui ni non, et continueront \u00e0 ne dire ni l\u2019un ni l\u2019autre.&nbsp;<\/p>\n\n\n\n<p class=\"comment\"><em>Chatham House <\/em>d\u00e9signe le Royal Institute of International Affairs, un centre ind\u00e9pendant de r\u00e9flexion cr\u00e9\u00e9 en 1920 par diff\u00e9rentes personnalit\u00e9s connues d\u2019\u00c9lie Hal\u00e9vy, le colonel Edward Mandel House, le Vicomte Robert Cecil et Norman Angell. Le 24 avril 1934, \u00c9lie Hal\u00e9vy y a prononc\u00e9 une conf\u00e9rence,<em> \u00ab&#160;<\/em>Socialism and the Problem of Democratic Parliamentarianism<em>&#160;\u00bb<\/em> dont le texte est repris dans<em> L\u2019\u00c8re des tyrannies<\/em>.<\/p>\n\n\n\n<p>Quelle est donc cette ligne de navigation qui vous conduisit, madame de Meyendorff et vous-m\u00eame, de Rotterdam en Finlande&#160;? Il n\u2019est pas probable que nous fassions encore cet \u00e9t\u00e9 le voyage de Viborg. Mais qui sait&#160;? Et il est toujours bon d\u2019avoir les renseignements n\u00e9cessaires dans sa poche. R\u00e9pondez-moi \u00e0 Sucy, o\u00f9 nous serons le 20 au soir.<\/p>\n\n\n\n<p class=\"comment\">On doit lire ici les inqui\u00e9tudes d\u2019\u00c9lie Hal\u00e9vy pour sa sant\u00e9. Il a consult\u00e9 un cardiologue \u00e0 Londres apr\u00e8s des alertes s\u00e9rieuses.<\/p>\n\n\n\n<p>Veuillez pr\u00e9senter mes respectueux hommages \u00e0 madame de Meyendorff, et me croire, vous-m\u00eame, votre tr\u00e8s amicalement d\u00e9vou\u00e9&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-right\">\u00c9lie Hal\u00e9vy<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>Ch\u00e8re Gabrielle&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-256913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#easy-footnote-bottom-12-256913' title='Le 15 juin 1937.'><sup>12<\/sup><\/a><\/span><\/span>,<\/p>\n\n\n\n<p>[\u2026] Nous sommes bien \u00e9mus par le double assassinat des fr\u00e8res Rosselli, pour lesquels, principalement Carlo, mais aussi Nello, nous avions beaucoup d\u2019amiti\u00e9. Qu\u2019un homme qui s\u2019est constamment assis \u00e0 votre table, qui vous a rendu visite avec sa femme et ses enfants, ait \u00e9t\u00e9 assassin\u00e9 au coin des bois par les sbires d\u2019un tyran, c\u2019est une impression nouvelle pour moi, et am\u00e8re. Mais je fais cependant une diff\u00e9rence entre les victimes. Carlo, qui avait \u00e9t\u00e9 se battre en Espagne, savait les risques qu\u2019il courait. Mais son malheureux fr\u00e8re, un historien de valeur, antifasciste sans doute mais compl\u00e8tement en dehors de la politique, mari\u00e9 \u00e0 une femme qui n\u2019\u00e9tait rien moins qu\u2019antifasciste, ait pay\u00e9 de ce prix une visite faite par accident \u00e0 Carlo au jour fix\u00e9 par le destin, est vraiment une atrocit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Cette lettre du 15 juin 1937 est la derni\u00e8re qu\u2019il adresse d\u2019outre-Manche. \u00c9lie Hal\u00e9vy s\u2019appr\u00eate \u00e0 quitter l\u2019Angleterre pour revenir \u00ab&#160;sur cet infernal continent&#160;\u00bb. L\u00e0 triomphent les tyrannies, capables d\u00e9sormais de venir dicter leur ordre au sein m\u00eame des d\u00e9mocraties, comme le montre l\u2019assassinat des fr\u00e8res Rosselli, ses amis, d\u00e9cid\u00e9 par Mussolini et ex\u00e9cut\u00e9 par la Cagoule le 9 juin 1937. L\u2019\u00e9loquente protestation d\u2019\u00c9lie Hal\u00e9vy contre la politique d\u2019ind\u00e9cision et d\u2019abaissement des d\u00e9mocraties, l\u2019appel \u00e0 fonder leur action sur une connaissance r\u00e9solue des menaces qu\u2019elles encourent, traduisent l\u2019id\u00e9e qu\u2019il se fait de son r\u00f4le, r\u00f4le modeste mais essentiel que l\u2019on peut d\u00e9finir comme celui de l\u2019intellectuel d\u00e9mocratique. Les \u00e9v\u00e9nements qui s\u2019encha\u00eenent depuis l\u2019automne 1936 confirment la th\u00e8se de l\u2019\u00ab&#160;\u00e8re des tyrannies&#160;\u00bb pr\u00e9sent\u00e9e devant la Soci\u00e9t\u00e9 fran\u00e7aise de philosophie. Ils rendent toujours plus n\u00e9cessaire d\u2019armer la d\u00e9mocratie en revenant \u00e0 ses valeurs fondamentales, afin de lui donner les moyens de r\u00e9sister et m\u00eame de vaincre. Cette pens\u00e9e antitotalitaire qu\u2019avec ses amis \u00c9lie Hal\u00e9vy est le seul \u00e0 d\u00e9finir constitue un engagement intellectuel sans pr\u00e9c\u00e9dent. Sa mise \u00e0 la disposition d\u2019un large public, gr\u00e2ce \u00e0 une \u00e9dition resserr\u00e9e et actualis\u00e9e du livre de 1938, avec une pr\u00e9face \u00e9clairante de Perrine Simon-Nahum, conf\u00e8re \u00e0 l\u2019intellectuel d\u00e9mocratique qu\u2019il incarne une post\u00e9rit\u00e9 nouvelle, n\u00e9cessaire pour aujourd\u2019hui et pour demain. Le legs hal\u00e9vyen est majeur, en particulier dans la force de la caract\u00e9risation du r\u00e9el&nbsp;&#160;: l\u2019 \u00ab&#160;\u00e8re des tyrannies&#160;\u00bb d\u00e9voil\u00e9e est d\u00e9j\u00e0 une d\u00e9faite des tyrannies. Souvenons-nous de cette le\u00e7on d\u2019outre-tombe.&nbsp;<\/p>\n\n\n\n<p>H\u00e9las&nbsp;&#160;! tel est le si\u00e8cle.&nbsp;<\/p>\n\n\n\n<p>Bien affectueusement,&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-right\">\u00c9lie Hal\u00e9vy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En novembre 1936, peu avant sa mort soudaine, \u00c9lie Hal\u00e9vy prononce une conf\u00e9rence \u00e0 \u00ab&#160;&#160;l\u2019inqui\u00e9tude proph\u00e9tique&#160;&#160;\u00bb. Pour lui, la Grande Guerre a engendr\u00e9 de nouvelles formes d\u2019\u00c9tats et d\u2019id\u00e9ologies qui, de l\u2019Allemagne \u00e0 l\u2019Italie en passant par l\u2019Union sovi\u00e9tique, \u00e9crasent les libert\u00e9s individuelles. Il donne un nom \u00e0 cette matrice&#160;&#160;: \u00ab&#160;&#160;l\u2019\u00e8re des tyrannies&#160;&#160;\u00bb. Nous publions ce texte ainsi que les deux derni\u00e8res lettres envoy\u00e9es par son auteur \u2014 introduits et comment\u00e9s par l\u2019historien Vincent Duclert.<\/p>\n<p><a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/politique\/leurope-face-au-fascisme\/\">L&rsquo;Europe face au fascisme \u2014\u00a08\/9<\/a><\/p>\n","protected":false},"author":10,"featured_media":256924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":27,"footnotes":""},"categories":[4187],"tags":[],"staff":[3786],"editorial_format":[4943],"serie":[],"audience":[],"geo":[1917],"class_list":["post-256913","post","type-post","status-publish","format-standard","hentry","category-leurope-face-au-fascisme","staff-vincent-duclert","editorial_format-discours","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":256924,"excerpt":"En novembre 1936, peu avant sa mort soudaine, \u00c9lie Hal\u00e9vy prononce une conf\u00e9rence \u00e0 \u00abl\u2019inqui\u00e9tude proph\u00e9tique\u00bb. Pour lui, la Grande Guerre a engendr\u00e9 de nouvelles formes d\u2019\u00c9tats et d\u2019id\u00e9ologies qui, de l\u2019Allemagne \u00e0 l\u2019Italie en passant par l\u2019Union sovi\u00e9tique, \u00e9crasent les libert\u00e9s individuelles. Il donne un nom \u00e0 cette matrice : \u00abl\u2019\u00e8re des tyrannies\u00bb. Nous publions ce texte ainsi que les deux derni\u00e8res lettres envoy\u00e9es par son auteur \u2014 introduits et comment\u00e9s par l\u2019historien Vincent Duclert.\r\n\r\n<a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/politique\/leurope-face-au-fascisme\/\">L'Europe face au fascisme \u2014\u00a08\/9<\/a>","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abTel est le si\u00e8cle\u00bb: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab\u00e8re des tyrannies\u00bb | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abTel est le si\u00e8cle\u00bb: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab\u00e8re des tyrannies\u00bb | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"En novembre 1936, peu avant sa mort soudaine, \u00c9lie Hal\u00e9vy prononce une conf\u00e9rence \u00e0 \u00ab&#160;l\u2019inqui\u00e9tude proph\u00e9tique&#160;\u00bb. Pour lui, la Grande Guerre a engendr\u00e9 de nouvelles formes d\u2019\u00c9tats et d\u2019id\u00e9ologies qui, de l\u2019Allemagne \u00e0 l\u2019Italie en passant par l\u2019Union sovi\u00e9tique, \u00e9crasent les libert\u00e9s individuelles. Il donne un nom \u00e0 cette matrice&#160;: \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb. Nous publions ce texte ainsi que les deux derni\u00e8res lettres envoy\u00e9es par son auteur \u2014 introduits et comment\u00e9s par l\u2019historien Vincent Duclert.  L&#039;Europe face au fascisme \u2014\u00a08\/9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-03T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/gc-halevy-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/gc-halevy-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/\",\"name\":\"\u00abTel est le si\u00e8cle\u00bb: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab\u00e8re des tyrannies\u00bb | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png\",\"datePublished\":\"2025-01-03T17:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png\",\"width\":4480,\"height\":2520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Tel est le si\u00e8cle&#160;\u00bb&#160;: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab&#160;\u00e8re des tyrannies&#160;\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abTel est le si\u00e8cle\u00bb: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab\u00e8re des tyrannies\u00bb | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00abTel est le si\u00e8cle\u00bb: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab\u00e8re des tyrannies\u00bb | Le Grand Continent","og_description":"En novembre 1936, peu avant sa mort soudaine, \u00c9lie Hal\u00e9vy prononce une conf\u00e9rence \u00e0 \u00ab&#160;l\u2019inqui\u00e9tude proph\u00e9tique&#160;\u00bb. Pour lui, la Grande Guerre a engendr\u00e9 de nouvelles formes d\u2019\u00c9tats et d\u2019id\u00e9ologies qui, de l\u2019Allemagne \u00e0 l\u2019Italie en passant par l\u2019Union sovi\u00e9tique, \u00e9crasent les libert\u00e9s individuelles. Il donne un nom \u00e0 cette matrice&#160;: \u00ab&#160;l\u2019\u00e8re des tyrannies&#160;\u00bb. Nous publions ce texte ainsi que les deux derni\u00e8res lettres envoy\u00e9es par son auteur \u2014 introduits et comment\u00e9s par l\u2019historien Vincent Duclert.  L'Europe face au fascisme \u2014\u00a08\/9","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/","og_site_name":"Le Grand Continent","article_published_time":"2025-01-03T17:00:00+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/gc-halevy-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/gc-halevy-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/","name":"\u00abTel est le si\u00e8cle\u00bb: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab\u00e8re des tyrannies\u00bb | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png","datePublished":"2025-01-03T17:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png","width":4480,"height":2520},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/03\/tel-est-le-siecle-elie-halevy-et-la-resistance-a-lere-des-tyrannies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Tel est le si\u00e8cle&#160;\u00bb&#160;: \u00c9lie Hal\u00e9vy et la r\u00e9sistance \u00e0 l\u2019\u00ab&#160;\u00e8re des tyrannies&#160;\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":4187,"name":"L'Europe face au fascisme&#160;: neuf figures pour s\u2019orienter","slug":"leurope-face-au-fascisme"}],"lgc_author":{"id":3786,"name":"Vincent Duclert","slug":"vincent-duclert","description":"<span style=\"font-weight: 400\">Vincent Duclert, historien, est chercheur titulaire et ancien directeur du Centre Raymond Aron (CESPRA, EHESS-CNRS). Il est sp\u00e9cialiste des soci\u00e9t\u00e9s d\u00e9mocratiques et de l\u2019histoire des g\u00e9nocides. De 2016 \u00e0 2018, il a pr\u00e9sid\u00e9 la Mission d\u2019\u00e9tude en France sur la recherche et l\u2019enseignement des g\u00e9nocides et des crimes de masse et, de 2019 \u00e0 2021, la Commission de recherche sur les archives fran\u00e7aises relatives au Rwanda et au g\u00e9nocide des Tutsi.<\/span>","first_name":"Vincent","last_name":"Duclert","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/imageedit_2_8432666079-modified.png","width":825,"height":825,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png","width":4480,"height":2520,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/01\/Capture-decran-2025-01-03-a-17.13.55.png","width":4480,"height":2520,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/256913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=256913"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/256913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/256924"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=256913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=256913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=256913"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=256913"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=256913"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=256913"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=256913"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=256913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}