{"id":252175,"date":"2024-11-18T15:55:06","date_gmt":"2024-11-18T14:55:06","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=252175"},"modified":"2024-11-18T15:55:08","modified_gmt":"2024-11-18T14:55:08","slug":"quattendre-du-sommet-du-g20-de-rio","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/","title":{"rendered":"Qu\u2019attendre du sommet du G20 de Rio&#160;?"},"content":{"rendered":"\n<p>Bien que l&rsquo;ordre du jour officiel du sommet du G20 qui s\u2019ouvre aujourd\u2019hui \u00e0 Rio comprenne des discussions sur la lutte contre le changement climatique, le financement durable et la transition \u00e9nerg\u00e9tique, la victoire de Trump et l&rsquo;impact de son programme \u00ab&#160;America First&#160;\u00bb sur l&rsquo;\u00e9conomie mondiale devraient largement dominer les \u00e9changes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Joe Biden, qui s&rsquo;est pr\u00e9sent\u00e9 comme un <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/03\/18\/pourquoi-le-sommet-pour-la-democratie-de-biden-est-un-echec\/\">d\u00e9fenseur de la d\u00e9mocratie \u00e0 l&rsquo;\u00e9chelle mondiale<\/a>, se trouvera dans la difficile position de devoir rassurer ses homologues quant \u00e0 l&rsquo;engagement futur des \u00c9tats-Unis sur la sc\u00e8ne internationale.<\/li>\n\n\n\n<li>L\u2019\u00e9lection de Trump et son entr\u00e9e en fonction le 20 janvier ont d\u00e9j\u00e0 des cons\u00e9quences sur la lutte contre le changement climatique&#160;: Javier Milei a retir\u00e9 la semaine derni\u00e8re sa d\u00e9l\u00e9gation de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/11\/la-cop-29-de-bakou-est-elle-ratee-davance\/\">la COP 29, qui se d\u00e9roule jusqu&rsquo;\u00e0 vendredi \u00e0 Bakou<\/a>, en Azerba\u00efdjan.<\/li>\n\n\n\n<li>Selon le minist\u00e8re des Affaires \u00e9trang\u00e8res argentin, cette d\u00e9cision serait due \u00e0 une \u00ab&#160;r\u00e9\u00e9valuation de la situation et \u00e0 une r\u00e9flexion&#160;\u00bb. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/18\/javier-milei-en-10-phrases-choc-le-paleolibertaire-qui-veut-prendre-largentine\/\">Milei<\/a>, l\u2019un des dirigeants les plus proches du pr\u00e9sident-\u00e9lu, a \u00e9t\u00e9 re\u00e7u par Donald Trump \u00e0 Mar-a-Lago le 14 novembre.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/DWUUW\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Les membres du G20 devraient r\u00e9affirmer au cours du sommet \u00ab&#160;un engagement fort en faveur du multilat\u00e9ralisme, en particulier \u00e0 la lumi\u00e8re des progr\u00e8s r\u00e9alis\u00e9s dans le cadre de l&rsquo;Accord de Paris&#160;\u00bb et souligner \u00ab&#160;la n\u00e9cessit\u00e9 de garantir un syst\u00e8me commercial multilat\u00e9ral fond\u00e9 sur des r\u00e8gles, non discriminatoire, juste, ouvert, inclusif, \u00e9quitable, durable et transparent, avec l&rsquo;OMC au c\u0153ur de ce syst\u00e8me&#160;\u00bb.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/YJAh8\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La partie concernant la g\u00e9opolitique \u2014 et donc la guerre en Ukraine \u2014 reste quant \u00e0 elle encore \u00e0 n\u00e9gocier.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Russie se f\u00e9licite du fait que, face \u00e0 la \u00ab&#160;politisation actuelle du G20, le Br\u00e9sil s&rsquo;efforce d&rsquo;exercer ses fonctions de pr\u00e9sident [du groupe] en toute impartialit\u00e9, afin de restaurer l&rsquo;esprit de confiance et de solidarit\u00e9 au sein du forum&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-252175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#easy-footnote-bottom-1-252175' title='&lt;a href=&quot;https:\/\/mid.ru\/en\/foreign_policy\/news\/1981883\/&quot;&gt;Press release on Foreign Minister Sergey Lavrov\u2019s upcoming participation in the G20 summit&lt;\/a&gt;, Minist\u00e8re russe des Affaires \u00e9trang\u00e8res, 17 novembre 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>L\u2019insistance de Moscou sur la \u00ab&#160;d\u00e9politisation&#160;\u00bb du G20 en tant qu\u2019espace multipolaire et de ses d\u00e9clarations vise \u00e0 lutter contre <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/09\/24\/isolement-diplomatique-poutine-voyage-deux-fois-moins-a-linternational-depuis-2022\/\">l\u2019isolement diplomatique dont fait l\u2019objet Vladimir Poutine<\/a> depuis 2022.<\/li>\n\n\n\n<li>Tout comme la Russie tente de continuer \u00e0 porter sa voix dans les enceintes internationales auxquelles elle appartient toujours (notamment les Nations unies), elle cherche \u00e9galement \u00e0 \u00e9liminer tout \u00e9l\u00e9ment de langage soulignant ses multiples violations du droit international en Ukraine.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/6Omud\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019an dernier, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/08\/le-sommet-du-g20-2023-souvre-en-inde\/\">\u00e0 New Delhi<\/a>, la d\u00e9claration finale du sommet du G20 soulignait \u00ab&#160;les souffrances humaines et les r\u00e9percussions n\u00e9gatives de la guerre en Ukraine&#160;\u00bb, sans pour autant attribuer la responsabilit\u00e9 \u00e0 Moscou \u2014 un \u00e9l\u00e9ment qui se trouvait pourtant dans la d\u00e9claration de Bali de novembre 2022. Cette ann\u00e9e, \u00e0 Rio, les membres du G20 semblent pour le moment pencher vers une r\u00e9p\u00e9tition du format du communiqu\u00e9 de 2023&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-252175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#easy-footnote-bottom-2-252175' title='Lisandra Paraguassu, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/world\/g20-diplomats-hit-snags-climate-taxation-ukraine-sources-say-2024-11-16\/&quot;&gt;G20 diplomats hit snags on climate, taxation and Ukraine, sources say&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 16 novembre 2024.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les dirigeants des pays du G20 se r\u00e9unissent aujourd\u2019hui et demain \u00e0 Rio, au Br\u00e9sil, pour le sommet annuel du forum. Seule la Russie n\u2019y sera pas repr\u00e9sent\u00e9e par son chef d\u2019\u00c9tat ou de gouvernement, mais par son ministre des Affaires \u00e9trang\u00e8res, Sergue\u00ef Lavrov. Les \u00e9l\u00e9ments de langage sur l\u2019Ukraine dans la d\u00e9claration finale du sommet t\u00e9moigneront de la capacit\u00e9 de la Russie \u00e0 peser, apr\u00e8s pr\u00e8s de 1 000 jours de guerre, dans l\u2019une des enceintes multilat\u00e9rales parmi les plus diverses.<\/p>\n","protected":false},"author":2622,"featured_media":252182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[1731],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525],"class_list":["post-252175","post","type-post","status-publish","format-standard","hentry","category-politique","editorial_format-actu-breves","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":252182,"excerpt":"Les dirigeants des pays du G20 se r\u00e9unissent aujourd\u2019hui et demain \u00e0 Rio, au Br\u00e9sil, pour le sommet annuel du forum. Seule la Russie n\u2019y sera pas repr\u00e9sent\u00e9e par son chef d\u2019\u00c9tat ou de gouvernement, mais par son ministre des Affaires \u00e9trang\u00e8res, Sergue\u00ef Lavrov. Les \u00e9l\u00e9ments de langage sur l\u2019Ukraine dans la d\u00e9claration finale du sommet t\u00e9moigneront de la capacit\u00e9 de la Russie \u00e0 peser, apr\u00e8s pr\u00e8s de 1 000 jours de guerre, dans l\u2019une des enceintes multilat\u00e9rales parmi les plus diverses.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u2019attendre du sommet du G20 de Rio ? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u2019attendre du sommet du G20 de Rio ? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Les dirigeants des pays du G20 se r\u00e9unissent aujourd\u2019hui et demain \u00e0 Rio, au Br\u00e9sil, pour le sommet annuel du forum. Seule la Russie n\u2019y sera pas repr\u00e9sent\u00e9e par son chef d\u2019\u00c9tat ou de gouvernement, mais par son ministre des Affaires \u00e9trang\u00e8res, Sergue\u00ef Lavrov. Les \u00e9l\u00e9ments de langage sur l\u2019Ukraine dans la d\u00e9claration finale du sommet t\u00e9moigneront de la capacit\u00e9 de la Russie \u00e0 peser, apr\u00e8s pr\u00e8s de 1 000 jours de guerre, dans l\u2019une des enceintes multilat\u00e9rales parmi les plus diverses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-18T14:55:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T14:55:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-share-sommet-G20-Rio.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1750\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-share-sommet-G20-Rio.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/\",\"name\":\"Qu\u2019attendre du sommet du G20 de Rio ? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-sommet-G20-Rio.png\",\"datePublished\":\"2024-11-18T14:55:06+00:00\",\"dateModified\":\"2024-11-18T14:55:08+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-sommet-G20-Rio.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-sommet-G20-Rio.png\",\"width\":1746,\"height\":980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u2019attendre du sommet du G20 de Rio&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u2019attendre du sommet du G20 de Rio ? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu\u2019attendre du sommet du G20 de Rio ? | Le Grand Continent","og_description":"Les dirigeants des pays du G20 se r\u00e9unissent aujourd\u2019hui et demain \u00e0 Rio, au Br\u00e9sil, pour le sommet annuel du forum. Seule la Russie n\u2019y sera pas repr\u00e9sent\u00e9e par son chef d\u2019\u00c9tat ou de gouvernement, mais par son ministre des Affaires \u00e9trang\u00e8res, Sergue\u00ef Lavrov. Les \u00e9l\u00e9ments de langage sur l\u2019Ukraine dans la d\u00e9claration finale du sommet t\u00e9moigneront de la capacit\u00e9 de la Russie \u00e0 peser, apr\u00e8s pr\u00e8s de 1 000 jours de guerre, dans l\u2019une des enceintes multilat\u00e9rales parmi les plus diverses.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/","og_site_name":"Le Grand Continent","article_published_time":"2024-11-18T14:55:06+00:00","article_modified_time":"2024-11-18T14:55:08+00:00","og_image":[{"width":1750,"height":980,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-share-sommet-G20-Rio.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-share-sommet-G20-Rio.png","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/","name":"Qu\u2019attendre du sommet du G20 de Rio ? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-sommet-G20-Rio.png","datePublished":"2024-11-18T14:55:06+00:00","dateModified":"2024-11-18T14:55:08+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-sommet-G20-Rio.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-sommet-G20-Rio.png","width":1746,"height":980},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/18\/quattendre-du-sommet-du-g20-de-rio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Qu\u2019attendre du sommet du G20 de Rio&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/11\/gc-sommet-G20-Rio.png","width":1746,"height":980,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/252175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=252175"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/252175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/252182"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=252175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=252175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=252175"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=252175"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=252175"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=252175"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=252175"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=252175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}