{"id":249087,"date":"2024-10-22T11:01:10","date_gmt":"2024-10-22T09:01:10","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=249087"},"modified":"2024-10-22T11:05:15","modified_gmt":"2024-10-22T09:05:15","slug":"moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/","title":{"rendered":"Moldavie&#160;: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00ab&#160;syndrome Gorbatchev&#160;\u00bb"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Lors de sa conf\u00e9rence de presse <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/21\/referendum-sur-lue-en-moldavie-la-carte-dun-vote-sur-le-fil-du-rasoir-2\/\">au soir du r\u00e9f\u00e9rendum du 20 octobre 2024<\/a>, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/22\/ladhesion-de-la-moldavie-a-lunion-est-une-question-existentielle-une-conversation-avec-maia-sandu\/\">la pr\u00e9sidente Maia Sandu<\/a>, qui briguait en m\u00eame temps un second mandat pr\u00e9sidentiel, a d\u00e9clar\u00e9 que la Moldavie avait \u00e9t\u00e9 confront\u00e9e \u00e0 \u00ab&#160;une attaque sans pr\u00e9c\u00e9dent contre la libert\u00e9 et la d\u00e9mocratie le jour des \u00e9lections et ces derniers mois&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-1-249087' title='&lt;a href=&quot;https:\/\/www.ipn.md\/ro\/maia-sandu-moldova-s-a-confruntat-cu-un-atac-8013_1108280.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Maia Sandu&amp;#160;: Moldova s-a confruntat cu un atac f\u0103r\u0103 precedent. \u021ainta au fost 300 de mii de voturi | IPN&lt;\/a&gt;'><sup>1<\/sup><\/a><\/span><\/span>. Parlant d\u2019un vol de 300\u00a0000 voix, elle d\u00e9clare \u00e9galement \u00e0 cette occasion que \u00ab&#160;des groupes criminels travaillant de concert avec des forces \u00e9trang\u00e8res hostiles \u00e0 nos int\u00e9r\u00eats nationaux ont attaqu\u00e9 notre pays avec des dizaines de millions d\u2019euros&#160;\u00bb. En cause&#160;: Ilan Shor, sulfureux homme politique moldave et leader du bloc \u00ab&#160;victoire&#160;\u00bb lanc\u00e9 en avril 2024 \u00e0 Moscou, qui vit actuellement en Russie. Objet de diff\u00e9rentes enqu\u00eates pour corruption et fraudes, la police a notamment communiqu\u00e9 quelques jours avant le scrutin que ce dernier aurait soudoy\u00e9 pr\u00e8s de 130\u00a0000 \u00e9lecteurs&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-2-249087' title='&lt;a href=&quot;https:\/\/adevarul.ro\/stiri-externe\/republica-moldova\/politia-de-la-chisinau-peste-130000-de-2392130.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Poli\u021bia de la Chi\u0219in\u0103u&amp;#160;: 130.000 de moldoveni, mitui\u021bi de gruparea \u0218or ca s\u0103 voteze contra referendumului pe tema UE | adevarul.ro&lt;\/a&gt;'><sup>2<\/sup><\/a><\/span><\/span>. Allant dans le sens de la pr\u00e9sidente Sandu, le porte-parole de la Commission europ\u00e9enne, Peter Stano, a avanc\u00e9 que \u00ab&#160;ce vote s\u2019est d\u00e9roul\u00e9 sous l\u2019ing\u00e9rence et l\u2019intimidation sans pr\u00e9c\u00e9dent de la Russie et de ses mandataires, dans le but de d\u00e9stabiliser les processus d\u00e9mocratiques en R\u00e9publique de Moldavie&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-3-249087' title='&lt;a href=&quot;https:\/\/www.reuters.com\/world\/europe\/eu-slams-unprecedented-interference-by-russia-moldova-referendum-2024-10-21\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;EU slams &amp;lsquo;unprecedented interference&amp;rsquo; by Russia in Moldova referendum | Reuters&lt;\/a&gt;'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Du c\u00f4t\u00e9 de l\u2019opposition, ce m\u00eame Shor a mis en doute la sinc\u00e9rit\u00e9 du vote&#160;: \u00ab&#160;Nous avons vu ces donn\u00e9es vers minuit. Puis ils ont commenc\u00e9 \u00e0 compter les votes de la diaspora. On nous a dit qu\u2019environ 250 000 personnes avaient vot\u00e9 (&#8230;). Au moment o\u00f9 ces bureaux de vote \u00e9taient vides, nous avons constat\u00e9 une augmentation fictive de la participation dans les bureaux de vote \u00e9trangers sur le site web de la CEC\u00a0[Commission \u00e9lectorale centrale]&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-4-249087' title='&lt;a href=&quot;https:\/\/lenta.ru\/articles\/2024\/10\/22\/moldavia\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;\u0421\u0435\u044f\u043b\u0438 \u0441\u0442\u0440\u0430\u0445 \u0438 \u043f\u0430\u043d\u0438\u043a\u0443&amp;#160;\u00bb \u041c\u043e\u043b\u0434\u0430\u0432\u0438\u044f \u043f\u0440\u043e\u0433\u043e\u043b\u043e\u0441\u043e\u0432\u0430\u043b\u0430 \u0437\u0430 \u0432\u0441\u0442\u0443\u043f\u043b\u0435\u043d\u0438\u0435 \u0432 \u0415\u0421. \u041f\u043e\u0447\u0435\u043c\u0443 \u043f\u043e\u043b\u043e\u0432\u0438\u043d\u0430 \u0441\u0442\u0440\u0430\u043d\u044b \u0441 \u044d\u0442\u0438\u043c \u043d\u0435 \u0441\u043e\u0433\u043b\u0430\u0441\u0438\u043b\u0430\u0441\u044c&amp;#160;?&lt;\/a&gt;'><sup>4<\/sup><\/a><\/span><\/span>. L\u2019opposition a \u00e9galement pu critiquer le fait que seuls deux bureaux de vote ont \u00e9t\u00e9 ouverts en Russie, uniquement \u00e0 Moscou contre cinq r\u00e9clam\u00e9s par la Commission \u00e9lectorale centrale&#160;; ce faible nombre de bureaux contraste avec un nombre beaucoup plus \u00e9lev\u00e9 dans les \u00c9tats-membres de l\u2019Union et en Am\u00e9rique du Nord. Le porte-parole du Kremlin, Dmitri Peskov, a pour sa part qualifi\u00e9 la campagne \u00e9lectorale moldave de \u00ab&#160;non libre&#160;\u00bb, se plaignant que l\u2019opposition n\u2019avait pas eu la possibilit\u00e9 de faire campagne et avait \u00e9t\u00e9 soumise \u00e0 la r\u00e9pression des autorit\u00e9s&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-5-249087' title='&lt;a href=&quot;https:\/\/www.reuters.com\/world\/europe\/kremlin-says-moldovas-elections-were-not-free-results-raise-many-questions-2024-10-21\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Kremlin says Moldova&amp;rsquo;s elections were not free and results raise questions | Reuters&lt;\/a&gt;'><sup>5<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Une participation d\u2019\u00e0 peine un \u00e9lecteur sur deux pour un r\u00e9sultat aussi \u00e9triqu\u00e9 appara\u00eet comme un relatif insucc\u00e8s \u2014 d\u2019autant que des membres de l\u2019opposition avait appel\u00e9 au boycott, permettant paradoxalement la victoire du oui.<\/p><cite>Florent Parmentier<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Au-del\u00e0 de ces passes d\u2019armes politiciennes, il convient de revenir au scrutin lui-m\u00eame. L&rsquo;id\u00e9e d&rsquo;un r\u00e9f\u00e9rendum constitutionnel organis\u00e9 le m\u00eame jour que l&rsquo;\u00e9lection pr\u00e9sidentielle a \u00e9t\u00e9 lanc\u00e9e par la Pr\u00e9sidente de la Moldavie elle-m\u00eame \u00e0 la fin de l&rsquo;ann\u00e9e 2023, lorsqu&rsquo;elle a annonc\u00e9 son intention de briguer un nouveau mandat. \u00c0 la demande de Maia Sandu, la faction PAS du Parlement a entam\u00e9 le processus de modification de la l\u00e9gislation \u00e9lectorale et a approuv\u00e9 l&rsquo;amendement de la loi, permettant ainsi d&rsquo;organiser simultan\u00e9ment une \u00e9lection pr\u00e9sidentielle et un r\u00e9f\u00e9rendum r\u00e9publicain. D\u00e8s lors, la pr\u00e9sidente et les membres du PAS ont investi un capital politique cons\u00e9quent \u00e0 l\u2019occasion de ce r\u00e9f\u00e9rendum, y voyant un moyen d\u2019ancrer d\u00e9finitivement l\u2019orientation europ\u00e9enne du pays, mais aussi d\u2019utiliser des ressources administratives pour faire campagne. Dans ce contexte, une participation d\u2019\u00e0 peine un \u00e9lecteur sur deux pour un r\u00e9sultat aussi \u00e9triqu\u00e9 appara\u00eet comme un relatif insucc\u00e8s, d\u2019autant que des membres de l\u2019opposition avait appel\u00e9 au boycott, permettant paradoxalement la victoire du oui. En r\u00e9alit\u00e9, cela signifie que seul un quart des inscrits a vot\u00e9 en faveur du oui \u00e0 l\u2019int\u00e9gration europ\u00e9enne.&nbsp;<\/p>\n\n\n\n<p>Concr\u00e8tement, le r\u00e9f\u00e9rendum avait pour enjeu l\u2019insertion du texte suivant dans le pr\u00e9ambule de la Constitution&#160;:<\/p>\n\n\n\n<p><em>\u00ab&#160;R\u00c9AFFIRMANT l\u2019identit\u00e9 europ\u00e9enne du peuple de la R\u00e9publique de Moldavie et l\u2019irr\u00e9versibilit\u00e9 de la trajectoire europ\u00e9enne de la R\u00e9publique de Moldavie,\u00a0<\/em><br><em>D\u00c9CLARANT que l\u2019int\u00e9gration dans l\u2019Union europ\u00e9enne est un objectif strat\u00e9gique de la R\u00e9publique de Moldavie&#160;\u00bb.<\/em><\/p>\n\n\n\n<p>En d\u2019autres termes, le r\u00e9f\u00e9rendum avait pour objet de constitutionnaliser une orientation de politique \u00e9trang\u00e8re, en faveur de l\u2019Union europ\u00e9enne. L\u2019enjeu est donc juridique, mais \u00e9galement politique, suivant les exemples g\u00e9orgien et ukrainien. Du fait de la neutralit\u00e9 inscrite dans la Constitution, le r\u00e9f\u00e9rendum ne concernait pas l\u2019OTAN \u2014 dont le taux de popularit\u00e9 est bien moindre que celui de l\u2019Union europ\u00e9enne. Pour \u00eatre valide, un tiers des \u00e9lecteurs inscrits sur les listes \u00e9lectorales&nbsp;devait participer au scrutin&#160;: pr\u00e9c\u00e9demment, le r\u00e9f\u00e9rendum constitutionnel du 5 septembre 2010 sur l\u2019\u00e9lection du pr\u00e9sident au suffrage universel direct avait pr\u00e9cis\u00e9ment \u00e9t\u00e9 rejet\u00e9 pour en raison d\u2019une participation insuffisante.<\/p>\n\n\n\n<p>Alors que le non \u00e0 l\u2019Union dominait les r\u00e9sultats la majeure partie de la soir\u00e9e, le oui l\u2019a finalement emport\u00e9 au matin avec 50,38&#160;% des voix \u2014 environ 750\u00a0000 voix contre 739\u00a0000, soit une avance de 5 voix par bureau de vote. Ce r\u00e9sultat masque de grands \u00e9carts dans les r\u00e9sultats\u00a0selon les bureaux de vote&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-6-249087' title='Les chiffres sont ceux de la Commission \u00e9lectorale centrale&amp;#160;: &lt;a href=&quot;https:\/\/pv.cec.md\/cec-template-referendum-results.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/pv.cec.md\/cec-template-referendum-results.html&lt;\/a&gt;'><sup>6<\/sup><\/a><\/span><\/span>&#160;: la diaspora a jou\u00e9 un r\u00f4le essentiel dans la victoire du oui, ayant convaincu 77&#160;% des quelques 235\u00a0000 votants. Ce r\u00e9sultat, certes cons\u00e9quent, n\u2019est toutefois pas aussi \u00e9lev\u00e9 que celui qui avait soutenu Maia Sandu au second tour de la pr\u00e9sidentielle en 2020. Par contraste, seuls un peu plus de 5&#160;% des \u00e9lecteurs de la r\u00e9gion de Gagaouzie ont vot\u00e9 en faveur du oui au r\u00e9f\u00e9rendum, une r\u00e9gion il est vrai domin\u00e9e par une partisane d\u2019Ilan Shor, la <em>bashkan<\/em> (cheffe de la r\u00e9gion autonome) Evghenia Hutsul. Ce taux est substantiellement plus bas que celui de la r\u00e9gion s\u00e9paratiste de Transnistrie, \u00e0 l\u2019Est du pays, qui quant \u00e0 elle a tout de m\u00eame vu 31&#160;% des suffrages exprim\u00e9s pour le oui. Plusieurs r\u00e9gions (<em>raions<\/em>) du nord de la Moldavie ont d\u2019ailleurs obtenu des scores moins \u00e9lev\u00e9s en faveur de l\u2019int\u00e9gration europ\u00e9enne, comme Ocnita (21&#160;%), Donduseni (27,2&#160;%) et Briceni (28,6&#160;%). Au total, il appara\u00eet qu\u2019une majorit\u00e9 des <em>raions<\/em> ont rejet\u00e9 le r\u00e9f\u00e9rendum.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/9siyr\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Les r\u00e9sultats \u00e9triqu\u00e9s du r\u00e9f\u00e9rendum conduisent certains observateurs \u00e0 parler de \u00ab&#160;syndrome Gorbatchev&#160;\u00bb\u00a0\u00e0 propos de Maia Sandu&#160;: extr\u00eamement populaire \u00e0 l\u2019\u00e9tranger, notamment aupr\u00e8s de l\u2019Union europ\u00e9enne, elle suscite le rejet d\u2019une partie significative des gens vivant en Moldavie. Ce d\u00e9calage peut interroger dans la mesure o\u00f9 jamais la Moldavie n\u2019a b\u00e9n\u00e9fici\u00e9 d\u2019autant d\u2019attention et de soutien que depuis la guerre en Ukraine, y compris pour aider le pays dans sa lutte contre la d\u00e9sinformation en provenance de Russie. Si cette derni\u00e8re constitue une menace bien r\u00e9elle, expliquer tout \u00e9chec \u00e9lectoral par l\u2019influence russe fait l\u2019impasse sur les questions \u00e9conomiques (inflation, pauvret\u00e9) ou l\u2019\u00e9chec de r\u00e9formes (par exemple en mati\u00e8re de justice). <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/26\/politique-technocratie-et-mondialisation-a-lepreuve-des-guerres-culturelles\/\">On retrouve ici ce que Giovanni Orsina avait nomm\u00e9 la dialectique du \u00ab&#160;ou\u00ef-dire&#160;\u00bb et du \u00ab&#160;touch\u00e9 du doigt&#160;\u00bb<\/a>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-7-249087' title='Giovanni Orsina, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2023\/10\/26\/politique-technocratie-et-mondialisation-a-lepreuve-des-guerres-culturelles\/&quot;&gt;Politique, technocratie et mondialisation \u00e0 l\u2019\u00e9preuve des guerres culturelles&lt;\/a&gt;&amp;#160;\u00bb, pp.147-168, in le Grand Continent, &lt;em&gt;Fractures de la guerre \u00e9tendue. De l\u2019Ukraine au m\u00e9tavers&lt;\/em&gt;, Paris, Gallimard, 2023.'><sup>7<\/sup><\/a><\/span><\/span>&#160;: le \u00ab&#160;ou\u00ef-dire&#160;\u00bb parle des b\u00e9n\u00e9fices de l\u2019int\u00e9gration europ\u00e9enne pour rompre avec l\u2019\u00e9nergie russe, le \u00ab&#160;touch\u00e9 du doigt&#160;\u00bb observe que les prix de l\u2019\u00e9nergie ont augment\u00e9 depuis le d\u00e9but de la guerre en Ukraine. En mati\u00e8re \u00e9conomique, la perception compte au moins autant que la r\u00e9alit\u00e9, puisque les acteurs moldaves exportent aujourd\u2019hui davantage vers les march\u00e9s europ\u00e9ens que vers la Russie.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les r\u00e9sultats \u00e9triqu\u00e9s du r\u00e9f\u00e9rendum conduisent certains observateurs \u00e0 parler de \u00ab&#160;syndrome Gorbatchev&#160;\u00bb\u00a0\u00e0 propos de Maia Sandu&#160;: extr\u00eamement populaire \u00e0 l\u2019\u00e9tranger, notamment aupr\u00e8s de l\u2019Union, elle suscite le rejet d\u2019une partie significative des gens vivant en Moldavie.<\/p><cite>Florent Parmentier<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ainsi, si le r\u00e9f\u00e9rendum, qui ne r\u00e9pondait \u00e0 aucune obligation, avait pour but d\u2019assurer la r\u00e9\u00e9lection de Maia Sandu et de l\u2019aider \u00e0 renforcer sa l\u00e9gitimit\u00e9, elle ressort fragilis\u00e9e de cette s\u00e9quence politique. En effet, une victoire \u00e9triqu\u00e9e peut plus facilement \u00eatre contest\u00e9e par l\u2019opposition et devenir une cible suppl\u00e9mentaire de la d\u00e9sinformation russe qu\u2019un pl\u00e9biscite. Si Maia Sandu a pu virer en t\u00eate au premier tour de la pr\u00e9sidentielle avec 42,45&#160;% des suffrages, elle ne dispose quasiment pas de r\u00e9servoir de voix. La dynamique de report de l\u2019opposition et dans un degr\u00e9 moindre la mobilisation de la diaspora deviennent d\u00e8s lors les deux facteurs clefs du second tour de scrutin, le r\u00e9sultat du r\u00e9f\u00e9rendum ne pouvant \u00eatre utilis\u00e9 par aucun des deux camps. Il est certes toujours possible de se rassurer en rappelant, comme l\u2019a fait l\u2019ancien Ministre des affaires \u00e9trang\u00e8res Nicu Popescu que \u00ab&#160;m\u00eame une victoire de justesse\u00a0reste une victoire&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-8-249087' title='&lt;a href=&quot;https:\/\/www.ipn.md\/ro\/nicu-popescu-chiar-si-o-victorie-la-limita-este-7965_1108301.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Nicu Popescu&amp;#160;: Chiar \u0219i o victorie la limit\u0103 este tot o victorie&lt;\/a&gt;'><sup>8<\/sup><\/a><\/span><\/span> et de se dire qu\u2019\u00e0 pr\u00e9sent c\u2019est une nouvelle campagne qui s\u2019ouvre pour le second tour. N\u00e9anmoins, le camp de Maia Sandu aborde avec moins de certitudes le second tour qu\u2019elle l\u2019esp\u00e9rait.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/3fusc\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Enfin, il convient par ailleurs de ne pas oublier que des \u00e9lections l\u00e9gislatives auront lieu au plus tard en juillet 2025. Obtenir comme en 2021 une majorit\u00e9 au Parlement sera une t\u00e2che difficile pour le PAS, qui ne parvient pas \u00e0 \u00e9largir son audience et \u00e0 constituer des alliances, y compris avec des partis pro-europ\u00e9ens. Si Maia Sandu parvenait \u00e0 \u00eatre r\u00e9\u00e9lue le 3 novembre prochain, il lui faudra n\u00e9anmoins, dans un r\u00e9gime parlementaire, disposer d\u2019un soutien au Parlement sans lequel elle ne pourra pas mettre en \u0153uvre sa politique. Comme le note justement Dionis Cenusa, le pouvoir l\u00e9gislatif est un \u00e9l\u00e9ment essentiel dans la d\u00e9finition de l\u2019agenda des affaires \u00e9trang\u00e8res&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-249087' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#easy-footnote-bottom-9-249087' title='&lt;a href=&quot;https:\/\/www.ifri.org\/en\/editorials\/moldovas-foreign-policy-after-2024-presidential-elections-staying-eu-path-moving&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Moldova\u2019s Foreign Policy after 2024 Presidential Elections&amp;#160;: Staying on the EU Path, Moving Eastwards or Becoming Multi-vector&amp;#160;? | Ifri&lt;\/a&gt;'><sup>9<\/sup><\/a><\/span><\/span>. D\u00e8s lors, on mesure que l\u2019adoption du r\u00e9f\u00e9rendum n\u2019est qu\u2019une \u00e9tape sur le chemin du rapprochement europ\u00e9en de la Moldavie, qui d\u00e9pendra \u00e9galement des futures \u00e9volutions au sein de l\u2019Union, du sort de la guerre en Ukraine comme du devenir des r\u00e9formes int\u00e9rieures initi\u00e9es par la Moldavie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au r\u00e9f\u00e9rendum sur l\u2019inscription de l\u2019adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne dans la Constitution, pouss\u00e9 par la Pr\u00e9sidente moldave, seul un quart des inscrits a vot\u00e9 en faveur du \u00ab&#160;&#160;oui&#160;&#160;\u00bb dans une campagne fortement marqu\u00e9e par l\u2019ing\u00e9rence russe.<\/p>\n<p>Ce r\u00e9sultat, suffisant pour la faire adopter, ouvre la voie \u00e0 un potentiel retour de flamme politique \u00e0 Chisinau.<\/p>\n<p>Maia Sandu est-elle en train d\u2019\u00eatre victime du \u00ab&#160;&#160;syndrome Gorbatchev&#160;&#160;\u00bb&#160;&#160;?<\/p>\n","protected":false},"author":10,"featured_media":249092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":9,"footnotes":""},"categories":[2980],"tags":[],"staff":[3105],"editorial_format":[4849],"serie":[],"audience":[],"geo":[1917],"class_list":["post-249087","post","type-post","status-publish","format-standard","hentry","category-elections","staff-florent-parmentier","editorial_format-etudes","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":249092,"excerpt":"Au r\u00e9f\u00e9rendum sur l\u2019inscription de l\u2019adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne dans la Constitution, pouss\u00e9 par la Pr\u00e9sidente moldave, seul un quart des inscrits a vot\u00e9 en faveur du \u00aboui\u00bb dans une campagne fortement marqu\u00e9e par l\u2019ing\u00e9rence russe.\r\n\r\nCe r\u00e9sultat, suffisant pour la faire adopter, ouvre la voie \u00e0 un potentiel retour de flamme politique \u00e0 Chisinau.\r\n\r\nMaia Sandu est-elle en train d\u2019\u00eatre victime du \u00absyndrome Gorbatchev\u00bb ?","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Moldavie\u00a0: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00absyndrome Gorbatchev\u00bb | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moldavie\u00a0: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00absyndrome Gorbatchev\u00bb | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Au r\u00e9f\u00e9rendum sur l\u2019inscription de l\u2019adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne dans la Constitution, pouss\u00e9 par la Pr\u00e9sidente moldave, seul un quart des inscrits a vot\u00e9 en faveur du \u00ab&#160;oui&#160;\u00bb dans une campagne fortement marqu\u00e9e par l\u2019ing\u00e9rence russe.  Ce r\u00e9sultat, suffisant pour la faire adopter, ouvre la voie \u00e0 un potentiel retour de flamme politique \u00e0 Chisinau.  Maia Sandu est-elle en train d\u2019\u00eatre victime du \u00ab&#160;syndrome Gorbatchev&#160;\u00bb&#160;?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-22T09:01:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T09:05:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-sandu-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-sandu-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/\",\"name\":\"Moldavie\u00a0: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00absyndrome Gorbatchev\u00bb | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg\",\"datePublished\":\"2024-10-22T09:01:10+00:00\",\"dateModified\":\"2024-10-22T09:05:15+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"La pr\u00e9sidente de la Moldavie, Maia Sandu, lors d'un point de presse apr\u00e8s la fermeture des bureaux de vote pour l'\u00e9lection pr\u00e9sidentielle et le r\u00e9f\u00e9rendum sur l'inscription dans la Constitution de l'adh\u00e9sion du pays \u00e0 l'Union europ\u00e9enne, \u00e0 Chisinau, en Moldavie, t\u00f4t le lundi 21 octobre 2024. \u00a9 AP Photo\/Vadim Ghirda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moldavie&#160;: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00ab&#160;syndrome Gorbatchev&#160;\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moldavie\u00a0: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00absyndrome Gorbatchev\u00bb | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/","og_locale":"fr_FR","og_type":"article","og_title":"Moldavie\u00a0: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00absyndrome Gorbatchev\u00bb | Le Grand Continent","og_description":"Au r\u00e9f\u00e9rendum sur l\u2019inscription de l\u2019adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne dans la Constitution, pouss\u00e9 par la Pr\u00e9sidente moldave, seul un quart des inscrits a vot\u00e9 en faveur du \u00ab&#160;oui&#160;\u00bb dans une campagne fortement marqu\u00e9e par l\u2019ing\u00e9rence russe.  Ce r\u00e9sultat, suffisant pour la faire adopter, ouvre la voie \u00e0 un potentiel retour de flamme politique \u00e0 Chisinau.  Maia Sandu est-elle en train d\u2019\u00eatre victime du \u00ab&#160;syndrome Gorbatchev&#160;\u00bb&#160;?","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/","og_site_name":"Le Grand Continent","article_published_time":"2024-10-22T09:01:10+00:00","article_modified_time":"2024-10-22T09:05:15+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-sandu-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-sandu-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/","name":"Moldavie\u00a0: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00absyndrome Gorbatchev\u00bb | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg","datePublished":"2024-10-22T09:01:10+00:00","dateModified":"2024-10-22T09:05:15+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg","width":2560,"height":1707,"caption":"La pr\u00e9sidente de la Moldavie, Maia Sandu, lors d'un point de presse apr\u00e8s la fermeture des bureaux de vote pour l'\u00e9lection pr\u00e9sidentielle et le r\u00e9f\u00e9rendum sur l'inscription dans la Constitution de l'adh\u00e9sion du pays \u00e0 l'Union europ\u00e9enne, \u00e0 Chisinau, en Moldavie, t\u00f4t le lundi 21 octobre 2024. \u00a9 AP Photo\/Vadim Ghirda"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/22\/moldavie-apres-la-victoire-etriquee-du-referendum-sur-lunion-le-spectre-du-syndrome-gorbatchev\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Moldavie&#160;: apr\u00e8s une victoire \u00e9triqu\u00e9e au r\u00e9f\u00e9rendum sur l\u2019Union, le spectre du \u00ab&#160;syndrome Gorbatchev&#160;\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":2980,"name":"\u00c9lections","slug":"elections"}],"lgc_author":{"id":3105,"name":"Florent Parmentier","slug":"florent-parmentier","description":"Florent Parmentier est secr\u00e9taire g\u00e9n\u00e9ral du Centre de recherches politiques de Sciences Po, ainsi que chercheur-associ\u00e9 au Centre de g\u00e9opolitique de HEC Paris. Docteur en science politique, invit\u00e9 aux universit\u00e9s de Beida (P\u00e9kin), Fudan (Shanghai) et du CEDS (Antananarivo), il enseigne sur les sujets g\u00e9opolitiques et de prospective.","first_name":"Florent","last_name":"Parmentier","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/09\/gc_Florent-Parmentier.png","width":659,"height":646,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/SIPA_ap22912410_000003-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/249087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=249087"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/249087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/249092"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=249087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=249087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=249087"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=249087"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=249087"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=249087"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=249087"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=249087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}