{"id":247850,"date":"2024-10-08T11:43:54","date_gmt":"2024-10-08T09:43:54","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=247850"},"modified":"2024-10-08T11:43:55","modified_gmt":"2024-10-08T09:43:55","slug":"larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/","title":{"rendered":"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia&#160;?"},"content":{"rendered":"\n<p>Le porte-parole des Forces ukrainiennes de d\u00e9fense du Sud, Vladyslav Voloshyn, a d\u00e9clar\u00e9 samedi 5 octobre que des \u00ab&#160;forces russes se rassemblent pour effectuer une perc\u00e9e en direction d&rsquo;Orikhiv et de Mala Tokmachka dans l&rsquo;oblast de Zaporizhzhia dans les jours \u00e0 venir&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-247850' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#easy-footnote-bottom-1-247850' title='Edouard Tkach, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.rbc.ua\/rus\/news\/rf-gotue-novi-shturmi-dvoh-napryamkah-zaporizkoyi-1728138335.html&quot;&gt;\u0420\u0424 \u0433\u043e\u0442\u0443\u0454 \u043d\u043e\u0432\u0456 \u0448\u0442\u0443\u0440\u043c\u0438 \u043d\u0430 \u0434\u0432\u043e\u0445 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0430\u0445 \u0417\u0430\u043f\u043e\u0440\u0456\u0437\u044c\u043a\u043e\u0457 \u043e\u0431\u043b\u0430\u0441\u0442\u0456, &amp;#8211; \u0432\u0456\u0439\u0441\u044c\u043a\u043e\u0432\u0438\u0439&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;\u0420\u0411\u041a-\u0423\u043a\u0440\u0430\u0457\u043d\u0430&lt;\/em&gt;, 5 octobre 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon les renseignements militaires ukrainiens, Moscou y concentre des \u00ab&#160;groupes d\u2019assaut&#160;\u00bb \u2014 soit de petites unit\u00e9s d\u2019infanterie \u2014, du soutien logistique, du renseignement ainsi que des v\u00e9hicules l\u00e9gers.<\/li>\n\n\n\n<li>Ces mouvements sont observ\u00e9s aux alentours du village de Robotyne \u2014 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/28\/a-robotyne-kiev-a-perce-la-premiere-ligne-de-defense-russe\/\">o\u00f9 l\u2019arm\u00e9e ukrainienne avait perc\u00e9 les lignes de d\u00e9fense russes<\/a> \u00e0 la fin de l\u2019\u00e9t\u00e9 2023 lors de sa contre-offensive \u2014, en direction de Mala Tokmachka et d\u2019Orikhiv, \u00e0 une cinquantaine de kilom\u00e8tres au sud-est de la capitale de l\u2019oblast.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/XospU\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019oblast de Zaporijia, \u00e0 l\u2019ouest de Donetsk, a \u00e9t\u00e9 relativement \u00e9pargn\u00e9 par les bombardements et combats qui se sont principalement concentr\u00e9s dans le Donbass depuis le d\u00e9but de l\u2019ann\u00e9e. Avec la r\u00e9cente chute de Vuhledar, l\u2019\u00e9tat-major russe pourrait chercher \u00e0 progresser en direction de Zaporijia afin de couper les lignes logistiques ukrainiennes qui relient les deux oblasts&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-247850' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#easy-footnote-bottom-2-247850' title='Olga Denisyaka, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/hromadske.ua\/viyna\/232440-rosiiany-shturmuvatymut-zaporizkyy-napriamok-shchob-obrizaty-lohistyku-zsu-rechnyk-syl-oborony-pivdnia&quot;&gt;\u0440\u043e\u0441\u0456\u044f\u043d\u0438 \u0448\u0442\u0443\u0440\u043c\u0443\u0432\u0430\u0442\u0438\u043c\u0443\u0442\u044c \u0417\u0430\u043f\u043e\u0440\u0456\u0437\u044c\u043a\u0438\u0439 \u043d\u0430\u043f\u0440\u044f\u043c\u043e\u043a, \u0449\u043e\u0431 \u043e\u0431\u0440\u0456\u0437\u0430\u0442\u0438 \u043b\u043e\u0433\u0456\u0441\u0442\u0438\u043a\u0443 \u0417\u0421\u0423 \u2014 \u0440\u0435\u0447\u043d\u0438\u043a \u0421\u0438\u043b \u043e\u0431\u043e\u0440\u043e\u043d\u0438 \u043f\u0456\u0432\u0434\u043d\u044f&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;\u0413\u0440\u043e\u043c\u0430\u0434\u0441\u044c\u043a\u0435&lt;\/em&gt;, 5 octobre 2024.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/wyBAO\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Certains observateurs se montrent m\u00e9fiants vis-\u00e0-vis de cette menace, pointant plut\u00f4t une potentielle PsyOp (op\u00e9ration psychologique) russe&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-247850' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#easy-footnote-bottom-3-247850' title='V\u00e9ra Konoval, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/24tv.ua\/rosiyani-gotuyut-nastup-zaporizkomu-napryamku-de-mozhut-buti_n2657571&quot;&gt;\u0412\u0436\u0435 \u0433\u043e\u0442\u0443\u044e\u0442\u044c\u0441\u044f \u0434\u043e \u0448\u0442\u0443\u0440\u043c\u0456\u0432&amp;#160;: \u0447\u0438 \u0437\u043c\u043e\u0436\u0443\u0442\u044c \u0440\u043e\u0441\u0456\u044f\u043d\u0438 \u043f\u0440\u043e\u0440\u0432\u0430\u0442\u0438\u0441\u044f \u043d\u0430 \u041f\u0456\u0432\u0434\u043d\u0456&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;24 \u041a\u0430\u043d\u0430\u043b&lt;\/em&gt;, 7 octobre 2024.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Moscou, relay\u00e9 par de nombreux commentateurs affili\u00e9s au Kremlin sur des r\u00e9seaux comme Telegram, lance fr\u00e9quemment ce type d\u2019op\u00e9rations afin de susciter la panique chez les populations et d\u2019inciter Kiev \u00e0 d\u00e9tourner ses ressources militaires.<\/li>\n\n\n\n<li>Cette fois-ci, ces informations sont n\u00e9anmoins confirm\u00e9es par le renseignement militaire ukrainien depuis fin septembre. Entre-temps, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/02\/vuhledar-est-tombee-aux-mains-de-larmee-russe-que-se-passe-t-il-maintenant\/\">Vuhledar, plus \u00e0 l\u2019Est, est tomb\u00e9e<\/a> aux mains des Russes.<\/li>\n\n\n\n<li>Des images g\u00e9olocalis\u00e9es publi\u00e9es dimanche 6 et lundi 7 octobre indiquent que des troupes russes ont marginalement progress\u00e9 en direction de Kamianske, \u00e0 l\u2019ouest de l\u2019oblast de Zaporijia&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-247850' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#easy-footnote-bottom-4-247850' title='Angelica Evans, Nicole Wolkov, Grace Mappes, George Barros et Frederick W. Kagan, &lt;a href=&quot;https:\/\/www.understandingwar.org\/backgrounder\/russian-offensive-campaign-assessment-october-7-2024&quot;&gt;Russian Offensive Campaign Assessment, October 7, 2024&lt;\/a&gt;, Institute for the Study of War.'><sup>4<\/sup><\/a><\/span><\/span>. Il s\u2019agit de la premi\u00e8re tentative russe d\u2019avanc\u00e9e dans ce secteur depuis l\u2019hiver 2022-2023.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/TSPzt\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019objectif principal \u00e0 terme d\u2019une offensive russe sur le front sud serait d\u2019atteindre la capitale \u00e9ponyme de l\u2019oblast de Zaporijia, qui comptait une population de 700 000 habitants en 2022 \u2014 qui n\u2019est pour l\u2019heure pas menac\u00e9e, et qui est prot\u00e9g\u00e9e par plusieurs lignes de fortifications. En raison de l\u2019interd\u00e9pendance des lignes ukrainiennes dans le sud et l\u2019est, toute progression russe dans l\u2019oblast de Donetsk (notamment en direction de Velyka Novossilka) constitue \u00e9galement une menace pour le front sud dans la r\u00e9gion de Zaporijia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019oblast de Zaporijia, \u00e0 l\u2019ouest de Donetsk, a \u00e9t\u00e9 relativement \u00e9pargn\u00e9 par les combats et bombardements depuis le d\u00e9but d\u2019ann\u00e9e en comparaison du Donbass. Ces derniers jours, des sources militaires ukrainiennes alertent cependant sur une concentration de troupes russes pr\u00e8s de Robotyne susceptible de d\u00e9boucher sur un nouvel effort offensif sur le front sud.<\/p>\n","protected":false},"author":2622,"featured_media":247855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-247850","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":247855,"excerpt":"L\u2019oblast de Zaporijia, \u00e0 l\u2019ouest de Donetsk, a \u00e9t\u00e9 relativement \u00e9pargn\u00e9 par les combats et bombardements depuis le d\u00e9but d\u2019ann\u00e9e en comparaison du Donbass. Ces derniers jours, des sources militaires ukrainiennes alertent cependant sur une concentration de troupes russes pr\u00e8s de Robotyne susceptible de d\u00e9boucher sur un nouvel effort offensif sur le front sud.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia ? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia ? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"L\u2019oblast de Zaporijia, \u00e0 l\u2019ouest de Donetsk, a \u00e9t\u00e9 relativement \u00e9pargn\u00e9 par les combats et bombardements depuis le d\u00e9but d\u2019ann\u00e9e en comparaison du Donbass. Ces derniers jours, des sources militaires ukrainiennes alertent cependant sur une concentration de troupes russes pr\u00e8s de Robotyne susceptible de d\u00e9boucher sur un nouvel effort offensif sur le front sud.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T09:43:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-08T09:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-share-menace-front-sud-zapo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1906\" \/>\n\t<meta property=\"og:image:height\" content=\"1070\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-share-menace-front-sud-zapo.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/\",\"name\":\"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia ? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-menace-front-sud-zapo.png\",\"datePublished\":\"2024-10-08T09:43:54+00:00\",\"dateModified\":\"2024-10-08T09:43:55+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-menace-front-sud-zapo.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-menace-front-sud-zapo.png\",\"width\":1910,\"height\":1072},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia ? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia ? | Le Grand Continent","og_description":"L\u2019oblast de Zaporijia, \u00e0 l\u2019ouest de Donetsk, a \u00e9t\u00e9 relativement \u00e9pargn\u00e9 par les combats et bombardements depuis le d\u00e9but d\u2019ann\u00e9e en comparaison du Donbass. Ces derniers jours, des sources militaires ukrainiennes alertent cependant sur une concentration de troupes russes pr\u00e8s de Robotyne susceptible de d\u00e9boucher sur un nouvel effort offensif sur le front sud.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/","og_site_name":"Le Grand Continent","article_published_time":"2024-10-08T09:43:54+00:00","article_modified_time":"2024-10-08T09:43:55+00:00","og_image":[{"width":1906,"height":1070,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-share-menace-front-sud-zapo.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-share-menace-front-sud-zapo.png","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/","name":"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia ? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-menace-front-sud-zapo.png","datePublished":"2024-10-08T09:43:54+00:00","dateModified":"2024-10-08T09:43:55+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-menace-front-sud-zapo.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-menace-front-sud-zapo.png","width":1910,"height":1072},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/10\/08\/larmee-russe-sapprete-t-elle-a-lancer-une-offensive-massive-dans-loblast-de-zaporijia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019arm\u00e9e russe s\u2019appr\u00eate-t-elle \u00e0 lancer une offensive massive dans l\u2019oblast de Zaporijia&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-menace-front-sud-zapo.png","width":1910,"height":1072,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/247850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=247850"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/247850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/247855"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=247850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=247850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=247850"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=247850"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=247850"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=247850"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=247850"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=247850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}