{"id":234594,"date":"2024-06-21T16:24:34","date_gmt":"2024-06-21T14:24:34","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=234594"},"modified":"2024-06-24T09:50:17","modified_gmt":"2024-06-24T07:50:17","slug":"les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/","title":{"rendered":"\u00ab&#160;Les Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa&#160;\u00bb, bilan et perspectives de Pascal Lamy"},"content":{"rendered":"\n<p><em>Cet entretien est \u00e9galement disponible <a href=\"https:\/\/geopolitique.eu\/en\/2024\/06\/24\/the-2024-european-elections-marked-the-end-of-old-fashioned-sovereignism-pascal-lamys-assessment-and-perspectives\/\">en anglais sur le site du Groupe d&rsquo;\u00e9tudes g\u00e9opolitiques<\/a>.<\/em><\/p>\n\n\n\n<p><em>Depuis 2019, nous avons aid\u00e9 plus de 25 millions de personnes \u00e0 comprendre l&rsquo;Europe. Ce travail a un co\u00fbt. Pour le soutenir et contribuer au d\u00e9veloppement de la revue, <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\" target=\"_blank\" rel=\"noreferrer noopener\">abonnez-vous au Grand Continent<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Une dizaine de jours apr\u00e8s, alors qu\u2019au niveau europ\u00e9en commence le processus de nomination des <em>Top Jobs<\/em> et qu\u2019au niveau fran\u00e7ais la dissolution bouleverse l\u2019espace politique, que retenez-vous de <a href=\"https:\/\/legrandcontinent.eu\/fr\/elections\/europeennes-2024\/\">cette grande \u00e9lection europ\u00e9enne<\/a>&#160;?<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Les Europ\u00e9ennes sont des \u00e9lections hybrides. Les interpr\u00e9ter implique de consid\u00e9rer une trajectoire en deux phases, un peu comme un avion qui d\u00e9colle et qui monte en altitude. Vous traversez une zone de turbulences nationales puis vous continuez \u00e0 monter, et \u00e0 ce moment-l\u00e0, vous \u00eates dans une zone o\u00f9 la navigation est plus calme, les lignes plus claires.<\/p>\n\n\n\n<p>\u00c0 l\u2019\u00e9chelle des \u00c9tats il y a des cas particuliers \u2014 en France on est bien plac\u00e9 pour s\u2019en rendre compte \u2014 en fonction du rapport des forces politiques, du moment du cycle politique national, ce qui rend difficile de tirer des conclusions d\u2019ensemble \u00e0 partir de cette \u00e9chelle-l\u00e0. Il en va diff\u00e9remment au niveau europ\u00e9en. Puisque la sc\u00e8ne europ\u00e9enne est la r\u00e9sultante d\u2019une agr\u00e9gation, les \u00e9volutions sont in\u00e9vitablement plus lentes, plus amorties avec des plus et des moins nationaux qui se compensent en partie.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Puisque la sc\u00e8ne europ\u00e9enne est la r\u00e9sultante d\u2019une agr\u00e9gation, les \u00e9volutions sont in\u00e9vitablement plus lentes, plus amorties avec des plus et des moins nationaux qui se compensent en partie.&nbsp;<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L\u2019\u00e9picentre de Paris n\u2019a pas provoqu\u00e9 de tremblement \u00e0 Bruxelles&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>L\u2019approche continentale montre qu\u2019il n\u2019y a pas eu d\u2019\u00e0-coup, mais une lente d\u00e9rive continue. Quand vous regardez les chiffres depuis 1979 sur 50 ans, il y a toujours eu un l\u00e9ger d\u00e9port \u00e0 droite.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium \">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/flo.uri.sh\/visualisation\/18405373\/embed\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Cette fois-ci, c&rsquo;est un peu plus que d&rsquo;habitude, puisque le PPE et les deux groupes d&rsquo;extr\u00eame-droite ont obtenu plus de si\u00e8ges. Mais on n\u2019est pas dans les pr\u00e9visions extr\u00eames o\u00f9 chacun de ces groupes aurait r\u00e9ussi \u00e0 rafler 30 d\u00e9put\u00e9s de plus.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dans ce contexte, l&rsquo;option du deuxi\u00e8me mandat von der Leyen vous semble-t-elle s\u2019imposer&#160;?<\/strong><\/h3>\n\n\n\n<p>La gouvernance europ\u00e9enne est fond\u00e9e sur un syst\u00e8me parlementaire bicam\u00e9ral, avec une chambre haute, celle des \u00c9tats, et une chambre basse, celle du Parlement. Pour ce qui est de la chambre basse, il est probable, bien qu\u2019incertain, que la coalition entre chr\u00e9tien-d\u00e9mocrates, socio-d\u00e9mocrates et centristes qui a soutenu la Commission de la l\u00e9gislature pr\u00e9c\u00e9dente sera reconduite.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/lJCpv\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>On en saura plus dans les prochains jours, mais cette configuration donne \u00e0 Ursula von der Leyen de bonnes chances de devenir la prochaine pr\u00e9sidente de la Commission, c&rsquo;est-\u00e0-dire de se succ\u00e9der \u00e0 elle-m\u00eame. Une continuit\u00e9 bienvenue, je crois, en ces temps terriblement chahut\u00e9s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Avec la dissolution, ou la disparition apparente du Frexit comme option revendiqu\u00e9e par la droite historiquement eurosceptique, <a href=\"https:\/\/legrandcontinent.eu\/fr\/elections\/europeennes-2024\/\">les Europ\u00e9ennes 2024<\/a> marquent-elles une acc\u00e9l\u00e9ration vers l\u2019europ\u00e9anisation de la politique nationale&#160;?<\/strong><\/h3>\n\n\n\n<p>Oui, c\u2019est une interpr\u00e9tation int\u00e9ressante que je partage. L&rsquo;hybridation des \u00e9lections nationales et europ\u00e9ennes a d\u00e9bouch\u00e9 sur des cons\u00e9quences int\u00e9rieures particuli\u00e8rement frappantes du moins dans le cas fran\u00e7ais et peut-\u00eatre, apr\u00e8s l\u2019\u00e9t\u00e9 \u2014 avec l\u2019effet domino des \u00e9lections dans les L\u00e4nder \u2014 dans le cas allemand. J&rsquo;interpr\u00e8te ce <a href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/01\/08\/jalons-pour-une-anthropologie-europeenne\/\">processus qui a une dimension \u00e0 la fois politique et anthropologique<\/a> comme une \u00e9tape dans la construction de l&rsquo;espace unique europ\u00e9en.&nbsp;<\/p>\n\n\n\n<p>L\u2019imbrication des deux \u00e9chelles devient trop intense pour \u00eatre ignor\u00e9e. Il ne sert \u00e0 rien de dire que les \u00e9lections europ\u00e9ennes ne sont pas nationales si en pratique <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/09\/macron-je-dissous-donc-ce-soir-lassemblee-nationale-lannonce-integrale\/\">Emmanuel Macron dissout l&rsquo;Assembl\u00e9e<\/a> et Alexander De Croo d\u00e9missionne apr\u00e8s leurs \u00e9checs respectifs.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L\u2019imbrication des deux \u00e9chelles devient trop intense pour \u00eatre ignor\u00e9e.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>De <\/strong><strong><em>midterms<\/em><\/strong><strong> maudites \u2014 <\/strong><a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/13\/le-rn-pourrait-devenir-le-premier-parti-dans-lhistoire-de-la-cinquieme-republique-a-remporter-successivement-des-elections-europeennes-et-legislatives\/\"><strong>en France le gagnant perdait syst\u00e9matiquement la pr\u00e9sidentielle et les l\u00e9gislatives qui suivaient<\/strong><\/a><strong> \u2014 les Europ\u00e9ennes changent-elles de r\u00f4le&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Cette hybridation est aussi dynamique. Les \u00e9lections europ\u00e9ennes, bien qu\u2019elles soient \u00e0 un tour, vont avoir un deuxi\u00e8me tour qui sera purement national, \u2014 et puis peut-\u00eatre un troisi\u00e8me tour, si le r\u00e9sultat de ces \u00e9lections nationales am\u00e8ne \u00e0 une position diff\u00e9rente du gouvernement fran\u00e7ais au Conseil des ministres.&nbsp;<\/p>\n\n\n\n<p>Bien s\u00fbr en France le r\u00e9gime pr\u00e9sidentiel se r\u00e9serve la mainmise sur l&rsquo;international, la diplomatie et l&rsquo;Europe. N\u00e9anmoins, le rapport de force peut changer ces \u00e9quilibres. On peut penser qu&rsquo;un gouvernement Bardella \u2014 une hypoth\u00e8se qui ne me para\u00eet pas, h\u00e9las, de mon point de vue, improbable \u2014 voudra imprimer sa marque sur certains chantiers europ\u00e9ens.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" style=\"color:#000000;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tPortrait d&rsquo;un monde cass\u00e9\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#000000;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Sous la direction de Giuliano da Empoli.<\/p>\n<p>Avec les contributions d\u2019Anu Bradford, Josep Borrell, Julia Cag\u00e9, Javier Cercas, Dipesh Chakrabarty, Pierre Charbonnier, Aude Darnal, Jean-Yves Dormagen, Niall Ferguson, Timothy Garton Ash, Jean-Marc Jancovici, Paul Magnette, Hugo Micheron, Branko Milanovic, Nicholas Mulder, Vladislav Sourkov, Bruno Tertrais, Isabella Weber, Lea Ypi.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/portrait-dun-monde-casse\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Commandez le num\u00e9ro<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrez toutes nos offres<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#000000;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><strong><span style=\"text-decoration: underline\"><a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/portrait-dun-monde-casse\/\">Commandez le nouveau num\u00e9ro papier<\/a><\/span> du Grand Continent chez Gallimard qui para\u00eet cette semaine ou <span style=\"text-decoration: underline\"><a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\">cliquez ici pour vous abonner et recevoir l\u2019int\u00e9gralit\u00e9 de nos produits<\/a><\/span>.<\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/mediamodifier_image-5-1-7-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>Cette fois-ci, l\u2019imbrication ne serait pas statique, mais dynamique, en cr\u00e9ant une situation qui se r\u00e9verb\u00e8re au niveau national, puis de nouveau sans doute au niveau europ\u00e9en. Quelles que soient les vicissitudes du moment ou les pr\u00e9f\u00e9rences politiques que l&rsquo;on peut avoir, la construction d\u2019un espace d\u00e9mocratique europ\u00e9en hybride, c&rsquo;est-\u00e0-dire \u00e0 la fois national et supranational, est bel et bien en cours.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>On peut penser qu&rsquo;un gouvernement Bardella voudra imprimer sa marque sur certains chantiers europ\u00e9ens.&nbsp;<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Avant de revenir sur le cas fran\u00e7ais, concentrons-nous sur cette id\u00e9e d&rsquo;un glissement qui n&rsquo;aurait toutefois pas d\u2019effet majeur, en installant m\u00eame une forme de continuit\u00e9 avec la r\u00e9\u00e9lection de la pr\u00e9sidente de la Commission. Vous avez vous-m\u00eame d\u00e9montr\u00e9 dans <\/strong><a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/12\/lunion-europeenne-est-elle-toujours-pertinente-une-conversation-avec-pascal-lamy\/\"><strong>l\u2019un de nos entretiens<\/strong><\/a><strong> que l\u2019axe structurant de von der Leyen \u2014 mais peut-\u00eatre m\u00eame de l\u2019inertie europ\u00e9enne qui l&rsquo;a pr\u00e9c\u00e9d\u00e9 \u2014 c&rsquo;\u00e9tait le Pacte vert. Malgr\u00e9 les effets de surface et de continuit\u00e9, ne faisons-nous pas face \u00e0 un changement de cap&#160;?<\/strong><\/h3>\n\n\n\n<p>Je ne pense pas que ce glissement n\u2019affecte pas tant la direction que la d\u00e9riv\u00e9e \u2014 au sens math\u00e9matique du terme. C&rsquo;est-\u00e0-dire que la direction ne changera pas, mais&nbsp;pourra \u00eatre ralentie dans sa mise en \u0153uvre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pourquoi&#160;?<\/strong><\/h3>\n\n\n\n<p>Pour deux raisons. La premi\u00e8re est d&rsquo;ordre juridique&#160;: l&rsquo;essentiel des blocs l\u00e9gislatifs du Pacte vert sont en place, y compris la trajectoire de d\u00e9carbonation d&rsquo;ici 2050. Et avec l\u2019adoption miracle, cette semaine,&nbsp;de la loi sur la restauration de la nature gr\u00e2ce \u00e0 la courageuse indiscipline de L\u00e9onore Gewesler en Autriche, on est d\u00e9sormais plut\u00f4t dans la mise en \u0153uvre. Elle peut certes \u00eatre plus ou moins ralentie en fonction des vues du nouveau Parlement europ\u00e9en. Mais je pense que les changements s&rsquo;exprimeront autrement. Par exemple dans la composition de la Commission.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/V0IgM\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Le Conseil des ministres est nettement plus \u00e0 droite qu&rsquo;il y a cinq ans&#160;: il n&rsquo;y a plus que quatre gouvernements socio-d\u00e9mocrates en Europe, dont deux \u2014 l&rsquo;Allemagne et l&rsquo;Espagne \u2014 p\u00e8sent fortement, mais ils ne sont pas dans une position confortable. Les autres sont soit des lib\u00e9raux, soit des chr\u00e9tiens-d\u00e9mocrates, soit des forces qui sont plus \u00e0 droite que les chr\u00e9tiens d\u00e9mocrates, \u00e0 commencer par Giorgia Meloni.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le Conseil des ministres est nettement plus \u00e0 droite qu&rsquo;il y a cinq ans.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle est la deuxi\u00e8me raison&#160;?<\/strong><\/h3>\n\n\n\n<p>Dans la structure des opinions europ\u00e9ennes la question environnementale demeure d\u00e9terminante comme l\u2019a montr\u00e9 une \u00e9tude r\u00e9cente du centre Jacques Delors \u00e0 Berlin. Il est vrai qu\u2019elle n&rsquo;a pas fait l&rsquo;objet de l&rsquo;essentiel du d\u00e9bat au niveau de l&rsquo;\u00e9lection europ\u00e9enne. Mais les raisons tiennent \u00e0 son caract\u00e8re hybride. Le seul sujet qui est apparu, et contre lequel se sont prononc\u00e9es les forces d&rsquo;extr\u00eame droite, c&rsquo;est l&rsquo;interdiction de la vente de voitures thermiques neuves en 2035. J\u2019y vois plus l\u2019effet d\u2019une cristallisation provoqu\u00e9e par une date butoir&#160;: on comprend qu&rsquo;il y a des personnes qui ne veulent pas \u00eatre oblig\u00e9s de changer leur voiture. Mais pour les autres mesures les sondages et les \u00e9tudes d&rsquo;opinion montrent que la population europ\u00e9enne, dans ses structures id\u00e9ologiques profondes, reste pro-environnement, concernant la d\u00e9carbonation et aussi sur les questions de biodiversit\u00e9, m\u00eame si on en parle moins.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000072-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000072-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000072-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000072-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000072-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 Eliot Blondet\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous parlez d&rsquo;un glissement vers la droite, progressif et de longue dur\u00e9e. Mais \u00e0 bien regarder dans ces forces on observe un changement tectonique&#160;: les groupes qui \u00e9taient \u00e0 la droite du Parti populaire europ\u00e9en pr\u00e9sentaient une dimension eurosceptique \u00e9vidente. Aujourd\u2019hui le RN de Bardella obtient un score historique en ne soutenant plus explicitement le Frexit, alors que les seules forces qui sont pour le Frexit cumulent moins de 3&#160;%. Comment expliquez-vous cette conversion \u00e0 l\u2019Europe&#160;? Pensez-vous qu\u2019elle soit uniquement tactique et rh\u00e9torique&#160;? Est-ce qu\u2019elle change les \u00e9quilibres au sein du Parlement&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>C&rsquo;est la confirmation d&rsquo;un mouvement que le Grand Continent a d\u2019ailleurs, tout \u00e0 son honneur, identifi\u00e9 avant les autres, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/06\/21\/la-doctrine-dorban\/\">en faisant appara\u00eetre le r\u00f4le gramscien de Viktor Orb\u00e1n dans ce glissement.<\/a><\/p>\n\n\n\n<p>Il a \u00e9t\u00e9 celui qui a fait basculer l&rsquo;extr\u00eame droite des positions anti-europ\u00e9ennes du souverainisme \u00e0 la papa&#160;: \u00ab&#160;sortie de l&rsquo;Europe, \u00e0 bas l&rsquo;Europe, vive la nation&#160;\u00bb, \u00e0&#160;: \u00ab&#160;notre objectif c&rsquo;est de participer au pouvoir europ\u00e9en, d&rsquo;exercer le pouvoir europ\u00e9en, et donc on fera \u00e7a de dedans, au lieu de pr\u00e9tendre qu&rsquo;il faut \u00eatre dehors&#160;\u00bb.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Orb\u00e1n a fait sortir l&rsquo;extr\u00eame droite des positions anti-europ\u00e9ennes du souverainisme \u00e0 la papa.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Une partie des eurosceptiques \u00e0 la droite de l\u2019\u00e9chiquier sont ainsi pass\u00e9s du Brexit au Make Europe Great Again\u2026<\/strong><\/h3>\n\n\n\n<p>La <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/04\/le-scenario-meloni-conversation-avec-catherine-fieschi-et-mathieu-gallard\/\">m\u00e9lonisation<\/a> de l&rsquo;extr\u00eame droite au plan europ\u00e9en a bien \u00e9t\u00e9 provoqu\u00e9e par Orb\u00e1n, il est le vrai penseur de cette \u00e9volution. Que le premier ministre hongrois ait choisi comme devise de la pr\u00e9sidence tournante du Conseil \u00ab&#160;Make Europe Great Again&#160;\u00bb n\u2019est pas une co\u00efncidence. Une partie de l\u2019extr\u00eame droite europ\u00e9enne va maintenant tenter d&rsquo;influencer l&rsquo;exercice du pouvoir europ\u00e9en en essayant d\u2019y p\u00e9n\u00e9trer <em>via<\/em> des alliances parlementaires ou des nominations \u00e0 la Commission.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Y a-t-il une zone de rencontre entre le Parti populaire et sa droite&#160;?<\/strong><\/h3>\n\n\n\n<p>Oui. Elle&nbsp;prend des formes diff\u00e9rentes selon les pays. Dans un certain nombre de cas, la droite du PPE \u2014 car il y a une droite, un centre et une gauche au sein du PPE \u2014 peut \u00eatre tent\u00e9e de voter avec ECR. Comme le montre l\u2019examen d\u00e9taill\u00e9 des votes au parlement europ\u00e9en publi\u00e9 par l&rsquo;Institut Delors \u00e0 Paris, c&rsquo;est beaucoup moins probable du c\u00f4t\u00e9 d&rsquo;ID et des autres groupuscules qui n\u2019appartiennent ni \u00e0 ECR ni \u00e0 ID \u00e0 l&rsquo;extr\u00eame droite.<\/p>\n\n\n\n<p>Il y a aussi des pays o\u00f9 cette continuit\u00e9 possible fait surface. Par exemple en Italie, et m\u00eame d\u00e9sormais en France. En Allemagne, le fait d&rsquo;avoir la CDU et la CSU dans le m\u00eame groupe permet de mettre tout le monde chez les chr\u00e9tiens-d\u00e9mocrates, alors qu&rsquo;en Bavi\u00e8re ils pourraient peut-\u00eatre avoir un positionnement diff\u00e9rent si on mesurait correctement les pr\u00e9f\u00e9rences sur des axes politiques. Dans un syst\u00e8me parlementaire, il faut des compromis&#160;; il faut donc \u00eatre forts, et pour peser et occuper un maximum de positions qui comptent dans la d\u00e9termination de l\u2019ordre du jour ou la conduite des travaux en commission ou en pl\u00e9ni\u00e8re, et cette force l\u00e0 est faite du nombre.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Dans un certain nombre de cas, la droite du PPE peut \u00eatre tent\u00e9e de voter avec ECR.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment qualifier ce mouvement&#160;? Est-ce un renforcement de l\u2019inertie europ\u00e9enne hors cadre communautaire&#160;?&nbsp;<\/strong><\/h2>\n\n\n\n<p>C&rsquo;est un des ingr\u00e9dients de la politisation progressive de l&rsquo;espace supranational et de son articulation avec l&rsquo;espace national. Il s\u2019agit d\u2019une confirmation de cette hybridation&#160;: on n&rsquo;est pas dans l&rsquo;exercice d&rsquo;une forme de d\u00e9mocratie parlementaire au niveau national et d\u2019une autre forme de d\u00e9mocratie parlementaire au niveau europ\u00e9en. L&rsquo;imbrication de l&rsquo;extr\u00eame droite sur cette sc\u00e8ne est aussi un moment de progression de la constitution, de l\u2019\u00e9mergence lente de cet espace politique europ\u00e9en. Ces \u00e9lections en sont une \u00e9tape.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un sujet qui n&rsquo;a pas \u00e9t\u00e9 au c\u0153ur de la campagne, mais qui anime l&rsquo;agenda strat\u00e9gique et l&rsquo;inertie profonde des institutions, c&rsquo;est la question de la d\u00e9fense.<\/strong><strong> <\/strong><strong>S\u2019agit-il d\u2019un ingr\u00e9dient clef de cette hybridation&#160;?<\/strong><\/h3>\n\n\n\n<p>Oui, surtout pour des raisons qui tiennent \u00e0 l&rsquo;invasion russe en Ukraine. S&rsquo;il y a un th\u00e8me sur lequel les opinions europ\u00e9ennes ont toujours \u00e9t\u00e9 tr\u00e8s concordantes \u2014 y compris en Hongrie \u2014 c&rsquo;est le soutien \u00e0 une arm\u00e9e europ\u00e9enne. La proportion d&rsquo;Europ\u00e9ens en faveur d&rsquo;une arm\u00e9e europ\u00e9enne est \u00e9norme. Ce d\u00e9sir est compl\u00e8tement d\u00e9connect\u00e9 des r\u00e9alit\u00e9s de ce que cela impliquerait d&rsquo;avoir une arm\u00e9e europ\u00e9enne sur le plan de la transmutation de cet espace politique \u2014 parce que si on avait une arm\u00e9e europ\u00e9enne, cela voudrait dire que l&rsquo;espace d\u00e9mocratique supranational est devenu plus fort que l&rsquo;espace d\u00e9mocratique national.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>S&rsquo;il y a un th\u00e8me sur lequel les opinions europ\u00e9ennes ont toujours \u00e9t\u00e9 tr\u00e8s concordantes \u2014 y compris en Hongrie \u2014 c&rsquo;est le soutien \u00e0 une arm\u00e9e europ\u00e9enne.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment expliquez vous ce paradoxe&#160;?<\/strong><\/h3>\n\n\n\n<p>Ce d\u00e9sir est une sorte d\u2019utopie. Les opinions sont pour mais on bute sur l&rsquo;extraordinaire difficult\u00e9 \u00e0 porter au niveau supranational la chose militaire qui implique une seule strat\u00e9gie,&nbsp;des armes \u00e9changeables, des morts communs, des commandements unifi\u00e9s, des ordres rapides, un seul chef. Mais les forces qui bloquent diminuent sous la pression du danger. L&rsquo;Ukraine a chang\u00e9 la donne. S\u2019il est r\u00e9\u00e9lu, <a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/elections\/trump-contre-biden-pour-la-maison-blanche-suivre-les-elections-americaines-2024\/\">Donald Trump peut agir comme un deuxi\u00e8me choc<\/a>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>On ne peut pas dire que c\u2019est un sujet qui a \u00e9merg\u00e9 pendant la campagne\u2026<\/strong><\/h3>\n\n\n\n<p>Oui, mais si la d\u00e9fense n&rsquo;a pas fait l&rsquo;objet de controverses ni de d\u00e9bats dans les \u00e9lections europ\u00e9ennes, ce n&rsquo;est pas que les gens n&rsquo;ont pas envie d&rsquo;en parler, c&rsquo;est qu&rsquo;ils sont d&rsquo;accord. Toute proportion gard\u00e9e, la pr\u00e9f\u00e9rence des opinions pour une d\u00e9fense europ\u00e9enne ressemble au consensus en mati\u00e8re d&rsquo;environnement. Quand je parle d\u2019Europe avec des personnes qui ne sont pas des sp\u00e9cialistes, j&rsquo;en entends beaucoup se plaindre de l\u2019absence de d\u00e9fense europ\u00e9enne. Je respecte tout \u00e0 fait cette opinion&#160;; je constate simplement qu&rsquo;elle n\u00e9glige ou ignore les \u00e9tapes qu&rsquo;il faut franchir pour en arriver l\u00e0, \u00e0 la fois sur le plan technique comme politique. Si vous \u00eates pour une arm\u00e9e europ\u00e9enne, vous devez \u00eatre d&rsquo;accord avec le fait que le chef de cette arm\u00e9e ne sera probablement pas quelqu&rsquo;un de votre pays.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Toute proportion gard\u00e9e, la pr\u00e9f\u00e9rence des opinions pour une d\u00e9fense europ\u00e9enne ressemble au consensus en mati\u00e8re d&rsquo;environnement.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ne sommes-nous pas confront\u00e9s \u00e0 un <\/strong><a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/11\/ecologie-la-fin-du-consensus-mou-avant-les-elections-europeennes-une-conversation-avec-jean-yves-dormagen\/\"><strong>\u00ab&#160;consensus mou&#160;\u00bb, comme le d\u00e9finit Jean-Yves Dormagen dans nos pages pour la transition \u00e9cologique<\/strong><\/a><strong>&#160;? D&rsquo;une fa\u00e7on abstraite, tout le monde para\u00eet d&rsquo;accord, mais d\u00e8s qu&rsquo;on arrive sur les cons\u00e9quences concr\u00e8tes et qu\u2019on d\u00e9roule le syllogisme, imm\u00e9diatement on trouve des nouveaux clivages et des fractures.<\/strong><\/h3>\n\n\n\n<p>L&rsquo;invasion de l&rsquo;Ukraine a cr\u00e9\u00e9 une \u00e9nergie politique qui n&rsquo;\u00e9tait pas l\u00e0 auparavant. Les crises sont des moteurs d&rsquo;\u00e9nergie politique. Gr\u00e2ce \u00e0 celle-ci, nous avancerons. Dans ce qu&rsquo;on peut lire des signaux politiques qui ont \u00e9t\u00e9 envoy\u00e9s par les \u00e9lections europ\u00e9ennes et des cons\u00e9quences au Parlement et au Conseil, je ne vois pas de raison pour que ce d\u00e9but de dynamique, qui sera lent, soit interrompu. Notamment parce qu&rsquo;\u00e0 ECR, il n&rsquo;y a pas de r\u00e9sistance consid\u00e9rable sur ce sujet, et qu&rsquo;Orb\u00e1n, au fond, n&rsquo;est pas contre.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Il serait difficile de ne pas vous demander de consacrer un d\u00e9veloppement \u00e0 l&rsquo;effet politique national le plus impressionnant de ces <a href=\"https:\/\/legrandcontinent.eu\/fr\/elections\/europeennes-2024\/\">\u00e9lections europ\u00e9ennes<\/a>&#160;: la dissolution de l&rsquo;Assembl\u00e9e nationale. Pensez-vous qu&rsquo;un gouvernement Bardella marquerait une rupture vis-\u00e0-vis de la construction europ\u00e9enne&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Je ne sais pas bien, parce que, en dehors d\u2019une posture nationaliste de principe, le RN s&rsquo;est bien gard\u00e9 de pr\u00e9ciser sa position pour rester dans la strat\u00e9gie de l&rsquo;attrape-tout. Je parle donc avec prudence, mais dans le syst\u00e8me institutionnel et constitutionnel fran\u00e7ais, la question europ\u00e9enne est largement du domaine du pr\u00e9sident de la R\u00e9publique. Emmanuel Macron, \u00e9lu il y a 7 ans, a pu imprimer et continue \u00e0 imprimer une dynamique \u00e0 la construction europ\u00e9enne, avec Sorbonne 1 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/batir-un-nouveau-paradigme-le-discours-integral-demmanuel-macron-a-la-sorbonne\/\">et maintenant Sorbonne 2<\/a>, m\u00eame si l&rsquo;arbre de No\u00ebl est toujours un peu charg\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En dehors d\u2019une posture nationaliste de principe, le RN s&rsquo;est bien gard\u00e9 de pr\u00e9ciser sa position pour rester dans la strat\u00e9gie de l&rsquo;attrape-tout.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cela ne veut pas dire qu\u2019il n\u2019y aura pas de changement, parce qu&rsquo;il y a beaucoup de d\u00e9cisions quotidiennes, d&rsquo;arbitrages, qui doivent \u00eatre faits au niveau du gouvernement, notamment avec la machinerie du Secr\u00e9tariat g\u00e9n\u00e9ral des affaires europ\u00e9ennes (SGAE) qui pr\u00e9pare, fait adopter puis transmet les instructions&nbsp;sur les positions fran\u00e7aises \u00e0 la Repr\u00e9sentation Permanente \u00e0 Bruxelles qui les d\u00e9fend. Ces arbitrages seront diff\u00e9rents avec un gouvernement Bardella ou avec un gouvernement Attal. Si la Commission, pour faire voter un texte au Conseil des ministres, a besoin d&rsquo;une majorit\u00e9 et que la position de la France est d\u00e9terminante dans l\u2019obtention de cette majorit\u00e9, cela peut changer les choses.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sur quels sujets verriez-vous des possibles ruptures&#160;?<\/strong><\/h3>\n\n\n\n<p>Sur un sujet crucial, la d\u00e9fense de l\u2019Ukraine, ou sur&nbsp;des sujets \u00e0 venir comme la r\u00e9forme de la politique agricole commune, le budget europ\u00e9en, le rythme de la transition \u00e9cologique, un premier ministre RN pourrait produire des infl\u00e9chissements.<\/p>\n\n\n\n<p>Par contre sur l&rsquo;immigration, il y a relativement peu de chances que le sujet soit relanc\u00e9 \u00e0 court terme au niveau europ\u00e9en parce qu&rsquo;on vient de changer assez substantiellement la politique de migration en durcissant les accords de Dublin.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Sur l&rsquo;immigration, il y a relativement peu de chances que le sujet soit relanc\u00e9 \u00e0 court terme au niveau europ\u00e9en parce qu&rsquo;on vient de changer assez substantiellement la politique de migration en durcissant les accords de Dublin.<\/p><cite>Pascal Lamy<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le mouvement de fond de ce basculement ne pourrait-il pas ouvrir une phase o\u00f9 le Frexit deviendrait de nouveau une hypoth\u00e8se&#160;?<\/strong><\/h3>\n\n\n\n<p>Je ne le crois pas. Les circonstances et les contraintes ext\u00e9rieures \u2014 les affaires d\u2019un monde perclus de crises multiples \u2014 poussent dans l&rsquo;autre sens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De quoi les Europ\u00e9ennes sont-elles le r\u00e9sultat&#160;&#160;? Entre les tendances lourdes et l&rsquo;inertie, Pascal Lamy trace les coordonn\u00e9es d&rsquo;une \u00ab&#160;&#160;\u00e9lection hybride&#160;&#160;\u00bb. Au c\u0153ur de la phase d&rsquo;incertitude dans laquelle est plong\u00e9e la France avant les l\u00e9gislatives et apr\u00e8s le coup de tonnerre de la dissolution, il pr\u00e9vient&#160;&#160;: \u00ab&#160;&#160;un gouvernement Bardella voudra imprimer sa marque sur certains chantiers europ\u00e9ens.&#160;&#160;\u00bb<\/p>\n","protected":false},"author":10,"featured_media":234616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":14,"footnotes":""},"categories":[3810],"tags":[],"staff":[1553],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-234594","post","type-post","status-publish","format-standard","hentry","category-elections-europeennes-2024","staff-gilles-gressani","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":234616,"excerpt":"De quoi les Europ\u00e9ennes sont-elles le r\u00e9sultat ? Entre les tendances lourdes et l'inertie, Pascal Lamy trace les coordonn\u00e9es d'une \u00ab\u00e9lection hybride\u00bb. Au c\u0153ur de la phase d'incertitude dans laquelle est plong\u00e9e la France avant les l\u00e9gislatives et apr\u00e8s le coup de tonnerre de la dissolution, il pr\u00e9vient : \u00abun gouvernement Bardella voudra imprimer sa marque sur certains chantiers europ\u00e9ens.\u00bb","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abLes Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa\u00bb, bilan et perspectives de Pascal Lamy | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abLes Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa\u00bb, bilan et perspectives de Pascal Lamy | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"De quoi les Europ\u00e9ennes sont-elles le r\u00e9sultat&#160;? Entre les tendances lourdes et l&#039;inertie, Pascal Lamy trace les coordonn\u00e9es d&#039;une \u00ab&#160;\u00e9lection hybride&#160;\u00bb. Au c\u0153ur de la phase d&#039;incertitude dans laquelle est plong\u00e9e la France avant les l\u00e9gislatives et apr\u00e8s le coup de tonnerre de la dissolution, il pr\u00e9vient&#160;: \u00ab&#160;un gouvernement Bardella voudra imprimer sa marque sur certains chantiers europ\u00e9ens.&#160;\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-21T14:24:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T07:50:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/gc-lamyfive-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/gc-lamyfive-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/\",\"name\":\"\u00abLes Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa\u00bb, bilan et perspectives de Pascal Lamy | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg\",\"datePublished\":\"2024-06-21T14:24:34+00:00\",\"dateModified\":\"2024-06-24T07:50:17+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"\u00a9 Eliot Blondet\/SIPA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Les Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa&#160;\u00bb, bilan et perspectives de Pascal Lamy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abLes Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa\u00bb, bilan et perspectives de Pascal Lamy | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00abLes Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa\u00bb, bilan et perspectives de Pascal Lamy | Le Grand Continent","og_description":"De quoi les Europ\u00e9ennes sont-elles le r\u00e9sultat&#160;? Entre les tendances lourdes et l'inertie, Pascal Lamy trace les coordonn\u00e9es d'une \u00ab&#160;\u00e9lection hybride&#160;\u00bb. Au c\u0153ur de la phase d'incertitude dans laquelle est plong\u00e9e la France avant les l\u00e9gislatives et apr\u00e8s le coup de tonnerre de la dissolution, il pr\u00e9vient&#160;: \u00ab&#160;un gouvernement Bardella voudra imprimer sa marque sur certains chantiers europ\u00e9ens.&#160;\u00bb","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/","og_site_name":"Le Grand Continent","article_published_time":"2024-06-21T14:24:34+00:00","article_modified_time":"2024-06-24T07:50:17+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/gc-lamyfive-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/gc-lamyfive-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/","name":"\u00abLes Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa\u00bb, bilan et perspectives de Pascal Lamy | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg","datePublished":"2024-06-21T14:24:34+00:00","dateModified":"2024-06-24T07:50:17+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg","width":2560,"height":1707,"caption":"\u00a9 Eliot Blondet\/SIPA"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/06\/21\/les-europeennes-2024-ont-marque-la-fin-du-souverainisme-a-la-papa-bilan-et-perspectives-de-pascal-lamy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Les Europ\u00e9ennes 2024 ont marqu\u00e9 la fin du souverainisme \u00e0 la papa&#160;\u00bb, bilan et perspectives de Pascal Lamy"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3810,"name":"\u00c9lections europ\u00e9ennes 2024","slug":"elections-europeennes-2024"}],"lgc_author":{"id":1553,"name":"Gilles Gressani","slug":"gilles-gressani","description":"Gilles Gressani, directeur du Grand Continent, il pr\u00e9side le Groupe d\u2019\u00e9tudes g\u00e9opolitiques et enseigne \u00e0 Sciences Po. <a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/portrait-dun-monde-casse\/\"><em>Portrait d'un monde cass\u00e9<\/em><\/a> (Gallimard 2024) est en librairie. \r\n","first_name":"Gilles","last_name":"Gressani","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/portrait-gilles-1-e1669480105797.jpg","width":416,"height":416,"alt":"Directeur Grand Continent"}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/SIPA_01134148_000070-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/234594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=234594"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/234594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/234616"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=234594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=234594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=234594"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=234594"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=234594"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=234594"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=234594"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=234594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}