{"id":229254,"date":"2024-05-13T20:02:04","date_gmt":"2024-05-13T18:02:04","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=229254"},"modified":"2024-05-14T14:40:08","modified_gmt":"2024-05-14T12:40:08","slug":"transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/","title":{"rendered":"Transformer la Russie en \u00e9conomie de guerre&#160;: comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense"},"content":{"rendered":"\n<p>Dimanche 12 mai, Vladimir Poutine a envoy\u00e9 au Conseil de la F\u00e9d\u00e9ration ses propositions de candidats pour composer son nouveau cabinet \u2014 dont certains postes \u00e0 la t\u00eate de \u00ab&#160;minist\u00e8res d&rsquo;application de la loi&#160;\u00bb (<em>siloviki<\/em>). Le vice-premier ministre par int\u00e9rim, Andre\u00ef Belooussov, a notamment \u00e9t\u00e9 propos\u00e9 au poste de ministre de la D\u00e9fense en remplacement de Sergue\u00ef Cho\u00efgou, qui occupait cette fonction depuis presque 12 ans.<\/p>\n\n\n\n<p>Ce dernier devrait ainsi prendre la t\u00eate du Conseil de S\u00e9curit\u00e9 et occupera \u00e9galement la vice-pr\u00e9sidence de la Commission militaro-industrielle et la direction du Service f\u00e9d\u00e9ral pour la coop\u00e9ration militaro-technique \u2014 service directement subordonn\u00e9 au pr\u00e9sident&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-229254' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#easy-footnote-bottom-1-229254' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/meduza.io\/feature\/2024\/05\/12\/putin-uvolil-shoygu-s-posta-ministra-oborony-i-perevel-v-sovbez&quot;&gt;\u041f\u0443\u0442\u0438\u043d \u0443\u0432\u043e\u043b\u0438\u043b \u0428\u043e\u0439\u0433\u0443 \u0441 \u043f\u043e\u0441\u0442\u0430 \u043c\u0438\u043d\u0438\u0441\u0442\u0440\u0430 \u043e\u0431\u043e\u0440\u043e\u043d\u044b \u2014 \u0438 \u043f\u0435\u0440\u0435\u0432\u0435\u043b \u0432 \u0421\u043e\u0432\u0431\u0435\u0437 \u041d\u043e\u0432\u044b\u043c \u0433\u043b\u0430\u0432\u043e\u0439 \u0432\u043e\u0435\u043d\u043d\u043e\u0433\u043e \u0432\u0435\u0434\u043e\u043c\u0441\u0442\u0432\u0430 \u0441\u0442\u0430\u043d\u0435\u0442 \u044d\u043a\u043e\u043d\u043e\u043c\u0438\u0441\u0442 \u0410\u043d\u0434\u0440\u0435\u0439 \u0411\u0435\u043b\u043e\u0443\u0441\u043e\u0432&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Meduza&lt;\/em&gt;, 12 mai 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Belooussov est dipl\u00f4m\u00e9 de la facult\u00e9 d\u2019\u00c9conomie de l\u2019universit\u00e9 de Moscou, et a re\u00e7u le titre de Docteur des sciences \u2013 le plus haut titre de l&rsquo;enseignement sup\u00e9rieur dans l&rsquo;Union sovi\u00e9tique.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Apr\u00e8s une courte carri\u00e8re universitaire, il cr\u00e9e et dirige de 2000 \u00e0 2006 le Centre d&rsquo;analyse macro\u00e9conomique et de pr\u00e9vision \u00e0 court terme de l&rsquo;Acad\u00e9mie russe des sciences. Il devient au m\u00eame moment Conseiller externe du Premier ministre.<\/li>\n\n\n\n<li>\u00c0 partir de 2006, Belooussov occupe plusieurs postes de haut niveau li\u00e9s aux questions de d\u00e9veloppement \u00e9conomique au sein du gouvernement et de l&rsquo;administration pr\u00e9sidentielle.<\/li>\n\n\n\n<li>De 2015 \u00e0 2017, il pr\u00e9side \u00e9galement le conseil d\u2019administration de Rosneft, deuxi\u00e8me entreprise la plus importante de Russie, aujourd\u2019hui pr\u00e9sid\u00e9e par Gerhard Schr\u00f6der.<\/li>\n\n\n\n<li>En 2020, \u00e0 la suite de la d\u00e9mission du gouvernement de Medvedev, Belousov devient le num\u00e9ro deux du nouveau gouvernement et occupe le poste de premier vice-premier ministre de la F\u00e9d\u00e9ration de Russie. Au m\u00eame moment, il prend la t\u00eate du conseil d&rsquo;administration des Chemins de fer russes (<em>\u0420\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u0435 \u0436\u0435\u043b\u0435\u0437\u043d\u044b\u0435 \u0434\u043e\u0440\u043e\u0433\u0438<\/em>, RJD).<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/JYg46\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Belooussov est l\u2019un des architectes principaux de la doctrine \u00e9conomique russe contemporaine. Il est connu pour ses id\u00e9es dirigistes qui ont provoqu\u00e9 par le pass\u00e9 des conflits avec les ministres successifs de l\u2019\u00c9conomie et la Banque centrale.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon <em>The Bell<\/em>, organe de presse \u00e9conomique russe, Belooussov croit en l&rsquo;existence d\u2019un \u00ab&#160;cercle d\u2019ennemis de la Russie&#160;\u00bb. Il \u00e9tait le seul haut-fonctionnaire \u00e9conomiste \u00e0 soutenir l\u2019annexion de la Crim\u00e9e en 2014&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-229254' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#easy-footnote-bottom-2-229254' title='&lt;a href=&quot;https:\/\/en.thebell.io\/who-s-who-in-the-new-government\/&quot;&gt;Who\u2019s who in the new Russian government&lt;\/a&gt;, &lt;em&gt;The Bell&lt;\/em&gt;, 24 janvier 2020.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Le porte-parole de la pr\u00e9sidence, Dmitri Peskov, a li\u00e9 sa nomination \u00e0 la n\u00e9cessit\u00e9 d&rsquo;introduire \u00ab&#160;des innovations&#160;\u00bb et \u00ab&#160;d&rsquo;int\u00e9grer l&rsquo;\u00e9conomie du bloc s\u00e9curitaire \u00e0 l&rsquo;\u00e9conomie du pays&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-229254' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#easy-footnote-bottom-3-229254' title='&lt;a href=&quot;https:\/\/www.vedomosti.ru\/politics\/articles\/2024\/05\/12\/1036666-peskov-obyasnil-predlozhenie&quot;&gt;\u041f\u0435\u0441\u043a\u043e\u0432 \u043e\u0431\u044a\u044f\u0441\u043d\u0438\u043b \u043f\u0440\u0435\u0434\u043b\u043e\u0436\u0435\u043d\u0438\u0435 \u043d\u0430\u0437\u043d\u0430\u0447\u0438\u0442\u044c \u0411\u0435\u043b\u043e\u0443\u0441\u043e\u0432\u0430 \u043d\u0430 \u0434\u043e\u043b\u0436\u043d\u043e\u0441\u0442\u044c \u043c\u0438\u043d\u0438\u0441\u0442\u0440\u0430 \u043e\u0431\u043e\u0440\u043e\u043d\u044b&lt;\/a&gt;, &lt;em&gt;\u0412\u0435\u0434\u043e\u043c\u043e\u0441\u0442\u0438&lt;\/em&gt;, 12 janvier 2024.&amp;nbsp;'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Entre 2021 et 2023, le budget attribu\u00e9 \u00e0 la D\u00e9fense \u2014 d\u00e9penses li\u00e9es \u00e0 la \u00ab&#160;s\u00e9curit\u00e9&#160;\u00bb exclues \u2014 a bondi, passant de 3,6&#160;% en 2022 \u00e0 5,9&#160;% du PIB en 2023 selon le SIPRI. Il devrait atteindre 7, 1&#160;% du PIB cette ann\u00e9e.<\/li>\n<\/ul>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/SIPA_sipausa30417783_000010-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/SIPA_sipausa30417783_000010-330x220.jpg\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/SIPA_sipausa30417783_000010-690x460.jpg\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/SIPA_sipausa30417783_000010-990x660.jpg\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/SIPA_sipausa30417783_000010-690x460.jpg\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/SIPA_sipausa30417783_000010-990x660.jpg\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/SIPA_sipausa30417783_000010-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Andre\u00ef Belooussov assiste \u00e0 un \u00e9v\u00e9nement marquant le 50e anniversaire du d\u00e9but de la construction de la ligne principale Ba\u00efkal-Amour (BAM) au palais du Kremlin d\u2019\u00c9tat, le 23 avril 2024. \u00a9 Vladimir Astapkovich\/POOL\/TASS\/Sipa USA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Avec la nomination de Belooussov, Poutine souhaite parachever la transformation de l\u2019\u00e9conomie russe afin de la mettre int\u00e9gralement au service de l&rsquo;effort de guerre.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tout comme son successeur Cho\u00efgou, Belooussov n\u2019est pas un militaire. Il est un technocrate, proche de Poutine.<\/li>\n\n\n\n<li>Selon les analystes de l&rsquo;<em>Institute for the Study of War,<\/em> cette nomination s\u2019inscrit dans la ligne d\u2019efforts d\u00e9ploy\u00e9s par le pr\u00e9sident russe pour mettre en place toutes les conditions \u00e9conomiques d&rsquo;une guerre prolong\u00e9e, et \u00e9ventuellement se pr\u00e9parer \u00e0 une future confrontation avec l&rsquo;OTAN&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-229254' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#easy-footnote-bottom-4-229254' title='&lt;a href=&quot;https:\/\/www.understandingwar.org\/backgrounder\/russian-offensive-campaign-assessment-may-12-2024&quot;&gt;Russian offensive campaign assessment&lt;\/a&gt;, &lt;em&gt;Institute for the Study of War&lt;\/em&gt;, 12 mai 2024.&amp;nbsp;'><sup>4<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Malgr\u00e9 son manque d&rsquo;exp\u00e9rience militaire, Belooussov a \u00e9t\u00e9 impliqu\u00e9 dans un certain nombre de projets li\u00e9s \u00e0 l&rsquo;industrie de la d\u00e9fense.<\/li>\n\n\n\n<li>Il met l\u2019accent sur l&rsquo;optimisation de l&rsquo;innovation technologique et de la production de l\u2019industrie de d\u00e9fense. Il a notamment pr\u00e9sent\u00e9 un projet de commande publique de 4,4 milliards de roubles (environ 48 millions de dollars) pour la production de drones jusqu&rsquo;en 2030, ainsi que des plans pour former des fabricants et des op\u00e9rateurs de drones&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-229254' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#easy-footnote-bottom-5-229254' title='&lt;em&gt;Id&lt;\/em&gt;.'><sup>5<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<p>L&rsquo;une des t\u00e2ches de Belooussov sera de dissiper les d\u00e9saccords entre les militaires et les industriels afin de continuer \u00e0 approvisionner l&rsquo;arm\u00e9e et de transformer l\u2019\u00e9conomie. Selon Alexe\u00ef Govrin, membre de la commission des petites et moyennes entreprises de la Douma, Belousov jouit d&rsquo;une autorit\u00e9 \u00ab&#160;dans de nombreux cercles&#160;\u00bb, notamment en raison de sa capacit\u00e9 \u00e0 \u00ab&#160;toujours entendre et comprendre des arguments&#160;\u00bb de tous bords&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-229254' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#easy-footnote-bottom-6-229254' title='&lt;a href=&quot;https:\/\/rtvi.com\/news\/grazhdanskij-voczerkovlennyj-nauchruk-nabiullinoj-kak-v-kremle-obyasnili-vybor-belousova-ministrom-oborony\/&quot;&gt;\u0413\u0440\u0430\u0436\u0434\u0430\u043d\u0441\u043a\u0438\u0439, \u0432\u043e\u0446\u0435\u0440\u043a\u043e\u0432\u043b\u0435\u043d\u043d\u044b\u0439, \u043d\u0430\u0443\u0447\u0440\u0443\u043a \u041d\u0430\u0431\u0438\u0443\u043b\u043b\u0438\u043d\u043e\u0439&amp;#160;: \u043a\u0430\u043a \u0432 \u041a\u0440\u0435\u043c\u043b\u0435 \u043e\u0431\u044a\u044f\u0441\u043d\u0438\u043b\u0438 \u0432\u044b\u0431\u043e\u0440 \u0411\u0435\u043b\u043e\u0443\u0441\u043e\u0432\u0430 \u043c\u0438\u043d\u0438\u0441\u0442\u0440\u043e\u043c \u043e\u0431\u043e\u0440\u043e\u043d\u044b&lt;\/a&gt;, &lt;em&gt;RTVI&lt;\/em&gt;, 12 mai 2024.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>B\u00e9n\u00e9ficiant d&rsquo;une r\u00e9putation de technocrate, Belooussov devrait aussi s&rsquo;attaquer \u00e0 la corruption au sein du minist\u00e8re de la D\u00e9fense, \u00e9voqu\u00e9e \u00e0 plusieurs reprises notamment lors de l&rsquo;<a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/24\/evgueni-prigojine-la-fin-dun-nouveau-russe\/\">affrontement<\/a> entre Cho\u00efgou et Prigogine \u00e0 l&rsquo;\u00e9t\u00e9 2023.<\/li>\n<\/ul>\n\n\n\n<p>Le nouveau ministre de la D\u00e9fense russe fait l&rsquo;objet de sanctions ukrainiennes, europ\u00e9ennes et figure sur la liste des sanctions individuelles adopt\u00e9es par les \u00c9tats-Unis, le Japon, le Royaume-Uni, le Canada et l\u2019Australie. Contrairement \u00e0 Cho\u00efgou, qui est de confession bouddhiste, Belooussov, n\u00e9 \u00e0 Moscou, est un chr\u00e9tien orthodoxe pratiquant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andre\u00ef Belooussov n\u2019est pas un militaire, mais un technocrate. Au minist\u00e8re de la D\u00e9fense, son r\u00f4le sera de transformer l\u2019\u00e9conomie russe et de dissiper les d\u00e9saccords entre militaires et industriels afin de garantir la continuit\u00e9 de l\u2019approvisionnement de l\u2019arm\u00e9e. Avec cette nomination, Poutine confirme qu\u2019il compte gagner la guerre dans le temps long.<\/p>\n","protected":false},"author":2622,"featured_media":229260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"footnotes":""},"categories":[3594],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[550],"class_list":["post-229254","post","type-post","status-publish","format-standard","hentry","category-profil-clef","editorial_format-actu-breves","geo-russie"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":229260,"excerpt":"Andre\u00ef Belooussov n\u2019est pas un militaire, mais un technocrate. Au minist\u00e8re de la D\u00e9fense, son r\u00f4le sera de transformer l\u2019\u00e9conomie russe et de dissiper les d\u00e9saccords entre militaires et industriels afin de garantir la continuit\u00e9 de l\u2019approvisionnement de l\u2019arm\u00e9e. Avec cette nomination, Poutine confirme qu\u2019il compte gagner la guerre dans le temps long.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transformer la Russie en \u00e9conomie de guerre : comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transformer la Russie en \u00e9conomie de guerre : comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Andre\u00ef Belooussov n\u2019est pas un militaire, mais un technocrate. Au minist\u00e8re de la D\u00e9fense, son r\u00f4le sera de transformer l\u2019\u00e9conomie russe et de dissiper les d\u00e9saccords entre militaires et industriels afin de garantir la continuit\u00e9 de l\u2019approvisionnement de l\u2019arm\u00e9e. Avec cette nomination, Poutine confirme qu\u2019il compte gagner la guerre dans le temps long.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-13T18:02:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-14T12:40:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/\",\"name\":\"Transformer la Russie en \u00e9conomie de guerre : comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png\",\"datePublished\":\"2024-05-13T18:02:04+00:00\",\"dateModified\":\"2024-05-14T12:40:08+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png\",\"width\":1453,\"height\":816},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transformer la Russie en \u00e9conomie de guerre&#160;: comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transformer la Russie en \u00e9conomie de guerre : comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/","og_locale":"fr_FR","og_type":"article","og_title":"Transformer la Russie en \u00e9conomie de guerre : comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense | Le Grand Continent","og_description":"Andre\u00ef Belooussov n\u2019est pas un militaire, mais un technocrate. Au minist\u00e8re de la D\u00e9fense, son r\u00f4le sera de transformer l\u2019\u00e9conomie russe et de dissiper les d\u00e9saccords entre militaires et industriels afin de garantir la continuit\u00e9 de l\u2019approvisionnement de l\u2019arm\u00e9e. Avec cette nomination, Poutine confirme qu\u2019il compte gagner la guerre dans le temps long.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/","og_site_name":"Le Grand Continent","article_published_time":"2024-05-13T18:02:04+00:00","article_modified_time":"2024-05-14T12:40:08+00:00","og_image":[{"width":1453,"height":816,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/","name":"Transformer la Russie en \u00e9conomie de guerre : comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png","datePublished":"2024-05-13T18:02:04+00:00","dateModified":"2024-05-14T12:40:08+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png","width":1453,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/13\/transformer-la-russie-en-economie-de-guerre-comprendre-la-nomination-dandrei-belooussov-a-la-tete-de-la-defense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Transformer la Russie en \u00e9conomie de guerre&#160;: comprendre la nomination d\u2019Andre\u00ef Belooussov \u00e0 la t\u00eate de la D\u00e9fense"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3594,"name":"Profil clef","slug":"profil-clef"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/05\/gc-profil-Belooussov-e1715622777590.png","width":1453,"height":816,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/229254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=229254"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/229254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/229260"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=229254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=229254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=229254"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=229254"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=229254"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=229254"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=229254"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=229254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}