{"id":227534,"date":"2024-04-25T14:30:09","date_gmt":"2024-04-25T12:30:09","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=227534"},"modified":"2024-04-25T14:30:10","modified_gmt":"2024-04-25T12:30:10","slug":"washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/","title":{"rendered":"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin&#160;?"},"content":{"rendered":"\n<p>Alors que Joe Biden signait mercredi 24 avril <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/23\/sur-les-61-milliards-contenus-dans-le-projet-de-loi-americain-daide-a-kiev-2317-sont-pour-larmee-ukrainienne\/\">le paquet d\u2019assistance \u00e0 l\u2019Ukraine<\/a>, Isra\u00ebl et Ta\u00efwan \u2014 entre autres \u2014 vot\u00e9 la veille par le S\u00e9nat, le porte-parole adjoint du d\u00e9partement d\u2019\u00c9tat am\u00e9ricain Vedant Patel confiait au m\u00eame moment que le pr\u00e9sident am\u00e9ricain avait d\u00e9j\u00e0 \u00ab&#160;discr\u00e8tement demand\u00e9 \u00e0 son \u00e9quipe de s\u00e9curit\u00e9 nationale d&rsquo;envoyer des [missiles longue port\u00e9e] ATACMS&#160;\u00bb en f\u00e9vrier&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-227534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#easy-footnote-bottom-1-227534' title='&lt;a href=&quot;https:\/\/www.state.gov\/briefings\/department-press-briefing-april-24-2024\/&quot;&gt;Department Press Briefing \u2013 April 24, 2024&lt;\/a&gt;, D\u00e9partement d\u2019\u00c9tat am\u00e9ricain.'><sup>1<\/sup><\/a><\/span><\/span>. Ces derniers ont \u00e9t\u00e9 exp\u00e9di\u00e9s en Ukraine dans le cadre de l\u2019aide suppl\u00e9mentaire annonc\u00e9e le 12 mars par le d\u00e9partement de la D\u00e9fense.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/QNtZ4\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Cette d\u00e9claration t\u00e9moigne d\u2019un revirement significatif de la position de la Maison-Blanche dans le cadre de l\u2019assistance militaire qu\u2019elle fournit \u00e0 Kiev.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Washington a refus\u00e9 \u00e0 plusieurs reprises l\u2019envoi de ces missiles d\u2019une port\u00e9e de 300 kilom\u00e8tres au cours des derniers mois \u2014 malgr\u00e9 l\u2019insistance des autorit\u00e9s ukrainiennes \u2014, arguant que l\u2019arm\u00e9e am\u00e9ricaine ne disposait pas d\u2019assez de ces syst\u00e8mes pour se permettre de s\u2019en s\u00e9parer&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-227534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#easy-footnote-bottom-2-227534' title='Paul Mcleary, Lara Seligman et Alexander Ward, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.politico.com\/news\/2023\/02\/13\/u-s-wont-send-long-range-missiles-ukraine-00082652&quot;&gt;U.S. tells Ukraine it won\u2019t send long-range missiles because it has few to spare&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Politico&lt;\/em&gt;, 13 f\u00e9vrier 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Au-del\u00e0 de la question centrale des r\u00e9serves disponibles, les autorit\u00e9s am\u00e9ricaines craignaient \u00e9galement que l\u2019arm\u00e9e ukrainienne n\u2019utilise ces missiles longue port\u00e9e pour frapper des cibles sur le territoire russe.<\/li>\n\n\n\n<li>En addition d\u2019un nombre inconnu de missiles exp\u00e9di\u00e9s en mars, des syst\u00e8mes suppl\u00e9mentaires seront envoy\u00e9s \u00e0 Kiev dans le cadre de l\u2019aide d\u2019un milliard de dollars annonc\u00e9e mercredi 24 avril&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-227534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#easy-footnote-bottom-3-227534' title='Alexander Ward et Lara Seligman, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.politico.com\/news\/2024\/04\/24\/us-long-range-missiles-ukraine-00154110&quot;&gt;The US secretly sent long-range ATACMS to Ukraine \u2014 and Kyiv used them&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Politico&lt;\/em&gt;, 24 avril 2024.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<p>De la m\u00eame mani\u00e8re que les \u00c9tats-Unis avaient bris\u00e9 des tabous en envoyant \u00e0 Kiev des chars d\u2019assaut, des missiles courte port\u00e9e et autoris\u00e9 trois pays europ\u00e9ens \u00e0 transf\u00e9rer <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/22\/en-ukraine-loffensive-russe-continue-10-points-sur-letat-du-front-et-les-perspectives-dici-lete\/\">des avions de chasse am\u00e9ricains F-16<\/a> \u00e0 l\u2019arm\u00e9e ukrainienne, l\u2019annonce de l\u2019envoi de missiles longue port\u00e9e t\u00e9moigne de la prise en compte par Washington des risques croissants d\u2019une d\u00e9faite militaire de l\u2019Ukraine face \u00e0 la Russie. Jake Sullivan a n\u00e9anmoins pr\u00e9cis\u00e9 que les ATACMS longue port\u00e9e ne pourraient \u00eatre utilis\u00e9 qu\u2019\u00e0 l\u2019int\u00e9rieur du \u00ab&#160;territoire souverain de l\u2019Ukraine&#160;\u00bb \u2014 incluant donc la Crim\u00e9e&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-227534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#easy-footnote-bottom-4-227534' title='Aaron Metha, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/breakingdefense.com\/2024\/04\/sullivan-says-ukraine-supplemental-should-cover-all-of-2024-long-range-atacms-now-in-ukraine\/&quot;&gt;Sullivan says Ukraine supplemental should cover all of 2024, long-range ATACMS now in Ukraine&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Breaking Defense&lt;\/em&gt;, 24 avril 2024.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/PvoJ1\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019arm\u00e9e ukrainienne disposait d\u00e9j\u00e0 avant le mois de mars de missiles ATACMS am\u00e9ricains d\u2019une port\u00e9e de 160 kilom\u00e8tres ainsi que de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/02\/24\/du-drone-au-char-dassaut-la-guerre-dukraine-en-10-armes-clefs\/\">missiles franco-britanniques SCALP-EG \/ Storm Shadow<\/a> d\u2019une port\u00e9e de 250 kilom\u00e8tres.<\/li>\n\n\n\n<li>Ces syst\u00e8mes \u00e9tant disponibles en quantit\u00e9 limit\u00e9e (environ 850 pour le Royaume-Uni et 460 pour la France avant les premiers envois), l\u2019envoi par Washington d\u2019ATACMS d\u2019une port\u00e9e l\u00e9g\u00e8rement sup\u00e9rieure diversifiera les options de Kiev&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-227534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#easy-footnote-bottom-5-227534' title='Sylvia Pfeifer et Patricia Nilsson, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.ft.com\/content\/09f2ec36-de20-4ea2-abf2-49f70275c521&quot;&gt;Why Germany\u2019s Taurus is Europe\u2019s most-wanted long-range missile&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Financial Times&lt;\/em&gt;, 15 mars 2024.'><sup>5<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Plus important encore, l\u2019annonce de Washington pourrait inciter Olaf Scholz \u00e0 revenir sur son refus cat\u00e9gorique de livrer des missiles Taurus, plus performants contre les infrastructures renforc\u00e9es et disposant d\u2019une port\u00e9e de 500 kilom\u00e8tres.<\/li>\n\n\n\n<li>Le chancelier allemand justifie <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/02\/28\/lallemagne-en-proie-au-doute-a-loree-de-la-troisieme-annee-de-guerre-en-ukraine\/\">son opposition \u00e0 la livraison de Taurus<\/a> par le refus de Berlin de \u00ab&#160;devenir co-bellig\u00e9rant&#160;\u00bb dans le conflit, avan\u00e7ant que l\u2019op\u00e9ration de ces syst\u00e8mes n\u00e9cessiterait la pr\u00e9sence de militaires allemands sur le sol ukrainien \u2014 ce qui a \u00e9t\u00e9 d\u00e9menti \u00e0 de multiples reprises.<\/li>\n\n\n\n<li>Lors d\u2019une visite \u00e0 Berlin du Premier ministre britannique Rishi Sunak mercredi 24 f\u00e9vrier, Scholz a r\u00e9it\u00e9r\u00e9 son opposition \u00e0 l\u2019envoi de Taurus \u00e0 l\u2019Ukraine&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-227534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#easy-footnote-bottom-6-227534' title='Michael Nienaber et Alex Wickham, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bloomberg.com\/news\/articles\/2024-04-24\/rishi-sunak-olaf-scholz-find-common-cause-to-support-each-other-on-defense&quot;&gt;Sunak, Scholz Find Common Cause to Support Each Other on Defense&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Bloomberg&lt;\/em&gt;, 24 avril 2024.'><sup>6<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/WTM1G\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>En janvier 2023, l\u2019Allemagne avait attendu l\u2019envoi par les \u00c9tats-Unis de chars d\u2019assaut M1 Abrams \u00e0 l\u2019Ukraine pour annoncer la livraison de 14 chars Leopard 2. Dot\u00e9s d\u2019une ogive intelligente \u00e0 deux \u00e9tages, les Taurus allemands (dont 600 sont disponibles dans les r\u00e9serves de la Bundeswehr) peuvent \u00eatre programm\u00e9s de mani\u00e8re \u00e0 infliger des d\u00e9g\u00e2ts bien plus importants que les SCALP-EG \/ Storm Shadow et les ATACMS sur des infrastructures renforc\u00e9es. Ils pourraient notamment \u00eatre utilis\u00e9s pour d\u00e9truire <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/08\/lexplosion-sur-le-pont-de-crimee-confirme-lelargissement-du-champ-de-la-guerre\/\">le pont de Crim\u00e9e<\/a>, coupant une voie d\u2019approvisionnement majeure de l\u2019arm\u00e9e russe dans le sud de l\u2019Ukraine&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-227534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#easy-footnote-bottom-7-227534' title='Ben Hodges, Led Klosky, Robert Person et Eric Williamson, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.foreignaffairs.com\/united-states\/putins-weak-link-crimea?check_logged_in=1&quot;&gt;Putin\u2019s Weak Link to Crimea. Kyiv Should Target the Kerch Bridge\u2014but Needs Missiles to Take It Out&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Foreign Affairs&lt;\/em&gt;, 5 d\u00e9cembre 2023.'><sup>7<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec l\u2019envoi dissimul\u00e9 le 12 mars par la Maison-Blanche de plusieurs missiles ATACMS longue port\u00e9e, Washington a fait sauter un tabou suppl\u00e9mentaire dans le cadre de l\u2019assistance \u00e0 l\u2019Ukraine. Celui-ci pourrait ouvrir la voie \u00e0 la livraison de missiles Taurus par Berlin, mena\u00e7ant ainsi le pont de Crim\u00e9e et le ravitaillement de l\u2019arm\u00e9e russe dans le sud de l\u2019Ukraine.<\/p>\n","protected":false},"author":2622,"featured_media":227537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525],"class_list":["post-227534","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":227537,"excerpt":"Avec l\u2019envoi dissimul\u00e9 le 12 mars par la Maison-Blanche de plusieurs missiles ATACMS longue port\u00e9e, Washington a fait sauter un tabou suppl\u00e9mentaire dans le cadre de l\u2019assistance \u00e0 l\u2019Ukraine. Celui-ci pourrait ouvrir la voie \u00e0 la livraison de missiles Taurus par Berlin, mena\u00e7ant ainsi le pont de Crim\u00e9e et le ravitaillement de l\u2019arm\u00e9e russe dans le sud de l\u2019Ukraine.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin ? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin ? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Avec l\u2019envoi dissimul\u00e9 le 12 mars par la Maison-Blanche de plusieurs missiles ATACMS longue port\u00e9e, Washington a fait sauter un tabou suppl\u00e9mentaire dans le cadre de l\u2019assistance \u00e0 l\u2019Ukraine. Celui-ci pourrait ouvrir la voie \u00e0 la livraison de missiles Taurus par Berlin, mena\u00e7ant ainsi le pont de Crim\u00e9e et le ravitaillement de l\u2019arm\u00e9e russe dans le sud de l\u2019Ukraine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T12:30:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T12:30:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"813\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/\",\"name\":\"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin ? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png\",\"datePublished\":\"2024-04-25T12:30:09+00:00\",\"dateModified\":\"2024-04-25T12:30:10+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png\",\"width\":1453,\"height\":813},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin ? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/","og_locale":"fr_FR","og_type":"article","og_title":"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin ? | Le Grand Continent","og_description":"Avec l\u2019envoi dissimul\u00e9 le 12 mars par la Maison-Blanche de plusieurs missiles ATACMS longue port\u00e9e, Washington a fait sauter un tabou suppl\u00e9mentaire dans le cadre de l\u2019assistance \u00e0 l\u2019Ukraine. Celui-ci pourrait ouvrir la voie \u00e0 la livraison de missiles Taurus par Berlin, mena\u00e7ant ainsi le pont de Crim\u00e9e et le ravitaillement de l\u2019arm\u00e9e russe dans le sud de l\u2019Ukraine.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/","og_site_name":"Le Grand Continent","article_published_time":"2024-04-25T12:30:09+00:00","article_modified_time":"2024-04-25T12:30:10+00:00","og_image":[{"width":1453,"height":813,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/","name":"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin ? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png","datePublished":"2024-04-25T12:30:09+00:00","dateModified":"2024-04-25T12:30:10+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png","width":1453,"height":813},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/25\/washington-a-annonce-lenvoi-de-missiles-longue-portee-a-lukraine-bientot-berlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Washington a annonc\u00e9 l\u2019envoi de missiles longue port\u00e9e \u00e0 l\u2019Ukraine. Bient\u00f4t Berlin&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/gc-ATACMS-Taurus-e1714047779991.png","width":1453,"height":813,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/227534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=227534"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/227534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/227537"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=227534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=227534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=227534"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=227534"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=227534"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=227534"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=227534"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=227534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}