{"id":225914,"date":"2024-04-14T13:52:38","date_gmt":"2024-04-14T11:52:38","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=225914"},"modified":"2024-04-15T10:11:58","modified_gmt":"2024-04-15T08:11:58","slug":"attaque-de-liran-sur-israel-le-point-du-jour-dapres","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/","title":{"rendered":"Attaque de l&rsquo;Iran sur Isra\u00ebl&#160;: le point du jour d&rsquo;apr\u00e8s"},"content":{"rendered":"\n<p>Le jour d\u2019apr\u00e8s, nous commen\u00e7ons \u00e0 disposer d\u2019un cadre clair sur les effets de l\u2019attaque.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon le porte-parole de l\u2019arm\u00e9e isra\u00e9lienne, \u00ab&#160;Plus de 300 projectils \u2014 drones, missiles de croisi\u00e8re et missiles balistiques \u2014 auraient \u00e9t\u00e9 tir\u00e9s depuis l&rsquo;Iran&#160;\u00bb.<\/li>\n\n\n\n<li>L\u2019op\u00e9ration a \u00e9t\u00e9 un \u00e9chec tactique. La plupart des munitions&nbsp;(\u00ab&#160;99&#160;%&#160;\u00bb) ont \u00e9t\u00e9 intercept\u00e9es en dehors de l&rsquo;espace a\u00e9rien isra\u00e9lien. Un tr\u00e8s petit nombre a touch\u00e9 le territoire, causant des dommages mineurs. Une petite fille a \u00e9t\u00e9 bless\u00e9e et une base militaire isra\u00e9lienne a \u00e9t\u00e9 l\u00e9g\u00e8rement endommag\u00e9e&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-225914' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#easy-footnote-bottom-1-225914' title='La base a\u00e9rienne de Nevatim, particuli\u00e8rement cibl\u00e9e par l\u2019Iran car elle aurait \u00e9t\u00e9 \u00e0 l\u2019origine de l\u2019op\u00e9ration du 1er avril contre le complexe diplomatique iranien de Damas, semble encore op\u00e9rationnelle.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Comment expliquer cet \u00e9chec&#160;? Comme l\u2019a not\u00e9 <a href=\"https:\/\/legrandcontinent.eu\/fr\/staff\/bruno-tertrais\/\">Bruno Tertrais<\/a> \u00ab&#160;l&rsquo;attaque iranienne \u00e9tait pr\u00e9vue, annonc\u00e9e, visible&#160;: Isra\u00ebl et ses alli\u00e9s ont pu se pr\u00e9parer \u00e0 la parer et les Iraniens le savaient sans doute&#160;\u00bb. Les drones se d\u00e9placent lentement et en ligne droite, au-dessus d&rsquo;un espace d\u00e9sertique o\u00f9 personne ne sera bless\u00e9 s&rsquo;ils sont intercept\u00e9s \u00e0 temps.<\/li>\n\n\n\n<li>Les \u00c9tats-Unis ont aid\u00e9 Isra\u00ebl \u00e0 abattre la plupart des drones et des missiles. Un point notable&#160;: selon des sources consult\u00e9es par Reuters, l&rsquo;aviation jordanienne aurait abattu des dizaines de drones iraniens qui traversaient le nord et le centre de la Jordanie en direction d&rsquo;Isra\u00ebl.<\/li>\n\n\n\n<li>Bien que les effets r\u00e9els aient \u00e9t\u00e9 peu probants, il s&rsquo;agit bien de la premi\u00e8re attaque lanc\u00e9e par l&rsquo;Iran depuis son sol contre Isra\u00ebl. \u00ab&#160;Un seuil a \u00e9t\u00e9 franchi. Celui d&rsquo;une attaque isra\u00e9lienne massive sur le territoire iranien.&#160;\u00bb.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Si techniquement, l\u2019Iran est \u00e0 l\u2019origine d\u2019une escalade, \u00e0 T\u00e9h\u00e9ran, les autorit\u00e9s se f\u00e9licitent du succ\u00e8s de l\u2019op\u00e9ration, en appelant \u00e0 la retenue.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le chef d\u2019\u00e9tat-major des Forces arm\u00e9es iraniennes, Mohammed Hossein Baqeri, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/pourquoi-liran-a-attaque-israel-comprendre-la-doctrine-de-la-nouvelle-equation\/\">a pris la parole aujourd\u2019hui<\/a> pour indiquer que le pays n\u2019avait pas \u00ab&#160;l&rsquo;intention de poursuivre l&rsquo;op\u00e9ration contre Isra\u00ebl&#160;\u00bb et que les autorit\u00e9s consideraient que \u00ab&#160;cette op\u00e9ration est parvenue \u00e0 ses objectifs et qu\u2019elle est d\u00e9sormais termin\u00e9e.&#160;\u00bb.&nbsp;<\/li>\n\n\n\n<li>Le r\u00e9gime de T\u00e9h\u00e9ran, \u00e0 travers le chef des Gardiens de la R\u00e9volution iranienne,&nbsp;Ali Jafari, parle d\u00e9sormais d\u2019<a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/pourquoi-liran-a-attaque-israel-comprendre-la-doctrine-de-la-nouvelle-equation\/\">une doctrine de la \u00ab&#160;nouvelle \u00e9quation&#160;\u00bb<\/a>&#160;: \u00ab&#160;si le r\u00e9gime sioniste attaque, il fera l\u2019objet d\u2019une contre-attaque depuis l&rsquo;Iran.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-225914' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#easy-footnote-bottom-2-225914' title='Golnaz Esfandiari, Twitter, 14 avril 2024, &lt;a href=&quot;https:\/\/twitter.com\/GEsfandiari\/status\/1779414303503753219&quot;&gt;Accessible en ligne&lt;\/a&gt;.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Le Pr\u00e9sident du Parlement iranien, Mohammad Ghalibaf, s\u2019est \u00e9galement f\u00e9licit\u00e9 d\u2019une attaque \u00ab&#160;pr\u00e9cise&#160;\u00bb qui avait \u00ab&#160;donn\u00e9 une le\u00e7on&#160;\u00bb au \u00ab&#160;r\u00e9gime sioniste&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-225914' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#easy-footnote-bottom-3-225914' title='&lt;em&gt;Iran Press News Agency&lt;\/em&gt;, Vid\u00e9o de la session parlementaire du 14 avril, &lt;a href=&quot;https:\/\/twitter.com\/irannewsvideo\/status\/1779391699493560771&quot;&gt;Disponible en ligne&lt;\/a&gt;.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<p>Revenons en Isra\u00ebl. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/israel-et-gaza-guerre-etendue-une-conversation-avec-gerard-araud\/\">G\u00e9rard Araud<\/a> pose la question clef&#160;: \u00ab&#160;La doctrine strat\u00e9gique isra\u00e9lienne veut que l\u2019ennemi n\u2019ait jamais \u2018le dernier mot\u2019. L\u2019Iran a tir\u00e9 certes sans succ\u00e8s. Maintenant, quoi que disent les Am\u00e9ricains, que va d\u00e9cider Isra\u00ebl&#160;?&#160;\u00bb.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le cabinet de guerre \u00e0 Tel-Aviv se r\u00e9unira aujourd\u2019hui pour d\u00e9cider comment r\u00e9agir. Le Conseil de s\u00e9curit\u00e9 des Nations unies devrait \u00e9galement se r\u00e9unir \u00e0 la demande d&rsquo;Isra\u00ebl.<\/li>\n\n\n\n<li>Le soutien interne \u00e0 Netanyahu reste fort. \u00ab&#160;88&#160;% des Isra\u00e9liens juifs interrog\u00e9s en janvier estiment que le nombre de morts palestiniens reste justifi\u00e9. Une grande majorit\u00e9 pense \u00e9galement que les forces de d\u00e9fense isra\u00e9liennes utilisent une force ad\u00e9quate, voire insuffisante, \u00e0 Gaza&#160;\u00bb.<\/li>\n\n\n\n<li>Il est difficile aujourd&rsquo;hui de voir ce qui pourrait inciter Netanyahou \u00e0 faire autre chose qu&rsquo;une nouvelle escalade \u2014 m\u00eame si l&rsquo;effet de la riposte de l&rsquo;Iran s&rsquo;av\u00e8re symbolique. La frappe du 1er avril en Syrie a donn\u00e9 lieu \u00e0 des promesses de soutien de la part des alli\u00e9s am\u00e9ricains et europ\u00e9ens et a d\u00e9tourn\u00e9 l&rsquo;attention de la question \u00e9pineuse de la survie du Hamas et des mouvements de contestation internes.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019Iran vient de d\u00e9tourner l\u2019attention du conflit \u00e0 Gaza \u2014 s\u2019agit-il d\u2019un pi\u00e8ge strat\u00e9gique isra\u00eblien&#160;? Selon le sp\u00e9cialiste <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/02\/26\/le-futur-dune-ambition-geopolitique-de-liran-dans-lere-post-khamenei-une-conversation-avec-ali-vaez\/\">Ali Vaez<\/a> il ne faut pas sous-estimer le gain de <em>soft power<\/em> dans le monde musulman de cette attaque. <\/p>\n\n\n\n<p>Les images des drones passant sur la Mosqu\u00e9e al-Aqsa sont actuellement en train de faire le tour du monde.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"in\" dir=\"ltr\">Jerusalem now <a href=\"https:\/\/t.co\/ydgrbjFPfD\">pic.twitter.com\/ydgrbjFPfD<\/a><\/p>&mdash; Hind Khoudary (@Hind_Gaza) <a href=\"https:\/\/twitter.com\/Hind_Gaza\/status\/1779289594946625889?ref_src=twsrc%5Etfw\">April 13, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Le soutien \u00e0 Isra\u00ebl de certains pays, comme la Jordanie, produit d&rsquo;ailleurs une clarification sur son positionnement par rapport \u00e0 la crise de Gaza, en le for\u00e7ant \u00e0 prendre parti.<\/p>\n\n\n\n<p>\u00c0 Washington, le pr\u00e9sident des \u00c9tats-Unis Biden a convoqu\u00e9 son Conseil de s\u00e9curit\u00e9 nationale dans la soir\u00e9e d\u2019hier.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>S\u2019il a publiquement r\u00e9affirm\u00e9 \u00ab&#160;un soutien in\u00e9branlable \u00e0 la s\u00e9curit\u00e9 d&rsquo;Isra\u00ebl face aux menaces de l&rsquo;Iran et de ses proxies&#160;\u00bb, selon des informations obtenues par Axios, dans une conversation t\u00e9l\u00e9phonique d\u2019environ 25 minutes le pr\u00e9sident am\u00e9ricain aurait dit \u00e0 Netanyahu que les \u00c9tats-Unis ne seraient pas pr\u00eat \u00e0 soutenir aucune contre-attaque visant l\u2019Iran et son territoire.<\/li>\n\n\n\n<li>Biden a \u00e9galement d\u00e9clar\u00e9&#160;: \u00ab&#160;J&rsquo;ai dit au Premier ministre Netanyahu qu&rsquo;Isra\u00ebl avait fait preuve d&rsquo;une capacit\u00e9 remarquable \u00e0 se d\u00e9fendre contre des attaques sans pr\u00e9c\u00e9dent et \u00e0 les vaincre, envoyant ainsi un message clair \u00e0 ses ennemis&#160;: ils ne peuvent pas menacer efficacement la s\u00e9curit\u00e9 d&rsquo;Isra\u00ebl&#160;\u00bb.<\/li>\n\n\n\n<li>Sur initiative du pr\u00e9sident des \u00c9tats-Unis, les dirigeants du G7 se r\u00e9uniront aujourd\u2019hui pour coordonner une position commune.<\/li>\n<\/ul>\n\n\n\n<p>Il faut noter une tendance contre-intuitive&#160;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comme le remarque <a href=\"https:\/\/legrandcontinent.eu\/fr\/staff\/jean-marie-guehenno\/\">Jean-Marie Gu\u00e9henno<\/a>&#160;: \u00ab&#160;Les attaques relativement mod\u00e9r\u00e9es du Hezbollah et maintenant de l&rsquo;Iran contre Isra\u00ebl sugg\u00e8rent que le concept isra\u00e9lien de dissuasion (utilisation d&rsquo;une force massive comme au Liban en 2006) peut fonctionner&#160;: une conclusion dangereuse qui confortera ceux qui veulent continuer \u00e0 utiliser une force \u00e9crasante \u00e0 Gaza&#160;\u00bb.&nbsp;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Avec l\u2019attaque iranienne d\u2019Isra\u00ebl un seuil a \u00e9t\u00e9 franchi \u2013 mais nous ne sommes pas encore dans une guerre totale. De T\u00e9h\u00e9ran \u00e0 Washington, en passant par Tel Aviv et la Jordanie, nous faisons un point de situation avec tout ce qu\u2019il faut retenir de cette s\u00e9quence particuli\u00e8rement chaude.<\/p>\n","protected":false},"author":40,"featured_media":225915,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"footnotes":""},"categories":[3611],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[],"class_list":["post-225914","post","type-post","status-publish","format-standard","hentry","category-la-guerre-de-soukkot","editorial_format-actu-breves"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":225915,"excerpt":"Avec l\u2019attaque iranienne d\u2019Isra\u00ebl un seuil a \u00e9t\u00e9 franchi \u2013 mais nous ne sommes pas encore dans une guerre totale. De T\u00e9h\u00e9ran \u00e0 Washington, en passant par Tel Aviv et la Jordanie, nous faisons un point de situation avec tout ce qu\u2019il faut retenir de cette s\u00e9quence particuli\u00e8rement chaude.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Attaque de l&#039;Iran sur Isra\u00ebl : le point du jour d&#039;apr\u00e8s | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attaque de l&#039;Iran sur Isra\u00ebl : le point du jour d&#039;apr\u00e8s | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Avec l\u2019attaque iranienne d\u2019Isra\u00ebl un seuil a \u00e9t\u00e9 franchi \u2013 mais nous ne sommes pas encore dans une guerre totale. De T\u00e9h\u00e9ran \u00e0 Washington, en passant par Tel Aviv et la Jordanie, nous faisons un point de situation avec tout ce qu\u2019il faut retenir de cette s\u00e9quence particuli\u00e8rement chaude.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-14T11:52:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T08:11:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ramona Bloj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ramona Bloj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/\",\"name\":\"Attaque de l'Iran sur Isra\u00ebl : le point du jour d'apr\u00e8s | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg\",\"datePublished\":\"2024-04-14T11:52:38+00:00\",\"dateModified\":\"2024-04-15T08:11:58+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg\",\"width\":2560,\"height\":1769,\"caption\":\"(240414) -- JERUSALEM, April 14, 2024 (Xinhua) -- This photo taken on April 14, 2024 shows flares from explosions in the sky over Jerusalem as Israel's Iron Dome anti-missile system intercepts missiles and drones from Iran. A combined attack of dozens of ballistic missiles and hundreds of drones from Iran triggered air raid alerts across Israel early on Sunday, the Israeli army said, as residents reported multiple bombings were heard. (Photo by Jamal Awad\/Xinhua) - Jamal Awad -\/\/CHINENOUVELLE_XxjpbeE007045_20240414_PEPFN0A001\/Credit:CHINE NOUVELLE\/SIPA\/2404141034\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attaque de l&rsquo;Iran sur Isra\u00ebl&#160;: le point du jour d&rsquo;apr\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\",\"name\":\"Ramona Bloj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"caption\":\"Ramona Bloj\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attaque de l'Iran sur Isra\u00ebl : le point du jour d'apr\u00e8s | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/","og_locale":"fr_FR","og_type":"article","og_title":"Attaque de l'Iran sur Isra\u00ebl : le point du jour d'apr\u00e8s | Le Grand Continent","og_description":"Avec l\u2019attaque iranienne d\u2019Isra\u00ebl un seuil a \u00e9t\u00e9 franchi \u2013 mais nous ne sommes pas encore dans une guerre totale. De T\u00e9h\u00e9ran \u00e0 Washington, en passant par Tel Aviv et la Jordanie, nous faisons un point de situation avec tout ce qu\u2019il faut retenir de cette s\u00e9quence particuli\u00e8rement chaude.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/","og_site_name":"Le Grand Continent","article_published_time":"2024-04-14T11:52:38+00:00","article_modified_time":"2024-04-15T08:11:58+00:00","og_image":[{"width":2560,"height":1769,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg","type":"image\/jpeg"}],"author":"Ramona Bloj","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ramona Bloj","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/","name":"Attaque de l'Iran sur Isra\u00ebl : le point du jour d'apr\u00e8s | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg","datePublished":"2024-04-14T11:52:38+00:00","dateModified":"2024-04-15T08:11:58+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg","width":2560,"height":1769,"caption":"(240414) -- JERUSALEM, April 14, 2024 (Xinhua) -- This photo taken on April 14, 2024 shows flares from explosions in the sky over Jerusalem as Israel's Iron Dome anti-missile system intercepts missiles and drones from Iran. A combined attack of dozens of ballistic missiles and hundreds of drones from Iran triggered air raid alerts across Israel early on Sunday, the Israeli army said, as residents reported multiple bombings were heard. (Photo by Jamal Awad\/Xinhua) - Jamal Awad -\/\/CHINENOUVELLE_XxjpbeE007045_20240414_PEPFN0A001\/Credit:CHINE NOUVELLE\/SIPA\/2404141034"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/04\/14\/attaque-de-liran-sur-israel-le-point-du-jour-dapres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Attaque de l&rsquo;Iran sur Isra\u00ebl&#160;: le point du jour d&rsquo;apr\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697","name":"Ramona Bloj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","caption":"Ramona Bloj"}}]}},"lgc_categories":[{"id":3611,"name":"Isra\u00ebl, Hamas&#160;: le 7-Octobre deux ans apr\u00e8s","slug":"la-guerre-de-soukkot"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/04\/SIPA_01153840_000001-scaled.jpg","width":2560,"height":1769,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/225914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=225914"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/225914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/225915"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=225914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=225914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=225914"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=225914"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=225914"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=225914"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=225914"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=225914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}