{"id":215995,"date":"2024-01-23T17:32:55","date_gmt":"2024-01-23T16:32:55","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=215995"},"modified":"2024-01-26T10:19:09","modified_gmt":"2024-01-26T09:19:09","slug":"houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/","title":{"rendered":"Houthis, \u00c9tats-Unis&#160;: comment la guerre s&rsquo;est \u00e9tendue \u00e0 la mer Rouge"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Plus la guerre de Gaza se prolonge, plus la crainte qu&rsquo;elle ne d\u00e9g\u00e9n\u00e8re en quelque chose de beaucoup plus important s\u2019accentue. Elle concerne un pays en particulier&#160;: l&rsquo;Iran, surveill\u00e9 de tr\u00e8s pr\u00e8s puisqu\u2019il est le chef d\u2019orchestre d\u2019un \u00ab&#160;axe de la r\u00e9sistance&#160;\u00bb dont fait partie le Hamas, il pourrait donner \u00e0 ses autres membres, dont le Hezbollah au Liban et les Houthis au Y\u00e9men, le feu vert pour augmenter le niveau de leurs attaques.<\/p>\n\n\n\n<p>L&rsquo;attention s&rsquo;\u00e9tait surtout port\u00e9e derni\u00e8rement sur le Hezbollah, \u00e0 la fronti\u00e8re nord d&rsquo;Isra\u00ebl. Les \u00e9changes de tirs de part et d\u2019autres n&rsquo;ont pas d\u00e9bouch\u00e9 sur des hostilit\u00e9s \u00e0 grande \u00e9chelle, mais l\u2019on y a peut-\u00eatre \u00e9chapp\u00e9 de justesse. Ces affrontements ont commenc\u00e9 juste apr\u00e8s les attaques du Hamas le 7 octobre, lorsque le Hezbollah a tir\u00e9 des roquettes et des obus \u00ab&#160;en solidarit\u00e9&#160;\u00bb avec l\u2019organisation terroriste. Il continue \u00e0 le faire et Isra\u00ebl d\u00e9truit quant \u00e0 lui des <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/03\/frappe-a-beyrouth-nouvelles-craintes-dextension-regionale-de-la-guerre-israel-hamas\/\">positions du Hamas au Liban<\/a>. Au cours des trois derniers mois, neuf soldats isra\u00e9liens et quatre civils ont \u00e9t\u00e9 tu\u00e9s, tandis que 123 personnes, dont au moins 21 civils, auraient trouv\u00e9 la mort au Liban&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-1-215995' title='Wyre Davies, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bbc.com\/news\/world-middle-east-67921167&quot;&gt;&amp;lsquo;I cannot sleep in peace&amp;rsquo; &amp;#8211; Israelis fearful as Hezbollah tensions soar&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;BBC&lt;\/em&gt;, 9 janvier 2024.'><sup>1<\/sup><\/a><\/span><\/span>. Plus de 80 000 r\u00e9sidents isra\u00e9liens ont \u00e9t\u00e9 \u00e9vacu\u00e9s des zones frontali\u00e8res.<\/p>\n\n\n\n<p>Apr\u00e8s que Wissam Tawil, un commandant des forces d&rsquo;\u00e9lite Radwan du Hezbollah, a \u00e9t\u00e9 tu\u00e9 par une frappe isra\u00e9lienne, le Hezbollah a ripost\u00e9 par une attaque de drone contre le quartier g\u00e9n\u00e9ral de l&rsquo;arm\u00e9e isra\u00e9lienne \u00e0 Safed, dans le nord d&rsquo;Isra\u00ebl, mais sans apparemment causer de d\u00e9g\u00e2ts ou de victimes. Le chef adjoint du Hezbollah, Na\u00efm Qassem, a \u00e9galement soulign\u00e9 que le groupe ne souhaitait pas \u00e9tendre la guerre, ajoutant que si elle \u00e9tait \u00e9tendue par Isra\u00ebl, \u00ab&#160;la r\u00e9ponse serait in\u00e9vitable, dans toute la mesure n\u00e9cessaire pour dissuader Isra\u00ebl&#160;\u00bb. Or, le Liban ne serait pas en mesure de faire face \u00e0 une confrontation majeure. C\u2019est dans ce sens que le secr\u00e9taire d&rsquo;\u00c9tat am\u00e9ricain Antony Blinken a insist\u00e9 aupr\u00e8s d&rsquo;Isra\u00ebl pour qu&rsquo;il n&rsquo;ajoute pas au chaos r\u00e9gional actuel en <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/06\/le-moyen-orient-selon-nasrallah-geopolitique-du-hezbollah\/\">s&rsquo;engageant dans une guerre majeure avec le Hezbollah<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le Liban ne serait pas en mesure de faire face \u00e0 une confrontation majeure<\/p><cite>Lawrence Freedman<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En parall\u00e8le, les troupes am\u00e9ricaines en Irak et en Syrie, toujours pr\u00e9sentes apr\u00e8s la lutte contre Daech, ont \u00e9t\u00e9 attaqu\u00e9es par des milices soutenues par l&rsquo;Iran \u00e0 plus de 130 reprises depuis le 17 octobre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-2-215995' title='Steven Erlanger, David E. Sanger, Farnaz Fassihi et Ronen Bergman, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.nytimes.com\/2024\/01\/12\/us\/politics\/mideast-war-israel-yemen.html&quot;&gt;The Regional War No One Wanted Is Here. How Wide Will It Get&amp;#160;?&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The New York Times&lt;\/em&gt;, 12 janvier 2024.'><sup>2<\/sup><\/a><\/span><\/span>. S\u2019il n&rsquo;y a pas eu de morts am\u00e9ricains, on d\u00e9nombre plusieurs bless\u00e9s. Ces attaques ont suscit\u00e9 des ripostes de la part des \u00c9tats-Unis \u2014 une dizaine jusqu&rsquo;\u00e0 pr\u00e9sent. La plus s\u00e9rieuse a eu lieu le 4 janvier, lorsqu&rsquo;un chef de milice accus\u00e9 d&rsquo;\u00eatre \u00e0 l&rsquo;origine de celles-ci a \u00e9t\u00e9 tu\u00e9 \u00e0 Bagdad.<\/p>\n\n\n\n<p>Mais l\u2019escalade la plus spectaculaire \u2014 et celle qui retient aujourd\u2019hui l\u2019attention de la communaut\u00e9 internationale \u2014 concerne la confrontation avec les Houthis y\u00e9m\u00e9nites en mer Rouge. La menace que leurs actions font <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/04\/comment-les-attaques-houthistes-provoquent-une-reorganisation-du-trafic-maritime-mondial\/\">peser sur le transport maritime international<\/a> a conduit les \u00c9tats-Unis et le Royaume-Uni \u00e0 lancer des frappes t\u00f4t dans la matin\u00e9e du vendredi 12 janvier. Depuis, cette op\u00e9ration continue et les \u00c9tats-Unis ont accentu\u00e9 leurs frappes. La guerre est-elle sur le point de s&rsquo;\u00e9tendre davantage&#160;?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qui sont les Houthis&#160;?<\/strong><\/h2>\n\n\n\n<p>Les Houthis \u2014 qui pr\u00e9f\u00e8rent qu\u2019on les appelle du nom d&rsquo;Ansar Allah (\u00ab&#160;Partisans de Dieu&#160;\u00bb) \u2014 ne sont pas de simples marionnettes de l&rsquo;Iran. Ils prennent leurs propres d\u00e9cisions. Mais leurs int\u00e9r\u00eats sont tr\u00e8s clairement align\u00e9s et leurs capacit\u00e9s ont \u00e9t\u00e9 renforc\u00e9es gr\u00e2ce au soutien substantiel de T\u00e9h\u00e9ran. Bien qu&rsquo;ils fassent partie de \u00ab&#160;l&rsquo;axe de la r\u00e9sistance&#160;\u00bb, ils ont leurs propres caract\u00e9ristiques \u2014 et leurs propres int\u00e9r\u00eats. Les Houthis sont originaires du Y\u00e9men du Nord, qui s&rsquo;est joint \u00e0 l&rsquo;ancienne colonie britannique du Y\u00e9men du Sud pour former un \u00c9tat unifi\u00e9, mais qui s&rsquo;est ensuite d\u00e9chir\u00e9 en 1990. Sur le plan religieux, ils sont chiites zaydites, c\u2019est-\u00e0-dire relativement mod\u00e9r\u00e9s. Au fil des ann\u00e9es, leur politique a \u00e9t\u00e9 souple et, bien qu\u2019ils se soient d\u00e9velopp\u00e9s \u00e0 partir d\u2019une tribu, ils b\u00e9n\u00e9ficient d&rsquo;un soutien plus large&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-3-215995' title='\u00a0Pour une excellente pr\u00e9sentation des Houthis, voir&amp;#160;: Elisabeth Kendall, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/engelsbergideas.com\/essays\/the-houthis-forgotten-war-goes-global\/?utm_source=substack&amp;amp;utm_medium=email&quot;&gt;The Houthis\u2019 forgotten war goes global&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Engelsberg Ideas&lt;\/em&gt;, 11 janvier 2024.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22845902_000012-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22845902_000012-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22845902_000012-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22845902_000012-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22845902_000012-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Cette image fournie par la marine am\u00e9ricaine montre un avion lanc\u00e9 depuis l&rsquo;USS Dwight D. Eisenhower (CVN 69) lors d&rsquo;op\u00e9rations de vol en mer Rouge, le 22 janvier 2024. Les arm\u00e9es am\u00e9ricaine et britannique ont bombard\u00e9 plusieurs cibles sur huit sites utilis\u00e9s par les Houthis soutenus par l&rsquo;Iran au Y\u00e9men dans la nuit de lundi \u00e0 mardi. C&rsquo;est la deuxi\u00e8me fois que les deux alli\u00e9s m\u00e8nent des frappes de repr\u00e9sailles coordonn\u00e9es sur un ensemble de capacit\u00e9s de lancement de missiles des rebelles. \u00a9 Kaitlin Watt\/U.S. Navy via AP<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Leur identit\u00e9 chiite dans un \u00c9tat majoritairement sunnite \u2014 ils repr\u00e9sentent environ un tiers de la population \u2014 a fait d&rsquo;eux une force radicale dans la politique y\u00e9m\u00e9nite. Le gouvernement du Y\u00e9men a tent\u00e9 \u00e0 plusieurs reprises de les \u00e9liminer lors de combats qui ont dur\u00e9 de 2004 \u00e0 2010, les Saoudiens les ayant directement rejoints en 2010. C\u2019est lors des printemps arabes de 2011 qu\u2019ils se joignent \u00e0 la tentative de forger un nouvel ordre politique pour le Y\u00e9men. Malheureusement, ils d\u00e9chantent vite et d\u00e9cident, en septembre 2014, de prendre les armes contre le gouvernement. Ils s\u2019emparent de la capitale, Sanaa, chassent le pr\u00e9sident Abdrabbo Mansour Hadi et cherchent \u00e0 \u00e9largir leur audience en insistant sur la n\u00e9cessit\u00e9 de lutter contre la corruption et l&rsquo;incomp\u00e9tence. Alors qu&rsquo;ils gagnent en puissance dans la guerre civile qui les oppose au gouvernement, Hadi \u2014 qui est toujours reconnu internationalement comme pr\u00e9sident du Y\u00e9men \u2014 cherche un soutien ext\u00e9rieur. Celui-ci prendra la forme d&rsquo;une coalition dirig\u00e9e par les Saoudiens, qui se retrouvent dans une situation beaucoup plus difficile que pr\u00e9vu. En lieu et place de la victoire rapide qu\u2019ils esp\u00e9raient, ils s\u2019enlisent dans une guerre longue et douloureuse au cours de laquelle ils sont accus\u00e9s d&rsquo;avoir caus\u00e9 la mort de pas moins de 20 000 civils, le blocus des ports y\u00e9m\u00e9nites ayant provoqu\u00e9 une grave crise humanitaire.<\/p>\n\n\n\n<p>Cette guerre a fa\u00e7onn\u00e9 les Houthis. Au cours de son d\u00e9roulement, le groupe est devenu \u00e0 la fois plus dur, plus r\u00e9pressif et plus proche de l&rsquo;Iran. C&rsquo;est dans le contexte de cet affrontement qu&rsquo;ils d\u00e9veloppent des drones d&rsquo;attaque et des missiles \u00e0 longue port\u00e9e \u2014 qu&rsquo;ils utilisent pour lancer des attaques r\u00e9guli\u00e8res contre des installations p\u00e9troli\u00e8res en Arabie saoudite et aux \u00c9mirats arabes unis. Dans un premier temps, ils attaquent des cibles proches de la fronti\u00e8re. Puis leurs attaques deviennent plus sophistiqu\u00e9es et de plus longue port\u00e9e. Les Houthis vont finir par d\u00e9velopper des capacit\u00e9s de fabrication locales pour leurs drones a\u00e9riens et navals \u00e0 longue port\u00e9e en important d\u2019Iran des pi\u00e8ces de contrebande. En d\u00e9cembre 2021, le Royaume indique que les Houthis auraient envoy\u00e9 430 missiles balistiques et 851 drones arm\u00e9s sur l&rsquo;Arabie saoudite depuis le d\u00e9but de la guerre en 2015, tuant 59 civils saoudiens&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-4-215995' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/world\/middle-east\/houthis-have-fired-430-missiles-851-drones-saudi-arabia-since-2015-saudi-led-2021-12-26\/?utm_source=substack&amp;amp;utm_medium=email&quot;&gt;Houthis have fired 430 missiles, 851 drones at Saudi Arabia since 2015 &amp;#8211; Saudi-led coalition&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 26 d\u00e9cembre 2021.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La guerre a fa\u00e7onn\u00e9 les Houthis<\/p><cite>Lawrence Freedman<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L\u2019attitude de Joe Biden vis-\u00e0-vis de Riyad a \u00e9t\u00e9 beaucoup moins dure que celle de Donald Trump. Une fois pr\u00e9sident, il a cherch\u00e9 \u00e0 am\u00e9liorer la situation humanitaire en supprimant la d\u00e9signation des Houthis comme organisation terroriste \u2014 qui n&rsquo;avait \u00e9t\u00e9 impos\u00e9e que r\u00e9cemment \u2014 car ce label emp\u00eache l&rsquo;acheminement de l&rsquo;aide au Y\u00e9men. Les Saoudiens conclurent qu&rsquo;ils n&rsquo;avaient pas d&rsquo;autre choix que d\u2019engager la discussion avec les Houthis pour mettre fin \u00e0 la guerre, bien qu&rsquo;une formule de paix n&rsquo;ait pas encore \u00e9t\u00e9 trouv\u00e9e. Une tr\u00eave pr\u00e9caire a \u00e9t\u00e9 conclue en avril 2022, qui a dur\u00e9 jusqu&rsquo;\u00e0 pr\u00e9sent, soit plus que les six mois initialement pr\u00e9vus. Elle a laiss\u00e9 aux Houthis le contr\u00f4le du nord du Y\u00e9men et plus des deux tiers de la population totale de 20 millions d&rsquo;habitants. Comme l&rsquo;a rapport\u00e9 r\u00e9cemment <em>The Economist<\/em>, les combats ont laiss\u00e9 un pays exsangue&#160;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><\/p>\n<cite>\u00ab&#160;Les Nations unies estiment que 223 000 personnes sont mortes de faim et du manque de soins m\u00e9dicaux depuis le d\u00e9but de la guerre. 80&#160;% de la population vit aujourd&rsquo;hui dans la pauvret\u00e9. Rien de tout cela ne d\u00e9range les Houthis, qui volent l&rsquo;aide alimentaire, imposent une s\u00e9rie de taxes pour lever des fonds et s&rsquo;appuient sur l&rsquo;Iran pour leur soutien militaire. Ils ont maintenu un long si\u00e8ge sur la ville de Ta&rsquo;izz, dans le sud-ouest du pays, emp\u00eachant les civils d&rsquo;apporter de la nourriture et des m\u00e9dicaments, exactement comme ils accusent Isra\u00ebl de le faire \u00e0 Gaza&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-5-215995' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.economist.com\/middle-east-and-africa\/2024\/01\/12\/the-houthis-have-survived-worse-than-americas-and-britains-strikes?utm_source=substack&amp;amp;utm_medium=email&quot;&gt;The Houthis have survived worse than America\u2019s and Britain\u2019s strikes&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Economist&lt;\/em&gt;, 12 janvier 2024.'><sup>5<\/sup><\/a><\/span><\/span>.<br><\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Op\u00e9ration Prosperity Guardian<\/strong><\/h2>\n\n\n\n<p>Le 8 octobre 2023, au lendemain des attaques du Hamas contre Isra\u00ebl qui ont provoqu\u00e9 le d\u00e9clenchement de <a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/guerre\/la-guerre-de-soukkot\/\">la guerre de Soukkot<\/a>, Washington a d\u00e9ploy\u00e9 en M\u00e9diterran\u00e9e orientale un groupe a\u00e9ronaval comprenant le porte-avions <em>USS Gerald R. Ford,<\/em> un croiseur et trois destroyers. Cette man\u0153uvre avait en grande partie pour but de mettre en garde l&rsquo;Iran contre toute intervention directe. Les attaques des Houthis contre les navires commerciaux ont commenc\u00e9 le m\u00eame jour.<\/p>\n\n\n\n<p>Le 19 octobre, l&rsquo;un des destroyers, l&rsquo;USS <em>Carney, <\/em>intercepte quatre missiles de croisi\u00e8re et 15 drones lanc\u00e9s par les Houthis, manifestement dirig\u00e9s contre Isra\u00ebl. Le 19 novembre, ayant peut-\u00eatre d\u00e9cid\u00e9 qu&rsquo;ils ne pouvaient pas s&rsquo;en prendre directement \u00e0 Isra\u00ebl, ils se tournent vers la navigation commerciale en s&#8217;emparant d&rsquo;un cargo, le <em>Galaxy Leader<\/em>, et en le d\u00e9tournant vers le port de Hodeidah. Bien qu&rsquo;il appartienne \u00e0 des Britanniques et soit exploit\u00e9 par des Japonais, ils affirment que ce navire est li\u00e9 \u00e0 Isra\u00ebl. \u00c0 ce jour, cela reste leur principal succ\u00e8s dans cette s\u00e9quence. Le 3 d\u00e9cembre, l\u2019USS <em>Carney <\/em>et quelques navires commerciaux sont attaqu\u00e9s dans les eaux internationales par des missiles balistiques anti-navires tir\u00e9s depuis le Y\u00e9men. Trois navires commerciaux sont touch\u00e9s, tandis que le<em> Carney <\/em>abat trois drones.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les attaques de Houthis contre les navires commerciaux ont commenc\u00e9 le jour m\u00eame o\u00f9 Washington a d\u00e9ploy\u00e9 un groupe a\u00e9ronaval en M\u00e9diterran\u00e9e orientale.<\/p><cite>Lawrence Freedman<\/cite><\/blockquote><\/figure>\n\n\n\n<p>C\u2019est \u00e0 partir de ce moment que les \u00c9tats-Unis intensifient leur r\u00e9ponse. Des sanctions \u00e0 l&rsquo;encontre de 13 personnes et entit\u00e9s soup\u00e7onn\u00e9es de financer les Houthis sont annonc\u00e9es le 7 d\u00e9cembre, puis d&rsquo;autres entit\u00e9s sont sanctionn\u00e9es \u00e0 la fin du mois pour avoir achemin\u00e9 de l&rsquo;argent iranien vers les forces houthistes. Le 19 d\u00e9cembre, le secr\u00e9taire \u00e0 la D\u00e9fense am\u00e9ricain Lloyd Austin annonce la formation d&rsquo;une coalition de vingt pays qui enverront des navires pour s&rsquo;opposer aux attaques contre la navigation en mer Rouge.&nbsp;<\/p>\n\n\n\n<p>Cette coalition est difficile \u00e0 mettre en place&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-6-215995' title='Phil Stewart, David Latona et Angelo Amante, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/world\/us-allies-reluctant-red-sea-task-force-2023-12-28\/&quot;&gt;US allies reluctant on Red Sea task force&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 28 d\u00e9cembre 2023.'><sup>6<\/sup><\/a><\/span><\/span>. La plupart des \u00c9tats partagent les inqui\u00e9tudes concernant la menace qui p\u00e8se sur la navigation, mais craignent d&rsquo;\u00eatre associ\u00e9s \u00e0 quoi que ce soit qui puisse \u00eatre per\u00e7u comme une aide \u00e0 Isra\u00ebl. C&rsquo;est pourquoi huit des vingt \u00c9tats ne souhaitent pas se d\u00e9clarer partie prenante \u2014&nbsp;pr\u00e9servant en quelque sorte leur \u00ab&#160;anonymat&#160;\u00bb. L&rsquo;Italie et l&rsquo;Espagne prennent quant \u00e0 elles leurs distances par rapport \u00e0 cette force. Compte tenu de leurs relations tendues avec les Houthis, les Saoudiens et les \u00c9miratis ne veulent pas entendre parler de cette force conjointe \u2014 du moins publiquement \u2014 car ils souhaitent toujours s&rsquo;extraire de la guerre au Y\u00e9men&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-7-215995' title='Alexander Cornwell et Pesha Magid, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/world\/middle-east\/riyadh-reluctant-derail-iran-detente-over-us-red-sea-taskforce-2023-12-20\/?utm_source=substack&amp;amp;utm_medium=email&quot;&gt;Riyadh reluctant to derail Iran detente over U.S. Red Sea taskforce&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 20 d\u00e9cembre 2023.'><sup>7<\/sup><\/a><\/span><\/span>. La France d\u00e9clare qu&rsquo;elle souhaite \u00e9galement prot\u00e9ger la libert\u00e9 de navigation, mais que ses navires resteraient sous son commandement. New Delhi adopte une position similaire en envoyant des destroyers dans le golfe d&rsquo;Aden apr\u00e8s l&rsquo;attaque d&rsquo;un de ses navires.<\/p>\n\n\n\n<p>Au cours des derni\u00e8res semaines, l&rsquo;inqui\u00e9tude s&rsquo;est toutefois accrue quant \u00e0 l&rsquo;ampleur de la menace qui p\u00e8se sur le transport maritime&#160;: la mer Rouge est le point d&rsquo;entr\u00e9e des navires empruntant le canal de Suez, qui assure environ 12&#160;% du commerce mondial. En raison des attaques des Houthis, de nombreux navires se sont retrouv\u00e9s d\u00e9rout\u00e9s autour du cap de Bonne-Esp\u00e9rance en Afrique, ce qui a consid\u00e9rablement augment\u00e9 la dur\u00e9e et les co\u00fbts de navigation et perturb\u00e9 les cha\u00eenes d&rsquo;approvisionnement.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/ZhKty\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La veille du Nouvel An, le <em>Maersk Hangzhou<\/em>, un porte-conteneurs, a signal\u00e9 \u00eatre la cible de tirs de la part de quatre petits navires houthis. Il signale \u00e9galement des tentatives d&rsquo;abordage. Une \u00e9quipe de s\u00e9curit\u00e9 \u00e0 bord repousse les intrus. Le porte-avions USS <em>Dwight D. Eisenhower <\/em>et le destroyer USS <em>Gravely <\/em>r\u00e9pondent \u00e0 l&rsquo;appel de d\u00e9tresse. Selon le commandement central des \u00c9tats-Unis, les navires de guerre ont lanc\u00e9 des \u00ab&#160;appels verbaux&#160;\u00bb aux petites embarcations&#160;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><\/p>\n<cite>\u00ab&#160;Les petites embarcations ont tir\u00e9 sur les h\u00e9licopt\u00e8res am\u00e9ricains avec des armes de service et des armes l\u00e9g\u00e8res. Les h\u00e9licopt\u00e8res de la marine am\u00e9ricaine ont ripost\u00e9 en l\u00e9gitime d\u00e9fense, coulant trois des quatre petites embarcations et tuant leurs \u00e9quipages. Le quatri\u00e8me bateau a fui la zone. Le personnel et le mat\u00e9riel am\u00e9ricains n&rsquo;ont subi aucun d\u00e9g\u00e2t&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-8-215995' title='&lt;a href=&quot;https:\/\/twitter.com\/CENTCOM\/status\/1741381969936834951?s=20&amp;amp;utm_source=substack&amp;amp;utm_medium=email&quot;&gt;Publication sur X (Twitter) du U.S. Central Command&lt;\/a&gt;, 31 d\u00e9cembre 2023.'><sup>8<\/sup><\/a><\/span><\/span>.<br><\/cite><\/blockquote>\n\n\n\n<p>Le 10 janvier, les navires de la force op\u00e9rationnelle am\u00e9ricaine et le <em>HMS Diamond <\/em>de la Royal Navy abattent 18 drones, deux missiles de croisi\u00e8re et un missile balistique. Il s&rsquo;agit de l&rsquo;attaque la plus importante men\u00e9e \u00e0 ce jour par les Houthis.<\/p>\n\n\n\n<p>La menace est l\u00e0&#160;: elle ne peut plus \u00eatre contourn\u00e9e. D\u00e8s le 3 janvier, le Royaume-Uni, les \u00c9tats-Unis, l&rsquo;Australie, Bahre\u00efn, la Belgique, le Canada, le Danemark, l&rsquo;Allemagne, l&rsquo;Italie, le Japon, les Pays-Bas, la Nouvelle-Z\u00e9lande, la Cor\u00e9e du Sud et Singapour mettent conjointement en garde les Houthis qui \u00ab&#160;assumeront la responsabilit\u00e9 des cons\u00e9quences s&rsquo;ils continuent \u00e0 menacer des vies, l&rsquo;\u00e9conomie mondiale ou la libre circulation du commerce dans les voies navigables essentielles de la r\u00e9gion&#160;\u00bb.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22832907_000004.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"1620\" \n                    data-pswp-height=\"1080\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22832907_000004.jpg\" alt=\"Sur cette photographie publi\u00e9e par le Houthi Media Center, des forces houthies abordent le Galaxy Leader, le dimanche 19 novembre 2023. Les Houthis du Y\u00e9men se sont empar\u00e9s du navire en mer Rouge, au large des c\u00f4tes du Y\u00e9men, apr\u00e8s avoir menac\u00e9 de saisir tous les navires appartenant \u00e0 des soci\u00e9t\u00e9s isra\u00e9liennes. \u00a9 Houthi Media Center via AP\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Sur cette photographie publi\u00e9e par le Houthi Media Center, des forces houthies abordent le Galaxy Leader, le dimanche 19 novembre 2023. Les Houthis du Y\u00e9men se sont empar\u00e9s du navire en mer Rouge, au large des c\u00f4tes du Y\u00e9men, apr\u00e8s avoir menac\u00e9 de saisir tous les navires appartenant \u00e0 des soci\u00e9t\u00e9s isra\u00e9liennes. \u00a9 Houthi Media Center via AP<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22832907_000002.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"1620\" \n                    data-pswp-height=\"1080\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22832907_000002.jpg\" alt=\"Sur cette photographie publi\u00e9e par le Houthi Media Center, un h\u00e9licopt\u00e8re des forces houthies s'approche du cargo Galaxy Leader le dimanche 19 novembre 2023. Les Houthis se sont empar\u00e9s du navire dans la mer Rouge, au large des c\u00f4tes du Y\u00e9men, apr\u00e8s avoir menac\u00e9 de saisir tous les navires appartenant \u00e0 des soci\u00e9t\u00e9s isra\u00e9liennes. \u00a9 Houthi Media Center via AP\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Sur cette photographie publi\u00e9e par le Houthi Media Center, un h\u00e9licopt\u00e8re des forces houthies s&rsquo;approche du cargo Galaxy Leader le dimanche 19 novembre 2023. Les Houthis se sont empar\u00e9s du navire dans la mer Rouge, au large des c\u00f4tes du Y\u00e9men, apr\u00e8s avoir menac\u00e9 de saisir tous les navires appartenant \u00e0 des soci\u00e9t\u00e9s isra\u00e9liennes. \u00a9 Houthi Media Center via AP<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>Sur cette photographie publi\u00e9e par le Houthi Media Center, des forces houthies abordent le Galaxy Leader, le dimanche 19 novembre 2023. Les Houthis du Y\u00e9men se sont empar\u00e9s du navire en mer Rouge, au large des c\u00f4tes du Y\u00e9men, apr\u00e8s avoir menac\u00e9 de saisir tous les navires appartenant \u00e0 des soci\u00e9t\u00e9s isra\u00e9liennes. \u00a9 Houthi Media Center via AP<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>Sur cette photographie publi\u00e9e par le Houthi Media Center, un h\u00e9licopt\u00e8re des forces houthies s&rsquo;approche du cargo Galaxy Leader le dimanche 19 novembre 2023. Les Houthis se sont empar\u00e9s du navire dans la mer Rouge, au large des c\u00f4tes du Y\u00e9men, apr\u00e8s avoir menac\u00e9 de saisir tous les navires appartenant \u00e0 des soci\u00e9t\u00e9s isra\u00e9liennes. \u00a9 Houthi Media Center via AP<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>Apr\u00e8s l&rsquo;attaque du 10 janvier, la vingt-sixi\u00e8me sur les voies de navigation commerciale en mer Rouge depuis le 19 novembre, une r\u00e9solution du Conseil de s\u00e9curit\u00e9 des Nations unies, parrain\u00e9e par les \u00c9tats-Unis et le Japon, est adopt\u00e9e. Elle exige \u00ab&#160;que les Houthis cessent imm\u00e9diatement toutes ces attaques, qui entravent le commerce mondial et portent atteinte aux droits et libert\u00e9s de la navigation ainsi qu&rsquo;\u00e0 la paix et \u00e0 la s\u00e9curit\u00e9 r\u00e9gionales&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-9-215995' title='David Gritten, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bbc.com\/news\/world-middle-east-67932725?utm_source=substack&amp;amp;utm_medium=email&quot;&gt;US and UK hint at military action after largest Houthi attack in Red Sea&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;BBC&lt;\/em&gt;, 11 janvier 2024.'><sup>9<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Il est important de noter qu&rsquo;elle permet aux \u00c9tats membres, conform\u00e9ment au droit international, \u00ab&#160;de d\u00e9fendre leurs navires contre les attaques, y compris celles qui portent atteinte aux droits et libert\u00e9s de navigation&#160;\u00bb. Onze pays votent en sa faveur \u2014 la Russie, la Chine, le Mozambique et l&rsquo;Alg\u00e9rie s\u2019abstiennent.<\/p>\n\n\n\n<p>Jeudi 11 janvier, une vingt-septi\u00e8me attaque a lieu lorsqu&rsquo;un missile balistique antinavire est tir\u00e9 \u00e0 proximit\u00e9 d&rsquo;un navire commercial \u2014 finissant dans l\u2019eau. Apr\u00e8s avoir averti les Houthis de ne pas poursuivre leurs attaques, les membres de ce qu\u2019il est d\u00e9sormais convenu d\u2019appeler<a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/19\/dix-pays-sunissent-face-aux-attaques-des-houthistes-en-mer-rouge\/\"> l&rsquo;op\u00e9ration \u00ab&#160;Prosperity Guardian&#160;\u00bb<\/a> sont toujours susceptibles de r\u00e9agir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La r\u00e9ponse des \u00c9tats-Unis et du Royaume-Uni<\/strong><\/h2>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/12\/les-etats-unis-et-le-royaume-uni-frappent-des-cibles-houthistes-au-yemen\/\">Les frappes<\/a> men\u00e9es par les \u00c9tats-Unis et le Royaume-Uni contre les capacit\u00e9s des Houthis au Y\u00e9men, t\u00f4t dans la matin\u00e9e du vendredi 12 janvier, n&rsquo;\u00e9taient pas destin\u00e9es \u00e0 punir ou \u00e0 \u00ab&#160;envoyer un message&#160;\u00bb. De mani\u00e8re beaucoup plus op\u00e9rationnelle, elles visaient \u00e0 rendre tr\u00e8s difficile la poursuite par les Houthis de leur campagne de piraterie maritime. Les cibles n&rsquo;\u00e9taient d\u2019ailleurs pas du tout \u00ab&#160;symboliques&#160;\u00bb&#160;: ces attaques ont \u00e9t\u00e9 men\u00e9es contre les capteurs qui permettaient aux Houthis d&rsquo;identifier et de suivre les cibles, ainsi que contre des missiles, des drones, les usines qui les fabriquent et des entrep\u00f4ts. Au total, une centaine d&rsquo;armes de pr\u00e9cision ont touch\u00e9 60 cibles r\u00e9parties sur 16 sites. Les quatre Typhoons de la <em>Royal Air Force<\/em> ont attaqu\u00e9 deux sites, tous deux utilis\u00e9s pour lancer des drones de reconnaissance et d&rsquo;attaque, ainsi que des missiles. Les cibles semblent avoir \u00e9t\u00e9 touch\u00e9es comme pr\u00e9vu. L&rsquo;importance de l&rsquo;acquisition des capteurs explique le fait qu\u2019il y ait eu une frappe successive le lendemain matin contre un radar qui avait vraisemblablement surv\u00e9cu \u00e0 une premi\u00e8re tentative de destruction le vendredi.<\/p>\n\n\n\n<p>Les dommages collat\u00e9raux sont rest\u00e9s limit\u00e9s. La majorit\u00e9 des cibles n&rsquo;\u00e9taient pas situ\u00e9es dans des agglom\u00e9rations. Les Houthis ont d\u00e9clar\u00e9 que cinq de leurs combattants avaient \u00e9t\u00e9 tu\u00e9s et six bless\u00e9s lors des frappes. Malgr\u00e9 la rh\u00e9torique du pr\u00e9sident turc Erdo\u011fan sur la transformation de la mer Rouge en une \u00ab&#160;mer de sang&#160;\u00bb, ce n&rsquo;est pas ce qui est ressorti de cette op\u00e9ration. Aucun dirigeant houthi ni conseiller iranien n&rsquo;a par ailleurs \u00e9t\u00e9 pris pour cible. Nous sommes assez loin d\u2019une tentative de changement de r\u00e9gime.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les frappes men\u00e9es par les \u00c9tats-Unis et le Royaume-Uni contre les capacit\u00e9s des Houthis au Y\u00e9men, t\u00f4t dans la matin\u00e9e du vendredi 12 janvier, n&rsquo;\u00e9taient pas destin\u00e9es \u00e0 punir ou \u00e0 \u00ab&#160;envoyer un message&#160;\u00bb. Elles visaient op\u00e9rationnellement \u00e0 rendre tr\u00e8s difficile la poursuite par les Houthis de leur campagne de piraterie maritime.<\/p><cite>Lawrence Freedman<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Or, pour la suite des \u00e9v\u00e9nements, cela n&rsquo;est pas sans importance.<\/p>\n\n\n\n<p>Des pertes civiles substantielles, surtout \u00e0 la lumi\u00e8re de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/a-gaza-le-bilan-humain-continue-de-salourdir\/\">ce qui se passe \u00e0 Gaza<\/a>, auraient intensifi\u00e9 les demandes de repr\u00e9sailles et une tentative de destitution des dirigeants pourrait d\u00e9boucher sur un conflit beaucoup plus grave. Or, m\u00eame si ces frappes peuvent \u00eatre \u2014 et seront sans doute \u2014 lourdes de cons\u00e9quences, elles \u00e9taient pr\u00e9cises, discr\u00e8tes et conservaient un objectif limit\u00e9. Le leader des Houthis, Mohammed al-Bukhaiti, a d\u00e9clar\u00e9 que les \u00c9tats-Unis et le Royaume-Uni \u00ab&#160;se rendraient bient\u00f4t compte&#160;\u00bb que cette action \u00e9tait \u00ab&#160;la plus grande folie de leur histoire&#160;\u00bb. Mais cela s&rsquo;est produit alors que les frappes \u00e9taient en cours et avant qu&rsquo;ils n&rsquo;aient eu la possibilit\u00e9 d&rsquo;\u00e9valuer les d\u00e9g\u00e2ts. Il est toutefois difficile de savoir dans quelle mesure elles auront r\u00e9ellement d\u00e9grad\u00e9 les capacit\u00e9s des Houthis, car les renseignements sur l&rsquo;ensemble de leurs r\u00e9serves de missiles sont limit\u00e9s&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-10-215995' title='Pour un \u00e9tat des lieux, voir&amp;#160;: Fabian Hinz, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.iiss.org\/online-analysis\/military-balance\/2024\/01\/houthi-anti-ship-missile-systems-getting-better-all-the-time\/&quot;&gt;Houthi anti-ship missile systems&amp;#160;: getting better all the time&lt;\/a&gt;&amp;#160;\u00bb, International Institute for Strategic Studies (IISS), 8 janvier 2024.'><sup>10<\/sup><\/a><\/span><\/span>, et les frappes ont \u00e9t\u00e9 t\u00e9l\u00e9graphi\u00e9es suffisamment \u00e0 l&rsquo;avance pour que certains syst\u00e8mes aient d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9plac\u00e9s vers un endroit plus s\u00fbr.<\/p>\n\n\n\n<p>Une guerre des r\u00e9cits est d\u00e9j\u00e0 en cours. Les Houthis ont affirm\u00e9 que leur objectif \u00e9tait de nuire \u00e0 Isra\u00ebl et de faire preuve de solidarit\u00e9 avec la population de Gaza \u2014 une cause qui a retrouv\u00e9 une certaine popularit\u00e9 au Moyen-Orient. Mais la plupart de leurs attaques ont \u00e9t\u00e9 dirig\u00e9es contre les navires qui se trouvaient en vue et \u00e0 port\u00e9e, qu&rsquo;ils aient ou non des liens avec Isra\u00ebl. Si cette situation se prolonge, elle portera atteinte \u00e0 l&rsquo;\u00e9conomie mondiale. Certains pourraient penser que la communaut\u00e9 internationale a raison de ne pas faire plus pour arr\u00eater les Isra\u00e9liens, mais jusqu&rsquo;\u00e0 pr\u00e9sent, les grands perdants sont les pays qui tirent leurs revenus de la route maritime, notamment l&rsquo;\u00c9gypte, dont les recettes provenant du canal de Suez ont chut\u00e9 d&rsquo;au moins 40&#160;%&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-11-215995' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/markets\/commodities\/egypts-suez-canal-revenues-down-40-due-houthi-attacks-2024-01-11\/#:~:text=CAIRO%2C%20Jan%2012%20(Reuters),divert%20away%20from%20the%20route.&quot;&gt;Egypt&amp;rsquo;s Suez Canal revenues down 40&amp;#160;% due to Houthi attacks&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 12 janvier 2024.'><sup>11<\/sup><\/a><\/span><\/span>. Quoi qu&rsquo;il arrive d\u00e9sormais, il faudra du temps avant que les compagnies maritimes et leurs assureurs ne concluent que la route est redevenue s\u00fbre.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/u0mZL\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L&rsquo;attitude de l&rsquo;Iran sera d\u00e9terminante. Selon un journaliste de la <em>BBC<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-215995' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#easy-footnote-bottom-12-215995' title='&lt;a href=&quot;https:\/\/twitter.com\/MarkUrban01\/status\/1745743049320182111?s=20&amp;amp;utm_source=substack&amp;amp;utm_medium=email&quot;&gt;Publication sur X (Twitter) de Mark Urban&lt;\/a&gt;, 12 janvier 2024.'><sup>12<\/sup><\/a><\/span><\/span>, le navire iranien qui avait aid\u00e9 les Houthis \u00e0 cibler la navigation a quitt\u00e9 la zone deux jours avant les frappes du 12 janvier. Cela pourrait sugg\u00e9rer qu&rsquo;ils ne voulaient pas \u00eatre pris dans les frappes am\u00e9ricaines. S&rsquo;il reste \u00e0 l&rsquo;\u00e9cart, cela limitera \u00e9galement les renseignements des Houthis sur les cibles potentielles de repr\u00e9sailles. Il n&rsquo;y a aucune raison de supposer que l&rsquo;Iran soit plus enclin \u00e0 chercher la confrontation avec les \u00c9tats-Unis qu&rsquo;il ne l&rsquo;\u00e9tait il y a trois mois. On pourrait m\u00eame plut\u00f4t consid\u00e9rer qu&rsquo;il pr\u00e9f\u00e8re attendre que son programme d&rsquo;armement nucl\u00e9aire produise des r\u00e9sultats avant de se lancer dans une v\u00e9ritable \u00e9preuve de force. T\u00e9h\u00e9ran a probablement aussi retenu la le\u00e7on sur la mani\u00e8re dont le commerce maritime pourrait \u00eatre \u00e9trangl\u00e9 lors d&rsquo;une future confrontation \u2014 le d\u00e9troit de Bab el-Mandeb s&rsquo;ajoutant d\u00e9sormais au d\u00e9troit d&rsquo;Ormuz. Pour l&rsquo;instant, il se r\u00e9jouit de voir l&rsquo;agitation monter dans la r\u00e9gion.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_sipausa31627171_000003-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_sipausa31627171_000003-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_sipausa31627171_000003-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_sipausa31627171_000003-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_sipausa31627171_000003-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Le destroyer \u00e0 missiles guid\u00e9s de classe Arleigh Burke USS Carney (DDG 64) d\u00e9fait une combinaison de missiles Houthi et de drones en mer Rouge, le 19 octobre. Le Carney est d\u00e9ploy\u00e9 dans la zone d&rsquo;op\u00e9rations de la 5e flotte am\u00e9ricaine afin d&rsquo;assurer la s\u00e9curit\u00e9 maritime et la stabilit\u00e9 dans la r\u00e9gion du Moyen-Orient. Bien que la cible principale des missiles et des drones n&rsquo;ait pas encore \u00e9t\u00e9 \u00e9tablie, des responsables am\u00e9ricains ont d\u00e9clar\u00e9 qu&rsquo;ils se dirigeaient potentiellement vers Isra\u00ebl. \u00a9 U.S. Navy<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Mais l\u2019attitude de T\u00e9h\u00e9ran influencera la r\u00e9ponse des Houthis. Il est probable que ces derniers chercheront \u00e0 agir. Tout d\u00e9pendra de s&rsquo;ils souhaitent montrer qu&rsquo;ils ne sont pas intimid\u00e9s ou s&rsquo;ils sont d\u00e9termin\u00e9s \u00e0 poursuivre leur campagne anti-navires, voire \u00e0 riposter d&rsquo;une autre mani\u00e8re. Ces \u00e9changes ne doivent pas n\u00e9cessairement conduire \u00e0 une escalade massive. Souvenons-nous&#160;: lorsque le g\u00e9n\u00e9ral Qasem Soleimani, commandant de la force Qods, a \u00e9t\u00e9 assassin\u00e9 sur ordre de Donald Trump en r\u00e9ponse aux attaques des milices soutenues par l&rsquo;Iran contre les forces am\u00e9ricaines en Irak, des repr\u00e9sailles avaient \u00e9t\u00e9 promises. Le 8 janvier 2020, les forces iraniennes avaient lanc\u00e9 des missiles balistiques sur une base a\u00e9rienne en Irak o\u00f9 se trouvait du personnel am\u00e9ricain. Dans un premier temps, aucune victime am\u00e9ricaine n&rsquo;avait \u00e9t\u00e9 signal\u00e9e, mais il s&rsquo;\u00e9tait av\u00e9r\u00e9 par la suite que certains avaient \u00e9t\u00e9 bless\u00e9s. Du point de vue iranien, l&rsquo;honneur \u00e9tait sauf. Et les \u00c9tats-Unis n&rsquo;avaient pas besoin d&rsquo;aller plus loin. Dans la s\u00e9quence actuelle, le pr\u00e9sident Biden a li\u00e9 toute nouvelle action am\u00e9ricaine au fait que les Houthis continuent ou non d&rsquo;attaquer les navires \u2014 \u00ab&#160;nous veillerons \u00e0 r\u00e9pondre aux Houthis s&rsquo;ils poursuivent ce comportement scandaleux&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il n&rsquo;y a aucune raison de supposer que l&rsquo;Iran soit plus enclin \u00e0 chercher la confrontation avec les \u00c9tats-Unis qu&rsquo;il ne l&rsquo;\u00e9tait il y a trois mois<\/p><cite>Lawrence Freedman<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Mais il serait embarrassant pour les \u00c9tats-Unis que les attaques contre les navires reprennent et s\u2019intensifient. Les frappes du 12 janvier ont \u00e9t\u00e9 co\u00fbteuses \u2014 les missiles de d\u00e9fense a\u00e9rienne de la marine \u00e9tant beaucoup plus chers que les drones des Houthis. N\u00e9anmoins, les syst\u00e8mes de ces derniers, y compris la collecte de renseignements, ont \u00e9t\u00e9 d\u00e9grad\u00e9s et ils pourraient avoir du mal \u00e0 se r\u00e9organiser en vue d\u2019une frappe efficace. Une tentative a eu lieu le jour de l\u2019op\u00e9ration, mais la cible s&rsquo;est av\u00e9r\u00e9e \u00eatre un navire transportant du p\u00e9trole russe. Le missile a manqu\u00e9 sa cible. Trois petites embarcations \u00e9taient pr\u00e9sentes pour assurer le suivi, mais elles ont quitt\u00e9 les lieux. Il ne sera pas utile aux Houthis de poursuivre la campagne si elle continue \u00e0 \u00e9chouer. Cela est plus probable \u00e0 court terme, alors que les forces am\u00e9ricaines et britanniques seront en \u00e9tat d&rsquo;alerte et que de nombreuses cibles potentielles se font rares en \u00e9vitant la mer Rouge. Il convient \u00e9galement de noter que tr\u00e8s peu de navires r\u00e9ellement li\u00e9s \u00e0 Isra\u00ebl sont sur place pour \u00eatre attaqu\u00e9s.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/95rkZ\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Mais tant que les Houthis sont capables de reprendre leur campagne, un probl\u00e8me plus large pourrait \u00eatre de persuader la navigation commerciale d\u2019emprunter \u00e0 nouveau la route de la mer Rouge. Le moyen le plus \u00e9vident de r\u00e9duire les risques serait d&rsquo;obtenir un cessez-le-feu \u00e0 Gaza. Mais si les gouvernements occidentaux cherchent des moyens de mettre un terme \u00e0 la guerre \u2014 m\u00eame s&rsquo;il semble impossible de l&rsquo;arr\u00eater compl\u00e8tement \u2014, c&rsquo;est surtout parce qu&rsquo;ils sont exasp\u00e9r\u00e9s par les politiques du gouvernement isra\u00e9lien et alarm\u00e9s par le risque croissant de maladie et de famine \u00e0 Gaza, et non en raison de probl\u00e8mes de transport maritime.<\/p>\n\n\n\n<p>La r\u00e9gion est tr\u00e8s instable et il existe d&rsquo;autres points chauds. Nous vivons une p\u00e9riode inqui\u00e9tante. Mais les frappes du 12 janvier ne sont pas susceptibles, en soi, d&rsquo;entra\u00eener une escalade majeure. Nous ne vivons pas le d\u00e9but d&rsquo;une nouvelle intervention occidentale d&rsquo;envergure dans un pays du Moyen-Orient. Les objectifs des frappes \u00e9taient limit\u00e9s et visaient \u00e0 faire valoir la libert\u00e9 de navigation. Aucune force terrestre n&rsquo;est employ\u00e9e et il n&rsquo;y a \u2014 pour l&rsquo;instant&nbsp;\u2014 pas d&rsquo;intention de chasser les Houthis de leur position au Y\u00e9men.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui sont les Houthis&#160;&#160;? Pourquoi les \u00c9tats-Unis s\u2019engagent-ils d\u00e9sormais en mer Rouge&#160;&#160;? Comment va \u00e9voluer la situation&#160;&#160;? Depuis quelques semaines, la guerre de Soukkot s\u2019est \u00e9tendue. Elle a pris une nouvelle forme par l\u2019attaque de navires et implique d\u00e9sormais les puissances occidentales dans l\u2019op\u00e9ration <em>Prosperity Guardian<\/em>. Point de rupture ou continuit\u00e9 strat\u00e9gique&#160;&#160;? Lawrence Freedman fait le point.<\/p>\n","protected":false},"author":2622,"featured_media":215955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":19,"footnotes":""},"categories":[3611],"tags":[],"staff":[3505],"editorial_format":[4944],"serie":[],"audience":[],"geo":[530],"class_list":["post-215995","post","type-post","status-publish","format-standard","hentry","category-la-guerre-de-soukkot","staff-lawrence-freedman","editorial_format-actu-longues","geo-asie-intermediaire"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":215955,"excerpt":"Qui sont les Houthis ? Pourquoi les \u00c9tats-Unis s\u2019engagent-ils d\u00e9sormais en mer Rouge ? Comment va \u00e9voluer la situation ? Depuis quelques semaines, la guerre de Soukkot s\u2019est \u00e9tendue. Elle a pris une nouvelle forme par l\u2019attaque de navires et implique d\u00e9sormais les puissances occidentales dans l\u2019op\u00e9ration <em>Prosperity Guardian<\/em>. Point de rupture ou continuit\u00e9 strat\u00e9gique ? Lawrence Freedman fait le point.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Houthis, \u00c9tats-Unis : comment la guerre s&#039;est \u00e9tendue \u00e0 la mer Rouge | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Houthis, \u00c9tats-Unis : comment la guerre s&#039;est \u00e9tendue \u00e0 la mer Rouge | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Qui sont les Houthis&#160;? Pourquoi les \u00c9tats-Unis s\u2019engagent-ils d\u00e9sormais en mer Rouge&#160;? Comment va \u00e9voluer la situation&#160;? Depuis quelques semaines, la guerre de Soukkot s\u2019est \u00e9tendue. Elle a pris une nouvelle forme par l\u2019attaque de navires et implique d\u00e9sormais les puissances occidentales dans l\u2019op\u00e9ration Prosperity Guardian. Point de rupture ou continuit\u00e9 strat\u00e9gique&#160;? Lawrence Freedman fait le point.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T16:32:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-26T09:19:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/gc-houthis-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/gc-houthis-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/\",\"name\":\"Houthis, \u00c9tats-Unis : comment la guerre s'est \u00e9tendue \u00e0 la mer Rouge | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg\",\"datePublished\":\"2024-01-23T16:32:55+00:00\",\"dateModified\":\"2024-01-26T09:19:09+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg\",\"width\":2560,\"height\":1663,\"caption\":\"Des partisans des Houthis participent \u00e0 une manifestation contre les frappes a\u00e9riennes men\u00e9es par les \u00c9tats-Unis, le vendredi 12 janvier 2024, \u00e0 Sanaa, au Y\u00e9men. Les arm\u00e9es am\u00e9ricaine et britannique ont bombard\u00e9 plus d'une douzaine de sites utilis\u00e9s par les Houthis, soutenus par l'Iran. Les cibles militaires comprenaient des sites de d\u00e9fense a\u00e9rienne et des radars, ainsi que des sites de stockage et de lancement de drones et de missiles. \u00a9 AP Photo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Houthis, \u00c9tats-Unis&#160;: comment la guerre s&rsquo;est \u00e9tendue \u00e0 la mer Rouge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Houthis, \u00c9tats-Unis : comment la guerre s'est \u00e9tendue \u00e0 la mer Rouge | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/","og_locale":"fr_FR","og_type":"article","og_title":"Houthis, \u00c9tats-Unis : comment la guerre s'est \u00e9tendue \u00e0 la mer Rouge | Le Grand Continent","og_description":"Qui sont les Houthis&#160;? Pourquoi les \u00c9tats-Unis s\u2019engagent-ils d\u00e9sormais en mer Rouge&#160;? Comment va \u00e9voluer la situation&#160;? Depuis quelques semaines, la guerre de Soukkot s\u2019est \u00e9tendue. Elle a pris une nouvelle forme par l\u2019attaque de navires et implique d\u00e9sormais les puissances occidentales dans l\u2019op\u00e9ration Prosperity Guardian. Point de rupture ou continuit\u00e9 strat\u00e9gique&#160;? Lawrence Freedman fait le point.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/","og_site_name":"Le Grand Continent","article_published_time":"2024-01-23T16:32:55+00:00","article_modified_time":"2024-01-26T09:19:09+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/gc-houthis-scaled.jpg","type":"image\/jpeg"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/gc-houthis-scaled.jpg","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/","name":"Houthis, \u00c9tats-Unis : comment la guerre s'est \u00e9tendue \u00e0 la mer Rouge | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg","datePublished":"2024-01-23T16:32:55+00:00","dateModified":"2024-01-26T09:19:09+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg","width":2560,"height":1663,"caption":"Des partisans des Houthis participent \u00e0 une manifestation contre les frappes a\u00e9riennes men\u00e9es par les \u00c9tats-Unis, le vendredi 12 janvier 2024, \u00e0 Sanaa, au Y\u00e9men. Les arm\u00e9es am\u00e9ricaine et britannique ont bombard\u00e9 plus d'une douzaine de sites utilis\u00e9s par les Houthis, soutenus par l'Iran. Les cibles militaires comprenaient des sites de d\u00e9fense a\u00e9rienne et des radars, ainsi que des sites de stockage et de lancement de drones et de missiles. \u00a9 AP Photo"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/23\/houthis-etats-unis-comment-la-guerre-sest-etendue-a-la-mer-rouge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Houthis, \u00c9tats-Unis&#160;: comment la guerre s&rsquo;est \u00e9tendue \u00e0 la mer Rouge"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3611,"name":"Isra\u00ebl, Hamas&#160;: le 7-Octobre deux ans apr\u00e8s","slug":"la-guerre-de-soukkot"}],"lgc_author":{"id":3505,"name":"Lawrence Freedman","slug":"lawrence-freedman","description":"Sir Lawrence Freedman est professeur \u00e9m\u00e9rite de War Studies au King's College de Londres. Il a \u00e9crit sur l'histoire internationale, la th\u00e9orie strat\u00e9gique et les questions relatives aux armes nucl\u00e9aires, et commente les questions de s\u00e9curit\u00e9 contemporaines.","first_name":"Freedman","last_name":"Lawrence","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/GC_Lawrence-Freedman.jpg","width":800,"height":900,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg","width":2560,"height":1663,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SIPA_ap22843684_000004-scaled.jpg","width":2560,"height":1663,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/215995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=215995"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/215995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/215955"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=215995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=215995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=215995"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=215995"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=215995"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=215995"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=215995"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=215995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}