{"id":215268,"date":"2024-01-15T15:38:36","date_gmt":"2024-01-15T14:38:36","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=215268"},"modified":"2024-01-15T15:38:39","modified_gmt":"2024-01-15T14:38:39","slug":"nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/","title":{"rendered":"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te"},"content":{"rendered":"\n<p>L\u2019annonce de Nauru, petit \u00c9tat insulaire d\u2019Oc\u00e9anie, survient dans le sillage de l\u2019\u00e9lection pr\u00e9sidentielle ayant d\u00e9bouch\u00e9 le 13 janvier sur la victoire de Lai Ching-te, candidat du Parti d\u00e9mocrate progressiste \u2014 qui succ\u00e9dera ainsi \u00e0 Tsai Ing-wen, \u00e9galement issue du PDD, apr\u00e8s deux mandats.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/mwgdB\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Le Parti d\u00e9mocrate progressiste, s\u2019il ne revendique plus une ind\u00e9pendance formelle de l\u2019\u00c9tat ta\u00efwanais, d\u00e9fend la conservation de l\u2019ind\u00e9pendance politique et \u00e9conomique de Ta\u00efwan vis-\u00e0-vis de la Chine et la pr\u00e9servation du syst\u00e8me politique ta\u00efwanais.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sur le plan \u00e9conomique, le parti est par ailleurs oppos\u00e9 \u00e0 une int\u00e9gration compl\u00e8te avec le march\u00e9 chinois&#160;: \u00ab&#160;nous nous sommes compl\u00e8tement \u00e9cart\u00e9s de l&rsquo;approche de l&rsquo;administration pr\u00e9c\u00e9dente, qui tentait de s&rsquo;appuyer sur l&rsquo;accord-cadre de coop\u00e9ration \u00e9conomique (ECFA) pour faire de Ta\u00efwan une \u00eele semblable \u00e0 Hong Kong en empruntant une voie acc\u00e9l\u00e9r\u00e9e vers l&rsquo;int\u00e9gration \u00e9conomique avec la Chine&#160;\u00bb, rappelait la pr\u00e9sidente actuelle Tsai Ing-wen le 1er janvier.<\/li>\n\n\n\n<li>Apr\u00e8s que le secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain Antony Blinken a f\u00e9licit\u00e9 Ta\u00efwan pour des \u00e9lections t\u00e9moignant la \u00ab&#160;solidit\u00e9 de [son] syst\u00e8me d\u00e9mocratique et de son processus \u00e9lectoral&#160;\u00bb, la Chine a r\u00e9pondu en d\u00e9non\u00e7ant l\u2019envoi d\u2019un \u00ab&#160;mauvais signal&#160;\u00bb aux \u00ab&#160;forces s\u00e9paratistes&#160;\u00bb et une \u00ab&#160;violation du principe d\u2019une seule Chine&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-215268' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#easy-footnote-bottom-1-215268' title='\u00a0&lt;a href=&quot;http:\/\/dk.china-embassy.gov.cn\/eng\/fyrth\/202401\/t20240114_11223454.htm&quot;&gt;Foreign Ministry Spokesperson\u2019s Remarks on US State Department\u2019s Statement on the Election in China\u2019s Taiwan Region&lt;\/a&gt;, 14 janvier 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/VJQxl\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Deux jours apr\u00e8s les \u00e9lections, l\u2019\u00c9tat insulaire de Nauru a annonc\u00e9 sa d\u00e9cision de reconna\u00eetre la R\u00e9publique populaire de Chine et de rompre ses relations diplomatiques avec Ta\u00efwan, qu\u2019il ne reconna\u00eet plus \u00ab&#160;comme un pays distinct, mais comme une partie inali\u00e9nable du territoire chinois&#160;\u00bb.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La d\u00e9cision de Nauru r\u00e9duit le nombre d\u2019\u00c9tats reconnaissant officiellement Ta\u00efwan \u00e0 12, en comptant le Vatican.<\/li>\n\n\n\n<li>Taipei a d\u00e9nonc\u00e9 une d\u00e9cision destin\u00e9e \u00e0 \u00ab&#160;attaquer la d\u00e9mocratie ta\u00efwanaise&#160;\u00bb suite aux r\u00e9sultats des \u00e9lections qui serait motiv\u00e9e par une offre d\u2019aide financi\u00e8re chinoise \u00e0 Nauru sup\u00e9rieure \u00e0 celle de Ta\u00efwan&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-215268' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#easy-footnote-bottom-2-215268' title='Reuters, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/world\/asia-pacific\/taiwan-loses-first-ally-post-election-nauru-goes-over-china-2024-01-15\/&quot;&gt;Taiwan loses ally Nauru, accuses China of post-election ploy&lt;\/a&gt;&amp;#160;\u00bb, 15 janvier 2024.'><sup>2<\/sup><\/a><\/span><\/span> \u2014 de 100 millions de dollars par an, d\u2019apr\u00e8s les propos d\u2019un responsable ta\u00efwanais rapport\u00e9s par <em>Reuters<\/em>.\u00a0<\/li>\n\n\n\n<li>Le minist\u00e8re des Affaires \u00e9trang\u00e8res chinois a salu\u00e9 une d\u00e9cision qui \u00ab&#160;d\u00e9montre que le principe d\u2019une seule Chine est le lieu o\u00f9 l&rsquo;opinion mondiale s&rsquo;oriente et o\u00f9 l&rsquo;arc de l&rsquo;histoire s&rsquo;infl\u00e9chit&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-215268' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#easy-footnote-bottom-3-215268' title='&lt;a href=&quot;https:\/\/www.mfa.gov.cn\/eng\/xwfw_665399\/s2510_665401\/202401\/t20240115_11223838.html&quot;&gt;Foreign Ministry Spokesperson\u2019s Remarks on the Government of the Republic of Nauru\u2019s Announcement to Break Diplomatic Ties with the Taiwan Region and Seek to Reestablish Diplomatic Ties with China&lt;\/a&gt;, 15 janvier 2024.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/k44zq\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Au-del\u00e0 des \u00e9lections, la r\u00e9duction du groupe de pays reconnaissant Ta\u00efwan s\u2019inscrit dans une tendance de long terme.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Depuis 2000, Ta\u00efwan a perdu ses relations diplomatiques avec 18 \u00c9tats, dont 3 depuis 2020 \u2014 et 62 \u00c9tats au total depuis la reconnaissance de la R\u00e9publique populaire de Chine par les Nations unies en 1971.&nbsp;<\/li>\n\n\n\n<li>Le dernier en date \u00e9tait le Honduras, qui a rompu ses relations avec Ta\u00efwan en mars 2023 en qualifiant Ta\u00efwan, comme Nauru, de \u00ab&#160;partie inali\u00e9nable du territoire chinois&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-215268' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#easy-footnote-bottom-4-215268' title='Bloomberg, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bloomberg.com\/news\/articles\/2023-03-26\/taiwan-honduras-to-cut-diplomatic-ties-on-china-recognition&quot;&gt;Taiwan Loses Ally of Eight Decades as Honduras Recognizes China&lt;\/a&gt;&amp;#160;\u00bb, 26 mars 2023.'><sup>4<\/sup><\/a><\/span><\/span>.\u00a0<\/li>\n\n\n\n<li>\u00c0 ce jour, la moiti\u00e9 des pays entretenant toujours des relations diplomatiques avec Ta\u00efwan sont de petits \u00c9tats insulaires du Pacifique et des Cara\u00efbes.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Deux jours apr\u00e8s l\u2019\u00e9lection pr\u00e9sidentielle ayant d\u00e9bouch\u00e9 sur la victoire du Parti d\u00e9mocrate progressiste, le groupe restreint de pays ayant officiellement \u00e9tabli des relations diplomatiques avec Ta\u00efwan s\u2019est encore r\u00e9duit lorsque Nauru a annonc\u00e9 lundi 15 janvier reconna\u00eetre la R\u00e9publique populaire de Chine.<\/p>\n","protected":false},"author":6617,"featured_media":215278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1731],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[531],"class_list":["post-215268","post","type-post","status-publish","format-standard","hentry","category-politique","editorial_format-actu-breves","geo-chine"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":215278,"excerpt":"Deux jours apr\u00e8s l\u2019\u00e9lection pr\u00e9sidentielle ayant d\u00e9bouch\u00e9 sur la victoire du Parti d\u00e9mocrate progressiste, le groupe restreint de pays ayant officiellement \u00e9tabli des relations diplomatiques avec Ta\u00efwan s\u2019est encore r\u00e9duit lorsque Nauru a annonc\u00e9 lundi 15 janvier reconna\u00eetre la R\u00e9publique populaire de Chine.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Deux jours apr\u00e8s l\u2019\u00e9lection pr\u00e9sidentielle ayant d\u00e9bouch\u00e9 sur la victoire du Parti d\u00e9mocrate progressiste, le groupe restreint de pays ayant officiellement \u00e9tabli des relations diplomatiques avec Ta\u00efwan s\u2019est encore r\u00e9duit lorsque Nauru a annonc\u00e9 lundi 15 janvier reconna\u00eetre la R\u00e9publique populaire de Chine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-15T14:38:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-15T14:38:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2218\" \/>\n\t<meta property=\"og:image:height\" content=\"1194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"elenam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"elenam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/\",\"name\":\"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png\",\"datePublished\":\"2024-01-15T14:38:36+00:00\",\"dateModified\":\"2024-01-15T14:38:39+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png\",\"width\":2218,\"height\":1194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48\",\"name\":\"elenam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g\",\"caption\":\"elenam\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/","og_locale":"fr_FR","og_type":"article","og_title":"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te | Le Grand Continent","og_description":"Deux jours apr\u00e8s l\u2019\u00e9lection pr\u00e9sidentielle ayant d\u00e9bouch\u00e9 sur la victoire du Parti d\u00e9mocrate progressiste, le groupe restreint de pays ayant officiellement \u00e9tabli des relations diplomatiques avec Ta\u00efwan s\u2019est encore r\u00e9duit lorsque Nauru a annonc\u00e9 lundi 15 janvier reconna\u00eetre la R\u00e9publique populaire de Chine.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/","og_site_name":"Le Grand Continent","article_published_time":"2024-01-15T14:38:36+00:00","article_modified_time":"2024-01-15T14:38:39+00:00","og_image":[{"width":2218,"height":1194,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png","type":"image\/png"}],"author":"elenam","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"elenam","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/","url":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/","name":"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png","datePublished":"2024-01-15T14:38:36+00:00","dateModified":"2024-01-15T14:38:39+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png","width":2218,"height":1194},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/15\/nauru-rompt-ses-relations-diplomatiques-avec-taiwan-suite-a-lelection-de-lai-ching-te\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Nauru rompt ses relations diplomatiques avec Ta\u00efwan suite \u00e0 l\u2019\u00e9lection de Lai Ching-te"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48","name":"elenam","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g","caption":"elenam"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/Capture-decran-2024-01-15-a-15.29.58.png","width":2218,"height":1194,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/215268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/6617"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=215268"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/215268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/215278"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=215268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=215268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=215268"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=215268"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=215268"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=215268"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=215268"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=215268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}