{"id":212594,"date":"2023-12-18T20:00:00","date_gmt":"2023-12-18T19:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=212594"},"modified":"2023-12-18T19:02:05","modified_gmt":"2023-12-18T18:02:05","slug":"en-ukraine-la-confiance-dans-les-institutions-en-baisse","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/","title":{"rendered":"En Ukraine, la confiance dans les institutions en baisse"},"content":{"rendered":"\n<p>La confiance accord\u00e9e aux institutions occupe une place centrale dans l\u2019Ukraine d\u2019aujourd\u2019hui. En raison de la guerre de haute intensit\u00e9 livr\u00e9e par la Russie depuis f\u00e9vrier 2022, les capacit\u00e9s de l\u2019Ukraine \u00e0 d\u00e9fendre son territoire et \u00e0 \u0153uvrer pour reprendre possession des r\u00e9gions saisies par Moscou d\u00e9pendent, au moins partiellement, de la capacit\u00e9 de l\u2019\u00c9tat \u00e0 continuer de fonctionner.<\/p>\n\n\n\n<p>L\u2019Institut international de sociologie de Kiev (KIIS) a publi\u00e9 lundi 18 d\u00e9cembre une enqu\u00eate d\u2019opinion publique \u00ab&#160;panukrainienne&#160;\u00bb pour laquelle les entretiens t\u00e9l\u00e9phoniques ont \u00e9t\u00e9 conduits entre fin novembre et d\u00e9but d\u00e9cembre 2023&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-212594' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#easy-footnote-bottom-1-212594' title='&lt;a href=&quot;https:\/\/www.kiis.com.ua\/?lang=eng&amp;amp;cat=reports&amp;amp;id=1335&amp;amp;page=1&quot;&gt;Dynamics Of Trust In Social Institutions In 2021-2023&lt;\/a&gt;, Institut international de sociologie de Kiev (KIIS), 18 d\u00e9cembre 2023.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seules les personnes vivant dans les r\u00e9gions contr\u00f4l\u00e9es par Kiev jusqu\u2019au 24 f\u00e9vrier 2022 \u2014 \u00e0 l\u2019exception donc de la Crim\u00e9e, de S\u00e9bastopol ainsi que de certains districts des oblasts de Louhansk et Donetsk \u2014 ont \u00e9t\u00e9 sollicit\u00e9es pour ce sondage.<\/li>\n\n\n\n<li>Les r\u00e9sultats r\u00e9v\u00e8lent une importante perte de confiance dans le gouvernement ukrainien (passant de 52&#160;% en d\u00e9cembre 2022 \u00e0 26&#160;%), dans le parlement (35&#160;% \u00e0 15&#160;%), la police (58&#160;% \u00e0 41&#160;%) ainsi que dans les tribunaux et procureurs (25&#160;% \u00e0 12&#160;%).<\/li>\n\n\n\n<li>Le pr\u00e9sident Volodymyr Zelensky conserve un niveau \u00e9lev\u00e9 de confiance, bien que celui-ci ait significativement baiss\u00e9 depuis d\u00e9cembre 2022 (62&#160;% contre 84&#160;%). Le niveau de confiance quasi-absolu dans les forces arm\u00e9es reste quant \u00e0 lui inchang\u00e9 par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente (96&#160;%).<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium \">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/flo.uri.sh\/visualisation\/16190882\/embed\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Les mouvements b\u00e9n\u00e9voles continuent eux aussi \u00e0 \u00eatre per\u00e7us tr\u00e8s positivement par la soci\u00e9t\u00e9 ukrainienne (84&#160;% de confiance, inchang\u00e9 depuis d\u00e9cembre 2022). Comme l\u2019explique Anna Colin Lebedev dans <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/ukraine-lapres-guerre-commence-maintenant\/\">une \u00e9tude sur l\u2019apr\u00e8s-guerre en Ukraine<\/a>, \u00ab&#160;les mouvements b\u00e9n\u00e9voles ont tiss\u00e9 un filet de s\u00e9curit\u00e9 alternatif dans un \u00c9tat o\u00f9 la protection sociale reste d\u00e9faillante&#160;\u00bb. L\u2019arm\u00e9e est quant \u00e0 elle \u00ab&#160;devenue une institution de jonction entre l\u2019\u00c9tat et la soci\u00e9t\u00e9&#160;\u00bb.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La publication de ces donn\u00e9es intervient \u00e0 un moment critique pour l\u2019Ukraine. Tandis que le vote d\u2019une nouvelle aide am\u00e9ricaine par le Congr\u00e8s est <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/11\/a-washington-comme-a-bruxelles-orban-oeuvre-contre-le-soutien-a-lukraine\/\">pour l\u2019heure plus qu\u2019incertain<\/a>, la Hongrie s\u2019est oppos\u00e9e \u00e0 octroyer une aide europ\u00e9enne de 50 milliards d\u2019euros \u00e0 Kiev lors du Conseil des 14-15 d\u00e9cembre.<\/li>\n\n\n\n<li>Depuis plus d\u2019un an, tous les salaires des fonctionnaires ukrainiens sont financ\u00e9s par le programme <em>Public Expenditures for Administrative Capacity Endurance<\/em> (PEACE) de la Banque mondiale. Sur les 23,4 milliards envoy\u00e9s \u00e0 l\u2019Ukraine via celui-ci, 20,2 provenaient des \u00c9tats-Unis&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-212594' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#easy-footnote-bottom-2-212594' title='William Mauldin et Marcus Walker, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.wsj.com\/world\/europe\/u-s-funding-cutoff-threatens-ukraines-economic-stability-82716679&quot;&gt;U.S. Funding Cutoff Threatens Ukraine\u2019s Economic Stability&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Wall Street Journal&lt;\/em&gt;, 3 octobre 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Si d\u2019autres pays contribuent \u00e0 ce programme, la fin du soutien am\u00e9ricain compromettrait les capacit\u00e9s de l\u2019\u00c9tat ukrainien \u00e0 fonctionner comme il l\u2019a fait jusqu\u2019\u00e0 pr\u00e9sent, malgr\u00e9 la guerre.<\/li>\n\n\n\n<li>Au d\u00e9but du mois de d\u00e9cembre, en amont d\u2019une visite de Volodymyr Zelensky \u00e0 Washington, la d\u00e9put\u00e9 ukrainienne Oleksandra Ustinova d\u00e9clarait&#160;: \u00ab&#160;Si nous ne survivons pas en tant qu&rsquo;\u00c9tat, nous ne pourrons pas gagner une guerre&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-212594' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#easy-footnote-bottom-3-212594' title='Isabelle Khurshudyan, Siobh\u00e1n O&amp;rsquo;Grady et David L. Stern, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.washingtonpost.com\/politics\/2023\/12\/09\/zelensky-us-ukraine-zaluzhny\/&quot;&gt;Ukraine\u2019s Zelensky appears increasingly embattled as U.S. backing wavers&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Washington Post&lt;\/em&gt;, 9 d\u00e9cembre 2023.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>L\u2019Union europ\u00e9enne a directement contribu\u00e9 au financement de 46&#160;% du budget de l\u2019\u00c9tat ukrainien depuis le d\u00e9but de l\u2019ann\u00e9e. Pour les \u00c9tats-Unis, ce chiffre est de 28&#160;%.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/tVV6d\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Un \u00e9ventuel retard voire arr\u00eat des financements octroy\u00e9s \u00e0 l\u2019\u00c9tat ukrainien serait susceptible de contribuer \u00e0 la baisse de confiance dans les institutions d\u00e9j\u00e0 observ\u00e9e plus haut. Tandis qu\u2019il est peu probable que la ligne de front \u00e9volue au cours des prochains mois, la poursuite de l\u2019\u00e9rosion de la confiance accord\u00e9e aux autorit\u00e9s nuirait aux capacit\u00e9s de Kiev \u00e0 continuer le combat en 2024 \u2014 alors que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/14\/les-objectifs-du-kremlin-en-ukraine-pour-2024\/\">l\u2019effort de guerre russe devrait quant \u00e0 lui s\u2019intensifier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le dernier sondage de l\u2019Institut international de sociologie de Kiev (KIIS) r\u00e9v\u00e8le une baisse significative de la confiance accord\u00e9e par les Ukrainiens \u00e0 leurs institutions par rapport \u00e0 d\u00e9cembre 2022&#160;&#160;: parlement, gouvernement, justice, police\u2026 La pr\u00e9sidence, les forces arm\u00e9es et les mouvements b\u00e9n\u00e9voles conservent quant \u00e0 eux un niveau de confiance \u00e9lev\u00e9.<\/p>\n","protected":false},"author":2622,"featured_media":212598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-212594","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":212598,"excerpt":"Le dernier sondage de l\u2019Institut international de sociologie de Kiev (KIIS) r\u00e9v\u00e8le une baisse significative de la confiance accord\u00e9e par les Ukrainiens \u00e0 leurs institutions par rapport \u00e0 d\u00e9cembre 2022 : parlement, gouvernement, justice, police\u2026 La pr\u00e9sidence, les forces arm\u00e9es et les mouvements b\u00e9n\u00e9voles conservent quant \u00e0 eux un niveau de confiance \u00e9lev\u00e9.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Ukraine, la confiance dans les institutions en baisse | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Ukraine, la confiance dans les institutions en baisse | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le dernier sondage de l\u2019Institut international de sociologie de Kiev (KIIS) r\u00e9v\u00e8le une baisse significative de la confiance accord\u00e9e par les Ukrainiens \u00e0 leurs institutions par rapport \u00e0 d\u00e9cembre 2022&#160;: parlement, gouvernement, justice, police\u2026 La pr\u00e9sidence, les forces arm\u00e9es et les mouvements b\u00e9n\u00e9voles conservent quant \u00e0 eux un niveau de confiance \u00e9lev\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-18T19:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"814\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/\",\"name\":\"En Ukraine, la confiance dans les institutions en baisse | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png\",\"datePublished\":\"2023-12-18T19:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png\",\"width\":1453,\"height\":814},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Ukraine, la confiance dans les institutions en baisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Ukraine, la confiance dans les institutions en baisse | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/","og_locale":"fr_FR","og_type":"article","og_title":"En Ukraine, la confiance dans les institutions en baisse | Le Grand Continent","og_description":"Le dernier sondage de l\u2019Institut international de sociologie de Kiev (KIIS) r\u00e9v\u00e8le une baisse significative de la confiance accord\u00e9e par les Ukrainiens \u00e0 leurs institutions par rapport \u00e0 d\u00e9cembre 2022&#160;: parlement, gouvernement, justice, police\u2026 La pr\u00e9sidence, les forces arm\u00e9es et les mouvements b\u00e9n\u00e9voles conservent quant \u00e0 eux un niveau de confiance \u00e9lev\u00e9.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/","og_site_name":"Le Grand Continent","article_published_time":"2023-12-18T19:00:00+00:00","og_image":[{"width":1453,"height":814,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/","name":"En Ukraine, la confiance dans les institutions en baisse | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png","datePublished":"2023-12-18T19:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png","width":1453,"height":814},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/18\/en-ukraine-la-confiance-dans-les-institutions-en-baisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"En Ukraine, la confiance dans les institutions en baisse"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-confiance-institutions-ukraine-KISS-e1702921457595.png","width":1453,"height":814,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/212594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=212594"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/212594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/212598"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=212594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=212594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=212594"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=212594"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=212594"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=212594"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=212594"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=212594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}