{"id":211102,"date":"2023-12-04T12:53:57","date_gmt":"2023-12-04T11:53:57","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=211102"},"modified":"2023-12-04T12:53:59","modified_gmt":"2023-12-04T11:53:59","slug":"en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/","title":{"rendered":"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus"},"content":{"rendered":"\n<p>Les chiffres communiqu\u00e9s ces derni\u00e8res semaines par le minist\u00e8re de la D\u00e9fense ukrainien font \u00e9tat d\u2019<a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/larmee-russe-na-jamais-subi-autant-de-pertes-humaines-depuis-le-debut-de-lannee\/\">un niveau de pertes russes jamais atteint depuis au moins janvier<\/a>. Selon Kiev, 332 040 combattants russes auraient \u00e9t\u00e9 tu\u00e9s ou bless\u00e9s en Ukraine entre le lancement de l\u2019invasion et le 3 d\u00e9cembre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-211102' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#easy-footnote-bottom-1-211102' title='&lt;a href=&quot;https:\/\/www.mil.gov.ua\/news\/2023\/12\/03\/zagalni-vtrati-rosijskih-okupantiv-stanovlyat-bilshe-332-tis-osib-znishheno-ponad-600-zasobiv-ppo-voroga-%E2%80%92-generalnij-shtab-zsu\/&quot;&gt;\u0417\u0430\u0433\u0430\u043b\u044c\u043d\u0456 \u0432\u0442\u0440\u0430\u0442\u0438 \u0440\u043e\u0441\u0456\u0439\u0441\u044c\u043a\u0438\u0445 \u043e\u043a\u0443\u043f\u0430\u043d\u0442\u0456\u0432 \u0441\u0442\u0430\u043d\u043e\u0432\u043b\u044f\u0442\u044c \u0431\u0456\u043b\u044c\u0448\u0435 332 \u0442\u0438\u0441. \u043e\u0441\u0456\u0431, \u0437\u043d\u0438\u0449\u0435\u043d\u043e \u043f\u043e\u043d\u0430\u0434 600 \u0437\u0430\u0441\u043e\u0431\u0456\u0432 \u041f\u041f\u041e \u0432\u043e\u0440\u043e\u0433\u0430 \u2012 \u0413\u0435\u043d\u0435\u0440\u0430\u043b\u044c\u043d\u0438\u0439 \u0448\u0442\u0430\u0431 \u0417\u0421\u0423&lt;\/a&gt;, Minist\u00e8re ukrainien de la D\u00e9fense, 3 d\u00e9cembre 2023.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/UecOD\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dans sa mise \u00e0 jour sur la situation en Ukraine du 4 d\u00e9cembre, les services de renseignement militaires britanniques ont \u00e9valu\u00e9 les pertes russes (bless\u00e9s et tu\u00e9s) en moyenne \u00e0 320 000, soit un chiffre quasiment similaire \u00e0 celui fourni par Kiev&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-211102' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#easy-footnote-bottom-2-211102' title='&lt;a href=&quot;https:\/\/twitter.com\/DefenceHQ\/status\/1731611263799537767&quot;&gt;Publication sur X (Twitter) du minist\u00e8re de la D\u00e9fense britannique&lt;\/a&gt;, 4 d\u00e9cembre 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Au total, 70 000 combattants russes auraient \u00e9t\u00e9 tu\u00e9s en Ukraine, dont 50 000 appartenant \u00e0 l\u2019arm\u00e9e r\u00e9guli\u00e8re (sans diff\u00e9rencier leur statut) et 20 000 \u00e0 Wagner.<\/li>\n\n\n\n<li>Malgr\u00e9 cette nouvelle confirmation que l\u2019arm\u00e9e russe conna\u00eet des pertes tr\u00e8s importantes, Moscou n\u2019a \u00e9tendu son contr\u00f4le du territoire ukrainien que de 4 km\u00b2 au cours du mois de novembre, soit la progression mensuelle la plus faible depuis le d\u00e9but du conflit&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-211102' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#easy-footnote-bottom-3-211102' title='&lt;a href=&quot;https:\/\/twitter.com\/War_Mapper\/status\/1731460344017563879&quot;&gt;Publication sur X (Twitter) de War Mapper&lt;\/a&gt;, 4 d\u00e9cembre 2023.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium \">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/flo.uri.sh\/visualisation\/14701390\/embed\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Cette donn\u00e9e n\u2019indique pas que le conflit est gel\u00e9, mais que les progr\u00e8s pour les deux camps deviennent de plus en plus compliqu\u00e9s en raison de la d\u00e9gradation r\u00e9cente des conditions m\u00e9t\u00e9orologiques ainsi que de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/22\/la-fausse-impasse-de-la-guerre-dukraine\/\">certains facteurs identifi\u00e9s par le commandant en chef des forces arm\u00e9es d&rsquo;Ukraine Valeri Zaloujny<\/a>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/rGCQ5\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La tactique \u00ab&#160;d\u2019infanterie jetable&#160;\u00bb utilis\u00e9e par Moscou ne semble cependant pas conduire \u00e0 une attrition de ses forces disponibles, en raison des efforts continus d\u00e9ploy\u00e9s par l\u2019\u00c9tat russe. En prenant en compte les recrutements, la mobilisation partielle, les membres du personnel achevant leur service militaire et les pertes en Ukraine, l\u2019Institute for the Study of War consid\u00e8re que le d\u00e9cret sign\u00e9 le 1er d\u00e9cembre par Poutine sur l\u2019augmentation de la taille de l\u2019arm\u00e9e serait en r\u00e9alit\u00e9 \u00ab&#160;une reconnaissance formelle d&rsquo;une augmentation nette de 170 000 membres du personnel de combat entre le 25 ao\u00fbt 2022 et le 1er d\u00e9cembre 2023, et non un appel \u00e0 augmenter imm\u00e9diatement le nombre actuel de membres du personnel de combat de 170 000 personnes suppl\u00e9mentaires&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-211102' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#easy-footnote-bottom-4-211102' title='Nicole Wolkov, Christina Harward, Riley Bailey, Grace Mappes et Frederick W. Kagan, &lt;a href=&quot;https:\/\/www.understandingwar.org\/backgrounder\/russian-offensive-campaign-assessment-december-3-2023&quot;&gt;Russian Offensive Campaign Assessment, December 3, 2023&lt;\/a&gt;, Institute for the Study of War.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium \">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/flo.uri.sh\/visualisation\/15999859\/embed\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Tandis que la Maison-Blanche a averti le Congr\u00e8s lundi 4 d\u00e9cembre que Washington manquera de ressources \u00ab&#160;d\u2019ici la fin de l\u2019ann\u00e9e pour acheter davantage d&rsquo;armes et d&rsquo;\u00e9quipements pour l&rsquo;Ukraine et pour fournir des \u00e9quipements provenant des stocks de l&rsquo;arm\u00e9e am\u00e9ricaine&#160;\u00bb, le dernier rapport du SIPRI sur les ventes d\u2019armes r\u00e9v\u00e8le que la production ne suit pas l\u2019augmentation de la demande&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-211102' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#easy-footnote-bottom-5-211102' title='&lt;a href=&quot;https:\/\/www.whitehouse.gov\/omb\/briefing-room\/2023\/12\/04\/letter-to-congressional-leadership-regarding-the-need-for-urgent-action-to-support-ukraines-defense\/?utm_source=twitter&quot;&gt;Letter to Congressional Leadership Regarding the Need for Urgent Action to Support Ukraine\u2019s Defense&lt;\/a&gt;, Maison-Blanche, 4 d\u00e9cembre 2023.'><sup>5<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les revenus des 42 entreprises am\u00e9ricaines parmi les 100 principaux producteurs d&rsquo;armements ont chut\u00e9 de 7,9&#160;% l\u2019an dernier.<\/li>\n\n\n\n<li>\u00c0 l\u2019\u00e9chelle globale, les industriels du secteur de l\u2019armement ont enregistr\u00e9 une baisse de leurs recettes de 3,5&#160;% par rapport \u00e0 2021&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-211102' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#easy-footnote-bottom-6-211102' title='Xiao Liang, Lorenzo Scarazzato, Lucie B\u00e9raud-sudreau, Nan Tian, Diego Lopes Da Silva, Yeoun Choi et Eero Kristjan Sild, &lt;a href=&quot;https:\/\/www.sipri.org\/sites\/default\/files\/2023-11\/fs_2312_top_100_2022.pdf&quot;&gt;The Sipri Top 100 Arms producing And Military Services Companies, 2022&lt;\/a&gt;, Institut international de recherche sur la paix de Stockholm, 4 d\u00e9cembre 2023.'><sup>6<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019arm\u00e9e russe n\u2019a \u00e9tendu son contr\u00f4le du territoire ukrainien que de 4 km\u00b2 au cours du mois de novembre, soit la plus faible progression mensuelle depuis f\u00e9vrier 2022 \u2013 et ce malgr\u00e9 un niveau de pertes in\u00e9dit depuis le d\u00e9but de l\u2019ann\u00e9e.<\/p>\n","protected":false},"author":2622,"featured_media":211108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-211102","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":211108,"excerpt":"L\u2019arm\u00e9e russe n\u2019a \u00e9tendu son contr\u00f4le du territoire ukrainien que de 4 km\u00b2 au cours du mois de novembre, soit la plus faible progression mensuelle depuis f\u00e9vrier 2022 \u2013 et ce malgr\u00e9 un niveau de pertes in\u00e9dit depuis le d\u00e9but de l\u2019ann\u00e9e.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"L\u2019arm\u00e9e russe n\u2019a \u00e9tendu son contr\u00f4le du territoire ukrainien que de 4 km\u00b2 au cours du mois de novembre, soit la plus faible progression mensuelle depuis f\u00e9vrier 2022 \u2013 et ce malgr\u00e9 un niveau de pertes in\u00e9dit depuis le d\u00e9but de l\u2019ann\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T11:53:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T11:53:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"809\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/\",\"name\":\"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png\",\"datePublished\":\"2023-12-04T11:53:57+00:00\",\"dateModified\":\"2023-12-04T11:53:59+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png\",\"width\":1453,\"height\":809},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/","og_locale":"fr_FR","og_type":"article","og_title":"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus | Le Grand Continent","og_description":"L\u2019arm\u00e9e russe n\u2019a \u00e9tendu son contr\u00f4le du territoire ukrainien que de 4 km\u00b2 au cours du mois de novembre, soit la plus faible progression mensuelle depuis f\u00e9vrier 2022 \u2013 et ce malgr\u00e9 un niveau de pertes in\u00e9dit depuis le d\u00e9but de l\u2019ann\u00e9e.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/","og_site_name":"Le Grand Continent","article_published_time":"2023-12-04T11:53:57+00:00","article_modified_time":"2023-12-04T11:53:59+00:00","og_image":[{"width":1453,"height":809,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/","name":"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png","datePublished":"2023-12-04T11:53:57+00:00","dateModified":"2023-12-04T11:53:59+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png","width":1453,"height":809},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/12\/04\/en-ukraine-malgre-la-violence-des-combats-la-ligne-de-front-ne-bouge-plus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"En Ukraine, malgr\u00e9 la violence des combats, la ligne de front ne bouge plus"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/12\/gc-ligne-front-ukraine-ne-bouge-plus-e1701689950808.png","width":1453,"height":809,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/211102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=211102"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/211102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/211108"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=211102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=211102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=211102"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=211102"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=211102"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=211102"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=211102"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=211102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}