{"id":209677,"date":"2023-11-27T11:54:54","date_gmt":"2023-11-27T10:54:54","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=209677"},"modified":"2023-11-27T11:54:57","modified_gmt":"2023-11-27T10:54:57","slug":"leurope-face-a-ses-empires","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/","title":{"rendered":"L&rsquo;Europe face \u00e0 ses empires&#160;: futur d&rsquo;une id\u00e9e"},"content":{"rendered":"\n<p class=\"has-drop-cap\">La Ligue de D\u00e9los, l&rsquo;Empire romain, Charlemagne, le Saint Empire romain germanique, Napol\u00e9on, le Concert de l&rsquo;Europe, l&rsquo;Union europ\u00e9enne. Depuis que l&rsquo;Europe existe, existent des plans pour l\u2019unifier. Aucun n&rsquo;a enti\u00e8rement r\u00e9ussi. La Ligue D\u00e9lienne \u00e9tait une association de cit\u00e9s-\u00c9tats de la Gr\u00e8ce antiques sous la direction d&rsquo;Ath\u00e8nes, le \u00ab&#160;monde occidental&#160;\u00bb connu \u00e0 cette \u00e9poque. L&#8217;empire romain contr\u00f4lait la M\u00e9diterran\u00e9e, mais pas l&rsquo;Europe du Nord. L&#8217;empire carolingien \u00e9tait centr\u00e9 sur la France, l&rsquo;Allemagne et l&rsquo;Italie. Le Saint Empire romain germanique englobait l&rsquo;Europe centrale, s&rsquo;\u00e9tendant, \u00e0 travers le patrimoine de la famille des Habsbourg, jusque dans la p\u00e9ninsule ib\u00e9rique. Le Concert de l&rsquo;Europe, qui r\u00e9unissait l&rsquo;Autriche, la France, la Prusse, la Russie et le Royaume-Uni \u00e9tait un d\u00e9licat rapport de force pour r\u00e9primer tout soul\u00e8vement r\u00e9volutionnaire apr\u00e8s la d\u00e9faite de Napol\u00e9on. L&rsquo;Union compte actuellement vingt-sept \u00c9tats membres, la Suisse, la Norv\u00e8ge et le Royaume-Uni \u00e9tant les principaux absents. Un nombre de pays de l&rsquo;ex-Yougoslavie souhaitent y adh\u00e9rer. Apr\u00e8s l&rsquo;invasion de l&rsquo;Ukraine par la Russie, l&rsquo;Ukraine, la G\u00e9orgie et la Moldavie ont \u00e9galement postul\u00e9. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/20\/lunion-comme-empire-post-imperial\/\">Depuis l\u2019\u00e9poque de l\u2019Empire romain, l\u2019Union est sans doute la tentative la plus r\u00e9ussie d&rsquo;unification du continent.<\/a> Et elle l\u2019a fait d\u00e9mocratiquement.<\/p>\n\n\n\n<p>Quelle comparaison historique est la plus utile pour penser l&rsquo;Union aujourd&rsquo;hui&#160;? Pour l&rsquo;historien Anthony Pagden, professeur d&rsquo;histoire et de sciences politiques \u00e0 UCLA, la r\u00e9ponse est Rome&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-209677' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#easy-footnote-bottom-1-209677' title='Anthony Pagden, &lt;em&gt;The Pursuit of Europe&amp;#160;: A History&lt;\/em&gt;, Oxford University Press, 2022.'><sup>1<\/sup><\/a><\/span><\/span>. L&rsquo;Empire romain \u00e9tait un patchwork de diff\u00e9rents r\u00e9gimes politiques maintenus ensemble sous la Pax Romana, la paix romaine qui a dur\u00e9 200 ans. La loi romaine \u00e9tait la clef, tout comme les l\u00e9gions romaines, qui emp\u00eachaient les barbares d&rsquo;entrer. Les parall\u00e8les sont convaincants&#160;: l&rsquo;Union a \u00e9t\u00e9, apr\u00e8s tout, construite pour assurer la paix sur le continent apr\u00e8s un si\u00e8cle de guerres mondiales. C&rsquo;est aussi un patchwork de politiques et d&rsquo;accords diff\u00e9rents&#160;: certains dans la zone euro, d&rsquo;autres pas&#160;; certains dans Schengen, l&rsquo;espace commun de voyage, d&rsquo;autres pas&#160;; certains dans l&rsquo;OTAN, d&rsquo;autres pas. Le droit europ\u00e9en, enfin, prime sur le droit national.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Depuis l\u2019\u00e9poque de l\u2019Empire romain, l\u2019Union est sans doute la tentative la plus r\u00e9ussie d&rsquo;unification du continent.<\/p><cite>Hugo Drochon<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le plus grand regret de Pagden est que la citoyennet\u00e9 europ\u00e9enne, promulgu\u00e9e par le trait\u00e9 de Maastricht de 1992, n&rsquo;ait \u00e9t\u00e9 qu&rsquo;un compl\u00e9ment \u00e0 la citoyennet\u00e9 nationale, et non quelque chose en soi. La citoyennet\u00e9 romaine \u00e9tait une cat\u00e9gorie distincte qui impliquait certains privil\u00e8ges et obligations. Dans <em>Gladiator,<\/em> le personnage de Russell Crowe est \u00e0 la fois lusitanien, qui englobait le Portugal moderne et l\u2019Ouest de l&rsquo;Espagne, et citoyen romain. Mais apr\u00e8s le Brexit, les citoyens britanniques ont perdu leurs droits europ\u00e9ens, rompant les liens individuels que les Britanniques auraient pu avoir avec l&rsquo;Union.<\/p>\n\n\n\n<p>Il y a bien s\u00fbr d&rsquo;autres diff\u00e9rences. La M\u00e9diterran\u00e9e n&rsquo;est plus une <em>mare nostrum<\/em>, mais plut\u00f4t une fronti\u00e8re pour emp\u00eacher les migrants d&rsquo;entrer. Rome n&rsquo;\u00e9tait en aucun cas d\u00e9mocratique et l&rsquo;Union n&rsquo;a aucune forme de pouvoir centralis\u00e9 comme celui de l&#8217;empereur. L&rsquo;analogie historique la plus pr\u00e9cise pourrait \u00eatre le Second Triumvirat, apr\u00e8s l&rsquo;assassinat de C\u00e9sar, quand Octave, Marc Antoine et L\u00e9pide ont r\u00e9gn\u00e9 sur la r\u00e9publique romaine. Octave contr\u00f4lait l&rsquo;ouest (France, Espagne), Marc Antoine l&rsquo;est (Gr\u00e8ce, Asie Mineure et surtout l&rsquo;\u00c9gypte, avec son bl\u00e9) et L\u00e9pide le sud (Afrique du Nord). Les parall\u00e8les avec la France, l&rsquo;Allemagne et l&rsquo;Italie d&rsquo;aujourd&rsquo;hui sont frappants, surtout quand on sait que c&rsquo;est le moteur franco-allemand qui fait avancer la construction europ\u00e9enne. \u00c0 la fin, Octave a vaincu Marc Antoine et Cl\u00e9op\u00e2tre \u00e0 la bataille d&rsquo;Actium, se d\u00e9clarant C\u00e9sar Auguste, le premier empereur romain.<\/p>\n\n\n\n<p>Dans la continuit\u00e9 de son best-seller <em>The Enlightenment&#160;: And why it still matters <\/em>(2013), Pagden ouvre son r\u00e9cit du projet europ\u00e9en, <em>The Pursuit of Europe <\/em>(2022), avec l&rsquo;affirmation r\u00e9trospective (discutable) de Napol\u00e9on selon laquelle il avait cherch\u00e9 \u00e0 r\u00e9aliser l&rsquo;unification de l&rsquo;Europe non par la coercition ou les liens familiaux, mais en rapprochant les nations europ\u00e9ennes. Pagden nous montre que pour le nationaliste italien Giuseppe Mazzini, nationalisme et europ\u00e9anisme ne s\u2019opposaient pas, mais allaient de pair&#160;: les r\u00e9volutions nationales contre le r\u00e9gime monarchique \u00e9taient une \u00e9tape essentielle sur la voie d&rsquo;une \u00ab&#160;fraternit\u00e9 de l&rsquo;humanit\u00e9&#160;\u00bb plus large. Retra\u00e7ant avec subtilit\u00e9 et bienveillance les diff\u00e9rents projets politiques, philosophiques et litt\u00e9raires d&rsquo;unification europ\u00e9enne \u2014 le pacte Kellogg-Briand, la \u00ab&#160;Paix perp\u00e9tuelle&#160;\u00bb de Kant, les \u00c9tats-Unis d&rsquo;Europe de Victor Hugo \u2014 l&rsquo;\u00e9tude approfondie de Pagden est un guide s\u00fbr dans un domaine de plus en plus dense, mettant au profit tous les outils de l&rsquo;historien intellectuel.&nbsp;<\/p>\n\n\n\n<p>Et Pagden a un point \u00e0 faire valoir. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/09\/17\/conquerir-la-paix-une-conversation-avec-stella-ghervas\/\">S&rsquo;appuyant sur l&rsquo;opinion de Kant selon laquelle une r\u00e9publique d\u00e9mocratique europ\u00e9enne ne peut voir le jour que lorsque ses membres sont eux-m\u00eames des r\u00e9publiques<\/a> \u2014 raison de se m\u00e9fier du glissement de la Hongrie vers l&rsquo;autoritarisme \u2014 il explique que ce qui a frein\u00e9 l&rsquo;int\u00e9gration europ\u00e9enne est la notion de la souverainet\u00e9 \u00e9tatique. D\u00e9velopp\u00e9e apr\u00e8s la paix de Westphalie (1648) pour mettre fin \u00e0 la guerre de religion entre catholiques et protestants, la souverainet\u00e9 de l&rsquo;\u00c9tat a maintenant perdu son utilit\u00e9, soutient Pagden. Un concept n\u00e9 en Europe et qui l&rsquo;a bien servi a depuis \u00e9t\u00e9 utilis\u00e9 par des \u00c9tats-nations plus grands au cours du XXe si\u00e8cle (\u00c9tats-Unis, Russie, Chine), laissant derri\u00e8re eux les petits \u00c9tats europ\u00e9ens. Si l&rsquo;Europe veut avoir sa place au XXIe si\u00e8cle, elle doit \u00e0 nouveau innover et devenir un \u00c9tat post-national. Elle doit passer \u00e0 la notion de souverainet\u00e9 partag\u00e9e telle qu\u2019elle est incarn\u00e9e dans l&rsquo;Union.<\/p>\n\n\n\n<p>Alors que pour Pagden la comparaison historique pour l&rsquo;Union est Rome, son coll\u00e8gue \u00e0 UCLA, Perry Anderson, professeur d&rsquo;histoire et de sociologie, voit un parall\u00e8le avec le Concert de l&rsquo;Europe&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-209677' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#easy-footnote-bottom-2-209677' title='Perry Anderson, &lt;em&gt;Ever Closer Union&amp;#160;? Europe in the West&lt;\/em&gt;, Verso, 2021.'><sup>2<\/sup><\/a><\/span><\/span>. Anderson imagine Angela Merkel dans le r\u00f4le de Klemens von Metternich, qui a donn\u00e9 son nom au \u00ab&#160;syst\u00e8me Metternich&#160;\u00bb r\u00e9actionnaire, mis en place au Congr\u00e8s de Vienne. La preuve pour Anderson qu&rsquo;un tel arrangement in\u00e9gal existe est le traitement de la Gr\u00e8ce pendant la crise de la dette souveraine, et le r\u00f4le jou\u00e9 par Merkel dans la r\u00e9pression des demandes exprim\u00e9es d\u00e9mocratiquement par le peuple grec. Sur ce point, il a sans doute raison, et l&rsquo;Union continue de souffrir d&rsquo;un \u00ab&#160;d\u00e9ficit d\u00e9mocratique&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si l&rsquo;Europe veut avoir sa place au XXIe si\u00e8cle, elle doit \u00e0 nouveau innover et devenir un \u00c9tat post-national.<\/p><cite>Hugo Drochon<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Souvent d\u00e9crit comme un \u00ab&#160;marxiste britannique&#160;\u00bb, Anderson est surtout connu pour avoir \u00e9t\u00e9 r\u00e9dacteur en chef de la <em>New Left Review<\/em>. \u00ab&#160;Anglo-irlandais&#160;\u00bb pourrait \u00eatre une meilleure d\u00e9signation, et expliquerait son utilisation joycienne du langage&nbsp;&#160;: <em>Chefsachen<\/em>, <em>shenanigans<\/em>, <em>Schicksalsgemeinschaft<\/em>, dignit\u00e9 <em>\u00e0 la hollandaise<\/em>, pour donner une saveur d\u2019<em>Ever Closer Union&nbsp;&#160;? <\/em>(2021). Le livre est un recueil de longs essais critiques, une forme dans laquelle il est pass\u00e9 ma\u00eetre, d&rsquo;abord publi\u00e9s dans la <em>New Left Review <\/em>et la <em>London Review of Books<\/em>. Dans ses essais Anderson d\u00e9veloppe une vaste \u00e9tude du ou des auteurs en question, dialoguant pleinement et respectueusement avec leur pens\u00e9e. Cela a donn\u00e9 lieu \u00e0 un nombre d&rsquo;\u00e9changes passionnants, comme avec le social-lib\u00e9ral italien Norberto Bobbio. Et au-del\u00e0 des divergences id\u00e9ologiques, Anderson a toujours rendu \u00e0 C\u00e9sar ce qui est \u00e0 C\u00e9sar&#160;: adversaire politique de Raymond Aron, Anderson n&rsquo;a jamais h\u00e9sit\u00e9 \u00e0 lui prodiguer des \u00e9loges intellectuels et \u00e0 exiger le m\u00eame niveau de ses \u00e9pigones de moindre calibre.&nbsp;<\/p>\n\n\n\n<p>Reprenant l\u00e0 o\u00f9 s&rsquo;est termin\u00e9e sa pr\u00e9c\u00e9dente \u00e9tude sur l&rsquo;Union europ\u00e9enne, <em>The New Old World <\/em>(2009), <em>Ever Closer Union&#160;? <\/em>est l&rsquo;un des plus s\u00e9rieux d\u00e9fis intellectuels \u00e9mis \u00e0 l\u2019encontre de l\u2019Union. Pour Anderson, la construction de l&rsquo;Union europ\u00e9enne doit \u00eatre comprise comme une s\u00e9rie de coups d&rsquo;\u00c9tat. Non pas des coups d&rsquo;\u00c9tat au sens de putsch militaire, voire de \u00ab&#160;coup de palais&#160;\u00bb, mais au sens originel du terme tel qu&rsquo;il a \u00e9t\u00e9 donn\u00e9 par Gabriel Naud\u00e9. Si on se souvient de Naud\u00e9 aujourd\u2019hui, c\u2019est du grand biblioth\u00e9caire de la Biblioth\u00e8que Mazarine, la plus ancienne biblioth\u00e8que publique de France. Mais il est aussi l&rsquo;auteur des <em>Consid\u00e9rations politiques sur les coups d\u2019\u00c9tat,<\/em> texte obscur dont on n&rsquo;imprima que douze exemplaires. Nous sommes redevables \u00e0 Anderson d&rsquo;avoir ramen\u00e9 Naud\u00e9 \u00e0 notre attention.<\/p>\n\n\n\n<p>Disciple autoproclam\u00e9 de Machiavel, Naud\u00e9 consid\u00e9rait un coup d&rsquo;\u00c9tat comme un coup men\u00e9 par l&rsquo;\u00c9tat lui-m\u00eame pour renforcer son pouvoir. Ce coup peut contenir un \u00e9l\u00e9ment esth\u00e9tique&#160;: le \u00ab&#160;spectaculaire&#160;\u00bb. Coup d&rsquo;\u00e9tat, pour Naud\u00e9, \u00e9tait synonyme de \u00ab&#160;coup d&rsquo;\u00e9clat&#160;\u00bb. Il est fonci\u00e8rement antid\u00e9mocratique. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/08\/le-massacre-par-en-bas-conversation-avec-jeremie-foa\/\">Son exemple est le massacre de la Saint-Barth\u00e9lemy<\/a>.<\/p>\n\n\n\n<p>L&rsquo;Union europ\u00e9enne, selon Anderson, peut \u00eatre vue \u00e0 travers ce prisme, avec chaque trait\u00e9 une nouvelle prise de pouvoir au nom de l&rsquo;Union&#160;: en t\u00e9moigne la Cour de justice europ\u00e9enne d\u00e9clarant en 1964 la supr\u00e9matie du droit europ\u00e9en sur le droit national, qui n&rsquo;avait aucun fondement dans le trait\u00e9 de Rome, ou Val\u00e9ry Giscard d&rsquo;Estaing d\u00e9terminant qu&rsquo;une r\u00e9union informelle des chefs d&rsquo;\u00c9tat en 1974 \u00e9tait d\u00e9sormais le Conseil europ\u00e9en, l&rsquo;une des institutions les plus puissantes de l&rsquo;Union. Jusqu&rsquo;\u00e0 pr\u00e9sent, ces mouvements contenaient tous l&rsquo;ingr\u00e9dient de la furtivit\u00e9, que Naud\u00e9 jugeait n\u00e9cessaire pour un coup d&rsquo;\u00c9tat r\u00e9ussi, pr\u00e9sentant la prise soudaine du pouvoir comme un fait accompli. Mais l&rsquo;\u00e9l\u00e9ment esth\u00e9tique reste insaisissable&#160;: tous ces coups se sont d\u00e9roul\u00e9s \u00e0 huis clos. O\u00f9 est le spectacle que Naud\u00e9 r\u00e9clame&#160;?<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000009-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000009-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000009-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000009-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000009-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Un train ukrainien porte les stigmates des bombardements russes. \u00a9 SOPA Images\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Anderson ouvre sur une critique du livre de Luuk van Middelaar,&nbsp;<em>Le Passage \u00e0 l&rsquo;Europe <\/em>(2012). Van Middelaar fut le conseiller d&rsquo;Herman Van Rompuy, le premier pr\u00e9sident du Conseil europ\u00e9en, et son livre raconte le temps pass\u00e9 avec lui&nbsp;&#160;: comment l&rsquo;Europe, selon van Middelaar, est devenue une union, pour reprendre le sous-titre du livre. Mais le cadre intellectuel est fourni par le th\u00e9oricien politique n\u00e9erlandais Frank Ankersmit, aupr\u00e8s duquel van Middelaar a \u00e9tudi\u00e9 \u00e0 l&rsquo;universit\u00e9 de Groningue. C&rsquo;est Ankersmit qui a r\u00e9habilit\u00e9 Naud\u00e9.<\/p>\n\n\n\n<p>Van Middelaar se demande comment faire adh\u00e9rer le public europ\u00e9en au projet europ\u00e9en, auquel, depuis le rejet danois du trait\u00e9 de Maastricht en 1992, il a fait preuve de r\u00e9sistance. Il d\u00e9finit trois strat\u00e9gies. \u00ab&#160;L&rsquo;Allemand&#160;\u00bb, proposant des \u00e9l\u00e9ments classiques du nationalisme&#160;: le drapeau de l&rsquo;Union, l&rsquo;\u00ab&#160;Hymne \u00e0 la joie&#160;\u00bb, l&rsquo;euro. Le \u00ab&#160;Romain&#160;\u00bb, en particulier celui d&rsquo;Auguste&nbsp;&#160;: offrant des avantages mat\u00e9riels, ou ce que l&rsquo;on appelle dans le jargon de l&rsquo;Union la \u00ab&#160;l\u00e9gitimit\u00e9 produite (<em>output legitimacy<\/em>)&#160;\u00bb (voyage sans entrave, droit de vivre et de travailler dans l&rsquo;Union, appels mobiles bon march\u00e9). Et enfin le \u00ab&#160;grec&#160;\u00bb&nbsp; \u2013 ancien \u2013 centr\u00e9 sur la trag\u00e9die, avec le public europ\u00e9en comme spectateur (le \u00ab&#160;ch\u0153ur&#160;\u00bb de Nietzsche) du drame de la politique europ\u00e9enne. C&rsquo;est la politique comme spectacle, et c&rsquo;est ici que nous retrouvons Naud\u00e9.<\/p>\n\n\n\n<p>Dans <em>The Idea of Europe <\/em>(2021), Shane Weller offre une autre voix critique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-209677' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#easy-footnote-bottom-3-209677' title='Shae Weller, &lt;em&gt;The Idea of Europe&amp;#160;: A Critical History&lt;\/em&gt;, Cambridge University Press, 2021.'><sup>3<\/sup><\/a><\/span><\/span>. Weller met l&rsquo;Europe au d\u00e9fi d&rsquo;\u00e9viter de tomber dans \u00ab&#160;l&rsquo;eurocentrisme, l&rsquo;euro-supr\u00e9macisme, l&rsquo;euro-universalisme&#160;\u00bb, un mantra qu&rsquo;il r\u00e9p\u00e8te tout au long de son livre. Il a certainement raison de dire que l&rsquo;Europe, \u00e0 travers les actions de certains de ses \u00c9tats membres, a poursuivi une forme de politique coloniale, en particulier en Afrique, mais <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/01\/europeens-vous-valez-davantage-que-vos-mythes\/\">l&rsquo;Union, que les pays demandent librement \u00e0 rejoindre, peut \u00e9galement \u00eatre qualifi\u00e9e de projet anti-imp\u00e9rial<\/a>. La preuve en est le Brexit&#160;: aucun empire n&rsquo;inclurait la libre s\u00e9cession de l&rsquo;une de ses parties dans ses fondements juridiques.<\/p>\n\n\n\n<p>Un professeur de litt\u00e9rature compar\u00e9e \u00e0 l&rsquo;Universit\u00e9 du Kent \u2014 sp\u00e9cialiste de Beckett \u2014 Weller se r\u00e9f\u00e8re \u00e0 des philosophes et \u00e9crivains \u00ab&#160;continentaux&#160;\u00bb tels Jacques Derrida et Tzvetan Todorov. Il conclut son livre par un appel (louable) \u00e0 \u00e9couter des voix non europ\u00e9ennes, bien qu&rsquo;aucune de ces voix, \u00e0 l&rsquo;exception de l&rsquo;Am\u00e9ricaine Susan Sontag, n&rsquo;apparaisse directement dans son livre. Il veut aussi conserver la distinction entre l&rsquo;Europe et l&rsquo;Union, distinction qui politiquement est souvent l&rsquo;apanage de l&rsquo;euroscepticisme, qui pr\u00e9tend vouloir construire une alternative europ\u00e9enne \u00e0 l&rsquo;Union. Weller a raison de ne pas voir le monde en termes binaires&#160;: nous pouvons distinguer le peuple russe du r\u00e9gime de Poutine. Et les lignes de communication doivent rester ouvertes. Mais \u00e0 la fin, c\u2019est toujours Poutine qui envahit l&rsquo;Ukraine.&nbsp;<\/p>\n\n\n\n<p>Que faire des millions de r\u00e9fugi\u00e9s ukrainiens qui affluent en Pologne et dans les autres \u00c9tats voisins&#160;? Ici, le journaliste n\u00e9erlandais Geert Mak pourrait avoir quelques id\u00e9es. <em>The Dream of Europe&#160;: Travels in the Twenty-First Century <\/em>(2021) retrace les \u00e9v\u00e9nements des vingt-deux derni\u00e8res ann\u00e9es (1999-2021) \u00e0 travers ses voyages personnels et ses rencontres \u00e0 travers l&rsquo;Europe&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-209677' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#easy-footnote-bottom-4-209677' title='Geert Mak, &lt;em&gt;The Dream of Europe&amp;#160;: Travels in the Twenty-First Century&lt;\/em&gt;, Harvill Secker, 2021.'><sup>4<\/sup><\/a><\/span><\/span>. Pr\u00e9monitoire pour un livre publi\u00e9 en n\u00e9erlandais en 2019, Mak ouvre ses souvenirs \u00e0 Kirkenes, dans l&rsquo;extr\u00eame nord de la Norv\u00e8ge, juste \u00e0 la fronti\u00e8re avec la Russie. Bien que minuscule \u2014 \u00e0 peine 3 500 habitants \u2014 elle est devenue un point central de la comp\u00e9tition internationale entre l&rsquo;Europe, la Russie et la Chine. Comme l&rsquo;explique Mak, en raison du r\u00e9chauffement climatique, \u00ab&#160;d&rsquo;ici 2030 environ, les mers arctiques seront probablement navigables pendant douze mois de l&rsquo;ann\u00e9e, et le temps de navigation de Shanghai \u00e0 Rotterdam par cette route est d&rsquo;environ vingt jours, au lieu de trente ou quarante via le Canal de Suez&#160;\u00bb. Il y a des signes avant-coureurs d&rsquo;une mont\u00e9e des tensions&#160;: un personnage local tr\u00e8s appr\u00e9ci\u00e9, Frode Berg, a \u00e9t\u00e9 arr\u00eat\u00e9 pour espionnage par le FSB lors d&rsquo;une visite \u00e0 Moscou en 2017. Il \u00e9tait le pr\u00e9sident du conseil de l&rsquo;\u00e9glise, l&rsquo;un des organisateurs du festival des arts frontaliers et un ardent d\u00e9fenseur du rapprochement avec la Russie. (Il a avou\u00e9 plus tard et est revenu en Norv\u00e8ge dans le cadre d&rsquo;un \u00e9change d&rsquo;espions.).&nbsp;<\/p>\n\n\n\n<p>La plus grande le\u00e7on que retient Mak vient de ses conversations avec Bart Somers, maire depuis 2001 de Malines, une petite ville de Flandre. Confront\u00e9 \u00e0 des tensions avec une population musulmane croissante apr\u00e8s le 11 septembre, il a mis en place un certain nombre d&rsquo;initiatives \u2014 ayant des \u00ab&#160;p\u00e8res de quartier&#160;\u00bb visitant la ville au coucher du soleil, des \u00ab&#160;grands fr\u00e8res&#160;\u00bb surveillant les aires de jeux communes, des contrats de six mois avec les parents pour que leurs enfants rejoignent un club de sport, un \u00ab&#160;pote&#160;\u00bb de la ville pour accueillir les nouveaux r\u00e9fugi\u00e9s \u2014 qui ont pu r\u00e9tablir la confiance entre les diff\u00e9rentes communaut\u00e9s et avec les autorit\u00e9s. Somers est issu d&rsquo;une famille \u00ab&#160;noire&#160;\u00bb, comme on appelle les nationalistes flamands qui ont collabor\u00e9 pendant la guerre, ce qui lui a donn\u00e9 un aper\u00e7u de l&rsquo;\u00e9tat d&rsquo;esprit ferm\u00e9 qui domine des environnements tels que dans sa ville natale, avec sa nostalgie, sa mentalit\u00e9 du \u00ab&#160;nous-contre-eux&#160;\u00bb et sa parano\u00efa. Dans un contexte tr\u00e8s diff\u00e9rent, c&rsquo;est le genre d&rsquo;atmosph\u00e8re qui a produit Vladimir Poutine. Pour Mak, les villes alli\u00e9es au niveau europ\u00e9en, et non les \u00c9tats-nations, sont la voie \u00e0 suivre pour s&rsquo;attaquer au double probl\u00e8me de l&rsquo;immigration et du nationalisme.<\/p>\n\n\n\n<p>Dans son \u00e9pilogue, Mak \u00e9crit une lettre \u00e0 son \u00ab&#160;\u00e9l\u00e8ve&#160;\u00bb de 2069. Il conclut en citant l&rsquo;un de ses \u00ab&#160;mentors&#160;\u00bb, l&rsquo;historien am\u00e9ricano-hongrois John Lukacs, qui a proph\u00e9tis\u00e9 que la fin du XXe si\u00e8cle marquerait la fin de la \u00ab&#160;soci\u00e9t\u00e9 bourgeoise&#160;\u00bb. Mak est ici sur un terrain dangereux&nbsp;&#160;: Lukacs \u00e9tait un penseur explicitement r\u00e9actionnaire. Mais l&rsquo;invasion de l&rsquo;Ukraine par Poutine marque certainement un \u00ab&#160;changement de paradigme&#160;\u00bb&#160;: le retour de la guerre sur le continent europ\u00e9en.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les villes alli\u00e9es au niveau europ\u00e9en, et non les \u00c9tats-nations, sont la voie \u00e0 suivre pour s&rsquo;attaquer au double probl\u00e8me de l&rsquo;immigration et du nationalisme.&nbsp;<\/p><cite>Hugo Drochon<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La question de savoir si le conflit bosniaque des ann\u00e9es 1990 \u00e9tait une guerre civile ou une \u00ab&#160;guerre d&rsquo;agression&#160;\u00bb fait toujours d\u00e9bat, et on aurait pu en dire autant de l\u2019Ukraine auparavant, compte tenu des liens \u00e9troits entre les peuples ukrainien et russe. Mais l&rsquo;invasion russe a r\u00e9v\u00e9l\u00e9 deux choses&#160;: les Ukrainiens se consid\u00e8rent Europ\u00e9ens, et les Europ\u00e9ens les consid\u00e8rent Europ\u00e9ens aussi. La notion de peuple \u00ab&#160;europ\u00e9en&#160;\u00bb est souvent ridiculis\u00e9e, mais le sentiment semble tangible ici, d&rsquo;une mani\u00e8re ouverte que Pagden et Weller accueilleraient favorablement \u2014 m\u00eame si Weller aurait raison de dire que le traitement des \u00e9tudiants africains \u00e0 la fronti\u00e8re polonaise montre que nous avons encore du chemin \u00e0 parcourir. Peut-\u00eatre que les Russes sont aussi des Europ\u00e9ens \u2014 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/11\/erdogan-se-voit-comme-lenchanteur-en-chef-de-la-turquie-contemporaine-une-conversation-avec-olivier-bouquet\/\">une \u00e9nigme permanente, tout comme la place que la Turquie est cens\u00e9e occuper par rapport \u00e0 l&rsquo;Europe<\/a>. Pour l&rsquo;instant, Poutine et Erdogan ont adopt\u00e9 des positions explicitement anti-europ\u00e9ennes, sans ignorer les m\u00e9saventures d&rsquo;apr\u00e8s-guerre de l&rsquo;Occident et de l&rsquo;Union.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000011-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000011-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000011-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000011-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000011-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Un train ukrainien porte les stigmates des bombardements russes. \u00a9 SOPA Images\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>\u00c9crivant en 1886, Nietzsche \u2013 personnage qui, par l&rsquo;\u00e9pigraphe de Pagden, le ch\u0153ur grec, la philosophie \u00ab&#160;continentale&#160;\u00bb ou le voyage \u00e0 travers l&rsquo;Europe, hante les quatre livres \u00e0 l&rsquo;\u00e9tude \u2013 souhaite une \u00ab&#160;augmentation de l&rsquo;attitude mena\u00e7ante de la Russie [afin] que l&rsquo;Europe se d\u00e9cide \u00e0 devenir \u00e9galement mena\u00e7ant et, pr\u00e9cis\u00e9ment, \u00e0 acqu\u00e9rir une volont\u00e9 unique&#160;\u00bb. Le temps de la \u00ab&#160;petite politique&#160;\u00bb, de la \u00ab&#160;longue com\u00e9die d\u00e9brid\u00e9e du petit provincialisme europ\u00e9en&#160;\u00bb et de la fragmentation, \u00e9crit-il dans <em>Par-del\u00e0 le bien et le mal<\/em>, est r\u00e9volu. L&rsquo;heure est \u00e0 la \u00ab&#160;grande politique&#160;\u00bb.<\/p>\n\n\n\n<p>Un si\u00e8cle et demi plus tard, le v\u0153u de Nietzsche semble avoir \u00e9t\u00e9 exauc\u00e9. Mais en cet homme qui, au cr\u00e9puscule de sa vie, perdant son emprise sur la raison, s&rsquo;est d\u00e9clar\u00e9 descendant d&rsquo;une longue lign\u00e9e de nobles polonais \u2014 Friedrich Nietzky \u2014 aurait r\u00e9pugn\u00e9 au sacrifice du peuple ukrainien. Sa \u00ab&#160;grande politique&#160;\u00bb devait \u00eatre men\u00e9e par de \u00ab&#160;bons Europ\u00e9ens&#160;\u00bb&#160;: \u00e0 son \u00e9poque, Nietzsche consid\u00e9rait les Juifs comme particuli\u00e8rement aptes. Volodymyr Zelensky semble certainement \u00e0 la hauteur de la t\u00e2che.<\/p>\n\n\n\n<p>On sait quel aurait \u00e9t\u00e9 le conseil de Naud\u00e9&#160;: une frappe audacieuse et inattendue contre l&rsquo;arm\u00e9e russe pour lib\u00e9rer l&rsquo;Ukraine. Il \u00e9crit&nbsp;&#160;: \u00ab&#160;dans les coups d&rsquo;\u00c9tat, on voit plut\u00f4t tomber le tonnerre qu\u2019on ne l\u2019a entendu gronder dans les nu\u00e9es, <em>il frappe avant que d\u2019\u00e9clater<\/em>, les matines s\u2019y disent auparavant qu\u2019on les sonne, l\u2019ex\u00e9cution pr\u00e9c\u00e8de la sentence\u2026 Tel re\u00e7oit le coup qui le pensait donner, tel y meurt qui pensait bien \u00eatre en s\u00fbret\u00e9, en p\u00e2tit qui n\u2019y songeait pas, tout s\u2019y fait de nuit, \u00e0 l\u2019obscur, et parmi les brouillards et t\u00e9n\u00e8bres\u2026&#160;\u00bb<\/p>\n\n\n\n<p>Un coup de ma\u00eetre spectaculaire&nbsp;&#160;: un \u00ab&#160;coup d&rsquo;\u00c9tat&#160;\u00bb au vrai sens du terme. Qui serait pr\u00eat \u00e0 donner un tel ordre&nbsp;&#160;? L&rsquo;Europe a peut-\u00eatre trouv\u00e9 son unit\u00e9, mais elle attend son nouvel Auguste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guerre en Ukraine a repos\u00e9 la question des limites de l\u2019Union. \u00c0 partir de la lecture d\u2019essais r\u00e9cents \u2014 d\u2019Anthony Pagden \u00e0 Perry Anderson \u2014 Hugo Drochon s\u2019interroge sur le pass\u00e9 et le futur de l\u2019id\u00e9e europ\u00e9enne au moment o\u00f9 celle-ci doit \u00e0 nouveau d\u00e9terminer sa forme politique. Quel coup d\u2019\u00e9clat sera suffisant pour faire advenir l\u2019\u00c9tat europ\u00e9en du futur&#160;&#160;?<\/p>\n","protected":false},"author":8153,"featured_media":210068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":15,"footnotes":""},"categories":[2024],"tags":[],"staff":[3649],"editorial_format":[4849],"serie":[],"audience":[],"geo":[1917],"class_list":["post-209677","post","type-post","status-publish","format-standard","hentry","category-histoire","staff-hugo-drochon","editorial_format-etudes","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":210068,"excerpt":"La guerre en Ukraine a repos\u00e9 la question des limites de l\u2019Union. \u00c0 partir de la lecture d\u2019essais r\u00e9cents \u2014 d\u2019Anthony Pagden \u00e0 Perry Anderson \u2014 Hugo Drochon s\u2019interroge sur le pass\u00e9 et le futur de l\u2019id\u00e9e europ\u00e9enne au moment o\u00f9 celle-ci doit \u00e0 nouveau d\u00e9terminer sa forme politique. Quel coup d\u2019\u00e9clat sera suffisant pour faire advenir l\u2019\u00c9tat europ\u00e9en du futur ?","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;Europe face \u00e0 ses empires : futur d&#039;une id\u00e9e | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Europe face \u00e0 ses empires : futur d&#039;une id\u00e9e | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La guerre en Ukraine a repos\u00e9 la question des limites de l\u2019Union. \u00c0 partir de la lecture d\u2019essais r\u00e9cents \u2014 d\u2019Anthony Pagden \u00e0 Perry Anderson \u2014 Hugo Drochon s\u2019interroge sur le pass\u00e9 et le futur de l\u2019id\u00e9e europ\u00e9enne au moment o\u00f9 celle-ci doit \u00e0 nouveau d\u00e9terminer sa forme politique. Quel coup d\u2019\u00e9clat sera suffisant pour faire advenir l\u2019\u00c9tat europ\u00e9en du futur&#160;?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T10:54:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T10:54:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/GC_Drochon-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"baptiste.rogerlacan@legrandcontinent.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/GC_Drochon1-1-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"baptiste.rogerlacan@legrandcontinent.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/\",\"name\":\"L'Europe face \u00e0 ses empires : futur d'une id\u00e9e | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg\",\"datePublished\":\"2023-11-27T10:54:54+00:00\",\"dateModified\":\"2023-11-27T10:54:57+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/df00512482cc39b0e3d34c195acd337b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Un train ukrainien porte les stigmates des bombardements russes. \u00a9 SOPA Images\/SIPA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Europe face \u00e0 ses empires&#160;: futur d&rsquo;une id\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/df00512482cc39b0e3d34c195acd337b\",\"name\":\"baptiste.rogerlacan@legrandcontinent.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8540881937341daae3b48048a533f299?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8540881937341daae3b48048a533f299?s=96&d=mm&r=g\",\"caption\":\"baptiste.rogerlacan@legrandcontinent.eu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Europe face \u00e0 ses empires : futur d'une id\u00e9e | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Europe face \u00e0 ses empires : futur d'une id\u00e9e | Le Grand Continent","og_description":"La guerre en Ukraine a repos\u00e9 la question des limites de l\u2019Union. \u00c0 partir de la lecture d\u2019essais r\u00e9cents \u2014 d\u2019Anthony Pagden \u00e0 Perry Anderson \u2014 Hugo Drochon s\u2019interroge sur le pass\u00e9 et le futur de l\u2019id\u00e9e europ\u00e9enne au moment o\u00f9 celle-ci doit \u00e0 nouveau d\u00e9terminer sa forme politique. Quel coup d\u2019\u00e9clat sera suffisant pour faire advenir l\u2019\u00c9tat europ\u00e9en du futur&#160;?","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/","og_site_name":"Le Grand Continent","article_published_time":"2023-11-27T10:54:54+00:00","article_modified_time":"2023-11-27T10:54:57+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/GC_Drochon-1-scaled.jpg","type":"image\/jpeg"}],"author":"baptiste.rogerlacan@legrandcontinent.eu","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/GC_Drochon1-1-scaled.jpg","twitter_misc":{"\u00c9crit par":"baptiste.rogerlacan@legrandcontinent.eu","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/","name":"L'Europe face \u00e0 ses empires : futur d'une id\u00e9e | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg","datePublished":"2023-11-27T10:54:54+00:00","dateModified":"2023-11-27T10:54:57+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/df00512482cc39b0e3d34c195acd337b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg","width":2560,"height":1707,"caption":"Un train ukrainien porte les stigmates des bombardements russes. \u00a9 SOPA Images\/SIPA"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/27\/leurope-face-a-ses-empires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Europe face \u00e0 ses empires&#160;: futur d&rsquo;une id\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/df00512482cc39b0e3d34c195acd337b","name":"baptiste.rogerlacan@legrandcontinent.eu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8540881937341daae3b48048a533f299?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8540881937341daae3b48048a533f299?s=96&d=mm&r=g","caption":"baptiste.rogerlacan@legrandcontinent.eu"}}]}},"lgc_categories":[{"id":2024,"name":"Histoire","slug":"histoire"}],"lgc_author":{"id":3649,"name":"Hugo Drochon","slug":"hugo-drochon","description":"Hugo Drochon est historien de la pens\u00e9e politique des XIXe et XXe si\u00e8cles et chercheur postdoctoral au CRASSH (Centre for Research in the Arts, Social Sciences, and Humanities) de l'universit\u00e9 de Cambridge.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/GC_Drochon.png","width":530,"height":534,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/SIPA_01134993_000004-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/209677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/8153"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=209677"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/209677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/210068"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=209677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=209677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=209677"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=209677"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=209677"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=209677"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=209677"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=209677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}