{"id":208913,"date":"2023-11-16T19:15:57","date_gmt":"2023-11-16T18:15:57","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=208913"},"modified":"2023-11-17T10:15:20","modified_gmt":"2023-11-17T09:15:20","slug":"israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/","title":{"rendered":"Isra\u00ebl, bande de Gaza, Cisjordanie&#160;: ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours"},"content":{"rendered":"\n<p>Apr\u00e8s quarante jours de guerre de Soukkot, des premi\u00e8res \u00e9valuations de son impact \u00e9conomique sur Isra\u00ebl et sur les territoires palestiniens de la bande de Gaza et de Cisjordanie \u00e9mergent.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le co\u00fbt de la guerre pour l\u2019\u00e9conomie isra\u00e9lienne s\u2019\u00e9l\u00e8verait \u00e0 260 millions de dollars par jour, d\u2019apr\u00e8s <em>Bloomberg<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-208913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#easy-footnote-bottom-1-208913' title='Bloomberg, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bloomberg.com\/news\/articles\/2023-11-12\/israel-s-hamas-war-budget-leaves-netanyahu-caught-between-markets-and-politics&quot;&gt;War Budget Leaves Netanyahu Caught Between Markets and Politics&lt;\/a&gt;&amp;#160;\u00bb, 12 November 2023.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>En termes de r\u00e9ponse budg\u00e9taire, l\u2019id\u00e9e de pr\u00e9lever des fonds initialement d\u00e9di\u00e9s \u00e0 des d\u00e9penses exig\u00e9es par les partis les plus nationalistes de la coalition (comme les fonds pour les \u00e9coles ultra-orthodoxes), demeure controvers\u00e9e. Ces coupes budg\u00e9taires sont toutefois encourag\u00e9es par la Banque d\u2019Isra\u00ebl, qui a mis en garde le 15 novembre contre un creusement excessif du d\u00e9ficit, mettant l\u2019accent sur le fait que les d\u00e9penses suppl\u00e9mentaires engag\u00e9es pour la s\u00e9curit\u00e9 devaient \u00eatre effectu\u00e9es dans \u00ab&#160;un cadre budg\u00e9taire responsable&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-208913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#easy-footnote-bottom-2-208913' title='Bank of Israel, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/boi.org.il\/en\/communication-and-publications\/press-releases\/a15-11-23\/&quot;&gt;The Bank of Israel\u2019s position on fiscal issues and adjustments to the 2023 budget following the \u201cSwords of Iron\u201d war&lt;\/a&gt;&amp;#160;\u00bb, 15 November 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>L\u2019impact de la guerre et les perspectives n\u00e9gatives pour l\u2019\u00e9conomie isra\u00e9lienne sont \u00e9galement visibles sur les march\u00e9s financiers. La prime de risque sur les titres de dette isra\u00e9lienne par rapport au taux sans risque est aujourd\u2019hui sup\u00e9rieure de 25 points de base \u00e0 sa valeur au 6 octobre.&nbsp;<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/gwVem\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le cours du shekel par rapport au dollar a connu une l\u00e9g\u00e8re remont\u00e9e au d\u00e9but du mois de novembre, mais reste \u00e0 des valeurs records par rapport aux cinq derni\u00e8res ann\u00e9es.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Aux c\u00f4t\u00e9s du <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/15\/a-gaza-1-personne-sur-200-aurait-ete-tuee-depuis-le-7-octobre\/\">bilan humain<\/a>, les pertes mat\u00e9rielles et \u00e9conomiques dans la bande de Gaza sont cons\u00e9quentes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019Organisation internationale du travail estime qu\u2019au moins 61&#160;% des emplois dans l\u2019enclave ont \u00e9t\u00e9 perdus \u2014 soit 182 000&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-208913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#easy-footnote-bottom-3-208913' title='International Labour Organisation, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.ilo.org\/wcmsp5\/groups\/public\/---arabstates\/---ro-beirut\/documents\/publication\/wcms_901136.pdf&quot;&gt;Impact of the Israel-Hamas conflict on the labour market and livelihoods in the Occupied Palestinian Territory&lt;\/a&gt;&amp;#160;\u00bb, Bulletin No.1, November 2023.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>208 000 Cisjordaniens ont perdu leur emploi \u2014 soit 24&#160;% de la population active et mes pertes en revenu du travail sont estim\u00e9es \u00e0 12,8 millions de dollars par jour&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-208913' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#easy-footnote-bottom-4-208913' title='Calcul de l\u2019OIT, approximant les revenus du travail par le salaire moyen des employ\u00e9s salari\u00e9s (qui repr\u00e9sente environ 75&amp;#160;% de l\u2019emploi total en Cisjordanie et dans la bande de Gaza).'><sup>4<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Les 20 000 Palestiniens disposant d\u2019un visa de travail d\u00e9livr\u00e9 par les autorit\u00e9s isra\u00e9liennes, les autorisant en temps normal \u00e0 travailler en Isra\u00ebl, se sont vus priv\u00e9s de leur emploi.&nbsp;<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/zvIiu\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La guerre aggrave ainsi une situation \u00e9conomique d\u00e9j\u00e0 tr\u00e8s d\u00e9t\u00e9rior\u00e9e dans les territoires palestiniens de la bande de Gaza et de Cisjordanie.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/Zg6mB\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le taux de ch\u00f4mage dans la bande de Gaza atteignait 46,4&#160;% au deuxi\u00e8me trimestre 2023. En Cisjordanie, bien que moins \u00e9lev\u00e9 et s\u2019\u00e9talant en moyenne sur des p\u00e9riodes moins longues (6 mois contre 14 mois en moyenne dans la bande de Gaza), le ch\u00f4mage s\u2019\u00e9levait \u00e0 13,4&#160;% au m\u00eame trimestre.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/y2WwY\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Avant m\u00eame les bombardements de la guerre de Soukkot, la proportion de Palestiniens ayant rencontr\u00e9 des difficult\u00e9s \u00e0 se procurer un logement \u00e9tait d\u00e9j\u00e0 de 29&#160;%.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Quarante jours apr\u00e8s le d\u00e9but de la guerre de Soukkot, alors que le bilan des victimes humaines et des destructions mat\u00e9rielles continue de s\u2019alourdir, son impact \u00e9conomique sur Isra\u00ebl et en Palestine se pr\u00e9cise. <\/p>\n","protected":false},"author":6617,"featured_media":208914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[3611],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-208913","post","type-post","status-publish","format-standard","hentry","category-la-guerre-de-soukkot","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":208914,"excerpt":"Quarante jours apr\u00e8s le d\u00e9but de la guerre de Soukkot, alors que le bilan des victimes humaines et des destructions mat\u00e9rielles continue de s\u2019alourdir, son impact \u00e9conomique sur Isra\u00ebl et en Palestine se pr\u00e9cise. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Isra\u00ebl, bande de Gaza, Cisjordanie : ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isra\u00ebl, bande de Gaza, Cisjordanie : ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Quarante jours apr\u00e8s le d\u00e9but de la guerre de Soukkot, alors que le bilan des victimes humaines et des destructions mat\u00e9rielles continue de s\u2019alourdir, son impact \u00e9conomique sur Isra\u00ebl et en Palestine se pr\u00e9cise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T18:15:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T09:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"elenam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"elenam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/\",\"name\":\"Isra\u00ebl, bande de Gaza, Cisjordanie : ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png\",\"datePublished\":\"2023-11-16T18:15:57+00:00\",\"dateModified\":\"2023-11-17T09:15:20+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png\",\"width\":1240,\"height\":1186},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isra\u00ebl, bande de Gaza, Cisjordanie&#160;: ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48\",\"name\":\"elenam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g\",\"caption\":\"elenam\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isra\u00ebl, bande de Gaza, Cisjordanie : ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/","og_locale":"fr_FR","og_type":"article","og_title":"Isra\u00ebl, bande de Gaza, Cisjordanie : ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours | Le Grand Continent","og_description":"Quarante jours apr\u00e8s le d\u00e9but de la guerre de Soukkot, alors que le bilan des victimes humaines et des destructions mat\u00e9rielles continue de s\u2019alourdir, son impact \u00e9conomique sur Isra\u00ebl et en Palestine se pr\u00e9cise.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/","og_site_name":"Le Grand Continent","article_published_time":"2023-11-16T18:15:57+00:00","article_modified_time":"2023-11-17T09:15:20+00:00","og_image":[{"width":1240,"height":1186,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png","type":"image\/png"}],"author":"elenam","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"elenam","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/","name":"Isra\u00ebl, bande de Gaza, Cisjordanie : ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png","datePublished":"2023-11-16T18:15:57+00:00","dateModified":"2023-11-17T09:15:20+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png","width":1240,"height":1186},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/16\/israel-bande-de-gaza-cisjordanie-ce-que-lon-sait-de-limpact-economique-de-la-guerre-de-soukkot-apres-40-jours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Isra\u00ebl, bande de Gaza, Cisjordanie&#160;: ce que l\u2019on sait de l\u2019impact \u00e9conomique de la guerre de Soukkot apr\u00e8s 40 jours"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/4321684816ae1d7e501f1fe2d98dbf48","name":"elenam","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bac1ca1e34271700e00edbab2385d1dc?s=96&d=mm&r=g","caption":"elenam"}}]}},"lgc_categories":[{"id":3611,"name":"Isra\u00ebl, Hamas&#160;: le 7-Octobre deux ans apr\u00e8s","slug":"la-guerre-de-soukkot"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/11\/zvIiu-taux-de-ch-mage-dans-la-bande-de-gaza-en-2022-par-localit-s-2.png","width":1240,"height":1186,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/208913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/6617"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=208913"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/208913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/208914"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=208913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=208913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=208913"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=208913"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=208913"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=208913"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=208913"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=208913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}