{"id":202736,"date":"2023-10-09T19:30:00","date_gmt":"2023-10-09T17:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=202736"},"modified":"2023-10-09T19:57:48","modified_gmt":"2023-10-09T17:57:48","slug":"bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/","title":{"rendered":"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl"},"content":{"rendered":"\n<p>Bilan humain. Les derni\u00e8res estimations \u00e0 19h30 (Paris) font \u00e9tat de&nbsp;&#160;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>700 Isra\u00e9liens tu\u00e9s, 2 400 bless\u00e9s&#160;;<\/li>\n\n\n\n<li>560 Palestiniens tu\u00e9s, au moins 2 700 bless\u00e9s.<\/li>\n\n\n\n<li>Le nombre d\u2019otages retenus par le Hamas est toujours \u00e9valu\u00e9 \u00e0 au moins 150.<\/li>\n\n\n\n<li>La r\u00e9gion de J\u00e9rusalem a \u00e9t\u00e9 cibl\u00e9e par des tirs de roquettes depuis Gaza, qui ont fait dix bless\u00e9s, dont deux graves.<\/li>\n<\/ul>\n\n\n\n<p>Le front et les combats. Des affrontements ont eu lieu tout au long de la journ\u00e9e dans le Sud du pays, o\u00f9 des membres du Hamas ont r\u00e9ussi \u00e0 s\u2019infiltrer depuis samedi matin, tuant plusieurs centaines d\u2019Isra\u00e9liens, civils et militaires et multipliant les prises d\u2019otages. Le 9 octobre au soir, le minist\u00e8re de la D\u00e9fense a annonc\u00e9 avoir repris le contr\u00f4le face au Hamas dans le Sud du pays. Si l\u2019infiltration semble contenue, la pr\u00e9sence du Hamas dans certaines poches \u00e9tait encore signal\u00e9e lundi soir.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/RZzar\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En plus de l\u2019annonce d\u2019un \u00ab&#160;si\u00e8ge complet&#160;\u00bb sur la bande de Gaza aujourd\u2019hui par le ministre de la D\u00e9fense isra\u00e9lien, les forces de d\u00e9fense du pays ont poursuivi les bombardements.&nbsp;<\/li>\n\n\n\n<li>Aux alentours de 17h30 (Paris), le ministre de la D\u00e9fense faisait savoir qu\u2019il avait ordonn\u00e9 une intensification des frappes sur Gaza. En r\u00e9ponse, les responsables du Hamas ont annonc\u00e9 par communiqu\u00e9 qu\u2019un otage sera ex\u00e9cut\u00e9 \u00ab&#160;pour chaque&nbsp; bombardement isra\u00e9lien&#160;\u00bb.&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Les services de t\u00e9l\u00e9phonie et d\u2019Internet auraient subi des coupures dans la bande de Gaza suite \u00e0 une frappe visant la principale entreprise de t\u00e9l\u00e9communication du pays Paltel, d\u2019apr\u00e8s le <em>New York Times<\/em>.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Des tirs de roquettes auraient \u00e9t\u00e9 rapport\u00e9s en Cisjordanie.<\/li>\n<\/ul>\n\n\n\n<p>La situation int\u00e9rieure. Les questionnements sur la faillite des services de renseignements et de la responsabilit\u00e9 du gouvernement Netanyahou dans l\u2019absence d&rsquo;anticipation de l\u2019attaque se renforcent. L\u2019\u00e9tau pourrait encore se resserrer autour du Premier ministre directement critiqu\u00e9 ce matin dans le quotidien national <em>Haaretz <\/em>(<a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/netanyahou-responsable-de-lechec-disrael-selon-haaretz-a-jerusalem\/\">nous avons traduit l\u2019\u00e9ditorial<\/a>).&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019\u00c9gypte a affirm\u00e9 dans l\u2019apr\u00e8s-midi avoir averti Benjamin Netanyahou, le Premier Ministre isra\u00e9lien, qu\u2019une attaque de grande ampleur se pr\u00e9parait, mais que l\u2019importance de l\u2019information avait \u00e9t\u00e9 minimis\u00e9e par les autorit\u00e9s isra\u00e9liennes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-202736' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#easy-footnote-bottom-1-202736' title='Associated Press, &lt;a href=&quot;https:\/\/apnews.com\/article\/israel-hamas-gaza-attack-intel-a5287a18773232f26ca171233be01721&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;\u00ab&amp;#160;What went wrong&amp;#160;? Questions emerge over Israel\u2019s intelligence prowess after Hamas attack&amp;#160;\u00bb&lt;\/a&gt;, 9 October 2023.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le cabinet de Netanyahou a imm\u00e9diatement d\u00e9menti l\u2019information et affirm\u00e9 que le Premier ministre n\u2019avait pas \u00e9t\u00e9 en contact avec le chef des services de renseignement \u00e9gyptien depuis la formation de son gouvernement en d\u00e9cembre 2022.<\/li>\n<\/ul>\n\n\n\n<p>Les r\u00e9actions internationales.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019Union europ\u00e9enne, premi\u00e8re contributrice \u00e0 l\u2019aide au d\u00e9veloppement \u00e0 la Palestine, a annonc\u00e9 cet apr\u00e8s-midi la suspension de son aide au pays, faisant suite \u00e0 des d\u00e9cisions similaires de l\u2019Allemagne et de l\u2019Autriche. Le minist\u00e8re espagnol des affaires \u00e9trang\u00e8res s\u2019est dit formellement \u00ab&#160;en d\u00e9saccord&#160;\u00bb avec cette d\u00e9cision. Selon le <em>Financial Times<\/em>, l\u2019Union a par la suite clarifi\u00e9 sa position en pr\u00e9cisant que l\u2019aide humanitaire vers la Palestine pourrait continuer.<\/li>\n\n\n\n<li>Le secr\u00e9taire g\u00e9n\u00e9ral des Nations Unies Antonio Guterres, qui a fermement condamn\u00e9 l\u2019attaque du Hamas contre Isra\u00ebl, s\u2019est dit \u00ab&#160;boulevers\u00e9&#160;\u00bb par l\u2019annonce du si\u00e8ge complet de la bande de Gaza d\u00e9cid\u00e9 par l\u2019arm\u00e9e isra\u00e9lienne et a alert\u00e9 sur les potentielles cons\u00e9quences humanitaires du blocus&#160;: \u00ab&#160;Tout en reconnaissant les inqui\u00e9tudes l\u00e9gitimes d\u2019Isra\u00ebl pour sa s\u00e9curit\u00e9, je rappelle \u00e9galement \u00e0 Isra\u00ebl que les op\u00e9rations militaires doivent \u00eatre men\u00e9es en accord avec le droit international humanitaire&#160;\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>Nous venons d\u2019actualiser la carte des r\u00e9actions internationales, plus de 120 pays ont d\u00e9sormais pris position.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/QAl65\/59\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Vous trouverez <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/07\/israel-et-la-guerre-du-soukkot-geopolitique-des-reactions-a-lattaque-du-hamas-du-7-octobre-carte-exclusive-mise-a-jour-15h30-x-x-x\/\">par ici notre analyse<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le brouillard de la guerre du Soukkot s\u2019\u00e9paissit. La strat\u00e9gie isra\u00e9lienne, avant le lancement d\u2019une offensive terrestre \u00e0 Gaza, semble se focaliser en parall\u00e8le sur deux points&#160;&#160;: la reprise du contr\u00f4le dans le Sud du pays et le bombardement de la bande de Gaza, dont le si\u00e8ge a commenc\u00e9. L\u2019hypoth\u00e8se de l\u2019ouverture d\u2019un nouveau front au Nord n\u2019est toujours pas exclue alors que des combats a\u00e9riens et terrestres ont \u00e9t\u00e9 signal\u00e9s \u00e0 la fronti\u00e8re libanaise. Nous faisons le point \u00e0 19h30 (Paris).<\/p>\n","protected":false},"author":10,"featured_media":202740,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[3611],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-202736","post","type-post","status-publish","format-standard","hentry","category-la-guerre-de-soukkot","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":202740,"excerpt":"Le brouillard de la guerre du Soukkot s\u2019\u00e9paissit. La strat\u00e9gie isra\u00e9lienne, avant le lancement d\u2019une offensive terrestre \u00e0 Gaza, semble se focaliser en parall\u00e8le sur deux points : la reprise du contr\u00f4le dans le Sud du pays et le bombardement de la bande de Gaza, dont le si\u00e8ge a commenc\u00e9. L\u2019hypoth\u00e8se de l\u2019ouverture d\u2019un nouveau front au Nord n\u2019est toujours pas exclue alors que des combats a\u00e9riens et terrestres ont \u00e9t\u00e9 signal\u00e9s \u00e0 la fronti\u00e8re libanaise. Nous faisons le point \u00e0 19h30 (Paris).","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le brouillard de la guerre du Soukkot s\u2019\u00e9paissit. La strat\u00e9gie isra\u00e9lienne, avant le lancement d\u2019une offensive terrestre \u00e0 Gaza, semble se focaliser en parall\u00e8le sur deux points&#160;: la reprise du contr\u00f4le dans le Sud du pays et le bombardement de la bande de Gaza, dont le si\u00e8ge a commenc\u00e9. L\u2019hypoth\u00e8se de l\u2019ouverture d\u2019un nouveau front au Nord n\u2019est toujours pas exclue alors que des combats a\u00e9riens et terrestres ont \u00e9t\u00e9 signal\u00e9s \u00e0 la fronti\u00e8re libanaise. Nous faisons le point \u00e0 19h30 (Paris).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-09T17:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-09T17:57:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/gc-breve-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/gc-breve-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/\",\"name\":\"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/carte.jpg\",\"datePublished\":\"2023-10-09T17:30:00+00:00\",\"dateModified\":\"2023-10-09T17:57:48+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/carte.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/carte.jpg\",\"width\":1832,\"height\":1690},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/","og_locale":"fr_FR","og_type":"article","og_title":"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl | Le Grand Continent","og_description":"Le brouillard de la guerre du Soukkot s\u2019\u00e9paissit. La strat\u00e9gie isra\u00e9lienne, avant le lancement d\u2019une offensive terrestre \u00e0 Gaza, semble se focaliser en parall\u00e8le sur deux points&#160;: la reprise du contr\u00f4le dans le Sud du pays et le bombardement de la bande de Gaza, dont le si\u00e8ge a commenc\u00e9. L\u2019hypoth\u00e8se de l\u2019ouverture d\u2019un nouveau front au Nord n\u2019est toujours pas exclue alors que des combats a\u00e9riens et terrestres ont \u00e9t\u00e9 signal\u00e9s \u00e0 la fronti\u00e8re libanaise. Nous faisons le point \u00e0 19h30 (Paris).","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/","og_site_name":"Le Grand Continent","article_published_time":"2023-10-09T17:30:00+00:00","article_modified_time":"2023-10-09T17:57:48+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/gc-breve-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/gc-breve-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/","name":"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/carte.jpg","datePublished":"2023-10-09T17:30:00+00:00","dateModified":"2023-10-09T17:57:48+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/carte.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/carte.jpg","width":1832,"height":1690},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/09\/bilan-du-troisieme-jour-de-la-guerre-declenchee-par-le-hamas-contre-israel-x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Si\u00e8ge complet sur Gaza. Roquettes sur J\u00e9rusalem. Combats \u00e0 la fronti\u00e8re libanaise. Un bilan du troisi\u00e8me jour de la guerre d\u00e9clench\u00e9e par le Hamas contre Isra\u00ebl"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3611,"name":"Isra\u00ebl, Hamas&#160;: le 7-Octobre deux ans apr\u00e8s","slug":"la-guerre-de-soukkot"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/carte.jpg","width":1832,"height":1690,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/202736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=202736"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/202736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/202740"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=202736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=202736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=202736"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=202736"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=202736"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=202736"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=202736"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=202736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}