{"id":199454,"date":"2023-09-22T20:34:14","date_gmt":"2023-09-22T18:34:14","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=199454"},"modified":"2024-06-07T00:13:18","modified_gmt":"2024-06-06T22:13:18","slug":"mort-de-giorgio-napolitano","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/","title":{"rendered":"Giorgio Napolitano (1925-2023), le communiste devenu Roi"},"content":{"rendered":"\n<p class=\"has-drop-cap\">La vie de Giorgio Napolitano, n\u00e9 en 1925 et disparu le 22 septembre, \u00e9claire tout un pan de l\u2019histoire de l\u2019Italie de l\u2019apr\u00e8s-1945. Voil\u00e0 un homme qui s\u2019engagea pr\u00e9cocement en politique et qui, ensuite jusqu\u2019\u00e0 son dernier souffle, s\u2019y consacra pleinement tout en \u00e9tant un intellectuel d\u2019une immense culture, fin, raffin\u00e9, mais \u00e9galement un expert en \u00e9conomie et questions institutionnelles. Il est l\u2019auteur de nombreux ouvrages et a re\u00e7u de nombreuses et prestigieuses distinctions en Italie et en Europe, comme, pour n\u2019en citer qu\u2019une, le doctorat Honoris causa conf\u00e9r\u00e9 par la Sorbonne en 2010. Tr\u00e8s jeune, il adh\u00e9ra au Parti communiste italien (PCI), le plus important parti communiste de l\u2019Europe occidentale, solidement implant\u00e9 dans la p\u00e9ninsule, qui, surtout \u00e0 partir des ann\u00e9es 1960, fascina nombre de militants de gauche et d\u2019intellectuels bien au-del\u00e0 de la p\u00e9ninsule. Non seulement il connut les \u00e9volutions parfois sinueuses de son parti mais, \u00e0 partir l\u00e0 encore du milieu des ann\u00e9es 1960, il joua un r\u00f4le fondamental dans les d\u00e9bats portant sur les changements d\u2019orientation et d\u2019identit\u00e9 de ce m\u00eame parti sans toujours convaincre la masse de ses camarades. Ancr\u00e9 \u00e0 Naples, attach\u00e9 au Mezzogiorno, s\u2019employant \u00e0 trouver des solutions \u00e0 la question m\u00e9ridionale qui obs\u00e8de l\u2019Italie depuis son unit\u00e9, il analysa aussi les consid\u00e9rables transformations socio-\u00e9conomiques de son pays et les multiples crises politiques qui le secou\u00e8rent avec le souci constant de proposer des id\u00e9es et une strat\u00e9gie d\u2019action pour son parti. Puis, au fil des ann\u00e9es, il a \u00e9largi le spectre de ses int\u00e9r\u00eats \u00e0 l\u2019international cherchant des d\u00e9cennies durant \u00e0 d\u00e9m\u00ealer le n\u0153ud si complexe form\u00e9, d\u2019un c\u00f4t\u00e9, par le rapport historique de plus en plus probl\u00e9matique qu\u2019entretint son parti avec l\u2019Union sovi\u00e9tique et, de l\u2018autre, par la reconnaissance, \u00e0 son instigation ainsi que de quelques autres de ses proches, des m\u00e9rites et des avantages pour l\u2019Italie de l\u2019Europe, de l\u2019OTAN et m\u00eame des \u00c9tats-Unis. Critique \u00e0 l\u2019origine de la social-d\u00e9mocratie, ce communiste amor\u00e7a, au nom de son parti, un dialogue avec les partis s\u2019en r\u00e9clamant et, \u00e0 la fin, s\u2019y rallia avec armes et bagages.<\/p>\n\n\n\n<p>Enfin, il exer\u00e7a des responsabilit\u00e9s fort importantes et, cons\u00e9cration ultime d\u2019une remarquable carri\u00e8re, fut \u00e9lu \u00e0 la Pr\u00e9sidence de la R\u00e9publique \u00e0 81 ans, devenant le premier communiste et le titulaire le plus \u00e2g\u00e9 \u00e0 occuper cette charge. Grande premi\u00e8re dans l\u2019histoire de la R\u00e9publique italienne, il fut r\u00e9\u00e9lu pour un second mandat qu\u2019il n\u2019acheva pas. Il exer\u00e7a cette fonction en une p\u00e9riode de grandes tensions politiques, italiennes et internationales. Laquelle, avant m\u00eame son acc\u00e8s au Palais du Quirinal, avait d\u00e9j\u00e0 acquis un poids politique et symbolique particuli\u00e8rement fort qu\u2019il renfor\u00e7a d\u00e9lib\u00e9r\u00e9ment, suscitant de grandes controverses entre constitutionnalistes et responsables politiques. Politique exp\u00e9riment\u00e9, il se livra \u00e0 de subtiles man\u0153uvres tactiques, parfois fortement critiqu\u00e9es et pas toujours r\u00e9ussies, contrebalanc\u00e9es par une large ampleur de vue \u00e0 propos de l\u2019Italie, de son pass\u00e9, de son pr\u00e9sent, de son avenir, de l\u2019Europe et du monde qu\u2019il exposait dans des discours de haute vol\u00e9e qu\u2019il pronon\u00e7ait \u00e9galement dans un fran\u00e7ais exquis.<\/p>\n\n\n\n<p>Sa renomm\u00e9e et sa visibilit\u00e9 en Italie comme \u00e0 l\u2019\u00e9tranger en furent accrues et son prestige d\u00e9multipli\u00e9. Giorgio Napolitano, pour qui l\u2019a connu et eu l\u2019honneur de l\u2019approcher, \u00e9tait impressionnant, d\u2019une envergure exceptionnelle sans jamais \u00eatre intimidant, extr\u00eamement courtois, fort curieux, toujours ouvert au dialogue, alternant des conversations d\u2019une rare profondeur avec de malicieux traits d\u2019esprit.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Critique \u00e0 l\u2019origine de la social-d\u00e9mocratie, ce communiste amor\u00e7a, au nom de son parti, un dialogue avec les partis s\u2019en r\u00e9clamant et, \u00e0 la fin, s\u2019y rallia avec armes et bagages.<\/p><cite>Marc Lazar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Giorgio Napolitano est un enfant du fascisme&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-199454' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#easy-footnote-bottom-1-199454' title='Voir son autobiographie&amp;nbsp;&amp;#160;: Giorgio Napolitano, &lt;em&gt;Dal PCI al socialismo europeo. Un\u2019autobiografia politica&lt;\/em&gt;, Bari-Rome, Laterza, 2005 et Paolo Franchi, &lt;em&gt;Giorgio Napolitano. La traversata da Botteghe Oscure al Quirinale&lt;\/em&gt;, Milan, Rizzoli, 2013.'><sup>1<\/sup><\/a><\/span><\/span>. \u00c0 sa naissance, Mussolini est au pouvoir depuis trois ans et la m\u00eame ann\u00e9e il amorce la transformation du fascisme en un r\u00e9gime \u00e0 parti unique avec la promulgation des lois fascistissimes. Sa famille bourgeoise, un p\u00e8re avocat lib\u00e9ral assez traditionaliste qui acceptera tr\u00e8s difficilement le futur engagement politique de son fils, une m\u00e8re ayant des ascendances nobles, vit \u00e0 Naples.<\/p>\n\n\n\n<p>C\u2019est dans le prestigieux lyc\u00e9e classique Umberto Premier que le jeune Giorgio entame ses \u00e9tudes qu\u2019il poursuivra \u00e0 Padoue o\u00f9 ses parents se sont transf\u00e9r\u00e9s&#160;: dans cette ville du Nord, il commence \u00e0 fr\u00e9quenter des milieux antifascistes. \u00c0 17 ans, il revient dans la capitale parth\u00e9nop\u00e9enne pour faire ses \u00e9tudes de droit \u00e0 l\u2019Universit\u00e9 Federico II. Comme tous les jeunes de l\u2019\u00e9poque encadr\u00e9s au plus pr\u00e8s par le syst\u00e8me totalitaire mis en place par le fascisme, il est membre du Gruppo Universitario Fascista de la ville. Il s\u2019y fait remarquer par sa passion pour les arts, notamment le th\u00e9\u00e2tre dont il couvre l\u2019actualit\u00e9 avec sa rubrique dans l\u2019hebdomadaire du Groupe. Alors que le r\u00e9gime du Duce sombre, une partie de la jeunesse estudiantine entre en \u00e9bullition&#160;: elle souhaite la victoire des Am\u00e9ricains qui ont d\u00e9barqu\u00e9 en Afrique du Nord en novembre 1942 et en Sicile en 1943, suit avec jubilation la progression de l\u2019Arm\u00e9e rouge de Staline et se forme au marxisme. L\u2019Italie accumule les revers militaires, Mussolini est destitu\u00e9 le 25 juillet 1943, le gouvernement du Mar\u00e9chal Badoglio annonce le 8 septembre avoir sign\u00e9 l\u2019armistice avec les alli\u00e9s, l\u2019Allemagne envahit la p\u00e9ninsule plongeant le pays dans un chaos \u00e9pouvantable. Giorgio Napolitano vit dans sa ville de Naples bombard\u00e9e depuis des mois, gangren\u00e9e par la mis\u00e8re et une d\u00e9liquescence g\u00e9n\u00e9ralis\u00e9e qui fournira la mati\u00e8re du saisissant roman <em>La peau<\/em> de Curzio Malaparte avec lequel Napolitano noua une relation intellectuelle et politique \u00e0 \u00e9clipses, et qui poussera la population \u00e0 se soulever du 27 au 30 septembre 1943 pour se lib\u00e9rer de l\u2019occupation allemande. Fr\u00e9quentant un milieu de communistes napolitains depuis 1944, Giorgio Napolitano franchit le pas et adh\u00e8re au PCI en novembre de l\u2019ann\u00e9e suivante.<\/p>\n\n\n\n<p>Palmiro Togliatti, le secr\u00e9taire du PCI, d\u00e9barqu\u00e9 \u00e0 Naples le 27 mars 1944 en provenance d\u2019URSS, applique, avec son g\u00e9nie propre, les grandes orientations strat\u00e9giques du ma\u00eetre du Kremlin. Renon\u00e7ant pour le moment \u00e0 s\u2019emparer seul du pouvoir, la priorit\u00e9 \u00e9tant d\u2019obtenir la d\u00e9faite du Troisi\u00e8me Reich, il d\u00e9ploie une politique d\u2019unit\u00e9 nationale et s\u2019efforce de construire une organisation solide, ins\u00e9r\u00e9e dans les coins et recoins de la soci\u00e9t\u00e9 italienne pour&nbsp;mener \u00ab&#160;une guerre de position&#160;\u00bb et instaurer une forme \u00ab&#160;d\u2019h\u00e9g\u00e9monie culturelle&#160;\u00bb pour reprendre les termes d\u2019Antonio Gramsci dont Togliatti se d\u00e9clare l\u2019h\u00e9ritier tout en contr\u00f4lant de pr\u00e8s la publication de ses \u0153uvres. Ce parti a besoin de talents, surtout dans le Sud \u00ab&#160;profond&#160;\u00bb qui se m\u00e9fie de lui.&nbsp;Pire, le PCI se heurte aux \u00e9lites locales, notamment les propri\u00e9taires fonciers et la bourgeoise urbaine, qui le combattent violemment. Faut-il rappeler qu\u2019au r\u00e9f\u00e9rendum du 2 juin 1946, les Italiens choisissent la r\u00e9publique mais pas le Mezzogiorno et moins encore Naples qui vote \u00e0 pr\u00e8s de 80&#160;% pour le maintien de la monarchie&nbsp;&#160;? \u00c0 22 ans, Giorgio Napolitano devient permanent du parti, \u00ab&#160;<em>funzionario<\/em>&#160;\u00bb selon la terminologie italienne, donc fait de la politique son m\u00e9tier au lieu de devenir avocat \u00e0 l\u2019instar de son p\u00e8re. Il termine n\u00e9anmoins ses \u00e9tudes, d\u00e9crochant sa <em>laurea <\/em>en droit avec un travail sur le d\u00e9veloppement industriel manqu\u00e9 du Mezzogiorno. Au sein du parti, deux dirigeants nationaux exp\u00e9riment\u00e9s et li\u00e9s au Sud vont le marquer et contribuer \u00e0 sa formation&nbsp;&#160;: Giorgio Amendola et Emilio Sereni.<\/p>\n\n\n\n<p>Comme de nombreux jeunes intellectuels venus au communisme \u00e0 cette \u00e9poque, la formation de Napolitano passe par des lectures, des travaux d\u2019expertise marxiste sur la situation du Sud et la confrontation quotidienne avec les r\u00e9alit\u00e9s \u00e9conomiques, sociales, culturelles et humaines des \u00ab&#160;classes subalternes&#160;\u00bb pour parler de nouveau comme Gramsci. Le PCI ayant \u00e9t\u00e9 \u00e9vinc\u00e9 du gouvernement d\u2019unit\u00e9 nationale d\u2019Alcide De Gasperi en mai 1947 puis ayant subi une lourde d\u00e9faite aux premi\u00e8res \u00e9lections politiques au suffrage universel d\u2019avril 1948, entre en guerre froide et s\u2019aligne plus que jamais sur Moscou. Giorgio Napolitano devient un communiste stalinien \u00e0 la sauce italienne.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Comme de nombreux jeunes intellectuels venus au communisme \u00e0 cette \u00e9poque, la formation de Napolitano passe par des lectures, des travaux d\u2019expertise marxiste sur la situation du Sud et la confrontation quotidienne avec les r\u00e9alit\u00e9s \u00e9conomiques, sociales, culturelles et humaines des \u00ab&#160;classes subalternes&#160;\u00bb<\/p><cite>Marc Lazar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Dot\u00e9 de grandes capacit\u00e9s politiques, il franchit les \u00e9tapes du cursus honorum de son parti. Dirigeant de la f\u00e9d\u00e9ration de Caserte en 1951, il est \u00e9lu deux ans plus tard \u00e0 la Chambre des d\u00e9put\u00e9s et restera contin\u00fbment en poste durant 43 ans hormis pour la seule l\u00e9gislature de 1963 \u00e0 1968.<\/p>\n\n\n\n<p>En f\u00e9vrier 1956, le rapport secret de Khrouchtchev au XX\u00e8me Congr\u00e8s du PCUS d\u00e9nonce une partie des crimes de Staline. Sa publication quatre mois plus tard secoue le mouvement communiste international, y compris le PCI. Togliatti, mis en difficult\u00e9, contraint et forc\u00e9 par une contestation interne de reconna\u00eetre la v\u00e9racit\u00e9 de ce rapport, rebondit en donnant un entretien en juin de la m\u00eame ann\u00e9e \u00e0 la revue <em>Nuovi argomenti<\/em>. Il ent\u00e9rine la fin du parti guide, celui de l\u2019URSS, et plaide pour un polycentrisme pour le communisme international sans pour autant rompre avec Moscou. Cependant, en novembre 1956, au moment de l\u2019insurrection de Budapest, il demande l\u2019intervention des chars de l\u2019arm\u00e9e rouge et salue leur r\u00e9pression impitoyable. Napolitano l\u2019approuve compl\u00e8tement et s\u2019en repentira plus tard dans son autobiographie. Davantage, il critique durement les communistes oppositionnels qui s sont oppos\u00e9 \u00e0 la direction du parti. Sa fid\u00e9lit\u00e9 et sa loyaut\u00e9 \u00e0 la ligne du secr\u00e9taire sont r\u00e9compens\u00e9es. <\/p>\n\n\n\n<p>Au 8<sup>\u00e8me<\/sup> congr\u00e8s du PCI, il entre avec de nombreux autres jeunes orthodoxes au Comit\u00e9 central. Il \u00ab&#160;monte&#160;\u00bb plus que jamais dans la hi\u00e9rarchie du parti et dans la vie institutionnelle de l\u2019Italie. Il occupe diverses fonctions aupr\u00e8s de la direction centrale, o\u00f9 il se forge une solide r\u00e9putation. Il en va de m\u00eame \u00e0 la Chambre des d\u00e9put\u00e9s o\u00f9 il s\u2019active dans diverses commissions. Il ma\u00eetrise parfaitement les sujets d\u2019\u00e9conomie politique, du Sud, de l\u2019Italie, des politiques industrielles ou encore des syndicats. Par ailleurs, de 1963 \u00e0 1966, il est secr\u00e9taire de la f\u00e9d\u00e9ration communiste de Naples. Son ascension continue apr\u00e8s la mort de Togliatti \u00e0 l\u2019\u00e9t\u00e9 1964. Alors que Luigi Longo lui succ\u00e8de \u00e0 la t\u00eate du parti, celui-ci est travers\u00e9 par un d\u00e9bat entre deux sensibilit\u00e9s principales (les tendances sont officiellement interdites). Celle de Pietro Ingrao, dite \u00ab&#160;movimentista&#160;\u00bb, assez radicale, tente de surfer sur les protestations qui commencent de se manifester dans une Italie en pleine m\u00e9tamorphose et fustige les socialistes qui ont rompu leur alliance avec les communistes pour gouverner avec la D\u00e9mocratie chr\u00e9tienne. Celle de Giorgio Amendola, tout en \u00e9tant pro-sovi\u00e9tique, se montre plus soucieuse du respect des institutions, veut obtenir des r\u00e9formes constructives et entend maintenir un rapport avec le PSI. Napolitano choisit celle de son mentor qui, les ann\u00e9es suivantes, sera qualifi\u00e9e par ses opposants, non sans une certaine condescendance, de \u00ab&#160;migliorista&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Giorgio Napolitano campe sur ces positions mais, en charge de la politique culturelle du PCI de 1969 \u00e0 1975, il s\u2019efforce de nouer des relations et un dialogue avec les non communistes.<\/p><cite>Marc Lazar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En 1972, Enrico Berlinguer acc\u00e8de \u00e0 la direction du parti. Il s\u2019efforce de jouer l\u2019\u00e9quilibriste entre les deux sensibilit\u00e9s alors que l\u2019Italie connait depuis 1967-1968 une d\u00e9ferlante de contestations de toute la soci\u00e9t\u00e9 qui basculera dans la violence avec des attentats terroristes d\u2019abord de l\u2019ultra droite puis de l\u2019ultra gauche. Giorgio Napolitano devient alors l\u2019un des principaux dirigeants du PCI. \u00c0 partir de 1973, le PCI s\u2019engage dans la politique du compromis historique consistant en la recherche d\u2019un accord de gouvernement avec la D\u00e9mocratie chr\u00e9tienne qui \u00e9chouera et sera abandonn\u00e9e six ans plus tard. Parall\u00e8lement, surtout apr\u00e8s l\u2019invasion de la Tch\u00e9coslovaquie par les troupes du Pacte de Varsovie le 21 ao\u00fbt 1968 condamn\u00e9e par le parti italien, le PCI se lance dans ce que l\u2019on a appel\u00e9 l\u2019eurocommunisme auquel se rallieront le parti espagnol et le parti fran\u00e7ais. Il s\u2019agit de d\u00e9finir une strat\u00e9gie d\u2019acc\u00e8s au pouvoir en Europe occidentale en respectant les r\u00e8gles de la d\u00e9mocratie repr\u00e9sentative, en prenant des distances avec l\u2019URSS, voire en la critiquant pour sa politique interne et m\u00eame internationale sans pour autant couper les liens avec elle. En effet, lui sont reconnus le r\u00f4le historique repr\u00e9sent\u00e9 par la R\u00e9volution d\u2019Octobre et la force qu\u2019elle constitue face \u00e0 l\u2019imp\u00e9rialisme am\u00e9ricain et aux puissances capitalistes. C\u2019est ainsi que le PCI, fort prudent et timor\u00e9, ne soutiendra jamais les dissidents de l\u2019Est \u00e0 la diff\u00e9rence des socialistes, ce qui le coupera de nombreux intellectuels. Giorgio Napolitano campe sur ces positions mais, en charge de la politique culturelle du PCI de 1969 \u00e0 1975, il s\u2019efforce de nouer des relations et un dialogue avec les non communistes.<\/p>\n\n\n\n<p>\u00c0 cet \u00e9gard, sa r\u00e9putation franchit les fronti\u00e8res de l\u2019Italie, par exemple avec la publication en 1976 du livre <em>Intervista sul PCI<\/em> avec l\u2019historien Eric Hobsbawm qui sera traduit dans de nombreuses langues&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-199454' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#easy-footnote-bottom-2-199454' title='Giorgio Napolitano, &lt;em&gt;Intervista sul comunismo a cura di Eric Hobsbawm&lt;\/em&gt;, Bari-Rome, Laterza, 1975.'><sup>2<\/sup><\/a><\/span><\/span>. Dans le m\u00eame temps, et plus encore par la suite, il devient en quelque sorte le ministre des affaires \u00e9trang\u00e8res du PCI. Il commence \u00e0 engager des discussions avec la social-d\u00e9mocratie, en particulier le SPD, et se familiarise avec les arcanes de la construction europ\u00e9enne que son parti et lui-m\u00eame avaient, au d\u00e9part, condamn\u00e9e et qu\u2019ils avaient peu \u00e0 peu soutenue. Il obtient un visa pour un cycle de conf\u00e9rences dans les universit\u00e9s am\u00e9ricaines et visite aussi diverses institutions fort r\u00e9put\u00e9es en Allemagne et en Grande-Bretagne. Il est membre de la commission des affaires \u00e9trang\u00e8res de la Chambre des d\u00e9put\u00e9s et en deviendra le pr\u00e9sident. De 1984 \u00e0 1992 puis de 1994 \u00e0 1996, il fait partie de la d\u00e9l\u00e9gation italienne \u00e0 l\u2019Assembl\u00e9e de l\u2019Atlantique Nord. Il acquiert ainsi une stature internationale sans \u00e9quivalent dans son parti et reconnu \u00e9galement par toutes les autres forces politiques italiennes, y compris chez ses principaux adversaires. En 1989, il est \u00e9lu au parlement europ\u00e9en. Il y si\u00e8ge jusqu\u2019en 1992 puis de 1999 \u00e0 2004, et s\u2019impose comme l\u2019un des parlementaires les plus \u00e9cout\u00e9s et respect\u00e9s. Sa connaissance des dossiers internationaux, les solides contacts parmi les d\u00e9cideurs de toute nature qu\u2019il a \u00e9tablis font que Giorgio Napolitano exerce une influence d\u00e9cisive sur la politique internationale de son parti qui s\u2019av\u00e8re de plus en plus pro-europ\u00e9enne et ne remet plus en cause l\u2019appartenance de l\u2019Italie \u00e0 l\u2019OTAN qu\u2019il avait d\u00e9nonc\u00e9 au moment de sa constitution. Par la voix de Berlinguer, le PCI condamne l\u2019invasion sovi\u00e9tique en Afghanistan en 1979 et le coup d\u2019\u00e9tat du g\u00e9n\u00e9ral Jaruzelski en Pologne en 1981.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Sa connaissance des dossiers internationaux, les solides contacts parmi les d\u00e9cideurs de toute nature qu\u2019il a \u00e9tablis font que Giorgio Napolitano exerce une influence d\u00e9cisive sur la politique internationale de son parti qui s\u2019av\u00e8re de plus en plus pro-europ\u00e9enne et ne remet plus en cause l\u2019appartenance de l\u2019Italie \u00e0 l\u2019OTAN.<\/p><cite>Marc Lazar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Bien qu\u2019il pr\u00e9side le groupe parlementaire communiste \u00e0 la Chambre des d\u00e9put\u00e9s de 1981 \u00e0 1986 et que son aura est consid\u00e9rable, Napolitano ne succ\u00e9dera pas \u00e0 Enrico Berlinguer apr\u00e8s le d\u00e9c\u00e8s de celui-ci \u00e0 l\u2019\u00e9t\u00e9 de 1984. Son appartenance \u00e0 l\u2019aile mod\u00e9r\u00e9e, \u00ab&#160;migliorista&#160;\u00bb l\u2019en emp\u00eache car la majorit\u00e9 des membres du parti se situe plus \u00e0 gauche. Le PCI, apr\u00e8s une progression spectaculaire durant la d\u00e9cennie des ann\u00e9es 1970, amorce un d\u00e9clin \u00e9lectoral, est isol\u00e9 et ressemble \u00e0 un bateau ivre, d\u00e9nu\u00e9 d\u2019une strat\u00e9gie claire et efficace. Napolitano, se rapprochant de plus en plus du socialisme europ\u00e9en, d\u00e9fend une orientation r\u00e9formiste qui passerait par une alliance avec le Parti socialiste italien de Bettino Craxi, lequel tente de r\u00e9\u00e9quilibrer le rapport des forces avec les communistes suscitant leur d\u00e9testation. Il n\u2019est donc pas \u00e9cout\u00e9. N\u00e9anmoins, apr\u00e8s la chute du mur en 1989, Napolitano soutient totalement le nouveau secr\u00e9taire du PCI, Achille Occhetto, qui propose de renoncer \u00e0 l\u2019identit\u00e9 communiste. En 1991, na\u00eet le parti d\u00e9mocratique de la Gauche (PDS) qui deviendra sept ans plus tard D\u00e9mocrates de gauche (DS) puis le Parti d\u00e9mocrate (PD) en 2007. Giorgio Napolitano fait figure de vieux sage dans ce parti dirig\u00e9 par des jeunes qui ont fait leurs premi\u00e8res armes aux c\u00f4t\u00e9s de Berlinguer. Une nouvelle s\u00e9quence politique s\u2019ouvre en Italie qui prend une tournure in\u00e9dite en 1994 avec l\u2019\u00e9croulement du syst\u00e8me traditionnel des partis politiques suite \u00e0 l\u2019op\u00e9ration Mains propres des juges milanais, et le surgissement en politique de nouveaux acteurs, notamment Silvio Berlusconi. Cela am\u00e8ne Giorgio Napolitano \u00e0 occuper des responsabilit\u00e9s institutionnelles de plus en plus importantes. Il est pr\u00e9sident de la Chambre des d\u00e9put\u00e9s de 1992 \u00e0 1994 puis ministre de l\u2019int\u00e9rieur de 1996 \u00e0 1998 dans le gouvernement de Romano Prodi. Dans ce minist\u00e8re, en 1998, avec Livia Turco, ministre pour la solidarit\u00e9 sociale, il fait adopter une loi qui, d\u2019un c\u00f4t\u00e9, vise \u00e0 favoriser l\u2019int\u00e9gration de l\u2019immigration l\u00e9gale notamment en facilitant l\u2019acc\u00e8s \u00e0 la citoyennet\u00e9 italienne et, de l\u2019autre, cherche \u00e0 ma\u00eetriser l\u2019immigration irr\u00e9guli\u00e8re en proc\u00e9dant \u00e0 l\u2019ouverture de camps d\u2019accueil et \u00e0 des expulsions. Un an apr\u00e8s avoir fini son mandat \u00e0 Strasbourg, donc en 2005, il est nomm\u00e9 s\u00e9nateur \u00e0 vie par le Pr\u00e9sident Carlo Azeglio Ciampi. L\u2019ann\u00e9e suivante, le 10 mai 2006, 543 parlementaires sur 991 votants l\u2019\u00e9lisent onzi\u00e8me pr\u00e9sident de la R\u00e9publique.<\/p>\n\n\n\n<p>C\u2019est, on l\u2019a dit, la premi\u00e8re fois qu\u2019un ancien communiste acc\u00e8de \u00e0 la Pr\u00e9sidence de la R\u00e9publique et cela constitue un tournant important et historique. Il entend \u00eatre encore plus que ses pr\u00e9d\u00e9cesseurs \u00e0 la hauteur de ce que l\u2019institution pr\u00e9sidentielle lui impose car il est conscient que son pass\u00e9 militant dans les rangs du PCI inqui\u00e8te une partie de l\u2019opinion&nbsp;&#160;: il doit donc se montrer absolument impartial et rassembler les Italiens alors que nombre de sujets les divisent profond\u00e9ment. Malgr\u00e9 son \u00e2ge avanc\u00e9, 81 ans, Napolitano se montre un pr\u00e9sident tr\u00e8s actif en Italie, en Europe et \u00e0 l\u2019international. Il entend assurer un bon fonctionnement des institutions. C\u2019est pourquoi, il critique le recours r\u00e9gulier aux d\u00e9crets-lois et aux votes de confiance de la part des gouvernements de Romano Prodi et de Silvio Berlusconi et rappelle l\u2019importance du travail du Parlement auquel il se montre tr\u00e8s attach\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>C\u2019est, on l\u2019a dit, la premi\u00e8re fois qu\u2019un ancien communiste acc\u00e8de \u00e0 la Pr\u00e9sidence de la R\u00e9publique et cela constitue un tournant important et historique.<\/p><cite>Marc Lazar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Durant le gouvernement Berlusconi de 2008 \u00e0 2011, les rapports sont souvent tendus entre le Palais Chigi, si\u00e8ge du Pr\u00e9sident du Conseil, et le Palais du Quirinal. Le Pr\u00e9sident de la R\u00e9publique refuse d\u2019approuver certains textes et s\u2019il s\u2019estime dans l\u2019obligation d\u2019apposer sa signature \u00e0 des lois qu\u2019il d\u00e9sapprouve, il n\u2019h\u00e9site pas \u00e0 faire conna\u00eetre son point de vue critique. La droite accuse le Pr\u00e9sident de la R\u00e9publique d\u2019entraver l\u2019action de l\u2019ex\u00e9cutif, tandis que la gauche et le Mouvement 5 \u00e9toiles lui reprochent de trop contresigner les lois \u00e9manant de l\u2019ex\u00e9cutif. Durant les trois ann\u00e9es o\u00f9 Silvio Berlusconi dirige le gouvernement, d\u2019une certaine fa\u00e7on, deux l\u00e9gitimit\u00e9s s\u2019affrontent , ou mieux sont mobilis\u00e9es&#160;: le Pr\u00e9sident du Conseil argue qu\u2019il a re\u00e7u l\u2019onction du suffrage universel qui lui permet d\u2019agir comme il l\u2019entend ou presque, le Pr\u00e9sident de la R\u00e9publique \u00e9voque le pouvoir que lui donne la Constitution. Par ailleurs, Giorgio Napolitano joue un r\u00f4le d\u00e9terminant lors des crises de gouvernement. Celles de l\u2019ex\u00e9cutif de Romano Prodi (centre gauche) en 2007 et 2008, pour lesquelles il se d\u00e9m\u00e8ne afin de trouver des solutions parlementaires et \u00e9viter des \u00e9lections anticip\u00e9es&nbsp;&#160;; entreprise couronn\u00e9e de succ\u00e8s en 2007 mais qui \u00e9choue l\u2019ann\u00e9e suivante.<\/p>\n\n\n\n<p>En 2011, le troisi\u00e8me gouvernement de Silvio Berlusconi, install\u00e9 en 2008 apr\u00e8s sa victoire au scrutin du printemps, est fragilis\u00e9 par les affaires de m\u0153urs du Pr\u00e9sident du Conseil et la grave d\u00e9gradation de la situation \u00e9conomique du pays due, entre autres, aux effets de la crise des <em>subprimes<\/em> commenc\u00e9e aux \u00c9tats-Unis en 2007 et qui touche le monde entier l\u2019ann\u00e9e suivante. Napolitano accompagne la pression exerc\u00e9e par la Banque centrale europ\u00e9enne, le pr\u00e9sident de la R\u00e9publique Nicolas Sarkozy et la chanceli\u00e8re Angela Merkel pour obtenir un changement de gouvernement. Le 12 novembre, assailli de toutes parts, Silvio Berlusconi remet sa d\u00e9mission au Pr\u00e9sident de la R\u00e9publique. Celui-ci r\u00e9ussit alors un v\u00e9ritable coup de ma\u00eetre \u2014 un coup de force selon ses d\u00e9tracteurs \u2014 qu\u2019il justifie par la n\u00e9cessit\u00e9 de sauver le pays&nbsp;mais qui fait couler beaucoup d\u2019encre. En effet, Giorgio Napolitano qui, le 10 novembre, avait nomm\u00e9 de mani\u00e8re anticip\u00e9e Mario Monti, \u00e9conomiste, pr\u00e9sident de la Bocconi et ancien commissaire europ\u00e9en, s\u00e9nateur \u00e0 vie arrive, six jours plus tard, \u00e0 le faire nommer Pr\u00e9sident du Conseil par le Parlement. L\u2019ex\u00e9cutif compos\u00e9e de personnalit\u00e9s techniques doit assainir l\u2019\u00e9conomie de la p\u00e9ninsule, rassurer les capitales europ\u00e9ennes et mondiales ainsi que les march\u00e9s financiers. Cette nomination est tr\u00e8s bien accueillie par les d\u00e9cideurs internationaux qui encensent le pr\u00e9sident Napolitano.<\/p>\n\n\n\n<p>Toutefois, elle d\u00e9montre l\u2019impuissance des responsables politiques et la profonde d\u00e9fiance du Pr\u00e9sident de la R\u00e9publique envers eux. Justement, Mario Monti manquant d\u2019exp\u00e9rience politique, son gouvernement sera un gouvernement Monti-Napolitano. En 2013, apr\u00e8s les \u00e9lections qui en f\u00e9vrier n\u2019ont pas d\u00e9gag\u00e9 une majorit\u00e9 claire, le Pr\u00e9sident sera l\u00e0 encore \u00e0 la man\u0153uvre. En effet, le Parlement \u00e9tant incapable de d\u00e9signer son successeur, il accepte de faire un deuxi\u00e8me mandat mais \u00e0 condition que les partis acceptent de former \u00ab&#160;un gouvernement de grandes ententes&#160;\u00bb, ce que seul refuse le Mouvement 5 \u00e9toiles, fond\u00e9 par le comique Beppe Grillo et devenu le premier parti \u00e0 l\u2019issue du scrutin avec pr\u00e8s de 26&#160;% des suffrages. Le 20 avril, 738 voix sur 997 votants se portent sur son nom. Toutefois, Giorgio Napolitano&nbsp;annonce d\u2019embl\u00e9e qu\u2019il n\u2019ira pas au terme de son second mandat. Le 22 avril, dans son discours d\u2019investiture devant le Parlement, il admoneste les partis politique, critique leur incapacit\u00e9 \u00e0 se mettre d\u2019accord pour agir au service des Italiens. Il les met en demeure de changer la loi \u00e9lectorale, d\u2019engager des modifications constitutionnelles notamment en supprimant le bicam\u00e9ralisme int\u00e9gral et en reformulant les rapports entre \u00c9tat et r\u00e9gions, enfin il les appelle \u00e0 promulguer des r\u00e9formes sociales, en particulier en faveur de l\u2019emploi des jeunes. Dans la semaine qui suit, il contribue \u00e0 la naissance du gouvernement de centre gauche d\u2019Enrico Letta, dirigeant du Parti d\u00e9mocrate avec qui il entretient un excellent rapport personnel, mais qui ne dure que quelques mois (28 avril 2013-22 f\u00e9vrier 2014).<\/p>\n\n\n\n<p>Il fait appel ensuite \u00e0 Matteo Renzi, lui aussi jeune dirigeant du PD mais dont il se m\u00e9fie quelque peu. Sa pr\u00e9occupation reste toujours la m\u00eame&nbsp;&#160;: faire durer la l\u00e9gislature aussi longtemps que possible et engager les r\u00e9formes qu\u2019il a indiqu\u00e9es. Plus g\u00e9n\u00e9ralement, les actions de Giorgio Napolitano, qu\u2019une certaine presse italienne et \u00e9trang\u00e8re surnomme \u00ab&#160;le roi Giorgio&#160;\u00bb, suscitent des controverses. La droite, le Mouvement 5 \u00e9toiles et la gauche de la gauche d\u00e9noncent un pr\u00e9sident envahissant, \u00ab&#160;un souverain&#160;\u00bb ayant de facto instaur\u00e9 \u00ab&#160;le semi-pr\u00e9sidentialisme&#160;\u00bb selon le titre de l\u2019hebdomadaire <em>Left<\/em>, le 27 juillet 2013. Des constitutionnalistes d\u00e9battent de l\u2019\u00e9volution de la Pr\u00e9sidence de la R\u00e9publique, s\u2019interrogeant sur le fait de savoir si Giorgio Napolitano se livre dans les circonstances exceptionnelles que vit l\u2019Italie \u00e0 une interpr\u00e9tation pleine et enti\u00e8re de la Constitution ou s\u2019il tend \u00e0 bousculer quelque peu celle-ci&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-199454' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#easy-footnote-bottom-3-199454' title='Francesco Clementi, \u00ab&amp;#160;Una monarchia repubblicana&amp;nbsp;&amp;#160;? Un bilancio della Presidenza di Giorgio Napolitano&amp;#160;\u00bb, &lt;em&gt;Rivista di politica&lt;\/em&gt;, 4\/2014, p. 5-8&amp;#160;; Vincenzo Lippolis, Giulio M. Salerno, &lt;em&gt;La presidenza pi\u00f9 lunga. I poteri del capo dello Stato e la Costituzione&lt;\/em&gt;, Bologne, Il Mulino, 2016.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les actions de Giorgio Napolitano, qu\u2019une certaine presse italienne et \u00e9trang\u00e8re surnomme \u00ab&#160;le roi Giorgio&#160;\u00bb, suscitent des controverses.<\/p><cite>Marc Lazar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Giorgio Napolitano s\u2019est fortement engag\u00e9 dans la comm\u00e9moration du 150\u00e8me anniversaire de l\u2019unit\u00e9 italienne en 2011. Dans la lign\u00e9e de son pr\u00e9d\u00e9cesseur, Carlo Azeglio Ciampi, il milite en faveur d\u2019une nation italienne unie et fi\u00e8re car fond\u00e9e sur le patriotisme constitutionnel, capable d\u2019int\u00e9grer les millions d\u2019immigr\u00e9s d\u00e9sormais install\u00e9s dans le pays qui vit un hiver d\u00e9mographique et pour lesquels il voudrait instaurer le droit du sol leur facilitant l\u2019acquisition de la citoyennet\u00e9 italienne&nbsp;&#160;; une nation aussi largement ouverte sur l\u2019Europe et non pas repli\u00e9e sur elle. Une Europe \u00e0 laquelle il s\u2019est d\u00e9vou\u00e9 totalement, surtout durant gouvernement Berlusconi qui provoque souvent des inqui\u00e9tudes quant \u00e0 la r\u00e9alit\u00e9 et \u00e0 la consistance de l\u2019engagement de l\u2019Italie dans la construction europ\u00e9enne. Comme l\u2019a \u00e9crit Sergio Romano, journaliste, historien et ex-ambassadeur, Giorgio Napolitano a \u00e9t\u00e9 le garant de l\u2019Italie en Europe. De m\u00eame, il se d\u00e9place dans le monde pour repr\u00e9senter au mieux son pays et intervient dans l\u2019\u00e9laboration et la r\u00e9alisation de la politique \u00e9trang\u00e8re de l\u2019Italie. Lors de sa pr\u00e9sidence, cet homme \u00e2g\u00e9 ne cesse de s\u2019adresser aux jeunes. Ainsi re\u00e7oit-il r\u00e9guli\u00e8rement des diplomates, des haut fonctionnaires, des chercheurs, des professeurs, des chefs d\u2019entreprise&nbsp;de cette cat\u00e9gorie d\u2019\u00e2ge&#160;: il les valorise et les montre en exemple. Il fait de m\u00eame avec des jeunes femmes, nommant en 2013 la biologiste Elena Cattaneo s\u00e9natrice \u00e0 vie alors qu\u2019elle n\u2019a que 50 ans, du jamais vu dans l\u2019histoire de la R\u00e9publique, ou en rendant le 22 d\u00e9cembre 2014 un hommage vibrant et \u00e9mu \u00e0 l\u2019astronaute Samantha Cristoforetti. Le Pr\u00e9sident Napolitano cherche ainsi, de mani\u00e8re symbolique, \u00e0 donner de l\u2019espoir aux nouvelles g\u00e9n\u00e9rations confront\u00e9es aux pesanteurs et aux rigidit\u00e9s de la g\u00e9rontocratie italienne. Le 14 janvier 2015, extr\u00eamement fatigu\u00e9, Giorgio Napolitano pr\u00e9sente sa d\u00e9mission. Il redevient s\u00e9nateur \u00e0 vie. De mani\u00e8re r\u00e9currente, il accepte de r\u00e9pondre \u00e0 des interviews et intervient dans le d\u00e9bat public pour exprimer son point de vue&nbsp;&#160;: c\u2019est ainsi qu\u2019il approuve le projet de changement constitutionnel propos\u00e9 par Matteo Renzi qui sera rejet\u00e9 par r\u00e9f\u00e9rendum en 2016.<\/p>\n\n\n\n<p>Reste maintenant \u00e0 savoir ce que la m\u00e9moire collective des Italiens conservera de Giorgio Napolitano. Rien n\u2019est \u00e9crit d\u2019avance. Cela d\u00e9pend entre autres de la perception qu\u2019en ont actuellement ses compatriotes. Une partie de la gauche appr\u00e9cie la longue vie du communiste Napolitano, tandis qu\u2019une autre composante, critique du PCI, ne l\u2019aime gu\u00e8re, et encore moins du fait de son \u00e9volution r\u00e9formiste. Un r\u00e9formisme auquel ne croit pas la droite anticommuniste et anti antifasciste pour qui il reste \u00e9ternellement un \u00ab&#160;rouge&#160;\u00bb y compris apr\u00e8s son arriv\u00e9e au Quirinal. Comme pr\u00e9sident de la R\u00e9publique, il fut davantage respect\u00e9 car l\u2019institution elle-m\u00eame est respect\u00e9e en tant qu\u2019elle symbolise l\u2019unit\u00e9 du pays. Lui-m\u00eame b\u00e9n\u00e9ficia d\u2019une forte popularit\u00e9 enregistr\u00e9e par les sondages Toutefois, il ne suscita pas un enthousiasme d\u00e9bordant, ce qu\u2019il ne cherchait d\u2019ailleurs pas. Parce qu\u2019il refusait de c\u00e9der \u00e0 la personnalisation et \u00e0 la m\u00e9diatisation de la vie politique, parce qu\u2019il entendait dans chacune de ses interventions en appeler \u00e0 la conscience et \u00e0 la mobilisation civique de ses concitoyens, parce qu\u2019il entendait d\u00e9montrer la complexit\u00e9 des d\u00e9fis que l\u2019Italie, l\u2019Europe et le monde devaient relever, peut-\u00eatre est-il apparu trop intellectuel et exigeant pour une partie de la population. Finalement, c\u2019est sans doute hors d\u2019Italie, parmi les \u00e9lites politiques et cultiv\u00e9es en Europe et dans le monde, que Napolitano jouit d\u2019une excellente r\u00e9putation et d\u2019une image largement positive. En attestent les hommages vibrants qui, \u00e0 l\u2019annonce de son d\u00e9c\u00e8s, ne manquent pas de lui \u00eatre rendus, saluant le grand europ\u00e9en qu\u2019il \u00e9tait devenu. Le 24 septembre 2015, \u00e0 Piacenza, il terminait son discours au Festival du Droit par ces mots&nbsp;&#160;: \u00ab&#160;Il reviendra \u00e0 chacun d\u2019apporter sa contribution en injectant dans la vie de l\u2019Union ce levain de culture et de participation d\u00e9mocratique dont la carence a expos\u00e9 le grand et irrempla\u00e7able projet europ\u00e9en \u00e0 tant de s\u00e9rieux ph\u00e9nom\u00e8nes et risques d\u2019usure&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-199454' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#easy-footnote-bottom-4-199454' title='http:\/\/www.cde.unict.it\/sites\/cde.unict.it\/files\/files\/2015-09-24-Piacenza-Festival-del-Diritto-layout-stampadocx-1.pdf'><sup>4<\/sup><\/a><\/span><\/span>. Alors que lui-m\u00eame a largement donn\u00e9 de sa personne au service de cet id\u00e9al auquel il s\u2019\u00e9tait converti, on ose esp\u00e9rer que son appel soit entendu, en particulier \u00e0 l\u2019occasion des \u00e9lections europ\u00e9ennes de juin 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec Giorgio Napolitano (1925-2023), le long XXe si\u00e8cle vient de s&rsquo;\u00e9teindre \u00e0 Rome.<\/p>\n<p>Fils du fascisme, communiste europ\u00e9en, figure embl\u00e9matique du \u00ab&#160;migliorismo&#160;\u00bb, homme clef des institutions r\u00e9publicaines et promoteur d&rsquo;une interpr\u00e9tation exceptionnelle du r\u00f4le du pr\u00e9sident de la R\u00e9publique&#8230; avec la mort \u00e0 Rome de Giorgio Napolitano, n\u00e9 en 1925 \u00e0 Naples, la r\u00e9publique italienne est confront\u00e9e \u2014 d\u00e9finitivement \u2014 \u00e0 la fin du long XXe si\u00e8cle.<\/p>\n<p>Un portrait sign\u00e9 Marc Lazar.<\/p>\n","protected":false},"author":10,"featured_media":199461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":23,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[3565],"tags":[],"staff":[3605],"editorial_format":[4849],"serie":[],"audience":[],"geo":[543],"class_list":["post-199454","post","type-post","status-publish","format-standard","hentry","category-in-memoriam","staff-marc-lazar","editorial_format-etudes","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":199461,"excerpt":"Avec Giorgio Napolitano (1925-2023), le long XXe si\u00e8cle vient de s'\u00e9teindre \u00e0 Rome.\r\n\r\nFils du fascisme, communiste europ\u00e9en, figure embl\u00e9matique du \u00abmigliorismo\u00bb, homme clef des institutions r\u00e9publicaines et promoteur d'une interpr\u00e9tation exceptionnelle du r\u00f4le du pr\u00e9sident de la R\u00e9publique... avec la mort \u00e0 Rome de Giorgio Napolitano, n\u00e9 en 1925 \u00e0 Naples, la r\u00e9publique italienne est confront\u00e9e \u2014 d\u00e9finitivement \u2014 \u00e0 la fin du long XXe si\u00e8cle.\r\n\r\nUn portrait sign\u00e9 Marc Lazar.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Giorgio Napolitano (1925-2023), le communiste devenu Roi | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giorgio Napolitano (1925-2023), le communiste devenu Roi | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Avec Giorgio Napolitano (1925-2023), le long XXe si\u00e8cle vient de s&#039;\u00e9teindre \u00e0 Rome.  Fils du fascisme, communiste europ\u00e9en, figure embl\u00e9matique du \u00ab&#160;migliorismo&#160;\u00bb, homme clef des institutions r\u00e9publicaines et promoteur d&#039;une interpr\u00e9tation exceptionnelle du r\u00f4le du pr\u00e9sident de la R\u00e9publique... avec la mort \u00e0 Rome de Giorgio Napolitano, n\u00e9 en 1925 \u00e0 Naples, la r\u00e9publique italienne est confront\u00e9e \u2014 d\u00e9finitivement \u2014 \u00e0 la fin du long XXe si\u00e8cle.  Un portrait sign\u00e9 Marc Lazar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-22T18:34:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T22:13:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-napolitano-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-napolitano-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/\",\"name\":\"Giorgio Napolitano (1925-2023), le communiste devenu Roi | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg\",\"datePublished\":\"2023-09-22T18:34:14+00:00\",\"dateModified\":\"2024-06-06T22:13:18+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg\",\"width\":2560,\"height\":1755,\"caption\":\"\u00a9 AP Photo\/Alessandra Tarantino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giorgio Napolitano (1925-2023), le communiste devenu Roi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giorgio Napolitano (1925-2023), le communiste devenu Roi | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/","og_locale":"fr_FR","og_type":"article","og_title":"Giorgio Napolitano (1925-2023), le communiste devenu Roi | Le Grand Continent","og_description":"Avec Giorgio Napolitano (1925-2023), le long XXe si\u00e8cle vient de s'\u00e9teindre \u00e0 Rome.  Fils du fascisme, communiste europ\u00e9en, figure embl\u00e9matique du \u00ab&#160;migliorismo&#160;\u00bb, homme clef des institutions r\u00e9publicaines et promoteur d'une interpr\u00e9tation exceptionnelle du r\u00f4le du pr\u00e9sident de la R\u00e9publique... avec la mort \u00e0 Rome de Giorgio Napolitano, n\u00e9 en 1925 \u00e0 Naples, la r\u00e9publique italienne est confront\u00e9e \u2014 d\u00e9finitivement \u2014 \u00e0 la fin du long XXe si\u00e8cle.  Un portrait sign\u00e9 Marc Lazar.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/","og_site_name":"Le Grand Continent","article_published_time":"2023-09-22T18:34:14+00:00","article_modified_time":"2024-06-06T22:13:18+00:00","og_image":[{"width":2560,"height":1435,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-napolitano-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-napolitano-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/","name":"Giorgio Napolitano (1925-2023), le communiste devenu Roi | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg","datePublished":"2023-09-22T18:34:14+00:00","dateModified":"2024-06-06T22:13:18+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg","width":2560,"height":1755,"caption":"\u00a9 AP Photo\/Alessandra Tarantino"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/22\/mort-de-giorgio-napolitano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Giorgio Napolitano (1925-2023), le communiste devenu Roi"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3565,"name":"In Memoriam","slug":"in-memoriam"}],"lgc_author":{"id":3605,"name":"Marc Lazar","slug":"marc-lazar","description":"Agr\u00e9g\u00e9 d\u2019histoire, Marc Lazar a effectu\u00e9 sept ans d\u2019enseignement dans le secondaire.\r\n\r\nTitulaire d\u2019une th\u00e8se d\u2019histoire de l\u2019EHESS, il a \u00e9t\u00e9 boursier Jean Monnet \u00e0 l\u2019Institut Universitaire Europ\u00e9en comme membre des d\u00e9partements d\u2019histoire et de science politique, d\u00e9tach\u00e9 ensuite au CNRS en science politique au CACSP (Centre d'Analyse Comparative des Syst\u00e8mes Politiques) Universit\u00e9 de Paris I (1987-1989), Ma\u00eetre de conf\u00e9rences en science politique \u00e0 l'Universit\u00e9 de Paris I (1989-1993), Ma\u00eetre de conf\u00e9rences \u00e0 Sciences Po (1990-1999) et Professeur-associ\u00e9 \u00e0 l'Universit\u00e9 de Stanford, Programme Stanford \u00e0 Paris (1994-2005).\r\n\r\nApr\u00e8s son HDR, il a \u00e9t\u00e9 Professeur de sociologie politique (1993-1999) \u00e0 l'Universit\u00e9 de Paris X et Professeur d'histoire et de sociologie politique \u00e0 l'IEP de Paris depuis1999. Il a \u00e9t\u00e9 visiting professor \u00e0 l\u2019Universit\u00e9 Luiss-Guido Carli de Rome (2007-2014).","first_name":"Marc","last_name":"Lazar","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/ID_LAZAR.jpg","width":600,"height":600,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg","width":2560,"height":1755,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap21986160_000011-scaled.jpg","width":2560,"height":1755,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/199454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=199454"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/199454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/199461"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=199454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=199454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=199454"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=199454"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=199454"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=199454"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=199454"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=199454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}