{"id":198776,"date":"2023-09-19T06:30:00","date_gmt":"2023-09-19T04:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=198776"},"modified":"2023-09-19T08:41:11","modified_gmt":"2023-09-19T06:41:11","slug":"a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/","title":{"rendered":"Contre Poutine \u00e0 front renvers\u00e9&#160;: en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire"},"content":{"rendered":"\n<p class=\"intro\">Journaliste ukrainien et d\u00e9fenseur des droits humains, Konstantin Reoutskyi s\u2019est engag\u00e9 volontairement dans les Forces de d\u00e9fense territoriale o\u00f9 il sert en tant qu\u2019officier, sur le front, depuis l\u2019invasion de son pays par la Russie, le 24 f\u00e9vrier 2022. Sa vie avait d\u00e9j\u00e0 \u00e9t\u00e9 boulevers\u00e9e en 2014, \u00e0 la suite de la d\u00e9stabilisation du Donbass par la Russie, quand il a d\u00fb quitter sa ville natale de Louhansk en raison de pers\u00e9cutions politiques.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Install\u00e9 \u00e0 Kyiv, il a fond\u00e9 d\u00e8s 2014 une association humanitaire \u00ab&#160;<a href=\"https:\/\/vostok-sos.org\/en\/\">Vostok SOS<\/a>&#160;\u00bb pour venir en aide aux populations du Donbass victimes de la guerre. Dans les semaines ayant suivi l&rsquo;invasion, cette association a \u00e9vacu\u00e9, dans le plus grand danger, plus de 30 000 personnes, dont environ 3 000 souffrant de d\u00e9mence et de troubles mentaux, allant les chercher jusqu&rsquo;au dernier kilom\u00e8tre et leur trouvant ensuite un lieu d\u2019h\u00e9bergement.<\/p>\n\n\n\n<p class=\"intro\">Dans ce texte, il revient sur les origines de la guerre en Ukraine, consid\u00e9rant qu\u2019elle n\u2019est pas seulement le r\u00e9sultat d\u2019une d\u00e9rive autoritaire en Russie, mais bien l\u2019aboutissement d\u2019un mod\u00e8le de construction imp\u00e9riale. Il s\u2019\u00e9rige contre l\u2019id\u00e9e, r\u00e9pandue dans les pays occidentaux, selon laquelle il serait possible de d\u00e9mocratiser la Russie dans ses fronti\u00e8res actuelles et appelle \u00e0 ne pas avoir peur d\u2019une d\u00e9sint\u00e9gration de la Russie.\u00a0<\/p>\n\n\n\n<p>Cet essai se veut un avertissement pour ceux qui croient encore qu\u2019une Russie d\u00e9mocratique peut exister et qu\u2019elle le peut dans ses fronti\u00e8res \u00ab&#160;imp\u00e9riales&#160;\u00bb. La Russie n\u2019a-t-elle pas pourtant constamment d\u00e9menti cette th\u00e8se au fil des si\u00e8cles&nbsp;&#160;?<\/p>\n\n\n\n<p>La d\u00e9mocratie constitue un poison mortel pour les empires du fait de son attachement \u00e0 l\u2019id\u00e9e et \u00e0 la pratique de la justice. Or la Russie est, dans son essence m\u00eame, un empire fond\u00e9 sur le mensonge et sur la coercition. Ce r\u00e9gime ne pourra pas se d\u00e9mocratiser tant qu\u2019il sera un empire et donc qu\u2019il continuera d\u2019exister dans ses fronti\u00e8res pr\u00e9sentes.<\/p>\n\n\n\n<p>Ceux qui appellent \u00e0 pr\u00e9server \u00e0 tout prix la Russie \u00ab&#160;\u00e9ternelle&#160;\u00bb proposent en r\u00e9alit\u00e9 d\u2019ent\u00e9riner les injustices et les violences sur lesquelles elle s\u2019est construite et par l\u00e0 m\u00eame \u00e0 maintenir un empire qui d\u00e9clare la guerre \u00e0 la civilisation europ\u00e9enne \u00e0 chaque fois qu&rsquo;il en a la force. \u00c0 quoi bon persister \u00e0 vouloir sauver celui qui veut vous tuer&#160;?<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La Russie est, dans son essence m\u00eame, un empire fond\u00e9 sur le mensonge et sur la coercition. \u00c0 quoi bon persister \u00e0 vouloir sauver celui qui veut vous tuer&#160;?<\/p><cite>Konstantin Reutskyi<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>*<\/strong><\/p>\n\n\n\n<p>L&rsquo;exp\u00e9rience des ann\u00e9es 1990 a prouv\u00e9 qu&rsquo;une d\u00e9mocratisation prudente ne permettait pas de faire dispara\u00eetre les inclinations imp\u00e9riales de ce pays. Les pays occidentaux ont p\u00e9ch\u00e9 par exc\u00e8s de na\u00efvet\u00e9 en pensant que l\u2019agressivit\u00e9 s\u2019effacerait avec la d\u00e9mocratisation. Aujourd\u2019hui la d\u00e9mocratie est \u00e9cras\u00e9e et l\u2019imp\u00e9rialisme de retour. De nouveau, le monde est au bord du gouffre.<\/p>\n\n\n\n<p>On ne force pas un loup \u00e0 devenir v\u00e9g\u00e9tarien. Ainsi il est inutile de se bercer d\u2019illusions concernant l\u2019av\u00e8nement d\u2019une Russie d\u00e9mocratique dans ses fronti\u00e8res actuelles. L&rsquo;injustice est au fondement de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/01\/24\/limpossible-mission-imperiale-de-poutine\/\">l&rsquo;id\u00e9ologie imp\u00e9riale russe<\/a> et de sa pratique politique. De longue date, la classe dirigeante russe consid\u00e8re l&rsquo;honn\u00eatet\u00e9 comme une faiblesse et la sournoiserie comme une vertu.&nbsp;<\/p>\n\n\n\n<p>Au cours des cinq derniers si\u00e8cles, la Russie n\u2019a eu de cesse de mener une politique d\u2019expansion aux d\u00e9pens de ses voisins. Ses dirigeants nient le caract\u00e8re sanglant de ces conqu\u00eates, laissant croire \u00e0 une assimilation volontaire. Toutefois, les faits historiques parlent d\u2019eux-m\u00eames.&nbsp;<\/p>\n\n\n\n<p>Ces appropriations territoriales ont \u00e9t\u00e9 r\u00e9alis\u00e9es non pas seulement par la force, mais \u00e9galement par la \u00ab&#160;ruse&#160;\u00bb. Les autorit\u00e9s concluaient d\u2019abord des accords de protectorat favorables aux nouveaux \u00ab&#160;alli\u00e9s&#160;\u00bb avant de les violer brutalement et de les retourner en leur faveur. Les \u00ab&#160;alli\u00e9s&#160;\u00bb d\u2019hier devenaient soudain sujets et propri\u00e9t\u00e9 de l&#8217;empire&nbsp;&#160;; leur soci\u00e9t\u00e9 se voyait expurg\u00e9e de ses opposants et pill\u00e9e de ses ressources.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>On ne force pas un loup \u00e0 devenir v\u00e9g\u00e9tarien. Au cours des cinq derniers si\u00e8cles, la Russie n\u2019a eu de cesse de mener une politique d\u2019expansion aux d\u00e9pens de ses voisins.<\/p><cite>Konstantin Reutskyi<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La Moscovie a initi\u00e9 ce mouvement d\u2019expansion au XVIe si\u00e8cle aux d\u00e9pens du khanat de Kazan et d\u2019une partie des territoires de la Sib\u00e9rie&nbsp;occidentale, puis \u00e9tendu, au si\u00e8cle suivant, ses conqu\u00eates jusqu\u2019en Extr\u00eame Orient et, de l\u2019autre c\u00f4t\u00e9, jusqu\u2019\u00e0 la rive gauche du Dniepr en Ukraine. Au XVIII<sup>e<\/sup> si\u00e8cle, l\u2019empire a absorb\u00e9 le khanat de Crim\u00e9e, ainsi qu\u2019une partie des territoires qui forment aujourd\u2019hui le Kazakhstan, le B\u00e9larus et surtout le sud, le centre et une partie de l\u2019ouest de l\u2019Ukraine. Au XIX<sup>e<\/sup> si\u00e8cle, sont tomb\u00e9s dans son escarcelle&nbsp;le Caucase du nord et du sud, ainsi qu\u2019une grande partie de l\u2019Asie centrale, la Bessarabie, la Finlande et une partie de la Pologne. Enfin, au XX<sup>e<\/sup> si\u00e8cle est venu le tour des territoires restants de l&rsquo;Ukraine, du B\u00e9larus et de la Prusse orientale. N\u2019oublions pas non plus qu\u2019au sortir de la Seconde guerre mondiale, l\u2019empire sovi\u00e9tique a instaur\u00e9 des r\u00e9gimes marionnettes dans six pays est-europ\u00e9ens.<\/p>\n\n\n\n<p>Aujourd\u2019hui, les dirigeants russes se plaisent \u00e0 faire pression sur la conscience des Europ\u00e9ens en leur rappelant les pratiques coloniales de leur pays en Afrique, en Asie et en Am\u00e9rique du Sud. N\u2019ayant pas la conscience en paix, les Europ\u00e9ens oublient que l\u2019histoire de leurs pays ne s\u2019est pas faite en une nuit et <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/26\/le-passe-impense-pour-un-recit-critique-europeen\/\">que les valeurs pr\u00f4n\u00e9es aujourd\u2019hui ne sont pas celles d\u2019hier<\/a>.<\/p>\n\n\n\n<p>Pour la Russie, au contraire, la conqu\u00eate par la force et par la ruse reste d\u2019actualit\u00e9 et <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/08\/9-mai-la-guerre-infinie-de-poutine\/\">constitue m\u00eame une vision d&rsquo;avenir<\/a>. Car, en r\u00e9alit\u00e9, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/10\/pour-poutine-cette-guerre-na-rien-a-voir-avec-lukraine-une-conversation-avec-grigori-yudin\/\">\u00e0 l&rsquo;int\u00e9rieur du pays tout va mal<\/a>. La Russie n&rsquo;appartient pas aux citoyens russes. Il n&rsquo;y a pas d&rsquo;\u00e9lections libres. Les droits et les libert\u00e9s sont abolis. La critique est impossible. Le pouvoir est usurp\u00e9 et ne sert pas les int\u00e9r\u00eats du peuple. Les ressources du pays sont confisqu\u00e9es au profit d\u2019une petite oligarchie.&nbsp;<\/p>\n\n\n\n<p>Pourquoi les Russes endurent-ils l&rsquo;humiliation permanente des \u00ab&#160;boyards&#160;\u00bb et consentent-ils \u00e0 participer aux crimes de l&#8217;empire&nbsp;&#160;? Cet assentiment est certainement li\u00e9 au contexte structurel destin\u00e9 \u00e0 contr\u00f4ler la soci\u00e9t\u00e9 dans ce vaste ensemble h\u00e9t\u00e9rog\u00e8ne. Seuls la force brute et le mensonge \u00e9hont\u00e9 permettent de restreindre les forces centrip\u00e8tes existant \u00e0 l\u2019\u00e9tat latent et de pallier les contradictions culturelles, religieuses et \u00e9conomiques des territoires de l&#8217;empire.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>D\u00e8s lors, la question est de savoir s\u2019il faut encourager ou pr\u00e9venir la d\u00e9sint\u00e9gration de la Russie. Emp\u00eacher la d\u00e9sint\u00e9gration de la Russie signifie cautionner l&rsquo;injustice et les mensonges sur lesquels elle s\u2019est construite. La Russie imp\u00e9riale est l\u2019antith\u00e8se de la d\u00e9mocratie car sa culture politique pr\u00f4ne l\u2019arbitraire, la loi du plus fort, la soumission du faible, qu\u2019elle pr\u00f4ne \u00ab&#160;l\u2019orthodoxie, l\u2019autocratie, le peuple&#160;\u00bb comme \u00e0 l\u2019\u00e9poque tsariste, \u00ab&#160;l\u2019avenir radieux et la construction du communisme&#160;\u00bb comme \u00e0 l\u2019\u00e9poque sovi\u00e9tique ou encore \u00ab&#160;le monde russe&#160;\u00bb comme \u00e0 l\u2019\u00e9poque poutinienne.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Emp\u00eacher la d\u00e9sint\u00e9gration de la Russie signifie cautionner l&rsquo;injustice et les mensonges sur lesquels elle s\u2019est construite.<\/p><cite>Konstantin Reutskyi<\/cite><\/blockquote><\/figure>\n\n\n\n<p>\u00c0 chaque fois que ce consensus social, proprement sadomasochiste, a vacill\u00e9, le territoire russe a r\u00e9tr\u00e9ci, comme apr\u00e8s la r\u00e9volution de 1917 et \u00e0 la suite de l\u2019effondrement de l\u2019Union sovi\u00e9tique en 1991. Au contraire, d\u00e8s que le pouvoir imp\u00e9rial parvient \u00e0 renforcer sa domination et \u00e0 imposer ce consensus, la Russie s\u2019agrandit aux d\u00e9pens des pays voisins. Il justifie cette injustice au nom de buts sup\u00e9rieurs, tout en vouant ceux qui osent exprimer un d\u00e9saccord \u00e0 la torture, \u00e0 la prison, \u00e0 la d\u00e9portation ou \u00e0 l\u2019ex\u00e9cution.<\/p>\n\n\n\n<p>Le consentement \u00e0 l&rsquo;injustice et l&rsquo;acceptation de l&rsquo;oppression forment l\u2019ossature \u2013 appel\u00e9e \u00ab&#160;skrepa&#160;\u00bb en russe \u2013 de l&#8217;empire. Le gouvernement russe investit d&rsquo;\u00e9normes ressources pour promouvoir et r\u00e9pandre cette culture de la soumission dans la soci\u00e9t\u00e9.&nbsp;<\/p>\n\n\n\n<p>Prenons l\u2019exemple du Tatarstan ou de toute autre r\u00e9gion qui dispose de ses propres ressources. Que peut lui apporter la Russie&nbsp;&#160;? Une langue et une culture&#160;? Ils ont la leur&nbsp;&#160;! La grandeur&#160;? De quelle grandeur peut-il s\u2019agir quand on conna\u00eet l\u2019\u00e9tat de d\u00e9labrement et de pauvret\u00e9 des r\u00e9gions \u00e9loign\u00e9es. La s\u00e9curit\u00e9&#160;? Ne vous leurrez pas&#160;! De quelle s\u00e9curit\u00e9 parlons-nous si \u00e0 la t\u00eate du pays se trouve un tyran assoiff\u00e9 de pouvoir qui pousse le monde vers un conflit nucl\u00e9aire.<\/p>\n\n\n\n<p>Le pouvoir russe se comporte comme un voyou qui fait les poches de ses voisins et de ses territoires, ne leur laissant qu&rsquo;un peu de monnaie \u00ab&#160;pour la tourte aux choux&#160;\u00bb ou un quignon de pain dirait-on en fran\u00e7ais. Craignant les foudres de la m\u00e9tropole, les provinces russes ne s\u2019\u00e9mancipent pas. En v\u00e9rit\u00e9, elles n&rsquo;ont aucune autre raison de rester sujets de Moscou que la simple habitude de supporter son joug.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le consentement \u00e0 l&rsquo;injustice et l&rsquo;acceptation de l&rsquo;oppression forment l\u2019ossature de l&#8217;empire. Le gouvernement russe investit d&rsquo;\u00e9normes ressources pour promouvoir et r\u00e9pandre cette culture de la soumission dans la soci\u00e9t\u00e9.\u00a0<\/p><cite>Konstantin Reutskyi<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>Bien s\u00fbr, la d\u00e9mocratie id\u00e9ale n\u2019existe pas. La fl\u00e9trissure de l&rsquo;injustice p\u00e9n\u00e8tre m\u00eame dans des d\u00e9mocraties solides. N\u00e9anmoins, l&rsquo;injustice y est per\u00e7ue comme un mal \u00e0 vaincre et non comme un pilier de l&rsquo;\u00c9tat. La tol\u00e9rance \u00e0 l\u2019injustice se voit dissoute par la d\u00e9mocratie&nbsp;&#160;: non seulement elle permet l\u2019\u00e9closion d\u2019espaces publics de r\u00e9flexion, mais elle soul\u00e8ve des questions auxquelles le pouvoir imp\u00e9rial ne peut apporter de r\u00e9ponse.<\/p>\n\n\n\n<p>La d\u00e9mocratie tuerait l\u2019empire en Russie, ram\u00e8nerait le pays \u00e0 ses fronti\u00e8res de 1478, ann\u00e9e o\u00f9 la principaut\u00e9 de Novgorod a \u00e9t\u00e9 soumise par la Moscovie et lib\u00e9rerait ainsi tous les peuples asservis depuis. Ce serait un immense soulagement pour les voisins de la Russie, pour le monde entier et pour les Russes eux-m\u00eames.<\/p>\n\n\n\n<p>Les pays occidentaux doivent reconna\u00eetre que toute tentative de maintenir l&rsquo;int\u00e9grit\u00e9 de la Russie dans ses fronti\u00e8res actuelles contribue \u00e0 perp\u00e9tuer la maladie de l&#8217;empire et ses \u00ab&#160;effets secondaires&#160;\u00bb que sont la m\u00e9galomanie, l\u2019expansionnisme, le militarisme, l\u2019oppression et le pillage des peuples conquis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis l\u2019Ukraine, une fatalit\u00e9 s\u2019installe contre le projet imp\u00e9rialiste de Poutine. Selon Konstantin Reutskyi, qui se bat au quotidien contre les soldats de l\u2019arm\u00e9e russe, il sera impossible de ne pas d\u00e9manteler la Russie. Pour comprendre comment le r\u00e9cit historique imp\u00e9rial russe est combattu avec la m\u00eame f\u00e9rocit\u00e9, la m\u00eame violence, qu\u2019une lutte au corps \u00e0 corps dans les tranch\u00e9es, nous introduisons et traduisons ce texte ukrainien.<\/p>\n","protected":false},"author":10,"featured_media":198788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[3116],"tags":[],"staff":[3601,3602],"editorial_format":[4943],"serie":[],"audience":[],"geo":[1917],"class_list":["post-198776","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","staff-celine-marange","staff-ioulia-shukan","editorial_format-discours","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":198788,"excerpt":"Depuis l\u2019Ukraine, une fatalit\u00e9 s\u2019installe contre le projet imp\u00e9rialiste de Poutine. Selon Konstantin Reutskyi, qui se bat au quotidien contre les soldats de l\u2019arm\u00e9e russe, il sera impossible de ne pas d\u00e9manteler la Russie. Pour comprendre comment le r\u00e9cit historique imp\u00e9rial russe est combattu avec la m\u00eame f\u00e9rocit\u00e9, la m\u00eame violence, qu\u2019une lutte au corps \u00e0 corps dans les tranch\u00e9es, nous introduisons et traduisons ce texte ukrainien.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contre Poutine \u00e0 front renvers\u00e9 : en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contre Poutine \u00e0 front renvers\u00e9 : en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Depuis l\u2019Ukraine, une fatalit\u00e9 s\u2019installe contre le projet imp\u00e9rialiste de Poutine. Selon Konstantin Reutskyi, qui se bat au quotidien contre les soldats de l\u2019arm\u00e9e russe, il sera impossible de ne pas d\u00e9manteler la Russie. Pour comprendre comment le r\u00e9cit historique imp\u00e9rial russe est combattu avec la m\u00eame f\u00e9rocit\u00e9, la m\u00eame violence, qu\u2019une lutte au corps \u00e0 corps dans les tranch\u00e9es, nous introduisons et traduisons ce texte ukrainien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-19T04:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-19T06:41:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-put-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-put-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/\",\"name\":\"Contre Poutine \u00e0 front renvers\u00e9 : en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg\",\"datePublished\":\"2023-09-19T04:30:00+00:00\",\"dateModified\":\"2023-09-19T06:41:11+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Des fl\u00e9chettes sont coll\u00e9es sur une cible en papier \u00e0 l'effigie du pr\u00e9sident russe Vladimir Poutine dans une attraction populaire sur la plage d'Odessa, en Ukraine, le dimanche 23 juillet 2023. \u00a9 AP Photo\/Jae C. Hong, File\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contre Poutine \u00e0 front renvers\u00e9&#160;: en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contre Poutine \u00e0 front renvers\u00e9 : en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Contre Poutine \u00e0 front renvers\u00e9 : en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire | Le Grand Continent","og_description":"Depuis l\u2019Ukraine, une fatalit\u00e9 s\u2019installe contre le projet imp\u00e9rialiste de Poutine. Selon Konstantin Reutskyi, qui se bat au quotidien contre les soldats de l\u2019arm\u00e9e russe, il sera impossible de ne pas d\u00e9manteler la Russie. Pour comprendre comment le r\u00e9cit historique imp\u00e9rial russe est combattu avec la m\u00eame f\u00e9rocit\u00e9, la m\u00eame violence, qu\u2019une lutte au corps \u00e0 corps dans les tranch\u00e9es, nous introduisons et traduisons ce texte ukrainien.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/","og_site_name":"Le Grand Continent","article_published_time":"2023-09-19T04:30:00+00:00","article_modified_time":"2023-09-19T06:41:11+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-put-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/gc-put-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/","name":"Contre Poutine \u00e0 front renvers\u00e9 : en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg","datePublished":"2023-09-19T04:30:00+00:00","dateModified":"2023-09-19T06:41:11+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg","width":2560,"height":1707,"caption":"Des fl\u00e9chettes sont coll\u00e9es sur une cible en papier \u00e0 l'effigie du pr\u00e9sident russe Vladimir Poutine dans une attraction populaire sur la plage d'Odessa, en Ukraine, le dimanche 23 juillet 2023. \u00a9 AP Photo\/Jae C. Hong, File"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/09\/19\/a-front-renverse-contre-poutine-en-ukraine-dans-les-tranchees-de-la-guerre-avec-les-armes-de-lhistoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Contre Poutine \u00e0 front renvers\u00e9&#160;: en Ukraine dans les tranch\u00e9es de la guerre avec les armes de l\u2019histoire"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":{"id":3601,"name":"C\u00e9line Marang\u00e9","slug":"celine-marange","description":"C\u00e9line Marang\u00e9 est chercheuse sur la Russie, l\u2019Ukraine et le Belarus \u00e0 l\u2019Institut de recherche strat\u00e9gique de l\u2019\u00c9cole militaire et membre associ\u00e9e du Centre de recherche en histoire des Slaves (Universit\u00e9 Paris 1 Panth\u00e9on-Sorbonne). Ses travaux portent sur la politique \u00e9trang\u00e8re et de d\u00e9fense, les \u00e9lites politiques et militaires russes, les strat\u00e9gies russes d\u2019influence et de dissuasion, ainsi que sur les conflits et les enjeux de s\u00e9curit\u00e9 dans l\u2019espace post-sovi\u00e9tique.","first_name":"C\u00e9line","last_name":"Marang\u00e9","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/cr150200-q90-acc154.png","width":148,"height":143,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/SIPA_ap22805306_000008-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/198776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=198776"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/198776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/198788"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=198776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=198776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=198776"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=198776"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=198776"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=198776"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=198776"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=198776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}