{"id":193598,"date":"2023-08-10T17:05:09","date_gmt":"2023-08-10T15:05:09","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=193598"},"modified":"2023-08-13T01:39:38","modified_gmt":"2023-08-12T23:39:38","slug":"los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/","title":{"rendered":"\u00ab&#160;Los Angeles a ce pouvoir de cr\u00e9er des images&#160;\u00bb, une conversation avec Alain Mabanckou\u00a0"},"content":{"rendered":"\n<p><em>\u00c9crivain&nbsp;et&nbsp;enseignant&nbsp;franco-congolais, Alain Mabanckou a remport\u00e9 en 2006 le prix&nbsp;Renaudot&nbsp;pour son&nbsp;roman&nbsp;<\/em>M\u00e9moires de porc-\u00e9pic<em>. Il a \u00e9galement \u00e9t\u00e9 r\u00e9compens\u00e9 en 2012 par l&rsquo;Acad\u00e9mie fran\u00e7aise&nbsp;(Grand prix de litt\u00e9rature Henri-Gal). Il enseigne la litt\u00e9rature francophone \u00e0 l&rsquo;Universit\u00e9 de Californie-Los Angeles (UCLA), ville dont il a choisi de nous parler pour son entretien Grand Tour. <a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/arts\/grand-tour\/\"><i>Tout au long du mois d&rsquo;ao\u00fbt, vous pouvez retrouver ici les autres \u00e9pisodes de notre iconique s\u00e9rie d\u2019\u00e9t\u00e9 \u00ab&#160;&nbsp;Grand Tour&nbsp;&#160;\u00bb<\/i><\/a><i>.<\/i><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dans les premi\u00e8res lignes de <em>Rumeurs d\u2019Am\u00e9riques<\/em>, vous \u00e9crivez&#160;: \u00ab&#160;J\u2019ai attendu une quinzaine d\u2019ann\u00e9es pour enfin poser le regard ailleurs que sur mon pays d\u2019origine, le Congo, ou sur ma terre d\u2019adoption, la France&#160;\u00bb. Pourquoi ce regard se pose sur l&rsquo;Am\u00e9rique en g\u00e9n\u00e9ral, et en particulier sur Los Angeles&#160;?<\/strong><\/h3>\n\n\n\n<p>Lorsqu&rsquo;on arrive dans un espace, dans un territoire, il faut dans un premier temps que l&rsquo;exp\u00e9rience, les souvenirs, les actes de la vie quotidienne, puissent s&rsquo;enraciner pour commencer \u00e0 cr\u00e9er en vous le sentiment m\u00eame de l&rsquo;absence lorsque vous vous en \u00e9loignez.<\/p>\n\n\n\n<p>Pour que je puisse \u00e9crire sur un territoire, il est fondamental que la notion d\u2019absence r\u00e9sonne en moi. J\u2019ai besoin de sentir un vide. L\u2019\u00e9criture est pour moi un moyen de combler ce vide. Si j&rsquo;\u00e9cris beaucoup, par exemple, sur la ville de Pointe-Noire au Congo-Brazzaville, c&rsquo;est parce que je me suis retrouv\u00e9 en France&#160;; d\u00e8s que je suis all\u00e9 aux \u00c9tats-Unis, j&rsquo;ai senti une double nostalgie&#160;: celle du Congo-Brazzaville et celle de la France.<\/p>\n\n\n\n<p>D\u00e9sormais, puisque je vis depuis maintes ann\u00e9es aux \u00c9tats-Unis, chaque fois que je viens en France, j&rsquo;ai l&rsquo;impression qu\u2019il y a l&rsquo;appel du lieu de r\u00e9sidence am\u00e9ricain qui est l\u00e0, lui aussi. Au fur et \u00e0 mesure, c&rsquo;est ce sentiment-l\u00e0 qui a commenc\u00e9 \u00e0 cr\u00e9er en moi le besoin d&rsquo;\u00e9crire sur mon exp\u00e9rience en Am\u00e9rique. Beaucoup d\u2019\u00e9diteurs me disaient que je devais \u00e9crire le \u00ab&#160;grand roman am\u00e9ricain&#160;\u00bb de la d\u00e9cennie, pour \u00e9pater le public. Or, on ne peut \u00e9crire que sur ce qu\u2019on ma\u00eetrise le plus. Je pense que c&rsquo;est le temps qui a fini par m&rsquo;orienter vers l&rsquo;Am\u00e9rique.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Pour que je puisse \u00e9crire sur un territoire, il est fondamental que la notion d\u2019absence r\u00e9sonne en moi.<\/p><cite>Alain Mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous dites que vous ne voulez pas brusquer les choses, mais au contraire attendre que les choses viennent \u00e0 vous. Vous dites que les choses \u201cse raccordent\u201d \u00e0 votre univers de cr\u00e9ation. Qu\u2019entendez-vous par l\u2019utilisation de ce verbe&#160;? Y a-t-il des \u00e9l\u00e9ments qui doivent s\u2019adapter \u00e0 votre univers de cr\u00e9ation ou \u00e0 l\u2019inverse, est-ce votre univers de cr\u00e9ation qui cherche \u00e0 s\u2019influencer de cet autre espace que vous d\u00e9couvrez&#160;?<\/strong><\/h3>\n\n\n\n<p>Le raccordement se fait presque de mani\u00e8re imperceptible. On ne sent pas que quelque chose est en train de se passer. On a le bonheur de se dire&#160;: je peux \u00eatre dans ma chambre aux \u00c9tats-Unis par exemple et ne pas \u00e9crire sur ce qui m&rsquo;entoure, mais sur ce qui est loin, de l&rsquo;autre c\u00f4t\u00e9. Le raccordement finit par se faire lorsqu\u2019on ressent en soi l&rsquo;appel de ce qui est autour. Plus on s\u2019installe quelque part, plus on sent que beaucoup d&rsquo;\u00e9l\u00e9ments vont se pr\u00e9senter et dire qu&rsquo;ils font partie de votre univers.<\/p>\n\n\n\n<p>Je pense que ce qui m\u2019entoure est venu vers moi. J&rsquo;ai r\u00e9agi en voulant en t\u00e9moigner. Le raccordement, c&rsquo;est en quelque sorte la recherche perp\u00e9tuelle que je fais entre ce que je suis, d&rsquo;o\u00f9 je viens et l&rsquo;endroit o\u00f9 je vis. Ce trio permet d&rsquo;avoir une sorte de danse harmonieuse.<\/p>\n\n\n\n<p>Au d\u00e9part, l\u2019Am\u00e9rique \u00e9tait \u00e9loign\u00e9e de moi et n\u2019avait aucune importance. Je pensais peut-\u00eatre ne jamais \u00e9crire sur l\u2019Am\u00e9rique. Je me disais que ce n\u2019\u00e9tait pas ma culture, qui est fondamentalement congolaise-fran\u00e7aise.<\/p>\n\n\n\n<p>J\u2019ai eu tort. En grattant un tout petit peu, on commence \u00e0 ressentir la diversit\u00e9 de cet espace et \u00e0 se dire que l\u2019on pourrait trouver la France et le Congo \u00e0 l\u2019int\u00e9rieur des \u00c9tats-Unis. C&rsquo;est une sorte de trinit\u00e9 entre la naissance au Congo, l&rsquo;adoption de la France et la profession aux \u00c9tats-Unis. Comment vais-je faire pour raccorder ces trois points&#160;? Ils forment d\u2019une certaine mani\u00e8re les fameuses trois pierres qui servent \u00e0 tenir ensemble la marmite et le feu qui la chauffe. Voil\u00e0, le raccordement, c&rsquo;est \u00e7a&#160;: comment une trinit\u00e9 en vient \u00e0 soutenir la marmite de l&rsquo;imaginaire&#160;?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous avez \u00e9crit <em>L&rsquo;Europe depuis l&rsquo;Afrique<\/em> et vous avez largement travaill\u00e9 sur le d\u00e9centrement du regard et des concepts europ\u00e9ens et fran\u00e7ais vu depuis l&rsquo;Afrique, depuis d&rsquo;anciens pays colonis\u00e9s. Puisque maintenant vous ajoutez cette troisi\u00e8me pierre&#160;: \u00e0 quoi ressemble l&rsquo;Europe depuis Los Angeles et \u00e0 quoi ressemble l&rsquo;Afrique depuis Los Angeles&#160;?<\/strong><\/h3>\n\n\n\n<p>L&rsquo;Europe reste un espace d&rsquo;attraction et un espace r\u00eav\u00e9 des Am\u00e9ricains. L\u2019Europe reste pour les Am\u00e9ricains l&rsquo;espace de la culture, l&rsquo;espace de la r\u00e9clamation des droits individuels et de la libert\u00e9 d&rsquo;expression. \u00c7a reste l&rsquo;espace de la pens\u00e9e. Parce que les Am\u00e9ricains reconnaissent que les grands penseurs qui les influencent (Bourdieu, Derrida\u2026) viennent d\u2019Europe. La France a encore aujourd&rsquo;hui ce prestige intellectuel, le prestige du go\u00fbt, le prestige culinaire et enfin m\u00eame le prestige de la mode. Tous ces \u00e9l\u00e9ments sont r\u00e9unis pour que les Am\u00e9ricains, souvent, pensent l&rsquo;Europe capitaliste \u2013 et donc plut\u00f4t l\u2019Europe de l\u2019Ouest \u2013 comme le lieu de l&rsquo;expression la plus raffin\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L\u2019Europe reste pour les Am\u00e9ricains l&rsquo;espace de la culture, l&rsquo;espace de la r\u00e9clamation des droits individuels et de la libert\u00e9 d&rsquo;expression.&nbsp;<\/p><cite>alain mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<p>\u00c0 quoi ressemble l\u2019Afrique depuis Los Angeles&#160;? La r\u00e9ponse est mitig\u00e9e. Les m\u00e9dias se sont souvent concentr\u00e9s sur la face sinistre du continent africain. On montre de l&rsquo;Afrique que ce qui va mal. Par cons\u00e9quent, l&rsquo;Afrique est encore per\u00e7ue comme un espace \u00e0 lib\u00e9rer, un espace qui n&rsquo;a pas encore atteint la d\u00e9mocratie. Un espace qui aurait gard\u00e9 le c\u00f4t\u00e9 barbare, le c\u00f4t\u00e9 naturel des choses. Par cons\u00e9quent, l\u2019Afrique reste un endroit d&rsquo;excursions \u2014 il y a toujours des Am\u00e9ricains qui r\u00eavent de voir des \u00e9l\u00e9phants, des z\u00e8bres, <em>etc<\/em>.<\/p>\n\n\n\n<p>Mais l&rsquo;Afrique a aussi, pour beaucoup d\u2019Am\u00e9ricains, des accents de terre-m\u00e8re. Les Afro-am\u00e9ricains continuent \u00e0 penser que leur destin serait de retourner un jour \u00e0 la terre de leurs anc\u00eatres. De ce fait, malheureusement, il y a aupr\u00e8s des noirs am\u00e9ricains une certaine mythification du continent africain, qui est en d\u00e9saccord avec la r\u00e9alit\u00e9 et les trag\u00e9dies que vivent les populations au quotidien.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Y a-t-il des lectures qui vous ont fait d\u00e9couvrir la Californie&#160;? Pouvez-vous nous guider dans vos lectures californienne et dans votre imaginaire de la ville de Los Angeles&#160;? Quelle est votre biblioth\u00e8que imaginaire de cet endroit&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>J\u2019aime beaucoup les livres de Charles Bukowski. N\u00e9 \u00e0 Los Angeles, il a un c\u00f4t\u00e9 un peu carnavalesque et dangereux m\u00eame. J\u2019aime beaucoup aussi les livres de James Ellroy, que j\u2019ai rencontr\u00e9s l\u00e0-bas.<\/p>\n\n\n\n<p>Mais mon go\u00fbt pour la litt\u00e9rature am\u00e9ricaine d\u00e9passe largement Los Angeles, parce que les grands auteurs que j\u2019adule, comme James Baldwin ou John Steinbeck, ne viennent pas forc\u00e9ment de l\u00e0\u2026 J\u2019ai aussi lu les classiques am\u00e9ricains \u2013 Mark Twain, Hemingway \u2013, des ouvrages plus contemporains \u2013 Bret Easton Ellis \u2013, mais aussi des auteurs venus de l\u2019\u00e9tranger, comme la Nig\u00e9riane Chimamanda Ngozi Adichie, c\u00e9l\u00e8bre en particulier pour son <em>Americanah<\/em>,<em> <\/em>ou comme Helon Habila. Il y a une grande litt\u00e9rature africaine aux \u00c9tats-Unis, en particulier en provenance du Nig\u00e9ria.&nbsp;<\/p>\n\n\n\n<p>\u00c9videmment, les anglophones d\u00e9tiennent les cl\u00e9s de la litt\u00e9rature africaine aux \u00c9tats-Unis. Je regrette souvent que nous ne connaissions pas le m\u00eame bouillonnement dans la litt\u00e9rature francophone aux \u00c9tats-Unis. Tandis que les autres \u00e9crivent en anglais, nous devons passer par le biais de la traduction, ce qui complique aussi la promotion des livres.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c0 propos de classiques, vous \u00e9crivez que vous tr\u00e8s longtemps pens\u00e9, apr\u00e8s l\u2019avoir d\u00e9couvert jeune, que William Faulkner \u00e9tait un \u00e9crivain noir.&nbsp;<\/strong><\/h3>\n\n\n\n<p>Absolument, oui&#160;! Quand je suis arriv\u00e9 dans le Michigan, \u00e0 Ann Arbor, je n\u2019avais encore jamais vu une image de Faulkner. Ses pages sur le sud et l\u2019orage \u00e9taient extraordinaires\u2026 Quand au d\u00e9but des ann\u00e9es 2000, la librairie Salman c\u00e9l\u00e9brait l\u2019anniversaire de Faulkner, je vis un blanc. Je me suis exclam\u00e9&#160;: \u00ab&#160;Le gars est blanc&#160;?&#160;!&#160;\u00bb&nbsp; Avant cette date, tout au long de ma jeunesse, je l&rsquo;avais lu comme un \u00e9crivain noir. La construction dramatique, l\u2019invention de tous ces lieux dans le sud des \u00c9tats-Unis, le c\u00f4t\u00e9 parfois sombre et presque surr\u00e9aliste, voire tragique\u2026 Je me disais qu\u2019il ne pouvait qu\u2019\u00eatre noir. Comme quoi la couleur qu\u2019on pr\u00eate \u00e0 une \u00e9criture \u2013 et \u00e0 un \u00e9crivain \u2013 d\u00e9pend de l\u2019id\u00e9e qu&rsquo;on se fait de ce qu&rsquo;on est en train de lire. Ce jour-l\u00e0, j\u2019ai compris l&rsquo;universalit\u00e9 de Faulkner. Un enfant africain, un paysan sud-am\u00e9ricain ou un Indien de la caste des Intouchables peuvent s\u2019identifier aux r\u00e9cits de Faulkner.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pourriez-vous nous parler d\u2019un lieu qui vous est particuli\u00e8rement cher \u00e0 Los Angeles&#160;?<\/strong><\/h3>\n\n\n\n<p>Je pourrais mentionner le MacArthur Park, au c\u0153ur de Los Angeles, entre Downtown et Koreatown, dans une partie o\u00f9 la ville est implant\u00e9e depuis longtemps. Dans ce parc, toutes les populations se m\u00e9langent. On voit des Latinos jouer au football \u2013&nbsp;europ\u00e9en \u2013, des gens qui prom\u00e8nent leur chien, des cours d&rsquo;eau artificiels. Quand on pense \u00e0 l\u2019histoire de Los Angeles depuis ce lieu, on a l&rsquo;impression que Los Angeles y a pris ses marques, avant de s\u2019agrandir par une sorte de spirale gigantesque.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckouwalking.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"482\"\n        data-pswp-height=\"640\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckouwalking-330x438.jpg\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckouwalking.jpg\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckouwalking.jpg\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckouwalking.jpg\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckouwalking.jpg\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckouwalking-125x166.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Alain Mabanckou \u00e0 Los Angeles. \u00a9 Frida Ramirez <\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Souvent, je m\u2019y assois tranquillement avec mon carnet, je suis \u00e0 c\u00f4t\u00e9 du petit tunnel qui fait le lien entre la rue et le parc et dans lequel tous les <em>homeless<\/em> ont peint sur les murs. Ils ont mis des couleurs spectaculaires. Quand vous entrez dans ce tunnel, la lumi\u00e8re vient seulement du fond, et vous devenez vous-m\u00eame comme un personnage de ce paysage. Quand je songe \u00e0 mon \u00e9criture \u00e0 Los Angeles, c\u2019est au MacArthur Park que je pense.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Quand je songe \u00e0 mon \u00e9criture \u00e0 Los Angeles, c\u2019est au MacArthur Park que je pense.<\/p><cite>alain mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Jean Baudrillard avait vu dans Los Angeles la ville de l\u2019hyperr\u00e9alisme, du culte des objets et des images. Quel regard portez-vous sur la culture visuelle de Los Angeles&#160;?<\/strong><\/h3>\n\n\n\n<p>La ville de Los Angeles en particulier et la Californie en g\u00e9n\u00e9ral ont ce pouvoir de cr\u00e9er des images. Los Angeles est la ville des anges, qui sont cens\u00e9s \u00eatre eux-m\u00eames des visions. Ce qui me frappe le plus, c\u2019est que, physiquement, Los Angeles n\u2019existe pas. Los Angeles est compos\u00e9e de nos obsessions, de notre admiration, de ce que nous y projetons. De ce fait, chacun a une certaine id\u00e9e, une certaine g\u00e9ographie imaginaire de Los Angeles.<\/p>\n\n\n\n<p>C&rsquo;est peut \u00eatre aussi pour cette raison que, malgr\u00e9 les mondes tr\u00e8s d\u00e9velopp\u00e9s du cin\u00e9ma et de l\u2019art, les quartiers ont gard\u00e9 cette pr\u00e9sence des visions, des images. D\u00e8s que vous arrivez dans le quartier arm\u00e9nien, vous vous sentez dans un espace arm\u00e9nien&#160;; d\u00e8s que vous rentrez dans le quartier Little Ethiopia, les fresques aux couleurs vertes, jaunes et rouges qui rappellent la religion rastafari, les dieux du reggae et leur empereur Ha\u00efl\u00e9 S\u00e9lassi\u00e9, font vous sentir dans un espace \u00e9thiopien.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La ville de Los Angeles en particulier et la Californie en g\u00e9n\u00e9ral ont ce pouvoir de cr\u00e9er des images.<\/p><cite>alain mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Los Angeles est la ville de l\u2019expression visuelle la plus absolue. Y vivre impose de questionner quotidiennement son imaginaire, de retravailler sa fa\u00e7on de voir les choses, mais aussi de faire attention \u00e0 ce qui est de l\u2019ordre de l\u2019\u00e9ph\u00e9m\u00e8re. Beaucoup de temporalit\u00e9s cohabitent, comme des mirages. Il m\u2019arrive d\u2019avoir l\u2019impression que Los Angeles est une ville beaucoup plus r\u00eav\u00e9e que v\u00e9cue.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Diriez-vous que c\u2019est une ville romanesque&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Ce ne serait pas ma ville romanesque id\u00e9ale, mais avec le pouvoir du roman et de la fiction, il est possible de transformer la ville la plus hideuse en ville embl\u00e9matique. Faulkner a cr\u00e9\u00e9 une ville que tout le monde cherche, bien qu\u2019elle n\u2019existe pas. Elle ressemble simplement \u00e0 certaines bourgades qui sont dans le coin o\u00f9 il vivait. Le pouvoir romanesque d\u2019une ville d\u00e9pend de la puissance imaginaire de l\u2019\u00e9criture. La ville de Pointe-Noire sur laquelle j\u2019ai \u00e9crit a pu devenir un objet de fantasme, alors que ce n\u2019est qu\u2019une petite bande de terre. Les villes sont romanesques en raison des romans qui sont \u00e9crits \u00e0 leur sujet. Mais Los Angeles est peut-\u00eatre plus une ville d\u2019images que de textes.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous travaillez avec de multiples supports&#160;: l\u2019\u00e9criture, la musique, les vid\u00e9os\u2026 Comment ces diff\u00e9rents formats s\u2019articulent-ils dans votre travail&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>J\u2019utilise les diff\u00e9rentes opportunit\u00e9s que nous offrent les technologies modernes. Ces formats permettent de ne pas r\u00e9server la r\u00e9flexion et les discours \u00e0 des gens qui ont plus de trente ans. On ne peut pas partir du principe que les enfants d\u2019aujourd\u2019hui ne lisent plus ou ne peuvent plus comprendre un m\u00eame degr\u00e9 de complexit\u00e9 que nous&#160;: le changement de g\u00e9n\u00e9ration repose principalement sur une transformation des formats et des rythmes \u2013 vitesse de consommation, vitesse de p\u00e9remption, <em>etc<\/em>.<\/p>\n\n\n\n<p>Quand vous investissez les r\u00e9seaux des jeunes comme TikTok, il est important d\u2019apporter un contenu qui leur permet de s\u2019interroger sur ce qu\u2019ils sont, ce qu\u2019ils voient et ce qu\u2019ils entendent. Le r\u00e9sultat est toujours extraordinaire. \u00c0 mon arriv\u00e9e sur TikTok, je n\u2019ai pas voulu parler de litt\u00e9rature, parce que cela aurait \u00e9t\u00e9 trop attendu, et que le format ne me semblait pas convenir. J\u2019ai alors d\u00e9cid\u00e9 d\u2019\u00e9voquer une danse que je connais bien, la rumba congolaise. En peu de temps, j\u2019ai vu le nombre de r\u00e9actions grimper, 200 ou 300&nbsp;000 personnes suivre ce que je faisais, des t\u00e9l\u00e9visions le retransmettre au Congo-Brazzaville\u2026 C\u2019est aussi \u00e7a, le rythme des r\u00e9seaux, potentiel d\u2019expansion incroyable.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Je vise la qu\u00eate de la jeunesse pour p\u00e9renniser le go\u00fbt de la lecture.<\/p><cite>alain mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Je vise la qu\u00eate de la jeunesse pour p\u00e9renniser le go\u00fbt de la lecture. En exposant un contenu face \u00e0 une g\u00e9n\u00e9ration beaucoup plus jeune que la mienne, je prenais le risque que cela marche, ou qu\u2019ils d\u00e9testent. Quand la jeunesse voit un homme s\u00e9rieux, un grand, qui parle de litt\u00e9rature, faire son apparition sur TikTok, cela \u00e9veille la curiosit\u00e9. J\u2019esp\u00e8re que cela donnera \u00e0 certains la curiosit\u00e9 de prolonger leurs d\u00e9couvertes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Andy Warhol disait que chacun a sa propre Am\u00e9rique. Quelle est la v\u00f4tre&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Mon Am\u00e9rique change avec le temps.<\/p>\n\n\n\n<p>Au d\u00e9part, l\u2019Am\u00e9rique \u00e9tait pour moi simplement une terre de passage. J\u2019\u00e9tais un r\u00e9sident de passage. Quand vous restez plus d\u2019une d\u00e9cennie, la terre de passage devient pratiquement une terre d\u2019immobilisation. Quand vous passez deux d\u00e9cennies, vous y avez v\u00e9cu une g\u00e9n\u00e9ration, vous avez vu plusieurs pr\u00e9sidents, vous avez vu mourir et na\u00eetre des \u00e9toiles, vous \u00eates dans la culture, vous apprenez tout.&nbsp;<\/p>\n\n\n\n<p>Mon Am\u00e9rique serait donc celle que j\u2019ai choisie. Elle est plus populaire et diversifi\u00e9e. C&rsquo;est pour cela que j&rsquo;avais choisi de vivre \u00e0 Koreatown, o\u00f9 je peux trouver des restaurants tha\u00eflandais, cor\u00e9ens, chinois\u2026 En m\u00eame temps, Koreatown est \u00e0 la crois\u00e9e de La Brea, des Ethiopiens, des Noirs am\u00e9ricains et, de l\u2019autre c\u00f4t\u00e9, des quartiers bourgeois o\u00f9 se trouvent les ambassadeurs africains et europ\u00e9ens. Je me suis mis au milieu de ce <em>melting pot<\/em> parce que je voulais non seulement vivre en Am\u00e9rique, mais surtout apprendre \u00e0 conna\u00eetre les gens, plut\u00f4t que le discours officiel qui vend l\u2019Am\u00e9rique comme \u00e9tant la plus belle nation du monde.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LAMabanckou.jpeg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"480\"\n        data-pswp-height=\"640\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LAMabanckou-330x440.jpeg\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LAMabanckou.jpeg\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LAMabanckou.jpeg\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LAMabanckou.jpeg\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LAMabanckou.jpeg\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LAMabanckou-125x167.jpeg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Alain Mabanckou \u00e0 Los Angeles<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Ce sont les rencontres qui font mon Am\u00e9rique. Mon Am\u00e9rique s\u2019est hiss\u00e9e \u00e0 travers les gens, les rencontres. Ce sont les \u00eatres vivants, y compris les chiens, qui font l\u2019Am\u00e9rique. C\u2019est lors des \u00e9changes avec les Am\u00e9ricains que l\u2019on comprend l\u2019ampleur de ce pays. Le discours politique ne m&rsquo;a jamais fait aimer les \u00c9tats-Unis. Ce qui compte r\u00e9ellement pour moi, ce sont les rencontres que j\u2019ai faites, dont certaines sont racont\u00e9es dans <em>Rumeurs d\u2019Am\u00e9rique<\/em>. Je me souviens d\u2019un bar o\u00f9 j\u2019ai vu une Cor\u00e9enne en train d\u2019enseigner le cor\u00e9en \u00e0 un Am\u00e9ricain. C\u2019est \u00e7a pour moi l\u2019Am\u00e9rique.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ce sont les rencontres qui font mon Am\u00e9rique.<\/p><cite>alain Mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tout en dissimulant le politique sous le divertissement, le sud de la Californie offre une sorte de condens\u00e9 de dynamiques g\u00e9opolitiques profondes du monde contemporain&#160;: le d\u00e9r\u00e8glement climatique (feux, ressources en eau, <em>etc<\/em>.), les enjeux migratoires (avec la fronti\u00e8re la plus c\u00e9l\u00e8bre du monde entre San Diego et Tijuana) et la r\u00e9volution technologique et num\u00e9rique. Comment voyez-vous ce carrefour des enjeux mondiaux depuis le cas californien&#160;?<\/strong><\/h3>\n\n\n\n<p>\u00c0 mes yeux, la Californie du Sud est un laboratoire. Ma compagne qui est Mexicaine, s\u2019occupe avec son organisation du destin des r\u00e9fugi\u00e9s qui veulent rentrer aux \u00c9tats-Unis par Tijuana. Nous nous rendons souvent \u00e0 cette fronti\u00e8re. C\u2019est l\u00e0 que je comprends que la Californie du Sud contient \u00e0 la fois le meilleur et le pire.&nbsp;<\/p>\n\n\n\n<p>Les plus grands bourgeois, \u00e0 Rodeo Drive, cohabitent avec une d\u00e9tresse sociale et avec une haine montante contre les populations asiatiques\u2026 C&rsquo;est \u00e9trange, mais peut-\u00eatre que la Californie du Sud offre, dans une sorte de condens\u00e9, le r\u00e9pertoire des ennemis<strong> <\/strong>de la soci\u00e9t\u00e9 am\u00e9ricaine enti\u00e8re.<\/p>\n\n\n\n<p>C\u2019est curieux et m\u00eame \u00e9trange que tout cela soit illustr\u00e9 dans l&rsquo;\u00c9tat le plus riche des \u00c9tats-Unis, la Californie. Tout cela cohabite aussi avec des \u00e9volutions politiques&#160;: on a eu un gouverneur comme Arnold Schwarzenegger \u2014 lui aussi un immigr\u00e9 \u2014 ou la maire actuelle de Los Angeles, Karen Bass, qui est une noire am\u00e9ricain qui veut lutter contre le probl\u00e8me des sans domicile fixe, cruciale \u00e0 Los Angeles. Aujourd\u2019hui, vous ne pouvez pas traverser plus de quatre rues sans voir une tente, des personnes sans domicile, sans assistance minimale, dans un v\u00e9ritable d\u00e9sespoir.<\/p>\n\n\n\n<p>La conscience que le peuple am\u00e9ricain est confront\u00e9 \u00e0 ces probl\u00e9matiques n&rsquo;est pas assez marqu\u00e9e. Mais c&rsquo;est aussi sans doute pour cette raison que j&rsquo;ai choisi la Californie&#160;: pour \u00eatre \u00e0 la fois au c\u0153ur de tout cela et pour voir comment, en g\u00e9n\u00e9ral, on peut vivre tous les malheurs du monde dans un seul territoire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous avez choisi la Californie. Aviez-vous d\u00e9j\u00e0 une id\u00e9e <em>a priori<\/em> sur ce lieu ou \u00eates-vous parti \u00e0 la d\u00e9couverte de l\u2019inconnu, sans id\u00e9es pr\u00e9con\u00e7ues&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Le Michigan fut le premier endroit o\u00f9 je me suis install\u00e9 aux \u00c9tats-Unis. C\u2019est l\u00e0 que j\u2019ai commenc\u00e9 \u00e0 \u00eatre professeur. Je r\u00eavais \u00e9videmment d\u2019\u00eatre plut\u00f4t au soleil, \u00e0 l\u2019Ouest. La Californie \u00e9tait la ligne de mire. Finalement, ce sont les \u00e9v\u00e9nements qui m\u2019ont appel\u00e9 pour que j\u2019y aille.&nbsp;<\/p>\n\n\n\n<p>D\u00e8s que je suis arriv\u00e9, je suis tomb\u00e9 amoureux de cet espace. J&rsquo;ai d\u2019abord v\u00e9cu \u00e0 Santa Monica. J&rsquo;\u00e9tais au milieu de la petite bourgeoisie am\u00e9ricaine compos\u00e9e d\u2019acteurs d&rsquo;Hollywood qui ne veulent pas habiter \u00e0 Beverly Hills pour fuir les paparazzis et qui s\u2019installent donc \u00e0 Santa Monica. L&rsquo;oc\u00e9an Pacifique est \u00e0 c\u00f4t\u00e9, c&rsquo;est la splendeur. C\u2019est un coin propre, polic\u00e9. La Third Street Promenade de l&rsquo;autre c\u00f4t\u00e9 a sa splendeur.&nbsp;<\/p>\n\n\n\n<p>Mais ce qui manquait, c&rsquo;\u00e9tait justement la population. Je me sentais \u00e0 l&rsquo;aise quand je me mettais au c\u0153ur de Los Angeles, et non de Santa Monica. Pour cela j\u2019ai d\u00e9cid\u00e9 d\u2019emm\u00e9nager \u00e0 Los Angeles et pas \u00e0 Santa Monica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelles tendances de fond ou quelles orientations voyez-vous prendre au monde universitaire que vous observez en tant que professeur \u00e0 UCLA&#160;? Comment le renouveau critique d\u2019il y a vingt \u00e0 trente ans \u2014 avec l\u2019apparition des <em>cultural, postcolonial <\/em>et<em> gender studies<\/em> \u2014 a-t-il \u00e9volu\u00e9&nbsp;&#160;?<\/strong><\/h3>\n\n\n\n<p>Ces nouveaux champs de nos disciplines \u00e9voluent, tout simplement parce que de plus en plus de recherches se font. Toute forme de discipline que l\u2019Am\u00e9rique a impliqu\u00e9 dans l&rsquo;\u00e9tude de la soci\u00e9t\u00e9 am\u00e9ricaine \u00e9volue au fil des transformations de la soci\u00e9t\u00e9 elle-m\u00eame. Par exemple, il y a une grande diff\u00e9rence entre ce qu\u2019on \u00e9tudiait dans le domaine des \u00e9tudes postcoloniales il y a dix ans et ce que l\u2019on y \u00e9tudie aujourd\u2019hui. La litt\u00e9rature s\u2019est ouverte, les m\u00e9tissages sont partout, on va \u00e0 la rencontre d\u2019autres litt\u00e9ratures, venues d\u2019autres espaces \u2014 Pakistan, Afghanistan, etc.&nbsp;<\/p>\n\n\n\n<p>Le seul reproche que je fais \u00e0 cette \u00e9volution c\u2019est la compartimentation, le fait que chacun reste dans son pr\u00e9-carr\u00e9. Le choix d\u2019un angle ne doit pas se faire en opposition aux autres \u00e0 mon avis. Il s\u2019agit de montrer comment notre soci\u00e9t\u00e9 a \u00e9volu\u00e9 pour bousculer les cat\u00e9gories pr\u00e9con\u00e7ues, et non pas en construire d\u2019autres qui auraient leur propre rigidit\u00e9.<\/p>\n\n\n\n<p>Ces avanc\u00e9es de la pens\u00e9e nous ont permis de donner \u00e0 l&rsquo;individu la libert\u00e9 de d\u00e9finir son identit\u00e9, de r\u00e9futer celle qu\u2019on lui a coll\u00e9 \u00e0 la peau depuis des si\u00e8cles et de consid\u00e9rer que c&rsquo;est un individu qui se d\u00e9finit par les rencontres qu\u2019il va faire.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ces avanc\u00e9es de la pens\u00e9e nous ont permis de donner \u00e0 l&rsquo;individu la libert\u00e9 de d\u00e9finir son identit\u00e9, de r\u00e9futer celle qu\u2019on lui a coll\u00e9 \u00e0 la peau depuis des si\u00e8cles et de consid\u00e9rer que c&rsquo;est un individu qui se d\u00e9finit par les rencontres qu\u2019il va faire.<\/p><cite>alain mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle position adoptez-vous par rapport au concept d\u2019appropriation culturelle, qui est souvent brandi contre des personnes qui s\u2019approchent d\u2019aires culturelles dont il ne sont pas issus&#160;?<\/strong><\/h3>\n\n\n\n<p>Sur la demande de Charles Dantzig, je suis en train d\u2019\u00e9crire pour Grasset un livre sur l\u2019appropriation culturelle, qui s\u2019intitulera <em>8 le\u00e7ons sur l\u2019appropriation culturelle<\/em> et portera sur huit domaines diff\u00e9rents (musique, cuisine, mode, litt\u00e9rature\u2026). Le mot <em>appropriation<\/em> implique qu\u2019on se rend propri\u00e9taire de quelque chose, en l&rsquo;occurrence de la culture. Or, le propri\u00e9taire en tant que tel, selon la d\u00e9finition juridique, dispose du droit de pouvoir jouir de la chose, de disposer de la chose comme il veut et de l\u2019abuser comme il veut.&nbsp;<\/p>\n\n\n\n<p>Il y a des personnes de bonne foi qui portent des dreadlocks parce qu\u2019ils sont fascin\u00e9s par la religion rastafari. Le danger de l&rsquo;appropriation culturelle, c&rsquo;est quand on utilise ces codes pour faire du capital au d\u00e9triment des gens qui sont d\u00e9positaires de ces cultures. Dans ce sens, la personne avec des dreadlocks ne fait pas de l&rsquo;appropriation, mais effectue simplement un emprunt culturel. En revanche, quand l\u2019emprunt est r\u00e9alis\u00e9 pour des raisons \u00e9conomiques, capitalistiques, il s\u2019agit r\u00e9ellement de l\u2019appropriation culturelle parce que l\u2019emprunt leur servira \u00e0 fabriquer un produit. Il s\u2019agit de s\u2019auto-proclamer cr\u00e9ateur du produit.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le danger de l&rsquo;appropriation culturelle, c&rsquo;est quand on utilise ces codes pour faire du capital au d\u00e9triment des gens qui sont d\u00e9positaires de ces cultures.<\/p><cite>alain mabanckou<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Parmi ces trois lieux \u2014 France, Congo, \u00c9tats-Unis \u2014 sur lesquels repose la \u00ab&#160;marmite de l\u2019imaginaire&#160;\u00bb dont vous avez parl\u00e9, y a-t-il un endroit o\u00f9 vous pr\u00e9f\u00e9rez \u00e9crire, o\u00f9 vous \u00e9crivez le mieux&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Cela a fini par s&rsquo;\u00e9quilibrer. Ayant quitt\u00e9 le Congo \u00e0 mes 20 ans, il y a 37 ans, j\u2019ai davantage v\u00e9cu \u00e0 l\u2019ext\u00e9rieur qu\u2019\u00e0 l\u2019int\u00e9rieur de mon pays d\u2019origine. L\u2019\u00e9quilibre se fait de sorte que m\u00eame quand je vais au Congo, j\u2019ai envie de retourner aux \u00c9tats-Unis. Certes, c\u2019est d\u00fb au fait que je m\u2019y suis install\u00e9, mais aussi au fait que les Congolais vont me d\u00e9signer comme un \u00e9tranger. Ils ne seront jamais naturels avec moi. On se sent chez soi, l\u00e0 o\u00f9 on est tranquille, l\u00e0 o\u00f9 on est enfin avec soi-m\u00eame.&nbsp;<\/p>\n\n\n\n<p>J&rsquo;ai toujours cette passion pour le Congo, la France et les \u00c9tats-Unis. La marmite s\u2019est un peu \u00e9quilibr\u00e9e \u00e0 mesure que j\u2019avance.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans ce nouvel \u00e9pisode de notre s\u00e9rie d&rsquo;\u00e9t\u00e9 \u00ab&#160;&#160;Grand Tour&#160;&#160;\u00bb, Alain Mabanckou partage sa d\u00e9couverte du continent am\u00e9ricain \u00e0 travers les lectures et rencontres qui ont nourri son univers de cr\u00e9ation. Los Angeles, ville r\u00eav\u00e9e, accompagne l\u2019auteur de <em>Rumeurs d\u2019Am\u00e9riques<\/em> dans ses p\u00e9r\u00e9grinations litt\u00e9raires entre la France, le Congo et les \u00c9tats-Unis. <\/p>\n","protected":false},"author":2877,"featured_media":193859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":20,"footnotes":""},"categories":[2984],"tags":[],"staff":[1631,1753],"editorial_format":[4854],"serie":[],"audience":[],"geo":[525],"class_list":["post-193598","post","type-post","status-publish","format-standard","hentry","category-grand-tour","staff-florent-zemmouche","staff-mathieu-roger-lacan","editorial_format-entretiens","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":193859,"excerpt":"Dans ce nouvel \u00e9pisode de notre s\u00e9rie d'\u00e9t\u00e9 \u00abGrand Tour\u00bb, Alain Mabanckou partage sa d\u00e9couverte du continent am\u00e9ricain \u00e0 travers les lectures et rencontres qui ont nourri son univers de cr\u00e9ation. Los Angeles, ville r\u00eav\u00e9e, accompagne l\u2019auteur de <em>Rumeurs d\u2019Am\u00e9riques<\/em> dans ses p\u00e9r\u00e9grinations litt\u00e9raires entre la France, le Congo et les \u00c9tats-Unis. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abLos Angeles a ce pouvoir de cr\u00e9er des images\u00bb, une conversation avec Alain Mabanckou\u00a0 | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abLos Angeles a ce pouvoir de cr\u00e9er des images\u00bb, une conversation avec Alain Mabanckou\u00a0 | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Dans ce nouvel \u00e9pisode de notre s\u00e9rie d&#039;\u00e9t\u00e9 \u00ab&#160;Grand Tour&#160;\u00bb, Alain Mabanckou partage sa d\u00e9couverte du continent am\u00e9ricain \u00e0 travers les lectures et rencontres qui ont nourri son univers de cr\u00e9ation. Los Angeles, ville r\u00eav\u00e9e, accompagne l\u2019auteur de Rumeurs d\u2019Am\u00e9riques dans ses p\u00e9r\u00e9grinations litt\u00e9raires entre la France, le Congo et les \u00c9tats-Unis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-10T15:05:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-12T23:39:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-mabnckou-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"luciemielle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-mabnckou-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"luciemielle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/\",\"name\":\"\u00abLos Angeles a ce pouvoir de cr\u00e9er des images\u00bb, une conversation avec Alain Mabanckou\u00a0 | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg\",\"datePublished\":\"2023-08-10T15:05:09+00:00\",\"dateModified\":\"2023-08-12T23:39:38+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b241fc8f1100abf3d4e57620ff269306\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg\",\"width\":1720,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Los Angeles a ce pouvoir de cr\u00e9er des images&#160;\u00bb, une conversation avec Alain Mabanckou\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b241fc8f1100abf3d4e57620ff269306\",\"name\":\"luciemielle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/763bc73834a2775717fbfb332269bd73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/763bc73834a2775717fbfb332269bd73?s=96&d=mm&r=g\",\"caption\":\"luciemielle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abLos Angeles a ce pouvoir de cr\u00e9er des images\u00bb, une conversation avec Alain Mabanckou\u00a0 | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00abLos Angeles a ce pouvoir de cr\u00e9er des images\u00bb, une conversation avec Alain Mabanckou\u00a0 | Le Grand Continent","og_description":"Dans ce nouvel \u00e9pisode de notre s\u00e9rie d'\u00e9t\u00e9 \u00ab&#160;Grand Tour&#160;\u00bb, Alain Mabanckou partage sa d\u00e9couverte du continent am\u00e9ricain \u00e0 travers les lectures et rencontres qui ont nourri son univers de cr\u00e9ation. Los Angeles, ville r\u00eav\u00e9e, accompagne l\u2019auteur de Rumeurs d\u2019Am\u00e9riques dans ses p\u00e9r\u00e9grinations litt\u00e9raires entre la France, le Congo et les \u00c9tats-Unis.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/","og_site_name":"Le Grand Continent","article_published_time":"2023-08-10T15:05:09+00:00","article_modified_time":"2023-08-12T23:39:38+00:00","og_image":[{"width":2560,"height":1435,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-mabnckou-scaled.jpg","type":"image\/jpeg"}],"author":"luciemielle","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-mabnckou-scaled.jpg","twitter_misc":{"\u00c9crit par":"luciemielle","Dur\u00e9e de lecture estim\u00e9e":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/","name":"\u00abLos Angeles a ce pouvoir de cr\u00e9er des images\u00bb, une conversation avec Alain Mabanckou\u00a0 | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg","datePublished":"2023-08-10T15:05:09+00:00","dateModified":"2023-08-12T23:39:38+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b241fc8f1100abf3d4e57620ff269306"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg","width":1720,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/08\/10\/los-angeles-a-ce-pouvoir-de-creer-des-images-une-conversation-avec-alain-mabanckou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Los Angeles a ce pouvoir de cr\u00e9er des images&#160;\u00bb, une conversation avec Alain Mabanckou\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b241fc8f1100abf3d4e57620ff269306","name":"luciemielle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/763bc73834a2775717fbfb332269bd73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/763bc73834a2775717fbfb332269bd73?s=96&d=mm&r=g","caption":"luciemielle"}}]}},"lgc_categories":[{"id":2984,"name":"Grand Tour","slug":"grand-tour"}],"lgc_author":{"id":1631,"name":"Florent Zemmouche","slug":"florent-zemmouche","description":"Florent Zemmouche dirige l'\u00e9dition en espagnol du Grand Continent, coordonne les s\u00e9minaires hebdomadaires de la revue \u00e0 Madrid, les <em>Mi\u00e9rcoles del GC.<\/em>","first_name":"Florent","last_name":"Zemmouche","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/gc-elzemmouche.jpg","width":399,"height":531,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg","width":1720,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-Mabanckou-scaled.jpg","width":1720,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/193598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2877"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=193598"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/193598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/193859"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=193598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=193598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=193598"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=193598"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=193598"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=193598"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=193598"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=193598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}