{"id":190781,"date":"2023-07-09T18:31:30","date_gmt":"2023-07-09T16:31:30","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=190781"},"modified":"2023-07-09T18:32:57","modified_gmt":"2023-07-09T16:32:57","slug":"le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/","title":{"rendered":"Le casse-t\u00eate chinois de Meloni&#160;: enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Dans la cour de la Villa Madama, le palais Renaissance qui domine la capitale italienne depuis le quartier de Monte Mario, le Pr\u00e9sident du Conseil Giuseppe Conte attend le pr\u00e9sident de la R\u00e9publique populaire de Chine, Xi Jinping. Nous sommes le 23 mars 2019&#160;: apr\u00e8s une chaleureuse poign\u00e9e de main, les deux hommes traversent le jardin sur un tapis rouge recouvrant le sol en gravier avant de prendre place dans l&rsquo;une des salles int\u00e9rieures. Ils s\u2019appr\u00eatent \u00e0 signer l&rsquo;acte de politique \u00e9trang\u00e8re le plus important du mandat du gouvernement Conte.<\/p>\n\n\n\n<p>Apr\u00e8s des mois de n\u00e9gociations, l&rsquo;Italie rejoint le projet controvers\u00e9 des Nouvelles Routes de la Soie de la Chine par le biais d&rsquo;un protocole d&rsquo;accord de cinq ans qui d\u00e9finit les contours de la participation italienne. Pour la Chine, cette signature a une valeur g\u00e9opolitique tr\u00e8s importante&#160;: Rome est la seule capitale du G7 \u00e0 faire un tel choix diplomatique. Si les autres \u00c9tats europ\u00e9ens signent des accords commerciaux parfois encore plus importants, ils d\u00e9cident de ne pas s&rsquo;impliquer symboliquement. Pour les \u00c9tats-Unis, le Canada et le Japon, une telle signature serait tout simplement inconcevable.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/6Fvfo\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Quatre ans plus tard, le gouvernement de droite dirig\u00e9 par Giorgia Meloni est confront\u00e9 \u00e0 un choix politique d\u00e9licat&#160;: au d\u00e9but de l&rsquo;ann\u00e9e 2024, le M\u00e9morandum sign\u00e9 par Conte sera automatiquement renouvel\u00e9, sauf si l&rsquo;une des deux parties signale sa volont\u00e9 de se retirer trois mois \u00e0 l&rsquo;avance. L&rsquo;h\u00e9ritage de la signature de Conte est un dossier difficile \u00e0 g\u00e9rer pour l&rsquo;ex\u00e9cutif actuel&#160;: un renouvellement serait risqu\u00e9 pour Giorgia Meloni, qui envoie depuis des mois des signaux de loyaut\u00e9 envers l&rsquo;alliance atlantique et tient une position d\u00e9cisive en faveur du soutien \u00e0 l&rsquo;Ukraine, mais qui doit encore d\u00e9montrer qu&rsquo;elle est align\u00e9e sur l&rsquo;Occident dans les relations avec la Chine&#160;; d&rsquo;un autre c\u00f4t\u00e9, quitter l&rsquo;accord implique une position diplomatique publique tr\u00e8s claire, qui pourrait irriter P\u00e9kin et exposer l&rsquo;Italie \u00e0 d&rsquo;\u00e9ventuelles repr\u00e9sailles, en particulier sur le plan commercial.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;h\u00e9ritage de la signature de Conte est un dossier difficile \u00e0 g\u00e9rer pour l&rsquo;ex\u00e9cutif actuel.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Comment l&rsquo;Italie a-t-elle pu se retrouver dans une telle impasse diplomatique&#160;?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La Chine dans la politique int\u00e9rieure du Mouvement 5 \u00e9toiles<\/strong><\/h2>\n\n\n\n<p>Alors qu&rsquo;au moment de la signature, P\u00e9kin semble tout \u00e0 fait conscient de la grande valeur de l&rsquo;adh\u00e9sion de l&rsquo;Italie, le gouvernement Conte I traite la question de mani\u00e8re incertaine \u2014 soulignant ou minimisant la port\u00e9e de l&rsquo;accord en fonction du contexte. Dans un premier temps, le rapprochement avec la Chine est un choix produit par des motivations politiques \u00e9videntes qui guident les actions des partis majoritaires. Les \u00e9lections italiennes de 2018, avec l&rsquo;affirmation et l&rsquo;alliance de deux partis anti-establishment comme la Lega de Matteo Salvini et le Movimento 5 stelle, ont fait de l&rsquo;Italie \u00ab&#160;le centre de l&rsquo;univers de la politique&#160;\u00bb selon la d\u00e9finition de Steve Bannon, ancien conseiller tr\u00e8s influent de Donald Trump \u00e0 la Maison Blanche et grand d\u00e9fenseur d&rsquo;une coalition qui unirait les populismes de droite et de gauche. L&rsquo;objectif de Bannon et d&rsquo;une partie de l&rsquo;administration r\u00e9publicaine de l&rsquo;\u00e9poque est de d\u00e9stabiliser la politique europ\u00e9enne et d&rsquo;alimenter les conflits entre les \u00c9tats membres, une vision qui accueille donc favorablement un gouvernement h\u00e9t\u00e9rodoxe \u00e0 la t\u00eate d&rsquo;un pays fondateur de l&rsquo;Union.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000048-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000048-scaled-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000048-scaled-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000048-scaled-1340x894.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000048-scaled-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Le pr\u00e9sident chinois Xi Jinping et la d\u00e9l\u00e9gation chinoise lors d&rsquo;une r\u00e9union avec le premier ministre italien Giuseppe Conte \u00e0 la Villa Madama \u00e0 Rome le 23 mars 2019. \u00a9 Alessandro Serrano&rsquo;\/AGF\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>L&rsquo;analyse de Bannon trouve un certain \u00e9cho dans la r\u00e9alit\u00e9. Le gouvernement Conte I tente de mettre en place une politique \u00e9trang\u00e8re moins ancr\u00e9e \u00e0 la plateforme euro-atlantique traditionnelle&#160;: le Mouvement 5 \u00e9toiles et la Ligue ont des positions ouvertement anti-atlantiques, en pol\u00e9mique dure avec Bruxelles, Paris et Berlin, proches de la Russie et de la Chine, cette derni\u00e8re \u00e9tant une r\u00e9f\u00e9rence majeure du Mouvement 5 \u00e9toiles et de son fondateur Beppe Grillo. Certes, le positionnement pro-chinois peut para\u00eetre contradictoire, notamment en raison de la fascination exerc\u00e9e par Donald Trump sur une grande partie des membres de l&rsquo;ex\u00e9cutif de la Ligue, celle-ci \u00e9tant traditionnellement moins ouverte \u00e0 P\u00e9kin et surtout plus attentive aux positions du pr\u00e9sident am\u00e9ricain, r\u00e9f\u00e9rence internationale \u00e0 l&rsquo;\u00e9poque de toute l&rsquo;extr\u00eame-droite europ\u00e9enne. Bannon th\u00e9orise lui-m\u00eame la n\u00e9cessit\u00e9 d&rsquo;un choc frontal avec P\u00e9kin, mais la politique italienne s&rsquo;est toujours accommod\u00e9e de ce type d&rsquo;ambigu\u00eft\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Malgr\u00e9 le grand \u00e9lan du Mouvement 5 \u00e9toiles, l&rsquo;homme au centre de la politique chinoise du gouvernement Conte est un membre de la Ligue. Il s&rsquo;appelle Michele Geraci.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Malgr\u00e9 le grand \u00e9lan du Mouvement 5 \u00e9toiles, l&rsquo;homme au centre de la politique chinoise du gouvernement Conte est un membre de la Ligue. Il s&rsquo;appelle Michele Geraci et il est sous-secr\u00e9taire au d\u00e9veloppement \u00e9conomique, en grand accord avec ses coll\u00e8gues 5 \u00e9toiles de l&rsquo;ex\u00e9cutif \u2014 \u00e0 tel point que beaucoup le confondent plus avec un Grillo qu&rsquo;avec un membre de la Ligue du Nord. Le professeur, qui se targue d&rsquo;une exp\u00e9rience professionnelle de plus de dix ans en Chine, \u00e0 l&rsquo;universit\u00e9 de Nottingham Ningbo China et \u00e0 la New York University Shanghai, noue une relation tr\u00e8s forte avec son ministre de tutelle, Luigi Di Maio, qui, \u00e0 l&rsquo;\u00e9poque, est en qu\u00eate de l\u00e9gitimit\u00e9 internationale et surtout d&rsquo;investissements directs \u00e9trangers en Italie. Il souhaite en effet attirer des investisseurs pour montrer au monde que le Mouvement 5 \u00e9toiles est ouvert aux opportunit\u00e9s d&rsquo;affaires et aux multinationales.<\/p>\n\n\n<section class=\"dive print-block my-16  \" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tDe l&rsquo;Ukraine au m\u00e9tavers\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Les clefs d&rsquo;un monde cass\u00e9.<\/p>\n<p>Du centre du globe \u00e0 ses fronti\u00e8res les plus lointaines, la guerre est l\u00e0. L\u2019invasion de l\u2019Ukraine par la Russie de Poutine nous a frapp\u00e9s, mais comprendre cet affrontement crucial n&rsquo;est pas assez.<\/p>\n<p>Notre \u00e8re est travers\u00e9e par un ph\u00e9nom\u00e8ne occulte et structurant, nous proposons de l\u2019appeler&#160;: guerre \u00e9tendue.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/precommandez-le-nouveau-numero\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Commandez le nouveau num\u00e9ro<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrez toutes nos offres<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/politiques-de-linterregne\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9j\u00e0 abonn\u00e9&#160;? commandez le num\u00e9ro pr\u00e9c\u00e9dent<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><em>Fractures de la guerre \u00e9tendue&#160;: de l\u2019Ukraine au m\u00e9tavers<\/em> est d\u00e9j\u00e0 disponible <a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/commandez-le-nouveau-numero\/\">\u00e0 l&rsquo;achat<\/a> et dans notre <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\">offre de lancement<\/a>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/mediamodifier_image-42-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>D\u00e8s son arriv\u00e9e au minist\u00e8re, Geraci a demand\u00e9 et obtenu la cr\u00e9ation d&rsquo;une <em>task force<\/em> enti\u00e8rement d\u00e9di\u00e9e \u00e0 la Chine. En arri\u00e8re-plan, il y a aussi la grande question de la soutenabilit\u00e9 de la dette italienne, le principal probl\u00e8me de politique \u00e9conomique que le gouvernement form\u00e9 par la Ligue et le Mouvement 5 \u00e9toiles entend r\u00e9soudre&#160;: pourquoi se soumettre aux r\u00e8gles budg\u00e9taires impos\u00e9es par Bruxelles et ses partenaires europ\u00e9ens alors qu&rsquo;il est possible de trouver d&rsquo;autres acheteurs d&rsquo;obligations d&rsquo;\u00c9tat comme la Russie et la Chine&#160;? Il ne s&rsquo;agit pas d&rsquo;une simple suggestion&#160;: \u00e0 l&rsquo;\u00e9poque, les informations sur les efforts de l&rsquo;Italie pour convaincre P\u00e9kin d&rsquo;investir dans la dette italienne se multiplient en coulisse. Une conviction \u00e9tay\u00e9e par les nombreuses missions que les membres de l&rsquo;ex\u00e9cutif ont men\u00e9es en Chine&#160;: le journal <em>Avvenire<\/em>, en analysant l&rsquo;agenda du voyage en Chine du ministre de l&rsquo;\u00c9conomie Giovanni Tria, \u00e9crit en ao\u00fbt 2018 \u00ab&#160;qu&rsquo;il est d\u00e9sormais officiel que l&rsquo;Italie demandera aux Chinois d&rsquo;acheter nos obligations Btp, m\u00eame si nous ne savons toujours pas ce que [la Chine] voudra en \u00e9change&#160;\u00bb. <em>Avvenire<\/em> \u00e9crit \u00e9galement que \u00ab&#160;favoriser l&rsquo;investissement chinois dans les obligations d&rsquo;\u00c9tat est en tout cas l&rsquo;un des objectifs d\u00e9clar\u00e9s de la China Task Force qui vient d&rsquo;\u00eatre lanc\u00e9e au minist\u00e8re du D\u00e9veloppement \u00e9conomique&#160;\u00bb. On retrouve une interpr\u00e9tation similaire dans le <em>Corriere della Sera<\/em>, pr\u00e9cis\u00e9ment en ce qui concerne la mission de Giovanni Tria&#160;: \u00ab&#160;Tria \u00e0 P\u00e9kin essaie de trouver de nouveaux investisseurs dans la dette italienne au sein des autorit\u00e9s chinoises, et pas seulement parmi les particuliers. Le ministre pr\u00e9voit des r\u00e9unions au plus haut niveau de la Banque populaire de Chine&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-190781' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#easy-footnote-bottom-1-190781' title='Federico Fubini, \u00ab&amp;#160;Tria prepara la missione Cina. Lo scambio tra l\u2019acquisto del debito pubblico e le rotte verso l\u2019Italia&amp;#160;\u00bb, &lt;em&gt;Corriere della Sera&lt;\/em&gt;, 13 ao\u00fbt 2018.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00c0 l&rsquo;\u00e9poque, les informations sur les efforts de l&rsquo;Italie pour convaincre P\u00e9kin d&rsquo;investir dans la dette italienne se multiplient en coulisse.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Aujourd&rsquo;hui, aucun document concernant la <em>task force<\/em> Chine n&rsquo;est disponible&#160;: sur le site du minist\u00e8re, toutes les pages sont inaccessibles. Michele Geraci explique cependant au Grand Continent que les reconstitutions de l&rsquo;\u00e9poque passent \u00e0 c\u00f4t\u00e9 de l&rsquo;essentiel&#160;: \u00ab&#160;La <em>task force<\/em> \u00e9tait un think tank sans objectif pr\u00e9cis. La premi\u00e8re phase \u00e9tait un <em>brainstorming<\/em>, volontairement chaotique. Tout ce que j&rsquo;ai dit sur les obligations d&rsquo;\u00c9tat, c&rsquo;est que tous les \u00c9tats peuvent en acheter, y compris la Chine. C&rsquo;est une \u00e9vidence mais ce n&rsquo;\u00e9tait pas ma t\u00e2che d&rsquo;arriver \u00e0 cet objectif, ni celle du gouvernement&#160;\u00bb. Pourtant, les propos des dirigeants politiques de l&rsquo;\u00e9poque sugg\u00e8rent le contraire. Paolo Savona, l&rsquo;un des principaux \u00e9conomistes et intellectuels de r\u00e9f\u00e9rence de la Ligue et du Mouvement 5 \u00e9toiles, qui est devenu ministre des affaires europ\u00e9ennes apr\u00e8s le rejet public et retentissant par le Quirinal de la demande de l\u2019aile gauche du M5S de le nommer ministre de l&rsquo;\u00e9conomie, a toujours \u00e9t\u00e9 explicite \u00e0 cet \u00e9gard. Dans son fameux \u00ab&#160;Plan B&#160;\u00bb pour quitter la zone euro, Savona a pr\u00e9sent\u00e9 une strat\u00e9gie assez claire&#160;: \u00ab&#160;Conclure des alliances internationales avec des pays int\u00e9ress\u00e9s \u00e0 prot\u00e9ger l&rsquo;autonomie politique de l&rsquo;Italie [&#8230;] et s&rsquo;opposer \u00e0 l&rsquo;influence du bloc des pays qui gravitent autour de l&rsquo;Allemagne [&#8230;] et fournir \u00e0 ces pays des alliances concr\u00e8tes pour agir en tant que \u00ab&#160;pr\u00eateurs en dernier ressort&#160;\u00bb afin de faire face \u00e0 la sp\u00e9culation qui serait d\u00e9clench\u00e9e par la d\u00e9cision de quitter l&rsquo;euro.&#160;\u00bb<\/p>\n\n\n\n<p>Mais si Geraci navigue autant \u00e0 son aise, c&rsquo;est aussi gr\u00e2ce \u00e0 une classe politique au sein de laquelle \u00ab&#160;personne ne sait rien de la Chine&#160;\u00bb, comme l&rsquo;\u00e9crivent les journalistes Giulia Pompili et Valerio Valentini dans leur livre sur le sujet, <em>Al Cuore dell&rsquo;Italia<\/em>, publi\u00e9 en 2022 par Mondadori. Or si c\u2019\u00e9tait vrai pour l&rsquo;opinion publique, encore peu habitu\u00e9e au r\u00f4le de P\u00e9kin dans les affaires internationales, une partie de l&rsquo;\u00e9lite politique et bureaucratique italienne est \u00e0 l\u2019\u00e9poque parfaitement au courant de ce dossier et int\u00e9ress\u00e9e \u00e0 rejoindre les Nouvelles Routes de la Soie. Francesca Ghiretti, analyste \u00e0 l&rsquo;institut Merics de Berlin et <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/14\/construire-la-securite-economique-de-leurope\/\">autrice dans ces pages d\u2019un article r\u00e9cent sur la s\u00e9curit\u00e9 \u00e9conomique de l\u2019Union<\/a>, se souvient de la grande effervescence de cette p\u00e9riode&#160;: \u00ab&#160;L&rsquo;id\u00e9e de travailler sur un protocole d&rsquo;accord est n\u00e9e en 2017 lors du forum BRI, auquel participait le gouvernement italien dirig\u00e9 par Paolo Gentiloni, soutenu par une coalition traditionnelle de centre-gauche aux all\u00e9geances atlantistes av\u00e9r\u00e9es. Il n&rsquo;y a pas encore eu de v\u00e9ritable n\u00e9gociation entre Rome et P\u00e9kin sur la question, mais en Italie, la possibilit\u00e9 a certainement \u00e9t\u00e9 envisag\u00e9e, au moins par une partie de l&rsquo;establishment.&#160;\u00bb En d&rsquo;autres termes, m\u00eame si le choix de n\u00e9gocier puis de signer le protocole d&rsquo;accord avec la Chine a \u00e9t\u00e9 utilis\u00e9 de mani\u00e8re rh\u00e9torique par le gouvernement Ligue-M5S pour signaler sa nouvelle autonomie en mati\u00e8re de politique \u00e9trang\u00e8re, il existe des \u00e9l\u00e9ments de continuit\u00e9 avec la position italienne des dix derni\u00e8res ann\u00e9es&#160;: \u00ab&#160;Tout se passe comme si, \u00e0 ce moment-l\u00e0, le gouvernement avait voulu signaler qu&rsquo;il \u00e9tait capable de mener une politique \u00e9trang\u00e8re ind\u00e9pendante des Am\u00e9ricains et de l&rsquo;Union europ\u00e9enne. C&rsquo;est aussi pour cela qu&rsquo;il s&rsquo;agit d&rsquo;un choix fait \u00e0 la h\u00e2te, qui n&rsquo;est pas le r\u00e9sultat d&rsquo;une r\u00e9flexion profonde ou d&rsquo;une grande coordination avec les alli\u00e9s&#160;\u00bb, explique Ieva Jakobsone Bellomi, ancienne membre de la Chambre de commerce europ\u00e9enne \u00e0 P\u00e9kin et aujourd&rsquo;hui chercheuse \u00e0 l&rsquo;Universit\u00e9 John Cabot \u00e0 Rome.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si le choix de n\u00e9gocier puis de signer le protocole d&rsquo;accord avec la Chine a \u00e9t\u00e9 utilis\u00e9 de mani\u00e8re rh\u00e9torique par le gouvernement Ligue-M5S pour signaler sa nouvelle autonomie en mati\u00e8re de politique \u00e9trang\u00e8re, il existe des \u00e9l\u00e9ments de continuit\u00e9 avec la position italienne des dix derni\u00e8res ann\u00e9es.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Comme l&rsquo;\u00e9crivent les chercheurs Giulio Pugliese, Francesca Ghiretti et Aurelio Insisa dans un rapport bien document\u00e9 sur la strat\u00e9gie du gouvernement italien \u00e0 l&rsquo;\u00e9poque&#160;: \u00ab&#160;Une lecture de \u00ab&#160;marketing politique&#160;\u00bb sugg\u00e8re que le gouvernement jaune-vert a utilis\u00e9 la marque BRI pour reconditionner l&rsquo;engagement avec la Chine poursuivi par ses pr\u00e9d\u00e9cesseurs, dans le but de signaler la suppos\u00e9e nouvelle libert\u00e9 d&rsquo;action de l&rsquo;Italie \u00e0 son \u00e9lectorat et \u00e0 l&rsquo;\u00e9lectorat italien dans son ensemble. Le protocole d&rsquo;accord relevait davantage de la gesticulation populiste que de la grande strat\u00e9gie et du r\u00e9alignement international.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-190781' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#easy-footnote-bottom-2-190781' title='Giulio Pugliese and others, Italy&amp;rsquo;s embrace of the Belt and Road Initiative&amp;#160;: populist foreign policy and political marketing, &lt;em&gt;International Affairs&lt;\/em&gt;, Volume 98, Issue 3, mai 2022, Pages 1033\u20131051, &lt;a href=&quot;https:\/\/doi.org\/10.1093\/ia\/iiac039&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/doi.org\/10.1093\/ia\/iiac039&lt;\/a&gt;.'><sup>2<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Ce qui est certain, c&rsquo;est qu&rsquo;au d\u00e9but de l&rsquo;ann\u00e9e 2019, alors que l&rsquo;adh\u00e9sion de l&rsquo;Italie aux Nouvelles Routes de la Soie est d\u00e9sormais concr\u00e8te et que la visite du pr\u00e9sident chinois Xi Jinping pour conclure l&rsquo;accord est pr\u00e9vue pour la fin du mois de mars, une partie de l&rsquo;opinion publique t\u00e9moigne son opposition. La presse italienne et internationale s&rsquo;interroge sur l&rsquo;opportunit\u00e9 d&rsquo;un tel choix, et le Parti d\u00e9mocrate (PD) lui-m\u00eame, interpr\u00e9tant en partie son r\u00f4le d&rsquo;opposition et conscient des implications g\u00e9opolitiques de l&rsquo;adh\u00e9sion, exprime plus d&rsquo;une critique. Au sein de l&rsquo;Union, le choix de Rome est remis en cause, mais le contexte g\u00e9opolitique pr\u00e9-pand\u00e9mique et les relations avec P\u00e9kin, qui \u00e9voluent certes vers plus de tension, sont incomparables avec le contexte actuel. Aux \u00c9tats-Unis, en revanche, la position est clairement d\u00e9favorable, comme l&rsquo;admet Michele Geraci lui-m\u00eame&#160;: \u00ab&#160;Lors d&rsquo;une r\u00e9union \u00e0 Washington avec mon homologue, on m&rsquo;a demand\u00e9 pourquoi nous avions sign\u00e9, et on m&rsquo;a fait remarquer que ce n&rsquo;\u00e9tait pas une bonne id\u00e9e de le faire. En Europe, en revanche, personne ne m&rsquo;a jamais appel\u00e9, t\u00e9l\u00e9phon\u00e9, \u00e9crit, et je ne pense pas qu&rsquo;ils aient appel\u00e9 mes coll\u00e8gues, car sinon ils me l&rsquo;auraient dit.&#160;\u00bb<\/p>\n\n\n\n<p>En Europe, personne ne fait peut-\u00eatre pression&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-190781' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#easy-footnote-bottom-3-190781' title='Le sujet est quand m\u00eame \u00e0 l\u2019\u00e9poque au centre des discussions&amp;#160;: Alexandra Brzozowski et Jorge Valero, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.euractiv.com\/section\/economy-jobs\/news\/dont-be-naive-with-china-eu-leaders-tell-italy\/&quot;&gt;Don\u2019t be naive with China\u2019, EU leaders tell Italy&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Euractiv&lt;\/em&gt;, 22 mars 2019.'><sup>3<\/sup><\/a><\/span><\/span>, mais les alli\u00e9s continentaux ne semblent certainement pas croire qu&rsquo;il est n\u00e9cessaire de rejoindre les Nouvelles routes de la soie pour faire des affaires&#160;: peu apr\u00e8s la visite de Xi \u00e0 Rome la m\u00eame ann\u00e9e, la France et l&rsquo;Allemagne ont conclu plusieurs accords commerciaux et industriels avec la Chine, \u00e0 l&rsquo;instar d&rsquo;autres \u00c9tats europ\u00e9ens. C&rsquo;est une consid\u00e9ration qui commence \u00e0 faire son chemin jusqu&rsquo;au gouvernement jaune-vert, quelques semaines seulement apr\u00e8s la grande visite d&rsquo;\u00c9tat organis\u00e9e par Xi Jinping \u00e0 l&rsquo;occasion de la signature.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les alli\u00e9s continentaux de Rome ne semblent certainement pas croire qu&rsquo;il est n\u00e9cessaire de rejoindre les Nouvelles routes de la soie pour faire des affaires&#160;: peu apr\u00e8s la visite de Xi \u00e0 Rome la m\u00eame ann\u00e9e, la France et l&rsquo;Allemagne ont conclu plusieurs accords commerciaux et industriels avec la Chine, \u00e0 l&rsquo;instar d&rsquo;autres \u00c9tats europ\u00e9ens.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un accord contre l\u2019Italie&#160;?<\/strong><\/h2>\n\n\n\n<p>En 2019, la Ligue a le vent en poupe&#160;: chaque mois, elle \u00e9largit son consensus et le gagne surtout sur son alli\u00e9\/adversaire. Au si\u00e8ge de la Via Bellerio, on commence \u00e0 envisager de faire tomber le gouvernement pour tenter de remporter les \u00e9lections et, pour la premi\u00e8re fois de l&rsquo;histoire, la pr\u00e9sidence du Conseil. Mais pour \u00eatre cr\u00e9dible, il faut l&rsquo;aval de Washington. Les signaux d&rsquo;all\u00e9geance \u00e0 la ligne am\u00e9ricaine en provenance de la Ligue se multiplient, une circonstance facilit\u00e9e par la grande proximit\u00e9 id\u00e9ologique entre le parti de Salvini et Donald Trump, cit\u00e9 comme mod\u00e8le politique par le ministre de l&rsquo;Int\u00e9rieur de l&rsquo;\u00e9poque. Peut-\u00eatre les Am\u00e9ricains n&rsquo;exercent-ils pas de pression sur le gouvernement italien par les canaux diplomatiques habituels, mais publiquement leur position est tr\u00e8s claire&#160;: \u00ab&#160;L&rsquo;approbation de Rome aux Nouvelles Routes de la soie l\u00e9gitime \u00e0 l&rsquo;\u00e9chelle internationale l&rsquo;approche pr\u00e9datrice de la Chine en mati\u00e8re d&rsquo;investissement et ne b\u00e9n\u00e9ficiera pas au peuple italien&#160;\u00bb, peut-on lire dans un tweet du compte du Conseil national de s\u00e9curit\u00e9 des \u00c9tats-Unis dat\u00e9 du 9 mars 2019.<\/p>\n\n\n\n<p>Ainsi commence une phase de redimensionnement, de l&rsquo;accord \u2014 ou \u00e0 tout le moins de sa valeur politique. Le 11 mars 2019, peu apr\u00e8s une visite \u00e0 New York et Washington du sous-secr\u00e9taire \u00e0 la pr\u00e9sidence du Conseil, le leghiste Giancarlo Giorgetti, Matteo Salvini commence \u00e0 signaler une certaine impatience de son parti face \u00e0 l&rsquo;adh\u00e9sion&#160;: \u00ab&#160;S&rsquo;il s&rsquo;agit d&rsquo;aider les entreprises italiennes \u00e0 investir \u00e0 l&rsquo;\u00e9tranger, nous sommes pr\u00eats \u00e0 raisonner avec tout le monde, mais s&rsquo;il s&rsquo;agit de coloniser l&rsquo;Italie et ses entreprises par des puissances \u00e9trang\u00e8res, non&#160;\u00bb d\u00e9clare le ministre de l&rsquo;Int\u00e9rieur en marge d&rsquo;une r\u00e9union de son parti. Le Pr\u00e9sident du Conseil Giuseppe Conte tente de minimiser l&rsquo;importance de la signature pr\u00e9vue \u00e0 la fin du mois&#160;: \u00ab&#160;Le m\u00e9morandum n&rsquo;a pas la nature d&rsquo;un accord international et ne cr\u00e9e pas de contraintes juridiques&#160;\u00bb, d\u00e9clare-t-il au <em>Corriere<\/em> deux jours plus tard. En r\u00e9alit\u00e9, le gouvernement \u00e9tait parfaitement conscient qu&rsquo;il pouvait devenir un instrument de la politique \u00e9trang\u00e8re chinoise, comme l&rsquo;explique tr\u00e8s clairement Michele Geraci&#160;: \u00ab&#160;Pour les Chinois, la relation est g\u00e9opolitique, pour nous, elle est commerciale. Nous ne pouvons pas contr\u00f4ler la mani\u00e8re dont ils revendiquent politiquement les accords, mais nous pouvons les accompagner \u00ab&#160;en cr\u00e9dit&#160;\u00bb&#160;; nous collectons ce cr\u00e9dit gr\u00e2ce \u00e0 la cascade de communication qui se cr\u00e9e apr\u00e8s une d\u00e9claration de Xi Jinping en faveur des affaires avec l&rsquo;Italie. Le pr\u00e9sident donne son avis \u00e0 ses entreprises, qui agissent ensuite. C&rsquo;\u00e9tait l&rsquo;esprit du protocole d&rsquo;accord&#160;: nous donnons quelque chose \u00e0 la Chine qui doit ensuite nous donner quelque chose en retour. Nous savions tr\u00e8s bien comment ils allaient s\u2019y prendre.&#160;\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le gouvernement \u00e9tait parfaitement conscient qu&rsquo;il pouvait devenir un instrument de la politique \u00e9trang\u00e8re chinoise.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Selon la reconstitution effectu\u00e9e par les journalistes du Foglio Giulia Pompili et Valerio Valentini, au cours de ces journ\u00e9es plut\u00f4t agit\u00e9es, d\u00e9montrant la grande valeur symbolique de l&rsquo;accord, Xi Jinping a menac\u00e9 de faire \u00e9chouer la visite d&rsquo;\u00c9tat. Tout se met en place, le voyage a lieu et, pour l&rsquo;Italie, le protocole d&rsquo;accord est sign\u00e9 par le ministre du d\u00e9veloppement \u00e9conomique, Luigi Di Maio, avec 29 accords, institutionnels et entre entreprises. \u00ab&#160;Il r\u00e9\u00e9quilibrera la balance commerciale en notre faveur&#160;\u00bb, d\u00e9clare Luigi Di Maio en marge de la c\u00e9r\u00e9monie.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000057-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000057-scaled-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000057-scaled-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000057-scaled-1340x894.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000057-scaled-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Le pr\u00e9sident chinois Xi Jinping et la d\u00e9l\u00e9gation chinoise lors d&rsquo;une r\u00e9union avec le premier ministre italien Giuseppe Conte \u00e0 la Villa Madama \u00e0 Rome le 23 mars 2019. \u00a9 Alessandro Serrano&rsquo;\/AGF\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Apr\u00e8s plus de quatre ans, les \u00e9changes commerciaux indiquent le contraire. Le d\u00e9s\u00e9quilibre manifeste de la balance des paiements, qui devait th\u00e9oriquement diminuer avec l&rsquo;accord, est encore plus marqu\u00e9 aujourd&rsquo;hui. Si les exportations italiennes s&rsquo;am\u00e9liorent, passant de 11 milliards en 2016 \u00e0 16,4 milliards en 2022, les importations en provenance de Chine augmentent de fa\u00e7on spectaculaire&#160;: en 2016, l&rsquo;Italie a import\u00e9 27,3 milliards de biens, en 2022, la somme atteindra 57,5 milliards. Si, en termes de biens achet\u00e9s \u00e0 P\u00e9kin, la position de l&rsquo;Italie est similaire \u00e0 celle de l&rsquo;Allemagne, Rome exporte beaucoup moins que la France et l&rsquo;Allemagne, qui vendent respectivement pr\u00e8s de deux fois (4,03&#160;% du march\u00e9) et trois fois (6,77&#160;% du march\u00e9) les biens vendus par les Italiens (2,73&#160;% du march\u00e9) \u00e0 la Chine.<\/p>\n\n\n\n<p>Contact\u00e9 \u00e0 plusieurs reprises par le Grand Continent pour lui demander de dresser un bilan politique et \u00e9conomique du m\u00e9morandum, l&rsquo;ancien ministre des affaires \u00e9trang\u00e8res Luigi Di Maio, l&rsquo;un des principaux artisans de cette signature, a refus\u00e9 de r\u00e9pondre \u00e0 nos questions.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le d\u00e9s\u00e9quilibre manifeste de la balance des paiements, qui devait th\u00e9oriquement diminuer avec l&rsquo;accord, est encore plus marqu\u00e9 aujourd&rsquo;hui.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>De P\u00e9kin \u00e0 Trieste&#160;: \u00ab&#160;nous ne nous rendrons pas aux mains des Chinois&#160;\u00bb<\/strong><\/h2>\n\n\n\n<p>L&rsquo;un des nombreux domaines dans lesquels l&rsquo;accord n&rsquo;a pas donn\u00e9 de grands r\u00e9sultats est celui des ports, qui aurait d\u00fb \u00eatre la principale infrastructure \u00e0 b\u00e9n\u00e9ficier d&rsquo;une coop\u00e9ration plus approfondie avec la Chine. L&rsquo;int\u00e9r\u00eat de la Chine pour les ports italiens fait depuis longtemps l&rsquo;objet de d\u00e9bats. Trieste, par exemple, \u00e9tait cens\u00e9e \u00eatre l&rsquo;un des principaux d\u00e9bouch\u00e9s des Nouvelles Routes de la soie en Europe du Sud \u2014 \u00e0 tel point que le pr\u00e9sident de l&rsquo;autorit\u00e9 portuaire de Trieste, Zeno D&rsquo;Agostino, v\u00e9ritable protagoniste de la renaissance du port de la ville, est pr\u00e9sent le 23 mars 2019 \u00e0 la Villa Madama et signe \u00e9galement un accord avec le g\u00e9ant chinois CCCC pour des investissements dans le Trihub \u2014 le projet d&rsquo;interconnexion entre le port et le n\u0153ud ferroviaire. L&rsquo;accord pr\u00e9voit des opportunit\u00e9s r\u00e9ciproques&#160;: le port de Trieste pourra participer aux projets logistiques de CCCC en Chine et en Slovaquie, ce qui se concr\u00e9tise quelques mois plus tard, le 5 novembre 2019, \u00e0 Shanghai, o\u00f9 Di Maio et D&rsquo;Agostino signent un partenariat avec l&rsquo;entreprise chinoise pour le d\u00e9veloppement de zones industrielles sino-italiennes en Chine, qui seront connect\u00e9es au port de Trieste et au syst\u00e8me logistique italien.<\/p>\n\n\n\n<p>Apr\u00e8s un grand int\u00e9r\u00eat initial qui laissait pr\u00e9sager un investissement chinois dans le terminal de la Plateforme Logistique de Trieste (PLT), la pand\u00e9mie et l&rsquo;escalade des tensions entre la Chine et les \u00c9tats-Unis ont chang\u00e9 la donne. Le 29 septembre 2020, ce n&rsquo;est pas une entreprise chinoise qui se voit attribuer la gestion de la PLT jusqu&rsquo;en 2052, mais la soci\u00e9t\u00e9 allemande Hamburger Hafen und Logistik (HHLA), bas\u00e9e \u00e0 Hambourg. Au moment de la signature de l&rsquo;accord, Zeno D&rsquo;Agostino pr\u00e9cise implicitement que le d\u00e9cor n\u2019est plus le m\u00eame&#160;: \u00ab&#160;L&rsquo;accord d\u00e9montre que la mise en \u0153uvre la plus compl\u00e8te des Nouvelles Routes de la soie ne s&rsquo;arr\u00eate pas \u00e0 l&rsquo;initiative Belt And Road men\u00e9e par la Chine. Jusqu&rsquo;\u00e0 pr\u00e9sent, il manquait une vision forte du c\u00f4t\u00e9 europ\u00e9en, capable d&rsquo;int\u00e9grer et d&rsquo;\u00e9quilibrer les points de vue et les int\u00e9r\u00eats de l&rsquo;Asie.&#160;\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le 29 septembre 2020, ce n&rsquo;est pas une entreprise chinoise qui se voit attribuer la gestion de la plateforme logistique de Trieste jusqu&rsquo;en 2052, mais la soci\u00e9t\u00e9 allemande Hamburger Hafen und Logistik (HHLA), bas\u00e9e \u00e0 Hambourg.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La trajectoire de l&rsquo;entreprise allemande t\u00e9moigne \u00e9galement du changement de contexte g\u00e9opolitique. HHLA n\u00e9gocie depuis des mois la vente de moins de 25&#160;% des parts de la soci\u00e9t\u00e9 Container Terminal Tollerort GmbH (CTT), qui exploite l&rsquo;un des principaux terminaux du port de Hambourg, \u00e0 l&rsquo;entreprise publique chinoise COSCO. L&rsquo;accord a fait l&rsquo;objet de plusieurs r\u00e9visions&#160;: initialement, les Chinois avaient l&rsquo;intention d&rsquo;acqu\u00e9rir une participation plus importante, mais le gouvernement f\u00e9d\u00e9ral a impos\u00e9 un plafond d&rsquo;un quart du capital. L&rsquo;accord, qui semblait \u00eatre conclu fin 2022, a \u00e9t\u00e9 remis en question d\u00e9but 2023, apr\u00e8s que le gouvernement f\u00e9d\u00e9ral a d\u00e9clar\u00e9 que les terminaux portuaires de Hambourg \u00e9taient des \u00ab&#160;infrastructures critiques&#160;\u00bb. Le 12 avril, le minist\u00e8re allemand de l&rsquo;\u00e9conomie avait annonc\u00e9 qu&rsquo;il se pronon\u00e7ait sur les modalit\u00e9s d&rsquo;entr\u00e9e de COSCO dans Container Terminal Tollerort GmbH (CTT), avant de conclure l&rsquo;op\u00e9ration le 10 mai, en accordant aux Chinois 24,9&#160;% des parts.<\/p>\n\n\n\n<p>La n\u00e9gociation a imm\u00e9diatement donn\u00e9 au gouvernement de Giorgia Meloni l&rsquo;occasion de souligner son hostilit\u00e9 aux accords d&rsquo;infrastructures avec la Chine, une sorte de pr\u00e9lude \u00e0 d&rsquo;\u00e9ventuelles d\u00e9cisions sur des dossiers li\u00e9s au M\u00e9morandum sign\u00e9 en 2019&#160;: \u00ab&#160;Nous ne nous rendrons pas aux mains des Chinois&#160;\u00bb, a r\u00e9pondu le ministre des Entreprises et du Made in Italy Adolfo Urso en octobre 2022 \u00e0 une question sur d&rsquo;\u00e9ventuels int\u00e9r\u00eats chinois dans le port de Trieste si l&rsquo;accord avec HHLA venait \u00e0 se concr\u00e9tiser. Notons en tout cas que COSCO n&rsquo;ach\u00e8te pas d&rsquo;actions de HHLA, mais seulement de la soci\u00e9t\u00e9 qu&rsquo;elle contr\u00f4le et qui g\u00e8re l&rsquo;un des principaux terminaux du port de Hambourg. En r\u00e9sum\u00e9, il s&rsquo;agit d&rsquo;un accord qui n&rsquo;a que peu d&rsquo;importance pour Trieste.<\/p>\n\n\n\n<p>En r\u00e9alit\u00e9, selon le <em>Secolo XIX<\/em>, COSCO s&rsquo;int\u00e9resse \u00e9galement aux anciennes emprises de l&rsquo;aci\u00e9rie Ilva \u00e0 G\u00eanes. COSCO Shipping Italy, en <em>joint venture<\/em> avec le groupe g\u00e9nois Fratelli Cosulich, a pr\u00e9sent\u00e9 une lettre, cit\u00e9e par le journal en ligne <em>Formiche<\/em>, dans laquelle elle fait part de son int\u00e9r\u00eat pour les zones situ\u00e9es dans la r\u00e9gion de G\u00eanes \u00ab&#160;en vue d&rsquo;un investissement pr\u00e9sent et futur sur le territoire ligure, avec des projets importants tels que la cr\u00e9ation d&rsquo;un parc automobile&#160;\u00bb. Cosco est \u00e9galement pr\u00e9sent \u00e0 Vado Ligure et a particip\u00e9 aux activit\u00e9s du port bien avant que l&rsquo;Italie ne rejoigne la Belt and Road Initiative. \u00ab&#160;En 2016, la soci\u00e9t\u00e9 a repris une partie du terminal, mais le projet n&rsquo;est entr\u00e9 dans le d\u00e9bat politique et public qu&rsquo;apr\u00e8s la signature du m\u00e9morandum&#160;\u00bb, ajoute Francesca Ghiretti. \u00ab&#160;G\u00eanes est un cas embl\u00e9matique qui nous montre l&rsquo;\u00e9volution de l&rsquo;\u00e9poque&#160;: en 2016, les accords sont pass\u00e9s inaper\u00e7us, tandis qu&rsquo;en 2019, ils sont devenus probl\u00e9matiques. Dans ces cas, il est clair que le m\u00e9morandum n&rsquo;a pas eu un impact particuli\u00e8rement positif&#160;: au contraire, il a attir\u00e9 les projecteurs, entravant les projets.&#160;\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La n\u00e9gociation a imm\u00e9diatement donn\u00e9 au gouvernement de Giorgia Meloni l&rsquo;occasion de souligner son hostilit\u00e9 aux accords d&rsquo;infrastructures avec la Chine, une sorte de pr\u00e9lude \u00e0 d&rsquo;\u00e9ventuelles d\u00e9cisions sur des dossiers li\u00e9s au M\u00e9morandum sign\u00e9 en 2019.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00ab&#160;Il faut faire tr\u00e8s attention \u00e0 la mani\u00e8re dont on annonce la sortie&#160;: personne ne veut d&rsquo;un conflit ouvert avec P\u00e9kin&#160;\u00bb<\/strong><\/h2>\n\n\n\n<p>Avec l&rsquo;arriv\u00e9e de Mario Draghi au gouvernement, la situation devient encore plus claire. Dans son premier discours au Parlement, le nouveau Pr\u00e9sident du Conseil ne mentionne la Chine qu&rsquo;une seule fois, et pas de mani\u00e8re positive&#160;: \u00ab&#160;Nous suivons \u00e9galement avec inqui\u00e9tude l&rsquo;augmentation des tensions en Asie autour de la Chine&#160;\u00bb, d\u00e9clare l&rsquo;ancien banquier central. L&rsquo;inqui\u00e9tude ne se limite pas \u00e0 l&rsquo;Asie, mais aussi aux activit\u00e9s chinoises en Italie&#160;: entre f\u00e9vrier 2021 et juin 2022, le gouvernement Draghi a utilis\u00e9 \u00e0 cinq reprises le golden power \u2014 les pouvoirs sp\u00e9ciaux accord\u00e9s \u00e0 l&rsquo;ex\u00e9cutif pour bloquer ou modifier les op\u00e9rations dans les entreprises publiques ou priv\u00e9es en cas \u00ab&#160;d&rsquo;existence d&rsquo;une menace de pr\u00e9judice grave pour les int\u00e9r\u00eats essentiels de la d\u00e9fense et de la s\u00e9curit\u00e9 nationale&#160;\u00bb \u2014 contre des investissements chinois.<\/p>\n\n\n\n<p>Giorgia Meloni arrive elle aussi au palais Chigi avec une r\u00e9putation plut\u00f4t anti-chinoise. Le 23 septembre 2022, deux jours avant le vote, elle accorde une interview \u00e0 la Central News Agency, l&rsquo;agence de presse de l&rsquo;\u00c9tat ta\u00efwanais. Dans cet entretien, Fratelli d&rsquo;Italia est qualifi\u00e9 de \u00ab&#160;parti ami de Ta\u00efwan&#160;\u00bb et Giorgia Meloni promet que l&rsquo;Italie, avec elle \u00e0 la t\u00eate du gouvernement, renforcera la coop\u00e9ration bilat\u00e9rale avec Taipei et condamnera fermement les menaces de la Chine \u00e0 l&rsquo;encontre de l&rsquo;int\u00e9grit\u00e9 territoriale de l&rsquo;\u00eele. Quelques jours plus t\u00f4t,&nbsp; Meloni avait rendu publique une rencontre avec le repr\u00e9sentant de Ta\u00efwan en Italie, Andrea Sing Ying Lee, autre \u00e9v\u00e9nement symbolique destin\u00e9 \u00e0 pr\u00e9ciser le cadre dans lequel la favorite des \u00e9lections l\u00e9gislatives entend \u00e9voluer une fois au pouvoir.<\/p>\n\n\n\n<p>Sur les Routes de la Soie, Giorgia Meloni a jusqu&rsquo;\u00e0 pr\u00e9sent exprim\u00e9 des positions claires. Elle a toujours critiqu\u00e9 le choix du gouvernement Conte, expliquant que l&rsquo;adh\u00e9sion au projet \u00e9tait une erreur&#160;: \u00ab&#160;Si je devais signer le renouvellement de ce m\u00e9morandum demain matin, je ne verrais pas les conditions politiques&#160;\u00bb, a-t-elle expliqu\u00e9 dans une interview accord\u00e9e \u00e0 l&rsquo;agence ta\u00efwanaise CNA. Le gouvernement italien a des positions tr\u00e8s divergentes sur la Russie, mais sur la Chine il semble plus qu&rsquo;uni&#160;: le parti Forza Italia de Silvio Berlusconi n&rsquo;a jamais aim\u00e9 P\u00e9kin, y compris pour des raisons id\u00e9ologiques anticommunistes, et la Ligue, apr\u00e8s la parenth\u00e8se jaune-vert pro-chinoise \u2014 qui, comme on l&rsquo;a vu, n&rsquo;\u00e9tait d\u00e9j\u00e0 pas tr\u00e8s enthousiaste \u2014 a maintenant une position atlantiste sur le dossier. Voil\u00e0 pour la coalition. Mais la haute administration italienne est \u00e9galement convaincue que la signature de 2019 \u00e9tait une erreur, et que le non-renouvellement est aujourd&rsquo;hui la seule option possible, comme a pu le v\u00e9rifier le Grand Continent apr\u00e8s de nombreuses conversations avec des officiels et diplomates italiens&#160;: \u00ab&#160;L&rsquo;accord, d&rsquo;un point de vue commercial, ne vaut pas grand-chose, et a \u00e9t\u00e9 progressivement vid\u00e9 de ses aspects op\u00e9rationnels. Cependant, symboliquement, il reste pertinent, il est difficile de le renouveler comme si rien ne s&rsquo;\u00e9tait pass\u00e9&#160;; bien s\u00fbr, il faut faire tr\u00e8s attention \u00e0 la mani\u00e8re dont on annonce la sortie, personne ne veut d&rsquo;un conflit ouvert avec P\u00e9kin&#160;\u00bb, souligne l&rsquo;un d&rsquo;eux.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Sur les Routes de la Soie, Giorgia Meloni a jusqu&rsquo;\u00e0 pr\u00e9sent exprim\u00e9 des positions claires. Elle a toujours critiqu\u00e9 le choix du gouvernement Conte, expliquant que l&rsquo;adh\u00e9sion au projet \u00e9tait une erreur.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le gouvernement italien n&rsquo;a pas encore annonc\u00e9 officiellement sa d\u00e9cision. Toutefois, de mani\u00e8re informelle, plusieurs membres de la majorit\u00e9, sans jamais \u00eatre explicitement nomm\u00e9s, ont fait part \u00e0 la presse de leur volont\u00e9 de ne pas renouveler l&rsquo;accord. D&rsquo;autre part, comme l&rsquo;a d\u00e9clar\u00e9 le ministre des affaires \u00e9trang\u00e8res Antonio Tajani au <em>Sole 24 Ore<\/em>&#160;: \u00ab&#160;Dans ce domaine, c&rsquo;est l&rsquo;Inde qui est en train de devenir notre partenaire strat\u00e9gique&#160;\u00bb. Et c&rsquo;est justement \u00e0 l&rsquo;Inde que Giorgia Meloni a consacr\u00e9 une visite de deux jours, sans oublier les autres partenaires choisis pour signer des m\u00e9morandums d&rsquo;entente, le Royaume-Uni et le Japon, avec lesquels l&rsquo;Italie a non seulement des accords commerciaux solides, mais aussi des accords militaires, comme le montre le programme Tempest pour le d\u00e9veloppement d&rsquo;un nouveau chasseur-bombardier.<\/p>\n\n\n\n<p>Selon diverses sources gouvernementales italiennes, la question n&rsquo;est pas de savoir si, mais comment et quand s\u2019organisera la sortie \u2014 une position qui est d\u00e9sormais consid\u00e9r\u00e9e comme acquise par Washington&#160;: \u00ab&#160;ce n&rsquo;est pas une question de si, mais de comment&#160;\u00bb, a r\u00e9p\u00e9t\u00e9 Jimmy Panetta, membre de la Chambre des repr\u00e9sentants des \u00c9tats-Unis, en visite en Italie le 9 juin dernier&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-190781' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#easy-footnote-bottom-4-190781' title='Marco Liconti, \u00ab&amp;#160;Giorgia sta superando le aspettative Usa. Il governo piace pure ai Democratici americani&amp;#160;\u00bb, &lt;em&gt;Il Giornale&lt;\/em&gt;, 9 juin 2023.'><sup>4<\/sup><\/a><\/span><\/span>, dans une interview accord\u00e9e \u00e0 <em>Il Giornale<\/em>. La d\u00e9cision semble donc prise, comme en t\u00e9moignent les nombreux articles de la presse italienne et internationale, o\u00f9 la fin du protocole d&rsquo;accord est consid\u00e9r\u00e9e comme acquise. L&rsquo;id\u00e9al, pour le gouvernement, serait donc \u00e0 ce stade de trouver un moyen de rendre le non-renouvellement le moins public possible, afin de rassurer les Am\u00e9ricains tout en minimisant les \u00e9ventuelles repr\u00e9sailles de P\u00e9kin. Mais pour Francesca Ghiretti, \u00ab&#160;maintenant que l&rsquo;affaire est publique et m\u00e9diatis\u00e9e, il est difficile de la garder sous les radars&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;id\u00e9al, pour le gouvernement Meloni, serait \u00e0 ce stade de trouver un moyen de rendre le non-renouvellement le moins public possible, afin de rassurer les Am\u00e9ricains tout en minimisant les \u00e9ventuelles repr\u00e9sailles de P\u00e9kin.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le 10 mai, en visite \u00e0 Prague, Giorgia Meloni s&rsquo;est exprim\u00e9e publiquement pour la premi\u00e8re fois sur le renouvellement du m\u00e9morandum&#160;: \u00ab&#160;C&rsquo;est une d\u00e9cision que nous n&rsquo;avons pas encore prise, c&rsquo;est un d\u00e9bat ouvert dans lequel je crois que les acteurs doivent \u00eatre nombreux et \u00e0 diff\u00e9rents niveaux. Le Parlement en fait partie. C&rsquo;est un d\u00e9bat que j&rsquo;ai d\u00e9j\u00e0 ouvert dans plusieurs enceintes comp\u00e9tentes. Il reste encore plusieurs mois pour prendre cette d\u00e9cision, qui est d\u00e9licate&#8230; Je n&rsquo;\u00e9tais pas d&rsquo;accord \u00e0 l&rsquo;\u00e9poque avec le choix que le gouvernement Conte a fait, mais aujourd&rsquo;hui il faut la traiter avec beaucoup de prudence parce que, de toute fa\u00e7on, il s&rsquo;agit d&rsquo;une situation qui touche \u00e0 de multiples dynamiques internationales.&#160;\u00bb<\/p>\n\n\n<section class=\"dive print-block my-16  \" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tDe l&rsquo;Ukraine au m\u00e9tavers\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Les clefs d&rsquo;un monde cass\u00e9.<\/p>\n<p>Du centre du globe \u00e0 ses fronti\u00e8res les plus lointaines, la guerre est l\u00e0. L\u2019invasion de l\u2019Ukraine par la Russie de Poutine nous a frapp\u00e9s, mais comprendre cet affrontement crucial n&rsquo;est pas assez.<\/p>\n<p>Notre \u00e8re est travers\u00e9e par un ph\u00e9nom\u00e8ne occulte et structurant, nous proposons de l\u2019appeler&#160;: guerre \u00e9tendue.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/precommandez-le-nouveau-numero\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Commandez le nouveau num\u00e9ro<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrez toutes nos offres<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/politiques-de-linterregne\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9j\u00e0 abonn\u00e9&#160;? commandez le num\u00e9ro pr\u00e9c\u00e9dent<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><em>Fractures de la guerre \u00e9tendue&#160;: de l\u2019Ukraine au m\u00e9tavers<\/em> est d\u00e9j\u00e0 disponible <a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/commandez-le-nouveau-numero\/\">\u00e0 l&rsquo;achat<\/a> et dans notre <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\">offre de lancement<\/a>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/mediamodifier_image-42-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>Pour l&rsquo;instant, quelques signaux faibles indiquent \u00e0 Rome qu&rsquo;il n&rsquo;y aura pas de renouvellement. Tout d&rsquo;abord, Ta\u00efwan a compris qu&rsquo;il \u00e9tait possible de renforcer sa pr\u00e9sence en Italie sans mettre le gouvernement actuel dans l&#8217;embarras. Le 17 avril 2023, le minist\u00e8re des affaires \u00e9trang\u00e8res a annonc\u00e9 l&rsquo;ouverture d&rsquo;un bureau de repr\u00e9sentation \u00e0 Milan&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-190781' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#easy-footnote-bottom-5-190781' title='Gabriele Carrer ed Emanuele Rossi, \u00ab&amp;#160;Taipei apre un ufficio a Milano, il secondo in Italia. Ecco perch\u00e9 \u00e8 importante&amp;#160;\u00bb, &lt;em&gt;Formiche&lt;\/em&gt;, 17 avril 2023.'><sup>5<\/sup><\/a><\/span><\/span> pour faciliter les relations commerciales et \u00e9conomiques et offrir des services consulaires et d&rsquo;urgence aux expatri\u00e9s ta\u00efwanais vivant et travaillant dans huit r\u00e9gions \u2014 Vall\u00e9e d&rsquo;Aoste, Pi\u00e9mont, Ligurie, Lombardie, \u00c9milie-Romagne, V\u00e9n\u00e9tie, Frioul-V\u00e9n\u00e9tie Julienne et Trentin-Haut-Adige. L&rsquo;annonce a \u00e9t\u00e9 suivie d&rsquo;une visite tr\u00e8s importante&#160;: le 17 juin, le ministre ta\u00efwanais des affaires \u00e9trang\u00e8res Joseph Wu a rencontr\u00e9 \u00e0 Milan deux d\u00e9put\u00e9s de la Ligue, Paolo Formentini et Igor Iezzi, et deux d\u00e9put\u00e9s de Fratelli d&rsquo;Italia, Emanuele Pozzolo et Gianpietro Maffoni. D&rsquo;autre part, Gian Marco Centinaio, vice-pr\u00e9sident du S\u00e9nat, a \u00e9t\u00e9 re\u00e7u \u00e0 Taipei par la pr\u00e9sidente Tsai Ing-wen lors d&rsquo;un voyage non officiel d&rsquo;une semaine.<\/p>\n\n\n\n<p>Le 16 juin, le gouvernement a fait usage de son <em>golden power<\/em> pour sauvegarder l&rsquo;autonomie de Pirelli, pr\u00e9cis\u00e9ment dans le but de limiter l&rsquo;influence chinoise au sein d&rsquo;une entreprise consid\u00e9r\u00e9e comme strat\u00e9gique. Cette d\u00e9cision fait suite au pacte d&rsquo;actionnaires sign\u00e9 entre Camfin, la soci\u00e9t\u00e9 de Marco Tronchetti Provera, qui d\u00e9tient 14&#160;% des actions de Pirelli, et Sinochem, soci\u00e9t\u00e9 chinoise et actionnaire majoritaire relatif avec 37&#160;% du capital. Ensemble, les deux entit\u00e9s contr\u00f4lent Pirelli, et l&rsquo;accord pr\u00e9voit une r\u00e9duction du nombre d&rsquo;administrateurs italiens au sein du conseil d&rsquo;administration et la possibilit\u00e9 pour Sinochem de nommer des postes ex\u00e9cutifs \u00e0 partir de 2026.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le 16 juin, le gouvernement a fait usage de son <em>golden power<\/em> pour sauvegarder l&rsquo;autonomie de Pirelli, pr\u00e9cis\u00e9ment dans le but de limiter l&rsquo;influence chinoise au sein d&rsquo;une entreprise consid\u00e9r\u00e9e comme strat\u00e9gique.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>\u00c0 travers cette intervention, le gouvernement veut poursuivre \u00ab&#160;l&rsquo;objectif de mettre en place un r\u00e9seau de mesures fonctionnant comme un tout pour prot\u00e9ger l&rsquo;autonomie de Pirelli et de sa direction, ainsi que pour prot\u00e9ger les technologies et les informations d&rsquo;importance strat\u00e9gique d\u00e9tenues par la soci\u00e9t\u00e9&#160;\u00bb, indique le communiqu\u00e9. Le d\u00e9cret \u00e9tablit explicitement que \u00ab&#160;l&rsquo;administrateur d\u00e9l\u00e9gu\u00e9 de Pirelli issu de la liste majoritaire sera d\u00e9sign\u00e9 par l&rsquo;actionnaire Camfin&#160;\u00bb, et pr\u00e9voit que \u00ab&#160;sur 12 administrateurs issus de la liste majoritaire, 4 seront d\u00e9sign\u00e9s par Camfin&#160;\u00bb, ce qui ne laisse que 8 administrateurs aux Chinois, alors que le pacte d&rsquo;actionnaires pr\u00e9voyait auparavant 9 administrateurs, sans oublier que \u00ab&#160;tous les organes d\u00e9l\u00e9gu\u00e9s par Pirelli seront identifi\u00e9s parmi les administrateurs d\u00e9sign\u00e9s par Camfin&#160;\u00bb et que les d\u00e9cisions sur les questions strat\u00e9giques doivent \u00eatre approuv\u00e9es par une majorit\u00e9 des 4\/5 au sein du conseil d&rsquo;administration. Au total, rien ne peut \u00eatre d\u00e9cid\u00e9 sans le consentement de l&rsquo;Italie.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000059-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000059-scaled-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000059-scaled-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000059-scaled-1340x894.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_00900361_000059-scaled-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Le pr\u00e9sident chinois Xi Jinping et la d\u00e9l\u00e9gation chinoise lors d&rsquo;une r\u00e9union avec le premier ministre italien Giuseppe Conte \u00e0 la Villa Madama \u00e0 Rome le 23 mars 2019. \u00a9 Alessandro Serrano&rsquo;\/AGF\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Le gouvernement est intervenu parce que Sinochem est une entreprise publique chinoise et, selon un d\u00e9cret de l&rsquo;administration Trump, employ\u00e9e par l&rsquo;arm\u00e9e chinoise, ce qui exposerait donc Pirelli \u00e0 d&rsquo;\u00e9ventuelles sanctions am\u00e9ricaines. L&rsquo;intervention est consid\u00e9r\u00e9e comme relativement peu invasive&#160;: selon la loi, le gouvernement aurait pu imposer un contr\u00f4le encore plus strict, en supprimant les droits de vote de Sinochem, ou m\u00eame en demandant \u00e0 l&rsquo;entreprise de r\u00e9duire sa participation. Le choix de Meloni est donc un signal fort adress\u00e9 \u00e0 P\u00e9kin et aux autres investisseurs chinois qui d\u00e9tiennent des participations dans des entreprises italiennes, mais il ne s&rsquo;agit pas d&rsquo;une d\u00e9claration de guerre.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La Chine cherche \u00e9videmment \u00e0 n\u00e9gocier un point d&rsquo;atterrissage.<\/p><cite>Francesco Maselli<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Selon le journal <em>Il Foglio<\/em>, la Farnesina \u00ab&#160;travaillerait sur un document &lsquo;alternatif&rsquo;&#160;\u00bb au M\u00e9morandum, afin de donner un nouveau cadre aux relations bilat\u00e9rales. Le minist\u00e8re des Affaires \u00e9trang\u00e8res et le Palais Chigi ne confirment toutefois pas cette possibilit\u00e9, se r\u00e9f\u00e9rant aux propos de la Pr\u00e9sidente du Conseil&#160;: pour l&rsquo;instant, les discussions au sein de l&rsquo;ex\u00e9cutif portent sur le renouvellement ou non de l&rsquo;accord, et non sur son remplacement par un accord \u00e0 ren\u00e9gocier. \u00c0 ce stade, il est probable qu&rsquo;il faudra attendre plusieurs semaines pour conna\u00eetre la d\u00e9cision de Giorgia Meloni \u2014 et il n&rsquo;est pas exclu que la question soit abord\u00e9e publiquement, au cours d&rsquo;un d\u00e9bat parlementaire, ou en tout cas \u00e9largie aux repr\u00e9sentants politiques pr\u00e9sents dans les deux Chambres, au sein du Comit\u00e9 pour la s\u00e9curit\u00e9 de la R\u00e9publique (COPASIR)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-190781' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#easy-footnote-bottom-6-190781' title='Giulia Pompili, \u00ab&amp;#160;Copasir&amp;#160;? Dibattito in Aula&amp;#160;? Nessuno sa uscire dalla Via della Seta, pare&amp;#160;\u00bb, &lt;em&gt;Il Foglio&lt;\/em&gt;, 1 juin 2023.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Entre-temps, la Chine cherche \u00e9videmment \u00e0 n\u00e9gocier un point d&rsquo;atterrissage. Selon les r\u00e9v\u00e9lations d&rsquo;<em>Il Foglio<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-190781' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#easy-footnote-bottom-7-190781' title='Giulia Pompili, \u00ab&amp;#160;Pechino fa lobby per la Via della seta a Roma&amp;#160;\u00bb, &lt;em&gt;Il Foglio&lt;\/em&gt;, 16 juin 2023.'><sup>7<\/sup><\/a><\/span><\/span>, Liu Jianchao, ministre en charge du d\u00e9partement des relations internationales du Parti communiste chinois, \u00e9tait en mission diplomatique \u00e0 Rome du 25 au 27 juin&#160;: il a rencontr\u00e9 le pr\u00e9sident du S\u00e9nat Ignazio La Russa et le ministre des Affaires \u00e9trang\u00e8res Antonio Tajani, puis s&rsquo;est \u00e9galement entretenu avec la secr\u00e9taire du Parti d\u00e9mocrate, Elly Schlein. Apr\u00e8s tout, jusqu&rsquo;\u00e0 la fin de l&rsquo;ann\u00e9e, il reste du temps pour n\u00e9gocier.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9but 2024, l\u2019Italie devra officiellement annoncer si elle d\u00e9cide ou non de prolonger le M\u00e9morandum sur son appartenance \u00e0 l\u2019Initiative Belt &amp; Road, sign\u00e9 en 2019 par Giuseppe Conte. Si Giorgia Meloni a d\u00e9j\u00e0 montr\u00e9 ses distances, la mani\u00e8re dont Rome pourrait se retirer du protocole d\u2019accord n\u2019a rien d\u2019\u00e9vident. Nous avons interrog\u00e9 les principaux acteurs sur ce dossier pour comprendre comment l\u2019Italie a pu se retrouver dans cette impasse diplomatique \u2014 et quelles sont ses chances d\u2019en sortir indemne.<\/p>\n<p>Une \u00e9tude en rouge sign\u00e9e Francesco Maselli.<\/p>\n","protected":false},"author":10,"featured_media":190791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":30,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1731],"tags":[],"staff":[1635],"editorial_format":[4849],"serie":[],"audience":[],"geo":[543],"class_list":["post-190781","post","type-post","status-publish","format-standard","hentry","category-politique","staff-francesco-maselli","editorial_format-etudes","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":190791,"excerpt":"D\u00e9but 2024, l\u2019Italie devra officiellement annoncer si elle d\u00e9cide ou non de prolonger le M\u00e9morandum sur son appartenance \u00e0 l\u2019Initiative Belt & Road, sign\u00e9 en 2019 par Giuseppe Conte. Si Giorgia Meloni a d\u00e9j\u00e0 montr\u00e9 ses distances, la mani\u00e8re dont Rome pourrait se retirer du protocole d\u2019accord n\u2019a rien d\u2019\u00e9vident. Nous avons interrog\u00e9 les principaux acteurs sur ce dossier pour comprendre comment l\u2019Italie a pu se retrouver dans cette impasse diplomatique \u2014 et quelles sont ses chances d\u2019en sortir indemne.\r\n\r\nUne \u00e9tude en rouge sign\u00e9e Francesco Maselli.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le casse-t\u00eate chinois de Meloni : enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le casse-t\u00eate chinois de Meloni : enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"D\u00e9but 2024, l\u2019Italie devra officiellement annoncer si elle d\u00e9cide ou non de prolonger le M\u00e9morandum sur son appartenance \u00e0 l\u2019Initiative Belt &amp; Road, sign\u00e9 en 2019 par Giuseppe Conte. Si Giorgia Meloni a d\u00e9j\u00e0 montr\u00e9 ses distances, la mani\u00e8re dont Rome pourrait se retirer du protocole d\u2019accord n\u2019a rien d\u2019\u00e9vident. Nous avons interrog\u00e9 les principaux acteurs sur ce dossier pour comprendre comment l\u2019Italie a pu se retrouver dans cette impasse diplomatique \u2014 et quelles sont ses chances d\u2019en sortir indemne.  Une \u00e9tude en rouge sign\u00e9e Francesco Maselli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-09T16:31:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-09T16:32:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-rossotorino-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-rossotorino-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/\",\"name\":\"Le casse-t\u00eate chinois de Meloni : enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg\",\"datePublished\":\"2023-07-09T16:31:30+00:00\",\"dateModified\":\"2023-07-09T16:32:57+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg\",\"width\":2560,\"height\":1448,\"caption\":\"Le caract\u00e8re chinois \\\"Fu\\\", qu'on pourrait traduire par \u00abbonne fortune\u00bb et projet\u00e9 sur fond rouge sur la Mole Antonelliana pour c\u00e9l\u00e9brer le Nouvel An chinois \u00e0 Turin le 21 janvier 2023. \u00a9 Federico Tardito\/Xinhua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le casse-t\u00eate chinois de Meloni&#160;: enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le casse-t\u00eate chinois de Meloni : enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/","og_locale":"fr_FR","og_type":"article","og_title":"Le casse-t\u00eate chinois de Meloni : enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie | Le Grand Continent","og_description":"D\u00e9but 2024, l\u2019Italie devra officiellement annoncer si elle d\u00e9cide ou non de prolonger le M\u00e9morandum sur son appartenance \u00e0 l\u2019Initiative Belt &amp; Road, sign\u00e9 en 2019 par Giuseppe Conte. Si Giorgia Meloni a d\u00e9j\u00e0 montr\u00e9 ses distances, la mani\u00e8re dont Rome pourrait se retirer du protocole d\u2019accord n\u2019a rien d\u2019\u00e9vident. Nous avons interrog\u00e9 les principaux acteurs sur ce dossier pour comprendre comment l\u2019Italie a pu se retrouver dans cette impasse diplomatique \u2014 et quelles sont ses chances d\u2019en sortir indemne.  Une \u00e9tude en rouge sign\u00e9e Francesco Maselli.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/","og_site_name":"Le Grand Continent","article_published_time":"2023-07-09T16:31:30+00:00","article_modified_time":"2023-07-09T16:32:57+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-rossotorino-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-rossotorino-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"30 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/","name":"Le casse-t\u00eate chinois de Meloni : enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg","datePublished":"2023-07-09T16:31:30+00:00","dateModified":"2023-07-09T16:32:57+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg","width":2560,"height":1448,"caption":"Le caract\u00e8re chinois \"Fu\", qu'on pourrait traduire par \u00abbonne fortune\u00bb et projet\u00e9 sur fond rouge sur la Mole Antonelliana pour c\u00e9l\u00e9brer le Nouvel An chinois \u00e0 Turin le 21 janvier 2023. \u00a9 Federico Tardito\/Xinhua"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/07\/09\/le-casse-tete-chinois-de-meloni-enquete-au-coeur-de-litalie-des-nouvelles-routes-de-la-soie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le casse-t\u00eate chinois de Meloni&#160;: enqu\u00eate au c\u0153ur de l\u2019Italie des Nouvelles Routes de la soie"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1635,"name":"Francesco Maselli","slug":"francesco-maselli","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg","width":2560,"height":1448,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/SIPA_01100320_000005-scaled.jpg","width":2560,"height":1448,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/190781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=190781"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/190781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/190791"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=190781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=190781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=190781"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=190781"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=190781"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=190781"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=190781"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=190781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}