{"id":189281,"date":"2023-06-25T12:57:22","date_gmt":"2023-06-25T10:57:22","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=189281"},"modified":"2023-08-21T17:14:17","modified_gmt":"2023-08-21T15:14:17","slug":"le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/","title":{"rendered":"Le conflit, l&rsquo;\u00e9thique, la guerre, l&rsquo;honneur&#160;: valeurs de Cormac McCarthy"},"content":{"rendered":"\n<p class=\"intro\">Mon premier livre de Cormac McCarthy \u00e9tait <em>La Route<\/em>. Je l&rsquo;ai lu pendant la pand\u00e9mie, lors du deuxi\u00e8me confinement. Je ne suis pas un lecteur syst\u00e9matique. Au milieu des myriades d\u2019essais qui rythment mon travail quotidien, je lis des romans sans aucun fil conducteur, m\u00e9langeant les genres et les \u00e9poques. Pourtant, et alors que je connaissais \u00e0 peine le nom de cet \u00e9crivain am\u00e9ricain lorsque je l\u2019ai commenc\u00e9 \u2014 il ne faut jamais s\u2019\u00e9tonner de sa propre ignorance \u2014, j&rsquo;ai lu l&rsquo;ensemble de son \u0153uvre en moins de trois ans. Je suis un amateur et je n&rsquo;ai donc aucune pr\u00e9tention critique, je voudrais simplement rendre hommage \u00e0 un grand \u00e9crivain, qui \u00e9tait sans doute plus qu&rsquo;un \u00e9crivain&#160;: un classique assur\u00e9ment, et peut-\u00eatre l&rsquo;un des grands humanistes de notre \u00e9poque.&nbsp;<\/p>\n\n\n\n<p class=\"intro\"><em>La Route <\/em>se d\u00e9roule dans un monde post-apocalyptique, racontant le voyage d&rsquo;un p\u00e8re et de son fils dans un monde d\u00e9vast\u00e9 et terrifiant. Je l&rsquo;ai lu alors que mon fils n&rsquo;avait que quelques mois&#160;; ma femme me l&rsquo;avait offert pendant que nous \u00e9tions clo\u00eetr\u00e9s chez nous \u00e0 cause d&rsquo;un virus meurtrier et d\u00e9vastateur. C&rsquo;est peut-\u00eatre pour toutes ces raisons que je me suis attach\u00e9 \u00e0 McCarthy. Mais au-del\u00e0 des contingences, d\u00e8s cette premi\u00e8re rencontre litt\u00e9raire, c&rsquo;est l&rsquo;esprit biblique et la puissance de sa prose qui ont retenu toute mon attention. Cormac nous plonge d&#8217;embl\u00e9e dans la solennit\u00e9 et la confrontation avec l&rsquo;infini.<\/p>\n\n\n\n<p>\u00ab&#160;Je te parlerai tous les jours, chuchotait-il. Et je n\u2019oublierai pas. Quoi qu\u2019il arrive. Puis il se releva et fit demi-tour et retourna sur la route. La femme quand elle le vit l\u2019entoura de ses bras et le serra contre elle. Oh, dit-elle, je suis si contente de te voir. Elle lui parlait quelquefois de Dieu. Il essayait de parler \u00e0 Dieu mais le mieux c\u2019\u00e9tait de parler \u00e0 son p\u00e8re et il lui parlait vraiment et il n\u2019oubliait pas. La femme disait que c\u2019\u00e9tait bien. Elle disait que le souffle de Dieu \u00e9tait encore le souffle de son p\u00e8re bien qu\u2019il passe d\u2019une cr\u00e9ature humaine \u00e0 une autre au fil des temps \u00e9ternels. Autrefois il y avait des truites de torrent dans les montagnes. On pouvait les voir immobiles dress\u00e9es dans le courant couleur d\u2019ambre o\u00f9 les bordures blanches de leurs nageoires ondulaient doucement au fil de l\u2019eau. Elles avaient un parfum de mousse quand on les prenait dans la main. Lisses et muscl\u00e9es et \u00e9lastiques. Sur leur dos il y avait des dessins en pointill\u00e9 qui \u00e9taient des cartes du monde en son devenir. Des cartes et des labyrinthes. D\u2019une chose qu\u2019on ne pourrait pas refaire. Ni r\u00e9parer. Dans les vals profonds qu\u2019elles habitaient toutes les choses \u00e9taient plus anciennes que l\u2019homme et leur murmure \u00e9tait de myst\u00e8re.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-1-189281' title='Cormac McCarthy, &lt;em&gt;La Route&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch, Paris, L\u2019Olivier, 2008, p. 244-245.'><sup>1<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Le souffle de Melville, les concepts de Flannery O&rsquo;Connor, le toucher stylistique de William Faulkner. Il n&rsquo;y a pas de fioritures chez McCarthy, qui est aussi sec, dur et essentiel que le sont les classiques. Il ne traite dans ses romans que des questions fondamentales comme, la relation entre l&rsquo;homme et la nature, ou entre l&rsquo;homme et la catastrophe.&nbsp;<\/p>\n\n\n\n<p>\u00ab&#160;\u00c7a va&#160;? dit-il. Le petit opina de la t\u00eate. Puis ils repartirent le long du macadam dans la lumi\u00e8re couleur m\u00e9tal de fusil, pataugeant dans la cendre, chacun tout l\u2019univers de l\u2019autre.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-2-189281' title='Cormac McCarthy, &lt;em&gt;La Route&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch, Paris, L\u2019Olivier, 2008, p. 11.'><sup>2<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Pour nous autres politologues, qui trouvons un esprit burk\u00e9en \u00e0 ses romans, il parle aussi de la libert\u00e9 humaine et de ses limites naturelles, des liens que l\u2019homme entretient avec le pass\u00e9, de la force des institutions, d\u2019une connaissance humaine toujours ind\u00e9finie et limit\u00e9e.&nbsp;<\/p>\n\n\n\n<p>\u00ab&#160;Chacun cherche sa propre destin\u00e9e et aucune autre, dit le juge. Bon gr\u00e9 mal gr\u00e9. En fin de compte quiconque pourrait y d\u00e9couvrir son propre destin et donc choisir une direction oppos\u00e9e arriverait fatalement au m\u00eame r\u00e9sultat, \u00e0 la m\u00eame heure fix\u00e9e d\u2019avance, car la destin\u00e9e de tout homme est aussi vaste que le monde qu\u2019il habite et contient en elle tous ses contraires. Ce d\u00e9sert sur lequel tant d\u2019hommes sont venus se briser est immense et exige de l\u2019homme un grand c\u0153ur mais finalement il est vide aussi. Il est cruel. Il est st\u00e9rile. Sa vraie nature est la pierre.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-3-189281' title='Cormac McCarthy, &lt;em&gt;M\u00e9ridien de sang&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch, Paris, Gallimard, 1988, p. 376.'><sup>3<\/sup><\/a><\/span><\/span><\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tLa guerre s&rsquo;\u00e9tend\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Les clefs d&rsquo;un monde cass\u00e9.<\/p>\n<p>Du centre du globe \u00e0 ses fronti\u00e8res les plus lointaines, la guerre est l\u00e0. L\u2019invasion de l\u2019Ukraine par la Russie de Poutine nous a frapp\u00e9s, mais comprendre cet affrontement crucial n&rsquo;est pas assez.<\/p>\n<p>Notre \u00e8re est travers\u00e9e par un ph\u00e9nom\u00e8ne occulte et structurant, nous proposons de l\u2019appeler&#160;&#160;: guerre \u00e9tendue.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/precommandez-le-nouveau-numero\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Commandez le nouveau num\u00e9ro<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrez toutes nos offres<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#8d938c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/politiques-de-linterregne\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9j\u00e0 abonn\u00e9&#160;? commandez le num\u00e9ro pr\u00e9c\u00e9dent<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><em>Fractures de la guerre \u00e9tendue&#160;&#160;: de l\u2019Ukraine au m\u00e9tavers<\/em> est d\u00e9j\u00e0 disponible <a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/commandez-le-nouveau-numero\/\">\u00e0 l&rsquo;achat<\/a> et dans notre <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\">offre de lancement<\/a>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/fr\/offre\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/mediamodifier_image-42-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>\u00ab&#160;Le monde de nos p\u00e8re r\u00e9side en nous. Dix mille g\u00e9n\u00e9rations et davantage. Une forme sans histoire n\u2019a pas le pouvoir de se perp\u00e9tuer. Ce qui n&rsquo;a pas de pass\u00e9 ne peut avoir d\u2019avenir. Au centre de notre vie il y a l\u2019histoire dont elle est faite et dans ce centre il n\u2019y a point d\u2019idiomes mais seulement l\u2019acte de connaissance et c&rsquo;est cela que nous partageons dans les r\u00eaves et en dehors des r\u00eaves.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-4-189281' title='Cormac McCarthy, &lt;em&gt;Des villes dans la plaine&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, L\u2019Olivier, 1999, p. 302.'><sup>4<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>\u00ab&#160;L&rsquo;h\u00e9ritage du verbe est chose fragile malgr\u00e9 toute sa puissance, mais je sais o\u00f9 tu te situes, Messire. Je sais qu\u2019il y a des mots prononc\u00e9s par des hommes morts depuis des si\u00e8cles qui jamais ne d\u00e9serteront ton c\u0153ur&#160;\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-5-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 191.'><sup>5<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">On touche ici \u00e0 la question charni\u00e8re de la transmission humaine, le pass\u00e9 p\u00e9n\u00e9trant dans le pr\u00e9sent, une arche entre les p\u00e8res et les fils, ce lien indissoluble entre la mort et la vie, entre les choses abandonn\u00e9es et les biens qui furent transmis.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Ce sont les seules prises sur la v\u00e9rit\u00e9, les seules certitudes terrestres, exprim\u00e9es brutalement par McCarthy, qui reprend un<em> topos <\/em>typique du XXe si\u00e8cle, \u00e0 savoir le d\u00e9calage entre l&rsquo;utopie et la r\u00e9alit\u00e9, entre le r\u00eave et le concret. Sans faux-semblants, sans chercher \u00e0 faire passer la pilule, plein d\u2019une sorte de nostalgie essentielle, le grand Am\u00e9ricain marque une rupture.<\/p>\n\n\n\n<p>\u00ab&#160;Nous nous souvenons \u00e0 notre r\u00e9veil des \u00e9v\u00e9nements dont ils se composent alors que le r\u00e9cit est souvent fugace et difficile \u00e0 retenir. C\u2019est pourtant le r\u00e9cit qui donne vie au r\u00eave alors que les \u00e9v\u00e9nements eux-m\u00eames sont souvent interchangeables. D\u2019un autre c\u00f4t\u00e9 les \u00e9v\u00e9nements qui se produisent quand nous sommes \u00e9veill\u00e9s nous sont impos\u00e9s et le r\u00e9cit est l\u2019axe insoup\u00e7onn\u00e9 autour duquel leur trame doit \u00eatre tiss\u00e9e. Il nous appartient de peser et de trier et d\u2019ordonner ces \u00e9v\u00e9nements. C\u2019est nous qui les assemblons pour en faire l\u2019histoire que nous sommes nous. Tout homme est le po\u00e8te de sa propre existence. C\u2019est ainsi qu\u2019il se rattache au monde. Car s\u2019il s\u2019\u00e9vade du monde qu\u2019il a r\u00eav\u00e9 cette \u00e9vasion est \u00e0 la fois sa punition et sa r\u00e9compense.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-6-189281' title='Cormac McCarthy, &lt;em&gt;Des villes dans la plaine&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, L\u2019Olivier, 1999, p. 304.'><sup>6<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">L&rsquo;histoire est l&rsquo;axe avec lequel il faut composer, tandis que le r\u00eave induit chaque homme en erreur. S&rsquo;ensuit une conception chr\u00e9tienne des limites de l&rsquo;\u00eatre humain&#160;; de la n\u00e9cessit\u00e9 d&rsquo;accepter le monde comme le lieu inhospitalier qu&rsquo;il est&#160;; de l&rsquo;in\u00e9luctabilit\u00e9 d&rsquo;un destin qui ressemble \u00e0 la Providence et qui peut \u00eatre compris mais jamais d\u00e9tourn\u00e9&#160;; de l&rsquo;impuissance de l&rsquo;homme dans un lieu o\u00f9, la plupart du temps, il est perdu&#160;; qui n&rsquo;est ni connaissable ni dominable et qui, t\u00f4t ou tard, foulera ses d\u00e9sirs aux pieds.<\/p>\n\n\n\n<p>\u00ab&#160;On n\u2019\u00e9voque que le monde qui a \u00e9t\u00e9 fa\u00e7onn\u00e9 par Dieu et ce monde-l\u00e0 seulement. Cette vie qui est tienne \u00e0 laquelle tu accordes tant de prix n\u2019est pas non plus ton ouvrage, aussi fort que tu l\u2019affirmes. Cette forme a \u00e9t\u00e9 impos\u00e9e au n\u00e9ant d\u00e8s l\u2019origine et tout bavardage sur ce qui aurait pu tourner autrement est absurde car il n\u2019y a pas d\u2019autrement. De quoi pourrait-il \u00eatre fait&#160;? O\u00f9 pourrait-il se cacher&#160;? Ou comment pourrait-il se manifester&#160;? La probabilit\u00e9 du r\u00e9el est absolue. Que nous n\u2019ayons pas le pouvoir de la deviner par avance ne le rend pas moins certain. Que l\u2019on puisse imaginer diff\u00e9rents parcours possibles ne signifie absolument rien.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-7-189281' title='Cormac McCarthy, &lt;em&gt;Des villes dans la plaine&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, L\u2019Olivier, 1999, p. 306.'><sup>7<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Si telles sont les conditions de l\u2019insignifiance humaine, alors on ne peut que s&rsquo;efforcer de croire, de porter ce \u00ab&#160;feu&#160;\u00bb que le p\u00e8re et le fils de <em>La Route<\/em> imaginent, de supporter les fusillades et la violence de la trilogie des confins, ou les atrocit\u00e9s du Far West de <em>M\u00e9ridien de sang<\/em>.<\/p>\n\n\n\n<p>\u00ab&#160;Il souleva du feuillage la t\u00eate raidie pour la tenir entre ses mains ou plut\u00f4t il fit le geste de tenir ce qui ne peut \u00eatre tenu, ce qui \u00e9tait d\u00e9j\u00e0 parti courir par les montagnes, \u00e0 la fois terrible et d\u2019une grande beaut\u00e9, comme des fleurs qui se nourrissent de chair. Ce dont sont faits la chair et le sang et les os mais qu\u2019ils ne peuvent eux-m\u00eames cr\u00e9er ni sur un autel ni par blessure de guerre. Ce qui, nous pouvons bien le croire, a le pouvoir de d\u00e9couper et de modeler et de ciseler la sombre forme du monde, sans nulle doute si le vent le peut, si la pluie le peut. Mais qui ne peut \u00eatre tenu jamais \u00eatre tenu et n\u2019est point une fleur mais qui est prompt et qui est chasseresse et le vent lui-m\u00eame en est terrifi\u00e9 et le monde ne peut pas le perdre.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-8-189281' title='Cormac McCarthy, &lt;em&gt;Le grand passage&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Seuil, 2000, p. 145.'><sup>8<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">La d\u00e9votion, la foi et la gratitude sont les sentiments de r\u00e9signation et d&rsquo;espoir que l\u2019homme doit glaner pour survivre \u00e0 une nature maligne et aux limites impuissantes de sa connaissance.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">C&rsquo;est justement parce que la nature est terrible et insondable qu&rsquo;elle doit \u00eatre contempl\u00e9e et v\u00e9n\u00e9r\u00e9e comme une d\u00e9tentrice du myst\u00e8re de la vie.<\/p>\n\n\n\n<p>\u00ab&#160;Il dit que les hommes croient que le sang de la victime mise \u00e0 mort ne compte pas, mais le loup est plus clairvoyant. Il dit que le loup est d\u2019abord une cr\u00e9ature d\u2019ordre et que le loup sait ce que les hommes ne savent pas&#160;: qu\u2019il n\u2019est d\u2019autre ordre dans le monde que celui que la mort y a mis.&#160;! dit pour finir que si les hommes boivent le sang de Dieu ils ne comprennent pas le s\u00e9rieux de ce qu\u2019ils font. Il dit que les hommes veulent \u00eatre s\u00e9rieux mais ne comprennent pas comment il faut s\u2019y prendre pour l&rsquo;\u00eatre. Entre leurs actes et leurs rites il y a l\u2019univers et dans cet univers soufflent des temp\u00eates et les arbres se tordent dans le vent et tous les animaux que Dieu a cr\u00e9\u00e9s vont et viennent mais ce monde-l\u00e0 les hommes ne le voient pas. Ils voient les actes de leurs propres mains ou bien ils voient ce qu\u2019ils d\u00e9signent d\u2019un nom et qu\u2019ils se d\u00e9signent les uns aux autres mais le monde qu\u2019il y \u00e0 entre tout cela leur reste cach\u00e9.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-9-189281' title='Cormac McCarthy, &lt;em&gt;Le grand passage&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Seuil, 2000, p. 55-56.'><sup>9<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Il en r\u00e9sulte une m\u00e9fiance \u00e0 l&rsquo;\u00e9gard de la raison et de ses instruments que McCarthy, par la bouche de ses cow-boys, jette \u00e0 la figure du lecteur europ\u00e9en d\u00e8s les premi\u00e8res pages de <em>Si jolis chevaux<\/em>.<\/p>\n\n\n\n<p>\u00ab&#160;Il me semble que nous ne croyons plus que la raison puisse am\u00e9liorer la nature humaine. C\u2019est une id\u00e9e bien fran\u00e7aise \u00e0 mon avis.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-10-189281' title='Cormac McCarthy, &lt;em&gt;De si jolis chevaux&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Actes Sud, 1993, p. 166.'><sup>10<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>\u00ab&#160;Sa foi en la bont\u00e9 fondamentale de l\u2019esp\u00e8ce humaine est devenue sa perte.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-11-189281' title='Cormac McCarthy, &lt;em&gt;De si jolis chevaux&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Actes Sud, 1993, p. 267.'><sup>11<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>\u00ab&#160;Celui qui croit que les secrets de l\u2019univers sont \u00e0 jamais cach\u00e9s vit dans le myst\u00e8re et la peur. La superstition le m\u00e8nera \u00e0 sa perte. Les \u0153uvres de sa vie seront \u00e9rod\u00e9es par les pluies. Mais celui qui s\u2019est donn\u00e9 pour t\u00e2che de trouver dans la tapisserie le fil conducteur de l\u2019ordre aura par cette seule d\u00e9cision assum\u00e9 la responsabilit\u00e9 de l\u2019univers et ce n\u2019est qu\u2019en assumant cette responsabilit\u00e9 qu\u2019il peut trouver le moyen de dicter les clauses de son propre destin.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-12-189281' title='Cormac McCarthy, &lt;em&gt;M\u00e9ridien de sang&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch, Paris, Gallimard, 1988, p. 230.'><sup>12<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Pour autant, il ne s\u2019agit pas de renoncer, de s\u2019abandonner aux facilit\u00e9s de la pens\u00e9e magique ou d\u2019admettre ses propres limites.<\/p>\n\n\n\n<p>\u00ab&#160;Il dit que le monde ne peut \u00eatre connu que tel qu\u2019il existe dans le c\u0153ur des hommes. Car si le monde semble \u00eatre un lieu o\u00f9 r\u00e9sident les hommes c\u2019est dans l\u2019homme en r\u00e9alit\u00e9 que r\u00e9side le monde et pour le conna\u00eetre c\u2019est donc l\u00e0 qu\u2019il faut chercher et apprendre \u00e0 conna\u00eetre le c\u0153ur des hommes et pour cela il faut vivre avec les hommes sans se contenter de passer parmi eux.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-13-189281' title='Cormac McCarthy, &lt;em&gt;Le grand passage&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Seuil, 2000, p. 152-153.'><sup>13<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">La synth\u00e8se entre l\u2019id\u00e9e d\u2019un fil rouge qui serait la trame de tout et le rejet du rationalisme aboutit \u00e0 un romantisme original, forg\u00e9 par les sentiments face \u00e0 un monde impitoyable et manich\u00e9en.<\/p>\n\n\n\n<p>\u00ab&#160;Or que sommes-nous&#160;? Dix pour cent de biologie et quatre-vingt-dix pour cent de rumeur nocturne&#160;\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-14-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 529.'><sup>14<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Ce concept r\u00e9appara\u00eet dans <em>Le Passager<\/em>, paru plus r\u00e9cemment, qui s\u2019interroge sur le myst\u00e8re de l\u2019homme.<\/p>\n\n\n\n<p class=\"comment\">Sans myst\u00e8re, sans c\u0153ur, la raison se transforme en un monstre aride et mortel car elle est capable d&rsquo;annihiler toutes les diff\u00e9rence sont les sources de l\u2019\u00e9lan vital.&nbsp;<\/p>\n\n\n\n<p>\u00ab&#160;Le choix d\u2019un homme plut\u00f4t que d\u2019un autre est une pr\u00e9f\u00e9rence absolue et irr\u00e9vocable et il faudrait \u00eatre assur\u00e9ment bien stupide pour croire qu\u2019une aussi lourde d\u00e9cision est sans autorit\u00e9 ou sans signification, \u00e0 votre choix. Dans ces parties qui ont pour enjeu l\u2019annihilation du vaincu les d\u00e9cisions sont tout \u00e0 fait claires. L\u2019homme qui tient tel assortiment de cartes dans sa main est du m\u00eame coup ray\u00e9 de l\u2019existence. C\u2019est la nature m\u00eame de la guerre dont l\u2019enjeu est \u00e0 la fois le jeu et la puissance et la justification. Vue sous cet angle la guerre est la forme la plus vraie de la divination. C\u2019est la confrontation de la volont\u00e9 d\u2019un homme et de la volont\u00e9 d\u2019un autre au sein de cette volont\u00e9 plus vaste qui se trouve contrainte de choisir parce qu\u2019elle est ce qui les unit. La guerre est le jeu supr\u00eame parce que la guerre est en fin de compte une manifestation forc\u00e9e de l\u2019unit\u00e9 de l\u2019existence. La guerre c\u2019est Dieu.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-15-189281' title='Cormac McCarthy, &lt;em&gt;M\u00e9ridien de sang&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch, Paris, Gallimard, 1988, p. 286-287.'><sup>15<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Un tel postulat conduit \u00e0 une vision politique qui m\u00eale le scepticisme m\u00e9thodologique du conservateur \u00e0 une vision hobbesienne de la vie associ\u00e9e. C\u2019est ce que McCarthy fait dire au juge Holden, qui est sans doute son personnage le plus r\u00e9ussi, tant il allie \u00e0 parts \u00e9gale la cruaut\u00e9 et la sagesse.<\/p>\n\n\n\n<p>\u00ab&#160;Mais bien s\u00fbr la vraie menace pour le transgresseur ce n\u2019est pas la soci\u00e9t\u00e9 juste mais la soci\u00e9t\u00e9 d\u00e9cadente. C&rsquo;est l\u00e0 qu\u2019il se d\u00e9couvre de moins en moins distinct de la communaut\u00e9. Il se retrouve coopt\u00e9. Il est difficile de nos jours d\u2019\u00eatre un rou\u00e9 ou un coquin. Un libertin. Un d\u00e9viant&#160;? Un pervers&#160;? Vous plaisantez, j\u2019esp\u00e8re. Les indulgences nouvelles ont pratiquement \u00e9limin\u00e9 ces cat\u00e9gories de la langue. On ne peut plus \u00eatre une femme de mauvaise vie. \u00c0 titre d\u2019exemple. Une gourgandine. Le concept m\u00eame n\u2019a plus de sens. On ne peut m\u00eame plus \u00eatre un drogu\u00e9. Au mieux on est un consommateur. Un consommateur&#160;? Qu&rsquo;est-ce que c\u2019est que cette connerie&#160;? En une poign\u00e9e d\u2019ann\u00e9es on est pass\u00e9 d\u2019opiomanes \u00e0 consommateurs. Pas besoin d\u2019\u00eatre Nostradamus pour voir vers quoi on s\u2019achemine. Les plus ha\u00efssables des criminels r\u00e9clameront un statut. Les tueurs en s\u00e9rie et les cannibales revendiqueront le droit \u00e0 leur mode de vie. Et comme tout le monde j\u2019essaie de me situer dans cette m\u00e9nagerie. Sans les malfaisants le monde des vertueux est d\u00e9pouill\u00e9 de toute signification&#160;\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-16-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 197-198.'><sup>16<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Dans <em>Le Passager<\/em> r\u00e9appara\u00eet aussi cette loi d\u2019airain de la nature, qui l&#8217;emporte sur les lois formelles.<\/p>\n\n\n\n<p>\u00ab&#160;Il comprenait ce que le pr\u00eatre ne pouvait pas comprendre. Que ce que nous cherchons c\u2019est l\u2019adversaire digne d\u2019\u00eatre affront\u00e9. Car nous nous pr\u00e9cipitons pour retomber en gesticulant parmi des diables de ficelle et de chiffon et nous voudrions avoir quelque chose de ferme en face de nous. Quelque chose qui r\u00e9siste et arr\u00eate notre main. Sinon notre \u00eatre m\u00eame n\u2019aurait plus de contours et nous devrions nous aussi \u00e9tendre les limites de notre territoire au point de perdre toute d\u00e9finition.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-17-189281' title='Cormac McCarthy, &lt;em&gt;Le grand passage&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Seuil, 2000, p. 174.'><sup>17<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Dans <em>Le grand passage<\/em>, \u00e0 un moment qui rappelle la pens\u00e9e de Kissinger, le conflit appara\u00eet toujours comme le seul moyen de d\u00e9finir qui nous sommes, le seul m\u00e9canisme qui, en somme, \u00e9tablisse une limite \u00e0 l\u2019emprise humaine, un frein sa la domination ind\u00e9finie et destructrice.<\/p>\n\n\n\n<p>\u00ab&#160;La loi morale a \u00e9t\u00e9 invent\u00e9e par l\u2019humanit\u00e9 pour priver les puissants de leurs droits en faveur des faibles. La loi de l\u2019histoire la d\u00e9ment \u00e0 chaque instant.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-18-189281' title='Cormac McCarthy, &lt;em&gt;M\u00e9ridien de sang&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch, Paris, Gallimard, 1988, p. 287.'><sup>18<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Le po\u00e8te italien Davide Brullo a \u00e9crit&#160;: \u00ab&#160;Comme Tolsto\u00ef, Cormac McCarthy est le dernier h\u00e9ritier de la tradition du roman \u201cmoral\u201d, c&rsquo;est-\u00e0-dire naturellement immoral.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-19-189281' title='Panottico, newsletter di Rivista Pangea, pangeanews.it, giugno 2023'><sup>19<\/sup><\/a><\/span><\/span>\u00a0S\u2019il en est ainsi, notre condition humaine ne peut \u00eatre support\u00e9e qu\u2019en investissant une valeur aussi ancienne que l\u2019honneur. McCarthy ch\u00e2tie l&rsquo;Am\u00e9rique du si\u00e8cle dernier \u2014 celle qui a oubli\u00e9 ses origines. Dans <em>Le Passager<\/em>, le conflit entre les Kennedy, symbole par excellence de l&rsquo;\u00e9lite d\u00e9mocrate, et la mafia italo-am\u00e9ricaine, se r\u00e9sout en la faveur\u00a0 de ces derniers, qui se vivent comme des hommes d\u2019honneur.<\/p>\n\n\n\n<p>\u00ab&#160;Le probl\u00e8me des Kennedy c\u2019est qu\u2019ils n\u2019\u00e9taient pas \u00e0 m\u00eame de comprendre l\u2019inflexibilit\u00e9 \u00e9thique guerri\u00e8re des Siciliens. Les Kennedy \u00e9taient des Irlandais et ils pensaient qu\u2019on pouvait toujours s\u2019en tirer avec du baratin. Ils ne concevaient m\u00eame pas qu\u2019il existe une autre fa\u00e7on de faire. Pour leurs discours politiques ils recouraient \u00e0 de grandes abstractions. Le peuple. La pauvret\u00e9. Ne demandez pas \u00e0 votre pays blablabla. Ils ne comprenaient pas qu\u2019il y avait encore des gens \u00e0 notre \u00e9poque qui croyaient sinc\u00e8rement \u00e0 des valeurs telles que l\u2019honneur&#160;\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-20-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 469-470.'><sup>20<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">In\u00e9luctablement, cela mute en une philosophie machiav\u00e9lienne de l\u2019histoire.<\/p>\n\n\n\n<p>\u00ab&#160;Il pensait que pour que batte le c\u0153ur du monde il y avait un prix terrible \u00e0 payer et que la souffrance du monde et sa beaut\u00e9 \u00e9voluaient l\u2019une par rapport \u00e0 l\u2019autre selon des principes de justice divergents et que dans cet abyssal d\u00e9ficit le sang des multitudes pourrait \u00eatre le prix finalement exig\u00e9 pour la vision d\u2019une seule fleur.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-21-189281' title='Cormac McCarthy, &lt;em&gt;De si jolis chevaux&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Actes Sud, 1993, p. 316.'><sup>21<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Le conflit, l&rsquo;\u00e9thique, la guerre, l&rsquo;honneur sont les valeurs qui, dans le myst\u00e8re irr\u00e9solu de l&rsquo;homme et de Dieu, donnent leur vibration aux romans de McCarthy. Il s\u2019agit d\u2019un monde o\u00f9 la justice n&rsquo;existe pas car elle ne peut pas \u00eatre rendue. McCarthy se mue ainsi en proph\u00e8te de la r\u00e9action.<\/p>\n\n\n\n<p>\u00ab&#160;Si j\u2019ai perdu tous ceux que j\u2019aimais au monde qu\u2019est-ce que \u00e7a change pour moi d\u2019\u00eatre libre d\u2019aller \u00e0 l\u2019\u00e9picerie&#160;?&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-22-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-22-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 504.'><sup>22<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>\u00ab&#160;Tout le bien du monde ne suffit pas \u00e0 effacer une catastrophe. Seule une pire catastrophe parvient \u00e0 l\u2019effacer.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-23-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-23-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 520.'><sup>23<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>\u00ab&#160;Elle l\u2019observait de ses yeux jaunes o\u00f9 il n\u2019y avait point de d\u00e9sespoir mais seulement le m\u00eame insondable ab\u00eeme de solitude qui taraudait le monde jusqu\u2019au c\u0153ur.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-24-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-24-189281' title='Cormac McCarthy, &lt;em&gt;Le grand passage&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Seuil, 2000, p. 121.'><sup>24<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Mais sa vision chr\u00e9tienne offre deux possibilit\u00e9s&#160;: le libre arbitre et la catharsis. Le h\u00e9ros ombrageux du <em>Passager<\/em> est happ\u00e9 par des mots brutaux, qui l\u2019am\u00e8ne d\u2019un verre au bar \u00e0 un meurtre.&nbsp;<\/p>\n\n\n\n<p>\u00ab&#160;La souffrance fait partie de la condition humaine et doit \u00eatre endur\u00e9e. Mais s\u2019y complaire est un choix&#160;\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-25-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-25-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 487.'><sup>25<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Le pardon, au contraire, constitue la vraie lib\u00e9ration. C\u2019est le seul exercice r\u00e9volutionnaire qui permette d\u2019\u00e9chapper \u00e0 la masse.<\/p>\n\n\n\n<p>\u00ab&#160;La mis\u00e9ricorde est le domaine de l\u2019individu seul. Il y a des haines collectives, il y a des deuils collectifs. Des vengeances collectives et m\u00eame des suicides collectifs. Mais il n\u2019y a pas de pardon collectif. Il n\u2019y a que toi.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-26-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-26-189281' title='Cormac McCarthy, &lt;em&gt;Le passager&lt;\/em&gt;, traduit par Serge Chauvin, Paris, L\u2019Olivier, 2023, p. 533.'><sup>26<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>\u00ab&#160;Le soir. Les morts enfouis dans la cro\u00fbte terrestre et tournant selon le lent diurnal de la roue terrestre, en paix avec les \u00e9clipses, les ast\u00e9ro\u00efdes, les poudreuses novas leurs os tach\u00e9s de moisissure et la moelle captive chang\u00e9e en pierre fragile, tournant, leurs doigts enchev\u00eatr\u00e9s de racines, ne faisant qu\u2019un avec Toutankhamon et Agamemnon, avec la semence et les naissances \u00e0 venir&#160;\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-27-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-27-189281' title='Cormac McCarthy, &lt;em&gt;Le gardien du verger&lt;\/em&gt;, traduit par Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, Seuil, 1996, p. 286-287.'><sup>27<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Cormac McCarthy s&rsquo;est \u00e9teint il y a quelques jours \u00e0 pr\u00e8s de quatre-vingt-dix ans, au terme d&rsquo;une vie d\u2019ermite et de p\u00e9lerin. Priv\u00e9 de prix Nobel, il fut encore capable, quelques mois avant de mourir, de publier deux chefs-d&rsquo;\u0153uvre. Mais c\u2019est dans son premier livre, <em>Le Gardien du verger<\/em>, que ce g\u00e9ant trouve les mots les plus justes pour \u00e9voquer son adieu \u00e0 la vie terrestre.<\/p>\n\n\n\n<p class=\"comment\">Pour nous autres, profanes, mais touch\u00e9s par la grandeur de ce ma\u00eetre, la douceur inqui\u00e8te du po\u00e8me qui cl\u00f4t la trilogie des confins nous suffit pour continuer \u00e0 faire vivre sa m\u00e9moire.&nbsp;<\/p>\n\n\n\n<p>\u00ab&#160;<em>En vieillissant<\/em><\/p>\n\n\n\n<p><em>Je serai ton enfant<\/em><\/p>\n\n\n\n<p><em>Port\u00e9 par toi<\/em><\/p>\n\n\n\n<p><em>Et toi tu seras moi.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Le monde froidit<\/em><\/p>\n\n\n\n<p><em>L\u2019impie fait rage<\/em><\/p>\n\n\n\n<p><em>L\u2019histoire est diteTourne la page.<\/em>&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-28-189281' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#easy-footnote-bottom-28-189281' title='Cormac McCarthy, &lt;em&gt;Des villes dans la plaine&lt;\/em&gt;, traduction de Fran\u00e7ois Hirsch et Patricia Schaeffer, Paris, L\u2019Olivier, 1999, p. 315.'><sup>28<\/sup><\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cormac McCarthy s&rsquo;est \u00e9teint il y a quelques jours. Dans le temps vertigineux de la guerre \u00e9tendue, nous vous proposons de relire une s\u00e9lection d&rsquo;extraits du plus grand romancier am\u00e9ricain du politique.<\/p>\n","protected":false},"author":10,"featured_media":189282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":19,"footnotes":""},"categories":[3565],"tags":[],"staff":[1563],"editorial_format":[4943],"serie":[],"audience":[],"geo":[1917],"class_list":["post-189281","post","type-post","status-publish","format-standard","hentry","category-in-memoriam","staff-lorenzo-castellani","editorial_format-discours","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":189282,"excerpt":"Cormac McCarthy s'est \u00e9teint il y a quelques jours. Dans le temps vertigineux de la guerre \u00e9tendue, nous vous proposons de relire une s\u00e9lection d'extraits du plus grand romancier am\u00e9ricain du politique.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le conflit, l&#039;\u00e9thique, la guerre, l&#039;honneur : valeurs de Cormac McCarthy | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le conflit, l&#039;\u00e9thique, la guerre, l&#039;honneur : valeurs de Cormac McCarthy | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Cormac McCarthy s&#039;est \u00e9teint il y a quelques jours. Dans le temps vertigineux de la guerre \u00e9tendue, nous vous proposons de relire une s\u00e9lection d&#039;extraits du plus grand romancier am\u00e9ricain du politique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-25T10:57:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-21T15:14:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/gc-cormac-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/gc-cormac-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/\",\"name\":\"Le conflit, l'\u00e9thique, la guerre, l'honneur : valeurs de Cormac McCarthy | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg\",\"datePublished\":\"2023-06-25T10:57:22+00:00\",\"dateModified\":\"2023-08-21T15:14:17+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg\",\"width\":979,\"height\":1460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le conflit, l&rsquo;\u00e9thique, la guerre, l&rsquo;honneur&#160;: valeurs de Cormac McCarthy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le conflit, l'\u00e9thique, la guerre, l'honneur : valeurs de Cormac McCarthy | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/","og_locale":"fr_FR","og_type":"article","og_title":"Le conflit, l'\u00e9thique, la guerre, l'honneur : valeurs de Cormac McCarthy | Le Grand Continent","og_description":"Cormac McCarthy s'est \u00e9teint il y a quelques jours. Dans le temps vertigineux de la guerre \u00e9tendue, nous vous proposons de relire une s\u00e9lection d'extraits du plus grand romancier am\u00e9ricain du politique.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/","og_site_name":"Le Grand Continent","article_published_time":"2023-06-25T10:57:22+00:00","article_modified_time":"2023-08-21T15:14:17+00:00","og_image":[{"width":2560,"height":1435,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/gc-cormac-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/gc-cormac-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/","name":"Le conflit, l'\u00e9thique, la guerre, l'honneur : valeurs de Cormac McCarthy | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg","datePublished":"2023-06-25T10:57:22+00:00","dateModified":"2023-08-21T15:14:17+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg","width":979,"height":1460},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/06\/25\/le-conflit-lethique-la-guerre-lhonneur-valeurs-de-cormac-mccarthy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le conflit, l&rsquo;\u00e9thique, la guerre, l&rsquo;honneur&#160;: valeurs de Cormac McCarthy"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3565,"name":"In Memoriam","slug":"in-memoriam"}],"lgc_author":{"id":1563,"name":"Lorenzo Castellani","slug":"lorenzo-castellani","description":"Lorenzo Castellani est chercheur postdoctoral \u00e0 la LUISS Guido Carli et professeur adjoint en histoire institutionnelle europ\u00e9enne et en histoire des institutions politiques. Ses principaux th\u00e8mes de recherche sont : l'histoire des institutions, l'histoire de l'administration publique et l'histoire et la politique.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/imageedit_2_8972048175-modified.png","width":401,"height":401,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg","width":979,"height":1460,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Cormac_McCarthy_Child_of_God_author_portrait.jpg","width":979,"height":1460,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/189281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=189281"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/189281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/189282"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=189281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=189281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=189281"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=189281"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=189281"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=189281"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=189281"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=189281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}