{"id":186321,"date":"2023-05-25T10:00:00","date_gmt":"2023-05-25T08:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=186321"},"modified":"2023-05-25T15:57:23","modified_gmt":"2023-05-25T13:57:23","slug":"ron-desantis-est-candidat-a-lelection-presidentielle-americaine","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/","title":{"rendered":"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine"},"content":{"rendered":"\n<p>L\u2019annonce officielle de la candidature de Ron DeSantis aux primaires pr\u00e9sidentielles du Parti r\u00e9publicain de 2024 f\u00fbt un fiasco rythm\u00e9 par des probl\u00e8mes techniques ayant suscit\u00e9 des moqueries au sein des deux partis. Le choix d\u2019annoncer sa candidature tant attendue sur Twitter, le r\u00e9seau social rachet\u00e9 par Elon Musk en octobre 2022, est quant \u00e0 lui caract\u00e9ristique de l\u2019id\u00e9ologie du gouverneur de Floride.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dans son dernier livre publi\u00e9 en f\u00e9vrier, <em>The Courage to Be Free&#160;: Florida&rsquo;s Blueprint for America&rsquo;s Revival<\/em>, DeSantis fait part extensivement de sa m\u00e9fiance vis-\u00e0-vis des grands m\u00e9dias traditionnels (les <em>legacy media<\/em>) ainsi que des \u00ab&#160;\u00e9lites&#160;\u00bb, mentionn\u00e9es pas moins de 20 fois dans l\u2019introduction longue de 12 pages&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-186321' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#easy-footnote-bottom-1-186321' title='Manuel Roig-Franzia, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.washingtonpost.com\/books\/2023\/02\/27\/ron-desantis-courage-be-free\/&quot;&gt;Ron DeSantis\u2019s scorn-filled book sets the tone for a potential campaign&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Washington Post&lt;\/em&gt;, 27 f\u00e9vrier 2023.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Bien que Musk ait confi\u00e9 avoir vot\u00e9 pour Joe Biden lors de l\u2019\u00e9lection pr\u00e9sidentielle de 2020, le magnat n\u2019a jamais cach\u00e9 nourrir la m\u00eame d\u00e9fiance vis-\u00e0-vis des m\u00e9dias <em>mainstream<\/em> \u2014 qui s\u2019est traduite par un affaiblissement notoire de la politique de mod\u00e9ration des contenus sur la plateforme visant, selon celui-ci, \u00e0 encourager la libert\u00e9 d\u2019expression absolue.<\/li>\n\n\n\n<li>En novembre 2022, quelques semaines apr\u00e8s le rachat de Twitter, le <em>Washington Post <\/em>titrait que les membres r\u00e9publicains du Congr\u00e8s avaient gagn\u00e9 plusieurs dizaines de milliers d\u2019abonn\u00e9s, tandis que les \u00e9lus d\u00e9mocrates en avaient perdu en moyenne 4 000&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-186321' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#easy-footnote-bottom-2-186321' title='Gerrit De Vynck, Jeremy B. Merrill et Luis Melgar, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.washingtonpost.com\/technology\/2022\/11\/27\/musk-followers-bernie-cruz\/&quot;&gt;High-profile Republicans gain followers in first weeks of Musk\u2019s reign&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Washington Post&lt;\/em&gt;, 28 novembre 2022.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>La plateforme a depuis \u00e9t\u00e9 choisie par le chroniqueur conservateur Tucker Carlson pour h\u00e9berger une \u00ab&#160;nouvelle version&#160;\u00bb de son \u00e9mission auparavant diffus\u00e9e sur la cha\u00eene Fox News.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Our Great American Comeback\" width=\"1778\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/D7ULRytIpo0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Au cours du <em>live <\/em>audio d\u2019une dur\u00e9e de 25 minutes aux c\u00f4t\u00e9s d\u2019Elon Musk, Ron DeSantis a eu du mal \u00e0 faire passer son message \u2014 au-del\u00e0 de l\u2019annonce elle-m\u00eame \u2014 en raison des nombreuses coupures provoqu\u00e9es par des probl\u00e8mes techniques, tourn\u00e9es par le gouverneur \u00e0 son avantage en revendiquant avoir r\u00e9ussi \u00e0 \u00ab&#160;casser Internet&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-186321' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#easy-footnote-bottom-3-186321' title='&lt;a href=&quot;https:\/\/twitter.com\/TeamDeSantis\/status\/1661522427363610631?s=20&quot;&gt;Tweet de @TeamDeSantis&lt;\/a&gt;, 25 mai 2023.'><sup>3<\/sup><\/a><\/span><\/span>. Le clip<em> <\/em>de campagne publi\u00e9 dans la nuit \u2014 qui s\u2019ouvre sur la phrase \u00ab&#160;notre fronti\u00e8re est un d\u00e9sastre&#160;\u00bb \u2014 offre quant \u00e0 lui l\u2019image d\u2019un candidat seul aux c\u00f4t\u00e9s d\u2019un drapeau am\u00e9ricain, en rupture avec la place accord\u00e9e aux Am\u00e9ricains dans la <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/25\/joe-biden-sera-candidat-a-lelection-presidentielle-de-2024\/\">vid\u00e9o de campagne publi\u00e9e par Joe Biden<\/a> le mois dernier&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-186321' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#easy-footnote-bottom-4-186321' title='&lt;a href=&quot;https:\/\/www.youtube.com\/watch?v=ChjibtX0UzU&amp;amp;ab_channel=JoeBiden&quot;&gt;Joe Biden Launches His Campaign For President&amp;#160;: Let&amp;rsquo;s Finish the Job&lt;\/a&gt;, YouTube, 25 avril 2023.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/PJ641\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Bien que le lancement de la campagne de DeSantis n\u2019ait pas eu le succ\u00e8s escompt\u00e9, le gouverneur de Floride mise sur le temps long pour s\u00e9duire les \u00e9lecteurs r\u00e9publicains et convaincre la base \u00e9lectorale de Donald Trump.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si les sondages le placent pour le moment loin derri\u00e8re l\u2019ancien pr\u00e9sident r\u00e9publicain en termes d\u2019intention de vote, DeSantis demeure \u00ab&#160;l\u2019\u00e9toile montante&#160;\u00bb du parti r\u00e9publicain et le seul opposant cr\u00e9dible face \u00e0 Donald Trump.<\/li>\n\n\n\n<li>Bien qu\u2019il incarne une ligne dure sur des sujets clivants (<a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/11\/expiration-du-title-42-aux-etats-unis-un-defi-pour-joe-biden\/\">l\u2019immigration<\/a>, qu\u2019il consid\u00e8re incontr\u00f4l\u00e9e, la pens\u00e9e \u00ab&#160;<em>woke <\/em>&#160;\u00bb, responsable du d\u00e9classement des \u00c9tats-Unis, l\u2019interdiction de l\u2019avortement apr\u00e8s six semaines de grossesse\u2026), il est n\u00e9anmoins per\u00e7u comme un candidat capable d\u2019aller au-del\u00e0 du discours pour v\u00e9ritablement impl\u00e9menter des politiques refl\u00e9tant son agenda conservateur \u2014 \u00e0 la diff\u00e9rence donc de Donald Trump.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/R2LOy\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le gouverneur de Floride \u2014 qui peut se reposer sur sa confortable r\u00e9\u00e9lection de novembre 2022 \u2014 est notamment appr\u00e9ci\u00e9 par les conservateurs am\u00e9ricains pour avoir \u00e9t\u00e9 l\u2019un des premiers \u00e0 \u0153uvrer pour rouvrir progressivement les bars, restaurants, espaces publics de son \u00c9tat au cours de la pand\u00e9mie de Covid-19.<\/li>\n\n\n\n<li>Auteur de plusieurs \u00ab&#160;actions coup de poing&#160;\u00bb \u2014 notamment l\u2019envoi par avion de plusieurs migrants sur l\u2019\u00eele de Martha&rsquo;s Vineyard (o\u00f9 r\u00e9sident de nombreuses personnalit\u00e9s lib\u00e9rales ais\u00e9es), dans le Massachusetts, sans que ceux-ci soient avertis de leur destination \u2014, DeSantis partage l\u2019essentiel des valeurs conservatrices de Donald Trump tout en revendiquant un style diff\u00e9rent&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-186321' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#easy-footnote-bottom-5-186321' title='Jonathan Allen et Ted Hesson, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/world\/us\/republican-governor-florida-flies-migrants-marthas-vineyard-political-stunt-2022-09-15\/&quot;&gt;Migrants flown to Martha&amp;rsquo;s Vineyard by Florida governor say they were misled&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 17 septembre 2022.'><sup>5<\/sup><\/a><\/span><\/span>.\u00a0<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/HJVe1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Avec environ 21&#160;% d\u2019intentions de vote selon l\u2019agr\u00e9gateur de sondages de <em>FiveThirtyEight<\/em>, le gouverneur de Floride est pour le moment loin derri\u00e8re Donald Trump en termes d\u2019intentions de vote, tandis que certains sondages le d\u00e9claraient gagnant au d\u00e9but de l\u2019ann\u00e9e 2023. Cependant, il reste encore plus d\u2019un an avant la primaire r\u00e9publicaine et les d\u00e9bats organis\u00e9s par le Republican National Committee (dont le premier devrait se tenir en ao\u00fbt prochain) pourraient lui permettre de se pr\u00e9senter comme un candidat capable de se faire \u00e9lire en 2024 et de mettre en oeuvre l\u2019agenda conservateur qu\u2019il promeut&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-186321' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#easy-footnote-bottom-6-186321' title='Maggie Haberman et Maggie Astor, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.nytimes.com\/2023\/02\/23\/us\/politics\/presidential-debate-milwaukee.html&quot;&gt;Republicans Will Hold Their First Presidential Debate in Milwaukee&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The New York Times&lt;\/em&gt;, 23 f\u00e9vrier 2023.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercredi 24 mai, lors d\u2019un direct sur Twitter aux c\u00f4t\u00e9s du propri\u00e9taire du r\u00e9seau social Elon Musk, le gouverneur r\u00e9publicain de Floride Ron DeSantis a officiellement annonc\u00e9 sa candidature \u00e0 la pr\u00e9sidentielle de 2024. Les derniers sondages le placent pour le moment loin derri\u00e8re Donald Trump.<\/p>\n","protected":false},"author":2622,"featured_media":186320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[1731],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525],"class_list":["post-186321","post","type-post","status-publish","format-standard","hentry","category-politique","editorial_format-actu-breves","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":186320,"excerpt":"Mercredi 24 mai, lors d\u2019un direct sur Twitter aux c\u00f4t\u00e9s du propri\u00e9taire du r\u00e9seau social Elon Musk, le gouverneur r\u00e9publicain de Floride Ron DeSantis a officiellement annonc\u00e9 sa candidature \u00e0 la pr\u00e9sidentielle de 2024. Les derniers sondages le placent pour le moment loin derri\u00e8re Donald Trump.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Mercredi 24 mai, lors d\u2019un direct sur Twitter aux c\u00f4t\u00e9s du propri\u00e9taire du r\u00e9seau social Elon Musk, le gouverneur r\u00e9publicain de Floride Ron DeSantis a officiellement annonc\u00e9 sa candidature \u00e0 la pr\u00e9sidentielle de 2024. Les derniers sondages le placent pour le moment loin derri\u00e8re Donald Trump.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-25T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-25T13:57:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/gc-candidature-presidentielle-ron-desantis-e1685022010344.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"817\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/gc-candidature-presidentielle-ron-desantis-e1685022010344.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/\",\"name\":\"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/Capture-de\u0301cran-2023-05-25-a\u0300-15.40.39.jpg\",\"datePublished\":\"2023-05-25T08:00:00+00:00\",\"dateModified\":\"2023-05-25T13:57:23+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/Capture-de\u0301cran-2023-05-25-a\u0300-15.40.39.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/Capture-de\u0301cran-2023-05-25-a\u0300-15.40.39.jpg\",\"width\":1914,\"height\":1068},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/","og_locale":"fr_FR","og_type":"article","og_title":"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine | Le Grand Continent","og_description":"Mercredi 24 mai, lors d\u2019un direct sur Twitter aux c\u00f4t\u00e9s du propri\u00e9taire du r\u00e9seau social Elon Musk, le gouverneur r\u00e9publicain de Floride Ron DeSantis a officiellement annonc\u00e9 sa candidature \u00e0 la pr\u00e9sidentielle de 2024. Les derniers sondages le placent pour le moment loin derri\u00e8re Donald Trump.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/","og_site_name":"Le Grand Continent","article_published_time":"2023-05-25T08:00:00+00:00","article_modified_time":"2023-05-25T13:57:23+00:00","og_image":[{"width":1453,"height":817,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/gc-candidature-presidentielle-ron-desantis-e1685022010344.jpg","type":"image\/jpeg"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/gc-candidature-presidentielle-ron-desantis-e1685022010344.jpg","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/","name":"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/Capture-de\u0301cran-2023-05-25-a\u0300-15.40.39.jpg","datePublished":"2023-05-25T08:00:00+00:00","dateModified":"2023-05-25T13:57:23+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/Capture-de\u0301cran-2023-05-25-a\u0300-15.40.39.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/Capture-de\u0301cran-2023-05-25-a\u0300-15.40.39.jpg","width":1914,"height":1068},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/05\/25\/ron-desantis-est-candidat-a-lelection-presidentielle-americaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Ron DeSantis est candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle am\u00e9ricaine"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/05\/Capture-de\u0301cran-2023-05-25-a\u0300-15.40.39.jpg","width":1914,"height":1068,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/186321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=186321"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/186321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/186320"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=186321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=186321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=186321"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=186321"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=186321"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=186321"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=186321"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=186321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}