{"id":183401,"date":"2023-04-27T16:35:08","date_gmt":"2023-04-27T14:35:08","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=183401"},"modified":"2023-05-03T12:52:36","modified_gmt":"2023-05-03T10:52:36","slug":"a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/","title":{"rendered":"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr"},"content":{"rendered":"\n<p>Depuis que l\u2019arm\u00e9e ukrainienne a <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/10\/larmee-ukrainienne-vient-de-reprendre-kherson-bientot-la-crimee\/\">repris la ville de Kherson<\/a>, situ\u00e9e sur le Dniepr, en novembre dernier, la ligne de front n\u2019avait pas boug\u00e9 (mis \u00e0 part quelques raids russes et ukrainiens sans importance strat\u00e9gique majeure). Alors que Kiev devrait lancer une contre-offensive \u2014 dont l\u2019ampleur reste \u00e0 d\u00e9terminer \u2014, des rapports ont indiqu\u00e9 ces derniers jours que des troupes ukrainiennes avaient \u00e9tabli des positions sur la rive est du Dniepr.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le 21 avril, l\u2019Institute for the Study of War (ISW) relayait des sources russes indiquant la pr\u00e9sence prolong\u00e9e de forces ukrainiennes dans les zones mar\u00e9cageuses situ\u00e9es dans le lit du Dniepr, en face de Kherson&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-183401' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#easy-footnote-bottom-1-183401' title='Kateryna Stepanenko, Riley Bailey, Grace Mappes et Frederick W. Kagan, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/understandingwar.org\/backgrounder\/russian-offensive-campaign-assessment-april-21-2023&quot;&gt;Russian Offensive Campaign Assessment&lt;\/a&gt;&amp;#160;\u00bb, Institute for the Study of War, 21 avril 2023.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Les jours suivants, plusieurs activit\u00e9s ukrainiennes ont \u00e9t\u00e9 document\u00e9es dans cette zone accessible uniquement par bateau et difficilement praticable. Selon certaines sources, les unit\u00e9s ukrainiennes y seraient install\u00e9es depuis plusieurs semaines et parviendraient \u00e0 se faire approvisionner depuis la rive ouest (sous contr\u00f4le de Kiev).<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/ao9sr\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Depuis la prise de la ville en novembre, les Ukrainiens n\u2019ont cess\u00e9 de mener des op\u00e9rations de petite taille visant \u00e0 cibler des d\u00e9p\u00f4ts de munitions russes ainsi que d\u2019autres objectifs tactiques sur la rive est du Dniepr. Dans les semaines ayant suivi, une op\u00e9ration amphibie avait \u00e9t\u00e9 lanc\u00e9e contre la pointe de Kinbourn (dans le golfe de Dniprovska) et des positions russes (notamment \u00e0 Oleshky) avaient \u00e9t\u00e9 vis\u00e9es par des frappes ukrainiennes.<\/p>\n\n\n\n<p>Bien que ces r\u00e9centes activit\u00e9s ne soient pas nouvelles, elles co\u00efncident toutefois avec une d\u00e9gradation de l\u2019\u00e9tat des positions russes dans la r\u00e9gion.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si l\u2019artillerie russe rendait l\u2019\u00e9tablissement de toute position ukrainienne pendant plusieurs jours sur l\u2019\u00eele de Velyki Potemkine impossible, un responsable de la r\u00e9gion de Kherson a d\u00e9clar\u00e9 que des troupes ukrainiennes avaient \u00ab&#160;maintenu une pr\u00e9sence dans la zone au cours des deux derni\u00e8res semaines&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-183401' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#easy-footnote-bottom-2-183401' title='Ian Lovett et Ann M. Simmons, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.wsj.com\/articles\/ukrainian-forces-recapture-land-across-key-river-in-south-think-tank-says-8fc9a06?mod=panda_wsj_custom_topic_alert&quot;&gt;Ukrainian Forces Recapture Land Across Key River in South, Think Tank Says&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Wall Street Journal&lt;\/em&gt;, 23 avril 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Il est peu probable que l\u2019\u00e9tat-major ukrainien cherche \u00e0 lancer une grande op\u00e9ration de travers\u00e9e du Dniepr tant celui-ci est difficilement franchissable pour des v\u00e9hicules blind\u00e9s, particuli\u00e8rement depuis la destruction partielle du pont d&rsquo;Antonivka.<\/li>\n\n\n\n<li>Cependant, ces activit\u00e9s \u2014 si elles venaient \u00e0 perdurer et \u00e0 s\u2019intensifier \u2014 pourraient servir de diversion en faveur d\u2019une offensive dans l\u2019est du pays. \u00c0 l\u2019automne dernier, Kiev avait annonc\u00e9 vouloir prendre Kherson pour finalement mener un assaut surprise dans la r\u00e9gion de Kharkiv.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/q1CUr\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Il est encore trop t\u00f4t pour affirmer que ces mouvements ukrainiens constituent autre chose qu\u2019une op\u00e9ration de reconnaissance et d\u2019attaques de cibles sp\u00e9cifiques qui n\u2019augurent pas de modification majeure de la ligne de front dans la r\u00e9gion de Kherson. Cependant, ces mouvements t\u00e9moignent de modifications du rapport de force dans des r\u00e9gions o\u00f9 les affrontements directs entre forces ukrainiennes et russes sont bien moins intensifs que dans l&rsquo;est du pays. Dans le cadre de la contre-offensive ukrainienne annonc\u00e9e de longue date, un des objectifs de Kiev serait d\u2019effectuer une perc\u00e9e vers le sud, en direction de Melitopol et de la Crim\u00e9e \u2014 ce qui para\u00eet pour l\u2019heure toutefois peu probable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au cours des derniers jours, l\u2019arm\u00e9e ukrainienne a intensifi\u00e9 ses activit\u00e9s et sa pr\u00e9sence sur les \u00eeles situ\u00e9es dans la lit du Dniepr ainsi que sur la rive gauche du fleuve. Il s\u2019agit de la premi\u00e8re fois que des images g\u00e9olocalis\u00e9es fiables confirment une pr\u00e9sence ukrainienne durable dans cette zone occup\u00e9e par l\u2019arm\u00e9e russe.<\/p>\n","protected":false},"author":2622,"featured_media":183399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-183401","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":183399,"excerpt":"Au cours des derniers jours, l\u2019arm\u00e9e ukrainienne a intensifi\u00e9 ses activit\u00e9s et sa pr\u00e9sence sur les \u00eeles situ\u00e9es dans la lit du Dniepr ainsi que sur la rive gauche du fleuve. Il s\u2019agit de la premi\u00e8re fois que des images g\u00e9olocalis\u00e9es fiables confirment une pr\u00e9sence ukrainienne durable dans cette zone occup\u00e9e par l\u2019arm\u00e9e russe.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Au cours des derniers jours, l\u2019arm\u00e9e ukrainienne a intensifi\u00e9 ses activit\u00e9s et sa pr\u00e9sence sur les \u00eeles situ\u00e9es dans la lit du Dniepr ainsi que sur la rive gauche du fleuve. Il s\u2019agit de la premi\u00e8re fois que des images g\u00e9olocalis\u00e9es fiables confirment une pr\u00e9sence ukrainienne durable dans cette zone occup\u00e9e par l\u2019arm\u00e9e russe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-27T14:35:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-03T10:52:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/gc-kherson-pont-Antonivka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1908\" \/>\n\t<meta property=\"og:image:height\" content=\"1070\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/gc-kherson-pont-Antonivka.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/\",\"name\":\"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Capture-de\u0301cran-2023-04-27-a\u0300-15.55.36.jpg\",\"datePublished\":\"2023-04-27T14:35:08+00:00\",\"dateModified\":\"2023-05-03T10:52:36+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Capture-de\u0301cran-2023-04-27-a\u0300-15.55.36.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Capture-de\u0301cran-2023-04-27-a\u0300-15.55.36.jpg\",\"width\":1906,\"height\":1070},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr | Le Grand Continent","og_description":"Au cours des derniers jours, l\u2019arm\u00e9e ukrainienne a intensifi\u00e9 ses activit\u00e9s et sa pr\u00e9sence sur les \u00eeles situ\u00e9es dans la lit du Dniepr ainsi que sur la rive gauche du fleuve. Il s\u2019agit de la premi\u00e8re fois que des images g\u00e9olocalis\u00e9es fiables confirment une pr\u00e9sence ukrainienne durable dans cette zone occup\u00e9e par l\u2019arm\u00e9e russe.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/","og_site_name":"Le Grand Continent","article_published_time":"2023-04-27T14:35:08+00:00","article_modified_time":"2023-05-03T10:52:36+00:00","og_image":[{"width":1908,"height":1070,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/gc-kherson-pont-Antonivka.jpg","type":"image\/jpeg"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/gc-kherson-pont-Antonivka.jpg","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/","name":"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Capture-de\u0301cran-2023-04-27-a\u0300-15.55.36.jpg","datePublished":"2023-04-27T14:35:08+00:00","dateModified":"2023-05-03T10:52:36+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Capture-de\u0301cran-2023-04-27-a\u0300-15.55.36.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Capture-de\u0301cran-2023-04-27-a\u0300-15.55.36.jpg","width":1906,"height":1070},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/04\/27\/a-kherson-des-forces-ukrainiennes-setablissent-plus-durablement-sur-la-rive-est-du-dniepr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 Kherson, des forces ukrainiennes s\u2019\u00e9tablissent plus durablement sur la rive est du Dniepr"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Capture-de\u0301cran-2023-04-27-a\u0300-15.55.36.jpg","width":1906,"height":1070,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/183401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=183401"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/183401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/183399"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=183401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=183401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=183401"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=183401"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=183401"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=183401"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=183401"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=183401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}