{"id":180170,"date":"2023-03-20T07:00:00","date_gmt":"2023-03-20T06:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=180170"},"modified":"2023-03-20T07:08:09","modified_gmt":"2023-03-20T06:08:09","slug":"sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/","title":{"rendered":"Sondage exclusif&#160;: ce que pensent les Fran\u00e7ais de l&rsquo;\u00e9cologie de guerre"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Les Fran\u00e7ais cherchent le r\u00f4le qu\u2019ils doivent endosser dans la <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/18\/la-naissance-de-lecologie-de-guerre\/\">guerre \u00e9cologique<\/a> qui m\u00eale le besoin de d\u00e9carbonation rapide et de transition \u00e9nerg\u00e9tique acc\u00e9l\u00e9r\u00e9e de nos \u00e9conomies. Souvent consid\u00e9r\u00e9es comme structurelles et plut\u00f4t secondaires face aux sujets br\u00fblants dans le d\u00e9bat public, les questions \u00e9nerg\u00e9tiques sont devenues, en un an, avec les cons\u00e9quences de la guerre en Ukraine, une th\u00e9matique centrale. Comment les Fran\u00e7ais veulent-ils investir dans la transition \u00e9nerg\u00e9tique&#160;? Quelles menaces voient-ils pour l\u2019approvisionnement de leur pays en \u00e9nergie dans le moyen terme&#160;? Quelles strat\u00e9gies, nationales et internationales, ont leur pr\u00e9f\u00e9rence&#160;? Une \u00e9tude r\u00e9alis\u00e9e en mars 2023 par Kantar Public&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-180170' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#easy-footnote-bottom-1-180170' title='\u00ab&amp;#160;Les Fran\u00e7ais et la s\u00e9curit\u00e9 \u00e9nerg\u00e9tique&amp;#160;\u00bb, \u00e9tude men\u00e9e par Kantar Public pour Nuances d\u2019avenir et publi\u00e9e en mars 2023. L\u2019\u00e9tude a \u00e9t\u00e9 r\u00e9alis\u00e9e aupr\u00e8s d\u2019un \u00e9chantillon de 1000 adultes repr\u00e9sentatifs de la population fran\u00e7aise, selon la m\u00e9thode des quotas (sexe, \u00e2ge, CSP) et avec une stratification par r\u00e9gion, du 6 au 8 mars 2023.'><sup>1<\/sup><\/a><\/span><\/span>, que <em>le Grand Continent<\/em> publie en exclusivit\u00e9, d\u00e9voile les quelques clefs de lecture des perceptions des Fran\u00e7ais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>1 \u2014 Les Fran\u00e7ais pr\u00e9f\u00e8rent (l\u00e9g\u00e8rement) les \u00e9nergies renouvelables au nucl\u00e9aire<\/strong><\/h2>\n\n\n\n<p>Les Fran\u00e7ais ont la conscience profonde que m\u00eame si la sobri\u00e9t\u00e9 peut \u00eatre une partie de la solution, la production d&rsquo;\u00e9nergie \u00e9lectrique doit augmenter pour r\u00e9duire la part des \u00e9nergies fossiles dans la production \u00e9nerg\u00e9tique totale. Pour assurer leur s\u00e9curit\u00e9 \u00e9nerg\u00e9tique, plus de neuf Fran\u00e7ais sur dix (91&#160;%) pensent donc qu\u2019il faut augmenter la production d\u2019\u00e9lectricit\u00e9 renouvelable en France. La question porte ici exclusivement sur l\u2019\u00e9olien et le solaire, sans mention de l\u2019hydraulique (premi\u00e8re source d\u2019\u00e9lectricit\u00e9 renouvelable produite en France) ni des gaz renouvelables. Les 25-34 ans sont les plus avanc\u00e9s sur le sujet, puisque 55&#160;% d\u2019entre eux se disent \u201ctout \u00e0 fait d\u2019accord\u201d, contre 48&#160;% dans la population g\u00e9n\u00e9rale. La r\u00e9cente loi relative \u00e0 l\u2019acc\u00e9l\u00e9ration de la production d\u2019\u00e9nergies renouvelables, adopt\u00e9e par le Parlement en f\u00e9vrier dernier, abonde dans ce sens. Elle vise notamment \u00e0 corriger le retard fran\u00e7ais en la mati\u00e8re, puisque le pays n\u2019a pas atteint depuis 2020 ses objectifs en mati\u00e8re d\u2019\u00e9nergies renouvelables et \u00e9tait alors le seul dans ce cas parmi les vingt-sept&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-180170' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#easy-footnote-bottom-2-180170' title='&lt;a href=&quot;https:\/\/www.lemonde.fr\/planete\/article\/2022\/11\/24\/renouvelables-la-france-devra-debourser-plusieurs-centaines-de-millions-d-euros-pour-ne-pas-avoir-atteint-ses-objectifs_6151464_3244.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.lemonde.fr\/planete\/article\/2022\/11\/24\/renouvelables-la-france-devra-debourser-plusieurs-centaines-de-millions-d-euros-pour-ne-pas-avoir-atteint-ses-objectifs_6151464_3244.html&lt;\/a&gt;'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>En revanche, les Fran\u00e7ais sont \u00e9galement une tr\u00e8s large majorit\u00e9, toutefois dans une l\u00e9g\u00e8re moindre proportion (85&#160;%), \u00e0 penser qu\u2019il faut produire davantage d\u2019\u00e9lectricit\u00e9 de source nucl\u00e9aire. C\u2019est le sens du nouveau projet de loi en cours de discussion, qui vise \u00e0 prolonger la dur\u00e9e de vie des centrales actuelles et acc\u00e9l\u00e9rer la construction de nouveaux r\u00e9acteurs.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/9w1wa\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Lorsqu\u2019on leur demande leurs priorit\u00e9s en mati\u00e8re d\u2019investissement, 55&#160;% des Fran\u00e7ais classent les \u00e9nergies renouvelables en premier, contre 40&#160;% pour le nucl\u00e9aire et 5&#160;% seulement pour les \u00e9nergies fossiles.&nbsp; Il y a donc un double consensus fran\u00e7ais fort sur les renouvelables comme sur le nucl\u00e9aire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>2 \u2014 Contradictions sur les investissements bas-carbone<\/strong><\/h2>\n\n\n\n<p>Les Fran\u00e7ais pr\u00e9f\u00e8rent donc investir dans les \u00e9nergies renouvelables que dans le nucl\u00e9aire.&nbsp; Ce r\u00e9sultat est pour autant contraire \u00e0 la rationalit\u00e9 \u00e9conomique stricte qu\u2019ils expriment, car ils consid\u00e8rent que c\u2019est l&rsquo;\u00e9nergie nucl\u00e9aire qui est le moins cher \u00e0 produire. Une moiti\u00e9 (49&#160;%) de Fran\u00e7ais pense ainsi que le nucl\u00e9aire est l\u2019\u00e9nergie la moins ch\u00e8re \u00e0 produire en France (les plus de 65 ans sont 61&#160;% \u00e0 le d\u00e9clarer), contre 36&#160;% pour l\u2019\u00e9olien et le solaire. Ce n\u2019est donc pas seulement le prix qui guide les Fran\u00e7ais favorables aux \u00e9nergies renouvelables&#160;; une bonne partie d\u2019entre eux consent donc \u00e0 payer un prix plus \u00e9lev\u00e9 pour ces investissements.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/XxsuK\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Pour autant, les Fran\u00e7ais se trompent&#160;: le rapport <em>Futurs \u00e9nerg\u00e9tiques<\/em> publi\u00e9 par l\u2019op\u00e9rateur RTE en octobre 2021&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-180170' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#easy-footnote-bottom-3-180170' title='&lt;a href=&quot;https:\/\/www.rte-france.com\/analyses-tendances-et-prospectives\/bilan-previsionnel-2050-futurs-energetiques&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.rte-france.com\/analyses-tendances-et-prospectives\/bilan-previsionnel-2050-futurs-energetiques&lt;\/a&gt;'><sup>3<\/sup><\/a><\/span><\/span> (avant la guerre en Ukraine, mais \u00e0 un moment o\u00f9 les prix de l\u2019\u00e9nergie \u00e9taient d\u00e9j\u00e0 \u00e9lev\u00e9s sur fonds de reprise post-Covid) consid\u00e8re que le co\u00fbt de production du nouveau nucl\u00e9aire, de l\u2019ordre de 60-85 \u20ac le MWh, est sup\u00e9rieur au co\u00fbt du solaire et de l\u2019\u00e9olien (entre 30 et 45 \u20ac le MWh)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-180170' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#easy-footnote-bottom-4-180170' title='Ceci cependant sans int\u00e9grer les autres co\u00fbts associ\u00e9s \u00e0 la production des \u00e9nergies renouvelables, tels que le stockage et le transport, qui aboutissent \u00e0 un co\u00fbt total plus \u00e9lev\u00e9 que pour le nucl\u00e9aire.'><sup>4<\/sup><\/a><\/span><\/span> dans la plupart des configurations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3 \u2014 De mani\u00e8re g\u00e9n\u00e9rale, les Fran\u00e7ais ne veulent pas payer pour la transition<\/strong><\/h2>\n\n\n\n<p>Double contradiction&#160;: les Fran\u00e7ais veulent investir dans les technologies qui \u00e0 leurs yeux co\u00fbtent plus cher en moyenne\u2026 Cependant en majorit\u00e9 ils ne veulent pas payer tout court. \u00c0 la question de savoir s\u2019ils seraient pr\u00eats \u00e0 payer plus d\u2019imp\u00f4t pour financer la transition \u00e9nerg\u00e9tique et assurer leur s\u00e9curit\u00e9 \u00e9nerg\u00e9tique, 26&#160;% r\u00e9pondent par un non d\u00e9finitif, et 36&#160;% par \u201cplut\u00f4t non\u201d.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/tPOjg\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Ce choix t\u00e9moigne des pr\u00e9occupations financi\u00e8res plus g\u00e9n\u00e9rales des Fran\u00e7ais. Dans toutes les \u00e9tudes d\u2019opinion, leur inqui\u00e9tude premi\u00e8re porte sur leur pouvoir d\u2019achat, et non sur l\u2019environnement, l\u2019immigration ou les relations internationales. D\u2019ailleurs, selon l\u2019\u00e9tude, 81&#160;% des Fran\u00e7ais pensent que dans les mois \u00e0 venir les prix de l\u2019\u00e9nergie vont encore augmenter. En f\u00e9vrier, le prix moyen du MWh d\u2019\u00e9lectricit\u00e9 sur le march\u00e9 de gros s\u2019\u00e9levait en France \u00e0 149 \u20ac, ce qui est largement au-dessus de la moyenne de 2015 \u00e0 2020, autour de 30-50 \u20ac, mais en-dessous du <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/03\/observatoire-de-la-guerre-ecologique-energie-electricite-geopolitique-y-x\/\">pic \u00e0 presque 500 \u20ac en ao\u00fbt<\/a>. Cependant, malgr\u00e9 le refus de payer davantage, les Fran\u00e7ais sont conscients d\u2019une forme de fatalit\u00e9 \u00e0 une transition co\u00fbteuse puisqu\u2019ils pr\u00e9voient en majorit\u00e9 que le co\u00fbt de l&rsquo;\u00e9nergie augmentera de mani\u00e8re tendancielle.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/xWodD\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>4 \u2014 Une minorit\u00e9 importante de Fran\u00e7ais n\u2019a pas d\u2019inclinaison de principe envers les Occidentaux pour assurer sa s\u00e9curit\u00e9 \u00e9nerg\u00e9tique<\/strong><\/h2>\n\n\n\n<p>Les Fran\u00e7ais veulent majoritairement investir dans les \u00e9nergies renouvelables et, dans une l\u00e9g\u00e8rement moindre proportion, dans le nucl\u00e9aire. Une minorit\u00e9 significative n\u2019est n\u00e9anmoins pas du m\u00eame avis. Plus d\u2019un quart des Fran\u00e7ais (26&#160;%) ne pense pas que la France doit arr\u00eater d\u2019importer des \u00e9nergies fossiles (gaz, p\u00e9trole) provenant de pays autoritaires (Russie, Arabie saoudite, Afghanistan). Ils sont minoritaires, mais loin d\u2019\u00eatre anecdotiques.&nbsp;<\/p>\n\n\n\n<p>Rappelons qu\u2019en France, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/01\/cartographier-notre-dependance-energetique-a-la-russie\/\">le taux de d\u00e9pendance \u00e9nerg\u00e9tique \u00e0 la Russie avant la guerre <\/a>(p\u00e9trole, gaz, charbon) \u00e9tait \u00e9valu\u00e9 \u00e0 5,9&#160;%, c\u2019est-\u00e0-dire plus que l\u2019Espagne mais moins que la majorit\u00e9 des pays europ\u00e9ens, un taux qui a baiss\u00e9 en 2022 en raison de la r\u00e9duction des importations provenant de Russie et des tentatives de diversification des approvisionnements.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/wz3Nu\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>De plus, seul un tiers des Fran\u00e7ais (32&#160;%) pense qu\u2019il faut en priorit\u00e9 s\u2019appuyer sur nos alli\u00e9s occidentaux (Union, \u00c9tats-Unis, Royaume-Uni) pour assurer notre s\u00e9curit\u00e9 \u00e9nerg\u00e9tique. Cela ne signifie bien s\u00fbr pas qu\u2019une majorit\u00e9 de Fran\u00e7ais rejette les alliances occidentales sur le principe&#160;; cependant parmi les deux-tiers de Fran\u00e7ais qui pensent que la France doit d\u2019abord compter sur elle-m\u00eame, il y a fort \u00e0 parier qu\u2019une partie non significative souhaite collaborer avec d\u2019autres \u00c9tats, peut-\u00eatre autoritaires.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5 \u2014 Les Fran\u00e7ais restent favorables \u00e0 une coordination sur les questions \u00e9nerg\u00e9tiques<\/strong><\/h2>\n\n\n\n<p>Si seulement un tiers des Fran\u00e7ais souhaite s\u2019appuyer en priorit\u00e9 sur l\u2019Europe et les \u00c9tats-Unis pour assurer leur s\u00e9curit\u00e9, les trois-quarts d\u2019entre eux (77&#160;%) sont ouverts \u00e0 une coordination avec eux, qui pourrait prendre la forme d\u2019une concertation, d\u2019une planification commune voire d\u2019approvisionnements communs. De mani\u00e8re g\u00e9n\u00e9rale, en politique \u00e9nerg\u00e9tique comme en politique \u00e9trang\u00e8re, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/01\/18\/10-points-sur-lopinion-geopolitique-en-france-avant-la-presidentielle\/\">les Fran\u00e7ais restent ouverts sur leurs collaborations<\/a>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/DBz43\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>En cela, \u201cl\u2019alliance du nucl\u00e9aire\u201d lanc\u00e9e par le pr\u00e9sident Macron, pr\u00e9sent\u00e9e comme \u201cl\u2019un des nombreux outils permettant [&#8230;] de garantir la s\u00e9curit\u00e9 de l\u2019approvisionnement\u201d, pourrait \u00eatre bien re\u00e7ue par les Fran\u00e7ais. De m\u00eame, selon l\u2019Eurobarom\u00e8tre de f\u00e9vrier 2023&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-180170' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#easy-footnote-bottom-5-180170' title='&lt;a href=&quot;https:\/\/europa.eu\/eurobarometer\/surveys\/detail\/2653&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/europa.eu\/eurobarometer\/surveys\/detail\/2653&lt;\/a&gt;'><sup>5<\/sup><\/a><\/span><\/span>, 75&#160;% des Europ\u00e9ens, et 70&#160;% des Fran\u00e7ais, consid\u00e9raient le <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/18\/le-plan-repowereu\/\">plan REPowerEU<\/a> de la Commission comme \u201cune bonne chose\u201d.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusion<\/strong><\/h2>\n\n\n\n<p>Au bout du compte, cette \u00e9tude montre que les Fran\u00e7ais veulent en majorit\u00e9 sortir des \u00e9nergies fossiles, privil\u00e9gient tr\u00e8s l\u00e9g\u00e8rement les \u00e9nergies renouvelables par rapport au nucl\u00e9aire, mais ne veulent globalement pas financer davantage la transition par l\u2019imp\u00f4t. Ils veulent d\u2019abord que la France soit plus autonome en mati\u00e8re \u00e9nerg\u00e9tique mais esp\u00e8rent bien se coordonner avec leurs alli\u00e9s. Ces orientations ne font pas l\u2019unanimit\u00e9 et une minorit\u00e9 non n\u00e9gligeable reste favorable aux \u00e9nergies fossiles et n\u2019a pas d\u2019opposition de principe au commerce avec des puissances autoritaires.<\/p>\n\n\n\n<p>Concluons sur la place de la France dans l\u2019Union. Le dernier Eurobarom\u00e8tre de mars 2023&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-180170' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#easy-footnote-bottom-6-180170' title='&lt;a href=&quot;https:\/\/www.europarl.europa.eu\/at-your-service\/fr\/be-heard\/eurobarometer\/plenary-insights-march-2023&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.europarl.europa.eu\/at-your-service\/fr\/be-heard\/eurobarometer\/plenary-insights-march-2023&lt;\/a&gt;'><sup>6<\/sup><\/a><\/span><\/span> fait ressortir deux faits majeurs&#160;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>86&#160;% des Europ\u00e9ens en moyenne pensent que l\u2019Union devrait investir massivement dans les \u00e9nergies renouvelables. 80&#160;% des Fran\u00e7ais pensent de m\u00eame, ce qui en fait le 21e pays sur 27.<\/li>\n\n\n\n<li>Pour 84&#160;% des Europ\u00e9ens, il faut r\u00e9duire notre d\u00e9pendance \u00e0 l\u2019\u00e9gard des sources russes d\u2019approvisionnement \u00e9nerg\u00e9tique d\u00e8s que possible. C\u2019est le cas de 79&#160;% des Fran\u00e7ais, ce qui les place \u00e0 la 20e place sur 27.<\/li>\n<\/ul>\n\n\n\n<p>En somme, les Fran\u00e7ais sont tr\u00e8s majoritairement favorables \u00e0 la sortie des \u00e9nergies fossiles (<em>a fortiori<\/em> provenant de Russie), au profit des \u00e9nergies renouvelables, mais globalement beaucoup moins que leurs partenaires europ\u00e9ens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet d\u2019ordinaire consid\u00e9r\u00e9 comme technique et au second plan, les politiques \u00e9nerg\u00e9tiques sont brutalement entr\u00e9es dans la vie quotidienne et dans le d\u00e9bat, en Europe et en France. Le Grand Continent publie en exclusivit\u00e9 les r\u00e9sultats d\u2019une enqu\u00eate clef r\u00e9alis\u00e9e en mars 2023 pour Kantar, qui \u00e9claire les changements \u00e0 l&rsquo;\u0153uvre et offre  des perspectives nouvelles.<\/p>\n","protected":false},"author":10,"featured_media":180172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":8,"footnotes":""},"categories":[1730],"tags":[],"staff":[2553,1560,1970],"editorial_format":[4849],"serie":[],"audience":[],"geo":[1917],"class_list":["post-180170","post","type-post","status-publish","format-standard","hentry","category-energie-et-environnement","staff-ben-judah","staff-olivier-lenoir","staff-shahin-vallee","editorial_format-etudes","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":180172,"excerpt":"Sujet d\u2019ordinaire consid\u00e9r\u00e9 comme technique et au second plan, les politiques \u00e9nerg\u00e9tiques sont brutalement entr\u00e9es dans la vie quotidienne et dans le d\u00e9bat, en Europe et en France. Le Grand Continent publie en exclusivit\u00e9 les r\u00e9sultats d\u2019une enqu\u00eate clef r\u00e9alis\u00e9e en mars 2023 pour Kantar, qui \u00e9claire les changements \u00e0 l'\u0153uvre et offre  des perspectives nouvelles.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sondage exclusif : ce que pensent les Fran\u00e7ais de l&#039;\u00e9cologie de guerre | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sondage exclusif : ce que pensent les Fran\u00e7ais de l&#039;\u00e9cologie de guerre | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Sujet d\u2019ordinaire consid\u00e9r\u00e9 comme technique et au second plan, les politiques \u00e9nerg\u00e9tiques sont brutalement entr\u00e9es dans la vie quotidienne et dans le d\u00e9bat, en Europe et en France. Le Grand Continent publie en exclusivit\u00e9 les r\u00e9sultats d\u2019une enqu\u00eate clef r\u00e9alis\u00e9e en mars 2023 pour Kantar, qui \u00e9claire les changements \u00e0 l&#039;\u0153uvre et offre des perspectives nouvelles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-20T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T06:08:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/gc-ecol-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/gc-ecol-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/\",\"name\":\"Sondage exclusif : ce que pensent les Fran\u00e7ais de l'\u00e9cologie de guerre | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg\",\"datePublished\":\"2023-03-20T06:00:00+00:00\",\"dateModified\":\"2023-03-20T06:08:09+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg\",\"width\":2560,\"height\":1842,\"caption\":\"6279115 02.07.2020 Electric power lines from the largest in Russia Sayano-Shushenskaya Hydropower Station are pictured, near the town of Sayanogorsk in the Republic of Khakassia, Russia. Ilya Naymushin \/ Sputnik\/\/SPUTNIK_1500.0036\/2007031511\/Credit:Sputnik\/SIPA\/2007031519\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sondage exclusif&#160;: ce que pensent les Fran\u00e7ais de l&rsquo;\u00e9cologie de guerre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sondage exclusif : ce que pensent les Fran\u00e7ais de l'\u00e9cologie de guerre | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/","og_locale":"fr_FR","og_type":"article","og_title":"Sondage exclusif : ce que pensent les Fran\u00e7ais de l'\u00e9cologie de guerre | Le Grand Continent","og_description":"Sujet d\u2019ordinaire consid\u00e9r\u00e9 comme technique et au second plan, les politiques \u00e9nerg\u00e9tiques sont brutalement entr\u00e9es dans la vie quotidienne et dans le d\u00e9bat, en Europe et en France. Le Grand Continent publie en exclusivit\u00e9 les r\u00e9sultats d\u2019une enqu\u00eate clef r\u00e9alis\u00e9e en mars 2023 pour Kantar, qui \u00e9claire les changements \u00e0 l'\u0153uvre et offre des perspectives nouvelles.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/","og_site_name":"Le Grand Continent","article_published_time":"2023-03-20T06:00:00+00:00","article_modified_time":"2023-03-20T06:08:09+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/gc-ecol-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/gc-ecol-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/","url":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/","name":"Sondage exclusif : ce que pensent les Fran\u00e7ais de l'\u00e9cologie de guerre | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg","datePublished":"2023-03-20T06:00:00+00:00","dateModified":"2023-03-20T06:08:09+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg","width":2560,"height":1842,"caption":"6279115 02.07.2020 Electric power lines from the largest in Russia Sayano-Shushenskaya Hydropower Station are pictured, near the town of Sayanogorsk in the Republic of Khakassia, Russia. Ilya Naymushin \/ Sputnik\/\/SPUTNIK_1500.0036\/2007031511\/Credit:Sputnik\/SIPA\/2007031519"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/20\/sondage-exclusif-ce-que-pensent-les-francais-de-lecologie-de-guerre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Sondage exclusif&#160;: ce que pensent les Fran\u00e7ais de l&rsquo;\u00e9cologie de guerre"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1730,"name":"\u00c9nergie et environnement","slug":"energie-et-environnement"}],"lgc_author":{"id":2553,"name":"Ben Judah","slug":"ben-judah","description":"<span style=\"font-weight: 400\">Ben Judah est un journaliste, auteur et chercheur franco-britannique. Apr\u00e8s avoir \u00e9t\u00e9 Senior Fellow du Europe Center du Atlantic Council, il y est actuellement directeur de la Transform Europe Initiative. En tant que journaliste, il a travaill\u00e9 pour de nombreux journaux, dont Politico Europe, et notamment publi\u00e9 dans le Financial Times, The Atlantic et le New York Times. En juin 2023 est paru son troisi\u00e8me livre <\/span><i><span style=\"font-weight: 400\">This is Europe<\/span><\/i><span style=\"font-weight: 400\"> chez Picador Macmillan. <\/span>","first_name":"Ben","last_name":"Judah","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/gc-ben-judah.png","width":400,"height":400,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg","width":2560,"height":1842,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/SIPA_00970833_000002-scaled.jpg","width":2560,"height":1842,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/180170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=180170"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/180170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/180172"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=180170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=180170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=180170"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=180170"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=180170"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=180170"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=180170"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=180170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}