{"id":169858,"date":"2022-12-01T10:33:54","date_gmt":"2022-12-01T09:33:54","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=169858"},"modified":"2025-06-02T21:20:48","modified_gmt":"2025-06-02T19:20:48","slug":"la-lecture-intelligente-une-conversation-avec-pierre-nora","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/","title":{"rendered":"L&rsquo;obstination d&rsquo;une lecture intelligente, Pierre Nora (1931 &#8211; 2025)"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Vous avez plac\u00e9 le deuxi\u00e8me volume de vos M\u00e9moires sous le signe de l\u2019\u00ab&#160;obstination&#160;\u00bb. La premi\u00e8re de ces obstinations qui caract\u00e9risent votre parcours, c\u2019est celle \u00e0 ne pas choisir entre le m\u00e9tier d\u2019historien et celui d\u2019\u00e9diteur. Cela r\u00e9sulte-t-il d\u2019un choix r\u00e9fl\u00e9chi et t\u00f4t arr\u00eat\u00e9 de votre part de mener ces deux activit\u00e9s de front, ou bien d\u2019une incapacit\u00e9 \u00e0 choisir entre les deux&#160;?<\/strong><\/h3>\n\n\n\n<p>Au moment o\u00f9 il m\u2019a fallu choisir quelle voie embrasser, j\u2019h\u00e9sitais beaucoup \u00e0 me lancer dans une th\u00e8se, sachant que cela m\u2019aurait demand\u00e9 dix ans de labeur &#8211; c\u2019\u00e9tait l\u2019\u00e9poque des grandes th\u00e8ses &#8211; et me destinait \u00e0 embrasser une carri\u00e8re de professeur. Une autre voie \u00e9tait possible, qui m\u2019\u00e9tait inspir\u00e9e par mon premier livre sur les Fran\u00e7ais d\u2019Alg\u00e9rie qui avait \u00e9t\u00e9 salu\u00e9 et qui aurait pu me conduire \u00e0 embrasser une carri\u00e8re d\u2019essayiste. La vie en a finalement d\u00e9cid\u00e9 autrement parce que sans que je l&rsquo;ai d\u00e9cid\u00e9, apr\u00e8s avoir fait aux \u00e9ditions Julliard la petite collection Archives, j&rsquo;ai eu cette proposition rare de prendre la t\u00eate du secteur entier des id\u00e9es et des sciences humaines dans une maison aussi prestigieuse que Gallimard. J\u2019ai donc d\u00e9cid\u00e9 d\u2019essayer ce m\u00e9tier d\u2019\u00e9diteur pendant deux ans, et j\u2019ai vite \u00e9t\u00e9 happ\u00e9 par lui. C\u2019\u00e9tait tout m\u00eame beaucoup plus int\u00e9ressant de \u00ab&#160;corriger&#160;\u00bb Foucault et Le Goff que les \u00e9tudiants de Sciences Po. R\u00e9trospectivement, je pense que j\u2019ai eu une vie passionnante, qui a co\u00efncid\u00e9 avec une \u00e9poque historique rare du point de vue intellectuel, une sorte d\u2019entre parenth\u00e8ses heureuse. Je ne regrette donc pas de ne pas avoir choisi entre ces deux voies. Dans une tension entre l&rsquo;enseignement aux Hautes \u00c9tudes, l&rsquo;\u00e9criture personnelle et l&rsquo;\u00e9dition, j\u2019ai eu une vie pleinement satisfaisante.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>C\u2019\u00e9tait tout m\u00eame beaucoup plus int\u00e9ressant de \u00ab&#160;corriger&#160;\u00bb Foucault et Le Goff que les \u00e9tudiants de Sciences Po.<\/p><cite>Pierre Nora<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>R\u00e9trospectivement, diriez-vous qu\u2019\u00eatre historien vous a \u00e9t\u00e9 utile dans l\u2019exercice de votre m\u00e9tier d\u2019\u00e9diteur et qu\u2019inversement, le m\u00e9tier d\u2019\u00e9diteur a enrichi votre pratique d\u2019historien&#160;?<\/strong><\/h3>\n\n\n\n<p>Pour moi, les deux ont \u00e9t\u00e9 totalement compl\u00e9mentaires&#160;: si je n&rsquo;avais pas \u00e9t\u00e9 chez Gallimard, je n\u2019aurai pas \u00e9t\u00e9 l\u2019historien que j\u2019ai \u00e9t\u00e9, et inversement. Prenez <em>Les Lieux de m\u00e9moire. <\/em>Si j\u2019\u00e9tais all\u00e9 les proposer \u00e0 un \u00e9diteur, il m\u2019aurait \u00e9videmment \u00e9conduit sur le champ. Et si j\u2019\u00e9tais un pur \u00e9diteur et que je n&rsquo;\u00e9tais pas en m\u00eame temps un historien, jamais je n&rsquo;aurais pu \u00e9laborer un projet aussi fou. Je me souviens qu&rsquo;apr\u00e8s la parution des quatre premiers volumes, qui avaient d\u00e9j\u00e0 paru abusifs \u00e0 certains dans la maison, quand j&rsquo;ai dit \u00e0 Antoine Gallimard qu\u2019il allait y en avoir encore trois autres, qu\u2019ils allaient faire 1000 pages chacun et que je voulais qu\u2019ils paraissent en m\u00eame temps\u2026 Un \u00e9diteur normal se serait \u00e9pouvant\u00e9 et c&rsquo;est un peu ce qu&rsquo;il a fait avant de me faire finalement confiance.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quand on regarde votre parcours, aussi bien d\u2019\u00e9diteur que d&rsquo;historien, on est frapp\u00e9 par l&rsquo;importance qu\u2019y tient le collectif. Vous \u00eates un homme du travail d\u2019\u00e9quipe, au contraire de l&rsquo;image que l&rsquo;on se fait volontiers du savant solitaire. Aussi bien dans vos activit\u00e9s d&rsquo;historien que d&rsquo;\u00e9diteur, vous vous \u00eates toujours entour\u00e9 de coll\u00e8gues qui sont aussi souvent des amis. Comment expliquez-vous cette importance que rev\u00eat le collectif dans votre parcours&#160;?<\/strong><\/h3>\n\n\n\n<p>Vous me le faites vous-m\u00eame remarquer, je ne m\u2019en \u00e9tais pas vraiment aper\u00e7u. Mais il est vrai que si je n\u2019avais pas \u00e9t\u00e9 ce que je suis devenu, j\u2019aurais aim\u00e9, si j\u2019en avais \u00e9t\u00e9 capable, \u00eatre chef d\u2019orchestre. Plus jeune, j\u2019envisageais aussi de devenir acteur, d\u2019\u00e9crire des sketchs puis de les monter collectivement. Ce sont des m\u00e9tiers de rapport, de rapport avec les autres auxquels j\u2019\u00e9tais port\u00e9 naturellement, sans que je puisse dire pourquoi. Pour reprendre <em>Les Lieux de m\u00e9moire<\/em>, j\u2019avais d\u2019abord song\u00e9 \u00e0 les faire seul. Cela se serait r\u00e9sum\u00e9 \u00e0 l\u2019introduction d\u2019une cinquantaine de pages expliquant ce qu\u2019est un lieu de m\u00e9moire que j\u2019aurais fait suivre de quelques \u00e9tudes de cas. Je l\u2019ai envisag\u00e9 et puis j\u2019ai finalement pr\u00e9f\u00e9r\u00e9 en faire \u2014 un peu sur le mod\u00e8le de la parade du 14 juillet 1989 orchestr\u00e9e par Jean-Paul Goude \u2014 quelque chose comme le d\u00e9fil\u00e9 de toute une g\u00e9n\u00e9ration d\u2019historiens&#160;: j\u2019ai finalement r\u00e9uni 130 articles \u00e9crits par une centaine d\u2019historiens. Il y a quelque chose d\u2019exaltant dans ce collectif. Cela a \u00e9t\u00e9 la m\u00eame chose pour <em>Faire de l\u2019histoire<\/em>. Au d\u00e9part, cela devait \u00eatre un petit volume r\u00e9unissant Foucault, Le Roy Ladurie, Furet, Le Goff et accessoirement moi. Et puis c&rsquo;est devenu, un peu par la faute de Le Goff qui proposait \u00e0 tout bout de champ \u00e0 des coll\u00e8gues d\u2019\u00e9crire des contributions, une entreprise beaucoup plus volumineuse que pr\u00e9vue. Et je me suis dit \u00ab&#160;pourquoi pas&#160;?&#160;\u00bb&#160;: c\u2019est autre chose mais \u00e7a va marquer l\u2019\u00e9poque. Si j&rsquo;avais fait <em>Les Lieux de m\u00e9moire<\/em> en solitaire, est-ce que cela aurait autant marqu\u00e9&#160;? Probablement pas. Et si j\u2019avais fait un petit essai de 150 pages pour montrer dans les ann\u00e9es 1970 que l\u2019histoire \u00e9tait en train de changer, aurait-il eu le retentissement qu\u2019a eu la trilogie <em>Faire de l\u2019histoire&#160;?<\/em> Sans doute pas non plus. J&rsquo;ai pris go\u00fbt \u00e0 ce travail collectif.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Mais il est vrai que si je n\u2019avais pas \u00e9t\u00e9 ce que je suis devenu, j\u2019aurais aim\u00e9, si j\u2019en avais \u00e9t\u00e9 capable, \u00eatre chef d\u2019orchestre.<\/p><cite>Pierre Nora<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sans doute en lien avec cette pr\u00e9dilection pour le travail collectif, vous avez surtout \u00e9t\u00e9, s\u2019agissant de vos travaux de recherche personnels, un homme de l\u2019article plus que du livre.<\/strong><\/h3>\n\n\n\n<p>C&rsquo;est tout \u00e0 fait vrai car je pense qu&rsquo;on en dit souvent plus en une trentaine de pages que dans un livre entier. Pourquoi&#160;? Parce qu&rsquo;on ne peut pas faire un article sans qu\u2019il y ait une id\u00e9e forte qui se d\u00e9gage. Tandis que vous pouvez tout \u00e0 fait faire un livre sans id\u00e9e-force. L&rsquo;article, pour moi, \u00e7a a \u00e9t\u00e9 le moyen de faire des livres en vingt pages sur des sujets tr\u00e8s diff\u00e9rents. Et vous remarquerez que je ne suis pas le seul dans mon cas&#160;: la g\u00e9n\u00e9ration qui me pr\u00e9c\u00e8de de tr\u00e8s peu, celle des Furet, Le Goff, Le Roy Ladurie a op\u00e9r\u00e9 des perc\u00e9es en usant principalement de l\u2019article.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000002-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1705\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000002-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000002-690x459.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000002-1340x892.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000002-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 Bernard Bisson\/JDD\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\"><strong>Et c\u2019est vous finalement qui, par votre activit\u00e9 d\u2019\u00e9diteur, les avez conduit vers le livre en les incitant \u00e0 r\u00e9unir certains de ces articles dispers\u00e9s en revues dans des ouvrages \u00e9dit\u00e9s dans les collections que vous dirigiez chez Gallimard.<\/strong><\/h3>\n\n\n\n<p>Oui c&rsquo;est vrai, je l&rsquo;ai fait pour Jean Bott\u00e9ro avec<em> Naissance de Dieu<\/em>, pour Jacques Gernet avec <em>L\u2019intelligence de la Chine<\/em>, pour Jacques Le Goff avec <em>Pour un autre Moyen \u00c2ge<\/em>, pour Fran\u00e7ois Furet avec <em>Penser la R\u00e9volution fran\u00e7aise<\/em>. Toute cette g\u00e9n\u00e9ration trouvait dans l\u2019article un contrepoint \u00e0 la th\u00e8se, que certains ont faite et d\u2019autres pas, parce qu\u2019elle avait quelque chose d\u2019asc\u00e9tique voire de punitif.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dans votre cas, l\u2019article a \u00e9t\u00e9 une alternative \u00e0 la th\u00e8se que vous n\u2019avez finalement pas r\u00e9dig\u00e9e.<\/strong><\/h3>\n\n\n\n<p>La th\u00e8se \u00e9tait alors un vrai sacrifice et peut \u00eatre ai-je \u00e9t\u00e9 trop rapidement, excusez-moi du mot, \u00ab&#160;lanc\u00e9&#160;\u00bb dans la vie par ma famille tr\u00e8s parisienne, par mon fr\u00e8re Simon Nora qui \u00e9tait un haut fonctionnaire. J\u2019ai donc \u00e9t\u00e9 tr\u00e8s rapidement introduit gr\u00e2ce \u00e0 lui dans des milieux int\u00e9ressants, dans des amiti\u00e9s riches et je n&rsquo;aurai pas pu me condamner \u00e0 l\u2019aust\u00e9rit\u00e9 n\u00e9cessaire \u00e0 la r\u00e9alisation d\u2019un tel travail. J\u2019avais, qui plus est, une curiosit\u00e9 g\u00e9n\u00e9rale qui me compliquait le choix d\u2019un sujet. J\u2019en ai pris successivement trois ou quatre. \u00c0 chaque fois que j&rsquo;allais voir Pierre Renouvin, je lui annon\u00e7ai un nouveau sujet. L\u2019un d\u2019eux portait sur les intellectuels et la nation de 1905 \u00e0 1914. Et puis je suis tomb\u00e9 sur le livre d\u2019Eugen Weber, <em>The Nationalist Revival<\/em>, qui traitait \u00e0 peu pr\u00e8s de ce sujet, donc \u00e7a m\u2019a d\u00e9courag\u00e9. J\u2019avais pens\u00e9 \u00e0 d\u2019autres sujets, sur le parti colonial par exemple, parce que je revenais d\u2019Alg\u00e9rie. Mais la perspective de m\u2019enfermer dix ans avec Eug\u00e8ne Etienne et consorts du parti colonial avant 1914, quand on a le go\u00fbt plus \u00e9largi, plus spontan\u00e9, c\u2019\u00e9tait impossible. L&rsquo;\u00e9dition m&rsquo;a combl\u00e9 de ce point de vue car c&rsquo;est un v\u00e9ritable gyrophare permanent. La proposition que m\u2019a fait Gallimard, alors que j\u2019avais moins de 35 ans, que je cherchais encore mon sujet de th\u00e8se, que j\u2019avais fait spontan\u00e9ment une petite collection comme la collection Archives qui avait eu beaucoup de succ\u00e8s, \u00e9tait beaucoup plus attrayante.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>J&rsquo;ai eu tort de ne pas insister sur l\u2019aspect qui demeure le plus important du travail d\u2019\u00e9diteur&#160;: lire les manuscrits.<\/p><cite>Pierre Nora<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c0 lire le r\u00e9cit que vous en donnez, le m\u00e9tier d\u2019\u00e9diteur n\u2019a toutefois pas que des attraits. L\u2019image qui en ressort est parfois celle d\u2019une activit\u00e9 consistant plus \u00e0 g\u00e9rer des probl\u00e8mes d\u2019ego et de susceptibilit\u00e9 entre auteurs qu\u2019\u00e0 faire m\u00fbrir et \u00e0 diffuser leurs id\u00e9es.<\/strong><\/h3>\n\n\n\n<p>Je regrette de donner cette impression et vous me faites penser que j&rsquo;ai eu tort de ne pas insister sur l\u2019aspect qui demeure le plus important du travail d\u2019\u00e9diteur&#160;: lire les manuscrits. Je recevais trois cent manuscrits ou livres parus \u00e0 l\u2019\u00e9tranger chaque ann\u00e9e. Il fallait trier tout cela. Il y en a qui s\u2019\u00e9liminent d\u2019eux-m\u00eames, d\u2019autres qu\u2019il faut faire lire et pour lesquels il faut donc trouver des lecteurs, ce qui n\u2019est pas simple car m\u00eame des personnes par ailleurs brillantes peuvent ne pas savoir r\u00e9aliser cet exercice tr\u00e8s particulier. C\u2019est&nbsp; d\u2019ailleurs comme cela que j&rsquo;ai connu Marcel Gauchet qui excellait dans ce travail. Et puis il y a les manuscrits qu&rsquo;on lit soi-m\u00eame, soit parce que le lecteur vous dit que c\u2019est \u00e0 vous de juger, soit parce que le sujet fait que vous estimez \u00eatre le mieux \u00e0 m\u00eame de l\u2019\u00e9valuer. C\u2019est cela le c\u0153ur du m\u00e9tier d\u2019\u00e9diteur&#160;: la lecture forcen\u00e9e et, si j\u2019ose dire, la lecture intelligente, c\u2019est-\u00e0-dire celle qui se met \u00e0 la place de l\u2019auteur. La \u00ab&#160;gent \u00e9ditoriale&#160;\u00bb m\u2019agace souvent par le fait que s\u2019y exprime fr\u00e9quemment un peu de m\u00e9pris pour les auteurs, peut \u00eatre d\u2019ailleurs parce qu\u2019ils ne sont pas capables d\u2019en \u00eatre. Il y a une esp\u00e8ce d\u2019ironie vis-\u00e0-vis de l\u2019auteur, on se moque un peu de lui. Peut-\u00eatre parce que j\u2019\u00e9tais aussi un auteur, je n\u2019ai jamais partag\u00e9 cette rigolade. Je me mets \u00e0 la place des auteurs&#160;: ce sont des centaines d\u2019heures de travail qu\u2019on se doit de traiter avec s\u00e9rieux et avec un effort de compr\u00e9hension. Et ce que je vous dis du livre est encore plus vrai de l\u2019article&#160;: il s\u2019agit quand vous lisez un article non de savoir ce qu\u2019il est mais ce qu\u2019il peut devenir. Il faut entrer en empathie avec pour voir ce qu&rsquo;on peut en faire, par exemple pour \u00e9valuer si un article isol\u00e9 pourrait servir de point de d\u00e9part \u00e0 un d\u00e9bat, ce qui suppose souvent de demander \u00e0 l\u2019auteur de modifier son texte. Je regrette de ne pas avoir davantage dit dans ce livre que l\u2019essentiel du m\u00e9tier, c\u2019est de lire des manuscrits et pas de g\u00e9rer des egos.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Arr\u00eatons-nous tout de m\u00eame un peu sur ces questions d\u2019egos. \u00c9voquant une de vos nombreuses brouilles avec Michel Foucault, vous \u00e9crivez&#160;: \u00ab&#160;peut-\u00eatre les \u00e9diteurs sont-ils toujours un peu des tra\u00eetres&#160;\u00bb. Que voulez-vous dire par l\u00e0&#160;?<\/strong><\/h3>\n\n\n\n<p>Il y a un peu de boutade, de provocation dans ce que je dis l\u00e0. C\u2019est presque un aveu qui m\u2019est venu en \u00e9crivant ce chapitre. J\u2019ai \u00e9t\u00e9 dans une situation tr\u00e8s bizarre avec Foucault, au moment o\u00f9 <em>Le D\u00e9bat <\/em>s\u2019est cr\u00e9\u00e9 et o\u00f9 Marcel Gauchet s\u2019est rapproch\u00e9 de moi et moi de lui. Il y a eu pour moi une sorte de passation de l\u2019orbite foucaldienne \u00e0 l\u2019orbite gauchetienne. Et Foucault qui \u00e9tait un grand affectif et un grand sentimental, qui avait pour moi sans doute un v\u00e9ritable attachement, s\u2019est senti trahi. Il \u00e9tait venu \u00e0 mon s\u00e9minaire un jour que Gauchet y faisait un expos\u00e9. Il avait bien compris que c\u2019\u00e9tait quelqu\u2019un d\u2019arm\u00e9 intellectuellement. Et l\u00e0-dessus Gauchet avait publi\u00e9, en m\u00eame temps que nous lancions <em>Le D\u00e9bat<\/em>, un livre qui prenait le contrepied de <em>L\u2019Histoire de la folie<\/em>. Donc Foucault a vu en lui un concurrent. Le mot peut para\u00eetre abusif dans la mesure o\u00f9 Foucault r\u00e9gnait quasi-mondialement et que Gauchet \u00e9tait un d\u00e9butant, mais Foucault a senti une concurrence puisque Gauchet abordait le th\u00e8me de la folie pour d\u00e9mentir la lecture qu\u2019en avait faite Foucault, notamment \u00e0 propos du \u00ab&#160;grand renfermement&#160;\u00bb. Je me suis donc trouv\u00e9 tiraill\u00e9 entre ces deux hommes. Spontan\u00e9ment, j\u2019avais pour Foucault une esp\u00e8ce de fascination, d\u2019attachement, d\u2019amiti\u00e9. Il avait fait ma carri\u00e8re d\u2019\u00e9diteur et nous \u00e9tions tr\u00e8s li\u00e9s. Cependant j\u2019avais des r\u00e9serves profondes sur l\u2019essentiel et il le sentait bien. J\u2019ai v\u00e9cu p\u00e9niblement ce transfert mais je me suis senti intellectuellement plus proche de Gauchet que de Foucault qui \u00e9tait un sublime acrobate mais dont les pirouettes intellectuelles entretenaient un rapport probl\u00e9matique \u00e0 la v\u00e9rit\u00e9, qui \u00e9tait pourtant le sujet principal de sa r\u00e9flexion. En \u00e9crivant \u00e0 propos de cet \u00e9cart\u00e8lement, je me suis dis qu\u2019il y avait&nbsp; l\u00e0 quelque chose qui \u00e9tait vrai avec d\u2019autres auteurs, avec lesquels on se trouve souvent en empathie. Cela me rappelait ce que mon p\u00e8re qui \u00e9tait chirurgien m\u2019avait un jour dit \u00e0 propos de ses patients&#160;: il faut toujours donner l\u2019impression au malade qu\u2019on a fait tant d\u2019\u00e9tudes et qu\u2019on a v\u00e9cu que pour le jour o\u00f9 il vient en consultation. Il y a quelque chose de cet ordre dans le travail de l\u2019\u00e9diteur qui doit lui aussi donner \u00e0 chaque auteur l\u2019impression qu\u2019il n\u2019a v\u00e9cu que pour lui et qu\u2019il est tout \u00e0 lui. Or, c\u2019est faux.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous \u00e9voquiez tout \u00e0 l\u2019heure les livres re\u00e7us de l\u2019\u00e9tranger dont il faut \u00e9valuer la pertinence d\u2019une traduction. L\u2019\u00e9diteur est en effet au c\u0153ur de la circulation internationale des id\u00e9es. Vous entreteniez j\u2019imagine des relations avec vos coll\u00e8gues de nombreux autres pays&#160;?<\/strong><\/h3>\n\n\n\n<p>J&rsquo;avais des relations avec plusieurs personnalit\u00e9s ext\u00e9rieures. J\u2019\u00e9tais notamment li\u00e9 \u00e0 Robert Silvers, le directeur de la <em>New-York Review of Books.<\/em> Il \u00e9tait tr\u00e8s au courant de ce qui paraissait aux \u00c9tats-Unis et tr\u00e8s souvent, il m\u2019appelait pour attirer mon attention sur un auteur ou une publication. C\u2019est comme \u00e7a que j\u2019ai d\u00e9couvert <a href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/10\/24\/nous-avons-rencontre-timothy-snyder\/\">les <em>Terres de sang<\/em> de Timothy Snyder par exemple<\/a>. J&rsquo;avais le m\u00eame genre de rapport \u00e0 Londres avec George Weidenfeld qui \u00e9tait un homme tr\u00e8s international lui-m\u00eame, tr\u00e8s lanc\u00e9 dans le grand monde politique et un grand \u00e9diteur. J\u2019avais aussi des rapports tr\u00e8s \u00e9troits avec Giulio Einaudi. Il m\u2019avait rep\u00e9r\u00e9 lors d\u2019un de ses s\u00e9jours \u00e0 Paris et il m\u2019avait tout de suite invit\u00e9 \u00e0 Turin pour assister \u00e0 l\u2019un de ses comit\u00e9s de lecture. Nous \u00e9tions si proches qu\u2019il voulait que nous lancions des projets ensemble&#160;: c\u2019est ainsi que nous avons mis en chantier une Histoire des marxismes et une Histoire des psychanalyses. La r\u00e9alisation de l\u2019Histoire des marxismes s\u2019est av\u00e9r\u00e9e tr\u00e8s compliqu\u00e9e car les Italiens voulaient mettre des auteurs staliniens et finalement j&rsquo;avais fait admettre Eric Hobsbawm comme arbitre supr\u00eame. Cette histoire a dur\u00e9 au moins trois ans et finalement comme Hobsbawm tenait justement \u00e0 remettre encore des staliniens, je me suis retir\u00e9 de ce projet. J\u2019avais en revanche peu de rapports avec les Allemands, sauf \u00e0 travers \u00c9tienne Fran\u00e7ois, parce que je ne ma\u00eetrise pas la langue. C\u2019\u00e9tait un handicap \u00e9vident. Dans ce domaine et pour l\u2019Europe de l\u2019Est, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/24\/geopolitique-du-musee-une-conversation-avec-krzysztof-pomian\/\">Krzysztof Pomian, qui parle russe et allemand, m\u2019a \u00e9t\u00e9 d\u2019un grand secours<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Foucault et moi discutions pour savoir qui de lui ou de moi avait le pouvoir. Je pensais que c&rsquo;\u00e9tait lui et lui pensait que c&rsquo;\u00e9tait moi.<\/p><cite>Pierre Nora<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Par la position \u00e9minente que vous avez occup\u00e9e dans une maison aussi prestigieuse que Gallimard, vous avez \u00e9t\u00e9 un homme de pouvoir. Cela n\u2019est pas sans susciter convoitises, jalousies, flatteries. Comment avez-vous g\u00e9r\u00e9 cette dimension inh\u00e9rente \u00e0 votre travail d\u2019\u00e9diteur&#160;?<\/strong><\/h3>\n\n\n\n<p>Le probl\u00e8me du pouvoir intellectuel \u00e9tait \u00e0 l\u2019ordre du jour au moment o\u00f9 nous avons lanc\u00e9 <em>Le D\u00e9bat<\/em>. R\u00e9gis Debray avait ouvert le feu avec son livre sur <em>Le Pouvoir intellectuel en France <\/em>en<em> <\/em>1979. S\u2019en est suivie une r\u00e9flexion permanente sur le pouvoir intellectuel et ce sont des discussions que je me souviens d&rsquo;avoir eu avec Foucault qui accordait une grande place \u00e0 cette question du pouvoir. Nous discutions pour savoir qui de lui ou de moi avait le pouvoir. Je pensais que c&rsquo;\u00e9tait lui et lui pensait que c&rsquo;\u00e9tait moi. Je lui avais propos\u00e9 d\u2019ouvrir la revue par une discussion entre nous deux sur ce sujet, \u00e0 laquelle il s\u2019est finalement d\u00e9rob\u00e9. Et j&rsquo;ai donc \u00e9crit seul tout un \u00e9ditorial sur la nature du pouvoir intellectuel&#160;: \u00ab&#160;Que peuvent les intellectuels&#160;?&#160;\u00bb. Un article beaucoup trop long, que Claude Gallimard trouvait ridicule de mettre en t\u00eate de cette revue. Mais je tenais beaucoup \u00e0 faire cette d\u00e9monstration qui voulait signifier que faire une revue, c\u2019\u00e9tait assumer un pouvoir intellectuel. C\u2019est aussi vrai dans l\u2019\u00e9dition mais moins que dans une revue&#160;: si votre livre est refus\u00e9 par un \u00e9diteur, vous pouvez en d\u00e9marcher de nombreux autres, alors que s\u2019agissant du <em>D\u00e9bat<\/em>, il y avait bien s\u00fbr d\u2019autres revues, mais gu\u00e8re plus de trois si on consid\u00e8re les revues g\u00e9n\u00e9ralistes&#160;: <em>Esprit, Commentaire <\/em>et <em>Les Temps modernes<\/em>. Or toutes \u00e9taient id\u00e9ologiquement marqu\u00e9es alors que nous \u00e9tions une revue qui s&rsquo;affichait comme ouverte et purement intellectuelle \u00e0 une \u00e9poque o\u00f9 il ne s&rsquo;agissait selon nous non plus de transformer le monde mais de le comprendre. J\u2019ai donc beaucoup parl\u00e9 de ce pouvoir intellectuel et c\u2019est ce qui a d\u00e9clench\u00e9 l\u2019ire de Foucault contre mon \u00e9ditorial, car j\u2019y plaidais pour un intellectuel du type d\u00e9mocratique, c\u2019est-\u00e0-dire un intellectuel qui se soumet \u00e0 l\u2019appr\u00e9ciation des autres et qui les \u00e9coute, qui t\u00e2che d\u2019avoir avec la v\u00e9rit\u00e9 une sorte d\u2019honn\u00eatet\u00e9 pluraliste. C\u2019est pour \u00e7a que j\u2019ai appel\u00e9 la revue <em>Le D\u00e9bat<\/em>&#160;: cela voulait dire que tout \u00e9tait ouvert au d\u00e9bat. Nous sortions de l\u2019\u00e9poque structuraliste et nous souhaitions nous adresser aux citoyens de base. Par le mot m\u00eame de \u00ab&#160;d\u00e9bat&#160;\u00bb, nous voulions signifier une ambition pluraliste. Dans la rubrique \u00ab&#160;Un livre en d\u00e9bat&#160;\u00bb, nous donnions \u00e0 l\u2019auteur trois ou quatre lectures de son livre auxquelles il r\u00e9pondait. Il y avait l\u00e0 un processus qui n\u2019\u00e9tait pas l\u2019article fulminant qui ex\u00e9cute un livre sans appel. On a parfois dit que <em>Le D\u00e9bat<\/em> \u00e9tait un dialogue entre professeurs du Coll\u00e8ge de France, mais c\u2019est faux. Nous avons donn\u00e9 la parole \u00e0 de nombreux jeunes auteurs. Alors oui, l\u2019exercice de ce pouvoir, je l&rsquo;assume, mais pour l\u2019exercer de la fa\u00e7on la plus nette, la plus franche, la plus ouverte et la plus d\u00e9mocratique.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000003-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1704\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000003-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000003-690x459.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000003-1340x892.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000003-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 Bernard Bisson\/JDD\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\"><strong>En tant qu\u2019\u00e9diteur, quels sont vos plus grands regrets, les livres que vous avez laiss\u00e9 passer, que vous regrettez d\u2019avoir refus\u00e9s ou encore les projets qui ne sont pas all\u00e9s \u00e0 leur terme&#160;? <\/strong>&nbsp;<\/h3>\n\n\n\n<p>Il y a beaucoup de regrets, \u00e0 commencer par l\u2019Histoire des marxismes dont je vous parlais. Je suis all\u00e9 \u00e0 Londres, \u00e0 Turin, j\u2019y ai pass\u00e9 des semaines et je regrette que \u00e7a ne se soit pas fait. Et \u00e7a ne s\u2019est pas fait pr\u00e9cis\u00e9ment, parce que j\u2019ai voulu \u00eatre honn\u00eate et pas militant, comme j\u2019ai voulu le faire avec la revue. Je regrette aussi de ne pas avoir publi\u00e9 Philippe Ari\u00e8s. J\u2019avais beaucoup aim\u00e9 <em>Le temps de l\u2019histoire<\/em> et son <em>Historien du dimanche<\/em>, qui m\u2019a inspir\u00e9 l\u2019id\u00e9e d\u2019\u00e9go-histoire. Je l\u2019ai connu apr\u00e8s, trop tard. Il m\u2019a dit&#160;: \u00ab&#160;\u00e9coutez, je viendrai bien chez Gallimard mais j&rsquo;ai une petite collection chez Plon&#160;\u00bb. Il y avait publi\u00e9 Raoul Girardet et la premi\u00e8re \u00e9dition de l\u2019<em>Histoire de la folie<\/em> de Foucault. Un autre regret est bien s\u00fbr li\u00e9 \u00e0 l\u2019ach\u00e8vement du <em>D\u00e9bat<\/em>. Si j\u2019avais eu quinze ans de moins, j&rsquo;aurais pens\u00e9 \u00e0 transformer<em> Le D\u00e9bat<\/em> et \u00e0 le faire perdurer. Il \u00e9tait \u00e9vident qu\u2019au bout de quarante ans o\u00f9 rien n\u2019avait chang\u00e9, il \u00e9tait temps de proc\u00e9der \u00e0 des transformations de forme et de fond et je regrette de ne pas \u00eatre parvenu \u00e0 lui faire prendre un tournant. Je n\u2019aurais toutefois pas pu faire ce que <em>le Grand Continent<\/em> a r\u00e9ussi \u00e0 faire depuis son tout r\u00e9cent lancement car je ne suis pas assez familier avec le num\u00e9rique. J\u2019avais pr\u00e8s de 90 ans, et je tenais \u00e0 r\u00e9diger mes M\u00e9moires. Cela me permet d\u2019ailleurs de revenir \u00e0 votre premi\u00e8re question sur mon obstination \u00e0 ne pas choisir entre mes deux m\u00e9tiers. Quand j\u2019ai commenc\u00e9 \u00e0 penser s\u00e9rieusement \u00e0 \u00e9crire ces M\u00e9moires, je me suis d\u2019abord senti compl\u00e8tement incapable de les faire tellement la t\u00e2che me paraissait \u00e9norme. Il m\u2019a donc finalement fallu une v\u00e9ritable obstination et \u00e0 partir du moment o\u00f9 j\u2019ai eu cette id\u00e9e, je m\u2019y suis pleinement consacr\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Et quelles sont vos plus grandes fiert\u00e9s \u00e9ditoriales&#160;?<\/strong><\/h3>\n\n\n\n<p>Pour vous dire quelque chose d\u2019assez personnel, je suis assez fier du trio que nous avons form\u00e9 avec Marcel Gauchet et Krzysztof Pomian. Un trio incroyable de f\u00e9condit\u00e9 intellectuelle, de r\u00e9ciprocit\u00e9. Il fallait assister \u00e0 nos s\u00e9ances de travail du <em>D\u00e9bat <\/em>une fois par semaine&#160;: ils \u00e9taient tous les deux l\u00e0 et les id\u00e9es fusaient. Pomian a dit une fois qu\u2019il n\u2019y avait sans doute pas un s\u00e9minaire au Coll\u00e8ge de France qui ait cette densit\u00e9. Nous avons tous les trois attach\u00e9 notre nom \u00e0 une \u0153uvre reconnue comme \u00ab&#160;monumentale&#160;\u00bb&#160;: elle est collective pour moi, vous avez raison, ce sont <em>Les lieux de m\u00e9moire<\/em> mais ma marque n\u2019y est pas seulement celle d\u2019un ramasseur de copies&#160;; Krzysztof Pomian vient d\u2019achever sa monumentale <em>Le mus\u00e9e, une histoire mondiale<\/em>, un ouvrage magnifique achev\u00e9 dans des conditions tr\u00e8s difficiles alors qu\u2019il venait de perdre sa femme et qu\u2019il avait \u00e9t\u00e9 op\u00e9r\u00e9&#160;; Marcel Gauchet a publi\u00e9 les quatre volumes de<em> L\u2019av\u00e8nement de la d\u00e9mocratie <\/em>dont il suffit d\u2019ouvrir un chapitre pour mesurer l\u2019amplitude. Ce trio que nous avons form\u00e9, c\u2019est mieux que de la fiert\u00e9, c\u2019est du bonheur.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous avez connu un \u00e2ge o\u00f9 Paris \u00e9tait l\u2019un des phares du d\u00e9bat intellectuel mondial. Aujourd\u2019hui, elle tend \u00e0 \u00eatre provincialis\u00e9e. Selon vous, quand s\u2019est op\u00e9r\u00e9 ce tournant et comment l\u2019expliquez-vous&#160;?<\/strong><\/h3>\n\n\n\n<p>Ce tournant s\u2019est op\u00e9r\u00e9 autour de l\u2019ann\u00e9e 2000. L\u2019article que Jean-Fran\u00e7ois Sirinelli avait publi\u00e9 \u00e0 cette \u00e9poque dans <em>Le D\u00e9bat <\/em>sur l\u2019accueil international en perte de l\u2019historiographie fran\u00e7aise est un rep\u00e8re tr\u00e8s parlant de cette \u00e9volution. De mon temps, dans les congr\u00e8s internationaux, les historiens fran\u00e7ais \u00e9taient des rois et les \u00e9diteurs leur faisaient des contrats avant m\u00eame qu\u2019ils aient \u00e9crit un livre. Aujourd\u2019hui, r\u00e9ussir \u00e0 faire traduire un livre d\u2019un historien fran\u00e7ais \u00e0 l\u2019\u00e9tranger est extr\u00eamement compliqu\u00e9. Comment expliquer ce d\u00e9clin&#160;? Pardonnez l\u2019apparence de pr\u00e9tention, mais est-ce que vous connaissez une grande entreprise historiographique fran\u00e7aise depuis <em>Les Lieux de m\u00e9moire <\/em>&#160;? Quelque chose qui porte une vision renouvel\u00e9e de l\u2019histoire&#160;? C\u2019est la m\u00eame chose en sociologie. Apr\u00e8s Bourdieu, qui a \u00e9t\u00e9 la derni\u00e8re grande entreprise d\u2019envergure, il y a bien s\u00fbr des sociologues qui produisent des travaux int\u00e9ressants, mais qui ne portent pas une pens\u00e9e de l\u2019envergure de celle de Bourdieu. En philosophie, que dire si ce n\u2019est <a href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/07\/01\/onfray-fin-de-partie\/\">qu\u2019Onfray n\u2019est pas Foucault<\/a>. Toutes ces sciences humaines et sociales, dont on avait esp\u00e9r\u00e9 illusoirement qu\u2019elles pourraient contribuer \u00e0 une compr\u00e9hension unitaire des comportements humains et de l\u2019homme en g\u00e9n\u00e9ral, sont retourn\u00e9es chacune chez elles.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En philosophie, que dire si ce n\u2019est qu\u2019Onfray n\u2019est pas Foucault\u2026<\/p><cite>Pierre Nora<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pour terminer sur une note un peu plus positive, dans le paysage \u00e9ditorial actuel, que ce soit les maisons \u00e9ditions, les revues, qu\u2019est ce qui vous int\u00e9resse, qu\u2019est ce que vous lisez&#160;? Quels sont les projets qui vous semblent int\u00e9ressants, y a-t-il quand m\u00eame des choses qui vous paraissent prendre de bonnes directions&#160;?<\/strong><\/h3>\n\n\n\n<p>Bien s\u00fbr. Nous avons, nous, correspondu \u00e0 la fin de l\u2019\u00e2ge r\u00e9volutionnaire, simplificateur et militant, et \u00e0 l\u2019av\u00e8nement d\u2019un monde nouveau, marqu\u00e9 par la modernit\u00e9, la mondialisation, le r\u00e9veil de l\u2019Islam, l\u2019individualisme d\u00e9mocratique, l\u2019extension du patrimonial, la transformation du rapport au temps et \u00e0 l\u2019histoire. Un monde \u00e0 comprendre et \u00e0 explorer.<\/p>\n\n\n\n<p>Les conditions ont chang\u00e9 avec l\u2019av\u00e8nement mondial du num\u00e9rique, la priorit\u00e9 donn\u00e9e aux probl\u00e8mes n\u00e9s de l\u2019intelligence artificielle, aux changements climatiques, aux bouleversements g\u00e9opolitiques, aux probl\u00e8mes du vivant, \u00e0 tout ce que l\u2019on r\u00e9unit sous le nom d\u2019anthropoc\u00e8ne. C\u2019est \u00e0 d\u2019autres formes d\u2019intellectuels d\u2019intervenir et d\u2019en trouver les moyens. <em>Le Grand Continent<\/em> est un bon exemple.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pierre Nora vient de nous quitter.<\/p>\n<p>Nous voudrions vous proposer de relire ce grand entretien dans lequel il \u00e9voquait l&rsquo;obstination singuli\u00e8re qui avait guid\u00e9 sa carri\u00e8re d\u2019\u00e9diteur de livres et de revues chez Gallimard \u2014 de Foucault \u00e0 Le Goff en passant par Timothy Snyder.<\/p>\n<p>Dans la p\u00e9riode de rupture provoqu\u00e9e par le num\u00e9rique et l\u2019anthropoc\u00e8ne, il appelait une nouvelle g\u00e9n\u00e9ration d\u2019intellectuels \u00e0 repenser les revues.<\/p>\n","protected":false},"author":10,"featured_media":169860,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":21,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[3565,1734],"tags":[],"staff":[2508],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-169858","post","type-post","status-publish","format-standard","hentry","category-in-memoriam","category-doctrines","staff-florian-louis","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":169860,"excerpt":"Pierre Nora vient de nous quitter.\r\n\r\nNous voudrions vous proposer de relire ce grand entretien dans lequel il \u00e9voquait l'obstination singuli\u00e8re qui avait guid\u00e9 sa carri\u00e8re d\u2019\u00e9diteur de livres et de revues chez Gallimard \u2014 de Foucault \u00e0 Le Goff en passant par Timothy Snyder.\r\n\r\nDans la p\u00e9riode de rupture provoqu\u00e9e par le num\u00e9rique et l\u2019anthropoc\u00e8ne, il appelait une nouvelle g\u00e9n\u00e9ration d\u2019intellectuels \u00e0 repenser les revues.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;obstination d&#039;une lecture intelligente, Pierre Nora (1931 - 2025) | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;obstination d&#039;une lecture intelligente, Pierre Nora (1931 - 2025) | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Pierre Nora vient de nous quitter.  Nous voudrions vous proposer de relire ce grand entretien dans lequel il \u00e9voquait l&#039;obstination singuli\u00e8re qui avait guid\u00e9 sa carri\u00e8re d\u2019\u00e9diteur de livres et de revues chez Gallimard \u2014 de Foucault \u00e0 Le Goff en passant par Timothy Snyder.  Dans la p\u00e9riode de rupture provoqu\u00e9e par le num\u00e9rique et l\u2019anthropoc\u00e8ne, il appelait une nouvelle g\u00e9n\u00e9ration d\u2019intellectuels \u00e0 repenser les revues.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-01T09:33:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T19:20:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/gc-nora-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/gc-nora-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/\",\"name\":\"L'obstination d'une lecture intelligente, Pierre Nora (1931 - 2025) | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg\",\"datePublished\":\"2022-12-01T09:33:54+00:00\",\"dateModified\":\"2025-06-02T19:20:48+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg\",\"width\":2560,\"height\":1700,\"caption\":\"Pierre Nora, historien, en seance de poses a son bureau aux editions Gallimard a Paris, FRANCE - 12\/05\/2010.\/Credit:BERNARD BISSON\/JDD\/SIPA\/1005251233\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;obstination d&rsquo;une lecture intelligente, Pierre Nora (1931 &#8211; 2025)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'obstination d'une lecture intelligente, Pierre Nora (1931 - 2025) | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/","og_locale":"fr_FR","og_type":"article","og_title":"L'obstination d'une lecture intelligente, Pierre Nora (1931 - 2025) | Le Grand Continent","og_description":"Pierre Nora vient de nous quitter.  Nous voudrions vous proposer de relire ce grand entretien dans lequel il \u00e9voquait l'obstination singuli\u00e8re qui avait guid\u00e9 sa carri\u00e8re d\u2019\u00e9diteur de livres et de revues chez Gallimard \u2014 de Foucault \u00e0 Le Goff en passant par Timothy Snyder.  Dans la p\u00e9riode de rupture provoqu\u00e9e par le num\u00e9rique et l\u2019anthropoc\u00e8ne, il appelait une nouvelle g\u00e9n\u00e9ration d\u2019intellectuels \u00e0 repenser les revues.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/","og_site_name":"Le Grand Continent","article_published_time":"2022-12-01T09:33:54+00:00","article_modified_time":"2025-06-02T19:20:48+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/gc-nora-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/gc-nora-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"21 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/","name":"L'obstination d'une lecture intelligente, Pierre Nora (1931 - 2025) | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg","datePublished":"2022-12-01T09:33:54+00:00","dateModified":"2025-06-02T19:20:48+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg","width":2560,"height":1700,"caption":"Pierre Nora, historien, en seance de poses a son bureau aux editions Gallimard a Paris, FRANCE - 12\/05\/2010.\/Credit:BERNARD BISSON\/JDD\/SIPA\/1005251233"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/12\/01\/la-lecture-intelligente-une-conversation-avec-pierre-nora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;obstination d&rsquo;une lecture intelligente, Pierre Nora (1931 &#8211; 2025)"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3565,"name":"In Memoriam","slug":"in-memoriam"},{"id":1734,"name":"Livres","slug":"doctrines"}],"lgc_author":{"id":2508,"name":"Florian Louis","slug":"florian-louis","description":"Florian Louis est agr\u00e9g\u00e9 d\u2019histoire et docteur de l\u2019\u00c9cole des Hautes Etudes en sciences sociales (EHESS). Il enseigne l'histoire en classes pr\u00e9paratoires aux grandes \u00e9coles. Il a co-dirig\u00e9 avec Nicolas Beaupr\u00e9 une Histoire mondiale du XXe si\u00e8cle parue aux Presses Universitaires de France et publi\u00e9 Qu'est-ce que la g\u00e9opolitique ? (PUF, 2022).","first_name":"Florian","last_name":"Louis","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/Florian-Louis.png","width":794,"height":792,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg","width":2560,"height":1700,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/12\/SIPA_00599537_000001-scaled.jpg","width":2560,"height":1700,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/169858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=169858"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/169858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/169860"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=169858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=169858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=169858"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=169858"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=169858"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=169858"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=169858"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=169858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}