{"id":168428,"date":"2022-11-21T05:30:00","date_gmt":"2022-11-21T04:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=168428"},"modified":"2023-04-28T10:37:05","modified_gmt":"2023-04-28T08:37:05","slug":"leurope-comme-espace-puissance","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/","title":{"rendered":"L&rsquo;Europe comme espace-puissance"},"content":{"rendered":"\n<p><em>Ce texte est disponible <a href=\"https:\/\/geopolitique.eu\/en\/2022\/11\/21\/europe-as-a-power-space\/\" target=\"_blank\" rel=\"noreferrer noopener\">en version anglaise<\/a> sur le site du Groupe d&rsquo;\u00e9tudes g\u00e9opolitiques.<\/em><\/p>\n\n\n\n<p class=\"has-drop-cap\">Depuis quelques ann\u00e9es, le th\u00e8me de la \u00ab&#160;&nbsp;souverainet\u00e9 europ\u00e9enne&nbsp;&#160;\u00bb est mont\u00e9 dans le d\u00e9bat europ\u00e9en. Cette notion demeure le lieu de certaines incompr\u00e9hensions et le diagnostic m\u00eame auquel elle renvoie est souvent discut\u00e9. N\u00e9anmoins, secou\u00e9s par deux d\u00e9cennies de crises exog\u00e8nes \u2014 de la crise financi\u00e8re de 2008, en passant par la crise migratoire de 2015, jusqu\u2019\u00e0 la crise de la Covid-19 de 2020 et l\u2019actuelle guerre en Ukraine \u2014, les Europ\u00e9ens s\u2019interrogent sur les moyens de faire grandir leur ind\u00e9pendance vis-\u00e0-vis du monde ext\u00e9rieur, alors m\u00eame que leur mod\u00e8le de d\u00e9veloppement s\u2019est appuy\u00e9 sur l\u2019ouverture des \u00e9changes entre eux et avec le reste du monde. Le monde du XXI\u00e8me si\u00e8cle n\u2019est plus celui de l\u2019\u00e2ge d\u2019or de la mondialisation et de la paix&#160;: la d\u00e9gradation de la situation s\u00e9curitaire aux portes de l\u2019Union europ\u00e9enne, l\u2019acc\u00e9l\u00e9ration de la rivalit\u00e9 sino-am\u00e9ricaine, les vell\u00e9it\u00e9s agressives de certaines puissances r\u00e9gionales, la vuln\u00e9rabilit\u00e9 des interd\u00e9pendances lors de la crise sanitaire et d\u00e9sormais la guerre men\u00e9e par la Russie contre l\u2019Ukraine exigent de repenser le r\u00f4le que doit jouer l\u2019Union europ\u00e9enne \u00e0 la mesure des nouveaux d\u00e9fis du monde.&nbsp;<\/p>\n\n\n\n<p>Cette notion de souverainet\u00e9 europ\u00e9enne se distingue en partie de la notion classique de souverainet\u00e9 qui s\u2019applique g\u00e9n\u00e9ralement \u00e0 un \u00c9tat. La souverainet\u00e9 peut \u00eatre d\u00e9finie comme la capacit\u00e9 d\u2019un \u00c9tat \u00e0 produire des lois reconnues par ses citoyens et \u00e0 les faire respecter sur son territoire, ainsi qu\u2019\u00e0 d\u00e9clarer la guerre et \u00e0 faire la paix. L\u2019Union europ\u00e9enne n\u2019est pas un \u00c9tat, mais une construction originale reposant sur un pouvoir normatif. Sa souverainet\u00e9 d\u00e9rive de sa capacit\u00e9 \u00e0 \u00eatre productrice de normes s\u2019appliquant aux citoyens des diff\u00e9rents \u00c9tats membres et aux entreprises pr\u00e9sentes en Europe. Sa l\u00e9gitimit\u00e9 repose sur des Trait\u00e9s, dont la Commission est garante. D\u00e9velopper la souverainet\u00e9 europ\u00e9enne implique de faire de l\u2019Europe une \u00ab&#160;puissance&#160;\u00bb \u00e0 part \u00e9gale avec d\u2019autres puissances nationales, et pour cela de lui conf\u00e9rer plusieurs des attributs de la souverainet\u00e9&#160;: la puissance \u00e9conomique, l\u2019influence g\u00e9opolitique, la puissance normative, une capacit\u00e9 de d\u00e9fense et de s\u00e9curit\u00e9 commune, le d\u00e9veloppement d\u2019une identit\u00e9 europ\u00e9enne, c\u2019est-\u00e0-dire du sentiment d\u2019appartenance \u00e0 une histoire commune et la projection dans une destin\u00e9e partag\u00e9e, \u00e0 travers la production d\u2019un r\u00e9cit r\u00e9unissant les Europ\u00e9ens par-del\u00e0 l\u2019h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 de leurs identit\u00e9s nationales&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-168428' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#easy-footnote-bottom-1-168428' title='LAMY, Pascal, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/geopolitique.eu\/articles\/definir-la-souverainete-europeenne-une-conversation-avec-pascal-lamy\/&quot;&gt;D\u00e9finir la souverainet\u00e9 europ\u00e9enne, une conversation avec Pascal Lamy&lt;\/a&gt;&lt;em&gt;&amp;#160;\u00bb&lt;\/em&gt;, Revue europ\u00e9enne du droit, n\u00b03, &lt;em&gt;Les chemins de la puissance europ\u00e9enne&lt;\/em&gt;, Groupe d&amp;rsquo;\u00e9tudes g\u00e9opolitiques, D\u00e9cembre 2021.'><sup>1<\/sup><\/a><\/span><\/span>. Il s\u2019agit bien de renforcer la souverainet\u00e9 de chaque pays en renfor\u00e7ant la souverainet\u00e9 europ\u00e9enne, car chacun isol\u00e9ment sera moins fort que chacun dans l\u2019union.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le monde du XXI\u00e8me si\u00e8cle n\u2019est plus celui de l\u2019\u00e2ge d\u2019or de la mondialisation et de la paix.<\/p><cite>Laurence Boone<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Au cours des cinq derni\u00e8res ann\u00e9es, les dirigeants europ\u00e9ens se sont progressivement saisis de ce paradigme de souverainet\u00e9, d\u00e9finissant un agenda au sommet de Versailles en mars dernier&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-168428' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#easy-footnote-bottom-2-168428' title='D\u00e9claration de Versailles du 11 et 12 mars 2022.'><sup>2<\/sup><\/a><\/span><\/span>. Cette ambition met aujourd\u2019hui l\u2019Union europ\u00e9enne en meilleure position pour affronter le d\u00e9fi d\u2019un monde fait de rivalit\u00e9s g\u00e9opolitiques, non seulement en termes de r\u00e9silience, mais aussi de projection et de capacit\u00e9s. Cependant, il nous faut bien reconna\u00eetre que l\u2019Union malgr\u00e9 ses atouts objectifs de puissance \u00e9conomique, humanitaire et normative ne se per\u00e7oit pas comme telle \u00e0 l\u2019ext\u00e9rieur ni \u00e0 l\u2019int\u00e9rieur, notamment du fait de la persistance de rh\u00e9toriques anti-europ\u00e9ennes voire nationalistes qui font peser sur le projet europ\u00e9en un certain nombre d\u2019incertitudes. Durant la p\u00e9riode qui s\u2019ouvre, il nous faudra poursuivre cet agenda de souverainet\u00e9 europ\u00e9enne avec d\u00e9termination et sang-froid, en se fixant un ensemble clair de priorit\u00e9s, afin de collectivement traverser cette p\u00e9riode de crises et continuer \u00e0 forger une Union europ\u00e9enne \u00e0 la mesure des nombreux d\u00e9fis qui l\u2019attendent. C\u2019est ainsi que nous pr\u00e9serverons l\u2019unit\u00e9 europ\u00e9enne face aux cons\u00e9quences de la guerre en Ukraine et de la guerre hybride que la Russie m\u00e8ne \u00e0 l\u2019Europe.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>La construction d\u2019une Europe-puissance implique d\u2019engager notre action dans quatre chantiers prioritaires. D\u2019abord, nous devons consolider la puissance \u00e9conomique de l\u2019Union europ\u00e9enne. Cela veut dire compl\u00e9ter le march\u00e9 int\u00e9rieur en termes d\u2019\u00e9nergie, renforcer la r\u00e9silience des cha\u00eenes de valeurs, assurer notre ind\u00e9pendance technologique et spatiale. L\u2019ind\u00e9pendance \u00e9nerg\u00e9tique de l\u2019Union europ\u00e9enne constitue tr\u00e8s clairement l\u2019enjeu le plus urgent et le plus imm\u00e9diat. Si nous nous \u00e9loignons d\u2019ores et d\u00e9j\u00e0 de notre d\u00e9pendance collective \u00e0 l&rsquo;\u00e9gard du p\u00e9trole et du gaz russes, nous devons \u00e9galement acc\u00e9l\u00e9rer le d\u00e9veloppement des interconnexions afin d\u2019unifier le march\u00e9 de l&rsquo;\u00e9nergie dans toute l\u2019Union europ\u00e9enne et ainsi favoriser la s\u00e9curit\u00e9 de l\u2019approvisionnement. Notre d\u00e9pendance \u00e0 l&rsquo;\u00e9gard des combustibles fossiles doit en parall\u00e8le rapidement et drastiquement diminuer. La \u00ab&#160;&nbsp;crise&nbsp;&#160;\u00bb \u00e9nerg\u00e9tique repr\u00e9sente une double \u00ab&#160;opportunit\u00e9&#160;\u00bb&nbsp;&#160;: faire face au changement climatique tout en assurant notre s\u00e9curit\u00e9 \u00e9nerg\u00e9tique. Les n\u00e9gociations en cours entre le Parlement europ\u00e9en et le Conseil de l\u2019Union europ\u00e9enne sur le paquet \u00ab&#160;Ajustement \u00e0 l\u2019objectif -55&#160;%&#160;\u00bb seront essentielles pour acc\u00e9l\u00e9rer le d\u00e9veloppement de nouvelles capacit\u00e9s de production d&rsquo;\u00e9nergie d\u00e9carbon\u00e9e. Cela n\u00e9cessitera des investissements \u00e0 grande \u00e9chelle tant dans les infrastructures \u00e9nerg\u00e9tiques que dans les interconnexions. Si ces derni\u00e8res avaient \u00e9t\u00e9 planifi\u00e9es avant l\u2019agression de la Russie envers l\u2019Ukraine, les changements rapides entra\u00een\u00e9s par les cons\u00e9quences \u00e9nerg\u00e9tiques de la guerre \u2014 notamment avec le d\u00e9veloppement de terminaux m\u00e9thaniers et des \u00e9nergies renouvelables \u2014 demandent de revoir ce plan en le consolidant \u00e0 l\u2019\u00e9chelle de l\u2019union. Disons-le, de tels investissements n\u00e9cessiteront certainement de faire \u00e9voluer la gouvernance \u00e9conomique europ\u00e9enne.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/01_Daniel-Buren_Quand-le-textile-seclaire_Fibres-optiques-tissees_Travaux-situes-2013-2014_01-2048x1366-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2048\"\n        data-pswp-height=\"1366\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/01_Daniel-Buren_Quand-le-textile-seclaire_Fibres-optiques-tissees_Travaux-situes-2013-2014_01-2048x1366-1-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/01_Daniel-Buren_Quand-le-textile-seclaire_Fibres-optiques-tissees_Travaux-situes-2013-2014_01-2048x1366-1-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/01_Daniel-Buren_Quand-le-textile-seclaire_Fibres-optiques-tissees_Travaux-situes-2013-2014_01-2048x1366-1-1340x894.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/01_Daniel-Buren_Quand-le-textile-seclaire_Fibres-optiques-tissees_Travaux-situes-2013-2014_01-2048x1366-1-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Daniel Buren, Quand le textile s\u2019\u00e9claire&#160;&#160;: fibres optiques tiss\u00e9es. Travaux situ\u00e9s (Ausstellungsansicht), 2013\u20132014, Kunstsammlungen Chemnitz, 2018 \u00a9ADAGP\/Daniel Buren<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>L\u2019Union europ\u00e9enne doit plus g\u00e9n\u00e9ralement affirmer sa souverainet\u00e9 industrielle sur l\u2019ensemble des secteurs strat\u00e9giques. Gr\u00e2ce notamment \u00e0 Next Generation EU, des programmes europ\u00e9ens renforcent d\u2019ores et d\u00e9j\u00e0 notre ind\u00e9pendance strat\u00e9gique dans les domaines du num\u00e9rique, de la sant\u00e9, de l\u2019\u00e9nergie en g\u00e9n\u00e9ral et l&rsquo;hydrog\u00e8ne en particulier, et des semi-conducteurs. Avec les propositions de la Commission europ\u00e9enne sur les mati\u00e8res premi\u00e8res critiques et l&rsquo;instrument du march\u00e9 unique pour les situations d\u2019urgence, l&rsquo;Union est en train de renforcer la r\u00e9silience de sa cha\u00eene d\u2019approvisionnement. La loi sur les puces europ\u00e9ennes renforcera par ailleurs notre \u00e9cosyst\u00e8me des semi-conducteurs. Mais il nous faut faire davantage pour rattraper notre retard technologique face aux autres puissances. Nous devons acc\u00e9l\u00e9rer pour encourager l&rsquo;innovation de rupture, qui n\u00e9cessite des investissements massifs et diversifi\u00e9s. Les industries et les organismes de recherche europ\u00e9ens sont pr\u00eats \u00e0 se lancer dans le prochain \u00ab&#160;moonshot&#160;\u00bb et les \u00c9tats membres de l&rsquo;Union europ\u00e9enne se doivent de fournir les ressources financi\u00e8res autant que le soutien politique n\u00e9cessaire.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>Le passage d\u2019un espace \u00e9conomique \u00e0 un espace-puissance implique plus fondamentalement d\u2019ajouter \u00e0 l\u2019\u00e9conomie la capacit\u00e9 d\u2019influence. L\u2019influence de l\u2019Union europ\u00e9enne d\u00e9coule en grande partie de son march\u00e9 int\u00e9rieur de pr\u00e8s de 500 millions de consommateurs qui, par son pouvoir normatif, lui donne le moyen de peser de fa\u00e7on d\u00e9cisive sur l\u2019organisation des \u00e9changes internationaux. Dans les ann\u00e9es \u00e0 venir, la meilleure traduction de cette capacit\u00e9 d\u2019influence se trouve dans son mod\u00e8le de soutenabilit\u00e9 environnementale. Il nous faudra continuer de le porter, et ainsi de participer \u00e0 faire respecter l\u2019objectif que nous nous sommes collectivement fix\u00e9s de contenir la hausse des temp\u00e9ratures bien en dessous de 2\u00b0C. Porter haut et fort les couleurs vertes de la plus grande puissance leader sur le climat n\u00e9cessitera fermet\u00e9 et communication. Cela demandera aussi les efforts indispensables en faveur des pays \u00e9mergents et en d\u00e9veloppement, financiers et technologiques. L\u2019Union europ\u00e9enne peut et doit \u00eatre leader dans la r\u00e9duction des \u00e9missions, mais elle ne peut le faire qu\u2019en emmenant le reste du monde avec elle. Avec la taille de son march\u00e9 et sa capacit\u00e9 \u00e0 exporter ses normes, l\u2019Union europ\u00e9enne peut r\u00e9aliser ces ambitions. Le paquet \u00ab&#160;ajustement \u00e0 l\u2019objectif -55&#160;%&#160;\u00bb, et notamment la taxe carbone aux fronti\u00e8res, ou le r\u00e8glement sur la lutte contre la d\u00e9forestation import\u00e9e, ainsi que les clauses miroirs, vont pr\u00e9cis\u00e9ment permettre, dans les ann\u00e9es et d\u00e9cennies \u00e0 venir, de r\u00e9duire l\u2019empreinte climatique de l\u2019Union tout en incitant les pays tiers \u00e0 agir contre le r\u00e9chauffement climatique.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>De l\u2019Ukraine, \u00e0 la Moldavie, aux Balkans Occidentaux, jusqu\u2019au Royaume-Uni et la Norv\u00e8ge, nous allons construire un \u00ab&#160;grand continent&#160;\u00bb plus uni, davantage coordonn\u00e9, plus fort et int\u00e9gr\u00e9 \u00e9conomiquement.<\/p><cite>Laurence Boone<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Parall\u00e8lement, l\u2019Union europ\u00e9enne peut et doit faire rayonner le mod\u00e8le europ\u00e9en sur l\u2019ensemble du continent. En effet, pour que la paix, l\u2019\u00c9tat de droit, les libert\u00e9s fondamentales et la d\u00e9mocratie soient durables sur notre continent, l&rsquo;Union doit d\u00e9fendre ses valeurs en offrant sa capacit\u00e9 de s\u00e9curit\u00e9 ainsi que sa puissance \u00e9conomique \u00e0 l\u2019\u00e9chelle du continent. C\u2019est le sens de la Communaut\u00e9 politique europ\u00e9enne (CPE) lanc\u00e9e \u00e0 Prague le 6 octobre dernier. Elle va nous permettre de souder politiquement le grand continent europ\u00e9en, en s\u2019appuyant sur des coop\u00e9rations concr\u00e8tes dans un ensemble de domaines sur lesquels nous partageons les m\u00eames int\u00e9r\u00eats (infrastructures critiques, cybers\u00e9curit\u00e9, \u00e9nergie, mers r\u00e9gionales, jeunesse, migrations\u2026). Avec la communaut\u00e9 politique europ\u00e9enne c\u2019est l\u2019unit\u00e9 de toute l\u2019Europe qui sera renforc\u00e9e. De l\u2019Ukraine, \u00e0 la Moldavie, aux Balkans Occidentaux, jusqu\u2019au Royaume-Uni et la Norv\u00e8ge, nous allons construire un \u00ab&#160;grand continent&#160;\u00bb plus uni, davantage coordonn\u00e9, plus fort et int\u00e9gr\u00e9 \u00e9conomiquement. Ainsi, la CPE est un outil pr\u00e9cieux pour d\u00e9velopper l\u2019influence g\u00e9opolitique de l\u2019Europe. Car en toile de fond, il s\u2019agit du m\u00eame d\u00e9fi&#160;: faire du continent europ\u00e9en le continent des valeurs de libert\u00e9 et d\u2019\u00e9mancipation, de l\u2019ouverture \u00e0 la diversit\u00e9 et \u00e0 la richesse culturelle, de l\u2019\u00c9tat de droit et de la d\u00e9mocratie, d\u2019une certaine ambition d\u2019\u00e9galit\u00e9 et de respect.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>Une Europe-puissance ne peut se constituer sans un sentiment d\u2019appartenance \u00e0 une m\u00eame histoire, doubl\u00e9 de la projection dans un destin partag\u00e9, en d\u2019autres termes, d\u2019une identit\u00e9 europ\u00e9enne. C\u2019est parce qu\u2019elle a trop longtemps ignor\u00e9 cette v\u00e9rit\u00e9 que la construction europ\u00e9enne est rest\u00e9e cet objet souvent froid et technocratique aux yeux de nombre de nos concitoyens. Ce n\u2019est pas seulement en parlant des bienfaits du march\u00e9 int\u00e9rieur que nous convaincrons les Europ\u00e9ens des bienfaits de l\u2019Union europ\u00e9enne. L\u2019Union europ\u00e9enne, c\u2019est d\u2019abord un instrument de paix, de coop\u00e9ration et de solidarit\u00e9 entre les peuples europ\u00e9ens. Par la coop\u00e9ration quotidienne qu\u2019elle institue, par les espaces de sociabilit\u00e9 et de dialogue qu\u2019elle favorise, l\u2019Union europ\u00e9enne rend possible des relations pacifi\u00e9es et constructives entre les peuples europ\u00e9ens. Dans un contexte de r\u00e9surgence des nationalismes et de m\u00e9fiance croissante des citoyens \u00e0 l\u2019\u00e9gard des institutions, expliquer concr\u00e8tement ce qui, par-del\u00e0 nos diff\u00e9rences, nous rassemble entre Europ\u00e9ens, est indispensable.&nbsp;<\/p>\n\n\n\n<p>Le d\u00e9fi de notre Union est bien de d\u00e9velopper un r\u00e9cit unificateur, sans verser dans un discours civilisationnel. Marqu\u00e9e par une forte diversit\u00e9 culturelle, il ne s\u2019agit pas de produire un m\u00e9ta-r\u00e9cit c\u00e9l\u00e9brant sa singularit\u00e9 culturelle, comme une r\u00e9ponse aux r\u00e9cits culturalistes russes et chinois. C\u2019est plut\u00f4t d\u2019embrasser sa diversit\u00e9 qui fait la richesse de l\u2019Europe, ce \u00ab&#160;maximum de diversit\u00e9 sur un minimum d\u2019espace&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-168428' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#easy-footnote-bottom-3-168428' title='KUNDERA, Milan, &lt;em&gt;L\u2019Art du roman&lt;\/em&gt;.'><sup>3<\/sup><\/a><\/span><\/span> pour faire grandir la souverainet\u00e9 de l\u2019ensemble.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/14512a94-2fa7-4b5b-9e5e-af5c73404a92_1300_974.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1300\"\n        data-pswp-height=\"974\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/14512a94-2fa7-4b5b-9e5e-af5c73404a92_1300_974-330x247.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/14512a94-2fa7-4b5b-9e5e-af5c73404a92_1300_974-690x517.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/14512a94-2fa7-4b5b-9e5e-af5c73404a92_1300_974.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/14512a94-2fa7-4b5b-9e5e-af5c73404a92_1300_974-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Daniel Buren, Cadre Fragment\u00e9 C, 1991 \u00a9ADAGP\/Daniel Buren<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>L\u2019Europe, c\u2019est \u00e9galement un Pacte qui nous unit autour de principes fondamentaux&#160;: la d\u00e9mocratie, l\u2019\u00c9tat de droit, la libert\u00e9. Ces valeurs, ces principes sur lesquels l\u2019Union europ\u00e9enne s\u2019est fond\u00e9e, ils font notre force et \u2014 de plus en plus \u2014, notre singularit\u00e9&nbsp;&#160;: l\u2019ind\u00e9pendance et l\u2019impartialit\u00e9 de la justice, la pluralit\u00e9 et la libert\u00e9 de la presse, la lutte contre la corruption et la protection de la vie d\u00e9mocratique.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le d\u00e9fi de notre Union est bien de d\u00e9velopper un r\u00e9cit unificateur, sans verser dans un discours civilisationnel.<\/p><cite>Laurence Boone<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L\u2019Union europ\u00e9enne, enfin, c\u2019est la d\u00e9fense d\u2019un certain mod\u00e8le de soci\u00e9t\u00e9&#160;: une \u00e9conomie sociale de march\u00e9, l\u2019\u00e9galit\u00e9 des droits, l\u2019\u00e9mancipation et la protection des citoyens, l\u2019innovation et l\u2019ambition en mati\u00e8re de transition \u00e9cologique et num\u00e9rique.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:#474656;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/geopolitique.eu\/en\/2022\/11\/21\/europe-as-a-power-space\/\" style=\"color:#FFFFFF;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tRead it in English\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#FFFFFF;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>This text by Laurence Boone is also available on the Groupe d&rsquo;\u00e9tudes g\u00e9opolitiques website.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#a5a5a5;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/geopolitique.eu\/en\/2022\/11\/21\/europe-as-a-power-space\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Full text (EN)<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#a5a5a5;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/geopolitique.eu\/en\/geg-themes\/doctrine\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Doctrines<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#a5a5a5;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/geopolitique.eu\/en\/a-propos\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> About<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#FFFFFF;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p>Founded in 2017 at the \u00c9cole normale sup\u00e9rieure, Groupe d&rsquo;\u00e9tudes g\u00e9opolitiques (GEG), produces fundamental research based on the notion of scale.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/geopolitique.eu\/en\/2022\/11\/21\/europe-as-a-power-space\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/boone-e1668982476559-990x908.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>C\u2019est tout cet ensemble, cet \u00e9quilibre d\u00e9licat entre ouverture \u00e0 l\u2019autre et respect de soi qui fait le propre de l\u2019europ\u00e9anit\u00e9. Porter une r\u00e9flexion f\u00e9conde sur notre identit\u00e9 europ\u00e9enne et \u00e9clairer sa place dans le monde du XXI\u00e8me si\u00e8cle, c\u2019est le r\u00f4le que devra jouer dans les prochaines ann\u00e9es le projet d\u2019Acad\u00e9mie d\u2019Europe, pour nous aider \u00e0 incarner l\u2019identit\u00e9 europ\u00e9enne.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>La d\u00e9fense constitue une quatri\u00e8me dimension de la puissance, essentielle dans ce monde qui n\u2019est plus l\u2019\u00e2ge d\u2019or de la paix, o\u00f9 l\u2019Union europ\u00e9enne doit s\u2019affirmer comme une puissance protectrice de ses citoyens. Il nous faut renforcer nos capacit\u00e9s de d\u00e9fense par de la recherche et du d\u00e9veloppement capacitaire communs et \u00e9tendre l&rsquo;assistance militaire commune aux pays tiers. L\u2019Union europ\u00e9enne doit renforcer, am\u00e9liorer et mieux coordonner les investissements nationaux et europ\u00e9ens dans ses capacit\u00e9s de d\u00e9fense. Au cours des prochains mois, nous devons concr\u00e9tiser les engagements pris \u00e0 l\u2019occasion du sommet de Versailles. Je pense en particulier \u00e0 l&rsquo;op\u00e9rationnalisation de l&rsquo;instrument de recherche et d&rsquo;acquisitions conjointes d&rsquo;armement, annonc\u00e9 par le Commissaire Thierry Breton, \u00e0 la mise en place d\u2019ici 2025 d\u2019une capacit\u00e9 europ\u00e9enne de d\u00e9ploiement rapide, ou encore aux programmes communs d\u2019armement.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Daniel_Buren_Ph_Lorenzo_Palmieri_063.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1500\"\n        data-pswp-height=\"1000\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Daniel_Buren_Ph_Lorenzo_Palmieri_063-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Daniel_Buren_Ph_Lorenzo_Palmieri_063-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Daniel_Buren_Ph_Lorenzo_Palmieri_063-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Daniel_Buren_Ph_Lorenzo_Palmieri_063-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Illuminare lo spazio. Lavori in situ e situati, 2020, GAMeC, Bergame, ph. Lorenzo Palmieri \u00a9ADAGP\/Daniel Buren<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Sur le court terme, il nous faut assurer l\u2019articulation des capacit\u00e9s europ\u00e9ennes de d\u00e9fense avec l\u2019OTAN, en renfor\u00e7ant progressivement l\u2019Union europ\u00e9enne. Cela pourrait \u00eatre le cas avec des initiatives sur la mobilit\u00e9 militaire, afin d&rsquo;utiliser la logistique de l&rsquo;Union pour soutenir l&rsquo;OTAN et, en fin de compte, nous rendre tous plus forts et plus efficaces.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il nous faut renforcer nos capacit\u00e9s de d\u00e9fense par de la recherche et du d\u00e9veloppement capacitaire communs et \u00e9tendre l&rsquo;assistance militaire commune aux pays tiers.&nbsp;<\/p><cite>Laurence Boone<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La guerre en Ukraine a \u00e9t\u00e9 un acc\u00e9l\u00e9rateur qui a permis de d\u00e9passer nombre de r\u00e9ticences des Etats membres \u00e0 s\u2019engager, \u00e0 titre bilat\u00e9ral ou par le biais de m\u00e9canismes europ\u00e9ens comme la nouvelle Facilit\u00e9 europ\u00e9enne de paix, qui nous permet d\u00e9sormais de r\u00e9ellement d\u00e9fendre un Etat partenaire en facilitant son acc\u00e8s \u00e0 des \u00e9quipements l\u00e9taux. Nous devons aller plus loin. La constitution d\u2019une Europe de la d\u00e9fense implique de d\u00e9finir les int\u00e9r\u00eats strat\u00e9giques essentiels communs des Europ\u00e9ens et de clarifier la place que les Europ\u00e9ens entendent avoir dans le monde.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>L\u2019Union europ\u00e9enne est dans un \u00e9tat encore \u00e9volutif&#160;: elle est une puissance en construction, qui n\u2019est fondamentalement comparable \u00e0 aucune autre construction politique. Si l\u2019on veut construire l\u2019Europe souveraine, il ne nous faut pas chercher \u00e0 la calquer sur des mod\u00e8les existants. Car l\u2019Europe a une voix singuli\u00e8re \u00e0 porter au sein du concert des grandes puissances, celle de la d\u00e9mocratie de d\u00e9mocraties, d\u2019un mod\u00e8le fond\u00e9 sur une \u00e9conomie sociale de march\u00e9, qui constitue une r\u00e9f\u00e9rence aujourd\u2019hui en mati\u00e8re de transition \u00e9cologique et demain de r\u00e9volution num\u00e9rique.&nbsp;<\/p>\n\n\n\n<p>L\u2019Europe, au fond, vit une mue profonde&#160;: notre Vieux-Continent s\u2019est con\u00e7u pendant des si\u00e8cles comme le centre de l\u2019Histoire, avant de d\u00e9cider d\u2019en sortir, traumatis\u00e9 par ses propres actions. Apr\u00e8s avoir pris la marche rationnelle de l\u2019int\u00e9gration \u00e9conomique, l\u2019Europe s\u2019\u00e9veille de nouveau \u00e0 retrouver sa puissance dans la marche de l\u2019Histoire&#160;; alors elle se cherche, avec ces interrogations qui pr\u00e9c\u00e8dent toute grande d\u00e9cision. Elle est, en somme, entre deux \u00e9tats. Je crois que notre mission \u00e0 nous, acteurs politiques est d\u2019encourager cet \u00e9lan et d\u2019accompagner ce grand saut, en veillant toujours \u00e0 ce que ses valeurs, libert\u00e9, d\u00e9mocratie, \u00e9mancipation, demeurent la boussole qui oriente ses choix et guide ses actions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&#160;&#160;De l\u2019Ukraine, \u00e0 la Moldavie, aux Balkans Occidentaux, jusqu\u2019au Royaume-Uni et la Norv\u00e8ge, nous allons construire un \u00ab&#160;&#160;grand continent&#160;&#160;\u00bb plus uni, davantage coordonn\u00e9, plus fort et int\u00e9gr\u00e9 \u00e9conomiquement.&#160;&#160;\u00bb<br \/>\nLa Secr\u00e9taire d&rsquo;\u00c9tat charg\u00e9e de l&rsquo;Europe pr\u00e9sente quatre chantiers pour faire \u00e9merger la souverainet\u00e9 continentale \u2014\u00a0une pi\u00e8ce de doctrine sign\u00e9e Laurence Boone.<\/p>\n","protected":false},"author":10,"featured_media":168432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-editorials.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":13,"footnotes":""},"categories":[1731],"tags":[],"staff":[3282],"editorial_format":[4941],"serie":[],"audience":[],"geo":[1917],"class_list":["post-168428","post","type-post","status-publish","format-standard","hentry","category-politique","staff-laurence-boone","editorial_format-doctrine","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":168432,"excerpt":"\u00abDe l\u2019Ukraine, \u00e0 la Moldavie, aux Balkans Occidentaux, jusqu\u2019au Royaume-Uni et la Norv\u00e8ge, nous allons construire un \u00abgrand continent\u00bb plus uni, davantage coordonn\u00e9, plus fort et int\u00e9gr\u00e9 \u00e9conomiquement.\u00bb\r\nLa Secr\u00e9taire d'\u00c9tat charg\u00e9e de l'Europe pr\u00e9sente quatre chantiers pour faire \u00e9merger la souverainet\u00e9 continentale \u2014\u00a0une pi\u00e8ce de doctrine sign\u00e9e Laurence Boone.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;Europe comme espace-puissance | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Europe comme espace-puissance | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00ab&#160;De l\u2019Ukraine, \u00e0 la Moldavie, aux Balkans Occidentaux, jusqu\u2019au Royaume-Uni et la Norv\u00e8ge, nous allons construire un \u00ab&#160;grand continent&#160;\u00bb plus uni, davantage coordonn\u00e9, plus fort et int\u00e9gr\u00e9 \u00e9conomiquement.&#160;\u00bb La Secr\u00e9taire d&#039;\u00c9tat charg\u00e9e de l&#039;Europe pr\u00e9sente quatre chantiers pour faire \u00e9merger la souverainet\u00e9 continentale \u2014\u00a0une pi\u00e8ce de doctrine sign\u00e9e Laurence Boone.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T04:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T08:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-boone-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-boone-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/\",\"name\":\"L'Europe comme espace-puissance | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg\",\"datePublished\":\"2022-11-21T04:30:00+00:00\",\"dateModified\":\"2023-04-28T08:37:05+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg\",\"width\":1363,\"height\":2254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Europe comme espace-puissance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Europe comme espace-puissance | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Europe comme espace-puissance | Le Grand Continent","og_description":"\u00ab&#160;De l\u2019Ukraine, \u00e0 la Moldavie, aux Balkans Occidentaux, jusqu\u2019au Royaume-Uni et la Norv\u00e8ge, nous allons construire un \u00ab&#160;grand continent&#160;\u00bb plus uni, davantage coordonn\u00e9, plus fort et int\u00e9gr\u00e9 \u00e9conomiquement.&#160;\u00bb La Secr\u00e9taire d'\u00c9tat charg\u00e9e de l'Europe pr\u00e9sente quatre chantiers pour faire \u00e9merger la souverainet\u00e9 continentale \u2014\u00a0une pi\u00e8ce de doctrine sign\u00e9e Laurence Boone.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/","og_site_name":"Le Grand Continent","article_published_time":"2022-11-21T04:30:00+00:00","article_modified_time":"2023-04-28T08:37:05+00:00","og_image":[{"width":2560,"height":1433,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-boone-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-boone-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/","name":"L'Europe comme espace-puissance | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg","datePublished":"2022-11-21T04:30:00+00:00","dateModified":"2023-04-28T08:37:05+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg","width":1363,"height":2254},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/21\/leurope-comme-espace-puissance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Europe comme espace-puissance"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":3282,"name":"Laurence Boone","slug":"laurence-boone","description":"Laurence Boone occupe actuellement plusieurs fonctions cl\u00e9s dans le domaine de l\u2019\u00e9conomie. Elle est Directrice G\u00e9n\u00e9rale de Santander en France. Elle a \u00e9t\u00e9 Secr\u00e9taire d\u2019\u00c9tat aupr\u00e8s de la ministre de l\u2019Europe et des Affaires \u00e9trang\u00e8res, charg\u00e9e de l\u2019Europe (2022-2024). Elle est \u00e9galement membre du Conseil strat\u00e9gique SDA Bocconi et professeur associ\u00e9 \u00e0 Sciences-Po.","first_name":"Laurence","last_name":"Boone","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_1166_Laurence-Boone_umbertocostamagna\u00a92023.png","width":1549,"height":1549,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg","width":1363,"height":2254,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/Unknown-11.jpg","width":1363,"height":2254,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/168428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=168428"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/168428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/168432"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=168428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=168428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=168428"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=168428"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=168428"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=168428"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=168428"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=168428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}