{"id":167624,"date":"2022-11-15T12:32:19","date_gmt":"2022-11-15T11:32:19","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=167624"},"modified":"2022-11-15T14:28:24","modified_gmt":"2022-11-15T13:28:24","slug":"iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/","title":{"rendered":"Iran&#160;: les symboles d&rsquo;une r\u00e9volte, une conversation avec Farhad Khosrokhavar"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Le mouvement r\u00e9volutionnaire qui se d\u00e9roule en Iran depuis bient\u00f4t deux mois a comme point de d\u00e9part la mort de Mahs\u00e2 Amini, jeune femme kurde tu\u00e9e par la police des m\u0153urs car elle aurait mal port\u00e9 un voile. Est-ce que ce mouvement va conduire \u00e0 une d\u00e9sislamisation de la soci\u00e9t\u00e9 iranienne&#160;?<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Farhad Khosrokhavar<\/strong><\/h4>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-small\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/farhad-khosrokhavar-plus-daech-interdit-plus-il-devient-attrayantm274816_0.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"567\"\n        data-pswp-height=\"569\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/farhad-khosrokhavar-plus-daech-interdit-plus-il-devient-attrayantm274816_0-125x125.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/farhad-khosrokhavar-plus-daech-interdit-plus-il-devient-attrayantm274816_0-330x331.png\"\r\n                media=\"(min-width: 375px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/farhad-khosrokhavar-plus-daech-interdit-plus-il-devient-attrayantm274816_0-125x125.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>Je ne crois pas \u00e0 la d\u00e9sislamisation et donc \u00e0 la la\u00efcisation, au sens propre du terme, de la soci\u00e9t\u00e9 iranienne. On voit dans ce mouvement une forme de s\u00e9cularisation, effective, ind\u00e9niable, mais cette s\u00e9cularisation doit \u00eatre replac\u00e9e dans le contexte de la culture iranienne.<\/p>\n\n\n\n<p>Tout d\u2019abord, les manifestations ont d\u00e9but\u00e9 par le rejet du voile obligatoire. Il ne s\u2019agit pas d&rsquo;un mouvement de rejet du voile en g\u00e9n\u00e9ral. On voit tr\u00e8s bien dans les manifestations que des femmes voil\u00e9es accompagnent des femmes non voil\u00e9es pour d\u00e9noncer cette contrainte qui consiste \u00e0 dicter aux femmes leur attitude et leurs appr\u00eats vestimentaires. Ici, en France, il y a une partie des f\u00e9ministes qui a affirm\u00e9 que si le voile \u00e9tait enlev\u00e9 l\u00e0-bas il fallait aussi qu\u2019on l\u2019enl\u00e8ve aussi ici. Or en Iran, il ne s&rsquo;agit pas de d\u00e9noncer le voile, mais de dire que la femme doit d\u00e9cider elle-m\u00eame. Donc personnellement, conform\u00e9ment \u00e0 ce qui se passe en Iran, je pense que c&rsquo;est aux femmes elles-m\u00eames de d\u00e9cider. Si des femmes veulent porter le foulard ou le voile, qu&rsquo;elles le portent &#8211; \u00e9videmment pas le voile int\u00e9gral, puisqu\u2019il d\u00e9robe \u00e0 la femme son identit\u00e9 dans une soci\u00e9t\u00e9 ou les identit\u00e9s sont constitu\u00e9es par le visage. Si elles ne veulent pas le porter, aucune instance ne devrait tenter d\u2019infl\u00e9chir leur volont\u00e9 souveraine \u00e0 ce sujet.<\/p>\n\n\n\n<p>La diff\u00e9rence majeure, bien entendu, est que la France est une d\u00e9mocratie, ce qui fait qu\u2019il y a des droits inali\u00e9nables de l&rsquo;individu, m\u00eame voil\u00e9, alors qu&rsquo;en Iran les femmes non voil\u00e9es n&rsquo;ont pas de droits et par cons\u00e9quent sont soumises \u00e0 la r\u00e9pression, avec des amendes importantes, des coups de fouet, parfois des peines de prison et, dans le cas de Mahs\u00e2 Amini, la mort brutale.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>&nbsp;Hommes et femmes sont dans un rapport de coop\u00e9ration contre un ennemi commun qui est l&rsquo;Etat th\u00e9ocratique, c&rsquo;est-\u00e0-dire un Etat qui veut d\u00e9truire la soci\u00e9t\u00e9 au nom de principes islamiques de plus en plus rigidifi\u00e9s.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Dans ce contexte, les hommes et les femmes de 15 \u00e0 25 ans, c\u2019est-\u00e0-dire de la troisi\u00e8me g\u00e9n\u00e9ration apr\u00e8s la r\u00e9volution de 1979, sont en r\u00e9volte, ensemble, contre le r\u00e9gime th\u00e9ocratique. On voit tr\u00e8s bien que les hommes soutiennent les femmes et participent \u00e0 l&rsquo;affrontement avec les forces de l\u2019ordre dont la cruaut\u00e9 et la violence n\u2019est plus \u00e0 d\u00e9crire. Hommes et femmes sont dans un rapport de coop\u00e9ration contre un ennemi commun qui est l&rsquo;Etat th\u00e9ocratique, c&rsquo;est-\u00e0-dire un Etat qui veut d\u00e9truire la soci\u00e9t\u00e9 au nom de principes islamiques de plus en plus rigidifi\u00e9s, qui ne sont pas les principes traditionnels de l\u2019islam mais frott\u00e9s de ceux du totalitarisme moderne pour l\u00e9gitimer un Etat autocratique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Poursuivons sur la question du voile. Dans <em>L&rsquo;Utopie sacrifi\u00e9e, la sociologie de la r\u00e9volution iranienne<\/em>, vous rappelez comment, apr\u00e8s la r\u00e9volution, \u00ab&#160;tous les maux sont d\u00e9sormais imput\u00e9s \u00e0 la femme, \u00e0 la femme mal voil\u00e9e. Certains vont m\u00eame jusqu&rsquo;\u00e0 identifier en elle la source du mal absolu. De nombreux sermons des mollahs ou exhortations moralisantes des Bassidj transforment en cette p\u00e9riode la femme en objet d&rsquo;anath\u00e8me, en bouc \u00e9missaire&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-167624' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#easy-footnote-bottom-1-167624' title='Khosrokhavar, Farhad, &lt;em&gt;L\u2019Utopie sacrifi\u00e9e&lt;\/em&gt;, &lt;em&gt;Sociologie de la R\u00e9volution iranienne&lt;\/em&gt;, Paris, Presses de la FNSP, 1993, p. 132,'><sup>1<\/sup><\/a><\/span><\/span>. L&rsquo;impression se d\u00e9gage que ce qu&rsquo;on voit dans le mouvement serait justement la fin de l&rsquo;opposition des genres au sein de la soci\u00e9t\u00e9 iranienne, \u00e0 travers les manifestations de solidarit\u00e9 des hommes \u00e0 l&rsquo;\u00e9gard du mouvement des femmes et des femmes \u00e0 l&rsquo;\u00e9gard des hommes. On pense notamment aux slogans \u00ab&#160;femme, vie, libert\u00e9&#160;\u00bb (\u0632\u0646 \u0632\u0646\u062f\u06af\u06cc \u0622\u0632\u0627\u062f\u06cc) et \u00ab&#160;homme, patrie, prosp\u00e9rit\u00e9&#160;\u00bb (\u0645\u0631\u062f \u0645\u06cc\u0647\u0646 \u0622\u0628\u0627\u062f\u06cc)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-167624' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#easy-footnote-bottom-2-167624' title='En persan, \u00ab&amp;#160;libert\u00e9&amp;#160;\u00bb et \u00ab&amp;#160;prosp\u00e9rit\u00e9&amp;#160;\u00bb sont tr\u00e8s proches phon\u00e9tiquement&amp;#160;: \u00ab&amp;#160;\u00e2z\u00e2di&amp;#160;\u00bb et \u00ab&amp;#160;\u00e2b\u00e2di&amp;#160;\u00bb.'><sup>2<\/sup><\/a><\/span><\/span>qui se r\u00e9pondent dans de nombreuses manifestations. Est-ce que vous diriez que la bouc-\u00e9missarisation des femmes, qui a \u00e9t\u00e9 une des dimensions de la R\u00e9volution des premi\u00e8res ann\u00e9es de la R\u00e9volution, puis ensuite de la R\u00e9publique islamique, est d\u00e9finitivement r\u00e9volue&#160;?<\/strong><\/h3>\n\n\n\n<p>Je crois que c&rsquo;est pr\u00e9cis\u00e9ment le rejet de ce qu&rsquo;on pourrait appeler la th\u00e9ocratie islamique, dans le sens que vous venez de d\u00e9crire, qui voit dans la femme son talon d\u2019Achille du pouvoir. Mais pour comprendre ce sentiment de faiblesse vis-\u00e0-vis du corps des femmes, je voudrais d\u2019abord revenir sur les causes de ce mouvement.<\/p>\n\n\n\n<p>Tout d&rsquo;abord, en Iran, le foss\u00e9 entre les classes sociales s&rsquo;est transform\u00e9 en un gouffre de classes. Les riches du r\u00e9gime ont r\u00e9ussi par des passe-droits, par le client\u00e9lisme, par le bakchich et par une corruption r\u00e9pandue, \u00e0 s\u2019enrichir de fa\u00e7on ind\u00e9cente, comme le montrent les d\u00e9nonciations sur internet, souvent documents \u00e0 l\u2019appui. \u00c0 c\u00f4t\u00e9 de cela, un tiers de sa population iranienne vit aujourd\u2019hui sous le seuil de pauvret\u00e9, selon les normes internationales des Nations Unies. Or, l&rsquo;Iran du temps du Shah \u00e9tait une soci\u00e9t\u00e9 beaucoup plus prosp\u00e8re qui permettait aux classes moyennes d\u2019acc\u00e9der \u00e0 un confort ind\u00e9niable. Ces classes moyennes sont de plus en plus \u00e9cras\u00e9es depuis une quinzaine d&rsquo;ann\u00e9es et sont en voie de prol\u00e9tarisation.<\/p>\n\n\n\n<p>Sur le plan \u00e9cologique, c&rsquo;est la catastrophe. Le r\u00e9gime n&rsquo;a rien fait pour att\u00e9nuer les rigueurs du r\u00e9chauffement climatique. On voit, par exemple, des p\u00e9nuries d&rsquo;eau dans beaucoup de provinces en Iran et le dess\u00e9chement des fleuves caus\u00e9 par des forages inconsid\u00e9r\u00e9s par les tenants du r\u00e9gime pour s&rsquo;enrichir \u00e0 l&rsquo;abri de toute contrainte l\u00e9gale et le nombre incroyable de digues (plusieurs centaines&#160;!) pour en faire assumer les frais par l\u2019Etat au service de l\u2019Arm\u00e9e des pasdaran qui empoche ainsi des sommes \u00e9lev\u00e9es.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Sur le plan \u00e9cologique, c&rsquo;est la catastrophe. Le r\u00e9gime n&rsquo;a rien fait pour att\u00e9nuer les rigueurs du r\u00e9chauffement climatique.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Au niveau international, on remarque la constante d\u00e9gradation de la situation de l&rsquo;Iran, qui n\u2019a pratiquement plus d&rsquo;amis sauf la Syrie, le Hezbollah libanais et quelquefois des pays qui sont en rupture de ban avec la soci\u00e9t\u00e9 internationale, et de plus en plus la Russie, qui trouve en Iran un alli\u00e9 s\u00fbr qui l\u2019aide avec ses drones \u00e0 bombarder l&rsquo;Ukraine, bref l\u2019alliance de deux parias.<\/p>\n\n\n\n<p>Donc on est dans une situation o\u00f9 la troisi\u00e8me g\u00e9n\u00e9ration a le sentiment d&rsquo;un \u00e9chec total, d\u2019un fiasco g\u00e9n\u00e9ralis\u00e9, elle se sent sans avenir en vivant un pr\u00e9sent morose avec une r\u00e9pression qui s&rsquo;intensifie, notamment contre les femmes, au fur et \u00e0 mesure que le r\u00e9gime se rigidifie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment expliquer r\u00e9trospectivement que le voile ait \u00e9t\u00e9 accept\u00e9 lors de la r\u00e9volution de 1979&#160;?<\/strong><\/h3>\n\n\n\n<p>Lors de la R\u00e9volution de 1979, les femmes de gauche, les intellectuelles et les femmes engag\u00e9es pensaient qu\u2019il s&rsquo;agissait d&rsquo;une r\u00e9volution contre la grande bourgeoisie et qu\u2019il fallait que les femmes acceptent de sacrifier un certain nombre de leurs privil\u00e8ges en acceptant le voile, pour aller dans le sens de la r\u00e9volution. Elles esp\u00e9raient qu\u2019une fois que la r\u00e9volution petite bourgeoise serait accomplie par le clerg\u00e9 iranien sous la direction de l&rsquo;ayatollah Khomeini, elles pourraient passer \u00e0 la r\u00e9volution prol\u00e9tarienne et donc \u00e9liminer ais\u00e9ment cette petite bourgeoisie incarn\u00e9e par le clerg\u00e9.<\/p>\n\n\n\n<p>On sait que cette analyse \u00e9tait totalement fausse et que le r\u00e9sultat n&rsquo;a pas \u00e9t\u00e9 l&rsquo;\u00e9limination du clerg\u00e9 comme d\u00e9tenteur du pouvoir, mais l&rsquo;\u00e9limination de la gauche, en particulier de la gauche marxiste et de la gauche radicale comme courant politique prenant part au devenir de la soci\u00e9t\u00e9. Maintenant la nouvelle g\u00e9n\u00e9ration des jeunes femmes et hommes sait tr\u00e8s bien que la contrainte du voile doit \u00eatre d\u00e9nonc\u00e9e comme telle, comme atteinte \u00e0 l\u2019int\u00e9grit\u00e9 de l\u2019individu, au d\u00e9ni de sa libert\u00e9 fondamentale d\u2019incarner son corps propre.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_01092069_000001-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_01092069_000001-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_01092069_000001-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_01092069_000001-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_01092069_000001-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 SOPA Images\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment expliquer une telle rupture aujourd\u2019hui entre la nature religieuse du pouvoir et la soci\u00e9t\u00e9 civile&#160;?<\/strong><\/h3>\n\n\n\n<p>Je dirais qu\u2019il y a un changement total de culture, et cela en d\u00e9pit du fait que, depuis quatre d\u00e9cennies, on assiste \u00e0 ce qu&rsquo;on pourrait appeler une tentative de d\u00e9s\u00e9cularisation de la soci\u00e9t\u00e9 par le r\u00e9gime islamique.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Je dirais qu\u2019il y a un changement total de culture, et cela en d\u00e9pit du fait que, depuis quatre d\u00e9cennies, on assiste \u00e0 ce qu&rsquo;on pourrait appeler une tentative de d\u00e9s\u00e9cularisation de la soci\u00e9t\u00e9 par le r\u00e9gime islamique. Ainsi, la socialisation avec la diaspora iranienne \u00e0 l\u2019\u00e9tranger a limit\u00e9 voire annul\u00e9 les effets de l\u2019endoctrinement de l&rsquo;\u00e9cole en Iran.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le syst\u00e8me de l&rsquo;\u00e9ducation nationale a \u00e9t\u00e9 b\u00e2ti sur la destruction de l&rsquo;image de la femme comme \u00eatre autonome. Par cons\u00e9quent, les jeunes filles et les femmes qui actuellement sont dans la rue avec de jeunes hommes sont celles qui \u00e9taient cens\u00e9es \u00eatre endoctrin\u00e9es par ce syst\u00e8me ferm\u00e9 qui refuse l&rsquo;ind\u00e9niable modernit\u00e9 des jeunes femmes.<\/p>\n\n\n\n<p>On peut comprendre cette situation paradoxale si on prend en compte l&rsquo;\u00e9poque de socialisation de ces jeunes personnes. Aujourd\u2019hui, ils \u00e9voluent dans un syst\u00e8me o\u00f9 il y a une diaspora iranienne d&rsquo;au 3 \u00e0 4 millions d\u2019Iraniens \u00e0 l&rsquo;\u00e9tranger qui est tr\u00e8s \u00e9troitement associ\u00e9e \u00e0 la classe moyenne iranienne. Pratiquement toutes les familles ont quelqu&rsquo;un \u00e0 l&rsquo;\u00e9tranger et leurs relations sont des relations pr\u00e9serv\u00e9es, non rompues, \u00e0 l\u2019inverse des Russes blancs qui une fois partie de la Russie au moment de la R\u00e9volution d&rsquo;Octobre ont \u00e9t\u00e9 totalement s\u00e9par\u00e9s de la soci\u00e9t\u00e9 russe. Ce ph\u00e9nom\u00e8ne est renforc\u00e9 par internet. Ainsi, la socialisation avec la diaspora iranienne \u00e0 l\u2019\u00e9tranger a limit\u00e9 voire annul\u00e9 les effets de l\u2019endoctrinement de l&rsquo;\u00e9cole en Iran.<\/p>\n\n\n\n<p>Ensuite, l\u2019autre cause de r\u00e9sistance \u00e0 la d\u00e9s\u00e9cularisation est la tradition familiale. En Iran surtout, des classes moyennes sous le Shah avaient d\u00e9j\u00e0 presqu\u2019un demi-si\u00e8cle d\u2019exp\u00e9rience de s\u00e9cularisation par le haut, qui avait abouti certes \u00e0 des r\u00e9actions contre cette forme de s\u00e9cularisation brutale (le fait de faire \u00f4ter brutalement le voile des femmes par la police dans les ann\u00e9es 1930), mais une partie des classes moyennes avait adopt\u00e9 et int\u00e9rioris\u00e9 cette s\u00e9cularisation. Cons\u00e9quence \u00e0 long terme de cela, on voit bien que nombre de jeunes gens issus de l&rsquo;\u00e9lite de cette th\u00e9ocratie adoptent des modes de vie qui sont en rupture avec ceux de leurs parents et de leurs grands-parents. Ils choisissent le mod\u00e8le s\u00e9cularis\u00e9 de la vie avec promiscuit\u00e9 des genres et refusent de se soumettre aux diktats de l\u2019islamisme lorsqu\u2019ils vivent \u00e0 l\u2019\u00e9tranger.<\/p>\n\n\n\n<p>En somme, le syst\u00e8me d&rsquo;endoctrinement et de d\u00e9s\u00e9cularisation mis en place par le pouvoir a totalement \u00e9chou\u00e9. M\u00eame dans les familles traditionnelles, nombre de jeunes, femmes et hommes confondus rejettent la contrainte non seulement du voile, mais aussi toutes les formes de pudeur \u00ab&#160;islamique&#160;\u00bb, qui sont aussi des formes de pudeur traditionnelle, \u00e0 savoir que la femme ne doit pas regarder l&rsquo;homme dans les yeux et qu\u2019on doit respecter la s\u00e9paration des sexes. M\u00eame dans des villes religieuses comme \u00e0 Qom, une part grandissante de la jeunesse rejette la<s> <\/s>sociabilit\u00e9 traditionnelle qui consistait \u00e0 proc\u00e9der \u00e0 la s\u00e9gr\u00e9gation entre jeunes hommes et jeunes femmes, entre hommes et femmes non mari\u00e9s. En 2009, j&rsquo;avais fait un livre pour montrer que, \u00e0 Qom, ville de formation religieuse de l\u2019Iran, la nouvelle subjectivit\u00e9 \u00e9tait en place et qu&rsquo;elle \u00e9tait d\u00e9j\u00e0 en divergence par rapport aux orientations culturelles du clerg\u00e9 et des couches traditionnelles&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-167624' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#easy-footnote-bottom-3-167624' title='Khosrokhavar, Farhad, Nikpey Amir, &lt;em&gt;Avoir Vingt ans au pays des Ayatollahs&lt;\/em&gt;, Paris, Robert Lafont, 2009.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quel r\u00f4le les \u00e9tudiants jouent-ils dans ce processus que vous d\u00e9crivez&#160;?<\/strong><\/h3>\n\n\n\n<p>En 1979, il y avait 300 \u00e0 400 000 \u00e9tudiants en Iran. Actuellement, il y en a plus de 3 millions, dont la moiti\u00e9 de jeunes femmes. On trouve dans ces universit\u00e9s des formes de sociabilit\u00e9 et des modes d&rsquo;acquisition du savoir qui emp\u00eachent le r\u00e9gime d\u2019imposer son point de vue d\u00e9s\u00e9cularisant \u00e0 la soci\u00e9t\u00e9. Aujourd\u2019hui, l&rsquo;universit\u00e9 est le foyer principal de la r\u00e9volte contre le r\u00e9gime en place.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Aujourd\u2019hui, l&rsquo;universit\u00e9 est le foyer principal de la r\u00e9volte contre le r\u00e9gime en place.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous parlez de mouvement de nature r\u00e9volutionnaire. Vous avez \u00e9tudi\u00e9 en tant que sociologue et anthropologue la r\u00e9volution de 1979, dont vous avez identifi\u00e9 plusieurs causes, comme le bouleversement mental et mat\u00e9riel de la soci\u00e9t\u00e9, la modernisation de la soci\u00e9t\u00e9 entre les ann\u00e9es 1930 et les ann\u00e9es 1970, la d\u00e9sint\u00e9gration de l&rsquo;armature communautaire, une rupture g\u00e9n\u00e9rationnelle que vous identifiez aussi \u00e0 propos de cette r\u00e9volution en cours. \u00c0 quel point peut-on faire des parall\u00e8les entre la r\u00e9volution de 1979 et le mouvement en cours aujourd\u2019hui&#160;? Est ce qu&rsquo;il y a un bouleversement mental, par exemple, de la m\u00eame ampleur&#160;?<\/strong><\/h3>\n\n\n\n<p>Pour commencer, je ne vois pas comment un mouvement d\u2019une telle ampleur pourrait se produire sans qu&rsquo;il y ait un bouleversement au niveau de la subjectivit\u00e9. C&rsquo;est ce que les sociologues, Foucault, Touraine et nous-m\u00eames appelons la subjectivation. Il y a l\u2019affirmation de soi dans une subjectivit\u00e9 nouvelle qui ne reproduit pas les anciennes formes de subjectivit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il y a l\u2019affirmation de soi dans une subjectivit\u00e9 nouvelle qui ne reproduit pas les anciennes formes de subjectivit\u00e9.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La r\u00e9volution iranienne de 1979 s&rsquo;est produite apr\u00e8s une p\u00e9riode de grande modernisation. A l\u2019inverse, le mouvement actuel se produit apr\u00e8s des d\u00e9cennies de d\u00e9modernisation. Sur le plan \u00e9conomique, il y a une r\u00e9gression tr\u00e8s nette. Par exemple, en 1979 le revenu par habitant de l&rsquo;Iran \u00e9tait entre deux et trois fois sup\u00e9rieur \u00e0 celui de la Turquie. Aujourd\u2019hui, c\u2019est l&rsquo;inverse. Pour prendre un autre exemple, le dollar au moment de la r\u00e9volution iranienne valait sept toumans&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-167624' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#easy-footnote-bottom-4-167624' title='La monnaie iranienne est le \u00ab&amp;#160;rial&amp;#160;\u00bb. Un \u00ab&amp;#160;touman&amp;#160;\u00bb vaut dix rials.'><sup>4<\/sup><\/a><\/span><\/span>. Or maintenant, il est aux alentours de 36000 toumans, c&rsquo;est \u00e0 dire plus de cinq mille fois sup\u00e9rieur. L\u2019appauvrissement se manifeste aussi par la d\u00e9multiplication des bidonvilles, qui n\u2019existaient presque pas sous le Shah. Aujourd\u2019hui, plus de 20&#160;% des habitats en Iran pourraient \u00eatre consid\u00e9r\u00e9s comme des bidonvilles. Les rares acquis de l\u2019\u00e9conomie iranienne sont accapar\u00e9s par une \u00e9lite kleptocratique qui se permet d&#8217;empocher les biens et services sans avoir \u00e0 rendre compte \u00e0 qui que ce soit.<\/p>\n\n\n\n<p>En un sens, la modernisation intense du temps du Shah infligeait la violence \u00e0 la soci\u00e9t\u00e9 sur plusieurs plans. Aujourd\u2019hui, la d\u00e9modernisation provoque aussi de la violence, mais de fa\u00e7on d\u00e9multipli\u00e9e parce que la soci\u00e9t\u00e9 souffre de la perte de son pouvoir d&rsquo;achat, de la r\u00e9gression sociale et \u00e9conomique et de la r\u00e9duction d&rsquo;une bonne partie d\u2019elle \u00e0 la pauvret\u00e9 extr\u00eame. Le mouvement actuel est fond\u00e9 sur la d\u00e9nonciation de cette injustice sociale, des erreurs \u00e9conomiques et de la corruption en plus du d\u00e9ni de dignit\u00e9 aux femmes, mais aussi d\u2019une autre mani\u00e8re, aux hommes.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La r\u00e9volution iranienne de 1979 s&rsquo;est produite apr\u00e8s une p\u00e9riode de grande modernisation. A l\u2019inverse, le mouvement actuel se produit apr\u00e8s des d\u00e9cennies de d\u00e9modernisation. Par cons\u00e9quent, le r\u00e9gime est une sorte de thanatocratie qui s\u2019apparente de plus en plus, par la brutalit\u00e9 de son action, au r\u00e9gime syrien.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L\u2019Iran a commenc\u00e9 par \u00eatre une th\u00e9ocratie apr\u00e8s la r\u00e9volution de 1979, qui s\u2019est transform\u00e9e en une ploutocratie, elle-m\u00eame devenue une kleptocratie, qui est maintenant une thanatocratie c&rsquo;est \u00e0 dire un r\u00e9gime qui depuis 2015 n&rsquo;h\u00e9site pas \u00e0 tuer massivement la population, comme lors des mouvements de protestation de 2015-2019, o\u00f9 y a eu plus de 1500 morts, quelquefois par des tirs \u00e0 bout portant et par l\u2019utilisation de chars, sans compter les milliers de tortur\u00e9s.<\/p>\n\n\n\n<p>Aujourd\u2019hui, il y a plus de 14000 personnes emprisonn\u00e9es dans des conditions dramatiques, et plus de 330 morts av\u00e9r\u00e9s dont une quarantaine de mineurs. Beaucoup ne sont pas d\u00e9clar\u00e9s parce que les familles sont mises sous pression. Par cons\u00e9quent, le r\u00e9gime est une sorte de thanatocratie qui s\u2019apparente de plus en plus, par la brutalit\u00e9 de son action, au r\u00e9gime syrien.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qu\u2019entendez-vous par l\u2019id\u00e9e d\u2019une transformation de la subjectivit\u00e9 de la population iranienne&#160;?<\/strong><\/h3>\n\n\n\n<p>Je dis qu\u2019il y a d\u00e9sormais une subjectivit\u00e9 r\u00e9volutionnaire parce que si demain le r\u00e9gime d\u00e9clarait le port du voile non-obligatoire, je ne pense pas que le mouvement s&rsquo;arr\u00eaterait. En effet, le slogan qui au commencement \u00e9tait \u00ab&#160;femme, vie, libert\u00e9&#160;\u00bb s&rsquo;est radicalis\u00e9. Maintenant c&rsquo;est plut\u00f4t \u00ab&#160;\u00c0 mort le dictateur&#160;\u00bb, \u00ab&#160;\u00e0 mort la dictature&#160;\u00bb. Et c&rsquo;est dans ce sens-l\u00e0 qu&rsquo;il y a une subjectivit\u00e9 r\u00e9volutionnaire.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Je dis qu\u2019il y a d\u00e9sormais une subjectivit\u00e9 r\u00e9volutionnaire parce que si demain le r\u00e9gime d\u00e9clarait le port du voile non-obligatoire, je ne pense pas que le mouvement s&rsquo;arr\u00eaterait.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Jusqu&rsquo;\u00e0 pr\u00e9sent n\u00e9anmoins, c\u2019est un mouvement \u00e9clat\u00e9, sans leadership, sans organisation, non pas parce qu\u2019ils n&rsquo;en veulent pas, mais parce que le r\u00e9gime r\u00e9prime toute personne qui s\u2019\u00e9l\u00e8ve au-dessus de la m\u00eal\u00e9e&#160;: il l\u2019arr\u00eate, la met en prison, la torture et parfois l&rsquo;\u00e9limine. C\u2019est le d\u00e9fi de ce mouvement&#160;: effectuer une transition entre ce qu\u2019on pourrait appeler un temp\u00e9rament r\u00e9volutionnaire et une r\u00e9volution effective. Comment proc\u00e9der&#160;?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cela appelle deux questions<strong>. D&rsquo;une part, est-ce que le mouvement va se construire sur une longue dur\u00e9e, sur plusieurs mois ou m\u00eame plusieurs ann\u00e9es, comme la r\u00e9volution de 1979 qui avait commenc\u00e9 d\u00e8s janvier 1978&#160;? D\u2019autre part, quelle importance accordez-vous \u00e0 la martyrologie des manifestations, c\u2019est-\u00e0-dire \u00e0 la r\u00e9utilisation des traditions de l\u2019islam chiite, en pr\u00e9sentant les personnes tu\u00e9es par la police comme des martyrs, et en les comm\u00e9morant 40 jours apr\u00e8s leur d\u00e9c\u00e8s, comme le veut le chiisme&#160;?<\/strong><\/h3>\n\n\n\n<p>On voit tr\u00e8s bien que le mouvement continue apr\u00e8s huit semaines, contrairement \u00e0 ce que pr\u00e9tend le pouvoir, puisque depuis plusieurs semaines, il affirme l&rsquo;avoir mat\u00e9. Les c\u00e9r\u00e9monies du quaranti\u00e8me jour ont \u00e0 cet \u00e9gard un r\u00f4le essentiel. En effet, le pouvoir arrive \u00e0 mater les premiers jours de comm\u00e9moration d\u2019un d\u00e9c\u00e8s&#160;: le premier, le troisi\u00e8me, le septi\u00e8me. Mais dans de nombreux cas, le quaranti\u00e8me jour, les manifestations se constituent autour du cimeti\u00e8re et rassemblent quelques milliers de manifestants en d\u00e9pit des assauts des forces de s\u00e9curit\u00e9 du r\u00e9gime, des milices, dont la cruaut\u00e9 est insurpassable.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le martyre qui avait un ancrage religieux dans la r\u00e9volution de 1979 est d\u00e9sormais en passe de s\u00e9cularisation.&nbsp;La mort est attribu\u00e9e au pouvoir comme l&rsquo;expression disgracieuse de sa face r\u00e9elle. C&rsquo;est ce que j&rsquo;appelle la thanatocratie au lieu de la martyropathie.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cependant, la signification du martyre a chang\u00e9. Le martyre qui avait un ancrage religieux dans la r\u00e9volution de 1979 est d\u00e9sormais en passe de s\u00e9cularisation. Je ne dis pas d\u00e9sislamisation, mais s\u00e9cularisation. C\u2019est-\u00e0-dire, qu\u2019il y a toujours un cr\u00e9dit accord\u00e9 \u00e0 l&rsquo;islam, mais \u00e0 une version de l&rsquo;islam qui est soutenue par nombre d&rsquo;intellectuels iraniens qu&rsquo;on appelle les nouveaux intellectuels religieux (\u0627\u0646\u062f\u06cc\u0634\u0645\u0646\u062f\u0627\u0646 \u062f\u06cc\u0646\u06cc), comme Abdolkarim Soroush, Mohammad Mojtahed Shabestari ou Mohsen Kadivar, qui ont eu une influence \u00e9norme dans la d\u00e9nonciation de ce qu&rsquo;on appelle la souverainet\u00e9 de la doctrine khomeyniste du docteur de la loi islamique ou v\u00e9l\u00e2yat-\u00e9 faqih (\u0648\u0644\u0627\u06cc\u062a \u0641\u0642\u06cc\u0647) qui a \u00e9t\u00e9 la cl\u00e9 de vo\u00fbte de la th\u00e9ocratie islamique en Iran. Aujourd&rsquo;hui, on voit bien qu\u2019une \u00e9tape a \u00e9t\u00e9 franchie. La r\u00e9f\u00e9rence \u00e0 l&rsquo;islam est quasiment inexistante dans les manifestations, ce qui ne veut pas dire que la soci\u00e9t\u00e9 s&rsquo;est d\u00e9sislamis\u00e9e. Cela veut dire qu&rsquo;il y a une rupture avec l&rsquo;islam th\u00e9ocratique du r\u00e9gime au nom d\u2019un islam int\u00e9rieur qui n\u2019interviendrait pas dans la gestion des affaires politique de la Cit\u00e9.<\/p>\n\n\n\n<p>La deuxi\u00e8me diff\u00e9rence majeure avec le pass\u00e9, c&rsquo;est que ces jeunes ne veulent pas mourir. A l\u2019\u00e9poque de la r\u00e9volution de 1979 et de la guerre avec l\u2019Irak, il y avait des jeunes qui aspiraient \u00e0 mourir autant pour sauver la soci\u00e9t\u00e9 que pour sauver leur \u00e2me en d\u00e9sarroi. Ces groupes de jeunes, je les avais appel\u00e9s les martyropathes. On n\u2019en voit plus aujourd\u2019hui. La mort est attribu\u00e9e au pouvoir comme l&rsquo;expression disgracieuse de sa face r\u00e9elle. C&rsquo;est ce que j&rsquo;appelle la thanatocratie au lieu de la martyropathie. Cette thanatocratie remet en cause la l\u00e9gitimit\u00e9 du pouvoir dans la mesure o\u00f9 elle ne peut pas donner la vie, ne peut pas encourager la vie et ne peut abonder que dans le sens de la mort.<\/p>\n\n\n\n<p>On le voit si on se penche sur l\u2019affectologie de ces manifestations. L&rsquo;affect dominant de la r\u00e9volution iranienne de 1979, c\u2019\u00e9tait le martyre accompagn\u00e9 de tristesse et d\u2019un dolorisme qui consistait \u00e0 s&rsquo;apitoyer sur soi-m\u00eame, sur le monde, sur sa situation et de se r\u00e9volter au nom de cette piti\u00e9.<\/p>\n\n\n\n<p>A l\u2019inverse, ce mouvement se construit autour de la joie d\u00e9ni\u00e9e aux jeunes par l\u2019Etat thanatocratique et rabat-joie. La notion de rabat-joie n\u2019est pas adventice, elle est fondamentale o\u00f9 c\u2019est le mode dominant de la perception de cet Etat par les jeunes, voire les moins jeunes. On le voit avec les femmes qui dansent dans la rue, des danses occidentales mais aussi et surtout des danses iraniennes. Cette joie pouvait s\u2019exprimer en priv\u00e9 mais rencontre en public l&rsquo;obstacle de cette inf\u00e2me brigade des m\u0153urs qui est, en un certain sens, la brigade rabat-joie par excellence.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00c0 l\u2019inverse, ce mouvement se construit autour de la joie d\u00e9ni\u00e9e aux jeunes par l\u2019Etat thanatocratique et rabat-joie. Il y a donc une anthropologie nouvelle des affects en Iran qu\u2019il faut identifier et d\u00e9crire. La joie est une composante inali\u00e9nable de cette nouvelle subjectivit\u00e9. C\u2019est au nom de cette joie refus\u00e9e, de cette liesse d\u00e9ni\u00e9e que les jeunes se sont r\u00e9volt\u00e9s.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Il y a donc une anthropologie nouvelle des affects en Iran qu\u2019il faut identifier et d\u00e9crire. La joie est une composante inali\u00e9nable de cette nouvelle subjectivit\u00e9. C\u2019est au nom de cette joie refus\u00e9e, de cette liesse d\u00e9ni\u00e9e que les jeunes se sont r\u00e9volt\u00e9s.<\/p>\n\n\n\n<p>Une troisi\u00e8me diff\u00e9rence essentielle par rapport au pass\u00e9 est que, jusqu\u2019ici, il y avait toujours le souvenir vif du soutien des Etats-Unis et de l&rsquo;Occident \u00e0 l&rsquo;autoritarisme iranien qui \u00e9tait incarn\u00e9 par le Shah. Maintenant, cette soci\u00e9t\u00e9 demande une relation apais\u00e9e \u00e0 l&rsquo;Occident et que cette volont\u00e9 d&rsquo;en d\u00e9coudre avec l&rsquo;Occident, qui est l&rsquo;un des traits de l&rsquo;islamisme radical du r\u00e9gime, soit aussi remise en cause.<\/p>\n\n\n\n<p>Il s&rsquo;agit, en somme, de vivre et de laisser vivre. Il ne s&rsquo;agit absolument pas de faire la guerre \u00e0 l&rsquo;Occident, mais de trouver une relation apais\u00e9e avec l&rsquo;Occident et le monde ext\u00e9rieur. Et l\u00e0 aussi on le voit tr\u00e8s bien dans les slogans, qui montrent un changement de la focale d\u2019animosit\u00e9. Un des slogans dit \u00ab&#160;l\u2019ennemi n\u2019est pas l\u2019Am\u00e9rique&#160;; l\u2019ennemi est chez nous&#160;\u00bb &#8211; c\u2019est-\u00e0-dire le r\u00e9gime th\u00e9ocratique.<\/p>\n\n\n\n<p>Cette volont\u00e9 de vivre dans la joie est en rupture avec la dimension doloriste du martyre telle qu&rsquo;elle avait \u00e9t\u00e9 d\u00e9fendue par Ali Shariati et les autres intellectuels religieux pendant la p\u00e9riode d&rsquo;effervescence de la r\u00e9volution de 1979.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cette revendication d&rsquo;une joie d\u00e9ni\u00e9e avait semble-t-il d\u00e9j\u00e0 exist\u00e9, mais de fa\u00e7on br\u00e8ve, sous le mandat de Mohammed Khatami. Il avait dit lors d\u2019un discours pr\u00e9sidentiel qu\u2019il ne fallait pas toujours dire \u00ab&#160;\u00e0 mort [ceci]&#160;\u00bb mais aussi prendre en compte une forme de positivit\u00e9, qui s&rsquo;exprimait aussi dans ses relations avec l&rsquo;Occident par ce qu&rsquo;il appelait le \u00ab&#160;dialogue des civilisations&#160;\u00bb.<\/strong><\/h3>\n\n\n\n<p>Effectivement, \u00e7a a \u00e9t\u00e9 tr\u00e8s important sur le plan symbolique. Sous le mandat de Khatami, de 1997 \u00e0 2005, la soci\u00e9t\u00e9 a voulu croire qu&rsquo;il y avait la possibilit\u00e9 de transition d&rsquo;un pouvoir th\u00e9ocratique morose, martyropathe, inconciliable avec la modernit\u00e9, vers un r\u00e9gime plus ouvert et pluraliste, qui accepterait de s&rsquo;ouvrir culturellement \u00e0 la modernit\u00e9 par la joie, par l&rsquo;affirmation plut\u00f4t que par la d\u00e9n\u00e9gation.<\/p>\n\n\n\n<p>Khatami a \u00e9chou\u00e9. C&rsquo;est une p\u00e9riode o\u00f9 on attendait beaucoup de cette transition vers un pouvoir semi-ouvert. C\u2019est pr\u00e9cis\u00e9ment l&rsquo;\u00e9chec de cette tentative r\u00e9formiste qui a fait que le pouvoir actuel n&rsquo;a plus aucun lien avec la soci\u00e9t\u00e9 civile en Iran. Avoir r\u00e9prim\u00e9 l\u2019opposition et tous ceux qui refusent cette th\u00e9ocratie hagarde fait que le pouvoir ne sait pas \u00e0 qui parler aujourd\u2019hui.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>C\u2019est pr\u00e9cis\u00e9ment l&rsquo;\u00e9chec de cette tentative r\u00e9formiste qui a fait que le pouvoir actuel n&rsquo;a plus aucun lien avec la soci\u00e9t\u00e9 civile en Iran. Maintenant, plus personne ne pense que les r\u00e9formistes pourraient faire office de m\u00e9diateurs avec le pouvoir actuel.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En somme, la parenth\u00e8se r\u00e9formiste a \u00e9t\u00e9 ferm\u00e9e. Maintenant, plus personne ne pense que les r\u00e9formistes pourraient faire office de m\u00e9diateurs avec le pouvoir actuel. Les jeunes consid\u00e8rent que ce que disent les r\u00e9formistes est tout simplement insignifiant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Il est tr\u00e8s difficile d\u2019imaginer comment cette subjectivit\u00e9 r\u00e9volutionnaire pourrait se transformer en mouvement politique autour de leaders. \u00c0 partir de quand, dans la r\u00e9volution iranienne de 1978-79, pour poursuivre les parall\u00e8les, la subjectivit\u00e9 r\u00e9volutionnaire s&rsquo;est focalis\u00e9e sur la personne de l&rsquo;ayatollah Khomeini&#160;?<\/strong><\/h3>\n\n\n\n<p>Assez rapidement, parce que le r\u00e9gime du Shah avait jou\u00e9 un jeu dangereux en identifiant des opposants tr\u00e8s clairement. L\u2019ayatollah Khomeini, qui se trouvait en Irak, en raison de la constante de sa lutte, est rapidement devenu le chef charismatique du mouvement r\u00e9volutionnaire. Rappelons que pendant toute la p\u00e9riode de transition des six derniers mois, il a dit qu&rsquo;il refuserait de prendre part au pouvoir, qu&rsquo;il se retirerait dans la ville sainte de Qom et qu&rsquo;il laisserait la soci\u00e9t\u00e9 g\u00e9rer ses propres probl\u00e8mes. Apr\u00e8s, il a reconnu qu&rsquo;il avait menti et qu\u2019il avait menti au nom de l&rsquo;islam au nom de Taghieh, de ketman (mensonge pour le bien de l\u2019islam), pour cr\u00e9er une th\u00e9ocratie islamique gouvern\u00e9e par la v\u00e9l\u00e2yat-\u00e9 faqih.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>St\u00e9phane Dudoignon, qui a r\u00e9cemment publi\u00e9 un livre sur les Gardiens de la R\u00e9volution&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-167624' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#easy-footnote-bottom-5-167624' title='Dudoignon, St\u00e9phane, &lt;em&gt;Les Gardiens de la r\u00e9volution islamique d\u2019Iran&lt;\/em&gt;, Paris, CNRS Editions, 2022&lt;\/strong&gt;.&lt;strong&gt;'><sup>5<\/sup><\/a><\/span><\/span> <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/27\/iran-soulevement-unifie-repression-dispersee\/\">identifie dans nos colonnes<\/a> d\u2019une part une division au niveau du syst\u00e8me politique. Ainsi, Ali Larijani disait r\u00e9cemment que le hidjab avait une place secondaire dans le dogme islamique et que l&rsquo;intensification de la r\u00e9pression des \u00ab&#160;mauvais hidjab&#160;\u00bb au cours de l&rsquo;\u00e9t\u00e9 2022 n&rsquo;avait pas lieu d&rsquo;\u00eatre. D&rsquo;autre part, St\u00e9phane Dudoignon explique que, puisque les Gardiens ont un ancrage local tr\u00e8s fort, cela leur permet d\u2019avoir une emprise tr\u00e8s importante sur la population. Mais cette proximit\u00e9 favorise aussi d&rsquo;\u00e9ventuelles divisions par rapport \u00e0 des corps qui seraient tr\u00e8s centralis\u00e9s, comme peuvent l&rsquo;\u00eatre les arm\u00e9es classiques dans les pays dans les \u00c9tat modernes. Que pensez-vous de l&rsquo;hypoth\u00e8se d&rsquo;une division interne du r\u00e9gime&#160;?<\/strong><\/h3>\n\n\n\n<p>Il y a des divisions, au sein du r\u00e9gime, entre diff\u00e9rentes interpr\u00e9tations des manifestations et de leur importance. Le Guide pense qu\u2019il s\u2019agit d\u2019un mouvement lanc\u00e9 par les Etats-Unis et Isra\u00ebl contre l\u2019Iran pour mettre \u00e0 bas le pouvoir l\u00e9gitime de la R\u00e9publique islamique. Cette analyse n\u2019est pas partag\u00e9e par les autres composantes du r\u00e9gime. On a vu de nombreuses personnes dont Ezzatollah Zarghami, &nbsp;qui est ministre et disait que le voile obligatoire n\u2019avait plus lieu d\u2019\u00eatre. N\u00e9anmoins, ces contestations sont mineures et je ne crois pas que nous soyons encore dans une phase o\u00f9 les concessions soient possibles. Les forces majeures de r\u00e9pression (l\u2019Arm\u00e9e des pasdaran) font chorus autour du Guide supr\u00eame.<\/p>\n\n\n\n<p>Quant aux Pasdaran, la structure de leur ancrage local repose le Bassidj. Or le Bassidj est profond\u00e9ment d\u00e9test\u00e9 et rejet\u00e9 par la population. Pour l\u2019instant, on ne voit pas de rupture au sein du Bassidj, mais si le mouvement continue encore pendant plusieurs semaines, il est probable qu&rsquo;il y ait des ruptures dues \u00e0 la fatigue de ses membres. Il arrive aussi que l\u2019arm\u00e9e des Pasdarans intervienne directement, notamment dans les provinces frontali\u00e8res, au Kurdistan et au Baloutchistan. Pour l\u2019instant, on voit tr\u00e8s bien que la rupture n&rsquo;est pas en leur sein, mais entre eux et la soci\u00e9t\u00e9 civile.<\/p>\n\n\n\n<p>Tant que l\u2019ayatollah Khamenei est au pouvoir, il me para\u00eet difficile qu\u2019une division puisse se produire au sein des organes du pouvoir car c\u2019est lui qui a le dernier mot. Les autres ont beau sugg\u00e9rer des tentatives de r\u00e9conciliations ou de reconnaissance d\u2019un certain nombre de revendications de ce mouvement, leur voix est quasiment inaudible car le d\u00e9cideur en derni\u00e8re instance est le Guide Supr\u00eame. En revanche, si le mouvement continue pendant plusieurs semaines encore, il se peut qu&rsquo;il y ait un coup d\u2019Etat par l\u2019Arm\u00e9e des Pasdarans. C\u2019est en haut qu\u2019une partie de l&rsquo;arm\u00e9e des Pasdarans pourraient \u00eatre tent\u00e9e, pour sauver le r\u00e9gime, de d\u00e9mettre le Guide Supr\u00eame. Mais cette \u00e9ventualit\u00e9 est faible car pendant plus de 30 ans, le Guide a tiss\u00e9 des liens avec la hi\u00e9rarchie des Pasdarans. Surtout, son fils, Mojtaba Khamenei est directement li\u00e9 \u00e0 une partie de l&rsquo;arm\u00e9e des Pasdarans et cog\u00e8re la r\u00e9pression en Iran.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Tant que l\u2019ayatollah Khamenei est au pouvoir, il me para\u00eet difficile qu\u2019une division puisse se produire au sein des organes du pouvoir car c\u2019est lui qui a le dernier mot. En revanche, si le mouvement continue pendant plusieurs semaines encore, il se peut qu&rsquo;il y ait un coup d\u2019Etat par l\u2019Arm\u00e9e des Pasdarans.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Je ne vois donc pas encore de signe majeure de rupture. Les voix dissentes sont mineures. Quand on les entend, elles proposent des cataplasmes alors que le malade est dans une situation critique et oscille entre la vie et la mort. Quant aux tentatives de compromis, je ne vois pas comment elles pourraient se produire dans la mesure o\u00f9 reconnaitre la libert\u00e9 de porter ou non le voile ne change pas fondamentalement la situation d\u2019une soci\u00e9t\u00e9 en r\u00e9volte contre un pouvoir totalement discr\u00e9dit\u00e9, devenu thanatocratique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment les diff\u00e9rentes ethnies en Iran prennent-elles part \u00e0 ces manifestations&#160;?<\/strong><\/h3>\n\n\n\n<p>L\u2019ethnicit\u00e9 traditionnelle en Iran, Kurde, Turque, ou Arabe \u00e9tait en opposition au pouvoir et au nationalisme iranien. On voyait tr\u00e8s bien comment le nationalisme iranien \u00e9tait en quelque sorte antagoniste \u00e0 l\u2019affirmation identitaire des Kurdes, des Arabes, des Turcs, etc. Or ce mouvement montre qu&rsquo;il y a une nouvelle forme d\u2019ethnicit\u00e9 que j&rsquo;appelle la n\u00e9oethnicit\u00e9 iranienne, fond\u00e9e sur l&rsquo;unit\u00e9 profonde de la soci\u00e9t\u00e9 civile. Par exemple, dans les manifestations, les jeunes disent \u00ab&#160;les Kurdes sont la prunelle de nos yeux&#160;\u00bb. Les Kurdes disent pour leur part&#160;: \u00ab&#160;Avec toute la soci\u00e9t\u00e9 iranienne, nous allons reprendre possession de l&rsquo;Iran contre le pouvoir&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Or ce mouvement montre qu&rsquo;il y a une nouvelle forme d\u2019ethnicit\u00e9 que j&rsquo;appelle la n\u00e9oethnicit\u00e9 iranienne, fond\u00e9e sur l&rsquo;unit\u00e9 profonde de la soci\u00e9t\u00e9 civile.<\/p><cite>Farhad Khosrokhavar<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cette nouvelle ethnicit\u00e9 est fond\u00e9e sur l&rsquo;approfondissement du lien entre les Iraniens dans une nouvelle culture ou il n&rsquo;y a pas d&rsquo;affrontement entre le nationalisme et les diff\u00e9rentes formes d\u2019ethnicit\u00e9. On le voit fort bien avec les Baloutches qui ne cherchent pas \u00e0 se s\u00e9parer de l\u2019Iran mais \u00e0 faire paisiblement reconna\u00eetre leur sp\u00e9cificit\u00e9 dans un Iran pluraliste. Le r\u00e9gime r\u00e9pressif essaye pourtant de cr\u00e9er des divisions entre ces ethnies. En effet, le pouvoir est beaucoup plus brutal contre les ethnies, que ce soit par exemple \u00e0 Z\u00e2h\u00e9d\u00e2n du c\u00f4t\u00e9 des Baloutches, et dans des villes comme Saqqez du c\u00f4t\u00e9 kurde.<\/p>\n\n\n\n<p>L\u00e0 aussi je crois que nous assistons \u00e0 une r\u00e9volution culturelle profonde. Un symbole de cette r\u00e9volution de la n\u00e9o-ethnicit\u00e9 iranienne est le rap contemporain dans lequel des Iraniens de toutes les ethnies chantent \u00e0 l&rsquo;unisson contre ce pouvoir r\u00e9pressif.<\/p>\n\n\n\n<p>D&rsquo;ailleurs, le slogan \u00ab&#160;femme, vie, libert\u00e9&#160;\u00bb est un slogan que les Kurdes avaient d\u00e9j\u00e0 employ\u00e9 dans les provinces kurdes de la Turquie. Ce slogan a eu une vie renouvel\u00e9e en Iran, sous sa forme kurde qui est tr\u00e8s proche de la forme iranienne. En kurde \u00ab&#160;zan&#160;\u00bb devient \u00ab&#160;jan&#160;\u00bb, zend\u00e9gi devient \u00ab&#160;ji\u00e2n&#160;\u00bb et \u00ab&#160;\u00e2z\u00e2di&#160;\u00bb devient \u00ab&#160;n\u00e2z\u00e2di&#160;\u00bb.<\/p>\n\n\n\n<p>Je ne dirais pas qu\u2019il s\u2019agit de nationalisme mais de patriotisme dans le sens o\u00f9 cela r\u00e9v\u00e8le l\u2019existence d\u2019une soci\u00e9t\u00e9 iranienne que l&rsquo;\u00c9tat iranien ne comprend absolument pas, dans laquelle on trouve des liens tr\u00e8s profonds entre les Iraniens \u00ab&#160;ethniques&#160;\u00bb et \u00ab&#160;non-ethniques&#160;\u00bb. La n\u00e9oethnicit\u00e9 d\u00e9signe ce nouveau rapport au sein de la soci\u00e9t\u00e9 civile entre des Iraniens Kurdes, Arabes, Baloutches, et Persans, contre le pouvoir en place.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Iran est-il en train de vivre un moment r\u00e9volutionnaire&#160;&#160;? Alors que l&rsquo;Union europ\u00e9enne vient de prendre de nouvelles sanctions \u00e0 l&rsquo;\u00e9gard du r\u00e9gime au pouvoir \u00e0 T\u00e9h\u00e9ran, nous avons interrog\u00e9 Farhad Khosrokhavar, sp\u00e9cialiste de la sociologie de la r\u00e9volution iranienne de 1979. Nous revenons avec lui sur ce qui fait la diff\u00e9rence et la singularit\u00e9 des r\u00e9voltes qui embrasent le pays depuis l&rsquo;assassinat de Mahs\u00e2 Amini.<\/p>\n","protected":false},"author":3041,"featured_media":167706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":27,"footnotes":""},"categories":[1731],"tags":[],"staff":[1557],"editorial_format":[4849],"serie":[],"audience":[],"geo":[530],"class_list":["post-167624","post","type-post","status-publish","format-standard","hentry","category-politique","staff-pierre-ramond","editorial_format-etudes","geo-asie-intermediaire"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":167706,"excerpt":"L'Iran est-il en train de vivre un moment r\u00e9volutionnaire ? Alors que l'Union europ\u00e9enne vient de prendre de nouvelles sanctions \u00e0 l'\u00e9gard du r\u00e9gime au pouvoir \u00e0 T\u00e9h\u00e9ran, nous avons interrog\u00e9 Farhad Khosrokhavar, sp\u00e9cialiste de la sociologie de la r\u00e9volution iranienne de 1979. Nous revenons avec lui sur ce qui fait la diff\u00e9rence et la singularit\u00e9 des r\u00e9voltes qui embrasent le pays depuis l'assassinat de Mahs\u00e2 Amini.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iran : les symboles d&#039;une r\u00e9volte, une conversation avec Farhad Khosrokhavar | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iran : les symboles d&#039;une r\u00e9volte, une conversation avec Farhad Khosrokhavar | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"L&#039;Iran est-il en train de vivre un moment r\u00e9volutionnaire&#160;? Alors que l&#039;Union europ\u00e9enne vient de prendre de nouvelles sanctions \u00e0 l&#039;\u00e9gard du r\u00e9gime au pouvoir \u00e0 T\u00e9h\u00e9ran, nous avons interrog\u00e9 Farhad Khosrokhavar, sp\u00e9cialiste de la sociologie de la r\u00e9volution iranienne de 1979. Nous revenons avec lui sur ce qui fait la diff\u00e9rence et la singularit\u00e9 des r\u00e9voltes qui embrasent le pays depuis l&#039;assassinat de Mahs\u00e2 Amini.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-15T11:32:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-15T13:28:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-iran-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Antonio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-iran-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Antonio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/\",\"name\":\"Iran : les symboles d'une r\u00e9volte, une conversation avec Farhad Khosrokhavar | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg\",\"datePublished\":\"2022-11-15T11:32:19+00:00\",\"dateModified\":\"2022-11-15T13:28:24+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"FILE - In this photo taken by an individual not employed by the Associated Press and obtained by the AP outside Iran, Iranians protests the death of 22-year-old Mahsa Amini after she was detained by the morality police, in Tehran, Oct. 1, 2022. Iran\u2019s atomic energy agency alleged Sunday, Oct. 23, 2022, that hackers acting on behalf of an unidentified foreign country broke into a subsidiary\u2019s network and had free access to its email system. Sunday's hack comes as Iran continues to face nationwide unrest first sparked by the Sept. 16 death of Mahsa Amini, a 22-year-old woman in police custody. (AP Photo\/Middle East Images, File)\/CAITH101\/22296458219712\/FILE PHOTO PHOTO IS TAKEN BY AN INDIVIDUAL NOT EMPLOYED BY THE ASSOCIATED PRESS AND OBTAINED BY THE AP OUTSIDE IRAN\/2210231545\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iran&#160;: les symboles d&rsquo;une r\u00e9volte, une conversation avec Farhad Khosrokhavar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73\",\"name\":\"Alexandre Antonio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g\",\"caption\":\"Alexandre Antonio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iran : les symboles d'une r\u00e9volte, une conversation avec Farhad Khosrokhavar | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/","og_locale":"fr_FR","og_type":"article","og_title":"Iran : les symboles d'une r\u00e9volte, une conversation avec Farhad Khosrokhavar | Le Grand Continent","og_description":"L'Iran est-il en train de vivre un moment r\u00e9volutionnaire&#160;? Alors que l'Union europ\u00e9enne vient de prendre de nouvelles sanctions \u00e0 l'\u00e9gard du r\u00e9gime au pouvoir \u00e0 T\u00e9h\u00e9ran, nous avons interrog\u00e9 Farhad Khosrokhavar, sp\u00e9cialiste de la sociologie de la r\u00e9volution iranienne de 1979. Nous revenons avec lui sur ce qui fait la diff\u00e9rence et la singularit\u00e9 des r\u00e9voltes qui embrasent le pays depuis l'assassinat de Mahs\u00e2 Amini.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/","og_site_name":"Le Grand Continent","article_published_time":"2022-11-15T11:32:19+00:00","article_modified_time":"2022-11-15T13:28:24+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-iran-scaled.jpg","type":"image\/jpeg"}],"author":"Alexandre Antonio","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/gc-iran-scaled.jpg","twitter_misc":{"\u00c9crit par":"Alexandre Antonio","Dur\u00e9e de lecture estim\u00e9e":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/","name":"Iran : les symboles d'une r\u00e9volte, une conversation avec Farhad Khosrokhavar | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg","datePublished":"2022-11-15T11:32:19+00:00","dateModified":"2022-11-15T13:28:24+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg","width":2560,"height":1706,"caption":"FILE - In this photo taken by an individual not employed by the Associated Press and obtained by the AP outside Iran, Iranians protests the death of 22-year-old Mahsa Amini after she was detained by the morality police, in Tehran, Oct. 1, 2022. Iran\u2019s atomic energy agency alleged Sunday, Oct. 23, 2022, that hackers acting on behalf of an unidentified foreign country broke into a subsidiary\u2019s network and had free access to its email system. Sunday's hack comes as Iran continues to face nationwide unrest first sparked by the Sept. 16 death of Mahsa Amini, a 22-year-old woman in police custody. (AP Photo\/Middle East Images, File)\/CAITH101\/22296458219712\/FILE PHOTO PHOTO IS TAKEN BY AN INDIVIDUAL NOT EMPLOYED BY THE ASSOCIATED PRESS AND OBTAINED BY THE AP OUTSIDE IRAN\/2210231545"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/11\/15\/iran-les-symboles-dune-revolte-une-conversation-avec-farhad-khosrokhavar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Iran&#160;: les symboles d&rsquo;une r\u00e9volte, une conversation avec Farhad Khosrokhavar"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73","name":"Alexandre Antonio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g","caption":"Alexandre Antonio"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1557,"name":"Pierre Ramond","slug":"pierre-ramond","description":"Pierre Ramond est responsable des s\u00e9minaires, tables rondes et rencontres du Grand Continent. Apr\u00e8s une scolarit\u00e9 \u00e0 l'\u00c9cole normale sup\u00e9rieure (A\/L 2015) au cours de laquelle il a \u00e9tudi\u00e9 la philosophie, la science politique et le persan, il effectue aujourd'hui une th\u00e8se sur la diplomatie europ\u00e9enne sous la direction d'Alexandre Kazerouni et de Christian Lequesne.\r\n<h2 class=\"field-item even\"><\/h2>","first_name":"Pierre ","last_name":"Ramond ","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/01\/5hShlVtL_400x400-ConvertImage-1.jpg","width":400,"height":400,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg","width":2560,"height":1706,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/SIPA_AP22732527_000001-scaled.jpg","width":2560,"height":1706,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/167624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/3041"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=167624"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/167624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/167706"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=167624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=167624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=167624"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=167624"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=167624"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=167624"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=167624"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=167624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}