{"id":163726,"date":"2022-10-17T11:28:19","date_gmt":"2022-10-17T09:28:19","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=163726"},"modified":"2022-10-17T13:34:26","modified_gmt":"2022-10-17T11:34:26","slug":"la-tentation-de-lespoir-le-nouvel-inedit-de-celine","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/","title":{"rendered":"La tentation de l\u2019espoir&#160;: le nouvel in\u00e9dit de C\u00e9line"},"content":{"rendered":"\n<p class=\"has-drop-cap\">On retire parfois de la lecture de <em>Londres<\/em> des impressions analogues \u00e0 celle du <em>Temps retrouv\u00e9<\/em>, en raison de leur commune imperfection. Celui de Proust n\u2019eut pas le temps d\u2019\u00eatre r\u00e9vis\u00e9 par son auteur&#160;; celui de C\u00e9line est un premier jet \u00e9crit autour de 1934, et dont la mati\u00e8re romanesque servit finalement \u00e0 un livre fort diff\u00e9rent, intitul\u00e9 <em>Guignol\u2019s band<\/em> et publi\u00e9 dix ans plus tard&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-1-163726' title='La premi\u00e8re partie de &lt;em&gt;Guignol\u2019s band&lt;\/em&gt; a paru en 1944. Une seconde partie intitul\u00e9e &lt;em&gt;Le Pont de Londres&lt;\/em&gt; a \u00e9t\u00e9 reconstitu\u00e9e et publi\u00e9e apr\u00e8s la mort de C\u00e9line \u00e0 partir de ses manuscrits. La synopsis d\u2019un &lt;em&gt;Guignol\u2019s band III&lt;\/em&gt; pr\u00e9sente de nombreuses similitudes avec la troisi\u00e8me partie de &lt;em&gt;Londres&lt;\/em&gt;.'><sup>1<\/sup><\/a><\/span><\/span>. D\u2019o\u00f9, dans <em>Londres<\/em>, plusieurs redites, r\u00e9p\u00e9titions, flottements dans le nom des personnages, sans mentionner les trous du manuscrit. D\u2019o\u00f9 aussi des longueurs et une monotonie particuli\u00e8rement sensible \u00e0 partir de la deuxi\u00e8me partie. Malgr\u00e9 ces scories, le livre (et en particulier ses trois cents premi\u00e8res pages) pourrait bien nous inspirer le m\u00eame jugement que <em>Le Temps retrouv\u00e9<\/em> \u00e0 Drieu La Rochelle&#160;: \u00ab&#160;Sublime, quand m\u00eame.&#160;\u00bb<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9fendre C\u00e9line&#160;?<\/h2>\n\n\n\n<p><em>Londres<\/em> est accompagn\u00e9 d\u2019une pr\u00e9face et d\u2019une postface confi\u00e9es \u00e0 un universitaire, R\u00e9gis Tettamanzi, qui s\u2019est montr\u00e9 plus prudent <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/06\/05\/celine-apres-coup\/\">que Fran\u00e7ois Gibault avec celle de <em>Guerre<\/em><\/a>. Le titre du premier in\u00e9dit avait \u00e9t\u00e9 contest\u00e9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-2-163726' title='Voir l\u2019article de Pierre Benetti et Tiphaine Samoyault, \u00ab&amp;#160;Comment peut-on lire C\u00e9line aujourd\u2019hui&amp;#160;?&amp;#160;\u00bb,&lt;a href=&quot;https:\/\/www.en-attendant-nadeau.fr\/2022\/05\/05\/guerre-lire-celine\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt; https:\/\/www.en-attendant-nadeau.fr\/2022\/05\/05\/guerre-lire-celine\/&lt;\/a&gt; et celui de Giulia Mela et Pierluigi Pellini, \u00ab&amp;#160;Gen\u00e8se d\u2019un best-seller. Quelques hypoth\u00e8ses sur un pr\u00e9tendu \u2018roman in\u00e9dit\u2019 de Louis-Ferdinand C\u00e9line&amp;#160;\u00bb,&lt;a href=&quot;http:\/\/www.item.ens.fr\/guerre&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt; http:\/\/www.item.ens.fr\/guerre&lt;\/a&gt;.'><sup>2<\/sup><\/a><\/span><\/span>&#160;; celui de <em>Londres <\/em>a \u00e9t\u00e9, comme nous l\u2019apprend la \u00ab&#160;note sur l\u2019\u00e9dition&#160;\u00bb, appos\u00e9 par l\u2019auteur lui-m\u00eame sur les chemises contenant les manuscrits. L\u2019\u00e9dition est-elle h\u00e2tive&#160;? Pour ma part, je n\u2019irai pas reprocher \u00e0 un \u00e9diteur, si gros soit-il, de faire ses affaires et de mettre rapidement \u00e0 disposition un texte d\u00e9sir\u00e9 du public, et dont l\u2019\u00e9dition savante viendra en son temps. Doit-on formuler des r\u00e9serves sur la pr\u00e9face&#160;? Certes, sa d\u00e9marche apolog\u00e9tique est chauss\u00e9e de gros sabots&#160;: \u00ab&#160;la tentation sera forte d\u2019attribuer syst\u00e9matiquement \u00e0 l\u2019auteur ce qui rel\u00e8ve du personnage&#160;\u00bb dit Tettamanzi (or, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/06\/05\/celine-apres-coup\/\">l\u2019article de J\u00e9r\u00f4me Meizoz dans ces colonnes<\/a> avait justement rappel\u00e9 \u00e0 quel point \u00ab&#160;C\u00e9line&#160;\u00bb lui-m\u00eame \u00e9tait un personnage&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-3-163726' title='Voir J\u00e9r\u00f4me Meizoz, \u00ab&amp;#160;\u201cC\u00e9line\u201d apr\u00e8s coup&amp;#160;\u00bb,&lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2022\/06\/05\/celine-apres-coup\/&quot;&gt; https:\/\/legrandcontinent.eu\/fr\/2022\/06\/05\/celine-apres-coup\/&lt;\/a&gt;.'><sup>3<\/sup><\/a><\/span><\/span>), ou \u00ab&#160;l\u2019esth\u00e9tique n\u2019est pas la morale&#160;: elle alt\u00e8re les jugements qui nous serions en droit de porter sur telle situation ou telle repr\u00e9sentation&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-4-163726' title='Pr\u00e9face p. 14.'><sup>4<\/sup><\/a><\/span><\/span>. La pr\u00e9face et la notice d\u2019Henri Godard pour la Pl\u00e9iade de <em>Guignol\u2019s band<\/em>, discutables pour les m\u00eames raisons, \u00e9taient plus nuanc\u00e9es.<\/p>\n\n\n\n<p>R\u00e9gis Tettamanzi, du moins, ne d\u00e9nie ni la violence misogyne, ni l\u2019antis\u00e9mitisme de C\u00e9line qui \u00ab&#160;appara\u00eet dans le texte&#160;\u00bb \u2014 mais l\u2019une et l\u2019autre seraient contrebalanc\u00e9s par le renversement de la domination masculine \u00e0 la fin du roman (il faut le dire vite) et par le portrait positif du juif Yugenbitz (Clodovitz dans <em>Guignol\u2019s band<\/em>), qui initie Ferdinand \u00e0 la m\u00e9decine. Le nom de Yugenbitz (finalement pr\u00e9f\u00e9r\u00e9 par l\u2019auteur \u00e0 celui d\u2019\u00c9trosohn, qui appara\u00eet aussi dans le manuscrit), le sp\u00e9cialiste et \u00e9diteur des pamphlets qu\u2019est R. Tettamanzi aurait pu le rapprocher de celui de Yubelblat, l\u2019employeur juif de C\u00e9line \u00e0 la SDN dans <em>Bagatelles pour un massacre<\/em> \u2014 ou de Yudenzweck, nom qu\u2019on retrouve dans la synopsis de <em>Guignol\u2019s band III<\/em> et dans la pi\u00e8ce <em>L\u2019\u00c9glise<\/em>, bien ant\u00e9rieure. De m\u00eame, s\u2019il est vrai que dans <em>Londres<\/em>, certains juifs \u00ab&#160;sont l\u00e0, tout simplement&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-5-163726' title='Pr\u00e9face p. 17.'><sup>5<\/sup><\/a><\/span><\/span>&#160;\u00bb, d\u00e9peints dans la mis\u00e8re de leur quartier londonien, d\u2019autres phrases moins reluisantes, \u00e0 propos par exemple des danseuses qui \u00ab&#160;trouveront bien un juif plus tard, les mignonnes musculaires, qui leur boira l\u2019urine pour cher quand elles sauront danser&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-6-163726' title='Pr\u00e9face p. 49.'><sup>6<\/sup><\/a><\/span><\/span>&#160;\u00bb, annoncent plut\u00f4t l\u2019horreur des belles actrices blanches souill\u00e9es par les impresarios juifs&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-7-163726' title='\u00ab&amp;#160;Trafic des plus belles, des plus d\u00e9sirables petites Aryennes bien suceuses, bien dociles, bien s\u00e9lectionn\u00e9es, par les kh\u00e9dives n\u00e9grites juifs d\u2019Hollywood&amp;#160;\u00bb (Louis-Ferdinand C\u00e9line, &lt;em&gt;Bagatelles pour un massacre&lt;\/em&gt;, Paris, Deno\u00ebl, 1937, p. 223).'><sup>7<\/sup><\/a><\/span><\/span>. L\u2019ambivalence est incontestable&#160;; non pas parce qu\u2019elle \u00ab&#160;illustre l\u2019\u00e9tat d\u2019esprit de C\u00e9line avant la crise de 1936 et la furie pamphl\u00e9taire des ann\u00e9es suivantes&#160;\u00bb, mais parce qu\u2019elle rappelle \u00e0 quel point celui-ci attribue des vis\u00e9es diff\u00e9rentes \u00e0 ses romans et \u00e0 ses pamphlets, malgr\u00e9 un fond id\u00e9ologique dont Marie-Christine Bellosta a en son temps soulign\u00e9 la coh\u00e9rence&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-8-163726' title='Marie-Christine Bellosta, &lt;em&gt;C\u00e9line ou L\u2019art de la contradiction&amp;#160;: lecture de &lt;\/em&gt;Voyage au bout de la nuit, Paris, Presses universitaires de France, 1990.'><sup>8<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00e9line et l\u2019anarchie<\/h2>\n\n\n\n<p>Mon insistance sur le contenu politique du roman n\u2019est pas gratuite&#160;: sans en \u00eatre le th\u00e8me principal, la politique y est trait\u00e9e de fa\u00e7on r\u00e9currente, et sur un mode qui \u00e9claire pr\u00e9cieusement les rapports de C\u00e9line \u00e0 l\u2019anarchisme. Ferdinand re\u00e7oit une premi\u00e8re \u00e9ducation politique de la part de Borokrom, un anarchiste&#160;: \u00ab&#160;il m\u2019a instruit comment il y avait des classes sociales et je m\u2019en \u00e9tais jamais dout\u00e9.&#160;\u00bb C\u2019est une d\u00e9couverte de Marx, qui \u00ab&#160;demeurait pas loin d\u2019ici&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-9-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 83.'><sup>9<\/sup><\/a><\/span><\/span>. Mais le Borokrom de <em>Londres<\/em> n\u2019aime ni les juifs, ni les socialistes. S\u2019il se distingue du Borokrom misanthrope de <em>Bagatelles<\/em>, ou du terroriste grotesque de <em>Guignol\u2019s band<\/em>, il incarne typiquement l\u2019anarchisme individualiste et d\u00e9sesp\u00e9r\u00e9 d\u2019un Georges Darien, qui ne croit plus en l\u2019humanit\u00e9&#160;: \u00ab&#160;plus rien \u00e0 faire avec les hommes, [\u2026] ce qui leur pla\u00eet dans Marx, [\u2026] c\u2019est le g\u00e9ant d\u2019orgueil, quelque chose comme Victor Hugo mais alors en youpin, un romantique d\u00e9lirant avec des chiffres et des pr\u00e9cisions&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-10-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 84.'><sup>10<\/sup><\/a><\/span><\/span>.&#160;\u00bb Borokrom milite seul et ne croit plus qu\u2019\u00e0 la propagande par le fait&#160;; il regrette plus loin de ne pas \u00eatre all\u00e9 au martyr avec les ind\u00e9pendantistes du Sinn F\u00e9in, \u00ab&#160;des terroristes vrais de vrais&#160;\u00bb. Onomastique c\u00e9linienne oblige, le mouvement est rebaptis\u00e9 significativement \u00ab&#160;Sinn-Finn&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-11-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 245.'><sup>11<\/sup><\/a><\/span><\/span>&#160;: car il n\u2019y a pas de fin de l\u2019histoire, pas de fin \u00e0 la violence guerri\u00e8re, et le militantisme progressiste n\u2019est qu\u2019une mani\u00e8re de conjurer l\u2019angoisse de l\u2019infini, en \u00ab&#160;mont[ant] sur les estrades, avec les autres, roter [s]on n\u00e9ant&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-12-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 86.'><sup>12<\/sup><\/a><\/span><\/span>&#160;\u00bb.<\/p>\n\n\n\n<p>L\u2019autre progressiste libertaire du roman, le docteur Yugenbitz, ne convertit pas davantage Ferdinand. Saoul\u00e9 de journaux du monde entier et de discussions sur les motions et les congr\u00e8s, comme Borokrom et comme tous \u00ab&#160;les mecs du progr\u00e8s&#160;\u00bb, Yugenbitz veut \u00ab&#160;rem\u00e9dier \u00e0 la mis\u00e8re du monde par le grand c\u00f4t\u00e9&#160;\u00bb \u2014 au lieu d\u2019affronter l\u2019humanit\u00e9 qui souffre sous ses yeux. \u00ab&#160;Crever sur les barricades c\u2019est pas tout \u00e0 fait \u00eatre courageux&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-13-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 179'><sup>13<\/sup><\/a><\/span><\/span>&#160;: le pauvre docteur n\u2019est pas taill\u00e9 pour affronter la mort d\u2019un enfant (Peter, petit patient pauvre qui rappelle le B\u00e9bert du <em>Voyage<\/em>).<\/p>\n\n\n\n<p>Au lieu d\u2019\u00e9voquer la vague notion d\u2019anarchisme de droite, <em>Londres<\/em> permet au contraire de voir que C\u00e9line identifie fort bien le courant anarchiste de son \u00e9poque, avec ses controverses et ses revendications, et qu\u2019il entreprend d\u2019en d\u00e9monter le fond et la faiblesse trop humaine. Dans cette perspective d\u00e9sabus\u00e9e, la solidarit\u00e9 entre paum\u00e9s n\u2019est jamais que subie&#160;: \u00ab&#160;On \u00e9tait dans la fraternit\u00e9 jusqu\u2019au cou&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-14-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 147.'><sup>14<\/sup><\/a><\/span><\/span>.&#160;\u00bb<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plus d\u2019patrons<\/h2>\n\n\n\n<p>Il est un point toutefois que Ferdinand partage avec les libertaires, c\u2019est la haine des patrons et de la basse ob\u00e9issance (pr\u00e9sente d\u00e9j\u00e0 dans le <em>Voyage<\/em> puis dans <em>Mort \u00e0 cr\u00e9dit<\/em>)&#160;:<\/p>\n\n\n\n<p>\u00ab&#160;Des boulots r\u00e9guliers j\u2019en avais d\u00e9gust\u00e9 moi jusqu\u2019au fiel, et des bien emmerdants, qu\u2019abrutissent l\u2019homme jusqu\u2019au goulot. J\u2019en voulais plus, je parle des boulots comme avant guerre, \u00e0 l\u2019admiration du patron canaille, voleur et con&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-15-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 54.'><sup>15<\/sup><\/a><\/span><\/span>.&#160;\u00bb<\/p>\n\n\n\n<p>\u00ab&#160;faudrait alors, paix revenue comme on dit, que je me retape un, dix, vingt bas boulots, [\u2026] dans l\u2019oubliette d\u2019un autre vaseux bien f\u00e9roce, bien riche, bien sournois, un patron quoi. Faudrait que je reprenne le respect des nouvelles triques [\u2026] \u00e0 l\u00e9cher le con bien puant d\u2019o\u00f9 pendent nos petits salaires&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-16-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 167.'><sup>16<\/sup><\/a><\/span><\/span>&#160;\u00bb<\/p>\n\n\n\n<p>Mais les deux \u00e9chappatoires \u00e0 l\u2019exploitation qui s\u2019offrent dans le r\u00e9cit ne sont ni collectives ni \u00e9mancipatrices. <em>Londres <\/em>est d\u2019une part le roman de la vocation m\u00e9dicale, inspir\u00e9e \u00e0 Ferdinand par le docteur Yugenbitz. Celui-ci est un m\u00e9decin des pauvres \u2014 \u00e9l\u00e9ment crucial de la posture de C\u00e9line. La vocation de Ferdinand est ainsi une tentation de l\u2019altruisme&#160;: \u00ab&#160;\u00c7a m\u2019attirait comme la lumi\u00e8re d\u00e9cid\u00e9ment le coup d\u2019aller soigner des gens, [\u2026] de voir comment il faisait pour leur faire du bien&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-17-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 155.'><sup>17<\/sup><\/a><\/span><\/span>.&#160;\u00bb Yugenbitz est lui-m\u00eame un m\u00e9decin pauvre, mais il a \u00ab&#160;bien de la latitude dans son destin [\u2026], son dipl\u00f4me donne tant de privil\u00e8ges admirables. Y en a encore tr\u00e8s bas des privil\u00e8ges&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-18-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 167'><sup>18<\/sup><\/a><\/span><\/span>.&#160;\u00bb Outre le d\u00e9sir de secourir, la m\u00e9decine repr\u00e9sente une ascension sociale et une \u00e9mancipation individuelle, elle permet de devenir son propre patron quand on ne croit plus \u00e0 la fin de l\u2019exploitation. L\u2019altruisme m\u00e9dical prend d\u2019ailleurs volontiers une figure invasive, comme dans ce passage o\u00f9 la bande de Ferdinand se jette sur Borokrom pour lui arracher des dents&#160;: \u00ab&#160;Deux molaires qu\u2019il a au fond toutes pourries. \u00c7a m\u2019int\u00e9resse moi, \u00e7a me passionne. Je veux qu\u2019on le soulage. C\u2019est ma manie&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-19-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 228'><sup>19<\/sup><\/a><\/span><\/span>.&#160;\u00bb Curiosit\u00e9 avide pour la pourriture, d\u00e9sir de soigner l\u2019humanit\u00e9 en fouillant le fond de sa chair, m\u00eame \u00e0 son corps d\u00e9fendant&#160;: toute l\u2019\u00e9thique m\u00e9dicale et romanesque de C\u00e9line se r\u00e9sume dans cette op\u00e9ration&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-20-163726' title='L\u2019\u00e9tude de Marie-Christine Bellosta cit\u00e9e plus haut rappelle aussi toutes les ambivalences du Dr Destouches, partisan de politiques sanitaires susceptibles d\u2019\u00e9radiquer la mis\u00e8re, mais dans l\u2019int\u00e9r\u00eat du patronat (voir p. 279-280).'><sup>20<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>D\u2019autre part, <em>Londres<\/em> est un roman du \u00ab&#160;milieu&#160;\u00bb, des bas fonds, des voyous qui refusent de travailler de fa\u00e7on conventionnelle \u00e0 la mani\u00e8re des \u00ab&#160;caves&#160;\u00bb, et pr\u00e9f\u00e8rent vivre de trafics et de prox\u00e9n\u00e9tisme&#160;: on ne d\u00e9pend plus d\u2019un patron quand on vit de l\u2019argent des femmes. La deuxi\u00e8me partie du livre tourne m\u00eame au roman noir en huis-clos&#160;: de crainte d\u2019\u00eatre rep\u00e9r\u00e9s par la police, expuls\u00e9s ou renvoy\u00e9s au front, les personnages s\u2019enferment \u00e0 la Leicester Pension, tenue par le maquereau Cantaloup. Cette deuxi\u00e8me partie statique n\u2019est sans doute pas la plus r\u00e9ussie du livre, malgr\u00e9 sa crudit\u00e9 sordide. Elle r\u00e9v\u00e8le cependant un \u00e9l\u00e9ment de la po\u00e9tique c\u00e9linienne&#160;: la loi du milieu, c\u2019est la loi du silence. Interdit de \u00ab&#160;donner&#160;\u00bb (d\u00e9noncer) ses amis, de se \u00ab&#160;mettre \u00e0 table&#160;\u00bb. Or, cette loi du silence prend une dimension qui d\u00e9passe largement l\u2019univers interlope. Elle devient rapport au monde, pr\u00e9figurant le silence dans lequel se mure le h\u00e9ros de <em>Mort \u00e0 cr\u00e9dit<\/em> quand il arrive lui-m\u00eame en Angleterre.<\/p>\n\n\n\n<p>Ferdinand garde encore le silence face aux charmes du printemps anglais&#160;: \u00ab&#160;Je savais me taire. On peut \u00eatre fou d\u00e9j\u00e0 et savoir se tenir devant le monde. En ce joli parc exub\u00e9rant d\u2019ardeurs nouvelles, je me sentais inqui\u00e9t\u00e9 et pr\u00eat aux ind\u00e9cences.&#160;\u00bb Le silence devient une r\u00e9sistance \u00e0 l\u2019abandon lyrique&#160;: \u00ab&#160;Ferdinand, tu ramollis, t\u2019es d\u00e9j\u00e0 bien hypoth\u00e9qu\u00e9 si tu donnes au printemps \u00e0 cause des jonquilles et des pinsons.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-21-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 422.'><sup>21<\/sup><\/a><\/span><\/span> Donner au printemps, donner ses amis, tout \u00e7a rel\u00e8ve de la m\u00eame trahison et du m\u00eame manque de <em>tenue<\/em>. Jean-Pierre Richard, dans son \u00e9tude intitul\u00e9e <em>Naus\u00e9e de C\u00e9line<\/em>, avait admirablement soulign\u00e9 l\u2019angoisse du ramollissement et de la flaccidit\u00e9 de l\u2019\u00eatre qui hante l\u2019\u0153uvre c\u00e9linienne. Cette angoisse prend dans <em>Londres<\/em> une tournure tout \u00e0 fait bouleversante \u00e0 l\u2019\u00e9vocation de la drogue, qui en a fait \u00ab&#160;foirer&#160;\u00bb tant d\u2019autres \u00ab&#160;qui s\u2019aidaient avec dans le milieu, dans les moments les plus difficiles, \u00e0 froid, il faut du courage qu\u2019on a pas&#160;\u00bb. Ferdinand dit simplement&#160;: \u00ab&#160;J\u2019ai pas fait. C\u2019est pour \u00e7a que je suis encore capable de taper dans la page vingt ans apr\u00e8s, comme on dit.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-22-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-22-163726' title='&lt;em&gt;Londres&lt;\/em&gt;, p. 416-417.'><sup>22<\/sup><\/a><\/span><\/span> Le contraste entre l\u2019asc\u00e8se modeste de l\u2019\u00e9crivain compatissant et le moralisme anti-alcoolique du pamphl\u00e9taire&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-23-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-23-163726' title='D\u00e8s ses premiers pamphlets, on lit des phrases comme&amp;#160;: \u00ab&amp;#160;Je sais moi, ce qu\u2019il a besoin le peuple, c\u2019est pas d\u2019une R\u00e9volution, c\u2019est pas de dix R\u00e9volutions\u2026 Ce qu\u2019il a besoin, c\u2019est qu\u2019on le foute pendant dix ans au silence et \u00e0 l\u2019eau&amp;#160;! qu\u2019il d\u00e9gorge tout le trop d\u2019alcool qu\u2019il a bu depuis 93 et les mots qu\u2019il a entendus\u2026&amp;#160;\u00bb (Louis-Ferdinand C\u00e9line, &lt;em&gt;Bagatelles pour un massacre&lt;\/em&gt;, op. cit., p. 87-88). C\u00e9line (mais aussi Brasillach, Rebatet, Morand, etc.) est ici totalement en phase avec le discours anti-Front populaire et cong\u00e9s pay\u00e9s (dont l\u2019alcool n\u2019est qu\u2019une m\u00e9tonymie), annon\u00e7ant aussi la propagande anti-alcoolique de Vichy qui met la d\u00e9fait de 1940 sur le compte du pastis.'><sup>23<\/sup><\/a><\/span><\/span> (compl\u00e8tement align\u00e9 sur les discours anti-cong\u00e9s pay\u00e9s de Vichy expliquant la d\u00e9faite de 1940 par la consommation immod\u00e9r\u00e9e de pastis des Fran\u00e7ais) est ici appr\u00e9ciable.<\/p>\n\n\n\n<p>En somme, <em>Londres<\/em> n\u2019a rien de la \u00ab&#160;petite halte anglaise, pour la rigolade et l\u2019oubli&#160;\u00bb que C\u00e9line se promettait en 1930, o\u00f9 tout devait \u00ab&#160;se termine[r] en th\u00e9\u00e2tre, en bouffonnerie&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-24-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-24-163726' title='Lettres \u00e0 Joseph Garcin du 18 juin 1930 et du 18 juillet 1931, cit\u00e9es dans la notice (Louis-Ferdinand C\u00e9line, &lt;em&gt;Romans&lt;\/em&gt;, H. Godard (\u00e9d.), Paris, Gallimard, 1988, t. III, p. 946).'><sup>24<\/sup><\/a><\/span><\/span>. Cette direction farcesque, il ne l\u2019emprunte qu\u2019avec <em>Guignol\u2019s band<\/em>, r\u00e9dig\u00e9 \u00e0 une p\u00e9riode o\u00f9 il disposait encore du manuscrit. Le choix de reprendre l\u2019histoire de fond en comble tient peut-\u00eatre \u00e0 l\u2019\u00e9chec du programme initial non tenu&#160;: <em>Londres<\/em> est encore un roman de l\u2019angoisse \u2014 jusque dans son style parfois&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-25-163726' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#easy-footnote-bottom-25-163726' title='Certaines phrases semblent une tentative pour aller plus loin que le &lt;em&gt;Voyage&lt;\/em&gt; dans l\u2019emballement de la diction, sans aller encore jusqu\u2019\u00e0 la fragmentation de &lt;em&gt;Mort \u00e0 cr\u00e9dit&lt;\/em&gt;, comme ici avec ces compl\u00e9tives en cascade&amp;#160;: \u00ab&amp;#160;\u00c7a s\u2019est pas mal pass\u00e9 non plus pour la rentr\u00e9e \u00e0 Leicester Street mais quand m\u00eame j\u2019avais dans l\u2019id\u00e9e que c\u2019\u00e9tait si facilement survenu tout \u00e7a et qu\u2019on avait rencontr\u00e9 personne en route et que la m\u00e8re Council avait pas tiqu\u00e9 et qu\u2019on l\u2019avait foutu \u00e0 l\u2019eau le zouave si doucement et que la rivi\u00e8re avait pass\u00e9 sur l\u2019\u00e9v\u00e9nement si gentiment que c\u2019\u00e9tait presque pas arriv\u00e9 du tout.&amp;#160;\u00bb'><sup>25<\/sup><\/a><\/span><\/span> \u2014 et de la traque, mot qui revient de fa\u00e7on obsessionnelle. Il ne manque pourtant pas d\u2019\u00e9chapp\u00e9es et d\u2019infinis&#160;: le d\u00e9sir de soigner, la f\u00e9erie, l\u2019amour pour Ang\u00e8le, la soif d\u2019instruction. Autant de transcendances possibles, dont syst\u00e9matiquement C\u00e9line se d\u00e9tourne, convaincu d\u2019avance de l\u2019indignit\u00e9 humaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roman de l&rsquo;angoisse et de la traque<em>Londres<\/em>, ne manque pas d&rsquo;\u00e9chapp\u00e9es et d&rsquo;infinis \u2014 possibles seulement. Une lecture du nouvel in\u00e9dit de C\u00e9line par Vincent Berthelier, auteur du <em>Style r\u00e9actionnaire. De Maurras \u00e0 Houellebecq<\/em> (Amsterdam, 2022).<\/p>\n","protected":false},"author":3041,"featured_media":163790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-reviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":12,"footnotes":""},"categories":[1734],"tags":[],"staff":[2594],"editorial_format":[4868],"serie":[],"audience":[],"geo":[1917],"class_list":["post-163726","post","type-post","status-publish","format-standard","hentry","category-doctrines","staff-vincent-berthelier","editorial_format-comptes-rendus","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":163790,"excerpt":"Roman de l'angoisse et de la traque<em>Londres<\/em>, ne manque pas d'\u00e9chapp\u00e9es et d'infinis \u2014 possibles seulement. Une lecture du nouvel in\u00e9dit de C\u00e9line par Vincent Berthelier, auteur du <em>Style r\u00e9actionnaire. De Maurras \u00e0 Houellebecq<\/em> (Amsterdam, 2022).\r\n","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La tentation de l\u2019espoir\u00a0: le nouvel in\u00e9dit de C\u00e9line | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tentation de l\u2019espoir\u00a0: le nouvel in\u00e9dit de C\u00e9line | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Roman de l&#039;angoisse et de la traqueLondres, ne manque pas d&#039;\u00e9chapp\u00e9es et d&#039;infinis \u2014 possibles seulement. Une lecture du nouvel in\u00e9dit de C\u00e9line par Vincent Berthelier, auteur du Style r\u00e9actionnaire. De Maurras \u00e0 Houellebecq (Amsterdam, 2022).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-17T09:28:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-17T11:34:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/gc-celine-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Antonio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/gc-celine-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Antonio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/\",\"name\":\"La tentation de l\u2019espoir\u00a0: le nouvel in\u00e9dit de C\u00e9line | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg\",\"datePublished\":\"2022-10-17T09:28:19+00:00\",\"dateModified\":\"2022-10-17T11:34:26+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg\",\"width\":1677,\"height\":2421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La tentation de l\u2019espoir&#160;: le nouvel in\u00e9dit de C\u00e9line\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73\",\"name\":\"Alexandre Antonio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g\",\"caption\":\"Alexandre Antonio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La tentation de l\u2019espoir\u00a0: le nouvel in\u00e9dit de C\u00e9line | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/","og_locale":"fr_FR","og_type":"article","og_title":"La tentation de l\u2019espoir\u00a0: le nouvel in\u00e9dit de C\u00e9line | Le Grand Continent","og_description":"Roman de l'angoisse et de la traqueLondres, ne manque pas d'\u00e9chapp\u00e9es et d'infinis \u2014 possibles seulement. Une lecture du nouvel in\u00e9dit de C\u00e9line par Vincent Berthelier, auteur du Style r\u00e9actionnaire. De Maurras \u00e0 Houellebecq (Amsterdam, 2022).","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/","og_site_name":"Le Grand Continent","article_published_time":"2022-10-17T09:28:19+00:00","article_modified_time":"2022-10-17T11:34:26+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/gc-celine-scaled.jpg","type":"image\/jpeg"}],"author":"Alexandre Antonio","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/gc-celine-scaled.jpg","twitter_misc":{"\u00c9crit par":"Alexandre Antonio","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/","name":"La tentation de l\u2019espoir\u00a0: le nouvel in\u00e9dit de C\u00e9line | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg","datePublished":"2022-10-17T09:28:19+00:00","dateModified":"2022-10-17T11:34:26+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg","width":1677,"height":2421},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/17\/la-tentation-de-lespoir-le-nouvel-inedit-de-celine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"La tentation de l\u2019espoir&#160;: le nouvel in\u00e9dit de C\u00e9line"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/52f1217b490d99b0129aacfc21eb1a73","name":"Alexandre Antonio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/952fdff634ecaaa1a050dd647639f0e9?s=96&d=mm&r=g","caption":"Alexandre Antonio"}}]}},"lgc_categories":[{"id":1734,"name":"Livres","slug":"doctrines"}],"lgc_author":{"id":2594,"name":"Vincent Berthelier","slug":"vincent-berthelier","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg","width":1677,"height":2421,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/G06460.jpg","width":1677,"height":2421,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/163726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/3041"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=163726"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/163726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/163790"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=163726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=163726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=163726"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=163726"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=163726"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=163726"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=163726"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=163726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}