{"id":162547,"date":"2022-10-07T10:00:35","date_gmt":"2022-10-07T08:00:35","guid":{"rendered":"https:\/\/lgctesting.piramid.studio\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/"},"modified":"2022-10-11T16:19:14","modified_gmt":"2022-10-11T14:19:14","slug":"quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/","title":{"rendered":"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver&#160;?"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/08\/26\/les-prix-de-lenergie-atteignent-des-niveaux-historiques-en-europe\/\">Les prix de l\u2019\u00e9nergie ont atteint des niveaux historiques en Europe cet \u00e9t\u00e9<\/a>. En France, les prix des contrats \u00e0 terme d\u2019un an ont d\u00e9pass\u00e9 1000 \u20ac par MWh, et se sont \u00e9lev\u00e9s \u00e0 plus de 800 \u20ac en Allemagne. Si une baisse cons\u00e9quente a \u00e9t\u00e9 observ\u00e9e en septembre, les prix restent beaucoup plus \u00e9lev\u00e9s que la moyenne des ann\u00e9es pr\u00e9c\u00e9dentes.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/73ufn\/5\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hier, l&rsquo;Economist Intelligence Unit a publi\u00e9 ses perspectives \u00e9conomiques mondiales pour l\u2019ann\u00e9e 2022. Les conclusions rejoignent sensiblement celles des derniers rapports de l\u2019<a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/26\/le-ralentissement-de-la-croissance-mondiale-savere-etre-plus-prononce-quanticipe-selon-locde\/\">OCDE de septembre<\/a> et du <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/07\/27\/le-fonds-monetaire-international-annonce-le-risque-dune-recession-globale\/\">Fonds mon\u00e9taire international de juillet dernier<\/a>, caract\u00e9ris\u00e9es par une hausse globale des taux directeurs des principales banques centrales ainsi que par une r\u00e9vision \u00e0 la baisse de la croissance globale.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/yCUNA\/2\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon le rapport, l&rsquo;ampleur de la p\u00e9nurie d&rsquo;\u00e9nergie d\u00e9pendra de la baisse des temp\u00e9ratures en Europe cet hiver, de la solidit\u00e9 \u00e9nerg\u00e9tique des \u00c9tats-membres (r\u00e9cemment <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/le-plan-allemand-de-200-milliards-deuros-pointe-du-doigt-par-certains-etats-membres\/\">fragilis\u00e9e par le plan allemand de 200 milliards d\u2019euros<\/a>) ainsi que du degr\u00e9 de r\u00e9duction de la consommation de gaz par les entreprises&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-162547' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#easy-footnote-bottom-1-162547' title='&lt;a href=&quot;https:\/\/www.eiu.com\/n\/campaigns\/risk-outlook-2022\/#:~:text=The%20post%2Dpandemic%20economic%20rebound,that%20could%20derail%20the%20recovery.&quot;&gt;Global economic outlook 2022&lt;\/a&gt;, Economist Intelligence Unit, 5 octobre 2022.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/X44dW\/1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;Autriche et l&rsquo;Allemagne, qui d\u00e9pendent fortement du gaz russe et disposent de peu d&rsquo;autres options d&rsquo;approvisionnement, devraient \u00eatre confront\u00e9es \u00e0 des p\u00e9nuries cet hiver. L&rsquo;Italie serait \u00e9galement durement touch\u00e9e, et les pays enclav\u00e9s d&rsquo;Europe centrale \u2014 surtout Slovaquie et R\u00e9publique tch\u00e8que \u2014 subiront un triple choc d\u00fb aux p\u00e9nuries d&rsquo;\u00e9nergie, \u00e0 une inflation \u00e9lev\u00e9e et aux retomb\u00e9es de la r\u00e9cession allemande. En septembre, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/30\/en-septembre-linflation-a-atteint-10-dans-la-zone-euro\/\">l\u2019inflation d\u00e9passait les 10&#160;% en Allemagne pour la premi\u00e8re fois depuis 70 ans<\/a>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/RYJ1c\/1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Environ un tiers des pays europ\u00e9ens risquent d&rsquo;\u00eatre confront\u00e9s \u00e0 des p\u00e9nuries en raison de la baisse record des approvisionnements en gaz russe. La majorit\u00e9 de l&rsquo;Europe serait ainsi expos\u00e9e \u00e0 divers degr\u00e9s aux effets secondaires des p\u00e9nuries de gaz (qui p\u00e8seront principalement sur les productions ainsi que sur certains services publics).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La crise \u00e9nerg\u00e9tique europ\u00e9enne, principalement conduite par des p\u00e9nuries d\u2019approvisionnement en gaz, va n\u00e9cessiter d\u2019importantes r\u00e9ductions de la consommation dans les pays de l\u2019Union. Malgr\u00e9 celles-ci, certains \u00c9tats-membres seront toutefois plus susceptibles de faire face \u00e0 ces p\u00e9nuries en raison de leurs options d\u2019approvisionnement. Une analyse en deux cartes et deux graphs.<\/p>\n","protected":false},"author":2622,"featured_media":162550,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":2,"footnotes":""},"categories":[1730],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-162547","post","type-post","status-publish","format-standard","hentry","category-energie-et-environnement","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":162550,"excerpt":"La crise \u00e9nerg\u00e9tique europ\u00e9enne, principalement conduite par des p\u00e9nuries d\u2019approvisionnement en gaz, va n\u00e9cessiter d\u2019importantes r\u00e9ductions de la consommation dans les pays de l\u2019Union. Malgr\u00e9 celles-ci, certains \u00c9tats-membres seront toutefois plus susceptibles de faire face \u00e0 ces p\u00e9nuries en raison de leurs options d\u2019approvisionnement. Une analyse en deux cartes et deux graphs.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver ? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver ? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La crise \u00e9nerg\u00e9tique europ\u00e9enne, principalement conduite par des p\u00e9nuries d\u2019approvisionnement en gaz, va n\u00e9cessiter d\u2019importantes r\u00e9ductions de la consommation dans les pays de l\u2019Union. Malgr\u00e9 celles-ci, certains \u00c9tats-membres seront toutefois plus susceptibles de faire face \u00e0 ces p\u00e9nuries en raison de leurs options d\u2019approvisionnement. Une analyse en deux cartes et deux graphs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-07T08:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-11T14:19:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22713871_000014-scaled-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22713871_000014-scaled-3.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/\",\"name\":\"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver ? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22518112_000001-scaled-2.jpg\",\"datePublished\":\"2022-10-07T08:00:35+00:00\",\"dateModified\":\"2022-10-11T14:19:14+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22518112_000001-scaled-2.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22518112_000001-scaled-2.jpg\",\"width\":2560,\"height\":1900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver ? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/","og_locale":"fr_FR","og_type":"article","og_title":"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver ? | Le Grand Continent","og_description":"La crise \u00e9nerg\u00e9tique europ\u00e9enne, principalement conduite par des p\u00e9nuries d\u2019approvisionnement en gaz, va n\u00e9cessiter d\u2019importantes r\u00e9ductions de la consommation dans les pays de l\u2019Union. Malgr\u00e9 celles-ci, certains \u00c9tats-membres seront toutefois plus susceptibles de faire face \u00e0 ces p\u00e9nuries en raison de leurs options d\u2019approvisionnement. Une analyse en deux cartes et deux graphs.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/","og_site_name":"Le Grand Continent","article_published_time":"2022-10-07T08:00:35+00:00","article_modified_time":"2022-10-11T14:19:14+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22713871_000014-scaled-3.jpg","type":"image\/jpeg"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22713871_000014-scaled-3.jpg","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/","name":"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver ? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22518112_000001-scaled-2.jpg","datePublished":"2022-10-07T08:00:35+00:00","dateModified":"2022-10-11T14:19:14+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22518112_000001-scaled-2.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22518112_000001-scaled-2.jpg","width":2560,"height":1900},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/10\/07\/quels-etats-membres-sont-les-plus-exposes-a-des-risques-de-penuries-de-gaz-cet-hiver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Quels \u00c9tats-membres sont les plus expos\u00e9s \u00e0 des risques de p\u00e9nuries de gaz cet hiver&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":1730,"name":"\u00c9nergie et environnement","slug":"energie-et-environnement"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/10\/SIPA_AP22518112_000001-scaled-2.jpg","width":2560,"height":1900,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/162547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=162547"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/162547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/162550"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=162547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=162547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=162547"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=162547"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=162547"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=162547"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=162547"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=162547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}