{"id":157471,"date":"2022-09-12T05:32:00","date_gmt":"2022-09-12T03:32:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=157471"},"modified":"2022-09-12T14:53:35","modified_gmt":"2022-09-12T12:53:35","slug":"poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/","title":{"rendered":"\u00ab&#160;Poutine est en train de perdre la guerre \u00e9cologique&#160;\u00bb, une conversation avec Frans Timmermans"},"content":{"rendered":"\n<p><em>Cet entretien est disponible <a href=\"https:\/\/geopolitique.eu\/en\/2022\/09\/11\/a-conversation-with-frans-timmermans\/\" target=\"_blank\" rel=\"noreferrer noopener\">en anglais sur le site du Groupe d&rsquo;\u00e9tudes g\u00e9opolitiques<\/a>.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Assiste-t-on \u00e0 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/18\/la-naissance-de-lecologie-de-guerre\/\">la naissance de \u00ab&#160;l\u2019\u00e9cologie de guerre&#160;\u00bb<\/a>&#160;? L\u2019utilisation par le Kremlin du gaz comme arme aura-elle un effet sur la perception de la transition et plus largement de l\u2019action europ\u00e9enne&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Nous devons nous rendre compte que l&rsquo;Europe a besoin d&rsquo;\u00eatre souveraine dans le domaine de l&rsquo;\u00e9nergie et que notre souverainet\u00e9 ne peut se construire que sur l&rsquo;\u00e9nergie renouvelable. Nous n\u2019avons pas de p\u00e9trole, nous avons tr\u00e8s peu de gaz, tr\u00e8s peu de charbon et nous devons faire face \u00e0 des enjeux climatiques tr\u00e8s s\u00e9rieux. C\u2019est donc \u00e0 travers le vent, le soleil, la g\u00e9othermie, que nous allons pouvoir construire notre souverainet\u00e9, sans \u00eatre d\u00e9pendants ni du gaz russe, ni d\u2019autres exportateurs d\u2019hydrocarbures. Le march\u00e9 de l\u2019hydrog\u00e8ne vert sera un march\u00e9 mondial par exemple, mais il s\u2019agira d\u2019un march\u00e9 tr\u00e8s diversifi\u00e9, qui ne donnera pas \u00e0 certains pays la possibilit\u00e9 de chanter d&rsquo;autres.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le gaz est-il encore une \u00e9nergie de transition viable, comme un certain nombre des pays europ\u00e9ens, y compris l\u2019Allemagne, le soutiennent&#160;?<\/strong><\/h3>\n\n\n\n<p>Oui, bien s\u00fbr, \u00e0 la Commission nous avons toujours assum\u00e9 que le gaz naturel serait une \u00e9nergie de transition parce que les \u00e9missions du gaz naturel sont beaucoup plus faibles que celles du charbon par exemple. Pour certains pays, qui doivent se d\u00e9barrasser du charbon, le gaz est une \u00e9nergie de transition clef. Ce qui change, c\u2019est qu\u2019aujourd\u2019hui ce gaz ne peut plus venir de la Russie, ce qui, pour l\u2019Europe, signifie trouver d\u2019autres sources d&rsquo;approvisionnements, pour des prix qui seront certainement plus \u00e9lev\u00e9s.<\/p>\n\n\n\n<p>Ces derniers mois ont aussi montr\u00e9 que&nbsp;la transition vers les \u00e9nergies renouvelables va encore beaucoup plus vite qu&rsquo;avant. Il y un sc\u00e9nario dans lequel certains pays vont peut-\u00eatre continuer un peu plus longtemps avec le charbon pour ensuite imm\u00e9diatement aller vers les renouvelables au lieu d&rsquo;utiliser le gaz naturel comme source de transition.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>D\u2019ailleurs, le gaz ne jouera pas ce r\u00f4le uniquement en Europe, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/06\/29\/lafrique-a-le-plus-a-gagner-de-la-transition-vers-des-energies-propres\/\">mais aussi en Afrique<\/a>.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nous n\u2019avons pas de p\u00e9trole, nous avons tr\u00e8s peu de gaz, tr\u00e8s peu de charbon et nous devons faire face \u00e0 des enjeux climatiques tr\u00e8s s\u00e9rieux. C\u2019est donc \u00e0 travers le vent, le soleil, la g\u00e9othermie, que nous allons pouvoir construire notre souverainet\u00e9, sans \u00eatre d\u00e9pendants ni du gaz russe, ni d\u2019autres exportateurs d\u2019hydrocarbures.<\/p><cite>Frans Timmermans<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Que pensez-vous de l\u2019opposition au nucl\u00e9aire qui semblait faire consensus en Allemagne dans l\u2019\u00e8re Merkel&#160;? S\u2019agissait-il d\u2019une erreur strat\u00e9gique&#160;?<\/strong><\/h3>\n\n\n\n<p>Je comprends tr\u00e8s bien le raisonnement du gouvernement allemand que pr\u00e9sidait Merkel, ainsi la position du gouvernement fran\u00e7ais \u2013 ce n&rsquo;est pas \u00e0 la Commission de dicter le mix \u00e9nerg\u00e9tique des \u00c9tats-membres. Notre devoir est d&rsquo;imposer la r\u00e9duction de 55&#160;% des \u00e9missions d&rsquo;ici 2030 mais c&rsquo;est aux \u00c9tats membres de d\u00e9cider comment le faire. Cela dit, nous voyons clairement que, dans le contexte de la guerre et alors que le gaz naturel est devenu une arme pour Vladimir Poutine, le gouvernement allemand revient sur certaines positions \u2014 c\u2019est \u00e9galement le cas avec le nucl\u00e9aire.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L&rsquo;Europe pourrait-elle se passer du gaz russe cet hiver et avec quelle strat\u00e9gie&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Oui, nous allons pouvoir nous passer du gaz russe. Nous avons r\u00e9ussi \u00e0 organiser notre approvisionnement, nos r\u00e9serves sont remplies \u00e0 82,5&#160;% ce qui est une sorte d\u2019exploit.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quels sont les pays les plus vuln\u00e9rables&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Les pays plus vuln\u00e9rables sont ceux qui sont tr\u00e8s d\u00e9pendants du gaz russe&#160;: les pays d&rsquo;Europe centrale notamment, mais aussi l&rsquo;Allemagne. En m\u00eame temps, la solidarit\u00e9 europ\u00e9enne telle que nous l\u2019avons organis\u00e9e sera en mesure d&rsquo;\u00e9viter les pires sc\u00e9narios. \u00c0 moins que nous ne devions faire face \u00e0 un hiver exceptionnellement froid, je crois que nous sommes pr\u00e9par\u00e9s. L&rsquo;enjeu, en r\u00e9alit\u00e9, sera surtout de s&rsquo;organiser pour l&rsquo;ann\u00e9e prochaine puisque nous avons encore eu du gaz russe cette ann\u00e9e. Il nous faut nous pr\u00e9parer et assumer que, l&rsquo;ann\u00e9e prochaine, les livraisons depuis la Russie n\u2019existeront tout simplement plus.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les premi\u00e8res semaines de la guerre, plusieurs analystes soutenaient que si l&rsquo;Europe avait r\u00e9ussi \u00e0 adopter un embargo sur les hydrocarbures russes, la guerre aurait pris fin, tant les bases du r\u00e9gime de Poutine auraient \u00e9t\u00e9 bouscul\u00e9es. Aujourd\u2019hui, c\u2019est la Russie elle-m\u00eame qui arr\u00eate les exportations de gaz. Qu\u2019est-ce que nous n\u2019avons pas compris&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Il ne faut pas commettre l\u2019erreur de croire que les sanctions europ\u00e9ennes n&rsquo;ont pas eu et n\u2019ont pas d&rsquo;effet. Elles sont en train de transformer en profondeur la soci\u00e9t\u00e9 et l&rsquo;\u00e9conomie russe. J\u2019ai habit\u00e9 en Russie, je connais assez bien le pays. L&rsquo;avantage d&rsquo;une autocratie qui contr\u00f4le aussi fortement l\u2019information c&rsquo;est que vous pouvez manipuler la v\u00e9rit\u00e9 et c&rsquo;est ce qui fait tout le jeu de Poutine&#160;: il veut cr\u00e9er l&rsquo;impression que nous serions terriblement affaiblis par l&rsquo;utilisation des hydrocarbures comme arme, qu\u2019il serait en train de gagner la guerre \u00e9cologique.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La solidarit\u00e9 europ\u00e9enne telle que nous l\u2019avons organis\u00e9e sera en mesure d&rsquo;\u00e9viter les pires sc\u00e9narios. \u00c0 moins que nous ne devions faire face \u00e0 un hiver exceptionnellement froid, je crois que nous sommes pr\u00e9par\u00e9s. <\/p><cite>Frans Timmermans<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Au-del\u00e0 des manipulations, le contexte pourtant est clair&#160;: la Russie est isol\u00e9e et vraiment affaiblie mais en m\u00eame temps, elle a des revenus gigantesques gr\u00e2ce aux march\u00e9s des hydrocarbures. Je n\u2019ai jamais cru qu\u2019un embargo sur le gaz russe mettrait Poutine \u00e0 genoux, ni qu&rsquo;au terme de quelques semaines la guerre s&rsquo;arr\u00eaterait. La guerre va durer et une autocratie est capable de cacher des choses et de mettre des pressions incroyables sur les citoyens, qui n&rsquo;osent plus rien dire. La plupart des Russes, apr\u00e8s vingt ans de mensonges, ne savent plus quoi croire. Et puis, il y a la peur, les opposants sont arr\u00eat\u00e9s, enferm\u00e9s.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les gouvernements europ\u00e9ens ont jusqu\u2019\u00e0 maintenant opt\u00e9 pour des mesures limit\u00e9es et nationales pour faire face \u00e0 la hausse des prix de l\u2019\u00e9nergie. Quelles sont aujourd&rsquo;hui les possibilit\u00e9s pour se coordonner au niveau europ\u00e9en, surtout \u00e0 court terme pour faire face \u00e0 la hausse des prix&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Il existe d\u00e9j\u00e0 des mesures \u00e0 l&rsquo;\u00e9chelle nationale, prises par certains \u00c9tats membres. \u00c0 court terme, il faut maintenant organiser la solidarit\u00e9 europ\u00e9enne. Nous voyons clairement que la hausse des prix de l&rsquo;\u00e9nergie p\u00e8se plus lourdement sur ceux qui n&rsquo;ont que tr\u00e8s peu \u00e0 d\u00e9penser. D&rsquo;autres sont capables de payer, de porter ce fardeau&#160;: il s\u2019agit de redistribuer. Nous allons faire des propositions dans ce sens, pour voir comment all\u00e9ger la pression sur les couches les plus vuln\u00e9rables de la soci\u00e9t\u00e9. Une proposition \u2014 aussi soutenue par les gouvernements allemand et fran\u00e7ais \u2014 serait de faire en sorte que les profits excessifs du secteur \u00e9nerg\u00e9tique soient redistribu\u00e9s vers les entreprises et les citoyens.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La r\u00e9vision de l\u2019architecture du march\u00e9 de l\u2019\u00e9lectricit\u00e9 est-elle \u00e0 l\u2019ordre du jour&#160;? L&rsquo;accumulation des interventions politiques sur les march\u00e9s de l&rsquo;\u00e9nergie pousse \u00e0 ses limites l&rsquo;id\u00e9e que l&rsquo;\u00e9nergie peut circuler via les march\u00e9s. Pensez-vous qu\u2019il faudrait r\u00e9aliser que l&rsquo;\u00e9nergie n&rsquo;est pas une marchandise comme les autres&#160;?<\/strong><\/h3>\n\n\n\n<p>Il faut \u00eatre tr\u00e8s prudent.&nbsp;<\/p>\n\n\n\n<p>Nous avons eu besoin de trente ans pour b\u00e2tir le march\u00e9 de l\u2019\u00e9lectricit\u00e9, dans la structure que nous connaissons aujourd\u2019hui. \u00c0 la Commission, nous sommes convaincus qu&rsquo;il y a des raisons pour revoir cette architecture parce que le march\u00e9 a chang\u00e9, avec notamment l&rsquo;augmentation de la part des \u00e9nergies renouvelables dans le mix \u00e9nerg\u00e9tique. Cela nous pousse \u00e0 revoir l&rsquo;\u00e9quilibre entre les diff\u00e9rentes sources d&rsquo;\u00e9nergie et cela pourrait mener \u00e0 des propositions pour cr\u00e9er un nouvel \u00e9quilibre entre la partie du prix issue des renouvelables et celle qui vient des sources d\u2019\u00e9nergies carbon\u00e9es. Le point essentiel c\u2019est que le prix de l&rsquo;\u00e9lectricit\u00e9 ne devrait plus \u00eatre coupl\u00e9 au prix du gaz naturel de m\u00eame mani\u00e8re.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le lien entre les d\u00e9penses engag\u00e9es pour prot\u00e9ger les consommateurs de la hausse de prix de l\u2019\u00e9nergie et les r\u00e8gles budg\u00e9taires europ\u00e9ennes est d\u00e9sormais \u00e9vident. Le programme de travail de la Commission int\u00e8gre-t-il la r\u00e9vision du Pacte de stabilit\u00e9 et de croissance&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Pas pour le moment, mais nous devrons \u00e9videmment faire face, comme ce fut le cas pendant la pand\u00e9mie, \u00e0 une situation particuli\u00e8rement difficile. Les r\u00e8gles sont les r\u00e8gles \u2014 mais les circonstances sont fondamentalement diff\u00e9rentes. R\u00e9cemment, je me suis entretenu avec la directrice du FMI, elle m&rsquo;a r\u00e9it\u00e9r\u00e9 que nous aurons besoin d&rsquo;investir de mani\u00e8re massive \u00e0 l&rsquo;\u00e9chelle mondiale pour redresser l&rsquo;\u00e9conomie. Il faut donc repenser certaines r\u00e8gles sans pour autant pr\u00e9tendre que d\u00e9sormais l&rsquo;argent ne co\u00fbterait rien et que nous aurions un acc\u00e8s illimit\u00e9 \u00e0 des nouveaux moyens. Tout ce que nous d\u00e9pensons, il nous faudra le rembourser. Mais si nous n\u2019investissons pas dans un changement productif, nous placerons un fardeau insupportable sur les \u00e9paules de nos enfants.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Est-il possible d\u2019envisager un nouveau plan de relance d&rsquo;apr\u00e8s-guerre&#160;?<\/strong><\/h3>\n\n\n\n<p>Oui. Nous allons conna\u00eetre une p\u00e9riode tr\u00e8s difficile et je crains que nous ne comprenions pas tout \u00e0 fait les difficult\u00e9s auxquelles il faudra faire face. Je pense toutefois qu\u2019elle sera suivie d\u2019une p\u00e9riode de relance remarquable. Si nous regardons le potentiel d&rsquo;un pays comme l&rsquo;Ukraine, le potentiel des \u00e9nergies renouvelables, la vitesse avec laquelle, par exemple, l&rsquo;industrie s&rsquo;adapte, qu\u2019il s\u2019agisse de l\u2019automobile, de l&rsquo;acier de l&rsquo;informatique, je reste quand m\u00eame optimiste.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nous allons conna\u00eetre une p\u00e9riode tr\u00e8s difficile et je crains que nous ne comprenions pas tout \u00e0 fait les difficult\u00e9s auxquelles il faudra faire face. Je pense toutefois qu\u2019elle sera suivie d\u2019une p\u00e9riode de relance remarquable.<\/p><cite>Frans Timmermans<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Certains \u00c9tats membres engagent des investissements importants dans les infrastructures fossiles. Est-ce que c&rsquo;est un danger pour les objectifs climatiques&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Nous allons utiliser le charbon un peu plus longtemps que pr\u00e9vu, m\u00eame si \u00e0 l&rsquo;heure actuelle il est tr\u00e8s cher et il y en a pas trop. Concernant les infrastructures fossiles, si nous b\u00e2tissons des infrastructures pour le gaz naturel et que nous les pr\u00e9parons pour \u00eatre accessibles \u00e0 l&rsquo;hydrog\u00e8ne vert plus tard, c&rsquo;est un investissement que je peux totalement comprendre. Nous allons essayer de pousser ceux qui doivent investir encore dans des infrastructures pour le gaz naturel, pour assurer la chaleur dans les foyers et le fonctionnement de l&rsquo;industrie, de pr\u00e9parer cette infrastructure au transport de l&rsquo;hydrog\u00e8ne vert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L\u2019Union europ\u00e9enne s\u2019\u00e9tait donn\u00e9e un cadre pour agir&#160;: le Pacte vert. Est-elle en train de r\u00e9pondre aux mutations g\u00e9opolitiques \u2013 qu\u2019il s\u2019agisse de la guerre en Ukraine ou de la rivalit\u00e9 \u00c9tats-Unis-Chine \u2013 en suivant ce chemin qu\u2019elle s\u2019\u00e9tait trac\u00e9e, d\u2019atteindre la neutralit\u00e9 carbone \u00e0 l\u2019horizon 2050&#160;?<\/strong><\/h3>\n\n\n\n<p>Quand nous avons \u00e9labor\u00e9 et pr\u00e9sent\u00e9 le Pacte vert en 2019, avant donc la pand\u00e9mie et avant la Guerre en Ukraine, nous avons d\u00fb essuyer les critiques de ceux qui nous accusaient en disant en substance&#160;: \u201cC&rsquo;est bien le Pacte vert, mais revenez dans dix ans et on verra\u201d. Au fil des crises, nous avons pu prouver que le Pacte vert \u00e9tait aussi une r\u00e9ponse \u00e0 la pand\u00e9mie, parce qu&rsquo;il fallait reconstruire notre soci\u00e9t\u00e9, il fallait reconstruire notre \u00e9conomie, transformer notre industrie. Nous avons pu prouver que la transition \u00e9nerg\u00e9tique, que l&rsquo;\u00e9conomie circulaire, \u00e9taient cr\u00e9atrices d\u2019emploi, qu\u2019elles redonnent de l&rsquo;\u00e9nergie \u00e0 notre \u00e9conomie, tout en remettant l&rsquo;Europe dans la premi\u00e8re place mondiale du d\u00e9veloppement industriel. Avec la guerre Russe en Ukraine, l&rsquo;\u00e9l\u00e9ment du Pacte vert qui est devenu encore plus important, c&rsquo;est la transition vers les \u00e9nergies renouvelables. Le Pacte vert, au-d\u00e9l\u00e0 de son objectif de r\u00e9duction des \u00e9missions, est devenu l\u2019instrument pour cr\u00e9er une vraie souverainet\u00e9 \u00e9nerg\u00e9tique europ\u00e9enne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La crise \u00e9nerg\u00e9tique affaiblit-elle la position europ\u00e9enne de leader climatique&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Je reviens d\u2019une rencontre du G20, \u00e0 Bali et je n\u2019ai pas du tout l&rsquo;impression que nous ayons perdu notre position de leadership. Nous l\u2019avons&nbsp; affirm\u00e9 lors de la COP 26, \u00e0 Glasgow, et nous sommes en train de b\u00e2tir des ponts entre les diverses positions, par exemple sur la n\u00e9cessit\u00e9 d&rsquo;augmenter les d\u00e9penses pour l&rsquo;adaptation, pour pallier les pertes<em>. <\/em>Notre position est \u00e0 mi-chemin entre la position am\u00e9ricaine et la position des pays en voie de d\u00e9veloppement et je crois que nous avons une certaine cr\u00e9dibilit\u00e9, mais j&rsquo;esp\u00e8re qu&rsquo;on pourrait encore l\u2019augmenter. Plus de la moiti\u00e9 de nos d\u00e9penses pour la politique du climat va vers l&rsquo;adaptation. Les \u00c9tats membres doivent \u00eatre pr\u00eats \u00e0 d\u00e9penser un peu plus aussi pour les pertes et pr\u00e9judices caus\u00e9es par le changement climatique, car c\u2019est ce que demandent les pays en voie de d\u00e9veloppement. Ce qui est tragique c\u2019est que ceux qui souffrent le plus des effets du changement climatique ne font pas partie de ceux qui l&rsquo;ont cr\u00e9\u00e9. L&rsquo;Afrique n&rsquo;est responsable que de 3&#160;% des \u00e9missions globales. Il y a donc une responsabilit\u00e9 des certains pays d\u00e9velopp\u00e9s, qui sont responsables de 30&#160;% ou 20&#160;% des \u00e9missions, ou comme l&rsquo;Union europ\u00e9enne pour 8&#160;% des \u00e9missions globales. C&rsquo;est nous qui avons profit\u00e9 pendant deux cents ans du charbon, puis du p\u00e9trole et puis du gaz pour cr\u00e9er nos richesses.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les \u00c9tats membres doivent \u00eatre pr\u00eats \u00e0 d\u00e9penser un peu plus aussi pour les pertes et pr\u00e9judices caus\u00e9es par le changement climatique, car c\u2019est ce que demandent les pays en voie de d\u00e9veloppement. Ce qui est tragique c\u2019est que ceux qui souffrent le plus des effets du changement climatique ne font pas partie de ceux qui l&rsquo;ont cr\u00e9\u00e9.<\/p><cite>Frans Timmermans<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La COP 27 de novembre aura mis au premier plan la question du financement de l\u2019action climatique dans les pays en voie de d\u00e9veloppement. Comment se positionnera l\u2019Union&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Encore une fois, je le r\u00e9p\u00e8te, il faut prendre notre responsabilit\u00e9. Je crois que l&rsquo;Union europ\u00e9enne prend sa responsabilit\u00e9, nous sommes d\u00e9j\u00e0 responsables pour un tiers de tout le financement pour l\u2019adaptation et climat, mais il faut faire plus. Il faut aussi assurer des investissements dans ces pays, qui seront rendus plus faciles si nous sommes aussi capables d&rsquo;investir dans l&rsquo;adaptation. En m\u00eame temps, si nous ne r\u00e9duisons pas nos \u00e9missions \u2014 et c&rsquo;est la responsabilit\u00e9 du G20, parce que 80&#160;% des \u00e9missions mondiales viennent des 20 pays du G20 \u2014 alors n&rsquo;importe quel montant qu&rsquo;on d\u00e9pensera sera insuffisant pour faire face \u00e0 la crise climatique. Si nous d\u00e9passons les 2\u00b0 C et si nous nous dirigeons plut\u00f4t vers 3, 4\u00b0 C alors la crise sera tellement grave que nous ne pourrons pas y faire face. Il y a toujours cette relation entre mitigation et adaptation. Les pays d\u00e9velopp\u00e9s ont une responsabilit\u00e9 suppl\u00e9mentaire pour faire ce que nous avons&nbsp; promis, et en plus r\u00e9pondre de fa\u00e7on constructive aux exigences des pays en voie de d\u00e9veloppement pour les pertes et pr\u00e9judices caus\u00e9s par le changement climatique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pourquoi les partenaires africains ne sont pas align\u00e9s avec l\u2019Union europ\u00e9enne&#160;? Quelle est la strat\u00e9gie de la Commission pour contrer cela, et dans quelle mesure la lutte contre le changement climatique et l\u2019acc\u00e8s \u00e0 l\u2019\u00e9nergie ont-ils un r\u00f4le \u00e0 jouer&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>J&rsquo;ai parl\u00e9 r\u00e9cemment avec quatre pr\u00e9sidents africains et en effet, vous avez raison, ils ne sont pas align\u00e9s avec nous \u00e0 100&#160;% sur la guerre russe en Ukraine. Pourquoi&#160;? Parce qu&rsquo;ils ont des craintes pour l&rsquo;apprivoisement de c\u00e9r\u00e9ales, pour la politique \u00e9nerg\u00e9tique, mais aussi pour la politique de s\u00e9curit\u00e9 parce les Russes sont particuli\u00e8rement actifs en Afrique \u00e0 l&rsquo;heure actuelle.<\/p>\n\n\n\n<p>Je crois que la chose la plus importante, \u00e0 court terme, est de montrer notre solidarit\u00e9 surtout en ce qui concerne les denr\u00e9es alimentaires. Mais ce qui est encore beaucoup plus important, c&rsquo;est de faciliter les investissements dans les pays africains, pour les aider \u00e0 augmenter la production \u00e9nerg\u00e9tique. Six cent millions d&rsquo;Africains n&rsquo;ont aujourd\u2019hui pas acc\u00e8s \u00e0 l&rsquo;\u00e9lectricit\u00e9, et ce serait une r\u00e9volution d\u2019\u00eatre enfin capable de leur donner acc\u00e8s \u00e0 travers le photovolta\u00efque et les \u00e9oliennes. Deuxi\u00e8mement, il faut aider les pays africains \u00e0 faire cette transition \u00e9nerg\u00e9tique, y compris en utilisant le gaz naturel. Il ne devrait pas y avoir de tabou entre l&rsquo;Europe et l&rsquo;Afrique l\u00e0-dessus.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La Communaut\u00e9 politique europ\u00e9enne est-elle un cadre utile pour organiser le continent&#160;? Quel pourrait \u00eatre son apport dans le volet climatique&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Oui je crois qu&rsquo;il faut cr\u00e9er un forum, un lieu, une agora, o\u00f9 tous les pays europ\u00e9ens se rencontrent pour parler des sujets communs. Je vois tr\u00e8s mal comment on peut par exemple cr\u00e9er un espace d&rsquo;\u00e9nergie renouvelable en Europe sans les Britanniques ou sans les Norv\u00e9giens. Cela d\u00e9passe bien s\u00fbr les limites de l&rsquo;Union europ\u00e9enne. Je vois aussi tr\u00e8s mal comment nous pouvons parler de la s\u00e9curit\u00e9 en Europe sans avoir de discussions avec les Ukrainiens ou les pays du Caucase et surtout avec les pays des Balkans qui sont candidats \u00e0 l&rsquo;adh\u00e9sion. Je crois que l&rsquo;initiative du pr\u00e9sident Macron a une utilit\u00e9 pour la s\u00e9curit\u00e9 en Europe et aussi pour la transition \u00e9cologique et \u00e9nerg\u00e9tique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Que signifie la conversion g\u00e9opolitique de l&rsquo;Union&#160;? Quelle est sa logique et quel est son horizon<\/strong> <strong>&#160;?<\/strong><\/h3>\n\n\n\n<p>Je crois qu&rsquo;en tant qu\u2019hommes et femmes politiques, nous sommes responsables de la s\u00e9curit\u00e9 et de la prosp\u00e9rit\u00e9 de nos citoyens. Pourquoi une politique de s\u00e9curit\u00e9&#160;? Pour \u00e9viter la guerre, pour cr\u00e9er des relations internationales stables, pour donner la possibilit\u00e9 d&rsquo;un d\u00e9veloppement \u00e9conomique stable. Pour assurer la paix sociale et pour assurer que tous nos citoyens aient acc\u00e8s au d\u00e9veloppement et acc\u00e8s \u00e0 la croissance \u00e9conomique. C&rsquo;est le but de notre politique et si nous voulons y arriver,&nbsp; il faut affronter la crise climatique.<\/p>\n\n\n\n<p><em>[Le monde se transforme. Depuis le tout d\u00e9but de l\u2019invasion de la Russie de l\u2019Ukraine, avec nos cartes, nos analyses et nos perspectives nous avons aid\u00e9 presque 3 millions de personnes \u00e0 comprendre les transformations g\u00e9opolitiques de cette s\u00e9quence. Si vous trouvez notre travail utile et vous souhaitez contribuer \u00e0 ce que le Grand Continent reste une publication ouverte, vous pouvez vous abonner<\/em>&nbsp;<a href=\"https:\/\/legrandcontinent.eu\/fr\/user-dashboard\/register\/\"><em>par ici<\/em><\/a><em>.]<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Partagez-vous l\u2019id\u00e9e de plus en plus pr\u00e9sente \u00e0 Washington d\u2019une \u00ab&#160;nouvelle guerre froide&#160;\u00bb avec la Chine&#160;?<\/strong><\/h3>\n\n\n\n<p>Non, je ne partage pas cette id\u00e9e. Nos syst\u00e8mes sont diff\u00e9rents, notre vision de la soci\u00e9t\u00e9, de la d\u00e9mocratie est diff\u00e9rente de celle port\u00e9e par le Parti communiste en Chine. Mais cela ne veut pas dire que nous sommes dans une situation de confrontation ou de Guerre froide. Je vois toujours des possibilit\u00e9s de coop\u00e9ration avec P\u00e9kin, il ne faut pas \u00eatre excessif, ni na\u00eff.&nbsp; Je crois que l&rsquo;Europe a besoin de d\u00e9terminer exactement sa propre position, d&rsquo;\u00e9viter qu&rsquo;on entre dans une situation de d\u00e9pendance vis-\u00e0-vis de la Chine, comme nous l&rsquo;avons fait avec la Russie. La Chine peut \u00eatre un partenaire dans le domaine du climat, mais aussi dans le domaine du d\u00e9veloppement \u00e9conomique et du commerce international, qui pour nous est tr\u00e8s important.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il faut cr\u00e9er un forum, un lieu, une agora, o\u00f9 tous les pays europ\u00e9ens se rencontrent pour parler des sujets communs. Je vois tr\u00e8s mal comment on peut par exemple cr\u00e9er un espace d&rsquo;\u00e9nergie renouvelable en Europe sans les Britanniques ou sans les Norv\u00e9giens. Cela d\u00e9passe bien s\u00fbr les limites de l&rsquo;Union europ\u00e9enne.<\/p><cite>Frans Timmermans<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Y a-t-il un risque de devenir d\u00e9pendant des autres r\u00e9gions du monde pour les m\u00e9taux rares&#160;?<\/strong><\/h3>\n\n\n\n<p>Il y a toujours ce risque mais cela d\u00e9pend aussi de notre capacit\u00e9 de d\u00e9velopper de nouveaux produits, qui d\u00e9pendent moins des m\u00e9taux rares, d\u2019avoir une diversification de nos relations commerciales. Je crois que l&rsquo;exp\u00e9rience de la guerre de Poutine nous a appris \u00e0 \u00e9viter des d\u00e9pendances unilat\u00e9rales, qui nous affaiblissent. Je crois que l\u2019un des atouts les plus incroyables de notre continent est la capacit\u00e9 de se r\u00e9inventer et d&rsquo;inventer de nouvelles technologies, d&rsquo;inventer de nouveaux produits et je vois d\u00e9j\u00e0, par exemple, que dans le domaine des batteries, nous sommes en train d&rsquo;aller tr\u00e8s vite et de d\u00e9velopper des batteries recyclables produites en Europe. Nous ferons la m\u00eame chose avec les panneaux solaires, je n\u2019ai aucun doute l\u00e0 dessus.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Exercice difficile alors que la guerre ravage l\u2019Ukraine&#160;: comment pensez-vous que devrait s\u2019installer la relation de l\u2019Union avec la Russie&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Cela va durer tr\u00e8s longtemps jusqu&rsquo;\u00e0 ce que la Russie trouve une r\u00e9ponse elle-m\u00eame&#160;: o\u00f9 est ce qu&rsquo;elle veut aller&#160;? Quels seront ses amis&#160;? Quelles seront ses alliances&#160;?&nbsp;<\/p>\n\n\n\n<p>Je crois que nous pouvons aider ce processus en montrant de quelle mani\u00e8re la Russie peut faire partie de la famille europ\u00e9enne, c&rsquo;est-\u00e0-dire en respectant l&rsquo;\u00e9tat de droit, en respectant la d\u00e9mocratie. \u00c0 l&rsquo;heure actuelle, nous en sommes tr\u00e8s loin, mais le pays ne va pas dispara\u00eetre, il continuera \u00e0 faire partie du continent europ\u00e9en. Il nous faut donc aussi faire un effort d&rsquo;imagination, un effort intellectuel, un effort aussi, je dirais, politique&#160;: imaginer une relation constructive entre l&rsquo;Union et la Russie. Pour le moment, la ligne choisie par le pr\u00e9sident Poutine exclut un tel d\u00e9veloppement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Faut-il r\u00e9server une place \u00e0 la Russie dans la construction de l\u2019architecture de s\u00e9curit\u00e9 en Europe \u2013 \u00e0 quelles conditions&#160;?<\/strong><\/h3>\n\n\n\n<p>La Russie a d\u00e9j\u00e0 une place dans une construction qu&rsquo;on a \u00e9tablie dans les ann\u00e9es \u201870 sur la base de la Conf\u00e9rence sur la s\u00e9curit\u00e9 et la coop\u00e9ration en Europe, qui s&rsquo;est d\u00e9velopp\u00e9e dans une organisation, l\u2019OSCE, mais la Russie a pr\u00e9f\u00e9r\u00e9 s&rsquo;en isoler.&nbsp;<\/p>\n\n\n\n<p>La trag\u00e9die de la Russie est l\u00e0&#160;: elle s&rsquo;isole elle-m\u00eame. Les propositions de coop\u00e9ration de la part des pays europ\u00e9ens ont \u00e9t\u00e9 maintes et abondantes. Il faut maintenant attendre que la Russie revienne elle-m\u00eame vers une attitude de coop\u00e9ration et sorte de cette posture de domination. Il y a une diff\u00e9rence philosophique entre nous et les Russes sur ce qu&rsquo;est la s\u00e9curit\u00e9 et la coop\u00e9ration. Pour la Russie, la s\u00e9curit\u00e9 se trouve dans l&rsquo;exportation d&rsquo;instabilit\u00e9 vers les r\u00e9gions en dehors de la Russie \u2014 on domine son voisinage en cr\u00e9ant de l&rsquo;instabilit\u00e9 aux fronti\u00e8res. La vision europ\u00e9enne est exactement l&rsquo;oppos\u00e9&#160;: on cr\u00e9e de la stabilit\u00e9 en exportant notre stabilit\u00e9 et notre croissance. C&rsquo;est comme cela&nbsp; que nous avons fait apr\u00e8s la chute du mur de Berlin, c&rsquo;est comme cela que nous avons chang\u00e9 l&rsquo;Europe centrale et orientale. Et c&rsquo;est comme cela que nous devons&nbsp; continuer.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Architecte et porte-voix du Pacte vert, le Commissaire europ\u00e9en \u00e0 l&rsquo;Action pour le climat est l&rsquo;un des acteurs clefs de la guerre verte qui se joue en Europe avant l&rsquo;hiver. Dans ce long entretien, il revient sur une s\u00e9quence les buts politiques rejoignent les objectifs climatiques&#160;&#160;: l&rsquo;Union est bien entr\u00e9e dans l&rsquo;\u00e2ge de l&rsquo;\u00e9cologie de guerre.<\/p>\n","protected":false},"author":10,"featured_media":157476,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":19,"footnotes":""},"categories":[1730],"tags":[],"staff":[1697],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-157471","post","type-post","status-publish","format-standard","hentry","category-energie-et-environnement","staff-ramona-bloj","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":157476,"excerpt":"Architecte et porte-voix du Pacte vert, le Commissaire europ\u00e9en \u00e0 l'Action pour le climat est l'un des acteurs clefs de la guerre verte qui se joue en Europe avant l'hiver. Dans ce long entretien, il revient sur une s\u00e9quence les buts politiques rejoignent les objectifs climatiques : l'Union est bien entr\u00e9e dans l'\u00e2ge de l'\u00e9cologie de guerre.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00ab Poutine est en train de perdre la guerre \u00e9cologique\u00a0\u00bb, une conversation avec Frans Timmermans | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab Poutine est en train de perdre la guerre \u00e9cologique\u00a0\u00bb, une conversation avec Frans Timmermans | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Architecte et porte-voix du Pacte vert, le Commissaire europ\u00e9en \u00e0 l&#039;Action pour le climat est l&#039;un des acteurs clefs de la guerre verte qui se joue en Europe avant l&#039;hiver. Dans ce long entretien, il revient sur une s\u00e9quence les buts politiques rejoignent les objectifs climatiques&#160;: l&#039;Union est bien entr\u00e9e dans l&#039;\u00e2ge de l&#039;\u00e9cologie de guerre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-12T03:32:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T12:53:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/gc-timmermans-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/gc-timmermans-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/\",\"name\":\"\u00ab Poutine est en train de perdre la guerre \u00e9cologique\u00a0\u00bb, une conversation avec Frans Timmermans | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg\",\"datePublished\":\"2022-09-12T03:32:00+00:00\",\"dateModified\":\"2022-09-12T12:53:35+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg\",\"width\":1752,\"height\":2560,\"caption\":\"European Commissioner for European Green Deal Frans Timmermans speaks during a media conference at EU headquarters in Brussels, Wednesday, July 14, 2021. The European Union is unveiling Wednesday sweeping new legislation to help meet its pledge to cut emissions of the gases that cause global warming by 55% over this decade, including a controversial plan to tax foreign companies for the pollution they cause. (AP Photo\/Valeria Mongelli)\/BRU124\/21195483311685\/\/2107141530\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Poutine est en train de perdre la guerre \u00e9cologique&#160;\u00bb, une conversation avec Frans Timmermans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab Poutine est en train de perdre la guerre \u00e9cologique\u00a0\u00bb, une conversation avec Frans Timmermans | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab Poutine est en train de perdre la guerre \u00e9cologique\u00a0\u00bb, une conversation avec Frans Timmermans | Le Grand Continent","og_description":"Architecte et porte-voix du Pacte vert, le Commissaire europ\u00e9en \u00e0 l'Action pour le climat est l'un des acteurs clefs de la guerre verte qui se joue en Europe avant l'hiver. Dans ce long entretien, il revient sur une s\u00e9quence les buts politiques rejoignent les objectifs climatiques&#160;: l'Union est bien entr\u00e9e dans l'\u00e2ge de l'\u00e9cologie de guerre.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/","og_site_name":"Le Grand Continent","article_published_time":"2022-09-12T03:32:00+00:00","article_modified_time":"2022-09-12T12:53:35+00:00","og_image":[{"width":2560,"height":1438,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/gc-timmermans-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/gc-timmermans-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/","name":"\u00ab Poutine est en train de perdre la guerre \u00e9cologique\u00a0\u00bb, une conversation avec Frans Timmermans | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg","datePublished":"2022-09-12T03:32:00+00:00","dateModified":"2022-09-12T12:53:35+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg","width":1752,"height":2560,"caption":"European Commissioner for European Green Deal Frans Timmermans speaks during a media conference at EU headquarters in Brussels, Wednesday, July 14, 2021. The European Union is unveiling Wednesday sweeping new legislation to help meet its pledge to cut emissions of the gases that cause global warming by 55% over this decade, including a controversial plan to tax foreign companies for the pollution they cause. (AP Photo\/Valeria Mongelli)\/BRU124\/21195483311685\/\/2107141530"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/12\/poutine-est-en-train-de-perdre-la-guerre-ecologique-une-conversation-avec-frans-timmermans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Poutine est en train de perdre la guerre \u00e9cologique&#160;\u00bb, une conversation avec Frans Timmermans"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1730,"name":"\u00c9nergie et environnement","slug":"energie-et-environnement"}],"lgc_author":{"id":1697,"name":"Ramona Bloj","slug":"ramona-bloj","description":null,"first_name":"Ramona ","last_name":"Bloj","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Capture-de\u0301cran-2023-06-15-a\u0300-16.43.03.png","width":870,"height":906,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg","width":1752,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/SIPA_AP22586157_000011-scaled.jpg","width":1752,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/157471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=157471"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/157471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/157476"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=157471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=157471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=157471"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=157471"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=157471"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=157471"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=157471"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=157471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}