{"id":143096,"date":"2022-05-21T10:00:00","date_gmt":"2022-05-21T08:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=143096"},"modified":"2022-09-18T19:37:20","modified_gmt":"2022-09-18T17:37:20","slug":"de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/","title":{"rendered":"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l&rsquo;avenir de l&rsquo;Europe&#160;: un moment crucial pour l&rsquo;Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg"},"content":{"rendered":"\n<p><em>Cet entretien est la transcription d\u2019un \u00e9change entre George Pagoulatos et Fran\u00e7ois Heisbourg qui s\u2019est tenu le 9 mai 2022 dans le cadre de la Nuit des Id\u00e9es et de la pr\u00e9sidence fran\u00e7aise du Conseil de l\u2019Union europ\u00e9enne. En partenariat avec l\u2019Institut Fran\u00e7ais, le Grand Continent publie une s\u00e9rie de textes et d\u2019entretiens&nbsp;&#160;: ces \u00ab&#160;<a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/grands-dialogues\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grands Dialogues<\/a>&#160;\u00bb forment un dispositif r\u00e9unissant des personnalit\u00e9s intellectuelles de premier plan venues du monde des arts, des lettres, des sciences, du journalisme et de l\u2019engagement et repr\u00e9sentant l\u2019ensemble des \u00c9tats membres de l\u2019Union europ\u00e9enne.<\/em><\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/logos.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"3460\"\n        data-pswp-height=\"1374\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/logos-330x131.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/logos-690x274.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/logos-990x393.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/logos-690x274.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/logos-990x393.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/logos-125x50.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\"><strong>Pour commencer, je voudrais que vous interpr\u00e9tiez et analysiez deux \u00e9v\u00e9nements. D\u2019abord, la conf\u00e9rence sur l&rsquo;avenir de l&rsquo;Europe qui s&rsquo;est termin\u00e9e avec une belle c\u00e9r\u00e9monie \u00e0 Strasbourg, en pr\u00e9sence du Pr\u00e9sident Fran\u00e7ais et d&rsquo;Ursula Von Leyen et Roberta Metsola. Et le d\u00e9fil\u00e9 sur la Place Rouge. Ces derniers jours, la rumeur a \u00e9t\u00e9 agit\u00e9e que Poutine allait \u00e9voquer des menaces nucl\u00e9aires dans un discours incendiaire mais ce n\u2019a pas \u00e9t\u00e9 le cas. Il reste ferme sur ce qu\u2019il a toujours dit en \u00e9voquant son \u00ab&#160;op\u00e9ration sp\u00e9ciale&#160;\u00bb.<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>George Pagoulatos<\/strong><\/h4>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-small\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Pagoulatos.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"354\"\n        data-pswp-height=\"344\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Pagoulatos-125x121.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Pagoulatos-330x321.png\"\r\n                media=\"(min-width: 375px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Pagoulatos-125x121.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>Il semble clair aujourd&rsquo;hui que Poutine se trouve dans une impasse puisque ses visions et ambitions n&rsquo;ont pas pu se r\u00e9aliser. Mettre la barre encore plus haut aurait \u00e9largi l\u2019\u00e9cart de cet \u00e9chec. Prof\u00e9rer des menaces qui n&rsquo;auraient pu \u00eatre appliqu\u00e9es l&rsquo;aurait expos\u00e9 davantage et nous aurions aussi connu le risque de se retrouver dans un sch\u00e9ma d\u2019escalade incontr\u00f4lable. J&rsquo;aimerais retenir de cette journ\u00e9e, et de cette parade, l&rsquo;isolement de la Russie illustr\u00e9 par le fait qu&rsquo;il n&rsquo;y avait aucune autre personnalit\u00e9 \u00e9trang\u00e8re \u00e0 cette manifestation qui honore la fin de la Seconde Guerre mondiale et la contribution historique de l&rsquo;URSS. Aussi, aucun journaliste n&rsquo;avait pu pr\u00e9voir ce que Vladimir Poutine allait dire. C&rsquo;est encore un signe d&rsquo;isolement car personne ne peut anticiper les d\u00e9cisions de Poutine et de son syst\u00e8me herm\u00e9tique au reste du monde. Je retiens aussi cette semaine le militarisme de certaines images d\u2019enfants qui faisaient une parade avec des fausses-armes et qui, d&rsquo;une certaine mani\u00e8re, rappelaient la jeunesse nazi, nous revoyant au moment les plus obscurs du XX\u00e8me si\u00e8cle et des ann\u00e9es 1930.<\/p>\n\n\n\n<p>Avec ses choix, Vladimir Poutine s&rsquo;isole du monde non seulement d\u2019un point de vue \u00e9conomique, au niveau des \u00e9changes commerciaux, mais s&rsquo;\u00e9loigne d&rsquo;\u00e9l\u00e9ments acquis qui ont mis fin \u00e0 la barbarie connue pendant la Seconde Guerre mondiale. Le pr\u00e9sident russe permet en effet le retour de ce type de militarisme que refl\u00e9tait la parade de Moscou aujourd&rsquo;hui.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fran\u00e7ois Heisbourg, est-ce qu&rsquo;\u00e0 votre avis Vladimir Poutine est isol\u00e9&#160;? Ou est-ce qu&rsquo;il garde son jeu ferm\u00e9&#160;? Est-ce que vous pouvez pr\u00e9voir les prochaines \u00e9tapes&#160;?<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Fran\u00e7ois Heisbourg<\/strong><\/h4>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-small\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Heisbourg.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1587\"\n        data-pswp-height=\"1516\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Heisbourg-125x119.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Heisbourg-330x315.png\"\r\n                media=\"(min-width: 375px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/06\/Heisbourg-125x119.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>S&rsquo;agissant de la guerre elle-m\u00eame, le pr\u00e9sident Poutine n&rsquo;a rien dit de nouveau, il a seulement repris les th\u00e9matiques des derniers mois. C&rsquo;est ce qu&rsquo;il n&rsquo;a pas dit qui est int\u00e9ressant&#160;: il n&rsquo;a pas \u00e9voqu\u00e9 la mobilisation. Soit qu&rsquo;il n&rsquo;en ait pas les moyens politiques, soit qu&rsquo;il n&rsquo;en ait pas les moyens \u00e9conomiques. Toujours est-il qu&rsquo;il maintient donc le dispositif militaire actuel. De l&rsquo;autre c\u00f4t\u00e9, il n&rsquo;a pas dit qu&rsquo;il allait donner aux forces russes dans le Donbass, et ailleurs en Ukraine, des missions moins importantes que celles qu&rsquo;elles r\u00e9alisent aujourd&rsquo;hui. George Pagoulatos a utilis\u00e9 l&rsquo;expression \u00ab&#160;d&rsquo;impasse&#160;\u00bb mais c\u2019est encore pire qu&rsquo;une impasse, c&rsquo;est une d\u00e9faite annonc\u00e9e car les moyens militaires dont Vladimir Poutine dispose le condamnent \u00e0 perdre. Les troupes russes ne peuvent pas \u00eatre renouvel\u00e9es et donc la Russie manque \u00e9trangement de soldats, en partie parce que le pays a d\u00e9cid\u00e9 que c&rsquo;\u00e9tait une op\u00e9ration militaire sp\u00e9ciale. Qu\u2019est-ce que cela veut dire en pratique&#160;? Cela signifie qu&rsquo;il n&rsquo;y a pas de mobilisation g\u00e9n\u00e9rale, qu&rsquo;il n&rsquo;y pas d\u2019envois automatiques des conscrits vers le champ de batailles.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>C\u2019est encore pire qu&rsquo;une impasse, c&rsquo;est une d\u00e9faite annonc\u00e9e car les moyens militaires dont Vladimir Poutine dispose le condamnent \u00e0 perdre. <\/p><cite>Fran\u00e7ois Heisbourg<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Quant aux pr\u00e9visions, il semble assez logique que les Ukrainiens pourront repousser, dans le courant de l\u2019\u00e9t\u00e9, les troupes russes qui se trouvent \u00e0 l&rsquo;int\u00e9rieur des fronti\u00e8res internationales de l&rsquo;Ukraine. Cela \u00e9tant conditionn\u00e9 au fait qu\u2019il n\u2019y ait pas d\u2019ici l\u00e0 un accord de paix ou au moins un armistice. L&rsquo;artillerie lourde occidentale commence \u00e0 arriver, une partie des canons am\u00e9ricains sont d\u00e9j\u00e0 l\u00e0, les canons fran\u00e7ais ne vont pas tarder, les Britanniques ont commenc\u00e9 leur livraison&#8230; Il faut aussi prendre en compte que les Russes ne peuvent pas non plus remplacer leur mat\u00e9riel facilement. Aujourd&rsquo;hui, l&rsquo;industrie de d\u00e9fense du pays n&rsquo;a plus qu&rsquo;une seule cha\u00eene de production de tanks en activit\u00e9. Les Ukrainiens, eux, re\u00e7oivent des tanks T-72 de Pologne et d&rsquo;autres pays de l&rsquo;ex-Pacte de Varsovie. La Russie ne peut pas en faire autant. On se trouve dans un monde compl\u00e8tement renvers\u00e9. L&rsquo;Ukraine ne manque pas d&rsquo;hommes car tous ceux en \u00e2ge d\u2019\u00eatre mobilis\u00e9s le sont. Gr\u00e2ce \u00e0 cela, Kiev d\u00e9ploie aujourd&rsquo;hui plus de soldats que ne peut le faire la Russie. La question des conditions dans lesquelles la Russie va accepter ou non de cesser les combats, et sur quelle base se fera la n\u00e9gociation, va tr\u00e8s vite se poser. Il y a trois jours, le pr\u00e9sident Zelensky a d\u00e9j\u00e0 pos\u00e9 un premier jalon en disant que le pr\u00e9alable \u00e0 toute n\u00e9gociation \u00e9tait la reconnaissance des positions occup\u00e9es juste avant le 24 f\u00e9vrier. En quelque sorte, le pr\u00e9sident Zelensky n&rsquo;a pas dit qu&rsquo;il allait forc\u00e9ment vouloir reconqu\u00e9rir militairement les pr\u00e9tendues r\u00e9publiques populaires de Lougansk et de Donetsk. Voil\u00e0 donc o\u00f9 nous en sommes pour l\u2019instant dans cette \u00e9trange guerre. \u00c9trange car aucun expert que je connaisse, y compris moi-m\u00eame, n&rsquo;avait pens\u00e9 qu&rsquo;au bout de trois ou quatre mois, pouvait se poser la question des conditions dans lesquelles les Russes devraient quitter le territoire ukrainien.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Aucun expert que je connaisse, y compris moi-m\u00eame, n&rsquo;avait pens\u00e9 qu&rsquo;au bout de trois ou quatre mois, pouvait se poser la question des conditions dans lesquelles les Russes devraient quitter le territoire ukrainien. <\/p><cite>Fran\u00e7ois Heisbourg<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c0 la suite des sanctions europ\u00e9ennes et am\u00e9ricaines, le Kremlin cherche \u00e0 imposer les siennes. Le pouvoir russe se retrouve-t-il pi\u00e9g\u00e9 par les sanctions&#160;?<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>George Pagoulatos<\/strong><\/h4>\n\n\n\n<p>Il est clair que Poutine a sous-estim\u00e9 la r\u00e9action de l&rsquo;Occident et la volont\u00e9 de l&rsquo;Europe. Les d\u00e9g\u00e2ts des sanctions \u00e0 l\u2019heure actuelle sont aussi importants pour nous mais bien moins que ceux que subissent l&rsquo;\u00e9conomie russe. Il va y avoir de lourdes cons\u00e9quences \u00e0 Moscou, qui conna\u00eetra probablement une r\u00e9cession \u00e0 deux chiffres et un choc colossal engendr\u00e9 par la r\u00e9duction de son volume d&rsquo;exportation et de commerce ext\u00e9rieur. Il faut tout de m\u00eame souligner qu\u2019il sera difficile pour l&rsquo;Europe de r\u00e9soudre la situation \u00e9nerg\u00e9tique, surtout pour ce qui rel\u00e8ve du gaz naturel, et que cela aura un co\u00fbt important. Vladimir Poutine utilise le gaz naturel comme arme contre l&rsquo;Europe.&nbsp;<\/p>\n\n\n\n<p>Je suis assez partag\u00e9 sur ce qu\u2019\u00e0 dit Fran\u00e7ois Heisbourg. Apr\u00e8s des mois d&rsquo;op\u00e9rations militaires, il me semble tr\u00e8s difficile que Poutine accepte de revenir aux positions russes ant\u00e9rieures au 24 f\u00e9vrier. Ce serait une r\u00e9elle humiliation compte tenu des pertes colossales de l&rsquo;arm\u00e9e russe et de toutes les sanctions \u00e9conomiques qu\u2019a subi le pays. J&rsquo;ai le sentiment que cela rend Vladimir Poutine encore plus dangereux. Je crains l\u2019utilisation des armes de destruction massive ou d\u2019autres armes dans un effort russe d\u00e9sesp\u00e9r\u00e9 si la r\u00e9sistance des Ukrainiens reste aussi forte. Il semble en effet que les Ukrainiens r\u00e9sistent encore tr\u00e8s bien et que l\u2019Occident \u00e9quipe l&rsquo;Ukraine comme elle le doit. Il y a donc un risque d&rsquo;escalade qui pourrait \u00eatre une tentative ultime de Poutine de sortir de cette impasse qui se dessine en d\u00e9faite annonc\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il existe un risque d&rsquo;escalade qui pourrait \u00eatre une tentative ultime de Poutine de sortir de cette impasse qui se dessine en d\u00e9faite annonc\u00e9e.<\/p><cite>George Pagoulatos<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Est-ce que cette escalade pourrait concerner la Moldavie et la Transnistrie&#160;?<\/strong><\/h3>\n\n\n\n<p>Oui cela pourrait concerner aussi les pays voisins. La Russie pourrait arriver jusqu&rsquo;\u00e0 Odessa. Ce serait une r\u00e9elle ambition pour Poutine de les relier aux provinces de Donetsk et Lougansk car pour l\u2019instant il n\u2019a pas r\u00e9ussi jusqu\u2019\u00e0 Odessa. Je crains qu&rsquo;il n\u2019essaye de dire \u00e0 la fin de cette histoire qu\u2019il fallait annexer les provinces orientales pour les relier \u00e0 la Mer d&rsquo;Azov. Je pense que tout cela pour Poutine, en prenant en compte la relation solipsiste qu&rsquo;il a avec l&rsquo;histoire, sera un grand \u00e9chec.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dans une intervention r\u00e9cente vous avez utilis\u00e9 une phrase de Roosevelt&#160;: \u00ab&#160;Parlez doucement, et tenez un gros b\u00e2ton, vous irez loin&#160;\u00bb. Pourquoi avez-vous utilis\u00e9 cette phrase&#160;? Pensez-vous que la rh\u00e9torique de certains leaders soit trop dure&#160;? Est-ce qu&rsquo;ils pourraient communiquer autrement&#160;?<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Fran\u00e7ois Heisbourg<\/strong><\/h4>\n\n\n\n<p>Au moment o\u00f9 j&rsquo;ai employ\u00e9 cette phrase de Th\u00e9odore Roosevelt, je faisais r\u00e9f\u00e9rence \u00e0 la fa\u00e7on dont se comportait le pr\u00e9sident Biden au bout de trois ou quatre semaines de guerre. Il passait une large partie de son temps \u00e0 expliquer ce qu&rsquo;il ne ferait pas. Autrement dit, il ne \u00ab&#160;tenait pas un gros b\u00e2ton&#160;\u00bb en disant qu&rsquo;il n&rsquo;y aurait jamais un soldat am\u00e9ricain en Ukraine, qu\u2019il n&rsquo;y aurait jamais d&rsquo;armes offensives en Ukraine. Ces choses sont peut-\u00eatre raisonnables strat\u00e9giquement mais le probl\u00e8me est que dans un processus de contr\u00f4le de l&rsquo;escalade il ne faut pas donner quelque chose pour rien. Il est important de ne pas toujours tout d\u00e9voiler. Avec les propos de Joe Biden, le pr\u00e9sident Poutine \u00e9tait donc averti par les Am\u00e9ricains eux-m\u00eames qu&rsquo;il n&rsquo;y avait aucun risque qu&rsquo;il puisse y avoir un d\u00e9bordement de ce conflit. Quelques semaines plus tard, les Am\u00e9ricains ont vu que les Russes risquaient d&#8217;employer des armes chimiques. Et que pouvaient-ils donc faire&#160;? Ils ont dit qu&rsquo;ils n&rsquo;enverraient jamais des soldats am\u00e9ricain, qu\u2019il n&rsquo;y aura jamais de no fly zone et qu\u2019il n&rsquo;y aurait jamais de livraison d&rsquo;armes offensives. Donc si Poutine utilise une arme nucl\u00e9aire nous ne ferons rien&#160;? C&rsquo;est bien cela le signal&#160;? En m\u00eame temps le pr\u00e9sident Biden expliquait dans son discours de Varsovie que Poutine est un boucher, ce qui est d&rsquo;ailleurs parfaitement exact, et qu&rsquo;il faudrait que ce r\u00e9gime disparaisse. Pour reprendre la citation que j\u2019ai utilis\u00e9, Biden parlait donc fort et utilisait un petit b\u00e2ton. Mais cela a chang\u00e9. Les armes dites offensives sont en cours de livraisons, d&rsquo;autres sont livr\u00e9es et cela continuera.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/27\/conversation-avec-serguei-gouriev\/\">\u00c0 propos des sanctions<\/a>, il me semble que ces derni\u00e8res ont trois effets. Le premier est celui que l&rsquo;ont fait peser sur la Russie. J&rsquo;ajouterais que les Russes se sont mis dans une mauvaise passe avec l&rsquo;histoire du paiement en rouble car on ne c\u00e9dera pas l\u00e0-dessus et que s\u2019ils ne coupent pas le gaz, Poutine aura perdu la face. Mais il peut aussi mettre \u00e0 ex\u00e9cution sa menace&#160;: pas de rouble, pas de gaz. Ce serait une formule politiquement \u00e9patante pour l&rsquo;Union europ\u00e9enne et pour l&rsquo;Allemagne en particulier car, pour toutes les raisons que nous connaissons, il est difficile pour le pays de d\u00e9cider de son propre chef de cesser d&rsquo;importer du gaz de Russie. Toutefois, si ce sont les Russes qui coupent le gaz comme pour la Pologne et pour la Bulgarie, et prennent donc la d\u00e9cision que Berlin ne se r\u00e9sout \u00e0 prendre, alors l&rsquo;Allemagne n&rsquo;a plus de probl\u00e8me politique car il aura \u00e9t\u00e9 r\u00e9solu par Moscou. Le deuxi\u00e8me effet des sanctions est l\u2019effet ricochet qui fait qu&rsquo;elles p\u00e8sent contre nous. Et enfin, il y a les sanctions qui ne disent pas leur noms et qui seront les plus graves de toutes&#160;: le blocus des c\u00f4tes ukrainiennes par la Russie qui emp\u00eache l&rsquo;exportation de la nourriture, mati\u00e8re premi\u00e8re beaucoup plus vitale que le gaz et le p\u00e9trole. Pour le moment, le probl\u00e8me est encore g\u00e9rable et les exportations se font ailleurs comme par exemple en Roumanie <em>via<\/em> le port de Constanza. Bien entendu, nous ne sommes pas encore en p\u00e9riode de r\u00e9colte. Comment vont se nourrir l&rsquo;\u00c9gypte et l&rsquo;Afrique occidentale si les Russes maintiennent le blocus&#160;? Ce sont des sanctions non pas contre les Occidentaux mais contre des gens qui se sont abstenus ou qui ont vot\u00e9 pour la Russie \u00e0 l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations-Unies. Voil\u00e0 une fa\u00e7on dont la Russie va conforter et renforcer encore son image dans le monde. En Afrique et au Moyen-Orient, on va s\u2019apercevoir assez rapidement que c&rsquo;est la Russie qui ne veut pas lever le blocus. Les Ukrainiens rendent de leur c\u00f4t\u00e9 ce blocus de plus en plus difficile en coulant environ un navire russe par semaine. C\u2019est un effet des sanctions auquel l&rsquo;Union europ\u00e9enne devrait r\u00e9fl\u00e9chir. Nous devons prendre l&rsquo;initiative avec l&rsquo;Union Africaine, avec la Ligue Arabe, avec le programme alimentaire mondial pour pr\u00e9empter le drame absolu que sera non pas l&rsquo;augmentation des prix, qu&rsquo;il y a d\u00e9j\u00e0 dans le domaine des c\u00e9r\u00e9ales, mais la raret\u00e9 physique de ces biens.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Comment vont se nourrir l&rsquo;Egypte et l&rsquo;Afrique occidentale si les Russes maintiennent le blocus&#160;? Ce sont des sanctions non pas contre les Occidentaux mais contre des gens qui se sont abstenus ou qui ont vot\u00e9 pour la Russie \u00e0 l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations-Unies. <\/p><cite>Fran\u00e7ois Heisbourg<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Je voudrais dire un mot sur le danger de ce conflit et le risque d\u2019escalade. Que va faire Vladimir Poutine, que nous avons suppos\u00e9ment rendu malheureux en ne lui permettant pas de gagner sa guerre comme pr\u00e9vu&#160;? Conna\u00eetrons-nous une escalade horizontale ou verticale&#160;? L\u2019escalade horizontale serait un \u00e9largissement du conflit \u00e0 la Moldavie, Transnistrie ou d\u2019autres r\u00e9gions. Le pr\u00e9sident russe n&rsquo;en a pas les moyens. Je ne sais pas \u00e0 quoi ont correspondu les explosions qui ont eu lieu en Transnistrie. Je pense que c&rsquo;\u00e9tait pr\u00e9vu dans le plan du mois de janvier et f\u00e9vrier et qu&rsquo;il n&rsquo;ont pas mis le plan \u00e0 jour car d\u00e9stabiliser un endroit qu&rsquo;on ne peut pas atteindre peut r\u00e9pondre au principe de plaisir mais pas \u00e0 celui de r\u00e9alit\u00e9. La m\u00eame chose risque de se passer dans les Balkans et j&rsquo;ai davantage de craintes pour cette r\u00e9gion. La R\u00e9publique serbe de Bosnie peut tr\u00e8s bien d\u00e9clarer son ind\u00e9pendance, faire s\u00e9cession et demander l&rsquo;aide du grand fr\u00e8re russe. La Serbie peut \u00e9ventuellement donner un coup de main dans ce sens. Honn\u00eatement cela ne permettra pas \u00e0 Poutine de gagner sa guerre en Ukraine. Une gestion de cette crise serait pour nous tr\u00e8s d\u00e9sagr\u00e9able et d\u00e9sordonn\u00e9e, avec certainement un spectacle d&rsquo;improvisation mais nous pourrions la g\u00e9rer. Nous savons tr\u00e8s bien \u00e0 la fin que ce n&rsquo;est pas la Russie qui va gagner ce conflit.&nbsp;<\/p>\n\n\n\n<p>Pour l\u2019escalade verticale, le principal risque est celui du nucl\u00e9aire. Les Russes ont brandi la menace nucl\u00e9aire \u00e0 la fin du mois de f\u00e9vrier et de fa\u00e7on tr\u00e8s visible. D&rsquo;abord \u00e0 travers les d\u00e9clarations de Poutine \u00e0 l&rsquo;\u00e9poque sur les pays qui allaient conna\u00eetre les cons\u00e9quences les plus graves de leur histoire pour le citer. La France a pris tout cela tr\u00e8s au s\u00e9rieux et pour la premi\u00e8re fois depuis la Guerre Froide nous avions trois de nos quatre sous-marin nucl\u00e9aire lanceur d&rsquo;engins submerg\u00e9s. Chacun de ceux-ci est \u00e9quip\u00e9 de seize fus\u00e9es, elle-m\u00eame \u00e9quip\u00e9es chacune de six charges nucl\u00e9aires m\u00e9gatonniques. Largement donc de quoi r\u00e9pondre au Sarmat et autres engins du pr\u00e9sident Russe. A la m\u00eame \u00e9poque, les Russes ont fait manoeuvrer un certains nombres de leurs sous-marins en Atlantique-Nord et de mani\u00e8re bien d\u00e9tectable pour que l&rsquo;on sache qu&rsquo;il y avait une menace. Entre temps fran\u00e7ais, britanniques et am\u00e9ricains ont fait comprendre \u00e0 Poutine qu&rsquo;il n&rsquo;\u00e9tait pas le seul \u00e0 avoir des armes nucl\u00e9aires et que pour faire peser la menace nucl\u00e9aire il ne suffisait pas de diffuser des sujets sur la t\u00e9l\u00e9vision d&rsquo;Etat Russe pour faire peur aux enfants. Je pense notamment \u00e0 ces \u00e9missions o\u00f9 l\u2019on voyait le nombre de secondes n\u00e9cessaires pour qu\u2019une t\u00eate nucl\u00e9aire russes d\u00e9truise Berlin, Paris ou Londres. Les \u00e9valuations de la CIA, plut\u00f4t bonnes jusqu&rsquo;\u00e0 pr\u00e9sent dans la guerre, indiquent n&rsquo;avoir constat\u00e9 aucun pr\u00e9paratif nucl\u00e9aire russe r\u00e9cemment. La dissuasion est quelque chose d&rsquo;enti\u00e8rement mutuel et le pr\u00e9sident Poutine, je crois, s&rsquo;en est rendu compte.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>J\u2019ai lu une critique du <em>New York Times<\/em> sur la rh\u00e9torique agressive de Joe Biden. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/10\/discours-de-macron\/\">Emmanuel Macron a dit \u00e0 Strasbourg aujourd&rsquo;hui<\/a> que nous ne voulions pas humilier le pr\u00e9sident russe mais que la guerre cesse. L&rsquo;heure est venue de rouvrir la voie de communication, le dialogue au niveau diplomatique et de donner une chance \u00e0 la paix par la voie diplomatique car il y a eu une exacerbation des tons qui \u00e9tait une r\u00e9ponse \u00e0 ce r\u00e9visionnisme.&nbsp;<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>George Pagoulatos<\/strong><\/h4>\n\n\n\n<p>Je suis partisan de ce que vous venez de dire pour ce qui est de la phrase de Roosevelt. L&rsquo;Occident ne doit pas r\u00e9pondre par une escalade de sa rh\u00e9torique mais par une escalade de la d\u00e9termination des mesures prises pour pouvoir mettre fin \u00e0 la guerre. Nous ne sommes pas dans la phase du retour au dialogue mais dans celle du coup de frein puisque la guerre se poursuit tous les jours avec des images terribles de massacres de civiles et d&rsquo;actes qui constituent des crimes de guerre conform\u00e9ment au droit international de l&rsquo;apr\u00e8s guerre. L&rsquo;heure n&rsquo;est pas \u00e0 l&rsquo;engagement mais toutefois je suis convaincu, qu&rsquo;on doit laisser une porte ouverte et une voie de communication m\u00eame en temps de guerre. Il faut toujours garder ouverte une voie de communication pour que la diplomatie puisse poursuivre et continuer son travail. Cela devrait fonctionner parall\u00e8lement et le fait de voir que la France et l&rsquo;Allemagne ont essay\u00e9 de garder cela est particuli\u00e8rement positif. Bien s\u00fbr, on est dans la critique parfois injuste car \u00e0 l&rsquo;heure o\u00f9 les deux pays essaient de tenir les voies de communication ouverte, notamment monsieur Macron, ils font partie de l&rsquo;Alliance de l&rsquo;Occident qui impose des mesures tr\u00e8s strictes.&nbsp;<\/p>\n\n\n\n<p>Je crois aussi que la rh\u00e9torique doit \u00eatre un peu moins offensive pour ne pas donner l&rsquo;occasion \u00e0 Poutine de r\u00e9it\u00e9rer sa narration sur la reproduction de l&rsquo;histoire selon laquelle le pays est encercl\u00e9 par les forces de l&rsquo;OTAN et l&rsquo;Ukraine qui sont pr\u00eates \u00e0 envahir. L\u2019histoire, donc, selon laquelle la Russie doit d\u00e9fendre sa survie face aux vis\u00e9es expanssioniste de l&rsquo;Occident dont l&rsquo;outil est \u00ab&#160;le gouvernement nazi de l&rsquo;Ukraine&#160;\u00bb. L&rsquo;Europe et l&rsquo;Occident ne doivent pas lui donner l&rsquo;occasion de citer les Europ\u00e9ens pour sa propre rh\u00e9torique. Je suis d&rsquo;accord avec Fran\u00e7ois Heisbourg que la r\u00e9f\u00e9rence de Biden faite au changement de leadership en Russie \u00e9tait une erreur. La Maison Blanche a d\u00e9menti par la suite en disant que cela concernait le peuple russe et personne d&rsquo;autres. Aujourd&rsquo;hui, la strat\u00e9gie mise en \u0153uvre par l&rsquo;Occident est de retourner cette situation avec d\u00e9termination montrant que plus l&rsquo;agressivit\u00e9 culmine, plus notre d\u00e9termination augmentera pour ce qui est des sanctions et des mesures de pressions impos\u00e9es. Il ne faut pas donner le pr\u00e9texte \u00e0 Poutine de se pr\u00e9senter comme quelqu&rsquo;un qui est sur l&rsquo;autod\u00e9fense et comme un peuple sous le joug de l&rsquo;imp\u00e9rialisme d&rsquo;Occident. Il pourrait utiliser des d\u00e9clarations occidentales afin de justifier des actions qui pourraient se retourner directement contre l&rsquo;OTAN et non pas seulement contre l&rsquo;Ukraine.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;Europe ne doit pas perdre son \u00e2me mais m\u00fbrir et faire le pas en avant de l&rsquo;adaptation \u00e0 une r\u00e9alit\u00e9 qui \u00e9nonce la fin de l&rsquo;\u00e8re de l&rsquo;apr\u00e8s-guerre.<\/p><cite>George Pagoulatos&nbsp;<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La puissance de l&rsquo;Europe a toujours \u00e9t\u00e9 le <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/11\/conversation-avec-joseph-nye\/\"><em>soft power<\/em><\/a> et sa possibilit\u00e9 d&rsquo;utiliser intelligemment sa puissance \u00e9conomique <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/14\/penser-lunion-europeenne-dans-la-mondialisation-l-effet-bruxelles\/\">et r\u00e9glementaire<\/a> pour pouvoir promouvoir ses int\u00e9r\u00eats et ses valeurs dans le monde. Elle ne l&rsquo;a pas fait aussi efficacement qu&rsquo;elle aurait d\u00fb le faire \u00e9tant donn\u00e9 son poids dans l\u2019\u00e9conomie mondiale. Elle n&rsquo;a pas exploit\u00e9 les possibilit\u00e9s strat\u00e9giques de sa puissance quatre fois sup\u00e9rieure \u00e0 la Russie mais qui est en reste sur l&rsquo;efficacit\u00e9 en termes de d\u00e9fense. C&rsquo;est pourquoi face \u00e0 des menaces syst\u00e9miques, la force de dissuasion de l&rsquo;Europe s&rsquo;int\u00e8gre dans le cadre de l&rsquo;OTAN. L&rsquo;Europe doit parler la langue du <em>hard power<\/em> et doit \u00e9videmment le faire sans abandonner le <em>soft power<\/em>, sans abandonner le mod\u00e8le qu&rsquo;elle a construit car se serait abandonner ses valeurs et cela conduirait \u00e0 \u00eatre un mauvais mod\u00e8le d&rsquo;\u00c9tat militariste. L&rsquo;Europe ne doit pas perdre son \u00e2me mais m\u00fbrir et faire le pas en avant de l&rsquo;adaptation \u00e0 une r\u00e9alit\u00e9 qui \u00e9nonce la fin de l&rsquo;\u00e8re de l&rsquo;apr\u00e8s-guerre. Dans le cadre du <em>soft power<\/em>, elle doit utiliser les outils de hardpower l\u00e0 o\u00f9 cela est n\u00e9cessaire. C&rsquo;est ce qu&rsquo;elle fait aujourd&rsquo;hui et c&rsquo;est le sens de cette autonomie strat\u00e9gique de l&rsquo;Europe. Elle doit avoir les moyens et les outils n\u00e9cessaires \u00e0 la protection de ses int\u00e9r\u00eats et ses valeurs en sachant que ceux-ci ne sont pas identiques \u00e0 ceux de notre grand partenaire am\u00e9ricain. En effet, les \u00c9tats-Unis traversent une p\u00e9riode de crise et nous ne savons pas si le pr\u00e9sident pro-europ\u00e9en et pro-atlantiste Biden, qui parle la m\u00eame langue que nous les Europ\u00e9ens, sera r\u00e9\u00e9lu.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fran\u00e7ois Heisbourg <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/leurope-entre-paix-et-guerre\/\">lorsque vous avez \u00e9crit votre livre <em>Le retour de la guerre<\/em><\/a> qui a \u00e9t\u00e9 publi\u00e9 avant l&rsquo;invasion russe en Ukraine. Quels \u00e9taient les signes que vous d\u00e9celiez&#160;?<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Fran\u00e7ois Heisbourg<\/strong><\/h4>\n\n\n\n<p>Tout d\u2019abord, le fait est qu&rsquo;en Europe il y a une puissance qui est la Russie. Le pays poss\u00e8de un agenda r\u00e9visionniste, et qui depuis le discours de Poutine \u00e0 Munich en 2007 veut redessiner l&rsquo;ordre de s\u00e9curit\u00e9 h\u00e9rit\u00e9 de la fin de la Guerre froide. Ce fut d\u2019ailleurs chose faite au mois de d\u00e9cembre dernier avec les projets des trait\u00e9s qui ont \u00e9t\u00e9 remis aux Am\u00e9ricains. Ces projets n\u2019ont pas \u00e9t\u00e9 remis aux Europ\u00e9ens car, selon les Russes, le sort de l&rsquo;Europe doit \u00eatre r\u00e9gl\u00e9 entre Moscou et Washington. Comme le disait un des responsables russes \u00e0 l&rsquo;\u00e9poque des projets de trait\u00e9s&#160;: \u00ab&#160;Nous parlons avec le patron&#160;\u00bb.&nbsp;C&rsquo;est probablement une des raisons pour laquelle les Europ\u00e9ens ont \u00e9t\u00e9 unanimes pour rejeter ces projets de trait\u00e9s. Nous savions aussi, au moins depuis 2014 et la premi\u00e8re guerre et partition d&rsquo;Ukraine, que la Russie n&rsquo;allait pas s&rsquo;accommoder de l&rsquo;existence d&rsquo;une entit\u00e9 politique ukrainienne susceptible d&rsquo;affirmer sa souverainet\u00e9.<\/p>\n\n\n\n<p>Qu&rsquo;est ce qui avait chang\u00e9&#160;? La capacit\u00e9 russe de d\u00e9velopper ses ambitions sur le plan militaire. Personnellement, je ne pensais pas que la guerre \u00e9claterait \u00e0 l&rsquo;\u00e9chelle du 24 f\u00e9vrier et aussi vite que ce jour-l\u00e0. Je pensais que les russes allaient prendre davantage de temps afin d\u2019am\u00e9liorer leur capacit\u00e9 militaire. Le pr\u00e9sident Poutine a fait une tr\u00e8s grosse erreur de calcul en frappant aussi vite et avec des buts de guerre aussi ambitieux que ceux qu&rsquo;il s&rsquo;est donn\u00e9 le 24 f\u00e9vrier. Il y aussi le fait que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/11\/jespere-que-linterregne-ne-conduira-pas-a-la-disparition-de-lordre-post-1945-une-conversation-avec-wolfgang-ischinger\/\">l&rsquo;ordre international b\u00e2ti d\u00e8s 1945 est en train de s&rsquo;effilocher et de dispara\u00eetre<\/a>. Je parlais il y a quelques instants des probl\u00e8mes alimentaires et du blocus. En d&rsquo;autres temps, il y aurait d\u00e9j\u00e0, au moment o\u00f9 nous parlons, une op\u00e9ration de convoyage des c\u00e9r\u00e9ales ukrainiennes pour nourrir le monde. Maintenant cela ne se fait plus. Il y a un parall\u00e8le avec la pand\u00e9mie durant laquelle l&rsquo;Organisation mondiale de la sant\u00e9 n&rsquo;a pas pu faire son travail car elle \u00e9tait sous discipline chinoise d&rsquo;un c\u00f4t\u00e9 et face \u00e0 l&rsquo;hostilit\u00e9 de l&rsquo;Am\u00e9rique de Trump de l&rsquo;autre. Nous sommes dans un monde o\u00f9 le r\u00e8glement des diff\u00e9rends par la guerre est devenu beaucoup plus actuel que ce n&rsquo;\u00e9tait le cas au cours du quart de si\u00e8cle pass\u00e9. Ceux-ci affectent de nouveau l&rsquo;Europe, et plus seulement le pays o\u00f9 la guerre n&rsquo;a jamais vraiment perdu son emprise, notamment au Moyen-Orient. C&rsquo;est tout cela qui m&rsquo;a amen\u00e9 \u00e0 \u00e9crire ce livre. Au moment de sa parution, beaucoup m&rsquo;ont reproch\u00e9 mon pessimisme. Lorsque la guerre a \u00e9clat\u00e9 le 24 f\u00e9vrier, je n&rsquo;ai plus entendu ce genre de critique.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L\u2019ordre international b\u00e2ti d\u00e8s 1945 est en train de s&rsquo;effilocher et de dispara\u00eetre. <\/p><cite>Fran\u00e7ois Heisbourg <\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Je voudrais vous demander, George Pagoulatos, si une adh\u00e9sion \u00e9ventuelle \u00e0 l&rsquo;OTAN de la Finlande et la Su\u00e8de pourrait r\u00e9gler des probl\u00e8mes ou en cr\u00e9er d&rsquo;autres&#160;?<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>George Pagoulatos<\/strong><\/h4>\n\n\n\n<p>Cela pourrait r\u00e9soudre le probl\u00e8me de s\u00e9curit\u00e9 de ces pays qui se sentent expos\u00e9s face \u00e0 la force r\u00e9visionniste et agressive qu&rsquo;est la Russie. Ce sont deux pays qui ne participent non seulement \u00e0 l&rsquo;Union europ\u00e9enne mais aussi au fonctionnement de l&rsquo;OTAN. Ils ont abandonn\u00e9 leur neutralit\u00e9 qui \u00e9tait un r\u00e9sidu de la Guerre Froide. Nous ne sommes plus dans l&rsquo;\u00e9poque de l&rsquo;apr\u00e8s Guerre froide o\u00f9 l&rsquo;Europe estimait que la Russie \u00e9tait un partenaire avec lequel nous pouvions d\u00e9velopper des relations commerciales. Nous vivons une \u00e9poque o\u00f9 l&rsquo;interd\u00e9pendance et la mondialisation peuvent se transformer en armes. Poutine a d\u2019ailleurs utilis\u00e9 toute cette interd\u00e9pendance. En ce sens, nous entrons donc dans une nouvelle \u00e8re qui ne signifie pas que l&rsquo;Europe doit abandonner mais les Etats-membres doivent s&rsquo;adapter \u00e0 un environnement de plus en plus agressif et hostile.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En ce sens, nous entrons donc dans une nouvelle \u00e8re qui ne signifie pas que l&rsquo;Europe doit abandonner mais que les \u00c9tats-membres doivent s&rsquo;adapter \u00e0 un environnement de plus en plus agressif et hostile. <\/p><cite>George Pagoulatos<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L\u2019enjeu de l\u2019adh\u00e9sion est presque clos car tous les Etats-membres se sont d\u00e9clar\u00e9s favorables. Il y a cependant la question de la protection de l&rsquo;OTAN pendant la p\u00e9riode de transition jusqu&rsquo;au moment o\u00f9 ils adh\u00e8ront officiellement. Au pr\u00e9c\u00e9dent conseil, les deux pays avaient envoy\u00e9 une lettre dans laquelle ils demandaient que la clause de la protection de d\u00e9fense soit plus expresse. C&rsquo;est important parce qu\u2019il y a les efforts d\u2019Emmanuel Macron et d&rsquo;autres, notamment la Gr\u00e8ce, de proc\u00e9der \u00e0 une unification en mati\u00e8re de d\u00e9fense. Nous voyons aujourd\u2019hui que des pays qui traditionnellement \u00e9taient neutres prennent en consid\u00e9ration le r\u00f4le tr\u00e8s important de l&rsquo;OTAN. Voil\u00e0 donc l&rsquo;architecture \u00e9mergente de s\u00e9curit\u00e9 en Europe pour ce qui est de la fa\u00e7on dont les pays europ\u00e9ens qui sont, ou vont devenir, membres de l&rsquo;OTAN, relient l&rsquo;Union europ\u00e9en \u00e0 l\u2019organisation atlantique comme deux piliers compl\u00e9mentaires dans un cadre plus \u00e9largi de s\u00e9curit\u00e9 Euro-atlantique.&nbsp;<\/p>\n\n\n\n<p>Il est bien clair que face \u00e0 des menaces syst\u00e9miques comme la Russie, nous avons besoin d&rsquo;une alliance Euro-atlantique et mais aussi d&rsquo;autonomie et cela signifie le d\u00e9veloppement d&rsquo;un pilier europ\u00e9en dans le cadre de l&rsquo;alliance Euro-atlantique. L\u00e0 o\u00f9 elle peut avancer avec l&rsquo;OTAN, l&rsquo;Europe doit le faire, et l\u00e0 o\u00f9 l&rsquo;OTAN n&rsquo;a pas d&rsquo;int\u00e9r\u00eats strat\u00e9giques, comme au Sahel ou en Afrique du Nord, l&rsquo;Europe devra \u00eatre en mesure d&rsquo;avoir les capacit\u00e9s de d\u00e9fendre ses int\u00e9r\u00eats et ses valeurs. C&rsquo;est cette r\u00e9alit\u00e9 qui \u00e9merge aujourd\u2019hui. L&rsquo;un des points positifs de cette conjoncture est la convergence au sein de l&rsquo;Union europ\u00e9enne. Il y a une sensibilisation et une prise de conscience, \u00e0 savoir que l&rsquo;Europe a besoin de ce pilier de d\u00e9fense mais aussi de prendre au s\u00e9rieux l&rsquo;unification dans ce m\u00eame domaine. Cela n&rsquo;est pas contradictoire \u00e0 son engagement envers l&rsquo;alliance Euro-atlantique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dans son discours de Strasbourg, Emmanuel Macron a parl\u00e9 d&rsquo;une industrie de d\u00e9fense europ\u00e9enne commune, d&rsquo;une nouvelle communaut\u00e9 europ\u00e9enne et d&rsquo;une nouvelle conf\u00e9d\u00e9ration europ\u00e9enne. Est-ce que les conditions sont m\u00fbres pour que cela se produise et que cela se fasse rapidement&#160;? On dit toujours que l&rsquo;Europe avance lentement mais ces deux derni\u00e8res ann\u00e9es, avec la pand\u00e9mie et la guerre, elle a montr\u00e9 qu&rsquo;elle pouvait acc\u00e9l\u00e9rer.<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Fran\u00e7ois Heisbourg<\/strong><\/h4>\n\n\n\n<p>Effectivement, l\u2019Union europ\u00e9enne a d\u00e9couvert qu&rsquo;elle savait agir de fa\u00e7on op\u00e9rationnelle. Ce n\u2019est pas simplement un organisme capable d&rsquo;\u00e9noncer des normes et g\u00e9rer des programmes comme la Politique Agricole Commune, ce qui reste bien entendu tr\u00e8s important et qu&rsquo;elle fait tr\u00e8s bien. Elle a appris, et de fa\u00e7on inopin\u00e9e, \u00e0 acqu\u00e9rir des comp\u00e9tences qu&rsquo;elle n&rsquo;avait pas et \u00e0 les mettre au service d&rsquo;une strat\u00e9gie. C&rsquo;est ce qui s&rsquo;est pass\u00e9 avec la strat\u00e9gie vaccinale. Ce fut une grande premi\u00e8re et les choses ont \u00e9t\u00e9 difficiles. Toutefois, cela a \u00e9t\u00e9 une grande r\u00e9ussite lorsqu&rsquo;on se compare \u00e0 la situation actuelle en Chine, r\u00e9gime qui nous regardait de haut la premi\u00e8re ann\u00e9e de pand\u00e9mie, ou aux Am\u00e9ricains qui ne juraient que par l&rsquo;action unilat\u00e9rale et qui ont r\u00e9ussi une tr\u00e8s belle politique vaccinale mais dont le bilan final de la mortalit\u00e9 est bien pire qu\u2019en Europe. Lorsque la guerre a \u00e9clat\u00e9 en Ukraine, l\u2019Union europ\u00e9enne a aussi montr\u00e9 qu&rsquo;elle savait aussi agir rapidement et c&rsquo;\u00e9tait une bonne surprise.<\/p>\n\n\n\n<p>Il y a l&rsquo;id\u00e9e que dans la crise actuelle de la guerre d&rsquo;Ukraine, l&rsquo;OTAN et l&rsquo;Union Europ\u00e9enne ont travaill\u00e9 de fa\u00e7on non seulement compl\u00e9mentaire mais \u00e0 certains \u00e9gards int\u00e9gr\u00e9s en \u00e9laborant des strat\u00e9gies communes. Il y a celle des sanctions par exemple, avec le leadership de l&rsquo;Union ou celle de fourniture des armes avec des d\u00e9cisions majoritairement individuelles mais un r\u00f4le majeur de l&rsquo;OTAN et de l&rsquo;Union europ\u00e9enne. Il y a donc un univers cr\u00e9\u00e9 par la guerre dans lequel les querelles th\u00e9ologiques n&rsquo;ont pas eu de place. On a pas oppos\u00e9 une vision d&rsquo;autonomie strat\u00e9gique \u00e0 son contraire. Cela aussi est quelque chose que nous avons appris. Ou allons nous comme \u00e7a&#160;? D&rsquo;abord, l&rsquo;Union europ\u00e9enne r\u00e9ussit mieux dans les domaines qui correspondent \u00e0 ses savoir-faire que d&rsquo;en d&rsquo;autres. C\u2019est de l\u00e0 que vient l&rsquo;insistance sur l&rsquo;industrie de d\u00e9fense. On a mis en place le fonds europ\u00e9en de d\u00e9fense et beaucoup d&rsquo;initiatives ont \u00e9t\u00e9 prises au cours des deux derni\u00e8res ann\u00e9es. Elles n&rsquo;ont pas assez de moyens financiers mais la question de la volont\u00e9 politique ne se pose gu\u00e8re. Je crois que nous sommes raisonnablement pr\u00eats m\u00eame s\u2019il risque d\u2019y avoir des obstacles. Rationaliser l&rsquo;industrie de d\u00e9fense veut dire fermer beaucoup d&rsquo;usines dans beaucoup de pays. Mais il faut le faire.<\/p>\n\n\n\n<p>Nous avons aussi eu beaucoup de chance avec le pr\u00e9sident am\u00e9ricain et son \u00e9quipe raisonnablement comp\u00e9tente. Nous avons surtout eu la chance d\u2019avoir une Am\u00e9rique qui n&rsquo;a pas tent\u00e9 de faire un arbitrage entre l&rsquo;Ukraine et Ta\u00efwan, ce qui est strat\u00e9giquement tr\u00e8s important. Nous aurions pu avoir, comme on peut le lire dans plusieurs articles de la litt\u00e9rature acad\u00e9mique am\u00e9ricaine, des responsables am\u00e9ricains disant qu&rsquo;ils \u00e9taient d\u00e9j\u00e0 assez occup\u00e9s en Indo-pacifique pour s&rsquo;occuper de l&rsquo;Ukraine et laissant ainsi les Europ\u00e9ens se d\u00e9brouiller. Ce ne fut pas le cas et bien au contraire les Am\u00e9ricains ont tr\u00e8s bien compris que s&rsquo;ils ne se montraient pas capables, \u00e0 la face du monde et de la Chine, de g\u00e9rer le d\u00e9fi russe en Ukraine, cela \u00f4terait toute cr\u00e9dibilit\u00e9 au positionnement des Etats-Unis face \u00e0 la Chine dans la r\u00e9gion Indo-Pacifique. C&rsquo;est une tr\u00e8s bonne nouvelle mais \u00e7a ne durera pas \u00e9ternellement. Pas simplement comme George Pagoulatos l&rsquo;a \u00e9voqu\u00e9 avec l&rsquo;inconnu du prochain pr\u00e9sident am\u00e9ricain car effectivement si Trump revient les choses pourraient mal se passer. Je dirais plut\u00f4t que les moyens am\u00e9ricains ne sont pas ind\u00e9finiment extensibles et qu&rsquo;ils devront \u00e9ventuellement faire des arbitrages. Pour cela les Europ\u00e9ens doivent pouvoir compter davantage sur eux-m\u00eame et pas seulement parce que l&rsquo;OTAN ne s\u2019int\u00e9resse pas au Sahel mais surtout parce que les Am\u00e9ricains ne seront pas toujours l\u00e0 pour faire le gros du travail par rapport \u00e0 la Russie.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les Am\u00e9ricains ont tr\u00e8s bien compris que s&rsquo;ils ne se montraient pas capables, \u00e0 la face du monde et de la Chine, de g\u00e9rer le d\u00e9fi russe en Ukraine, cela \u00f4terait toute cr\u00e9dibilit\u00e9 au positionnement des Etats-Unis face \u00e0 la Chine dans la r\u00e9gion Indo-Pacifique. <\/p><cite>Fran\u00e7ois heisbourg<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>J&rsquo;aimerais un commentaire de votre part sur la Conf\u00e9rence sur l&rsquo;avenir de l&rsquo;Europe. C&rsquo;\u00e9tait un processus participatif. Quarante-neuf propositions dont quelques-unes tr\u00e8s int\u00e9ressantes. Mais ce qu\u2019ont r\u00e9clam\u00e9 les citoyens europ\u00e9ens, c&rsquo;est la r\u00e9vision des trait\u00e9s et qu&rsquo;on arr\u00eate avec cette question de l&rsquo;unanimit\u00e9. Vous pensez que c&rsquo;est possible&#160;? Est-ce qu&rsquo;on peut avancer&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>George Pagoulatos<\/strong><\/h4>\n\n\n\n<p>J&rsquo;ai particip\u00e9 \u00e0 la pl\u00e9ni\u00e8re en tant que repr\u00e9sentant national. Ce que les citoyens veulent c&rsquo;est une Europe plus forte mais nous ne pouvons y arriver sans des changements qui imposent la r\u00e9vision des trait\u00e9s. Il faut donner \u00e0 l\u2019Europe plus de flexibilit\u00e9 et la possibilit\u00e9 de d\u00e9cider sur les questions cruciales qui sont au c\u0153ur de la souverainet\u00e9 europ\u00e9enne comme la politique ext\u00e9rieure, celle de d\u00e9fense et de s\u00e9curit\u00e9 commune, la&nbsp;politique budg\u00e9taire,&nbsp;le financements des domaines o\u00f9 elle a d\u00e9cid\u00e9 d&rsquo;investir mais n&rsquo;a pas les outils pour le faire\u2026&nbsp;<\/p>\n\n\n\n<p>La Conf\u00e9rence a \u00e9t\u00e9 un exercice important de participation des citoyens, huit-cents de toute l&rsquo;Europe, au processus d\u00e9mocratique. Certaines propositions peuvent \u00eatre mises en \u0153uvre imm\u00e9diatement sans r\u00e9vision des trait\u00e9s. C&rsquo;est un exercice de compl\u00e9mentarit\u00e9 du pilier des organes repr\u00e9sentatif avec le pilier de repr\u00e9sentation, sans aller pour autant vers une d\u00e9mocratie directe. Cela serait une erreur en plus d\u2019\u00eatre infaisable. La d\u00e9mocratie en Europe doit \u00eatre repr\u00e9sentative, seule celle-ci peut filtrer et trouver ses solutions aux probl\u00e8mes complexes auxquels nous sommes confront\u00e9s. L&rsquo;Europe est une d\u00e9mocratie multidimensionnelle qui n\u00e9cessite d\u2019importants consensus \u00e0 plusieurs niveaux de pouvoir et de puissance entre plusieurs Etats-membres. A eux-seuls ces consensus ne sont pas suffisants pour pouvoir \u00eatre \u00e0 la hauteur des d\u00e9fis lorsqu&rsquo;ils tendent \u00e0 \u00eatre dirig\u00e9s vers les secteurs mentionn\u00e9s plus haut. Il faut cr\u00e9er une nouvelle voix de participation, de consultation, de compl\u00e9mentarit\u00e9 des institutions et non pas de remplacement. La composition de ce pilier transmet un message aux citoyens&#160;: leur voix est \u00e9tendue.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il faut cr\u00e9er une nouvelle voix de participation, de consultation, de compl\u00e9mentarit\u00e9 des institutions et non pas de remplacement. <\/p><cite>george Pagoulatos<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Je ne suis pas optimiste non pas sur le fait que la majorit\u00e9 sp\u00e9ciale n\u00e9cessaire puisse d\u00e9cider de nouveaux trait\u00e9s mais davantage sur le fait qu&rsquo;il n&rsquo;y aura pas l&rsquo;unanimit\u00e9 de la part des vingt-sept pour pouvoir parvenir \u00e0 un nouveau trait\u00e9. Et si on y arrive, ce nouveau trait\u00e9 ne produira pas les changements escompt\u00e9s. J&rsquo;ai le sentiment que nous ne sommes pas pr\u00eats \u00e0 aller vers les propositions d&rsquo;une Europe concentrique, exprim\u00e9es par Emmanuel Macron.Si je pouvais sch\u00e9matiser, on aurait un cercle ext\u00e9rieur avec les pays candidats, le pr\u00e9sident Macron a parl\u00e9 de \u00ab&#160;Communaut\u00e9 politique&#160;\u00bb, d&rsquo;autres ont employ\u00e9 le terme de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/09\/leurope-des-sept-unions\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00ab&#160;Conf\u00e9d\u00e9ration politique<\/a>\u00ab&#160;. L&rsquo;autre cercle imm\u00e9diat est un cercle de gouvernance \u00e9conomique avec le march\u00e9 unique et l&rsquo;Euro. Puis un noyau encore plus \u00e9troit avec l&rsquo;unification politique de l&rsquo;Europe, c&rsquo;est-\u00e0-dire les pays qui veulent faire le grand saut vers l&rsquo;unification europ\u00e9enne. Ce serait le sens de ce projet. La d\u00e9fense doit \u00eatre un noyau \u00e9troit d&rsquo;unification tout comme une gouvernance \u00e9conomique commune.&nbsp;<\/p>\n\n\n\n<p>On parle aussi du scrutin europ\u00e9en avec une repr\u00e9sentation \u00e9gale de 28 eurod\u00e9put\u00e9s par pays. Je pense que cela serait possible car je doute s\u00e9rieusement que les citoyens europ\u00e9ens se r\u00e9veillent et se couchent avec l&rsquo;id\u00e9e d&rsquo;un scrutin europ\u00e9en. Il est important de comprendre que nous sommes membres d&rsquo;un Etat pan-europ\u00e9en. L&rsquo;Europe doit asseoir l&rsquo;image de son efficacit\u00e9 afin de montrer qu&rsquo;elle fait son travail pour pouvoir recouvrer la dynamique des forces anti-europ\u00e9ennes. Poutine veut d\u00e9truire l&rsquo;Europe par le biais de la mont\u00e9e des forces extr\u00eames et de la d\u00e9sinformation. C\u2019est un expert en la mati\u00e8re. Il faut une Europe plus efficace et coh\u00e9rente qui veille sur ceux qui sont \u00e0 la tra\u00eene. Une Europe qui a une voix et qui peut d\u00e9fendre les int\u00e9r\u00eats de tous.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;Europe doit asseoir l&rsquo;image de son efficacit\u00e9 afin de montrer qu&rsquo;elle fait son travail pour pouvoir recouvrer la dynamique des forces anti-europ\u00e9ennes. <\/p><cite>George Pagoulatos<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pour clore la discussion, j\u2019aimerais avoir votre opinion sur l\u2019importance des \u00e9lections l\u00e9gislatives en France. Seront-elles importantes pour que le pr\u00e9sident fran\u00e7ais puisse mettre en \u0153uvre sa vision pour l&rsquo;Europe&#160;? En collaboration bien s\u00fbr avec le chancelier allemand.&nbsp;<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Fran\u00e7ois Heisbourg<\/strong><\/h4>\n\n\n\n<p>Ma r\u00e9ponse va surprendre mais elles ne sont pas tr\u00e8s importantes. Cela pour plusieurs raisons. La premi\u00e8re est que tout tend \u00e0 indiquer que les oppositions auront un nombre de si\u00e8ges tr\u00e8s limit\u00e9 malgr\u00e9 les tentatives d&rsquo;union \u00e0 l&rsquo;extr\u00eame gauche qui pourrait donner davantage de si\u00e8ges que lors des derni\u00e8res \u00e9lections. Il n&rsquo;y a donc pas une grande incertitude sur l&rsquo;issue. La deuxi\u00e8me raison est qu&rsquo;en mati\u00e8re de s\u00e9curit\u00e9 et de d\u00e9fense le pr\u00e9sident fran\u00e7ais et les institutions donnent un poids \u00e0 l&rsquo;ex\u00e9cutif qui est extr\u00eamement important. Qu&rsquo;on aime cette situation ou qu&rsquo;on la d\u00e9plore, cette situation existe et est tr\u00e8s forte. Ce n&rsquo;est pas de l&rsquo;Assembl\u00e9e Nationale que viendra l&rsquo;initiative ou le blocage par rapport \u00e0 ces sujets-l\u00e0. Sur l&rsquo;Europe de fa\u00e7on plus g\u00e9n\u00e9rale, le fonctionnement constitutionnel donne, bien entendu, un r\u00f4le important aux l\u00e9gislateurs. Par rapport \u00e0 ces \u00e9lections, je n&rsquo;aurai pas les moments d&rsquo;inqui\u00e9tude que j&rsquo;ai pu avoir au moment des \u00e9lections pr\u00e9sidentielles qui viennent de se d\u00e9rouler.<\/p>\n\n\n\n<p>Juste un mot sur les propositions du pr\u00e9sident Macron. Si l&rsquo;id\u00e9e de la Communaut\u00e9 politique est de fournir une \u00e9tape \u00e0 mi-parcours de l&rsquo;adh\u00e9sion des nouveaux membres, et notamment de l&rsquo;Ukraine, c&rsquo;est une tr\u00e8s bonne chose. Je suis relativement confiant sur la possibilit\u00e9 pour l&rsquo;Union europ\u00e9enne de s&rsquo;accorder sur cette id\u00e9e de communaut\u00e9 politique. Je ne suis pas du tout s\u00fbr qu&rsquo;il faille modifier les trait\u00e9s pour \u00e7a. Tout comme George Pagoulatos, je ne suis personnellement pas un grand partisan du changement des trait\u00e9s pour le plaisir de changer les trait\u00e9s. Ce serait une situation dans laquelle nous passerions notre temps \u00e0 changer les trait\u00e9s, ce qui est d\u00e9j\u00e0 difficile, et qui montrerait l\u2019inefficacit\u00e9 de l&rsquo;Union europ\u00e9enne par rapport aux probl\u00e8mes qui int\u00e9ressent vraiment les citoyens. La plupart des gens ne s&rsquo;int\u00e9ressent pas \u00e0 l&rsquo;Europe mais \u00e0 la capacit\u00e9 que l&rsquo;Europe peut avoir \u00e0 r\u00e9soudre leurs probl\u00e8mes. Je ne suis pas certain que suspendre la capacit\u00e9 \u00e0 r\u00e9soudre les probl\u00e8mes pendant dix ans, parce qu&rsquo;on court derri\u00e8re des changements de trait\u00e9s, soit un tr\u00e8s bon plan. A moins que l&rsquo;on puisse d\u00e9montrer qu&rsquo;un tel changement de trait\u00e9 r\u00e9ponde de fa\u00e7on directe et \u00e9vidente \u00e0 un int\u00e9r\u00eat partag\u00e9 par l&rsquo;ensemble des citoyens europ\u00e9ens. Je ne pense pas que ce sera par ce biais l\u00e0 que nous aurons les avanc\u00e9es les plus importantes par rapport au travail qu&rsquo;\u00e0 fait la Conf\u00e9rence et au travail qui pourrait \u00eatre fait sur les propositions du pr\u00e9sident Macron.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&#160;L\u2019ordre international b\u00e2ti d\u00e8s 1945 est en train de s&rsquo;effilocher et de dispara\u00eetre&#160;\u00bb. Dans ce Grand Dialogue organis\u00e9 \u00e0 l\u2019occasion de la Nuit des Id\u00e9es, George Pagoulatos et Fran\u00e7ois Heisbourg \u00e9changent sur le tournant g\u00e9opolitique du retour de la guerre en Europe et sur l&rsquo;avenir proche de l&rsquo;Union.  <\/p>\n","protected":false},"author":1950,"featured_media":143478,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":32,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[3103],"tags":[],"staff":[3167],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-143096","post","type-post","status-publish","format-standard","hentry","category-grands-dialogues","staff-alexia-koulouri","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":143478,"excerpt":"\u00ab L\u2019ordre international b\u00e2ti d\u00e8s 1945 est en train de s'effilocher et de dispara\u00eetre \u00bb. Dans ce Grand Dialogue organis\u00e9 \u00e0 l\u2019occasion de la Nuit des Id\u00e9es, George Pagoulatos et Fran\u00e7ois Heisbourg \u00e9changent sur le tournant g\u00e9opolitique du retour de la guerre en Europe et sur l'avenir proche de l'Union.  ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l&#039;avenir de l&#039;Europe : un moment crucial pour l&#039;Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg\ufffc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l&#039;avenir de l&#039;Europe : un moment crucial pour l&#039;Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00ab&#160;L\u2019ordre international b\u00e2ti d\u00e8s 1945 est en train de s&#039;effilocher et de dispara\u00eetre&#160;\u00bb. Dans ce Grand Dialogue organis\u00e9 \u00e0 l\u2019occasion de la Nuit des Id\u00e9es, George Pagoulatos et Fran\u00e7ois Heisbourg \u00e9changent sur le tournant g\u00e9opolitique du retour de la guerre en Europe et sur l&#039;avenir proche de l&#039;Union.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg\ufffc\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-21T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-18T17:37:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/gc-pagoul-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valentinf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/gc-pagoul-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"valentinf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"32 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/\",\"name\":\"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l'avenir de l'Europe : un moment crucial pour l'Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg\",\"datePublished\":\"2022-05-21T08:00:00+00:00\",\"dateModified\":\"2022-09-18T17:37:20+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/c85110a0970a7ae08146cad05cfa9e4d\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Exhibition Idee di Pietra. Giuseppe Penone in Caracalla, curated by Francesco Stocchi, at the Baths of Caracalla until 30 October 2022. The four bronze and aluminum trees are located in the ancient natatio.\/\/AGFEDITORIAL_SIPA.2174\/2206070848\/Credit:Mimmo Frassineti\/AGF\/SIPA\/2206070854\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l&rsquo;avenir de l&rsquo;Europe&#160;: un moment crucial pour l&rsquo;Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/c85110a0970a7ae08146cad05cfa9e4d\",\"name\":\"valentinf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/74bcf6a86adb79e16547d6a9350e1703?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/74bcf6a86adb79e16547d6a9350e1703?s=96&d=mm&r=g\",\"caption\":\"valentinf\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l'avenir de l'Europe : un moment crucial pour l'Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg\ufffc\/","og_locale":"fr_FR","og_type":"article","og_title":"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l'avenir de l'Europe : un moment crucial pour l'Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg | Le Grand Continent","og_description":"\u00ab&#160;L\u2019ordre international b\u00e2ti d\u00e8s 1945 est en train de s'effilocher et de dispara\u00eetre&#160;\u00bb. Dans ce Grand Dialogue organis\u00e9 \u00e0 l\u2019occasion de la Nuit des Id\u00e9es, George Pagoulatos et Fran\u00e7ois Heisbourg \u00e9changent sur le tournant g\u00e9opolitique du retour de la guerre en Europe et sur l'avenir proche de l'Union.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg\ufffc\/","og_site_name":"Le Grand Continent","article_published_time":"2022-05-21T08:00:00+00:00","article_modified_time":"2022-09-18T17:37:20+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/gc-pagoul-scaled.jpg","type":"image\/jpeg"}],"author":"valentinf","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/gc-pagoul-scaled.jpg","twitter_misc":{"\u00c9crit par":"valentinf","Dur\u00e9e de lecture estim\u00e9e":"32 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/","name":"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l'avenir de l'Europe : un moment crucial pour l'Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg","datePublished":"2022-05-21T08:00:00+00:00","dateModified":"2022-09-18T17:37:20+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/c85110a0970a7ae08146cad05cfa9e4d"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg","width":2560,"height":1707,"caption":"Exhibition Idee di Pietra. Giuseppe Penone in Caracalla, curated by Francesco Stocchi, at the Baths of Caracalla until 30 October 2022. The four bronze and aluminum trees are located in the ancient natatio.\/\/AGFEDITORIAL_SIPA.2174\/2206070848\/Credit:Mimmo Frassineti\/AGF\/SIPA\/2206070854"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/05\/21\/de-la-guerre-en-ukraine-a-la-conference-sur-lavenir-de-leurope-un-moment-crucial-pour-lunion-une-conversation-avec-george-pagoulatos-et-francois-heisbourg%ef%bf%bc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"De la guerre en Ukraine \u00e0 la Conf\u00e9rence sur l&rsquo;avenir de l&rsquo;Europe&#160;: un moment crucial pour l&rsquo;Union, une conversation avec George Pagoulatos et Fran\u00e7ois Heisbourg"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/c85110a0970a7ae08146cad05cfa9e4d","name":"valentinf","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/74bcf6a86adb79e16547d6a9350e1703?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74bcf6a86adb79e16547d6a9350e1703?s=96&d=mm&r=g","caption":"valentinf"}}]}},"lgc_categories":[{"id":3103,"name":"Grands Dialogues","slug":"grands-dialogues"}],"lgc_author":{"id":3167,"name":"Alexia Koulouri","slug":"alexia-koulouri","description":"Journaliste \u00e0 la cha\u00eene t\u00e9l\u00e9vis\u00e9e du Parlement Grec, responsable du d\u00e9partement d\u2019information et de promotion de l\u2019\u0153uvre parlementaire.\r\n","first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/SIPA_01076162_000007-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/143096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1950"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=143096"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/143096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/143478"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=143096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=143096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=143096"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=143096"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=143096"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=143096"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=143096"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=143096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}