{"id":138270,"date":"2022-04-28T17:30:37","date_gmt":"2022-04-28T15:30:37","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=138270"},"modified":"2022-05-11T10:20:09","modified_gmt":"2022-05-11T08:20:09","slug":"une-politique-economique-de-guerre","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/","title":{"rendered":"Une politique \u00e9conomique de guerre"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Personne ne peut pr\u00e9dire avec certitude <a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/la-guerre-en-ukraine-au-jour-le-jour\/\">comment \u00e9voluera la guerre en Ukraine<\/a> et quelles seront <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/15\/un-nouveau-brouillard-de-guerre\/\">ses cons\u00e9quences g\u00e9opolitiques<\/a> sur les prochains mois, <em>a fortiori<\/em> sur les prochaines ann\u00e9es. N\u00e9anmoins, les responsables politiques doivent d\u00e8s aujourd\u2019hui penser les cons\u00e9quences de la guerre et les r\u00e9ponses \u00e0 y apporter, en sachant qu&rsquo;elles devront \u00eatre adapt\u00e9es au fil des \u00e9volutions de la situation. Par ailleurs, ils doivent r\u00e9fl\u00e9chir \u00e0 la coh\u00e9rence de leurs actions conjointes, qu&rsquo;il s&rsquo;agisse des <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/15\/sanctions-contre-la-russie-ou-en-sommes-nous\/\">sanctions contre la Russie<\/a> ou des subventions et transferts \u00e0 leurs propres citoyens. C&rsquo;est ce que nous essayons de faire dans ce texte, en nous concentrant sur les probl\u00e8mes macro\u00e9conomiques les plus pertinents pour l&rsquo;Europe.&nbsp;<\/p>\n\n\n\n<p>Nous commen\u00e7ons par envisager les implications potentielles de la guerre et passons en revue les diff\u00e9rents canaux par lesquels elle affecte les perspectives macro\u00e9conomiques. Il en ressort essentiellement que, m\u00eame si les canaux de la demande et de la finance entrent tous en jeu, et m\u00eame si les implications budg\u00e9taires directes de la guerre sont importantes &#8211; en raison de l&rsquo;augmentation des d\u00e9penses de d\u00e9fense et du co\u00fbt de la protection des r\u00e9fugi\u00e9s -, l\u2019impact le plus fort de la guerre en Europe se fera probablement sentir sur les prix de l&rsquo;\u00e9nergie et, dans une moindre mesure, sur les prix des denr\u00e9es alimentaires.&nbsp;<\/p>\n\n\n\n<p>Nous analysons ensuite les d\u00e9terminants du prix de l&rsquo;\u00e9nergie. Tout d\u00e9pend \u00e0 la fois des d\u00e9cisions de la Russie, quand bien m\u00eame il n\u2019y aurait pas de sanctions, et de l&rsquo;effet de potentielles sanctions sur ses d\u00e9cisions. \u00c0 cet \u00e9gard, il faut distinguer p\u00e9trole et charbon d&rsquo;une part, et le gaz d&rsquo;autre part. Concernant le p\u00e9trole et le charbon, la Russie doit plus ou moins aligner son prix sur celui du march\u00e9 mondial et concurrentiel, sur lequel elle est confront\u00e9e \u00e0 une demande tr\u00e8s \u00e9lastique. Pour le gaz, dont le commerce repose sur des infrastructures sp\u00e9cifiques faisant de l&rsquo;Union europ\u00e9enne un march\u00e9 \u00e0 part, la demande est plut\u00f4t in\u00e9lastique et la Russie peut donc \u00eatre consid\u00e9r\u00e9e comme en quasi-monopole.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L\u2019impact le plus fort de la guerre en Europe se fera probablement sentir sur les prix de l&rsquo;\u00e9nergie et, dans une moindre mesure, sur les prix des denr\u00e9es alimentaires.&nbsp;<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cela a des implications tr\u00e8s diff\u00e9rentes, tant pour le comportement probable de la Russie en l&rsquo;absence de sanctions, que pour les effets de sanctions telles que des tarifs douaniers sur les exportations russes. De fait, compte tenu de contraintes techniques, un embargo total sur le gaz n&rsquo;est pas envisageable. En revanche, la mise en place de tarifs douaniers est r\u00e9alisable&#160;: ils seraient efficaces et devraient \u00eatre envisag\u00e9s, malgr\u00e9 leurs effets probables sur les prix \u00e0 la consommation du gaz.<\/p>\n\n\n\n<p>Nous faisons ici l\u2019hypoth\u00e8se que les prix de l&rsquo;\u00e9nergie sont susceptibles d\u2019augmenter par rapport \u00e0 leurs niveaux d&rsquo;avant-guerre, bien qu&rsquo;il y ait une incertitude consid\u00e9rable quant \u00e0 l&rsquo;ampleur de cette augmentation. Jusqu&rsquo;\u00e0 pr\u00e9sent, les deux parties ont prot\u00e9g\u00e9 le commerce du p\u00e9trole et du gaz des retomb\u00e9es du conflit&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-1-138270' title='Au moment o\u00f9 ce papier est mis en page, la Russie annonce l\u2019arr\u00eat des exportations de gaz vers la Pologne et la Bulgarie.'><sup>1<\/sup><\/a><\/span><\/span>. Les fortes variations sur le march\u00e9 du p\u00e9trole et plus encore sur celui du gaz sont dues \u00e0 l&rsquo;anticipation des coupures russes et des sanctions. Mais cet \u00ab&#160;\u00e9quilibre de la terreur \u00e9nerg\u00e9tique&#160;\u00bb est pr\u00e9caire et ne peut \u00eatre consid\u00e9r\u00e9 comme acquis.&nbsp;<\/p>\n\n\n\n<p>Nous examinons ensuite les implications de la guerre pour les politiques budg\u00e9taire et mon\u00e9taire de l&rsquo;Union.&nbsp;<\/p>\n\n\n\n<p>Si on laisse de c\u00f4t\u00e9 les diverses sources de d\u00e9penses, de la d\u00e9fense aux r\u00e9fugi\u00e9s en passant par la n\u00e9cessit\u00e9 d&rsquo;adapter l&rsquo;infrastructure \u00e9nerg\u00e9tique \u00e0 un nouveau type d\u2019approvisionnement, la question centrale de la politique budg\u00e9taire est de savoir, dans la mesure o\u00f9 les prix des denr\u00e9es alimentaires et de l&rsquo;\u00e9nergie augmentent, si et comment compenser tout ou partie de la perte de revenu r\u00e9el des m\u00e9nages.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les fortes variations sur le march\u00e9 du p\u00e9trole et plus encore sur celui du gaz sont dues \u00e0 l&rsquo;anticipation des coupures russes et des sanctions. Mais cet \u00ab&#160;\u00e9quilibre de la terreur \u00e9nerg\u00e9tique&#160;\u00bb est pr\u00e9caire et ne peut \u00eatre consid\u00e9r\u00e9 comme acquis.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Deux probl\u00e8mes se posent alors. Le premier concerne la meilleure fa\u00e7on de proc\u00e9der&#160;: subventions, transferts ou r\u00e9glementation des prix&nbsp;&#160;? La principale question est de savoir \u00e0 quel point la combinaison de ces mesures et des embargos ou des tarifs douaniers joue sur les effets totaux des sanctions, les prix des imports d\u2019\u00e9nergie et les effets sur l&rsquo;inflation. Le deuxi\u00e8me probl\u00e8me est de savoir si ces mesures, dans le cas o\u00f9 elles seraient mises en place, doivent \u00eatre financ\u00e9es par des taxes ou par de la dette. S&rsquo;il existe un argument politique important en faveur d&rsquo;un imp\u00f4t de guerre exceptionnel, la perte de revenu r\u00e9el due au prix plus \u00e9lev\u00e9 des importations et l&rsquo;incertitude associ\u00e9e \u00e0 la guerre sont susceptibles de mener \u00e0 une situation de faible demande agr\u00e9g\u00e9e et des d\u00e9penses d\u00e9ficitaires seraient donc n\u00e9cessaires pour maintenir ou du moins limiter la baisse de la production. L&rsquo;endettement, m\u00eame s&rsquo;il s&rsquo;en trouve augment\u00e9, restera soutenable.&nbsp;<\/p>\n\n\n\n<p>En ce qui concerne la politique mon\u00e9taire, les bonnes pratiques de circonstance face \u00e0 une augmentation des prix de l&rsquo;\u00e9nergie ou des denr\u00e9es alimentaires \u2013 \u00e0 savoir l&rsquo;accommodation des effets de premier tour et le resserrement pour limiter les effets ult\u00e9rieurs \u2013 doivent \u00eatre r\u00e9examin\u00e9es. D&rsquo;une part, l&rsquo;inflation s\u2019ajouterait \u00e0 une inflation d\u00e9j\u00e0 \u00e9lev\u00e9e, ce qui augmente le risque de d\u00e9sancrer les anticipations. D&rsquo;autre part, malgr\u00e9 le soutien budg\u00e9taire, la demande agr\u00e9g\u00e9e risque d&rsquo;\u00eatre faible et d&rsquo;exercer une pression \u00e0 la baisse sur l&rsquo;inflation. Le premier effet sugg\u00e8re un resserrement de la politique mon\u00e9taire, le second un assouplissement. Pour le moment, les deux s&rsquo;annulent peu ou prou, ce qui laisse penser que la politique mon\u00e9taire pourrait rester un certain temps sur sa trajectoire d\u2019avant-guerre, tout en \u00e9tant vigilante.&nbsp;<\/p>\n\n\n\n<p>Dans le contexte actuel, il existe une interaction importante et inhabituelle entre les politiques budg\u00e9taire et mon\u00e9taire. Plus la politique budg\u00e9taire prot\u00e8ge le revenu r\u00e9el des travailleurs, moins la demande d&rsquo;augmentation des salaires risque d&rsquo;\u00eatre \u00e9lev\u00e9e lors des prochains tours. Plus une baisse de l&rsquo;inflation devient cr\u00e9dible, moins la Banque centrale europ\u00e9enne (BCE) sera amen\u00e9e \u00e0 resserrer la politique mon\u00e9taire afin d\u2019obtenir cette inflation plus faible. Ainsi, des d\u00e9ficits plus importants peuvent conduire \u00e0 un co\u00fbt de production plus faible pour lutter contre l&rsquo;inflation.&nbsp;<\/p>\n\n\n\n<p>Enfin, il s\u2019agit de savoir si ce r\u00f4le mod\u00e9rateur du soutien budg\u00e9taire peut \u00eatre explicitement pris en compte dans les n\u00e9gociations salariales. Au cours de la pand\u00e9mie, le ch\u00f4mage partiel et le soutien aux entreprises financ\u00e9s par le gouvernement ont socialis\u00e9 les pertes de revenus et se sont av\u00e9r\u00e9s un moyen tr\u00e8s efficace et rentable de minimiser les perturbations \u00e9conomiques et sociales. Il serait potentiellement utile d&rsquo;instaurer un dialogue tripartite entre les gouvernements, les employeurs et les employ\u00e9s et, id\u00e9alement, de proposer une mod\u00e9ration des salaires et des prix en \u00e9change d&rsquo;un soutien budg\u00e9taire important.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Dans le contexte actuel, il existe une interaction importante et inhabituelle entre les politiques budg\u00e9taire et mon\u00e9taire.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Notre propos est organis\u00e9 comme suit. Nous commen\u00e7ons par examiner les canaux par lesquels la guerre affectera l&rsquo;\u00e9conomie de l&rsquo;Union europ\u00e9enne. Nous passons en revue dans la section 2 les facteurs susceptibles de d\u00e9terminer l&rsquo;\u00e9volution des prix de l&rsquo;\u00e9nergie. Dans la section 3, nous examinons les implications pour la production et l&rsquo;inflation dans l&rsquo;Union europ\u00e9enne, et dans la section 4, les implications pour la politique budg\u00e9taire et mon\u00e9taire de l&rsquo;Union. Nous tirons une s\u00e9rie de conclusions dans la section 5.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>1 \u2014&nbsp;L\u2019impact \u00e9conomique de la guerre<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La nature des chocs<\/strong><\/h3>\n\n\n\n<p>Notre hypoth\u00e8se de travail est que le conflit, qui a commenc\u00e9 avec l&rsquo;invasion de la Russie le 24 f\u00e9vrier, ne sera pas r\u00e9solu \u00e0 court terme. \u00c0 l\u2019horizon des douze prochains mois environ, nous faisons l\u2019hypoth\u00e8se d\u2019une impasse, d\u2019une occupation russe avec une r\u00e9sistance ukrainienne, ou d\u2019un cessez-le-feu suivi de n\u00e9gociations acrimonieuses. Nous estimons qu&rsquo;il faudra plus de temps pour parvenir \u00e0 un r\u00e8glement permanent.&nbsp;<\/p>\n\n\n\n<p>Dans ce contexte, nous faisons une s\u00e9rie d\u2019hypoth\u00e8ses&#160;:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La violation des principes des Nations Unies, qui avaient \u00e9t\u00e9 observ\u00e9s pendant trois quarts de si\u00e8cle sur le continent europ\u00e9en, continuera \u00e0 obscurcir l&rsquo;horizon et \u00e0 affecter la confiance au-del\u00e0 des effets directs de la guerre.<\/li><li>La plupart des r\u00e9fugi\u00e9s ukrainiens retourneront dans leur ville natale, mais seulement progressivement, car l\u2019ampleur des destructions emp\u00eachera leur retour.&nbsp;<\/li><li>La crise entra\u00eenera <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/\">une augmentation durable des d\u00e9penses de d\u00e9fense<\/a> europ\u00e9ennes.&nbsp;<\/li><li>Apr\u00e8s la pand\u00e9mie, ce nouveau choc am\u00e8nera les entreprises mondiales \u00e0 reconsid\u00e9rer leur d\u00e9pendance \u00e0 l&rsquo;\u00e9gard des cha\u00eenes d&rsquo;approvisionnement \u00e9tendues et des syst\u00e8mes de livraison \u00ab&#160;juste \u00e0 temps&#160;\u00bb.&nbsp;<\/li><li>La guerre affectera les r\u00e9coltes et les exportations agricoles ukrainiennes (et potentiellement russes), r\u00e9duisant l&rsquo;offre mondiale et augmentant les prix alimentaires mondiaux.&nbsp;<\/li><li>Au-del\u00e0 de sa r\u00e9action imm\u00e9diate \u00e0 la guerre, l&rsquo;Union europ\u00e9enne s&rsquo;engagera dans une r\u00e9duction acc\u00e9l\u00e9r\u00e9e et, \u00e0 terme, dans l&rsquo;\u00e9limination de sa d\u00e9pendance \u00e0 l&rsquo;\u00e9gard de l&rsquo;\u00e9nergie russe gr\u00e2ce \u00e0 des sources d&rsquo;approvisionnement alternatives et <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/18\/la-naissance-de-lecologie-de-guerre\/\">\u00e0 une transition plus rapide vers les \u00e9nergies renouvelables<\/a>.<\/li><li>Les sanctions vont probablement perdurer ou s&rsquo;intensifier, entra\u00eenant une diminution substantielle des exportations russes de p\u00e9trole et de gaz, qu&rsquo;elle soit d\u00e9clench\u00e9e par une d\u00e9cision de l&rsquo;Union ou par de nouvelles d\u00e9cisions du gouvernement russe de restreindre ces exportations. Il s&rsquo;agit d&rsquo;un probl\u00e8me majeur, tant sur le plan g\u00e9opolitique qu&rsquo;\u00e9conomique, que nous \u00e9tudions en d\u00e9tail dans la section suivante.<\/li><\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/Woxho\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Dans cette pi\u00e8ce de doctrine, nous nous concentrons sur les implications \u00e0 court terme. Nous avons l&rsquo;intention de revenir sur les implications \u00e0 long terme dans une autre note. La plupart des hypoth\u00e8ses sont triviales. D\u2019autres m\u00e9ritent un examen plus approfondi.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Exports, investissements directs \u00e0 l\u2019\u00e9tranger et liens financiers<\/strong><\/h3>\n\n\n\n<p>Les exportations vers la Russie ont consid\u00e9rablement diminu\u00e9 et risquent de baisser encore davantage en raison de la combinaison des sanctions de l&rsquo;Union europ\u00e9enne, des restrictions impos\u00e9es par le gouvernement russe et des probl\u00e8mes de livraison. Des preuves anecdotiques indiquent que, m\u00eame en l&rsquo;absence de restrictions l\u00e9gales, les entreprises europ\u00e9ennes sont d\u00e9j\u00e0 r\u00e9ticentes \u00e0 commercer avec la Russie, craignant des probl\u00e8mes juridiques et de paiement. Selon les statistiques commerciales de l&rsquo;Union, les exportations de biens vers la Russie se sont \u00e9lev\u00e9es \u00e0 89 milliards d&rsquo;euros en 2021&#160;; si elles devaient cesser &#8211; une hypoth\u00e8se maximaliste &#8211; cela entra\u00eenerait, toutes choses \u00e9gales par ailleurs, une diminution de la demande globale de biens de l&rsquo;Union de 0,6&#160;% du PIB de 2019&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-2-138270' title='Le PIB nominal de l\u2019UE \u00e0 27 \u00e9tait de 14 017 milliards d\u2019euros en 2019. Source&amp;#160;: Eurostat.'><sup>2<\/sup><\/a><\/span><\/span>. Une r\u00e9duction de 50&#160;% des exportations de biens vers la Russie amputerait la demande globale de 0,3&#160;% du PIB.&nbsp;<\/p>\n\n\n\n<p>L&rsquo;Union europ\u00e9enne repr\u00e9sente \u00e9galement les trois quarts des investissements directs \u00e9trangers en Russie, pour un total de plus de 300 milliards d&rsquo;euros \u00e0 la fin de 2019&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-3-138270' title='Commission europ\u00e9enne, &lt;a href=&quot;https:\/\/ec.europa.eu\/trade\/policy\/countries-and-regions\/countries\/russia\/#:~:text=In%202019%2C%20the%20EU%20was,estimated%20at%20%E2%82%AC136%20billion&quot;&gt;Russia fact sheet&lt;\/a&gt;.'><sup>3<\/sup><\/a><\/span><\/span>. En supposant que la moiti\u00e9 de la valeur de ces investissements sera perdue, cela repr\u00e9senterait environ 1&#160;% du PIB de l&rsquo;Union et moins de 2&#160;% de son stock d&rsquo;IDE sortants. Bien que significative pour plusieurs banques et entreprises, une telle perte ne peut \u00eatre consid\u00e9r\u00e9e comme pr\u00e9sentant un probl\u00e8me macro\u00e9conomique majeur.&nbsp;<\/p>\n\n\n\n<p>Pendant la crise financi\u00e8re mondiale de 2008, les liens entre les institutions financi\u00e8res ont jou\u00e9 un r\u00f4le majeur, la d\u00e9faillance d&rsquo;une institution entra\u00eenant celle de certains de ses cr\u00e9anciers. Bien que la Russie ait fait des efforts visibles pour respecter ses engagements ext\u00e9rieurs et stabiliser l&rsquo;\u00e9conomie, un d\u00e9faut de paiement du gouvernement russe reste une possibilit\u00e9 r\u00e9elle. Les faits sugg\u00e8rent toutefois qu&rsquo;il est peu probable que cela entra\u00eene des probl\u00e8mes majeurs pour le syst\u00e8me financier de l&rsquo;Union. Des filiales de banques russes ont d\u00e9j\u00e0 \u00e9t\u00e9 ferm\u00e9es et liquid\u00e9es sans mettre le syst\u00e8me financier en danger.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Bien que la Russie ait fait des efforts visibles pour respecter ses engagements ext\u00e9rieurs et stabiliser l&rsquo;\u00e9conomie, un d\u00e9faut de paiement du gouvernement russe reste une possibilit\u00e9 r\u00e9elle.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Abstraction faite de l&rsquo;\u00e9nergie et des denr\u00e9es alimentaires, les importations en provenance de Russie et d&rsquo;Ukraine ont une importance \u00e9conomique mineure. Leur interruption peut toutefois contribuer \u00e0 la perturbation plus g\u00e9n\u00e9rale des cha\u00eenes d&rsquo;approvisionnement due \u00e0 la pand\u00e9mie.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>R\u00e9fugi\u00e9s<\/strong><\/h3>\n\n\n\n<p>Le flux de r\u00e9fugi\u00e9s a atteint 4,6 millions de personnes (sans compter les 7,1 millions de personnes d\u00e9plac\u00e9es \u00e0 l\u2019int\u00e9rieur du territoire ukrainien) au moment de la r\u00e9daction de cette note, dont la plupart sont des femmes et des enfants (HCR 2022)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-4-138270' title='Les noms entre parenth\u00e8ses suivies d&amp;rsquo;une date font r\u00e9f\u00e9rence \u00e0 la bibliographie suivante&amp;#160;:&lt;\/p&gt;\n\n\n\n&lt;ul class=&quot;wp-block-list&quot;&gt;&lt;li&gt;Bachmann, R., D. Baqaee, C. Bayer, M. Kuhn, A. L\u00f6schel, B. Moll, A. Peichl, K. Pittel, and M. Schularick. 2022. &lt;em&gt;What if&amp;#160;? The Economic Effects for Germany of a Stop of Energy Imports from Russia&lt;\/em&gt;. ECONtribute Policy Brief 028, March 7, &lt;a href=&quot;https:\/\/www.econtribute.de\/RePEc\/ajk\/ajkpbs\/ECONtribute_PB_028_2022.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.econtribute.&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.econtribute.de\/RePEc\/ajk\/ajkpbs\/ECONtribute_PB_028_2022.pdf&quot;&gt;de\/RePEc\/ajk\/ajkpbs\/ECONtribute_PB_028_2022.pdf&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Baqaee, D., and B. Moll. 2022. &lt;em&gt;What if Germany is cut off from Russian oil and gas&amp;#160;? &lt;\/em&gt;Markus\u2019 Academy, April 7, &lt;a href=&quot;https:\/\/bcf.princeton.edu\/events\/david-baquee-and-ben-moll-on-what-if-germany-is-cut-off-from-russian-oil-and-gas\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/bcf.princeton.edu\/events\/david-baquee-and-ben-moll-on-&lt;\/a&gt; &lt;a href=&quot;https:\/\/bcf.princeton.edu\/events\/david-baquee-and-ben-moll-on-what-if-germany-is-cut-off-from-russian-oil-and-gas\/&quot;&gt;what-if-germany-is-cut-off-from-russian-oil-and-gas\/&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Blanchard, Olivier, and Jordi Gal\u00ed. 2007. Real wage rigidities and the New Keynesian model. &lt;em&gt;Journal of Money, Credit, and Banking &lt;\/em&gt;39&amp;#160;: 35\u201365.&lt;\/li&gt;&lt;li&gt;Blanchard, Olivier. 2023. &lt;em&gt;Fiscal policy under low interest rates&lt;\/em&gt;. Forthcoming. MIT Press. Pre-publication version available at &lt;a href=&quot;https:\/\/fiscal-policy-under-low-interest-rates.pubpub.org\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/fiscal-policy-under-low-interest-&lt;\/a&gt; &lt;a href=&quot;https:\/\/fiscal-policy-under-low-interest-rates.pubpub.org\/&quot;&gt;rates.pubpub.org\/&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Bown, Chad P. 2022. Russia\u2019s war on Ukraine&amp;#160;: A sanctions timeline. PIIE RealTime Economic Issues Watch, April 14, &lt;a href=&quot;https:\/\/www.piie.com\/blogs\/realtime-economic-issues-watch\/russias-war-ukraine-sanctions-timeline&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.piie.com\/blogs\/realtime-economic-issues-watch\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.piie.com\/blogs\/realtime-economic-issues-watch\/russias-war-ukraine-sanctions-timeline&quot;&gt;russias-war-ukraine-sanctions-timeline&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;BP. 2021. &lt;a href=&quot;https:\/\/www.bp.com\/content\/dam\/bp\/business-sites\/en\/global\/corporate\/pdfs\/energy-economics\/statistical-review\/bp-stats-review-2021-full-report.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Statistical Review of World Energy. London&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Darvas, Zsolt. 2022. Bold European Union action is needed to support Ukrainian refugees. Bruegel blog, April 6, &lt;a href=&quot;https:\/\/www.bruegel.org\/2022\/04\/bold-european-union-action-is-needed-to-support-ukrainian-refugees\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.bruegel.org\/2022\/04\/bold-european-union-action-&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.bruegel.org\/2022\/04\/bold-european-union-action-is-needed-to-support-ukrainian-refugees\/&quot;&gt;is-needed-to-support-ukrainian-refugees\/&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Douenne, Thomas. 2019. Les effets de la fiscalit\u00e9 \u00e9cologique sur le pouvoir d\u2019achat des m\u00e9nages&amp;#160;: Simulation de plusieurs sc\u00e9narios de redistribution. Conseil d\u2019analyse \u00e9conomique Focus 030 (March), &lt;a href=&quot;https:\/\/www.cae-eco.fr\/staticfiles\/pdf\/cae-focus030.pdf&quot;&gt;https:\/\/www.cae-eco.fr\/staticfiles\/pdf\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.cae-eco.fr\/staticfiles\/pdf\/cae-focus030.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;cae-focus030.pdf&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;ECB (European Central Bank). 2010. Energy markets and the euro area economy.&lt;\/li&gt;&lt;li&gt;Occasional paper 113, &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/pub\/pdf\/scpops\/ecbocp113.pdf?4c4cb9ad3dc936175889f2ff40bcabe0&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Task Force of the Monetary Policy Committee of the European&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/pub\/pdf\/scpops\/ecbocp113.pdf?4c4cb9ad3dc936175889f2ff40bcabe0&quot;&gt;System of Central Banks&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;ECB (European Central Bank). 2022a. Macroeconomic projections for the euro area, &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/pub\/projections\/html\/ecb.projections202203_ecbstaff~44f998dfd7.en.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.ecb.europa.eu\/pub\/projections\/html\/ecb.projections202203_&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/pub\/projections\/html\/ecb.projections202203_ecbstaff~44f998dfd7.en.html&quot;&gt;ecbstaff~44f998dfd7.en.html&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;ECB (European Central Bank). 2022b. &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/press\/pr\/date\/2022\/html\/ecb.pr220415~fe6e06f22d.en.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Survey of Professional Forecasters&lt;\/a&gt;, April 15.&lt;\/li&gt;&lt;li&gt;European Commission. 2021. Energy prices&amp;#160;: Commission presents a toolbox of measures to tackle exceptional situation and its impacts, &lt;a href=&quot;https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/PDF\/?uri=CELEX%3A52021DC0660&amp;amp;from=EN&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/eur-lex.europa.eu\/legal-content\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/PDF\/?uri=CELEX%3A52021DC0660&amp;amp;from=EN&quot;&gt;EN\/TXT\/PDF\/?uri=CELEX:52021DC0660&amp;amp;from=EN&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;European Commission. 2022. REPowerEU&amp;#160;: Joint European Action for more affordable, secure and sustainable energy. Communication, March 8, &lt;a href=&quot;https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/en\/ip_22_1511&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/ec.europa.eu\/commission\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/en\/ip_22_1511&quot;&gt;presscorner\/detail\/en\/ip_22_1511&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Eurostat. 2022. Extra-EU trade in agricultural goods, &lt;a href=&quot;https:\/\/ec.europa.eu\/eurostat\/statistics-explained\/index.php?title=Extra-EU_trade_in_agricultural_goods&quot;&gt;https:\/\/ec.europa.eu\/eurostat\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/ec.europa.eu\/eurostat\/statistics-explained\/index.php?title=Extra-EU_trade_in_agricultural_goods&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;statistics-explained\/index.php?title=Extra-EU_trade_in_agricultural_goods&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;FAO (UN Food and Agriculture Organization). 2022. The importance of Ukraine and the Russian Federation for global agricultural markets and the risks associated with the current conflict (March 16). Rome. &lt;a href=&quot;https:\/\/nam02.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.fao.org%2F3%2Fcb9013en%2Fcb9013en.pdf&amp;amp;data=04%7C01%7CJSchott%40PIIE.COM%7Ce445f7adafb84341ef9308da08142bc7%7C55339d36654f44c1a1df1ed0983fadcd%7C1%7C0%7C637831180009689758%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000&amp;amp;sdata=w1VXaR2vxWLr9R7m6LyBYw9fwtP0u608wAOhYUGmUSM%3D&amp;amp;reserved=0&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.fao.org\/3\/cb9013en\/cb9013en.pdf&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;German institutes for economic research. 2022. Gemeinschafts-Diagnose 1\/2022 \u201cVon der Pandemie zur Energiekrise\u2014Wirtschaft und Politik im Dauerstress,\u201d &lt;a href=&quot;https:\/\/www.ifw-kiel.de\/fileadmin\/Dateiverwaltung\/IfW-Publications\/-ifw\/Gemeinschaftsdiagnose\/Langfassungen\/gd_2022_1.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.ifw-kiel.de\/fileadmin\/Dateiverwaltung\/IfW-Publications\/-ifw\/Gemeinschaftsdiagnose\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.ifw-kiel.de\/fileadmin\/Dateiverwaltung\/IfW-Publications\/-ifw\/Gemeinschaftsdiagnose\/Langfassungen\/gd_2022_1.pdf&quot;&gt;Langfassungen\/gd_2022_1.pdf&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Gouvernement fran\u00e7ais. 2022. Plan de r\u00e9silience \u00e9conomique et sociale, March 16, &lt;a href=&quot;https:\/\/www.gouvernement.fr\/sites\/default\/files\/document\/document\/2022\/03\/dossier_de_presse_-_plan_de_resilience_economique_et_sociale_-_16.03.2022.pdf?v=1647592494&quot;&gt;https:\/\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.gouvernement.fr\/sites\/default\/files\/document\/document\/2022\/03\/dossier_de_presse_-_plan_de_resilience_economique_et_sociale_-_16.03.2022.pdf?v=1647592494&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;www.gouvernement.fr\/sites\/default\/files\/document\/document\/2022\/03\/dossier_de_&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.gouvernement.fr\/sites\/default\/files\/document\/document\/2022\/03\/dossier_de_presse_-_plan_de_resilience_economique_et_sociale_-_16.03.2022.pdf?v=1647592494&quot;&gt;presse_-_plan_de_resilience_economique_et_sociale_-_16.03.2022.pdf?v=1647592494&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Gros, Daniel. 2022. Optimal tariff versus optimal sanction&amp;#160;: The case of European gas imports from Russia. EUI Policy Brief 2022\/19.&lt;\/li&gt;&lt;li&gt;Guardian. 2022. \u201cGermany will stop importing Russian gas \u2018very soon\u2019, says Olaf Scholz,\u201d April 8, &lt;a href=&quot;https:\/\/www.theguardian.com\/world\/2022\/apr\/08\/germany-russian-gas-imports-olaf-scholz-boris-johnson-ukraine&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.theguardian.com\/world\/2022\/apr\/08\/germany-russian-gas-&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.theguardian.com\/world\/2022\/apr\/08\/germany-russian-gas-imports-olaf-scholz-boris-johnson-ukraine&quot;&gt;imports-olaf-scholz-boris-johnson-ukraine&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Hamilton, James. 2022. Sanctions, energy prices, and the global economy. Markus\u2019 Academy, March 17, &lt;a href=&quot;https:\/\/economics.princeton.edu\/events\/james-hamilton-on-sanctions-energy-prices-and-the-global-economy&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/economics.princeton.edu\/events\/james-hamilton-on-&lt;\/a&gt; &lt;a href=&quot;https:\/\/economics.princeton.edu\/events\/james-hamilton-on-sanctions-energy-prices-and-the-global-economy&quot;&gt;sanctions-energy-prices-and-the-global-economy&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;IEA (International Energy Agency). 2022a. How Europe can cut natural gas imports from Russia significantly within a year, March 3, &lt;a href=&quot;https:\/\/www.iea.org\/news\/how-europe-can-cut-natural-gas-imports-from-russia-significantly-within-a-year&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.iea.org\/news\/how-europe-can-&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.iea.org\/news\/how-europe-can-cut-natural-gas-imports-from-russia-significantly-within-a-year&quot;&gt;cut-natural-gas-imports-from-russia-significantly-within-a-year&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;IEA (International Energy Agency). 2022b. A 10-point plan to reduce the European Union\u2019s reliance on Russian natural gas, &lt;a href=&quot;https:\/\/www.iea.org\/reports\/a-10-point-plan-to-reduce-the-european-unions-reliance-on-russian-natural-gas&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.iea.org\/reports\/a-10-point-plan-to-&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.iea.org\/reports\/a-10-point-plan-to-reduce-the-european-unions-reliance-on-russian-natural-gas&quot;&gt;reduce-the-european-unions-reliance-on-russian-natural-gas&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Lane, Philip R. 2022. The euro area outlook and monetary policy, speech, March 17, &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/press\/key\/date\/2022\/html\/ecb.sp220317_1~a7d800c4b6.en.pdf?08d189a3cd47024025a0dc9731383432&quot;&gt;https:\/\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/press\/key\/date\/2022\/html\/ecb.sp220317_1~a7d800c4b6.en.pdf?08d189a3cd47024025a0dc9731383432&quot;&gt;www.ecb.europa.eu\/press\/key\/date\/2022\/html\/ecb.sp220317_1~a7d800c4b6.en.pdf?0&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/press\/key\/date\/2022\/html\/ecb.sp220317_1~a7d800c4b6.en.pdf?08d189a3cd47024025a0dc9731383432&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;8d189a3cd47024025a0dc9731383432&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Macrotrends. 2022. Wheat prices\u201340 year historical chart, April 19, &lt;a href=&quot;https:\/\/www.macrotrends.net\/2534\/wheat-prices-historical-chart-data&quot;&gt;https:\/\/www.&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.macrotrends.net\/2534\/wheat-prices-historical-chart-data&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;macrotrends.net\/2534\/wheat-prices-historical-chart-data&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;McWilliams, Ben, Giovanni Sgaravatti, Simone Tagliapietra, Georg Zachmann. 2022. Can Europe manage if Russian oil and gas are cut off&amp;#160;?, Bruegel, March 17, &lt;a href=&quot;https:\/\/www.bruegel.org\/2022\/03\/can-europe-manage-if-russian-oil-and-coal-are-cut-off&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.bruegel.org\/2022\/03\/can-europe-manage-if-russian-oil-and-coal-are-cut-off&quot;&gt;bruegel.org\/2022\/03\/can-europe-manage-if-russian-oil-and-coal-are-cut-off&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Moll, Ben. 2022. Online appendix to Bachmann et al. (2022), &lt;a href=&quot;https:\/\/benjaminmoll.com\/RussianGas_Appendix\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/benjaminmoll.com\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/benjaminmoll.com\/RussianGas_Appendix\/&quot;&gt;RussianGas_Appendix\/&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Pisani-Ferry, Jean. 2022. Europe\u2019s economic response to the Russia-Ukraine war will redefine its priorities and future. RealTime Economic Issues Watch blog, March 10, Peterson Institute for International Economics, &lt;a href=&quot;https:\/\/www.piie.com\/blogs\/realtime-economic-issues-watch\/europes-economic-response-russia-ukraine-war-will-redefine-its&quot;&gt;https:\/\/www.piie.com\/blogs\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.piie.com\/blogs\/realtime-economic-issues-watch\/europes-economic-response-russia-ukraine-war-will-redefine-its&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;realtime-economic-issues-watch\/europes-economic-response-russia-ukraine-war-&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.piie.com\/blogs\/realtime-economic-issues-watch\/europes-economic-response-russia-ukraine-war-will-redefine-its&quot;&gt;will-redefine-its&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Ritchie, Hannah. 2022. How could the war in Ukraine impact global food supplies&amp;#160;? Our World in Data, March 24, &lt;a href=&quot;https:\/\/ourworldindata.org\/ukraine-russia-food&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/ourworldindata.org\/ukraine-russia-food&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Schnabel, Isabel. 2022. Managing policy trade-offs, April 2, &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/press\/key\/date\/2022\/html\/ecb.sp220402~9af4336c23.en.html&quot;&gt;https:\/\/www.ecb.europa.eu\/&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/press\/key\/date\/2022\/html\/ecb.sp220402~9af4336c23.en.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;press\/key\/date\/2022\/html\/ecb.sp220402~9af4336c23.en.html&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Sgaravatti, G., S. Tagliapietra, and G. Zachmann. 2022. National policies to shield consumers from rising energy prices. Bruegel, March 29, &lt;a href=&quot;https:\/\/www.bruegel.org\/publications\/datasets\/national-policies-to-shield-consumers-from-rising-energy-prices\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.bruegel.&lt;\/a&gt; &lt;a href=&quot;https:\/\/www.bruegel.org\/publications\/datasets\/national-policies-to-shield-consumers-from-rising-energy-prices\/&quot;&gt;org\/publications\/datasets\/national-policies-to-shield-consumers-from-rising-energy-prices\/&lt;\/a&gt;.&lt;\/li&gt;&lt;li&gt;Sturm, John. 2022. &lt;a href=&quot;https:\/\/drive.google.com\/file\/d\/1FN07m-B6X_AAJruNrT9_qQoT7JkP8udo\/view&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;The Simple Economics of Trade Sanctions on Russia&amp;#160;: A Policymaker\u2019s&lt;\/em&gt;&lt;\/a&gt;&lt;em&gt; &lt;\/em&gt;&lt;a href=&quot;https:\/\/drive.google.com\/file\/d\/1FN07m-B6X_AAJruNrT9_qQoT7JkP8udo\/view&quot;&gt;&lt;em&gt;Guide&lt;\/em&gt;&lt;\/a&gt;. Working paper, April 9, MIT.UNHCR (UN High Commissioner for Refugees). 2022. Ukraine situation flash update, April 13, &lt;a href=&quot;https:\/\/reliefweb.int\/report\/ukraine\/ukraine-situation-flash-update-8-13-april-2022&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/reliefweb.int\/report\/ukraine\/ukraine-situation-flash-update-8-13-april-2022&lt;\/a&gt;.&lt;\/li&gt;&lt;\/ul&gt;\n\n\n\n&lt;p&gt;'><sup>4<\/sup><\/a><\/span><\/span>. L&rsquo;exode se poursuit (bien qu&rsquo;\u00e0 un rythme plus lent), de sorte qu\u2019il est possible que ce chiffre atteigne 5 millions, et peut-\u00eatre plus. Il s&rsquo;agit d&rsquo;un drame humain aux proportions gigantesques qui pose des probl\u00e8mes majeurs d&rsquo;organisation et de r\u00e9partition entre les pays. Pourtant, les co\u00fbts macro\u00e9conomiques probables semblent relativement limit\u00e9s. Les estimations du co\u00fbt budg\u00e9taire annuel de l&rsquo;h\u00e9bergement, de la nourriture, des soins de sant\u00e9 et de l&rsquo;\u00e9ducation des r\u00e9fugi\u00e9s varient de 9 000 \u00e0 25 000 euros par personne et par an&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-5-138270' title='Voir l&amp;rsquo;enqu\u00eate r\u00e9cente de Darvas (2022). Les estimations sup\u00e9rieures sont bas\u00e9es sur des donn\u00e9es su\u00e9doises. Pisani-Ferry (2022) utilise une estimation de 10 000 \u20ac bas\u00e9e sur le co\u00fbt de la vague de r\u00e9fugi\u00e9s de 2015 en Allemagne. Les co\u00fbts sont forc\u00e9ment plus faibles en Pologne et dans d&amp;rsquo;autres pays de la ligne de front qu&amp;rsquo;ils ne l&amp;rsquo;\u00e9taient en Su\u00e8de. Nous nous en tenons donc \u00e0 l&amp;rsquo;estimation de 10 000 \u20ac.'><sup>5<\/sup><\/a><\/span><\/span>. En partant de l&rsquo;hypoth\u00e8se d&rsquo;un co\u00fbt de 10 000 euros par r\u00e9fugi\u00e9 (par an), le co\u00fbt du financement de 5 millions de r\u00e9fugi\u00e9s pendant un an s&rsquo;\u00e9l\u00e8ve \u00e0 50 milliards d&rsquo;euros, soit 0,35&#160;% du PIB de l&rsquo;UE. M\u00eame ce chiffre surestime le co\u00fbt, car au bout de quelques mois, certains r\u00e9fugi\u00e9s rentreront chez eux, d&rsquo;autres trouveront du travail et d&rsquo;autres encore \u00e9migreront de l&rsquo;Union europ\u00e9enne.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Alimentation<\/strong><\/h3>\n\n\n\n<p>La Russie et l&rsquo;Ukraine sont de grands producteurs, et surtout de grands exportateurs de denr\u00e9es alimentaires, de bl\u00e9 en particulier&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-6-138270' title='Pour plus de d\u00e9tails sur les cons\u00e9quences de la guerre sur les prix des denr\u00e9es alimentaires, voir &lt;a href=&quot;https:\/\/www.fao.org\/3\/cb9013en\/cb9013en.pdf&quot;&gt;FAO&lt;\/a&gt; (2022). Voir aussi &lt;a href=&quot;https:\/\/ourworldindata.org\/ukraine-russia-food&quot;&gt;Ritchie&lt;\/a&gt; (2022).'><sup>6<\/sup><\/a><\/span><\/span>. Selon l&rsquo;Organisation pour l&rsquo;alimentation et l&rsquo;agriculture (FAO), les exportations russes et ukrainiennes de bl\u00e9 ont repr\u00e9sent\u00e9 23&#160;% des exportations mondiales et 7&#160;% de la production mondiale en 2019. En Ukraine, les semis pour la prochaine r\u00e9colte pourraient \u00eatre difficiles&#160;; et les restrictions auto-impos\u00e9es pourraient limiter les exportations russes. Les probl\u00e8mes de distribution, compte tenu des combats dans les ports le long de la mer Noire, pourraient encore diminuer les exportations. Le prix du march\u00e9 du bl\u00e9 a d\u00e9j\u00e0 augment\u00e9 de pr\u00e8s de 50&#160;%, passant de 7,70 dollars le boisseau avant la guerre \u00e0 11 dollars, un niveau qui n&rsquo;a \u00e9t\u00e9 vu que pendant quelques jours en 2008 (Macrotrends 2022).<\/p>\n\n\n\n<p>L&rsquo;Union europ\u00e9enne \u00e9tant un exportateur net de produits agricoles (en 2021, son exc\u00e9dent commercial \u00e9tait proche de 50 milliards d&rsquo;euros, selon Eurostat), la hausse mondiale des prix pourrait bien am\u00e9liorer ses termes de l&rsquo;\u00e9change. Deux mises en garde importantes s&rsquo;imposent toutefois. La premi\u00e8re est que la perte pour les consommateurs de l&rsquo;Union (par opposition \u00e0 l&rsquo;Union europ\u00e9enne dans son ensemble, c&rsquo;est-\u00e0-dire les producteurs et les consommateurs r\u00e9unis) peut \u00eatre importante, une question sur laquelle nous reviendrons dans la section 3. La seconde est que les prix \u00e9lev\u00e9s des denr\u00e9es alimentaires ont d\u00e9j\u00e0 des cons\u00e9quences dramatiques pour de nombreux pays \u00e9mergents et en d\u00e9veloppement, affectant leur croissance et leur stabilit\u00e9 macro\u00e9conomique, et affectant potentiellement l&rsquo;Union europ\u00e9enne en retour.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:#ffffff;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/fr\/evenements\/colloque-sorbonne-interregne\/\" style=\"color:#281e1e;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tL&rsquo;\u00e9v\u00e9nement pour comprendre la guerre en Ukraine \t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#281e1e;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Depuis presque trois mois, la guerre de la Russie de Poutine \u00e0 l\u2019Ukraine bouleverse tout. <\/p>\n<p>Comment comprendre cette crise in\u00e9dite&#160;&#160;?<\/p>\n<p>Un \u00e9v\u00e9nement intellectuel europ\u00e9en avec entre autres Latour, Balibar, Roudinesco, Colin Lebedev, Gonzalez Laya, Kepel, Pisani-Ferry, Haski, Soutou, Aglietta&#8230;<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/evenements\/colloque-sorbonne-interregne\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrez le d\u00e9roul\u00e9 de la journ\u00e9e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/www.eventbrite.be\/e\/billets-apres-linvasion-de-lukraine-leurope-dans-linterregne-335974367377\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Inscription obligatoire ici<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/user-dashboard\/register\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrir notre offre de lancement<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#281e1e;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p>Mardi 17 mai de 10h15 \u00e0 18h, dans le Grand Amphith\u00e9\u00e2tre de la Sorbonne, en partenariat avec Le Monde, Repubblica, El Pais et l&rsquo;Acad\u00e9mie de Paris, un colloque international pour naviguer dans l&rsquo;interr\u00e8gne.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/fr\/evenements\/colloque-sorbonne-interregne\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/05\/Capture-de\u0301cran-2022-05-10-a\u0300-18.20.59-990x572.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>2 \u2014 Le probl\u00e8me de l\u2019\u00e9nergie<\/strong><\/h2>\n\n\n\n<p>L&rsquo;interd\u00e9pendance \u00e9conomique entre la Russie et l&rsquo;Union europ\u00e9enne r\u00e9sulte en grande partie du fait que la Russie est le principal fournisseur de combustibles fossiles de l&rsquo;Europe. Jusqu&rsquo;\u00e0 pr\u00e9sent, les deux parties se sont abstenues d&rsquo;utiliser l&rsquo;\u00e9nergie comme moyen de pression l&rsquo;une sur l&rsquo;autre. Mais le 8 avril, l&rsquo;Union europ\u00e9enne a d\u00e9cid\u00e9 d&rsquo;interdire les importations de charbon russe \u00e0 partir du 22 ao\u00fbt (Bown 2022). Certains pays de l&rsquo;Union sont d\u00e9j\u00e0 all\u00e9s plus loin. Le 30 mars, par exemple, la Pologne a annonc\u00e9 sa d\u00e9cision de ne plus importer aucune \u00e9nergie russe d&rsquo;ici \u00e0 la fin de 2022. En r\u00e9fl\u00e9chissant \u00e0 ce qui pourrait advenir des prix de l&rsquo;\u00e9nergie, en fonction \u00e0 la fois des d\u00e9cisions russes et des sanctions potentielles, il est important de faire la distinction entre le p\u00e9trole (et le charbon) et le gaz.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;interd\u00e9pendance \u00e9conomique entre la Russie et l&rsquo;Union europ\u00e9enne r\u00e9sulte en grande partie du fait que la Russie est le principal fournisseur de combustibles fossiles de l&rsquo;Europe.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le p\u00e9trole et le gaz<\/strong><em>&nbsp;<\/em><\/h3>\n\n\n\n<p>Les donn\u00e9es sur l&rsquo;\u00e9nergie peuvent facilement pr\u00eater \u00e0 confusion en raison de l&rsquo;h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 des unit\u00e9s de mesure, aussi un bref r\u00e9sum\u00e9 de la situation constitue-t-il un point de d\u00e9part utile. L&rsquo;approvisionnement en \u00e9nergie dans l&rsquo;Union repose essentiellement sur le p\u00e9trole (33&#160;%, presque enti\u00e8rement import\u00e9), le gaz (24&#160;%, principalement import\u00e9) et le charbon (12&#160;%, principalement import\u00e9) (figure 1). Les autres sources comprennent les \u00e9nergies renouvelables (nationales), le nucl\u00e9aire (essentiellement national, car le combustible lui-m\u00eame ne repr\u00e9sente qu&rsquo;une petite partie du co\u00fbt total) et l&rsquo;\u00e9lectricit\u00e9 import\u00e9e. La Russie est un important fournisseur de p\u00e9trole, de gaz et de charbon.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/a5SOT\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Avant la guerre, le prix des exportations russes de p\u00e9trole suivait de pr\u00e8s le prix du march\u00e9 mondial du Brent, indiquant une forte substituabilit\u00e9. La Russie \u00e9tant l&rsquo;un des nombreux fournisseurs de p\u00e9trole de l&rsquo;Union europ\u00e9enne, nous supposons que la baisse des importations de l&rsquo;Union en provenance de Russie peut \u00eatre remplac\u00e9e par des importations provenant d&rsquo;ailleurs. Et une baisse des exportations russes vers l&rsquo;Ouest peut \u00eatre partiellement compens\u00e9e par les achats de l&rsquo;Inde et de la Chine.&nbsp;<\/p>\n\n\n\n<p>Contrairement au p\u00e9trole, le march\u00e9 du gaz est r\u00e9gional. Il existe, en gros, trois march\u00e9s au niveau mondial&#160;: l&rsquo;Europe, l&rsquo;Am\u00e9rique du Nord et l&rsquo;Asie. Les prix sur ces march\u00e9s sont certes li\u00e9s, car le gaz naturel liqu\u00e9fi\u00e9 (GNL) peut \u00eatre achemin\u00e9 vers n&rsquo;importe lequel d&rsquo;entre eux, mais ils peuvent pr\u00e9senter des diff\u00e9rences consid\u00e9rables. \u00c0 partir de 2021, la forte demande en Asie a par exemple entra\u00een\u00e9 une divergence importante entre le prix du gaz en Am\u00e9rique du Nord et les prix en Asie et en Europe.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/ljnpL\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Le march\u00e9 pertinent pour discuter de l&rsquo;impact d&rsquo;une sanction de l&rsquo;Union est donc le march\u00e9 europ\u00e9en, et non le march\u00e9 mondial. Le gaz est essentiellement utilis\u00e9 pour la production d&rsquo;\u00e9lectricit\u00e9 (1\/3), par l&rsquo;industrie et les services (1\/3), et par les m\u00e9nages (un peu moins d\u2019un tiers). Il est tr\u00e8s substituable pour certains de ses usages (l&rsquo;\u00e9lectricit\u00e9 produite par le gaz peut \u00eatre remplac\u00e9e par de l&rsquo;\u00e9lectricit\u00e9 produite par d&rsquo;autres sources d\u2019\u00e9nergie), beaucoup moins pour certains autres (un syst\u00e8me de chauffage au gaz ne peut pas br\u00fbler du p\u00e9trole ou du charbon). En moyenne, le gaz russe repr\u00e9sente 8,4&#160;% de l&rsquo;approvisionnement en \u00e9nergie primaire dans l&rsquo;Union europ\u00e9enne, mais il existe de grandes variations entre les \u00c9tats membres. Par exemple, le Portugal n&rsquo;importe aucun gaz de Russie, mais en Hongrie, le gaz russe repr\u00e9sente 28,5&#160;% de l&rsquo;approvisionnement en \u00e9nergie primaire (Pisani-Ferry, 2022).&nbsp;<\/p>\n\n\n\n<p>Bien qu&rsquo;elles ne soient pas enti\u00e8rement interconnect\u00e9es (l&rsquo;Espagne et le Portugal, par exemple, n&rsquo;ont que des connexions par gazoduc limit\u00e9es avec l&rsquo;Europe du Nord), les diff\u00e9rences de prix dans l&rsquo;Union europ\u00e9enne peuvent \u00eatre largement arbitr\u00e9es par des transactions internes sur les importations en provenance du reste du monde, \u00e0 condition \u2013 ce qui n&rsquo;est pas acquis \u2013 qu&rsquo;il y ait un accord politique \u00e0 ce sujet&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-7-138270' title='Par exemple, les importations de GNL en provenance du reste du monde pourraient \u00eatre dirig\u00e9es vers les pays o\u00f9 la demande exc\u00e9dentaire est la plus forte.'><sup>7<\/sup><\/a><\/span><\/span>. Dans ce qui suit, nous traitons le march\u00e9 de l&rsquo;Union comme un seul march\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En moyenne, le gaz russe repr\u00e9sente 8,4&#160;% de l&rsquo;approvisionnement en \u00e9nergie primaire dans l&rsquo;Union europ\u00e9enne, mais il existe de grandes variations entre les \u00c9tats membres.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>R\u00e9flexion sur la d\u00e9termination des prix de l&rsquo;\u00e9nergie&nbsp;<\/strong><\/h3>\n\n\n\n<p>M\u00eame en l&rsquo;absence de sanctions, la Russie pourrait bien vouloir adopter un comportement strat\u00e9gique dans la d\u00e9termination de sa politique d&rsquo;exportation de p\u00e9trole et de gaz.&nbsp;<\/p>\n\n\n\n<p>Dans le cas du p\u00e9trole, elle pourrait vouloir augmenter ses revenus pour financer les d\u00e9penses suppl\u00e9mentaires li\u00e9es \u00e0 la guerre. Cela entra\u00eenerait une augmentation de l&rsquo;offre mondiale de p\u00e9trole et donc une baisse du prix mondial. La Russie, cependant, pourrait \u00eatre confront\u00e9e \u00e0 une s\u00e9rie de contraintes. L&rsquo;offre suppl\u00e9mentaire est actuellement limit\u00e9e par la difficult\u00e9 de mettre en circulation des cargaisons sur le march\u00e9 international (ce qui se refl\u00e8te dans la d\u00e9cote entre les prix du p\u00e9trole de l&rsquo;Oural et du Brent). En outre, la Russie fait partie de la coalition de l\u2019OPEP+, ce qui limite sa capacit\u00e9 \u00e0 augmenter ses exportations.&nbsp;<\/p>\n\n\n\n<p>Dans le cas du gaz, un effet plus subtil entre en ligne de compte. L&rsquo;Union europ\u00e9enne fait des pieds et des mains pour r\u00e9duire sa d\u00e9pendance \u00e0 l&rsquo;\u00e9gard du gaz naturel russe, mais son engagement \u00e0 r\u00e9duire ses importations de deux tiers d&rsquo;ici \u00e0 la fin de 2022 est optimiste&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-8-138270' title='Voir &lt;a href=&quot;https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/en\/ip_22_1511&quot;&gt;Communication de la Commission europ\u00e9enne&lt;\/a&gt; du 8 mars 2022.'><sup>8<\/sup><\/a><\/span><\/span>. Du c\u00f4t\u00e9 de l&rsquo;offre, une partie du gaz russe peut \u00eatre remplac\u00e9e par du gaz provenant de Norv\u00e8ge, d&rsquo;Alg\u00e9rie et d&rsquo;Azerba\u00efdjan, mais ces pays ont une capacit\u00e9 de production limit\u00e9e. Le reste doit \u00eatre livr\u00e9 par des navires sous forme de GNL, mais \u00e0 court terme, le nombre de navires GNL est fixe et l&rsquo;offre suppl\u00e9mentaire ne peut provenir que du d\u00e9tournement de cargaisons destin\u00e9es \u00e0 l&rsquo;Asie. Du c\u00f4t\u00e9 de la demande, la capacit\u00e9 \u00e0 remplacer le gaz par d&rsquo;autres sources d&rsquo;\u00e9nergie est \u00e9galement limit\u00e9e par les \u00e9quipements existants. Des recherches r\u00e9centes (AIE 2022b, McWilliams et al. 2022) concluent que l&rsquo;Union europ\u00e9enne ne peut, au cours de cette ann\u00e9e et de l&rsquo;ann\u00e9e prochaine, remplacer totalement les importations de gaz naturel russe&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-9-138270' title='Pour une discussion plus approfondie de l&amp;rsquo;\u00e9lasticit\u00e9 de substitution sous-jacente entre le gaz et les autres sources d&amp;rsquo;\u00e9nergie, et de ses implications pour le PIB en cas d&amp;#8217;embargo total sur le gaz, voir Bachmann et al. (2022), Baqaee et Moll (2022), et Moll (2022).'><sup>9<\/sup><\/a><\/span><\/span>. \u00c0 court terme, la demande de gaz de l&rsquo;Union est donc relativement in\u00e9lastique et, selon des hypoth\u00e8ses plausibles, l&rsquo;\u00e9lasticit\u00e9-prix de la demande de gaz russe de l&rsquo;Union (demande totale moins les importations du reste du monde) pourrait bien \u00eatre inf\u00e9rieure \u00e0 un.&nbsp;<\/p>\n\n\n\n<p>Dans l&rsquo;hypoth\u00e8se d&rsquo;un monopole standard, une \u00e9lasticit\u00e9 aussi faible conduirait la Russie \u00e0 fixer un prix tr\u00e8s \u00e9lev\u00e9, m\u00eame en l&rsquo;absence de guerre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-10-138270' title='Nous pensons \u00e0 la Russie comme un monopole face \u00e0 un grand nombre d&amp;rsquo;acheteurs nationaux. En pr\u00e9sence d&amp;rsquo;un tarif commun, et de coordination entre acheteurs, il peut \u00eatre plus appropri\u00e9 de r\u00e9fl\u00e9chir \u00e0 l&amp;rsquo;\u00e9quilibre de march\u00e9 comme le r\u00e9sultat d&amp;rsquo;un jeu entre deux joueurs. Pour le moment, en l\u2019absence de coordination, nous n&amp;rsquo;avons pas explor\u00e9 les implications de cette alternative.'><sup>10<\/sup><\/a><\/span><\/span>. La raison pour laquelle la Russie n&rsquo;a pas agi de la sorte dans le pass\u00e9 est que l&rsquo;\u00e9lasticit\u00e9 \u00e0 long terme est certainement sup\u00e9rieure \u00e0 un, et qu&rsquo;elle doit donc faire face \u00e0 un compromis intertemporel&#160;: un prix tr\u00e8s \u00e9lev\u00e9 augmente les revenus \u00e0 court terme mais les diminue \u00e0 long terme. Mais la guerre a deux effets sur ce calcul. Le premier est, encore une fois, le besoin de revenus plus \u00e9lev\u00e9s aujourd&rsquo;hui, ce qui conduit \u00e0 une augmentation du prix. Le second est que l&rsquo;anticipation de futures sanctions, et la d\u00e9cision claire de l&rsquo;Union europ\u00e9enne de se sevrer des exportations de gaz russe, r\u00e9duisent les effets d&rsquo;une augmentation du prix sur les revenus futurs, ce qui conduit \u00e0 nouveau la Russie \u00e0 augmenter le prix tant que la demande est encore pr\u00e9sente.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;Union europ\u00e9enne ne peut, au cours de cette ann\u00e9e et de l&rsquo;ann\u00e9e prochaine, remplacer totalement les importations de gaz naturel russe.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En bref, en faisant fi des sanctions, la Russie pourrait vouloir augmenter les revenus de ses exportations \u00e9nerg\u00e9tiques. Mais, contrairement au cas du p\u00e9trole pour lequel cela impliquerait d&rsquo;augmenter le volume des exportations (compte tenu du prix mondial), dans le cas du gaz, cela impliquerait d&rsquo;augmenter les prix (et donc de diminuer les volumes d&rsquo;exportation). Il est vrai que les contrats de gaz \u00e0 long terme emp\u00eachent normalement un tel comportement \u2013 car ils sp\u00e9cifient l&rsquo;indexation des prix sur le prix du march\u00e9 TTF (<em>title transfer facility<\/em>) europ\u00e9en. Mais la Russie dispose d&rsquo;une certaine souplesse pour transf\u00e9rer une partie de son approvisionnement des livraisons dans le cadre des contrats existants vers des ventes de gr\u00e9 \u00e0 gr\u00e9. Plus fondamentalement, les contrats peuvent, apr\u00e8s tout, \u00eatre r\u00e9vis\u00e9s ou abrog\u00e9s.&nbsp;<\/p>\n\n\n\n<p>En ce qui concerne les sanctions, qu&rsquo;il s&rsquo;agisse d&#8217;embargos ou de tarifs douaniers, la structure du march\u00e9 est aussi fondamentale, et il faut examiner s\u00e9par\u00e9ment les effets sur les exportations de p\u00e9trole et de gaz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sanctions&#160;: p\u00e9trole<\/strong><\/h3>\n\n\n\n<p>Pour sanctionner la Russie, l&rsquo;Union europ\u00e9enne pourrait imiter les \u00c9tats-Unis et le Royaume-Uni et d\u00e9cr\u00e9ter un embargo sur le p\u00e9trole russe. Il s&rsquo;agirait de l&rsquo;approche la plus simple, car un embargo europ\u00e9en renforcerait la r\u00e9ticence actuelle des entreprises \u00e9nerg\u00e9tiques, des armateurs, des banques et des assureurs \u00e0 prendre part aux exportations russes. Une telle mesure n&#8217;emp\u00eacherait pas la Russie d&rsquo;exporter, puisqu\u2019elle trouverait d&rsquo;autres acheteurs, comme la Chine, l&rsquo;Inde ou d&rsquo;autres pays, comme elle le fait d\u00e9j\u00e0, mais un embargo augmenterait certainement la d\u00e9cote du p\u00e9trole russe, comme nous le constatons d\u00e9j\u00e0 avec la d\u00e9cote du prix de l&rsquo;Oural (environ 25&#160;% pour le moment). En d&rsquo;autres termes, la strat\u00e9gie occidentale (d\u00e9j\u00e0 largement \u00e0 l\u2019\u0153uvre) consisterait \u00e0 maintenir le p\u00e9trole russe sur le march\u00e9, tout en trouvant des moyens de faire baisser son prix. Si les exportations russes nettes diminuaient, le prix mondial augmenterait, \u00e0 moins que la baisse des exportations russes ne soit compens\u00e9e par la d\u00e9cision d&rsquo;autres producteurs, de l&rsquo;Arabie saoudite \u00e0 l&rsquo;Iran en passant par le Venezuela, d&rsquo;augmenter leur production.&nbsp;<\/p>\n\n\n\n<p>La hausse du prix mondial d\u00e9pendrait <em>in fine<\/em> de la capacit\u00e9 de la Russie \u00e0 trouver d&rsquo;autres acheteurs et de la d\u00e9cision des autres pays de vendre davantage. Pour avoir une id\u00e9e de la fa\u00e7on dont l&rsquo;impact sur les prix d\u00e9pendrait de la diminution de l&rsquo;offre mondiale, il est utile de trouver quelques pr\u00e9c\u00e9dents historiques.&nbsp;<\/p>\n\n\n\n<p>L&#8217;embargo de l&rsquo;OPEP de 1973 avait r\u00e9duit l&rsquo;offre mondiale de 7&#160;% et entra\u00een\u00e9 une augmentation du prix de 51&#160;%. La r\u00e9volution iranienne de 1978 avait r\u00e9duit l&rsquo;offre mondiale de 4&#160;% et entra\u00een\u00e9 une hausse des prix de 57&#160;%. La guerre Iran-Irak de 1980 avait r\u00e9duit l&rsquo;offre mondiale de 4&#160;% et entra\u00een\u00e9 une hausse des prix de 45&#160;%. La guerre du Golfe de 1990 avait r\u00e9duit l&rsquo;offre mondiale de 6&#160;% et entra\u00een\u00e9 une hausse des prix de 93&#160;% (Hamilton 2022). La Russie repr\u00e9sentait en 2019 environ 13&#160;% de la production mondiale et ses exportations une proportion similaire du commerce mondial, de sorte qu&rsquo;une forte diminution de l&rsquo;offre russe, non compens\u00e9e par une augmentation de l&rsquo;offre ailleurs, aurait des effets majeurs <a href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/16\/prix-du-petrole\/\">sur le prix du p\u00e9trole<\/a> (BP 2021)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-11-138270' title='Ici et ailleurs, sauf indication contraire, nous utilisons les donn\u00e9es 2019 comme r\u00e9f\u00e9rence, car les donn\u00e9es 2020 ont \u00e9t\u00e9 affect\u00e9es par le choc Covid et les donn\u00e9es 2021 ne sont pas toujours disponibles.'><sup>11<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si les exportations russes nettes diminuaient, le prix mondial augmenterait, \u00e0 moins que la baisse des exportations russes ne soit compens\u00e9e par la d\u00e9cision d&rsquo;autres producteurs, de l&rsquo;Arabie saoudite \u00e0 l&rsquo;Iran en passant par le Venezuela, d&rsquo;augmenter leur production.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Toutefois, l&rsquo;histoire n&rsquo;est peut-\u00eatre pas un guide fiable. Les effets d&rsquo;une baisse de l&rsquo;offre d\u00e9pendent de l&rsquo;\u00e9lasticit\u00e9 de l&rsquo;offre de p\u00e9trole non russe et de la demande mondiale de p\u00e9trole. Et les deux sont diff\u00e9rentes de ce qu&rsquo;elles \u00e9taient dans les ann\u00e9es 1970 ou m\u00eame 1990. L&rsquo;\u00e9lasticit\u00e9 de l&rsquo;offre par rapport au prix a augment\u00e9 depuis les \u00e9pisodes cit\u00e9s plus haut, notamment depuis que les \u00c9tats-Unis ont commenc\u00e9 \u00e0 exploiter le p\u00e9trole de schiste. Mais il faut du temps avant que les nouveaux forages commencent \u00e0 augmenter la production.&nbsp;<\/p>\n\n\n\n<p>Par ailleurs, l&rsquo;\u00e9lasticit\u00e9 prix de la demande a diminu\u00e9, car le p\u00e9trole est de plus en plus utilis\u00e9 l\u00e0 o\u00f9 les substituts font d\u00e9faut (par exemple, pour alimenter les v\u00e9hicules \u00e0 moteur et les avions). Et les mesures gouvernementales visant \u00e0 prot\u00e9ger partiellement les acheteurs, qu&rsquo;il s&rsquo;agisse d&rsquo;entreprises ou de consommateurs, contre les hausses de prix peuvent encore r\u00e9duire l&rsquo;\u00e9lasticit\u00e9 de la demande. Comme nous le montrons dans la section 4, \u00e0 la fin de 2021 et \u00e0 nouveau depuis le d\u00e9but de la guerre, plusieurs gouvernements ont introduit des transferts et des subventions li\u00e9s \u00e0 l&rsquo;\u00e9nergie. Dans la mesure o\u00f9 elles affectent le signal de prix, ces mesures r\u00e9duisent la r\u00e9ponse de la demande. Cela n&rsquo;a pas d&rsquo;importance lorsqu\u2019un petit pays subventionne de mani\u00e8re isol\u00e9e, mais si beaucoup le font \u2013 et ce serait le cas si l&rsquo;Union europ\u00e9enne se joignait aux \u00c9tats-Unis et au Royaume-Uni pour offrir des subventions \u2013 le r\u00e9sultat serait forc\u00e9ment une augmentation plus importante du prix du march\u00e9 mondial.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sanctions&#160;: gaz<\/strong><\/h3>\n\n\n\n<p>La structure du march\u00e9 du gaz peut \u00eatre repr\u00e9sent\u00e9e comme une Russie en situation de monopole faisant face \u00e0 un grand nombre d&rsquo;acheteurs de l&rsquo;Union, pouvant s&rsquo;approvisionner en gaz aupr\u00e8s d&rsquo;autres sources, mais uniquement \u00e0 un co\u00fbt fortement accru. Comme nous l&rsquo;avons vu, m\u00eame en l&rsquo;absence de sanctions, la Russie pourrait vouloir augmenter les prix et r\u00e9duire l&rsquo;offre de gaz. La question ici est de savoir ce qui se passerait si l&rsquo;Union europ\u00e9enne d\u00e9cidait de recourir \u00e0 des sanctions, tr\u00e8s probablement par le biais d&rsquo;un tarif douanier sur les exportations russes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-12-138270' title='Il existe un d\u00e9bat juridique sur la question de savoir si une telle action n\u00e9cessite l&amp;rsquo;unanimit\u00e9 au sein de l&amp;rsquo;Union europ\u00e9enne. Les sanctions sont d\u00e9cid\u00e9es \u00e0 l&amp;rsquo;unanimit\u00e9 sur la base de l&amp;rsquo;art. 29 du trait\u00e9 sur l&amp;rsquo;Union europ\u00e9enne, mais mises en \u0153uvre \u00e0 la majorit\u00e9 qualifi\u00e9e. Les d\u00e9cisions de politique commerciale sont prises \u00e0 la majorit\u00e9 qualifi\u00e9e. Et dans le domaine de l&amp;rsquo;\u00e9nergie, chaque \u00c9tat membre a le droit de d\u00e9terminer \u00ab&amp;#160;la structure g\u00e9n\u00e9rale de son approvisionnement \u00e9nerg\u00e9tique&amp;#160;\u00bb (art. 194 du trait\u00e9 sur le fonctionnement de l&amp;rsquo;UE).'><sup>12<\/sup><\/a><\/span><\/span>. Ce serait un signal fort indiquant que les \u00c9tats membres de l&rsquo;Union sont pr\u00eats \u00e0 affronter conjointement la Russie. Elle pr\u00e9serverait la libert\u00e9 des contrats priv\u00e9s et serait l\u00e9galement applicable, puisque l&rsquo;Union europ\u00e9enne (ainsi que les \u00c9tats-Unis et d&rsquo;autres pays de la coalition soutenant l&rsquo;Ukraine) a exclu la Russie de la clause de la nation la plus favoris\u00e9e \u00e0 l\u2019OMC. Nous supposons que, en r\u00e9action, les contrats priv\u00e9s seraient soit rompus, soit ren\u00e9goci\u00e9s.&nbsp;<\/p>\n\n\n\n<p>Dans ce contexte, l&rsquo;effet du tarif douanier d\u00e9pend de l&rsquo;\u00e9lasticit\u00e9 de la demande nette (la demande de gaz russe moins l&rsquo;offre de gaz non russe \u00e0 l&rsquo;Union europ\u00e9enne). En g\u00e9n\u00e9ral, un tarif augmentera les prix \u00e0 la consommation, mais moins d\u2019un pour un&#160;; de mani\u00e8re \u00e9quivalente, il diminuera le prix avant tarif, mais moins de un pour un.&nbsp;<\/p>\n\n\n\n<p>Dans le cas particulier o\u00f9 l&rsquo;\u00e9lasticit\u00e9 de la demande de l&rsquo;Union est constante, la th\u00e9orie sugg\u00e8re que la Russie maintiendrait son prix (pr\u00e9tarifaire) inchang\u00e9, ce qui entra\u00eenerait une augmentation de un pour un des prix \u00e0 la consommation et une diminution de la demande. Les recettes russes diminueraient en m\u00eame temps que la demande. Dans le cas d&rsquo;une demande lin\u00e9aire, l&rsquo;effet du tarif sur le prix \u00e0 la consommation serait inf\u00e9rieur \u00e0 un pour un \u2013 la Russie diminuerait son prix avant tarifs, mais de moins qu\u2019un pour un. La demande diminuerait moins que dans le cas d&rsquo;une \u00e9lasticit\u00e9 constante. Les recettes russes diminueraient en raison de la baisse de la demande et des prix pr\u00e9tarifaires. Cette hypoth\u00e8se parait la plus raisonnable.&nbsp;<\/p>\n\n\n\n<p>Il est int\u00e9ressant de noter qu&rsquo;un petit droit de douane peut en fait accro\u00eetre le bien-\u00eatre de l&rsquo;Union&#160;: bien que les consommateurs paient davantage, les recettes provenant des droits de douane d\u00e9passent les d\u00e9penses suppl\u00e9mentaires, et donc, si elles sont correctement redistribu\u00e9es, les acheteurs peuvent \u00eatre mieux lotis&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-13-138270' title='Ce point est bien mis en \u00e9vidence par John Sturm (2022), qui montre la relation avec l&amp;rsquo;argument des tarifs douaniers am\u00e9liorant le bien-\u00eatre qui est standard dans le commerce international.'><sup>13<\/sup><\/a><\/span><\/span>. Des tarifs plus \u00e9lev\u00e9s auront un effet n\u00e9gatif sur les revenus de la Russie, mais aussi sur le bien-\u00eatre de l&rsquo;Union. Dans l&rsquo;hypoth\u00e8se d&rsquo;une demande lin\u00e9aire, Daniel Gros (2022) constate qu&rsquo;un tarif de 30&#160;% sur le gaz russe maximiserait en fait le bien-\u00eatre de l&rsquo;UE. Au-del\u00e0 de ce taux, le tarif diminuerait le bien-\u00eatre de l&rsquo;Union mais pourrait r\u00e9duire consid\u00e9rablement les recettes russes. Gros constate qu&rsquo;un tarif de 60&#160;% r\u00e9duirait les recettes d&rsquo;exportation de gaz de la Russie de trois quarts, mais au prix d&rsquo;un certain bien-\u00eatre pour l&rsquo;Union europ\u00e9enne.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Un petit droit de douane peut accro\u00eetre le bien-\u00eatre de l&rsquo;Union&#160;: bien que les consommateurs paient davantage, les recettes provenant des droits de douane d\u00e9passent les d\u00e9penses suppl\u00e9mentaires, et donc, si elles sont correctement redistribu\u00e9es, les acheteurs peuvent \u00eatre mieux lotis.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3 \u2014<\/strong><strong> <\/strong><strong>Augmentation du prix des mati\u00e8res premi\u00e8res, inflation, et pouvoir d\u2019achat<\/strong><\/h2>\n\n\n\n<p>La discussion pr\u00e9c\u00e9dente a montr\u00e9 clairement que, en fonction de nombreux facteurs, tant ceux qui affectent les d\u00e9cisions de la Russie que ceux qui concernent la nature et l&rsquo;intensit\u00e9 des sanctions, il existe une incertitude substantielle quant \u00e0 l&rsquo;\u00e9volution des prix du p\u00e9trole et du gaz. Nous sommes moins pessimistes que les derni\u00e8res <a href=\"https:\/\/www.ifw-kiel.de\/fileadmin\/Dateiverwaltung\/IfW-Publications\/-ifw\/Gemeinschaftsdiagnose\/Langfassungen\/gd_2022_1.pdf\">pr\u00e9visions conjointes<\/a> des instituts allemands de recherche \u00e9conomique qui, dans leur sc\u00e9nario central, pr\u00e9voient que le prix du Brent atteigne 135 dollars le baril et que le prix du gaz en Europe double \u00e0 peu pr\u00e8s pour atteindre 200 euros par MWh. Dans le reste de cette note, nous supposons \u2013 tout en \u00e9tant conscients de la tr\u00e8s grande incertitude associ\u00e9e \u00e0 cette hypoth\u00e8se \u2013 que les d\u00e9cisions de la Russie et les sanctions plus strictes entra\u00eeneront une augmentation des prix du p\u00e9trole et du gaz de 25&#160;% par rapport aux niveaux d&rsquo;avant-guerre.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/S3jxt\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Les augmentations des prix des mati\u00e8res premi\u00e8res se sont produites \u00e0 de nombreuses reprises dans le pass\u00e9. Prenons simplement les prix du p\u00e9trole&#160;: le prix du Brent est pass\u00e9 de 10,3 dollars le baril en f\u00e9vrier 1999 \u00e0 133 dollars en juin 2008, puis de 40 dollars en d\u00e9cembre 2008 \u00e0 123 dollars en avril 2011. Il est rest\u00e9 au-dessus de 100 dollars jusqu&rsquo;en ao\u00fbt 2014. Compte tenu de l&rsquo;inflation depuis 2014, 100 dollars d&rsquo;alors correspondent \u00e0 120 dollars d&rsquo;aujourd&rsquo;hui, de sorte que le prix r\u00e9el actuel du p\u00e9trole n&rsquo;a pas encore atteint les records historiques (figure 3)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-14-138270' title='&lt;a href=&quot;https:\/\/fred.stlouisfed.org\/series\/MCOILBRENTEU&quot;&gt;Donn\u00e9es Fred&lt;\/a&gt; provenant de l\u2019&lt;a href=&quot;https:\/\/www.eia.gov\/dnav\/pet\/TblDefs\/pet_pri_spt_tbldef2.asp&quot;&gt;US Energy Information Administration&lt;\/a&gt;.'><sup>14<\/sup><\/a><\/span><\/span>. Les \u00e9conomistes ont ainsi une bonne compr\u00e9hension des effets de la hausse des prix des mati\u00e8res premi\u00e8res sur l&rsquo;\u00e9conomie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Inflation<\/strong><em>&nbsp;<\/em><\/h3>\n\n\n\n<p>L&rsquo;effet imm\u00e9diat et le plus visible est celui sur l&rsquo;inflation, et il peut \u00eatre tr\u00e8s important. En 2021, l&rsquo;\u00e9lectricit\u00e9, les combustibles de chauffage et les carburants pour le transport repr\u00e9sentaient 9,6&#160;% des d\u00e9penses de consommation individuelle dans la zone euro, et l&rsquo;alimentation repr\u00e9sentait en moyenne 15,7&#160;% du panier de consommation&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-15-138270' title='Source&amp;#160;: &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/stats\/ecb_statistics\/escb\/html\/table.en.html?id=JDF_ICP_COICOP_INW&amp;amp;period=2021&quot;&gt;HICP weights&lt;\/a&gt; de la BCE pour 2021 (disponible seulement en anglais).'><sup>15<\/sup><\/a><\/span><\/span>. Au total, la part de la consommation qui est vuln\u00e9rable \u00e0 l&rsquo;impact direct des hausses de prix est \u00e9lev\u00e9e.<\/p>\n\n\n\n<p>Les estimations empiriques indiquent g\u00e9n\u00e9ralement que la r\u00e9percussion des hausses des prix des mati\u00e8res premi\u00e8res sur les prix \u00e0 la consommation est partielle mais rapide. Une \u00e9tude d\u00e9taill\u00e9e de l&rsquo;Eurosyst\u00e8me (BCE 2010) a constat\u00e9, pour un prix du p\u00e9trole \u00e0 pr\u00e8s de 100 dollars le baril, une \u00e9lasticit\u00e9 de la composante \u00e9nerg\u00e9tique de l&rsquo;IPCH (indice des prix \u00e0 la consommation harmonis\u00e9) par rapport au prix du p\u00e9trole de 0,4 (en grande partie \u00e0 cause des droits d&rsquo;accises insensibles au prix), dont 90&#160;% \u00e9tait effective en un mois. Ces estimations sont toutefois quelque peu d\u00e9pass\u00e9es, car elles supposent une indexation du prix du gaz sur le prix du p\u00e9trole (qui a \u00e9t\u00e9 abandonn\u00e9e) et une rigidit\u00e9 du prix de l&rsquo;\u00e9lectricit\u00e9 (qui ne tient plus) (BCE 2010, tableau 9).&nbsp;<\/p>\n\n\n\n<p>Prenons ensuite 10&#160;% pour la part de l&rsquo;\u00e9nergie dans la consommation priv\u00e9e et supposons une r\u00e9percussion de 50&#160;%. L&rsquo;impact direct de l&rsquo;augmentation suppos\u00e9e de 25&#160;% des prix est donc de 25&#160;% \u00d7 0,1 \u00d7 0,5 = 1,25&#160;%. Pour l&rsquo;alimentation, supposons une part de 15&#160;%, une augmentation de 10&#160;% et une r\u00e9percussion de 0,5&#160;%. L&rsquo;impact est de 10&#160;% \u00d7 0,15 \u00d7 0,5 = 0,75&#160;%. Cela implique une augmentation de 2&#160;% du co\u00fbt d&rsquo;un panier de consommation.&nbsp;<\/p>\n\n\n\n<p>Ces effets de premier tour peuvent difficilement \u00eatre \u00e9vit\u00e9s, mais ils ne sont que le d\u00e9but. Les cycles suivants refl\u00e8tent les r\u00e9actions des entreprises et des travailleurs. Les producteurs de biens qui utilisent l&rsquo;\u00e9nergie ou les produits agricoles dans leur production augmentent leurs prix pour r\u00e9tablir leurs marges. Les travailleurs dont les salaires \u00e9taient inf\u00e9rieurs aux prix \u00e0 la consommation au premier tour demandent des augmentations de salaire nominal pour r\u00e9tablir leur salaire r\u00e9el. Cela conduit \u00e0 de nouvelles augmentations des prix et des salaires. La force de ces nouveaux cycles d\u00e9pend de l&rsquo;effort des entreprises pour r\u00e9tablir leurs marges et de l&rsquo;effort des travailleurs pour maintenir leur salaire r\u00e9el. Finalement, si les prix des mati\u00e8res premi\u00e8res restent \u00e9lev\u00e9s, la pression sur l&rsquo;inflation ne retombe que lorsque les entreprises qui utilisent ces mati\u00e8res premi\u00e8res acceptent des marges inf\u00e9rieures et\/ou que les travailleurs acceptent des salaires r\u00e9els inf\u00e9rieurs. Comme nous le verrons, ce qui arrive \u00e0 l&rsquo;inflation et \u00e0 l&rsquo;activit\u00e9 au fil du temps d\u00e9pend alors de la politique mon\u00e9taire et budg\u00e9taire.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si les prix des mati\u00e8res premi\u00e8res restent \u00e9lev\u00e9s, la pression sur l&rsquo;inflation ne retombe que lorsque les entreprises qui utilisent ces mati\u00e8res premi\u00e8res acceptent des marges inf\u00e9rieures et\/ou que les travailleurs acceptent des salaires r\u00e9els inf\u00e9rieurs. <\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Revenu r\u00e9el&nbsp;<\/strong><\/h3>\n\n\n\n<p>Cette <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/14\/reunion-de-la-bce-sur-linflation\/\">dynamique de l&rsquo;inflation<\/a> est pr\u00e9sente, qu&rsquo;une \u00e9conomie produise ou importe ces produits de base. Mais le fait que l&rsquo;\u00e9conomie soit un importateur net ou non fait une diff\u00e9rence importante dans l&rsquo;\u00e9volution du revenu r\u00e9el global. Prenons le cas des \u00c9tats-Unis, qui couvrent \u00e0 peu pr\u00e8s leurs besoins en \u00e9nergie sur leur territoire. Une augmentation du prix de l&rsquo;\u00e9nergie se traduit par une diminution du revenu r\u00e9el des utilisateurs d&rsquo;\u00e9nergie (consommateurs et entreprises) et une augmentation du revenu r\u00e9el des producteurs d&rsquo;\u00e9nergie (et de leurs actionnaires). L&rsquo;effet sur le revenu r\u00e9el am\u00e9ricain dans son ensemble est \u00e0 peu pr\u00e8s \u00e9gal \u00e0 z\u00e9ro. L&rsquo;effet sur la demande globale aux \u00c9tats-Unis d\u00e9pend de la propension marginale \u00e0 d\u00e9penser des utilisateurs et des producteurs d&rsquo;\u00e9nergie, et peut donc augmenter ou diminuer. L&rsquo;Union europ\u00e9enne, cependant, importe la quasi-totalit\u00e9 du gaz et du p\u00e9trole qu&rsquo;elle consomme, de sorte qu&rsquo;une hausse des prix entra\u00eene une diminution du revenu r\u00e9el des utilisateurs d&rsquo;\u00e9nergie et une augmentation du revenu r\u00e9el des producteurs \u00e9trangers, qui ne d\u00e9penseront probablement pas beaucoup pour les produits de l&rsquo;Union. Ainsi, une augmentation des prix de ces produits de base est susceptible d&rsquo;avoir un effet n\u00e9gatif important sur la demande int\u00e9rieure. Dans les deux cas, les utilisateurs d&rsquo;\u00e9nergie, en particulier les consommateurs, peuvent se trouver dans une situation plus d\u00e9favorable. Mais l&rsquo;effet sur la demande globale d\u00e9pend du fait que le pays soit un importateur net ou non.&nbsp;<\/p>\n\n\n\n<p>Il est utile de r\u00e9fl\u00e9chir aux implications des hausses des prix du p\u00e9trole et du gaz sur le revenu r\u00e9el de l&rsquo;Union et de se faire une id\u00e9e des ordres de grandeur.&nbsp;<\/p>\n\n\n\n<p>Commen\u00e7ons par le p\u00e9trole. Les march\u00e9s p\u00e9troliers semblent supposer que la r\u00e9duction de l&rsquo;offre mondiale sera limit\u00e9e. Le prix du baril de Brent \u00e9tait de 99 dollars la veille du d\u00e9but de la guerre, contre 78 dollars au d\u00e9but de 2022&#160;; il est bri\u00e8vement mont\u00e9 \u00e0 133 dollars mais, au moment de la r\u00e9daction de ce rapport (14 avril), il \u00e9tait redescendu \u00e0 110 dollars. Supposons une augmentation du prix de 78 \u00e0 100 dollars, soit environ 25&#160;%&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-16-138270' title='&lt;a href=&quot;https:\/\/fred.stlouisfed.org\/series\/DCOILBRENTEU&quot;&gt;Prix du p\u00e9trole brut (Brent)&lt;\/a&gt;'><sup>16<\/sup><\/a><\/span><\/span>. Les importations de p\u00e9trole (de Russie et d&rsquo;ailleurs) par l&rsquo;Union \u00e9taient \u00e9gales \u00e0 5 900 millions de barils en 2021. Une telle augmentation du prix impliquerait une diminution du revenu r\u00e9el de l&rsquo;Union europ\u00e9enne de 5 900 x 22 x 100\/1,1 (pour le taux de change dollar-euro), soit 120 milliards d&rsquo;euros, ou 0,9&#160;% du PIB de 2019&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-17-138270' title='Source pour les importations de p\u00e9trole&amp;#160;: Bilans \u00e9nerg\u00e9tiques, &lt;a href=&quot;https:\/\/ec.europa.eu\/eurostat\/fr\/web\/energy\/data\/energy-balances&quot;&gt;Eurostat&lt;\/a&gt;'><sup>17<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>Les march\u00e9s du gaz se sont \u00e9galement repli\u00e9s par rapport aux prix \u00e9lev\u00e9s de f\u00e9vrier, mais ils restent \u00e9lev\u00e9s. Supposons que l&rsquo;augmentation en pourcentage du prix moyen du gaz pour l&rsquo;Union europ\u00e9enne soit la m\u00eame que pour le p\u00e9trole, soit environ 25&#160;%. Les importations de gaz (de Russie et d&rsquo;ailleurs) \u00e9taient \u00e9gales \u00e0 170 milliards d&rsquo;euros en 2021. Cela implique une diminution du revenu r\u00e9el pour l&rsquo;Union europ\u00e9enne de 170 x 0,25 \u2248 42 milliards d&rsquo;euros, soit 0,3&#160;% du PIB de 2019.<\/p>\n\n\n\n<p>Selon ces hypoth\u00e8ses relativement mod\u00e9r\u00e9es, la hausse des prix du p\u00e9trole et du gaz induite par la guerre amputerait le revenu r\u00e9el de l&rsquo;Union europ\u00e9enne d&rsquo;un peu plus de 1&#160;% du PIB. Mais cela viendrait s&rsquo;ajouter \u00e0 l&rsquo;effet des pr\u00e9c\u00e9dentes hausses de prix depuis 2019. Dans l&rsquo;ensemble, et sans tenir compte de la p\u00e9riode de blocage en 2020 au cours de laquelle les prix et les quantit\u00e9s se sont effondr\u00e9s, les importations d&rsquo;\u00e9nergie de l&rsquo;Union, qui s&rsquo;\u00e9levaient \u00e0 2,6&#160;% du PIB en 2019, auraient d\u00e9pass\u00e9 5&#160;% du PIB si les prix \u00e9taient rest\u00e9s \u00e0 leur niveau du d\u00e9but de 2022, et augmenteraient \u00e0 plus de 6&#160;% sur la base de nos hypoth\u00e8ses&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-18-138270' title='Selon nos calculs bas\u00e9s sur la valorisation des flux d&amp;rsquo;\u00e9nergie primaire avec nos hypoth\u00e8ses de prix.'><sup>18<\/sup><\/a><\/span><\/span>. Quel que soit le crit\u00e8re retenu, il s&rsquo;agit d&rsquo;un choc macro\u00e9conomique majeur ayant de graves cons\u00e9quences sur le revenu, la production et l&rsquo;inflation.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Quel que soit le crit\u00e8re retenu, il s&rsquo;agit d&rsquo;un choc macro\u00e9conomique majeur ayant de graves cons\u00e9quences sur le revenu, la production et l&rsquo;inflation.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Effets de r\u00e9partition<\/strong><\/h3>\n\n\n\n<p>Au-del\u00e0 de la perte globale de revenu r\u00e9el pour les consommateurs, les effets de r\u00e9partition sont importants. La consommation de gaz, de services publics et d&rsquo;aliments (en tant que part de la consommation totale) est plus \u00e9lev\u00e9e pour les m\u00e9nages \u00e0 faible revenu que pour les m\u00e9nages \u00e0 revenu \u00e9lev\u00e9, bien qu&rsquo;il existe de nettes diff\u00e9rences entre les pays. Sur la base des donn\u00e9es d&rsquo;Eurostat, la diff\u00e9rence est faible dans les pays scandinaves, par exemple 26&#160;% pour le quintile de revenu inf\u00e9rieur contre 25&#160;% pour le quintile sup\u00e9rieur au Danemark. Elle est plus importante en France et en Allemagne, 25&#160;% contre 21&#160;% en France, 26&#160;% contre 21&#160;% en Allemagne. Elle est encore plus importante dans les pays plus pauvres, par exemple 31&#160;% contre 23&#160;% en Espagne, et 50&#160;% contre 37&#160;% en Bulgarie&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-19-138270' title='Ces chiffres sont construits comme le rapport entre la consommation alimentaire (CP01) plus l&amp;rsquo;\u00e9lectricit\u00e9, le gaz et les autres combustibles (CP045) plus l&amp;rsquo;utilisation des transports personnels (CP072) et la consommation totale, pour chaque quintile. Les chiffres sont tir\u00e9s d&amp;rsquo;Eurostat.'><sup>19<\/sup><\/a><\/span><\/span>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-20-138270' title='Certains des chiffres qui ont \u00e9t\u00e9 publi\u00e9s semblent beaucoup plus \u00e9lev\u00e9s. Par exemple, les donn\u00e9es du BLS pour les \u00c9tats-Unis pour 2020 donnent un ratio de la consommation d&amp;rsquo;aliments, de transports et de services publics par rapport au revenu disponible de 74&amp;#160;% pour le quintile inf\u00e9rieur contre 20&amp;#160;% pour le quintile sup\u00e9rieur. Mais cela refl\u00e8te, en partie, des d\u00e9finitions diff\u00e9rentes de ce qui est inclus dans le panier de consommation plus petit et, surtout, le fait que l&amp;rsquo;analyse porte sur le rapport de la consommation de gaz, de services publics et de nourriture au revenu disponible plut\u00f4t qu&amp;rsquo;\u00e0 la consommation. Dans le quintile inf\u00e9rieur se trouvent de nombreux individus et m\u00e9nages qui n&amp;rsquo;\u00e9pargnent pas et pour lesquels le revenu disponible est faible par rapport \u00e0 la consommation.'><sup>20<\/sup><\/a><\/span><\/span>. De plus, les habitudes de consommation des m\u00e9nages \u00e0 faibles revenus sont souvent plus rigides, car une plus grande partie de leurs revenus est pr\u00e9-affect\u00e9e aux loyers et autres paiements mensuels qu&rsquo;ils ne peuvent pas facilement modifier. Ainsi, outre les effets globaux sur la production et l&rsquo;inflation, il faut tenir compte du fait que les m\u00e9nages pauvres souffrent davantage que les m\u00e9nages plus riches d&rsquo;une hausse des prix des produits de base. Cela a des implications claires pour la politique budg\u00e9taire.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>4 \u2014<\/strong><strong> <\/strong><strong>Implications en mati\u00e8re de politiques publiques<\/strong><\/h2>\n\n\n\n<p>Nous abordons enfin les r\u00e9ponses des politiques budg\u00e9taire et mon\u00e9taire. \u00c0 court terme, la principale question, et la source de d\u00e9penses potentiellement importantes, est de savoir s&rsquo;il faut prot\u00e9ger les consommateurs des hausses de prix des produits de base et comment le faire.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mesures fiscales et de transfert&nbsp;<\/strong><\/h3>\n\n\n\n<p>Selon nos hypoth\u00e8ses, l&rsquo;augmentation m\u00e9diane du prix du panier de consommation, compte tenu des salaires, est d&rsquo;environ 2&#160;%&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-21-138270' title='Dans le prolongement de la discussion pr\u00e9c\u00e9dente sur l&amp;rsquo;inflation, dans la mesure o\u00f9 les producteurs de biens finaux ne refl\u00e8tent pas enti\u00e8rement la hausse des prix des produits de base et acceptent une diminution de leur marge, l&amp;rsquo;effet au cours du cycle initial sera inf\u00e9rieur au chiffre indiqu\u00e9 dans le texte. Mais, s&amp;rsquo;ils r\u00e9tablissent leurs marges au fil du temps, le chiffre indiqu\u00e9 dans le texte est le plus pertinent.'><sup>21<\/sup><\/a><\/span><\/span>. Mais la diminution du revenu r\u00e9el pour le quintile de revenu le plus bas dans les pays les plus touch\u00e9s (par exemple, la Slovaquie) est deux fois plus \u00e9lev\u00e9e, soit 4&#160;%. Il s&rsquo;agit d&rsquo;un chiffre tr\u00e8s \u00e9lev\u00e9, sachant que la dispersion des effets sur les revenus entre les m\u00e9nages, m\u00eame au sein d&rsquo;une m\u00eame tranche de revenus, peut \u00eatre tr\u00e8s importante, en fonction des conditions de vie, et en acceptant que les augmentations des prix des produits de base peuvent \u00eatre plus importantes que dans nos hypoth\u00e8ses&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-22-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-22-138270' title='Dans le cas fran\u00e7ais, Douenne (2019) fournit des preuves sur les dispersions verticales et horizontales des effets d&amp;rsquo;une taxe carbone.'><sup>22<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Selon nos hypoth\u00e8ses, l&rsquo;augmentation m\u00e9diane du prix du panier de consommation, compte tenu des salaires, est d&rsquo;environ 2&#160;%.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La question est donc de savoir dans quelle mesure et comment prot\u00e9ger au mieux les m\u00e9nages. Depuis que les prix de l&rsquo;\u00e9nergie ont commenc\u00e9 \u00e0 augmenter fin 2021, les \u00c9tats membres de l&rsquo;Union se sont employ\u00e9s \u00e0 mettre en place une s\u00e9rie de dispositifs destin\u00e9s \u00e0 att\u00e9nuer le choc. Ces r\u00e9gimes peuvent \u00eatre regroup\u00e9s sous trois rubriques&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-23-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-23-138270' title='En octobre 2021, la Commission europ\u00e9enne a pr\u00e9sent\u00e9 une &lt;a href=&quot;https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/fr\/IP_21_5204&quot;&gt;bo\u00eete \u00e0 outils&lt;\/a&gt; de mesures pour faire face \u00e0 la situation \u00e9nerg\u00e9tique, comme autant d&amp;rsquo;options r\u00e9alisables \u00e0 envisager par les \u00c9tats membres.'><sup>23<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>R\u00e9duction temporaire des taxes sur l\u2019\u00e9nergie<\/strong> <\/h4>\n\n\n\n<p>Une premi\u00e8re possibilit\u00e9 consiste \u00e0 accorder des subventions directes g\u00e9n\u00e9ralis\u00e9es, par exemple sous la forme de r\u00e9ductions ou de rabais sur les taxes sur l&rsquo;\u00e9nergie, qui sont \u00e9lev\u00e9es dans la plupart des pays de l&rsquo;Union. La France, par exemple, a introduit en f\u00e9vrier une r\u00e9duction d&rsquo;un an des taxes sur l&rsquo;\u00e9lectricit\u00e9 (pour un co\u00fbt de 8 milliards d&rsquo;euros, soit 0,3&#160;% du PIB) et, le 1er avril, une r\u00e9duction des taxes sur l&rsquo;essence de 15 centimes par litre pour une p\u00e9riode de 4 mois, pour un co\u00fbt estim\u00e9 \u00e0 2,2 milliards d&rsquo;euros, soit environ 0,1&#160;% du PIB&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-24-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-24-138270' title='Pour plus de d\u00e9tails sur les mesures fran\u00e7aises, appel\u00e9es bouclier tarifaire, voir Gouvernement fran\u00e7ais (2022).'><sup>24<\/sup><\/a><\/span><\/span>. Cette subvention est pr\u00e9sent\u00e9e comme un palliatif d&rsquo;urgence en attendant la mise en place d&rsquo;un syst\u00e8me plus cibl\u00e9 au d\u00e9but de l&rsquo;\u00e9t\u00e9. Elle est tr\u00e8s visible, ce qui constitue un avantage politique. Des r\u00e9ductions temporaires similaires des droits d&rsquo;accises ont \u00e9t\u00e9 introduites ailleurs, notamment en Allemagne o\u00f9, le 23 mars, la taxe sur l&rsquo;essence a \u00e9t\u00e9 abaiss\u00e9e de 30 centimes par litre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-25-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-25-138270' title='Voir ce document du gouvernement allemand du 23 mars&amp;#160;: &lt;a href=&quot;https:\/\/www.bundesfinanzministerium.de\/Content\/DE\/Downloads\/2022-03-23-massnahmenpaket-bund-hohe-energiekosten.pdf?__blob=publicationFile&amp;amp;v=3&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.bundesfinanzministerium.de\/Content\/DE\/Downloads\/2022-03-23-massnahmenpaket-bund-hohe-energiekosten.pdf?__blob=publicationFile&amp;amp;v=3&lt;\/a&gt;. Un autre &lt;a href=&quot;https:\/\/www.bundesfinanzministerium.de\/Content\/DE\/Downloads\/schutzschild-fuer-vom-krieg-betroffene-Unternehmen-massnahmenueberblick.pdf?__blob=publicationFile&amp;amp;v=3&quot;&gt;ensemble de mesures&lt;\/a&gt; en soutien des entreprises affect\u00e9es a \u00e9t\u00e9 mis en \u0153uvre le 8 avril.'><sup>25<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Transferts forfaitaires<\/strong><\/h4>\n\n\n\n<p>Une autre approche consiste \u00e0 fournir des transferts ind\u00e9pendants de la consommation de nourriture, de p\u00e9trole et de gaz. L&rsquo;Allemagne, par exemple, a introduit le 23 mars un transfert forfaitaire universel (Energiepreis-Pauschale) de 300 \u20ac par personne, plus des suppl\u00e9ments pour les enfants. La France a introduit l&rsquo;ann\u00e9e derni\u00e8re une indemnit\u00e9 de 100 euros, vers\u00e9e automatiquement aux personnes dont le revenu ne d\u00e9passe pas 2 000 euros par mois, pour un co\u00fbt de 3,8 milliards d&rsquo;euros, soit environ 0,2&#160;% du PIB&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-26-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-26-138270' title='Ce paiement a \u00e9t\u00e9 introduit en 2021, donc avant la guerre Russie-Ukraine, pour compenser la hausse d\u00e9j\u00e0 importante des prix de nombreuses mati\u00e8res premi\u00e8res en 2021.'><sup>26<\/sup><\/a><\/span><\/span>. Il est peu probable que ces mesures affectent sensiblement les prix du march\u00e9 pour les denr\u00e9es alimentaires, le p\u00e9trole et le gaz (uniquement dans la mesure o\u00f9 le revenu suppl\u00e9mentaire est d\u00e9pens\u00e9 pour ces biens), et ont donc pour effet que les transferts vont principalement aux consommateurs plut\u00f4t qu&rsquo;aux producteurs de mati\u00e8res premi\u00e8res.&nbsp;<\/p>\n\n\n\n<p>Il existe sans doute des solutions r\u00e9alisables pour cibler plus pr\u00e9cis\u00e9ment les transferts afin de mieux prot\u00e9ger ceux qui ont \u00e0 la fois un faible revenu et d\u00e9pensent une plus grande partie de celui-ci en nourriture, p\u00e9trole et gaz. Par exemple, dans le cas de l&rsquo;\u00e9lectricit\u00e9, on pourrait effectuer des transferts proportionnels \u00e0 une facture r\u00e9cente de services publics et, en les combinant avec les informations sur le revenu du m\u00e9nage, les limiter aux personnes dont le revenu est inf\u00e9rieur \u00e0 un certain seuil. Ou encore, on pourrait \u00e9mettre des ch\u00e8ques essence &#8211; une somme d&rsquo;argent donn\u00e9e \u00e0 d\u00e9penser uniquement en \u00e9nergie ou en essence &#8211;&#160;; en effet, un ch\u00e8que \u00e9nergie existe en France et un ch\u00e8que essence est en cours de discussion aux \u00c9tats-Unis. Dans la mesure o\u00f9 le ch\u00e8que est inf\u00e9rieur \u00e0 ce que le b\u00e9n\u00e9ficiaire d\u00e9pense en \u00e9nergie, cette mesure n&rsquo;affecte pas le prix marginal auquel il est confront\u00e9 et n&rsquo;affecte donc pas les incitations \u00e0 r\u00e9duire la consommation d&rsquo;\u00e9nergie. Son acceptabilit\u00e9 politique peut toutefois \u00eatre moindre que celle des subventions g\u00e9n\u00e9rales.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>R\u00e9glementation des prix<\/strong><\/h4>\n\n\n\n<p>Une autre approche encore consiste \u00e0 d\u00e9coupler certains prix, comme celui de l&rsquo;\u00e9lectricit\u00e9, de leur co\u00fbt marginal. Cette question est devenue particuli\u00e8rement importante en raison des fluctuations extr\u00eamement importantes du prix du march\u00e9 du gaz naturel, qui constitue le co\u00fbt marginal pertinent pour la production d&rsquo;\u00e9lectricit\u00e9. L&rsquo;Espagne, en particulier, a vivement critiqu\u00e9 l&rsquo;effet inflationniste de la tarification de l&rsquo;\u00e9lectricit\u00e9 et a obtenu en mars l&rsquo;autorisation de l&rsquo;Union de d\u00e9connecter temporairement la p\u00e9ninsule ib\u00e9rique du march\u00e9 europ\u00e9en de l&rsquo;\u00e9lectricit\u00e9. La France a demand\u00e9 \u00e0 la principale compagnie d&rsquo;\u00e9lectricit\u00e9 du pays de limiter la hausse des prix \u00e0 4&#160;% pour 2022 et de satisfaire la demande \u00e0 ce prix, demandant ainsi \u00e0 la compagnie d&rsquo;absorber une grande partie du co\u00fbt, ce qui entra\u00eene une forte diminution anticip\u00e9e des flux de tr\u00e9sorerie et une forte baisse de la valeur marchande. Cela entra\u00eene une inefficacit\u00e9, car le prix est inf\u00e9rieur au co\u00fbt marginal, mais permet une augmentation potentiellement importante du surplus du consommateur \u2014 au prix d&rsquo;une diminution plus importante du surplus du producteur. Du point de vue du bien-\u00eatre, le gain en revenu r\u00e9el des consommateurs pourrait bien dominer la perte d&rsquo;efficacit\u00e9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-27-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-27-138270' title='Pour en savoir plus sur les mesures prises par les membres de l&amp;rsquo;Union, notamment les subventions, les transferts et la r\u00e9glementation des prix, voir &lt;a href=&quot;https:\/\/www.bruegel.org\/publications\/datasets\/national-policies-to-shield-consumers-from-rising-energy-prices\/&quot;&gt;Sgaravatti, Tagliapietra, and Zachmann&lt;\/a&gt; (2022).'><sup>27<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La France a demand\u00e9 \u00e0 la principale compagnie d&rsquo;\u00e9lectricit\u00e9 du pays de limiter la hausse des prix \u00e0 4&#160;% pour 2022 et de satisfaire la demande \u00e0 ce prix, demandant ainsi \u00e0 la compagnie d&rsquo;absorber une grande partie du co\u00fbt, ce qui entra\u00eene une forte diminution anticip\u00e9e des flux de tr\u00e9sorerie et une forte baisse de la valeur marchande.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Effets pervers potentiels des subventions<\/strong><\/h4>\n\n\n\n<p>Deux objections principales peuvent \u00eatre soulev\u00e9es contre les subventions. La premi\u00e8re est qu&rsquo;elles augmentent la demande d&rsquo;\u00e9nergie, contribuant ainsi \u00e0 maintenir les prix de l&rsquo;\u00e9nergie \u00e0 un niveau \u00e9lev\u00e9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-28-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-28-138270' title='Ils vont \u00e9galement \u00e0 l&amp;rsquo;encontre de la n\u00e9cessit\u00e9 de d\u00e9carboner le syst\u00e8me \u00e9nerg\u00e9tique.'><sup>28<\/sup><\/a><\/span><\/span>. Cette question est bien connue et fait partie de la discussion traditionnelle de l&rsquo;incidence fiscale. Prenons l&rsquo;exemple des subventions aux diff\u00e9rentes utilisations du p\u00e9trole. L&rsquo;effet sur les prix \u00e0 la consommation d\u00e9pend de l&rsquo;\u00e9volution du prix du p\u00e9trole sur le march\u00e9. Si un seul pays utilise de telles subventions et qu&rsquo;il est petit par rapport au march\u00e9 mondial, le prix du march\u00e9 mondial ne changera pas et la subvention se traduira donc \u00e0 l&rsquo;identique par une baisse du prix \u00e0 la consommation. Toutefois, si tous les pays de l&rsquo;UE, et \u00e9ventuellement d&rsquo;autres pays comme les \u00c9tats-Unis, introduisent de telles subventions, la courbe d&rsquo;offre pertinente est la courbe d&rsquo;offre mondiale, qui est in\u00e9lastique \u00e0 court terme. \u00c0 l&rsquo;extr\u00eame, si la courbe d&rsquo;offre est totalement in\u00e9lastique, l&rsquo;effet sera d&rsquo;augmenter le prix du march\u00e9 \u00e0 l&rsquo;unit\u00e9 et de ne pas affecter le prix \u00e0 la consommation&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-29-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-29-138270' title='&amp;nbsp;La pente de la courbe d&amp;rsquo;offre a fait l&amp;rsquo;objet d&amp;rsquo;une &lt;a href=&quot;https:\/\/twitter.com\/jasonfurman\/status\/1496483717027618826?s=20&amp;amp;t=Q1d9GIf5i7J1c9T9XaI0UA&quot;&gt;discussion sur Twitter&lt;\/a&gt; entre Paul Krugman et Jason Furman.'><sup>29<\/sup><\/a><\/span><\/span>. En d&rsquo;autres termes, les subventions iront aux producteurs de p\u00e9trole, y compris la Russie. Dans la pratique, le r\u00e9sultat sera probablement inf\u00e9rieur \u00e0 l&rsquo;effet un pour un des subventions sur les prix du march\u00e9, mais il reste peu attrayant.&nbsp;<\/p>\n\n\n\n<p>La deuxi\u00e8me objection, plus sp\u00e9cifique mais tr\u00e8s pertinente, est de savoir si les subventions peuvent aller \u00e0 l&rsquo;encontre d&rsquo;un \u00e9ventuel futur tarif et renforcer en fait la position de la Russie dans sa confrontation avec l&rsquo;Union europ\u00e9enne. Comme nous l&rsquo;avons vu dans la section pr\u00e9c\u00e9dente, un tarif sur le gaz ferait baisser \u00e0 la fois le prix et le volume des exportations russes, tandis que les recettes correspondantes pourraient \u00eatre utilis\u00e9es pour att\u00e9nuer l&rsquo;impact sur les consommateurs. La question, cependant, est de savoir comment le faire au mieux. Une subvention directe du prix du gaz sur le march\u00e9 int\u00e9rieur, telle qu&rsquo;une baisse des taxes indirectes sur le gaz, augmenterait la demande de gaz et le prix pratiqu\u00e9 par la Russie, contrebalan\u00e7ant ainsi les effets des tarifs. Les gouvernements ne devraient pas utiliser les recettes d&rsquo;un tarif sur le gaz russe pour subventionner la consommation d&rsquo;\u00e9nergie au point de faire baisser le prix marginal du gaz sur le march\u00e9 europ\u00e9en. Ils devraient plut\u00f4t s&rsquo;appuyer sur des syst\u00e8mes de transfert qui n&rsquo;affectent pas le prix marginal.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les gouvernements ne devraient pas utiliser les recettes d&rsquo;un tarif sur le gaz russe pour subventionner la consommation d&rsquo;\u00e9nergie au point de faire baisser le prix marginal du gaz sur le march\u00e9 europ\u00e9en. Ils devraient plut\u00f4t s&rsquo;appuyer sur des syst\u00e8mes de transfert qui n&rsquo;affectent pas le prix marginal.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Imp\u00f4ts contre financement par la dette<\/strong><\/h3>\n\n\n\n<p>La question suivante est de savoir dans quelle mesure les dispositifs budg\u00e9taires doivent \u00eatre financ\u00e9s par des taxes suppl\u00e9mentaires ou par de la dette. Les recettes tarifaires peuvent aider, mais, comme nous l&rsquo;avons vu plus haut, il est peu probable que les droits de douane produisent beaucoup de recettes pour le p\u00e9trole \u2014 ils en produiront probablement davantage dans le cas du gaz.&nbsp;<\/p>\n\n\n\n<p>Les d\u00e9penses budg\u00e9taires discr\u00e9tionnaires imm\u00e9diates consistent essentiellement en des achats de d\u00e9fense (y compris pour la fourniture d&rsquo;armes \u00e0 l&rsquo;Ukraine), l&rsquo;aide aux r\u00e9fugi\u00e9s, des mesures de soutien aux m\u00e9nages et des investissements d&rsquo;urgence pour adapter le syst\u00e8me \u00e9nerg\u00e9tique. Selon nos hypoth\u00e8ses de prix, les co\u00fbts budg\u00e9taires vont de faibles \u00e0 g\u00e9rables&#160;: en 2022, ils ne devraient pas d\u00e9passer un sixi\u00e8me de point de pourcentage du PIB de l&rsquo;Union pour la d\u00e9fense, un tiers pour l&rsquo;aide aux r\u00e9fugi\u00e9s et, selon les d\u00e9cisions des diff\u00e9rents \u00c9tats membres, entre un demi et un point de pourcentage pour les mesures d&rsquo;aide aux m\u00e9nages&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-30-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-30-138270' title='Le programme de soutien allemand consiste en deux paquets d&amp;rsquo;environ 15 milliards d&amp;rsquo;euros chacun.'><sup>30<\/sup><\/a><\/span><\/span>. Une question plus d\u00e9licate est de savoir combien peuvent co\u00fbter les investissements \u00e9nerg\u00e9tiques d&rsquo;urgence. Nous ne disposons pas d&rsquo;une bonne estimation mais supposons qu&rsquo;elle ne devrait pas d\u00e9passer un demi-point de pourcentage. Au total, le co\u00fbt budg\u00e9taire discr\u00e9tionnaire de la guerre devrait donc rester dans une fourchette de 1,5 \u00e0 2&#160;% du PIB. Cela repr\u00e9senterait moins de la moiti\u00e9 du co\u00fbt budg\u00e9taire des mesures de soutien \u00e0 la pand\u00e9mie, qui, en Europe, s&rsquo;\u00e9levait g\u00e9n\u00e9ralement \u00e0 4&#160;% du PIB en 2020.&nbsp;<\/p>\n\n\n\n<p>Ces d\u00e9penses suppl\u00e9mentaires doivent-elles \u00eatre financ\u00e9es par les imp\u00f4ts ou la dette&#160;? Pour des raisons classiques en finances publiques, il existe de bons arguments pour s&rsquo;appuyer en partie sur le financement par l&#8217;emprunt. Une partie de l&rsquo;augmentation des d\u00e9penses sera probablement temporaire, ce qui justifie le lissage des imp\u00f4ts.&nbsp;<\/p>\n\n\n\n<p>Sur le plan de l&rsquo;\u00e9conomie politique, la notion de taxe de guerre \u2014 une \u00ab&#160;taxe Poutine&#160;\u00bb, comme l&rsquo;a appel\u00e9e le pr\u00e9sident Biden aux \u00c9tats-Unis, bien qu&rsquo;il ait fait r\u00e9f\u00e9rence \u00e0 la diminution du revenu r\u00e9el plut\u00f4t qu&rsquo;\u00e0 une taxe explicite \u2014 peut \u00eatre moins impopulaire que dans d&rsquo;autres circonstances et souligner le fait que, contrairement aux perceptions actuelles en Europe occidentale, une guerre, m\u00eame une guerre \u00e9conomique, n&rsquo;est pas gratuite.&nbsp;<\/p>\n\n\n\n<p>Cependant, pour des raisons de stabilisation macro\u00e9conomique, il existe de bons arguments en faveur d&rsquo;un large recours au financement par la dette. La diminution du revenu r\u00e9el de l&rsquo;Union europ\u00e9enne est importante et risque d&rsquo;entra\u00eener une baisse de la consommation. La demande d&rsquo;exportation de la Russie devrait \u00eatre consid\u00e9rablement r\u00e9duite. L&rsquo;incertitude accrue, qui a jou\u00e9 un r\u00f4le important dans la r\u00e9duction de la consommation et de l&rsquo;investissement pendant la crise de Covid, pourrait \u00e0 nouveau jouer un r\u00f4le substantiel. Un soutien budg\u00e9taire et le recours au financement par l&#8217;emprunt plut\u00f4t qu&rsquo;\u00e0 une augmentation des imp\u00f4ts pour compenser la hausse des d\u00e9penses seront probablement n\u00e9cessaires&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-31-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-31-138270' title='Il est int\u00e9ressant \u00e0 cet \u00e9gard que l&amp;rsquo;Allemagne ait d\u00e9cid\u00e9 de combiner les deux approches en finan\u00e7ant un fonds de d\u00e9fense par une dette de 3&amp;#160;% du PIB, tout en s&amp;rsquo;engageant \u00e0 financer l&amp;rsquo;augmentation permanente des d\u00e9penses militaires par les imp\u00f4ts.'><sup>31<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Contrairement aux perceptions actuelles en Europe occidentale, une guerre, m\u00eame une guerre \u00e9conomique, n&rsquo;est pas gratuite.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cela soul\u00e8ve la question classique de la viabilit\u00e9 de la dette (une question que l&rsquo;un des auteurs a longuement abord\u00e9e dans d&rsquo;autres \u00e9crits)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-32-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-32-138270' title='Olivier Blanchard, \u201cFiscal policy under low interest rates\u201d (2023).'><sup>32<\/sup><\/a><\/span><\/span>. S&rsquo;il est vrai que le ralentissement de l&rsquo;inflation n\u00e9cessitera des taux d&rsquo;int\u00e9r\u00eat r\u00e9els temporairement plus \u00e9lev\u00e9s, les facteurs \u00e0 l&rsquo;origine des faibles taux r\u00e9els neutres n&rsquo;ont pas chang\u00e9 et, pour autant que l&rsquo;inflation reste ma\u00eetris\u00e9e, de sorte que le risque d&rsquo;inflation ne commence pas \u00e0 \u00eatre pris en compte dans les taux obligataires r\u00e9els, le taux neutre devrait, apr\u00e8s une augmentation temporaire, redevenir faible \u00e0 moyen terme. Jusqu&rsquo;\u00e0 pr\u00e9sent, les taux obligataires de r\u00e9f\u00e9rence \u00e0 10 ans n&rsquo;ont augment\u00e9 que de 50 points de base depuis le d\u00e9but de la guerre, un ajustement \u00e0 la hausse limit\u00e9 compte tenu de l&rsquo;ampleur du choc g\u00e9opolitique et \u00e9conomique.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/uN91T\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>\u00c0 court terme, la dynamique de la dette devrait rester extr\u00eamement favorable. Dans les pr\u00e9visions de mars de la BCE (2022a) concernant la croissance du PIB r\u00e9el de la zone euro, les taux directeurs nominaux et l&rsquo;inflation pour 2022 sont de 3,7&#160;%, 0,8&#160;% (pour le rendement \u00e0 10 ans) et 5,1&#160;%. Cela implique une valeur pour (r &#8211; g) de (0,8&#160;% &#8211; 5,1&#160;% &#8211; 3,7&#160;%) = -8&#160;%&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-33-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-33-138270' title='La BCE donne \u00e9galement deux autres sc\u00e9narios, l&amp;rsquo;un d\u00e9favorable et l&amp;rsquo;autre s\u00e9v\u00e8re. Dans le sc\u00e9nario pessimiste, la croissance est de 2,3&amp;#160;%, le rendement \u00e0 10 ans de 0,8&amp;#160;% et l&amp;rsquo;inflation de 7,1&amp;#160;%, ce qui implique une valeur de (r &amp;#8211; g) de -8,6&amp;#160;%.'><sup>33<\/sup><\/a><\/span><\/span>. Associ\u00e9 \u00e0 un ratio d&rsquo;endettement de 98&#160;%, cela permettrait aux gouvernements de l&rsquo;Union dans leur ensemble d&rsquo;enregistrer des d\u00e9ficits primaires de 8&#160;% tout en maintenant des ratios d&rsquo;endettement constants. Il existe donc une marge de man\u0153uvre importante pour creuser temporairement des d\u00e9ficits plus importants si n\u00e9cessaire.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Politique mon\u00e9taire<\/strong><\/h3>\n\n\n\n<p>Le conseil g\u00e9n\u00e9rique donn\u00e9 \u00e0 une banque centrale confront\u00e9e \u00e0 une hausse des prix des produits de base est de tenir compte des effets de premier tour (elle ne peut de toute fa\u00e7on pas y faire grand-chose) et de limiter les effets de second tour, si n\u00e9cessaire par une baisse de la production et une hausse du ch\u00f4mage, jusqu&rsquo;\u00e0 ce que l&rsquo;inflation revienne \u00e0 l&rsquo;objectif (Blanchard et Gal\u00ed, 2007).<\/p>\n\n\n\n<p>On peut s&rsquo;attendre \u00e0 ce que les entreprises finissent par r\u00e9tablir leur taux de marge. Ainsi, le degr\u00e9 d&rsquo;intervention de la banque centrale pour ralentir l&rsquo;activit\u00e9 d\u00e9pend en grande partie du comportement des salaires. Ayant subi une baisse de leur salaire r\u00e9el au premier tour, les travailleurs voudront se rattraper et demanderont une augmentation du salaire nominal. Et s&rsquo;ils s&rsquo;attendent \u00e0 ce que l&rsquo;inflation reste \u00e9lev\u00e9e, ils demanderont en plus une croissance des salaires nominaux. La force de ce premier effet, le d\u00e9sir des travailleurs de rattraper leur retard, d\u00e9pend, entre autres facteurs, de l&rsquo;ampleur de la baisse du revenu r\u00e9el qu&rsquo;ils subissent au premier tour et de leur force de n\u00e9gociation, donc de l&rsquo;\u00e9troitesse du march\u00e9 du travail. La force du second effet, l&rsquo;inflation anticip\u00e9e, d\u00e9pend de la cr\u00e9dibilit\u00e9 de la strat\u00e9gie de la banque centrale et de son engagement \u00e0 ramener l&rsquo;inflation \u00e0 son objectif.&nbsp;<\/p>\n\n\n\n<p>Il existe dans ce contexte une interaction importante entre la politique budg\u00e9taire et la politique mon\u00e9taire. Pour revenir aux diff\u00e9rentes mesures de protection que les gouvernements peuvent utiliser&#160;: les subventions aux prix \u2014 dans la mesure o\u00f9 elles r\u00e9duisent m\u00e9caniquement la hausse des prix \u00e0 la consommation \u2014 ou les plafonds de prix (comme dans le cas de la dissociation du prix de l&rsquo;\u00e9lectricit\u00e9 de son co\u00fbt marginal) diminuent l&rsquo;inflation de premier tour et limitent ainsi la baisse initiale du salaire r\u00e9el. Cela diminue \u00e0 son tour la pression sur les salaires au cours des cycles suivants, ce qui permet \u00e0 la BCE de r\u00e9duire plus facilement l&rsquo;inflation au fil du temps. Les transferts n&rsquo;affectent pas l&rsquo;inflation de premier tour, mais ils limitent la baisse initiale du revenu r\u00e9el, r\u00e9duisant ainsi potentiellement la pression salariale au deuxi\u00e8me tour et aux tours suivants. En bref, une protection accrue et des d\u00e9ficits plus \u00e9lev\u00e9s r\u00e9duisent la n\u00e9cessit\u00e9 de resserrer la politique mon\u00e9taire pour ramener l&rsquo;inflation \u00e0 son objectif.&nbsp;<\/p>\n\n\n\n<p>Il existe donc un compromis clair&#160;: dans une perspective d&rsquo;efficacit\u00e9 ainsi que pour garantir l&rsquo;efficacit\u00e9 des sanctions, les gouvernements devraient \u00e9viter les mesures de soutien au revenu qui affaiblissent le signal des prix et peuvent en fait profiter \u00e0 la Russie. Mais du point de vue de la ma\u00eetrise de l&rsquo;inflation, ils devraient s&rsquo;appuyer sur des mesures qui ont un impact direct et mesurable sur les prix \u00e0 la consommation. Certaines mesures peuvent remplir les deux conditions (c&rsquo;est le cas des transferts bas\u00e9s sur la consommation \u00e9nerg\u00e9tique pass\u00e9e, si l\u2019indice des prix refl\u00e8te non pas le prix marginal, mais le prix moyen paye par les m\u00e9nages). Mais bon nombre des mesures introduites jusqu&rsquo;\u00e0 pr\u00e9sent ne passent pas le test.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Dans une perspective d&rsquo;efficacit\u00e9 ainsi que pour garantir l&rsquo;efficacit\u00e9 des sanctions, les gouvernements devraient \u00e9viter les mesures de soutien au revenu qui affaiblissent le signal des prix et peuvent en fait profiter \u00e0 la Russie. Mais du point de vue de la ma\u00eetrise de l&rsquo;inflation, ils devraient s&rsquo;appuyer sur des mesures qui ont un impact direct et mesurable sur les prix \u00e0 la consommation. Bon nombre des mesures introduites jusqu&rsquo;\u00e0 pr\u00e9sent ne passent pas le test.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Discussions tripartites sur les salaires<\/strong><\/h3>\n\n\n\n<p>On peut aller un peu plus loin et plaider en faveur de discussions tripartites, voire de n\u00e9gociations, entre les entreprises, les travailleurs et l&rsquo;\u00c9tat. Tant que les prix des mati\u00e8res premi\u00e8res restent \u00e9lev\u00e9s, les salaires r\u00e9els et\/ou les marges b\u00e9n\u00e9ficiaires doivent \u00eatre plus faibles. Comme nous l&rsquo;avons \u00e9voqu\u00e9, l&rsquo;\u00c9tat peut limiter la baisse du revenu r\u00e9el des travailleurs par le biais de subventions, de transferts et de r\u00e9glementations des prix, financ\u00e9s par une combinaison d&rsquo;imp\u00f4ts sur les plus ais\u00e9s ou par le financement par la dette, transf\u00e9rant une partie de la charge aux futurs contribuables. L&rsquo;inflation est un moyen extr\u00eamement inefficace de parvenir \u00e0 un r\u00e9sultat \u00e9quitable. Une n\u00e9gociation dans laquelle les travailleurs, les entreprises et l&rsquo;\u00c9tat s&rsquo;accordent sur un meilleur r\u00e9sultat et, par voie de cons\u00e9quence, sur une r\u00e9duction de la deuxi\u00e8me vague d&rsquo;inflation et des suivantes, est clairement souhaitable.<\/p>\n\n\n\n<p>Est-elle r\u00e9alisable&#160;? Le r\u00f4le de telles n\u00e9gociations sociales a longtemps \u00e9t\u00e9 d\u00e9battu, et la r\u00e9ponse habituelle est qu&rsquo;elles n\u00e9cessitent un degr\u00e9 irr\u00e9aliste de coordination au sein des entreprises et des syndicats. Cette fois-ci, il peut en \u00eatre autrement, et les n\u00e9gociations tripartites, ou au moins les discussions, sont une option que les gouvernements devraient envisager.&nbsp;<\/p>\n\n\n\n<p>Tout succ\u00e8s dans la r\u00e9duction de la taille des effets de second tour permet une politique mon\u00e9taire plus souple. Deux autres facteurs sont pertinents ici, bien qu&rsquo;ils fassent \u00e9voluer la politique mon\u00e9taire souhaitable dans des directions oppos\u00e9es&nbsp;&#160;: l\u2019ancrage des anticipation et la faiblesse de la demande priv\u00e9e.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>D\u00e9sancrage potentiel des anticipations<\/strong><\/h3>\n\n\n\n<p>L&rsquo;inflation due au choc des mati\u00e8res premi\u00e8res s&rsquo;ajoute \u00e0 un taux d&rsquo;inflation nettement sup\u00e9rieur \u00e0 celui qui \u00e9tait pr\u00e9vu pour 2021. M\u00eame avant la guerre, cette situation avait suscit\u00e9 des inqui\u00e9tudes quant \u00e0 un d\u00e9sancrage des anticipations d&rsquo;inflation, qui rendrait la t\u00e2che de la BCE plus difficile. Selon l&rsquo;enqu\u00eate de la BCE aupr\u00e8s des pr\u00e9visionnistes professionnels (BCE 2022b), les anticipations d&rsquo;inflation \u00e0 long terme ont commenc\u00e9 \u00e0 augmenter, la pr\u00e9vision moyenne passant de 1,8&#160;% au d\u00e9but de 2021 \u00e0 2,1&#160;% en avril 2022 (Lane 2022)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-34-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-34-138270' title='L&amp;rsquo;augmentation de 1,8&amp;#160;% \u00e0 2&amp;#160;% \u00e9tait souhaitable&amp;#160;; la question est de savoir si elle s&amp;rsquo;arr\u00eatera l\u00e0.'><sup>34<\/sup><\/a><\/span><\/span>. Il s&rsquo;agissait initialement d&rsquo;une \u00e9volution positive apr\u00e8s des ann\u00e9es pendant lesquelles l&rsquo;inflation anticip\u00e9e \u00e9tait trop basse, mais la crainte est maintenant que l&rsquo;inflation suppl\u00e9mentaire de premier tour due \u00e0 la guerre ne conduise \u00e0 un d\u00e9sancrage pur et simple. Comme l&rsquo;a r\u00e9cemment soulign\u00e9 Isabel Schnabel (2022), membre du conseil des gouverneurs de la BCE, cela plaide en faveur d&rsquo;une orientation de la politique mon\u00e9taire plus stricte lors des tours suivants que ce ne serait le cas en l&rsquo;absence d&rsquo;une inflation ant\u00e9rieure plus \u00e9lev\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les n\u00e9gociations tripartites, ou au moins les discussions, sont une option que les gouvernements devraient envisager.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La faiblesse potentielle de la demande priv\u00e9e<\/strong><\/h3>\n\n\n\n<p>L&rsquo;autre facteur pertinent est l&rsquo;effet des chocs li\u00e9s \u00e0 la guerre sur la demande globale. La diminution des exportations, les pertes d&rsquo;investissement et l&rsquo;\u00e9branlement de la confiance g\u00e9n\u00e9rale sont de bonnes raisons de penser que, m\u00eame avec un soutien budg\u00e9taire, la demande globale sera plus faible, ind\u00e9pendamment de tout resserrement mon\u00e9taire. Cela implique qu&rsquo;il est moins n\u00e9cessaire de resserrer la politique mon\u00e9taire que ce n&rsquo;\u00e9tait le cas avant la guerre et, toutes choses \u00e9gales par ailleurs, plaide en faveur d&rsquo;une politique mon\u00e9taire plus souple.&nbsp;<\/p>\n\n\n\n<p>Il est difficile d&rsquo;\u00e9valuer \u00e0 ce stade lequel de ces facteurs dominera et si la politique mon\u00e9taire de la BCE devra \u00eatre plus stricte ou plus souple que ce qui \u00e9tait pr\u00e9vu avant la guerre. L&rsquo;ampleur des chocs, la force des effets de second tour, l&rsquo;ancrage des anticipations d&rsquo;inflation et la faiblesse de la demande globale sont tous incertains. Les march\u00e9s ont du mal \u00e0 \u00e9valuer quel devrait \u00eatre l&rsquo;effet net sur la politique mon\u00e9taire&#160;: la courbe de rendement de l&rsquo;euro a fortement baiss\u00e9 au d\u00e9but de la guerre, mais elle est maintenant un peu plus haute qu&rsquo;avant la guerre (voir figure 4)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-35-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-35-138270' title='Voir par exemple les &lt;a href=&quot;https:\/\/www.ecb.europa.eu\/stats\/financial_markets_and_interest_rates\/euro_area_yield_curves\/html\/index.en.html&quot;&gt;courbes de rendement&lt;\/a&gt; du 23 f\u00e9vrier, du 3 mars et du 17 mars.'><sup>35<\/sup><\/a><\/span><\/span>. La position actuelle de la BCE, qui consiste \u00e0 ne pas proc\u00e9der \u00e0 des ajustements majeurs en raison de la guerre, semble \u00eatre la bonne \u00e0 ce stade&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-36-138270' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#easy-footnote-bottom-36-138270' title='Nous partageons donc largement l&amp;rsquo;analyse et les conclusions d&amp;rsquo;Isabel Schnabel (2022) dans son discours du 2 avril.'><sup>36<\/sup><\/a><\/span><\/span>. Mais la BCE devra ajuster sa position et faire preuve d&rsquo;une agilit\u00e9 exceptionnelle pour \u00e9viter une inflation durable ou une r\u00e9cession.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5 <\/strong><strong>\u2014<\/strong><strong> Conclusion<\/strong><\/h2>\n\n\n\n<p>Pour l&rsquo;Europe, la guerre en Ukraine est un choc \u00e9conomique de premier ordre. Si les implications budg\u00e9taires directes de la prise en charge des r\u00e9fugi\u00e9s, de l&rsquo;augmentation des d\u00e9penses militaires et du renforcement de l&rsquo;autonomie \u00e9nerg\u00e9tique restent limit\u00e9es, l&rsquo;impact de la hausse des prix de l&rsquo;\u00e9nergie et des denr\u00e9es alimentaires sur le revenu national et sa r\u00e9partition est potentiellement substantiel. Cela soul\u00e8ve trois d\u00e9fis macro\u00e9conomiques.<\/p>\n\n\n\n<p>Le premier est de savoir comment utiliser au mieux les sanctions pour dissuader la Russie tout en limitant les effets n\u00e9gatifs sur l&rsquo;\u00e9conomie de l&rsquo;Union. \u00c0 cet \u00e9gard, il est important de faire la distinction entre le p\u00e9trole et le gaz. Pour le p\u00e9trole, la Russie peut se diversifier en s&rsquo;\u00e9loignant du march\u00e9 de l&rsquo;Union et en vendant sur le march\u00e9 mondial o\u00f9 elle op\u00e8re en tant que preneur de prix. Les cons\u00e9quences sont que les retomb\u00e9es des sanctions de l&rsquo;Union sont mondiales et qu&rsquo;un embargo ou des droits de douane europ\u00e9ens sur le p\u00e9trole peuvent avoir des effets limit\u00e9s sur les prix du p\u00e9trole \u00e0 la consommation. Pour le gaz, l&rsquo;Union europ\u00e9enne et la Russie ont un pouvoir de marchandage. La Russie est presque enti\u00e8rement d\u00e9pendante de l&rsquo;infrastructure de gazoducs qui la relie au march\u00e9 europ\u00e9en. L\u2019Europe a un acc\u00e8s limit\u00e9 \u00e0 d\u2019autres sources de gaz, \u00e0 un cout potentiellement \u00e9lev\u00e9. Du point de vue de l\u2019Europe, un embargo sur le gaz n&rsquo;est pas envisageable. En revanche, les tarifs douaniers devraient \u00eatre partiellement efficaces et devraient \u00eatre envisag\u00e9s, malgr\u00e9 leurs effets probables sur les prix du gaz \u00e0 la consommation en Europe.<\/p>\n\n\n\n<p>Le deuxi\u00e8me d\u00e9fi est de savoir comment faire face \u00e0 la diminution du revenu r\u00e9el due \u00e0 l&rsquo;augmentation de la facture des importations d&rsquo;\u00e9nergie. Ici, deux questions se posent. Premi\u00e8rement, si les gouvernements veulent prot\u00e9ger partiellement les acheteurs \u2014 consommateurs et entreprises \u2014 contre l&rsquo;augmentation des prix, ils ont le choix entre plusieurs mesures, allant des subventions directes aux transferts cibl\u00e9s, en passant par les r\u00e9glementations et les plafonds de prix. Pour le gaz et, dans une moindre mesure, pour le p\u00e9trole, les subventions \u2014 en particulier les r\u00e9ductions d&rsquo;imp\u00f4ts g\u00e9n\u00e9ralis\u00e9es \u2014 peuvent partiellement annuler l&rsquo;effet des sanctions et ne sont donc pas souhaitables. Les transferts forfaitaires qui n&rsquo;affectent pas le prix marginal, et par cons\u00e9quent ne diminuent pas les incitations \u00e0 r\u00e9duire la demande, sont pr\u00e9f\u00e9rables, surtout s&rsquo;ils sont destin\u00e9s aux m\u00e9nages \u00e0 faible revenu et aux autres m\u00e9nages les plus touch\u00e9s. Deuxi\u00e8mement, les gouvernements doivent d\u00e9cider de comment financer les d\u00e9penses suppl\u00e9mentaires. Parce qu&rsquo;une partie des d\u00e9penses est temporaire et en raison de l&rsquo;incertitude, de la perte de revenu r\u00e9el et de la baisse des exportations vers la Russie, qui entra\u00eenent toutes une faible demande globale, un soutien budg\u00e9taire et donc un financement suppl\u00e9mentaire du d\u00e9ficit peuvent \u00eatre n\u00e9cessaires. M\u00eame si les d\u00e9ficits sont plus importants, compte tenu de l&rsquo;inflation \u00e9lev\u00e9e et des taux nominaux encore bas, les ratios d&rsquo;endettement devraient diminuer \u00e0 un horizon de deux ans, et la dette restera viable.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Pour le p\u00e9trole, la Russie peut se diversifier en s&rsquo;\u00e9loignant du march\u00e9 de l&rsquo;Union et en vendant sur le march\u00e9 mondial o\u00f9 elle op\u00e8re en tant que preneur de prix. Les cons\u00e9quences sont que les retomb\u00e9es des sanctions de l&rsquo;Union sont mondiales et qu&rsquo;un embargo ou des droits de douane europ\u00e9ens sur le p\u00e9trole peuvent avoir des effets limit\u00e9s sur les prix du p\u00e9trole \u00e0 la consommation.<\/p><cite>Olivier Blanchard et Jean Pisani-Ferry<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le troisi\u00e8me d\u00e9fi macro\u00e9conomique consiste \u00e0 faire face \u00e0 l&rsquo;augmentation de l&rsquo;inflation due \u00e0 la hausse des prix de l&rsquo;\u00e9nergie et des denr\u00e9es alimentaires. Deux forces sont \u00e0 l&rsquo;\u0153uvre. La premi\u00e8re est la n\u00e9cessit\u00e9 d&rsquo;\u00e9viter un d\u00e9sancrage des anticipations d&rsquo;inflation, un d\u00e9fi plus grand que d&rsquo;habitude \u00e9tant donn\u00e9 que l&rsquo;inflation avait d\u00e9j\u00e0 consid\u00e9rablement augment\u00e9 avant la guerre. Pr\u00e9venir ce risque n\u00e9cessiterait un resserrement de la politique mon\u00e9taire. La deuxi\u00e8me est que la perte de revenu r\u00e9el est susceptible d&rsquo;entra\u00eener, m\u00eame avec une certaine compensation budg\u00e9taire, un affaiblissement de la demande globale, ce qui implique la n\u00e9cessit\u00e9 d\u2019assouplir la politique. Le d\u00e9fi pour les d\u00e9cideurs politiques est donc de faire face \u00e0 ces objectifs contradictoires. Dans ce contexte, les instruments de politique publique se compl\u00e8tent. La combinaison d&rsquo;un soutien budg\u00e9taire bien con\u00e7u aux m\u00e9nages et d&rsquo;une discussion tripartite sur les salaires peut contribuer \u00e0 am\u00e9liorer l&rsquo;arbitrage auquel la banque centrale est confront\u00e9e.&nbsp;<\/p>\n\n\n\n<p>Pour chacune de ces trois dimensions, il existe une grande incertitude quant au r\u00e9sultat. Les prix de l&rsquo;\u00e9nergie peuvent augmenter beaucoup plus qu&rsquo;ils ne l&rsquo;ont fait jusqu&rsquo;\u00e0 pr\u00e9sent, ou au contraire revenir aux niveaux d&rsquo;avant-guerre. Par cons\u00e9quent, la perte de revenu r\u00e9el et la pression inflationniste peuvent \u00eatre beaucoup plus importantes, ou au contraire constituer un probl\u00e8me moins important que pr\u00e9vu actuellement. Ceci nous am\u00e8ne \u00e0 notre derni\u00e8re conclusion. La politique budg\u00e9taire et la politique mon\u00e9taire doivent \u00eatre souples, constitu\u00e9es de mesures faciles \u00e0 ajuster en fonction des besoins, et non de mesures p\u00e9rennes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aucune guerre n&rsquo;est gratuite. Pour l&rsquo;Europe, l&rsquo;invasion de l&rsquo;Ukraine est un choc \u00e9conomique de premier ordre. Dans cette pi\u00e8ce de doctrine, Olivier Blanchard et Jean Pisani-Ferry articulent une r\u00e9ponse macro\u00e9conomique.<\/p>\n","protected":false},"author":10,"featured_media":138288,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-editorials.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":65,"footnotes":""},"categories":[1730],"tags":[],"staff":[2264,2545],"editorial_format":[4941],"serie":[],"audience":[],"geo":[1917],"class_list":["post-138270","post","type-post","status-publish","format-standard","hentry","category-energie-et-environnement","staff-jean-pisani-ferry","staff-olivier-blanchard","editorial_format-doctrine","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":138288,"excerpt":"Aucune guerre n'est gratuite. Pour l'Europe, l'invasion de l'Ukraine est un choc \u00e9conomique de premier ordre. Dans cette pi\u00e8ce de doctrine, Olivier Blanchard et Jean Pisani-Ferry articulent une r\u00e9ponse macro\u00e9conomique.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Une politique \u00e9conomique de guerre | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une politique \u00e9conomique de guerre | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Aucune guerre n&#039;est gratuite. Pour l&#039;Europe, l&#039;invasion de l&#039;Ukraine est un choc \u00e9conomique de premier ordre. Dans cette pi\u00e8ce de doctrine, Olivier Blanchard et Jean Pisani-Ferry articulent une r\u00e9ponse macro\u00e9conomique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-28T15:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-11T08:20:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/gc-bpis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/gc-bpis.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"65 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/\",\"name\":\"Une politique \u00e9conomique de guerre | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg\",\"datePublished\":\"2022-04-28T15:30:37+00:00\",\"dateModified\":\"2022-05-11T08:20:09+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"In this Jan. 19, 2019, photo provided by the U.S. Navy, the entrance to Tank 19 at the Red Hill Underground Fuel Storage Facility near Pearl Harbor, Hawaii, is seen. The Navy is scrambling to contain what one lawmaker has called a \\\"crisis of astronomical proportions\\\" after jet fuel leaked from an 80-year-old Hawaii tank farm, seeped into a drinking water well and polluted the water streaming out of faucets in Pearl Harbor military housing. (Shannon Haney\/U.S. Navy via AP)\/SE310\/22019783293621\/AP PROVIDES ACCESS TO THIS PUBLICLY DISTRIBUTED HANDOUT PHOTO PROVIDED BY U.S. ARMY CORPS OF ENGINEERS. MANDATORY CREDIT.\/2202051510\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une politique \u00e9conomique de guerre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une politique \u00e9conomique de guerre | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/","og_locale":"fr_FR","og_type":"article","og_title":"Une politique \u00e9conomique de guerre | Le Grand Continent","og_description":"Aucune guerre n'est gratuite. Pour l'Europe, l'invasion de l'Ukraine est un choc \u00e9conomique de premier ordre. Dans cette pi\u00e8ce de doctrine, Olivier Blanchard et Jean Pisani-Ferry articulent une r\u00e9ponse macro\u00e9conomique.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/","og_site_name":"Le Grand Continent","article_published_time":"2022-04-28T15:30:37+00:00","article_modified_time":"2022-05-11T08:20:09+00:00","og_image":[{"width":952,"height":536,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/gc-bpis.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/gc-bpis.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"65 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/","name":"Une politique \u00e9conomique de guerre | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg","datePublished":"2022-04-28T15:30:37+00:00","dateModified":"2022-05-11T08:20:09+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg","width":1707,"height":2560,"caption":"In this Jan. 19, 2019, photo provided by the U.S. Navy, the entrance to Tank 19 at the Red Hill Underground Fuel Storage Facility near Pearl Harbor, Hawaii, is seen. The Navy is scrambling to contain what one lawmaker has called a \"crisis of astronomical proportions\" after jet fuel leaked from an 80-year-old Hawaii tank farm, seeped into a drinking water well and polluted the water streaming out of faucets in Pearl Harbor military housing. (Shannon Haney\/U.S. Navy via AP)\/SE310\/22019783293621\/AP PROVIDES ACCESS TO THIS PUBLICLY DISTRIBUTED HANDOUT PHOTO PROVIDED BY U.S. ARMY CORPS OF ENGINEERS. MANDATORY CREDIT.\/2202051510"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/28\/une-politique-economique-de-guerre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Une politique \u00e9conomique de guerre"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1730,"name":"\u00c9nergie et environnement","slug":"energie-et-environnement"}],"lgc_author":{"id":2264,"name":"Jean Pisani-Ferry","slug":"jean-pisani-ferry","description":"<span style=\"font-weight: 400\">Jean Pisani-Ferry est senior fellow non r\u00e9sident au Peterson Institute for International Economics. Il est titulaire de la chaire Tommaso Padoa-Schioppa de l'Institut universitaire europ\u00e9en de Florence et est senior fellow chez Bruegel, le think tank europ\u00e9en. Il enseigne \u00e9galement \u00e0 Sciences Po Paris.\u00a0<\/span>","first_name":"Jean","last_name":"Pisani-Ferry","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/06\/Jean_Pisani-Ferry_par_Claude_Truong-Ngoc_janvier_2016-modified.png","width":800,"height":800,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg","width":1707,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/SIPA_AP22648929_000001-scaled.jpg","width":1707,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/138270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=138270"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/138270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/138288"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=138270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=138270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=138270"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=138270"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=138270"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=138270"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=138270"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=138270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}