{"id":136149,"date":"2022-04-08T17:17:55","date_gmt":"2022-04-08T15:17:55","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=136149"},"modified":"2023-10-11T11:35:40","modified_gmt":"2023-10-11T09:35:40","slug":"trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/","title":{"rendered":"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Hier, le 7 avril 2022, les 193 pays du monde \u00e9taient appel\u00e9s \u00e0 voter sur une r\u00e9solution \u00e0 l\u2019ONU visant \u00e0 suspendre la Russie du Conseil des droits de l\u2019homme des Nations Unies. Ce vote intervient apr\u00e8s la d\u00e9couverte des exactions de l\u2019arm\u00e9e russe sur des civils au Nord de Kiev, dans la localit\u00e9 de Boutcha. Les dirigeants russes ont ni\u00e9 \u00eatre impliqu\u00e9s dans ces massacres, mais les images satellites semblent confirmer l\u2019implication de l\u2019arm\u00e9e russe dans ces crimes de guerre.&nbsp;<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/6fjiG\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le vote sur la suspension de la Russie du Conseil des droits de l\u2019homme a \u00e9t\u00e9 bien plus partag\u00e9 que le dernier vote \u00e0 l\u2019Assembl\u00e9e g\u00e9n\u00e9rale des Nations unies sur la condamnation de l\u2019agression militaire russe de l\u2019Ukraine, le 2 mars 2022. Alors que 141 pays s\u2019\u00e9taient prononc\u00e9s en faveur de la condamnation, il n\u2019y a que 93 pays qui ont vot\u00e9 pour la suspension. Seulement cinq pays s\u2019\u00e9taient oppos\u00e9s \u00e0 la r\u00e9solution du 2 mars 2022, alors que vingt-quatre pays se sont oppos\u00e9s \u00e0 la suspension de la Russie du Conseil des droits de l\u2019homme des Nations Unies. Enfin, l\u2019abstention a augment\u00e9, avec 58 pays s\u2019\u00e9tant abstenus le 7 avril contre 35 le 2 mars.&nbsp;<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/3xEBR\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si on compare les deux cartes, on remarque que les Europ\u00e9ens, les \u00c9tats-Unis, le Canada et leurs alli\u00e9s \u2013 Cor\u00e9e du Sud, Japon, Australie, Nouvelle-Z\u00e9lande \u2013 restent soud\u00e9s face \u00e0 l\u2019action de la Russie. M\u00eame la Serbie et la Hongrie, dont les gouvernements sont proches de la Russie de Vladimir Poutine, ont vot\u00e9 \u00e0 deux reprises les r\u00e9solutions contre la Russie. En revanche, en Afrique, au Moyen-Orient et en Asie, les lignes de fractures demeurent, voire se renforcent.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En Afrique, alors que seule l\u2019Erythr\u00e9e s\u2019\u00e9tait positionn\u00e9e du c\u00f4t\u00e9 de la Russie le 2 mars, l\u2019Ethiopie, l\u2019Alg\u00e9rie, le Mali, la R\u00e9publique centrafricaine, le Burundi, le Congo, le Gabon et l\u2019Angola ont aussi vot\u00e9 contre la suspension de la Russie, le 7 avril. Environ la moiti\u00e9 des pays africains se sont abstenus ou n\u2019ont pas pris part au vote hier. Seulement neuf pays africains ont vot\u00e9 en faveur de la r\u00e9solution lors du vote au Conseil des droits de l\u2019homme de l&rsquo;ONU.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En Am\u00e9rique Latine, les trois pays s\u2019\u00e9tant abstenus le 2 mars \u2013 Cuba, Bolivie, Nicaragua \u2013 ont vot\u00e9 contre le 7 avril. Le V\u00e9n\u00e9zuela n\u2019a de nouveau pas particip\u00e9 au vote. De surcro\u00eet, le Br\u00e9sil et le Mexique se sont abstenus, tout comme le Guyana, le Suriname et le Salvador, alors que ces pays avaient vot\u00e9 pour condamner l\u2019agression militaire russe le 2 mars. En ce qui concerne le Br\u00e9sil, cela confirme les d\u00e9clarations du pr\u00e9sident Jair Bolsonaro, qui a expliqu\u00e9 vouloir rester \u201cneutre\u201d dans le conflit entre l\u2019Ukraine et la Russie, propos qui \u00e9taient en contradiction avec le premier vote du Br\u00e9sil sur le sujet \u00e0 l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU. Tous les autres pays d\u2019Am\u00e9rique latine et centrale ont confirm\u00e9 leur premier vote, en se pronon\u00e7ant pour la suspension de la Russie du Conseil des droits de l\u2019homme des Nations Unies<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Au Moyen-Orient, la majorit\u00e9 des pays qui profitent de leur alliance avec la Russie au sein de l\u2019OPEP+ pour maintenir les prix du p\u00e9trole et du gaz \u00e0 de hauts niveaux, se sont abstenus hier. Seul l\u2019Iran a rejoint la Syrie pour voter contre la suspension de la Russie. Isra\u00ebl et la Turquie se sont d\u00e9marqu\u00e9s et ont vot\u00e9 pour cette suspension. Dans le Caucase, l&rsquo;Arm\u00e9nie et l\u2019Azerba\u00efdjan n\u2019ont pas pris part au vote, tandis que la G\u00e9orgie a vot\u00e9 pour la r\u00e9solution.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En Asie Centrale, les pays membres de l\u2019OTSC \u2013 Kazakhstan, Tadjikistan, Kirghizistan \u2013 ont d\u00e9cid\u00e9 de voter contre, alors qu\u2019un mois plut\u00f4t, ils avaient juste choisi de s\u2019abstenir. La Chine et l\u2019Inde avaient agi de la m\u00eame mani\u00e8re, en s\u2019abstenant les 25 f\u00e9vrier et\u00a0 2 mars, lors des votes au Conseil de s\u00e9curit\u00e9 et de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU condamnant l\u2019action de la Russie. Cette fois-ci, l\u2019Inde s\u2019est encore abstenue, mais la Chine est all\u00e9e jusqu\u2019\u00e0 voter contre la suspension de la Russie, accompagn\u00e9e par le Vietnam et le Laos dans cette d\u00e9marche. La Cor\u00e9e du Nord a quant \u00e0 elle une nouvelle fois vot\u00e9 en se pla\u00e7ant du c\u00f4t\u00e9 de la Russie. Le vote du Myanmar n\u2019est pas repr\u00e9sentatif du pouvoir en place, car le pays est dirig\u00e9 par une junte militaire \u2013 alli\u00e9e de la Russie \u2013\u00a0 depuis f\u00e9vrier 2021.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/JD01W\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En d\u00e9finitive, la carte du vote du 7 avril, ressemble plus \u00e0 la carte des r\u00e9actions imm\u00e9diates des 193 pays du monde apr\u00e8s l\u2019invasion de l\u2019Ukraine par la Russie le 24 f\u00e9vrier qu\u2019\u00e0 celle du vote \u00e0 l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019ONU.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pour comprendre la tectonique des plaques g\u00e9opolitiques caus\u00e9e par la guerre en Ukraine, on peut analyser trois cartes qui montrent l\u2019\u00e9volution des positions diplomatiques des 193 pays du monde depuis l\u2019invasion de l\u2019Ukraine par la Russie le 24 f\u00e9vrier. Ces \u00e9volutions permettent d\u2019apercevoir les nouvelles alliances du monde en reconfiguration dans les ann\u00e9es Vingt.<\/p>\n","protected":false},"author":1971,"featured_media":136177,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[1731],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[2163],"class_list":["post-136149","post","type-post","status-publish","format-standard","hentry","category-politique","editorial_format-actu-breves","geo-monde"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":136177,"excerpt":"Pour comprendre la tectonique des plaques g\u00e9opolitiques caus\u00e9e par la guerre en Ukraine, on peut analyser trois cartes qui montrent l\u2019\u00e9volution des positions diplomatiques des 193 pays du monde depuis l\u2019invasion de l\u2019Ukraine par la Russie le 24 f\u00e9vrier. Ces \u00e9volutions permettent d\u2019apercevoir les nouvelles alliances du monde en reconfiguration dans les ann\u00e9es Vingt.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Pour comprendre la tectonique des plaques g\u00e9opolitiques caus\u00e9e par la guerre en Ukraine, on peut analyser trois cartes qui montrent l\u2019\u00e9volution des positions diplomatiques des 193 pays du monde depuis l\u2019invasion de l\u2019Ukraine par la Russie le 24 f\u00e9vrier. Ces \u00e9volutions permettent d\u2019apercevoir les nouvelles alliances du monde en reconfiguration dans les ann\u00e9es Vingt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T15:17:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T09:35:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"antoinecrouzet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"antoinecrouzet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/\",\"name\":\"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png\",\"datePublished\":\"2022-04-08T15:17:55+00:00\",\"dateModified\":\"2023-10-11T09:35:40+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/ee462dd0600baa2d22814bab6037fcff\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png\",\"width\":1240,\"height\":792},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/ee462dd0600baa2d22814bab6037fcff\",\"name\":\"antoinecrouzet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/329b17fa4fbf90afa92f6cb149268531?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/329b17fa4fbf90afa92f6cb149268531?s=96&d=mm&r=g\",\"caption\":\"antoinecrouzet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/","og_locale":"fr_FR","og_type":"article","og_title":"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine | Le Grand Continent","og_description":"Pour comprendre la tectonique des plaques g\u00e9opolitiques caus\u00e9e par la guerre en Ukraine, on peut analyser trois cartes qui montrent l\u2019\u00e9volution des positions diplomatiques des 193 pays du monde depuis l\u2019invasion de l\u2019Ukraine par la Russie le 24 f\u00e9vrier. Ces \u00e9volutions permettent d\u2019apercevoir les nouvelles alliances du monde en reconfiguration dans les ann\u00e9es Vingt.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/","og_site_name":"Le Grand Continent","article_published_time":"2022-04-08T15:17:55+00:00","article_modified_time":"2023-10-11T09:35:40+00:00","og_image":[{"width":1240,"height":792,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png","type":"image\/png"}],"author":"antoinecrouzet","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png","twitter_misc":{"\u00c9crit par":"antoinecrouzet","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/","name":"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png","datePublished":"2022-04-08T15:17:55+00:00","dateModified":"2023-10-11T09:35:40+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/ee462dd0600baa2d22814bab6037fcff"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png","width":1240,"height":792},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/04\/08\/trois-cartes-pour-comprendre-le-bouleversement-geopolitique-que-constitue-la-guerre-en-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Trois cartes pour comprendre le bouleversement g\u00e9opolitique que constitue la guerre en Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/ee462dd0600baa2d22814bab6037fcff","name":"antoinecrouzet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/329b17fa4fbf90afa92f6cb149268531?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/329b17fa4fbf90afa92f6cb149268531?s=96&d=mm&r=g","caption":"antoinecrouzet"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/04\/6fjiG-vote-sur-la-suspension-du-statut-de-membre-du-conseil-des-droits-de-l-homme-des-nations-unies-de-la-russie-nbsp-.png","width":1240,"height":792,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/136149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1971"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=136149"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/136149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/136177"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=136149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=136149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=136149"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=136149"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=136149"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=136149"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=136149"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=136149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}