{"id":135405,"date":"2022-03-31T11:13:30","date_gmt":"2022-03-31T09:13:30","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=135405"},"modified":"2022-03-31T15:27:16","modified_gmt":"2022-03-31T13:27:16","slug":"les-reves-contraries-douverture-a-lest-de-viktor-orban","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/","title":{"rendered":"Les r\u00eaves contrari\u00e9s \u00ab&#160;d\u2019ouverture \u00e0 l\u2019Est&#160;\u00bb de Viktor Orb\u00e1n"},"content":{"rendered":"\n<div class=\"wp-block-lgc-keypoints key-block\"><div class=\"keys\"><h6 class=\"font-fold text-sm uppercase\">Key Points<\/h6>\n<ul class=\"wp-block-list\"><li><span style=\"color: initial;\">Avec la guerre qui menace tant depuis l\u2019Ukraine que depuis les rangs de l\u2019opposition, le Premier ministre Viktor Orb\u00e1n endosse son r\u00f4le favori de d\u00e9fenseur de la nation en danger. La derni\u00e8re campagne d\u2019affichage en date montre Orb\u00e1n en tenue quasi militaire, appelant \u00e0 prot\u00e9ger la paix et la s\u00e9curit\u00e9 du pays.<\/span><\/li><li>Mais gr\u00e2ce \u00e0 son tout-puissant empire m\u00e9diatique, Viktor Orb\u00e1n  a r\u00e9ussi \u00e0 tourner la guerre en Ukraine \u00e0 son avantage. S&rsquo;il semble s\u2019\u00eatre assur\u00e9 sa r\u00e9\u00e9lection au 3 avril prochain, la question de sa majorit\u00e9 des deux tiers au parlement reste en suspens.<\/li><li>Si la guerre en Ukraine profite largement \u00e0 Viktor Orb\u00e1n sur le plan interne, elle \u00e9branle s\u00e9rieusement sa politique \u00e9trang\u00e8re en d\u00e9montrant toutes les limites de son \u00ab&#160;&nbsp;l\u2019Ouverture \u00e0 l\u2019Est&nbsp;&#160;\u00bb \u2013 et risque d&rsquo;accentuer son isolement au niveau europ\u00e9en.<\/li><\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"has-drop-cap\">Le 24 f\u00e9vrier au matin, Viktor Orb\u00e1n a d\u00fb se r\u00e9veiller bien contrari\u00e9. Alors que le monde entier apprenait avec effroi le d\u00e9clenchement de la guerre en Ukraine, le Premier ministre hongrois rassemblait ses hommes en urgence&nbsp;&#160;: comment devait-il, lui le grand promoteur d\u2019un rapprochement avec le Kremlin, l\u2019ami de Vladimir Poutine, r\u00e9agir \u00e0 ce bouleversement&nbsp;&#160;? Viktor Orb\u00e1n vise un quatri\u00e8me mandat d&rsquo;affil\u00e9e aux \u00e9lections l\u00e9gislatives du 3 avril, et il ne faudrait pas que sa proximit\u00e9 avec le Kremlin se retourne contre lui au dernier moment.&nbsp;<\/p>\n\n\n\n<p>Pendant qu\u2019Orb\u00e1n et ses troupes doutaient, les partis de l\u2019opposition, sous la direction de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/02\/peter-marki-zay-le-style-technocrate-de-lorbanien-qui-defie-orban\/\">leur candidat commun P\u00e9ter M\u00e1rki-Zay<\/a>, ont d\u00fb se r\u00e9jouir. Le soir m\u00eame, ils se r\u00e9unissaient en face de l\u2019ambassade de Russie. Certes pour exprimer leur soutien envers l\u2019Ukraine, mais surtout pour s\u2019attaquer au Premier ministre, qu\u2019il devenait alors si facile d\u2019associer au dictateur criminel russe. M\u00e1rki-Zay, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/13\/qui-etes-vous-peter-marki-zay\/\">qui n\u2019a toujours pas sa langue dans sa poche<\/a>, l\u2019accusait ainsi d\u2019\u00eatre \u00ab&#160;<em>un tra\u00eetre \u00e0 la patrie<\/em>\u00ab&#160;, quasiment \u00ab&#160;<em>coresponsable<\/em>&#160;\u00bb de la guerre en Ukraine.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Viktor Orb\u00e1n vise un quatri\u00e8me mandat d&rsquo;affil\u00e9e aux \u00e9lections l\u00e9gislatives du 3 avril, et il ne faudrait pas que sa proximit\u00e9 avec le Kremlin se retourne contre lui au dernier moment.<\/p><cite>Thomas Laffitte<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00ab&#160;&nbsp;L\u2019Ouverture \u00e0 l\u2019Est&nbsp;&#160;\u00bb de Viktor Orb\u00e1n<\/strong><\/h2>\n\n\n\n<p>Il faut dire que les liens tiss\u00e9s par Viktor Orb\u00e1n entre son pays et le g\u00e9ant russe sont nombreux et d\u2019importance. La d\u00e9pendance au gaz d\u2019abord&nbsp;&#160;: entre 80&#160;% et 90&#160;% des besoins en gaz de la Hongrie sont assur\u00e9s par des importations russes. Un \u00e9l\u00e9ment qui peut \u00eatre nuanc\u00e9 par la d\u00e9pendance g\u00e9n\u00e9rale des Europ\u00e9ens dans ce domaine, mais qui demeure en r\u00e9alit\u00e9 essentiel pour comprendre le volontarisme hongrois. Baisser le prix des \u00e9nergies pour les m\u00e9nages est l\u2019une des pierres angulaires de la strat\u00e9gie gouvernementale. En septembre dernier, Budapest signait m\u00eame un contrat de 15 ans avec le g\u00e9ant russe de l\u2019\u00e9nergie Gazprom, pour un tarif pr\u00e9f\u00e9rentiel. Alors que le prix du gaz atteint des sommets, le Fidesz sait qu\u2019il ne peut pas risquer de contrarier son \u00e9lectorat, biberonn\u00e9 aux prix bas de l\u2019\u00e9nergie, et qui souffre d\u00e9j\u00e0 de l\u2019inflation et de l\u2019effondrement du forint.<\/p>\n\n\n\n<p>Cependant, le rapprochement magyaro-russe va bien au-del\u00e0 de la seule question du gaz. D\u00e8s son retour aux affaires en 2010, celui qui se fit conna\u00eetre en 1989 par son cri d\u2019amour envers l\u2019Occident et son rejet de l\u2019occupation sovi\u00e9tique, lan\u00e7ait en grande pompe son \u00ab&#160;&nbsp;Ouverture \u00e0 l\u2019Est&nbsp;&#160;\u00bb. Un changement id\u00e9ologique aussi spectaculaire que total. Au fil des ann\u00e9es, Viktor Orb\u00e1n d\u00e9veloppe une doctrine se fondant sur la pr\u00e9somption du d\u00e9clin irr\u00e9versible de l\u2019Occident, au profit d\u2019un Est dont l\u2019ascension au sommet est d\u00e9sormais in\u00e9luctable. La Turquie d\u2019Erdogan, la Chine de Xi Jinping et bien s\u00fbr, la Russie de Vladimir Poutine sont pr\u00e9sent\u00e9es comme les futurs ma\u00eetres du jeu, avec lesquels la Hongrie serait bien inspir\u00e9e de s\u2019associer.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Alors que le prix du gaz atteint des sommets, le Fidesz sait qu\u2019il ne peut pas risquer de contrarier son \u00e9lectorat, biberonn\u00e9 aux prix bas de l\u2019\u00e9nergie, et qui souffre d\u00e9j\u00e0 de l\u2019inflation et de l\u2019effondrement du forint.<\/p><cite>Thomas Laffitte<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le corollaire d\u2019une telle vision du monde est <a href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/06\/21\/la-doctrine-dorban\/\">la d\u00e9nonciation de \u00ab&#160;&nbsp;Bruxelles&nbsp;&#160;\u00bb<\/a> et de toutes ces institutions occidentales qui privent les Hongrois de leur libert\u00e9, voire les exploitent pour leurs propres int\u00e9r\u00eats. Pour autant, cette doctrine reste largement \u00e0 l\u2019\u00e9tat de discours&nbsp;&#160;: sans les fonds structurels de l\u2019Union et les investissements des partenaires europ\u00e9ens, la petite Hongrie ne m\u00e8nerait pas large. Elle reste d\u2019ailleurs absolument fid\u00e8le \u00e0 l\u2019OTAN, Orb\u00e1n \u00e9tant m\u00eame l\u2019un des principaux promoteurs d\u2019une arm\u00e9e europ\u00e9enne commune.&nbsp;<\/p>\n\n\n\n<p>En 2014, l\u2019ouverture \u00e0 l\u2019Est a toutefois pris un tournant tr\u00e8s concret. De retour de Moscou, Viktor Orb\u00e1n prend tout le pays de court \u2013 y compris dans son propre parti \u2013 en annon\u00e7ant avoir confi\u00e9 au g\u00e9ant russe du nucl\u00e9aire Rosatom le gigantesque chantier de r\u00e9novation de l\u2019unique centrale atomique hongroise. Ce gigantesque projet industriel, d\u00e9nomm\u00e9 \u00ab&#160;&nbsp;Paks II&nbsp;&#160;\u00bb et estim\u00e9 \u00e0 pr\u00e8s de 12,5 milliards d\u2019euros, deviendrait ainsi le projet industriel le plus cher jamais entrepris en Hongrie. Principalement financ\u00e9 par une banque russe, ce chantier lie la Hongrie \u00e0 la Russie pour les d\u00e9cennies \u00e0 venir autour d\u2019une centrale qui fournit pr\u00e8s de la moiti\u00e9 de l\u2019\u00e9lectricit\u00e9 du pays.&nbsp;<\/p>\n\n\n\n<p>D\u2019autres dossiers t\u00e9moignent de la profondeur des liens magyaro-russes. En 2013, Budapest lan\u00e7ait en catimini un programme dit de <em>\u00ab&#160;&nbsp;visa&nbsp;dor\u00e9&#160;\u00bb <\/em>(golden visa). La Hongrie a ainsi propos\u00e9 jusqu\u2019en 2016 un programme tr\u00e8s g\u00e9n\u00e9reux offrant \u00e0 vie la r\u00e9sidence en Hongrie et l\u2019acc\u00e8s \u00e0 Schengen pour toute une famille, contre seulement 300 000 euros investis dans des bons du Tr\u00e9sor hongrois sur cinq ann\u00e9es. Le programme a pris fin en 2016 apr\u00e8s que plusieurs milliers de <em>visas dor\u00e9s <\/em>ont \u00e9t\u00e9 vendus dans la plus grande opacit\u00e9. De nombreux journalistes ind\u00e9pendants suspectent que ce programme ait largement b\u00e9n\u00e9fici\u00e9 \u00e0 des ressortissants russes.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En 2014, l\u2019ouverture \u00e0 l\u2019Est a toutefois pris un tournant tr\u00e8s concret. De retour de Moscou, Viktor Orb\u00e1n prend tout le pays de court \u2013 y compris dans son propre parti \u2013 en annon\u00e7ant avoir confi\u00e9 au g\u00e9ant russe du nucl\u00e9aire Rosatom le gigantesque chantier de r\u00e9novation de l\u2019unique centrale atomique hongroise.<\/p><cite>Thomas Laffitte<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En 2019, la banque russe International Investment Bank (IIB) s\u2019installait \u00e0 Budapest. Cette ancienne institution sovi\u00e9tique ressuscit\u00e9e en 2012 par Vladimir Poutine est soup\u00e7onn\u00e9e, tant par des observateurs am\u00e9ricains que des journalistes ind\u00e9pendants locaux, de servir fid\u00e8lement les int\u00e9r\u00eats du Kremlin et semble faciliter l\u2019arriv\u00e9e en Hongrie d\u2019espions russes. <a href=\"https:\/\/hvg.hu\/360\/20220228_Magyarorszag_Orban_Viktor_Oroszorszag_Vlagyimir_Putyin_hirszerzes_kemelharitas_Ukrajna\">Selon<\/a> le journaliste Andr\u00e1s Dezs\u0151, sp\u00e9cialiste des services de renseignement, l\u2019influence russe en Hongrie est telle qu\u2019elle concerne aussi les services secrets hongrois, avec lesquels les Occidentaux \u00e9viteraient maintenant de coop\u00e9rer, de peur de voir des informations passer chez les Russes.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les habits neufs de Viktor Orb\u00e1n&nbsp;<\/strong><\/h2>\n\n\n\n<p>Alors, la guerre en Ukraine a-t-elle pouss\u00e9 le gouvernement hongrois \u00e0 op\u00e9rer un virage \u00e0 180\u00b0, et \u00e0 couper tous les ponts avec Moscou&nbsp;&#160;? Au premier abord, il pourrait sembler que cela soit le cas. Le gouvernement hongrois a imm\u00e9diatement condamn\u00e9 l\u2019invasion russe et Viktor Orb\u00e1n a tr\u00e8s rapidement assur\u00e9 Kiev du soutien de la Hongrie en passant un coup de fil au pr\u00e9sident Zelensky. Lui et son gouvernement ont ensuite martel\u00e9 que la Hongrie soutenait toutes les sanctions d\u00e9cid\u00e9es tant par l\u2019Union europ\u00e9enne que par l\u2019OTAN.&nbsp;<\/p>\n\n\n\n<p>Au-del\u00e0 des sanctions, Budapest a \u00e9galement cess\u00e9 de bloquer le rapprochement de Kiev avec les institutions occidentales, chose qu\u2019elle faisait depuis 2017 et un contentieux li\u00e9 \u00e0 la minorit\u00e9 hongroise d\u2019Ukraine. Kiev a ainsi pu rejoindre le 3 mars le Centre d&rsquo;excellence de cyberd\u00e9fense coop\u00e9rative de l&rsquo;OTAN, mouvement que Budapest avait emp\u00each\u00e9 un mois plus t\u00f4t. Encore plus inattendu, la Hongrie s\u2019est m\u00eame ralli\u00e9e \u00e0 la demande d\u2019une dizaine de pays d\u2019Europe de l\u2019Est de proposer \u00e0 l\u2019Ukraine une proc\u00e9dure d\u2019adh\u00e9sion \u00ab&#160;express&#160;\u00bb \u00e0 l\u2019Union.<\/p>\n\n\n\n<p>Enfin, le retournement de veste du Premier ministre est complet sur la question de l\u2019accueil des r\u00e9fugi\u00e9s de guerre ukrainiens. Lui, le pourfendeur z\u00e9l\u00e9 de l\u2019immigration mart\u00e8le d\u00e9sormais nuit et jour que la Hongrie est pr\u00eate \u00e0 accueillir tous les r\u00e9fugi\u00e9s en provenance d\u2019Ukraine, leur promettant \u00e0 tous un accueil chaleureux, m\u00eame si dans les faits, ce sont largement des organisations issues de la soci\u00e9t\u00e9 civile qui se chargent de leur prise en charge.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Au-del\u00e0 des sanctions, Budapest a \u00e9galement cess\u00e9 de bloquer le rapprochement de Kiev avec les institutions occidentales, chose qu\u2019elle faisait depuis 2017 et un contentieux li\u00e9 \u00e0 la minorit\u00e9 hongroise d\u2019Ukraine.<\/p><cite>Thomas Laffitte<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sir\u00e8nes prorusses dans la presse hongroise<\/strong><\/h2>\n\n\n\n<p>Cependant, si dans le fond, Viktor Orb\u00e1n est rentr\u00e9 dans le rang, son revirement n\u2019est pas complet. D\u00e8s les premi\u00e8res annonces de soutien militaire \u00e0 l\u2019Ukraine, la Hongrie a annonc\u00e9 ne pas vouloir envoyer d\u2019armes en Ukraine, et ne laissera pas transiter d\u2019armes l\u00e9tales <em>via<\/em> son territoire. Budapest prend soin de s\u2019opposer \u00e0 toute sanction qui viserait le g\u00e9ant russe du nucl\u00e9aire, Rosatom, en charge de la r\u00e9novation de la centrale nucl\u00e9aire de Paks, ou d\u2019expulser de son territoire la Banque internationale d\u2019investissement (IIB). Le tr\u00e8s hypoth\u00e9tique embargo europ\u00e9en sur le gaz et le p\u00e9trole russe est l\u2019autre sujet de discorde. De nombreuses voix s\u2019\u00e9l\u00e8vent en Europe, appelant \u00e0 suivre les Am\u00e9ricains dans leur embargo. Viktor Orb\u00e1n s\u2019oppose quant \u00e0 lui tr\u00e8s fermement \u00e0 cette id\u00e9e.<\/p>\n\n\n\n<p>Mais l\u2019essentiel est presque ailleurs. Pour cacher les contradictions \u00e9videntes du discours du Fidesz ces dix derni\u00e8res ann\u00e9es, l\u2019empire m\u00e9diatique progouvernemental s\u2019est mis en ordre de bataille. Dans ce v\u00e9ritable matraquage m\u00e9diatique, le d\u00e9roulement de la guerre est certes correctement rapport\u00e9, mais \u00e9ditorialistes et autres influenceurs v\u00e9hiculent en permanence les discours du Kremlin, tout en omettant ostensiblement d\u2019\u00e9voquer les ann\u00e9es de rapprochement russo-hongrois tant promues par le gouvernement.&nbsp;<\/p>\n\n\n\n<p>\u00c0 cela s\u2019ajoute une rh\u00e9torique au mieux indiff\u00e9rente, au pire franchement hostile \u00e0 l\u2019\u00e9gard de l\u2019Ukraine, souvent pr\u00e9sent\u00e9e comme un \u00c9tat infr\u00e9quentable depuis la r\u00e9volution de Ma\u00efdan de 2014. Ce discours s\u2019inscrit dans une tendance plus ancienne, o\u00f9 m\u00e9dias progouvernementaux hongrois reprennent \u00e0 leur compte le discours port\u00e9 par les m\u00e9dias russes, de Sputnik \u00e0 Russia Today.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Pour cacher les contradictions \u00e9videntes du discours du Fidesz ces dix derni\u00e8res ann\u00e9es, l\u2019empire m\u00e9diatique progouvernemental s\u2019est mis en ordre de bataille.<\/p><cite>Thomas Laffitte<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ni la guerre, ni la gauche<\/strong><\/h2>\n\n\n\n<p>Enfin, la propagande d\u2019\u00c9tat mart\u00e8le surtout un message essentiel&nbsp;&#160;: les partis d\u2019opposition \u2013 simplement d\u00e9sign\u00e9 comme <em>\u00ab&#160;&nbsp;la gauche&nbsp;&#160;\u00bb<\/em> \u2013 veulent envoyer des soldats hongrois se battre en Ukraine. \u00c0 l\u2019origine de ce mensonge, une d\u00e9claration de P\u00e9ter M\u00e1rki-Zay, le leader de l\u2019opposition, qui expliquait \u00eatre pr\u00eat \u00e0 suivre l\u2019OTAN dans n\u2019importe quelle direction, y compris une aide militaire dans le cas o\u00f9 l\u2019alliance atlantique en d\u00e9cidait ainsi. Il n\u2019en fallait pas plus au Fidesz, pour qui <em>\u00ab&#160;&nbsp;la gauche veut envoyer des soldats hongrois se battre en Ukraine&nbsp;&#160;\u00bb<\/em>. Autrement dit, si la gauche gagne les \u00e9lections, c\u2019est la guerre.&nbsp;<\/p>\n\n\n\n<p>P\u00e9ter M\u00e1rki-Zay se d\u00e9m\u00e8ne pour r\u00e9futer ces accusations. Mais difficile de rivaliser face \u00e0 la machine m\u00e9diatique du Fidesz. Le 16 mars, le candidat commun de l\u2019opposition a par exemple \u00e9t\u00e9 exceptionnellement invit\u00e9 sur le plateau de la principale cha\u00eene TV publique, o\u00f9 il n\u2019a b\u00e9n\u00e9fici\u00e9 que de cinq minutes de temps d\u2019antenne, soit le minimum l\u00e9gal pour un candidat officiel.&nbsp;<\/p>\n\n\n\n<p>Ainsi, avec la guerre qui menace tant depuis l\u2019Ukraine que depuis les rangs de l\u2019opposition, le Premier ministre Viktor Orb\u00e1n endosse son r\u00f4le favori de d\u00e9fenseur de la nation en danger. La derni\u00e8re campagne d\u2019affichage en date montre Orb\u00e1n en tenue quasi militaire, appelant \u00e0 prot\u00e9ger la paix et la s\u00e9curit\u00e9 du pays. Chaque jour, il se met en sc\u00e8ne soit en chef des arm\u00e9es en visite \u00e0 la fronti\u00e8re du pays, soit en diplomate chevronn\u00e9 \u0153uvrant pour la paix.&nbsp;<\/p>\n\n\n\n<p>Cette image de chef d\u2019\u00c9tat engag\u00e9 pour la d\u00e9fense du pays lui a permis de creuser son avance en vue des \u00e9lections. Un <a href=\"https:\/\/visegradinsight.eu\/can-viktor-orbans-u-turn-be-trusted\/\" target=\"_blank\" rel=\"noreferrer noopener\">sondage<\/a> pla\u00e7ait le Fidesz \u00e0 quatre points devant le front uni de l\u2019opposition avant la guerre. Selon le m\u00eame sondeur, le Fidesz menait par plus de douze points apr\u00e8s le d\u00e9clenchement de la guerre. Viktor Orb\u00e1n, gr\u00e2ce \u00e0 son tout-puissant empire m\u00e9diatique, a donc r\u00e9ussi \u00e0 tourner la guerre en Ukraine \u00e0 son avantage. Il semble s\u2019\u00eatre assur\u00e9 sa r\u00e9\u00e9lection au 3 avril prochain, m\u00eame si la question de sa majorit\u00e9 des deux tiers au parlement reste en suspens.&nbsp;<\/p>\n\n\n\n<p><em>[Depuis le tout d\u00e9but de l\u2019invasion de la Russie de l\u2019Ukraine, avec nos cartes, nos analyses et nos perspectives nous avons aid\u00e9 presque 2 millions de personnes \u00e0 comprendre les transformations g\u00e9opolitiques de cette s\u00e9quence. Si vous trouvez notre travail utile et vous pensez qu\u2019il m\u00e9rite d\u2019\u00eatre soutenu, vous pouvez vous&nbsp;<\/em><a href=\"https:\/\/legrandcontinent.eu\/fr\/user-dashboard\/register\/\"><em>abonner ici<\/em><\/a><em>.]<\/em><\/p>\n\n\n\n<p>La guerre en Ukraine lui conf\u00e8re \u00e9galement un autre atout et non des moindres&nbsp;&#160;: la proc\u00e9dure en cours \u00e0 Bruxelles en vue de sanctionner la Hongrie et la Pologne pour non-respect de de l\u2019\u00c9tat de droit a \u00e9t\u00e9 quasiment jet\u00e9e aux oubliettes. Non pas que des sanctions venant de Bruxelles auraient handicap\u00e9 Viktor Orb\u00e1n \u2013 cela aurait \u00e9t\u00e9 probablement le contraire \u2013 mais la Hongrie aurait s\u00e9rieusement p\u00e2ti dans le cas o\u00f9 elle \u00e9tait priv\u00e9e d\u2019une partie des fonds du plan de relance europ\u00e9en.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Viktor Orb\u00e1n, gr\u00e2ce \u00e0 son tout-puissant empire m\u00e9diatique, a donc r\u00e9ussi \u00e0 tourner la guerre en Ukraine \u00e0 son avantage. Il semble s\u2019\u00eatre assur\u00e9 sa r\u00e9\u00e9lection au 3 avril prochain, m\u00eame si la question de sa majorit\u00e9 des deux tiers au parlement reste en suspens.<\/p><cite>Thomas Laffitte<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Isolement europ\u00e9en et tropisme balkanique<\/strong><\/h2>\n\n\n\n<p>Pour autant, tout n\u2019est pas rose pour le Premier ministre hongrois. Sur la sc\u00e8ne europ\u00e9enne, depuis son expulsion du Parti Populaire europ\u00e9en (PPE), il reste esseul\u00e9 et n\u2019a pas r\u00e9ussi \u00e0 rassembler une nouvelle force d\u2019extr\u00eame droite comme il l\u2019aurait souhait\u00e9. Qui plus est, la guerre en Ukraine accentue son isolement en mettant au jour <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/30\/titre-la-guerre-en-ukraine-reconfigure-les-alliances-en-europe-et-en-asie\/\">les fragmentations profondes au sein du groupe de Visegrad (V4)<\/a>, o\u00f9 m\u00eame la R\u00e9publique tch\u00e8que du tr\u00e8s russophile Milos Zeman s\u2019est d\u00e9tourn\u00e9e de Moscou et affiche un soutien sans faille \u00e0 Kiev. Il est bien difficile d\u2019envisager comment la Pologne, profond\u00e9ment anti-Russie et pro-Ukraine, pourrait ne pas prendre ses distances avec le gouvernement Orb\u00e1n qui continue d\u2019\u00eatre un v\u00e9ritable <em>proxy <\/em>russe dans la r\u00e9gion.&nbsp;<\/p>\n\n\n\n<p>Car sans oublier sa <em>\u00ab&#160;&nbsp;proposition d\u2019aide&nbsp;&#160;\u00bb <\/em>offerte au pr\u00e9sident du Kazakhstan Kassym-Jomart Toka\u00efev confront\u00e9 \u00e0 une r\u00e9bellion d\u00e9but janvier, c\u2019est bien dans les Balkans que Viktor Orb\u00e1n agit d\u00e9sormais comme un relais du Kremlin. \u00c0 l\u2019automne, il soutenait Milorad Dodik, le chef des Serbes de Bosnie soup\u00e7onn\u00e9 de pr\u00e9parer l\u2019\u00e9clatement de la Bosnie-Herz\u00e9govine. Il veille aussi \u00e0 rester proche du pr\u00e9sident serbe Aleksandar Vucic, \u00e9galement tr\u00e8s russophile, \u00e0 qui il a encore rendu visite le 19 mars dernier.&nbsp;<\/p>\n\n\n\n<p>Si la guerre en Ukraine profite largement \u00e0 Viktor Orb\u00e1n sur le plan interne, elle \u00e9branle s\u00e9rieusement sa politique \u00e9trang\u00e8re en d\u00e9montrant toutes les limites de son \u00ab&#160;&nbsp;l\u2019Ouverture \u00e0 l\u2019Est&nbsp;&#160;\u00bb. Et pourtant, le Premier ministre hongrois semble toujours parier sur le Kremlin, en t\u00e9moigne ses ambitions dans les Balkans ou sa rh\u00e9torique prudente \u00e0 l\u2019\u00e9gard de Moscou. En cas de r\u00e9\u00e9lection, Viktor Orb\u00e1n risque d\u2019accentuer son isolement sur la sc\u00e8ne europ\u00e9enne, sauf \u00e0 op\u00e9rer un revirement complet \u2013 pour de vrai cette fois.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guerre en Ukraine a pouss\u00e9 Viktor Orb\u00e1n, le pro-Poutine, sur une ligne de cr\u00eate diplomatique. <\/p>\n<p>Si elle a renforc\u00e9 son avance en vue des l\u00e9gislatives du 3 avril, elle a fragilis\u00e9 sa posture internationale en r\u00e9v\u00e9lant toutes les limites de son \u00ab&#160;&#160;ouverture \u00e0 l\u2019Est&#160;&#160;\u00bb.<\/p>\n","protected":false},"author":10,"featured_media":135408,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":13,"footnotes":""},"categories":[2980],"tags":[],"staff":[3038],"editorial_format":[4849],"serie":[],"audience":[],"geo":[536],"class_list":["post-135405","post","type-post","status-publish","format-standard","hentry","category-elections","staff-thomas-laffitte","editorial_format-etudes","geo-centres"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":135408,"excerpt":"La guerre en Ukraine a pouss\u00e9 Viktor Orb\u00e1n, le pro-Poutine, sur une ligne de cr\u00eate diplomatique. \r\n\r\nSi elle a renforc\u00e9 son avance en vue des l\u00e9gislatives du 3 avril, elle a fragilis\u00e9 sa posture internationale en r\u00e9v\u00e9lant toutes les limites de son \u00ab ouverture \u00e0 l\u2019Est \u00bb.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les r\u00eaves contrari\u00e9s \u00ab d\u2019ouverture \u00e0 l\u2019Est \u00bb de Viktor Orb\u00e1n | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les r\u00eaves contrari\u00e9s \u00ab d\u2019ouverture \u00e0 l\u2019Est \u00bb de Viktor Orb\u00e1n | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La guerre en Ukraine a pouss\u00e9 Viktor Orb\u00e1n, le pro-Poutine, sur une ligne de cr\u00eate diplomatique.   Si elle a renforc\u00e9 son avance en vue des l\u00e9gislatives du 3 avril, elle a fragilis\u00e9 sa posture internationale en r\u00e9v\u00e9lant toutes les limites de son \u00ab&#160;ouverture \u00e0 l\u2019Est&#160;\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T09:13:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-31T13:27:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/gc-urbietorban-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/gc-urbietorban-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/\",\"name\":\"Les r\u00eaves contrari\u00e9s \u00ab d\u2019ouverture \u00e0 l\u2019Est \u00bb de Viktor Orb\u00e1n | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg\",\"datePublished\":\"2022-03-31T09:13:30+00:00\",\"dateModified\":\"2022-03-31T13:27:16+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg\",\"width\":1955,\"height\":1287,\"caption\":\"FILE - Hungary's Prime Minister Viktor Orban walks through a sliding door as he leaves an EU summit in Brussels, Oct. 22, 2021. As coronavirus infections and deaths soar in Hungary, the country's journalists and public health professionals are demanding more detailed data on the outbreak from the government, with some experts saying that greater transparency might boost lagging vaccination rates. (Olivier Hoslet, Pool Photo via AP, File)\/BUD107\/21343521892868\/POOL PHOTO, FILE PHOTO\/2112130705\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les r\u00eaves contrari\u00e9s \u00ab&#160;d\u2019ouverture \u00e0 l\u2019Est&#160;\u00bb de Viktor Orb\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les r\u00eaves contrari\u00e9s \u00ab d\u2019ouverture \u00e0 l\u2019Est \u00bb de Viktor Orb\u00e1n | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/","og_locale":"fr_FR","og_type":"article","og_title":"Les r\u00eaves contrari\u00e9s \u00ab d\u2019ouverture \u00e0 l\u2019Est \u00bb de Viktor Orb\u00e1n | Le Grand Continent","og_description":"La guerre en Ukraine a pouss\u00e9 Viktor Orb\u00e1n, le pro-Poutine, sur une ligne de cr\u00eate diplomatique.   Si elle a renforc\u00e9 son avance en vue des l\u00e9gislatives du 3 avril, elle a fragilis\u00e9 sa posture internationale en r\u00e9v\u00e9lant toutes les limites de son \u00ab&#160;ouverture \u00e0 l\u2019Est&#160;\u00bb.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/","og_site_name":"Le Grand Continent","article_published_time":"2022-03-31T09:13:30+00:00","article_modified_time":"2022-03-31T13:27:16+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/gc-urbietorban-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/gc-urbietorban-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/","name":"Les r\u00eaves contrari\u00e9s \u00ab d\u2019ouverture \u00e0 l\u2019Est \u00bb de Viktor Orb\u00e1n | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg","datePublished":"2022-03-31T09:13:30+00:00","dateModified":"2022-03-31T13:27:16+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg","width":1955,"height":1287,"caption":"FILE - Hungary's Prime Minister Viktor Orban walks through a sliding door as he leaves an EU summit in Brussels, Oct. 22, 2021. As coronavirus infections and deaths soar in Hungary, the country's journalists and public health professionals are demanding more detailed data on the outbreak from the government, with some experts saying that greater transparency might boost lagging vaccination rates. (Olivier Hoslet, Pool Photo via AP, File)\/BUD107\/21343521892868\/POOL PHOTO, FILE PHOTO\/2112130705"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/31\/les-reves-contraries-douverture-a-lest-de-viktor-orban\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Les r\u00eaves contrari\u00e9s \u00ab&#160;d\u2019ouverture \u00e0 l\u2019Est&#160;\u00bb de Viktor Orb\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":2980,"name":"\u00c9lections","slug":"elections"}],"lgc_author":{"id":3038,"name":"Thomas Laffitte","slug":"thomas-laffitte","description":"Doctorant en science politique au Centre d'\u00e9tudes europ\u00e9ennes (CEE) \u00e0 Sciences Po Paris ainsi qu'\u00e0 la Central European University (CEU) de Vienne en Autriche. Ancien journaliste correspondant bas\u00e9 \u00e0 Budapest.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/09\/gc-Laffitte.png","width":336,"height":330,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg","width":1955,"height":1287,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22634057_000008.jpg","width":1955,"height":1287,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/135405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=135405"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/135405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/135408"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=135405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=135405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=135405"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=135405"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=135405"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=135405"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=135405"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=135405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}