{"id":13530,"date":"2019-03-24T22:00:17","date_gmt":"2019-03-24T21:00:17","guid":{"rendered":"https:\/\/lldl.eu\/?p=13530"},"modified":"2019-04-06T10:17:20","modified_gmt":"2019-04-06T08:17:20","slug":"laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/","title":{"rendered":"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment"},"content":{"rendered":"\n<p><em>Rome.<\/em> Dans la capitale italienne, il ne se passe pas un jour sans que le gouvernement \u00ab&#160;jaune-vert&#160;\u00bb, surnom de la coalition entre la Ligue et le Mouvement 5 \u00e9toiles, semble sur le point de s\u2019effondrer. Les deux partis s\u2019affrontent en effet sur quasiment toutes les affaires d\u00e9licates&#160;: de la TVA au revenu de base, en passant par le m\u00e9morandum d\u2019accord avec la Chine, sign\u00e9 le 22 mars dernier (<strong>1<\/strong>).<\/p>\n\n\n\n<p>C\u2019est justement au sujet de la Chine que la derni\u00e8re rupture grave a eu lieu. Apr\u00e8s les critiques f\u00e9roces \u00e9mises par les \u00c9tats-Unis \u00e0 l\u2019encontre de cet accord, les deux partis  semblent avoir adopt\u00e9 deux approches diff\u00e9rentes&#160;: d\u2019une part, le Mouvement 5 \u00c9toiles, et en particulier le vice-Premier ministre Luigi di Maio et le Premier ministre Giuseppe Conte, ont pris fait et cause pour l\u2019accord, en en louant les avantages \u00e9conomiques pour le pays. D\u2019autres part, Matteo Salvini est d\u2019un tout autre avis&#160;: \u00ab&#160;s\u2019il s\u2019agit d\u2019aider les entreprises italiennes \u00e0 investir \u00e0 l\u2019\u00e9tranger, nous sommes dispos\u00e9s \u00e0 parler avec tout le monde&#160;\u00bb, a expliqu\u00e9 le chef de la Ligue. \u00ab&#160;Mais si le moindre doute existe sur le fait que certaines acquisitions puissent mettre en difficult\u00e9 la s\u00e9curit\u00e9 nationale, en tant que ministre de l\u2019Int\u00e9rieur, j\u2019\u00e9mettrai un non d\u00e9finitif&#160;: l\u2019Italie est fort attach\u00e9e \u00e0 une alliance qui justement requiert de l\u2019attention&#160;\u00bb (<strong>3<\/strong>).<\/p>\n\n\n\n<p>La position de Salvini est partag\u00e9e par l\u2019ensemble de la Ligue \u2013 bien que, immense paradoxe, le principal <em>deus ex machina<\/em> derri\u00e8re l\u2019accord avec la Chine soit le sous-secr\u00e9taire Michele Geraci, technocrate choisi justement par la Ligue. La fermet\u00e9 de Salvini s\u2019explique par le fait que, sur la question de la Chine, un axe commun entre la Ligue et les \u00c9tats-Unis s\u2019est cr\u00e9\u00e9 d\u00e8s le d\u00e9but&#160;: les plaintes de Washington ont \u00e9t\u00e9 re\u00e7ues par le parti de Salvini, en particulier gr\u00e2ce au travail de ses deux meilleurs repr\u00e9sentants, Giancarlo Giorgetti et Guglielmo Picchi, qui jouissent d\u2019un entregent important et de bons rapports \u00e0 l\u2019int\u00e9rieur du Parti r\u00e9publicain am\u00e9ricain. Ce qui a contribu\u00e9 \u00e0 une redimensionnement encore en cours du texte du m\u00e9morandum, mais surtout \u00e0 l\u2019immense isolement du Mouvement Cinq \u00c9toiles dans l\u2019affaire. De fait, de fa\u00e7on peu commune, le minist\u00e8re des Affaires \u00e9trang\u00e8res italien est all\u00e9 jusqu\u2019\u00e0 se d\u00e9tacher de l\u2019accord, et l\u2019accueil de la d\u00e9l\u00e9gation chinoise a \u00e9t\u00e9 organis\u00e9 par le minist\u00e8re du D\u00e9veloppement \u00e9conomique, tenu par Di Maio. En substance, le m\u00e9morandum est d\u00e9sormais vu \u00e0 Rome comme l\u2019\u0153uvre solitaire du Mouvement Cinq \u00c9toiles, qui aurait imprudemment pris de dangereuses d\u00e9cisions ayant une r\u00e9sonance politique et g\u00e9opolitique et mettant en p\u00e9ril les alliances historiques (<strong>2<\/strong>).<\/p>\n\n\n\n<p>La question du m\u00e9morandum d\u2019accord avec la Chine met ainsi en lumi\u00e8re une importante \u00e9volution au long cours&#160;: face \u00e0 l\u2019inexp\u00e9rience du Mouvement Cinq \u00c9toiles, la Ligue se taille de plus en plus le r\u00f4le de parti repr\u00e9sentatif des instances de l\u2019<em>establishment<\/em> et des alliances traditionnelles. Si, sur le papier, Salvini continue \u00e0 avoir un message extr\u00e9miste et conflictuel, en v\u00e9rit\u00e9, en pratique, la Ligue tend de plus en plus, gr\u00e2ce \u00e0 ses vingt ans d\u2019exp\u00e9rience de gouvernement, \u00e0 devenir le v\u00e9ritable et authentique \u00ab&#160;parti de la nation&#160;\u00bb. Ainsi, en rel\u00e9guant au second plan ses liens, multiples et prouv\u00e9s, avec Poutine, Salvini rejoint d\u00e9sormais le bastion atlantiste. Il s\u2019agit d\u2019une \u00e9volution importante de laquelle il faut tenir compte, \u00e9galement au niveau europ\u00e9en avec les \u00e9lections de mai, au cours desquelles la Ligue devrait devenir le premier parti du pays. Si Salvini r\u00e9ussissait \u00e0 se pr\u00e9senter, m\u00eame \u00e0 Bruxelles, comme le parti de l\u2019<em>establishment<\/em>, l\u2019\u00e9quilibre de la politique europ\u00e9enne s\u2019en retrouverait fortement modifi\u00e9.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sources&#160;:<\/strong><\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li>GOLDSTEIN Andrea, Xi Jinping in Italia, 3 speranze e 3 timori per la visita del presidente cinese, Il Sole 24 Ore, 21 mars 2019.<\/li><li>POMPILI Giulia, <a href=\"https:\/\/www.ilfoglio.it\/home\/2019\/03\/21\/news\/cosi-siamo-arrivati-a-stare-con-i-cinesi-senza-avere-niente-in-cambio-244551\/\">Cos\u00ec siamo arrivati a stare con i cinesi senza avere niente in cambio,<\/a> Il Foglio, 21 mars 2019.<\/li><li><a href=\"http:\/\/www.rainews.it\/dl\/rainews\/articoli\/Cina-Salvini-memorandum-non-testo-sacro-si-puo-migliorare-03805226-b9bc-4b5f-a7ec-7836ed2677be.html?refresh_ce\">Cina, Salvini&#160;: memorandum non \u00e8 testo sacro, si pu\u00f2 migliorare,<\/a> Rai News, 14 mars 2019.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9saccord qui s\u2019est d\u00e9clar\u00e9 au sein du gouvernement italien au sujet de la signature de du m\u00e9morandum d\u2019accord avec la Chine, en vertu duquel Rome int\u00e8gre le projet des \u00ab&#160;&#160;nouvelles routes de la soie&#160;&#160;\u00bb, d\u00e9montre combien la Ligue, malgr\u00e9 ses messages populistes, se positionne dans les faits de plus en plus comme le garant de l\u2019atlantisme et du statu quo. Une \u00e9volution \u00e0 suivre au regard des \u00e9lections europ\u00e9ennes.<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[1644],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-13530","post","type-post","status-publish","format-standard","hentry","category-politique","staff-giovanni-collot","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Le d\u00e9saccord qui s\u2019est d\u00e9clar\u00e9 au sein du gouvernement italien au sujet de la signature de du m\u00e9morandum d\u2019accord avec la Chine, en vertu duquel Rome int\u00e8gre le projet des \u00ab nouvelles routes de la soie \u00bb, d\u00e9montre combien la Ligue, malgr\u00e9 ses messages populistes, se positionne dans les faits de plus en plus comme le garant de l\u2019atlantisme et du statu quo. Une \u00e9volution \u00e0 suivre au regard des \u00e9lections europ\u00e9ennes.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9saccord qui s\u2019est d\u00e9clar\u00e9 au sein du gouvernement italien au sujet de la signature de du m\u00e9morandum d\u2019accord avec la Chine, en vertu duquel Rome int\u00e8gre le projet des \u00ab&#160;nouvelles routes de la soie&#160;\u00bb, d\u00e9montre combien la Ligue, malgr\u00e9 ses messages populistes, se positionne dans les faits de plus en plus comme le garant de l\u2019atlantisme et du statu quo. Une \u00e9volution \u00e0 suivre au regard des \u00e9lections europ\u00e9ennes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-24T21:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-06T08:17:20+00:00\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/\",\"name\":\"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2019-03-24T21:00:17+00:00\",\"dateModified\":\"2019-04-06T08:17:20+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment | Le Grand Continent","og_description":"Le d\u00e9saccord qui s\u2019est d\u00e9clar\u00e9 au sein du gouvernement italien au sujet de la signature de du m\u00e9morandum d\u2019accord avec la Chine, en vertu duquel Rome int\u00e8gre le projet des \u00ab&#160;nouvelles routes de la soie&#160;\u00bb, d\u00e9montre combien la Ligue, malgr\u00e9 ses messages populistes, se positionne dans les faits de plus en plus comme le garant de l\u2019atlantisme et du statu quo. Une \u00e9volution \u00e0 suivre au regard des \u00e9lections europ\u00e9ennes.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/","og_site_name":"Le Grand Continent","article_published_time":"2019-03-24T21:00:17+00:00","article_modified_time":"2019-04-06T08:17:20+00:00","author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/","name":"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2019-03-24T21:00:17+00:00","dateModified":"2019-04-06T08:17:20+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/24\/laccord-sur-la-chine-montre-comment-la-ligue-est-devenue-le-nouveau-parti-de-lestablishment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019accord sur la Chine montre comment la Ligue est devenue le nouveau parti de l\u2019establishment"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1644,"name":"Giovanni Collot","slug":"giovanni-collot","description":"<span style=\"font-weight: 400\">Giovanni Collot est journaliste et expert de communication, s\u2019int\u00e9ressant particuli\u00e8rement aux affaires europ\u00e9ennes et \u00e0 la politique \u00e9trang\u00e8re. Depuis 2018, il est chef du projet Communication au European Committee for Standardization (CEN) et au European Committee for Electrotechnical Standardization (CENELEC). <\/span>","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-giovanni-collot.jpg","width":450,"height":450,"alt":""}},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/13530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=13530"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/13530\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=13530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=13530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=13530"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=13530"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=13530"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=13530"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=13530"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=13530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}