{"id":134154,"date":"2022-03-16T12:47:27","date_gmt":"2022-03-16T11:47:27","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=134154"},"modified":"2022-03-16T18:26:41","modified_gmt":"2022-03-16T17:26:41","slug":"cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/","title":{"rendered":"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne"},"content":{"rendered":"\n<div class=\"wp-block-lgc-keypoints key-block\"><div class=\"keys\"><h6 class=\"font-fold text-sm uppercase\">Key Points<\/h6>\n<ul class=\"wp-block-list\"><li>La dimension proprement allemande du tournant g\u00e9opolitique actuel peut \u00eatre mieux comprise en faisant appel au concept de \u00ab&#160;&nbsp;<em>wehrhafte Demokratie<\/em>&#160;\u00bb (d\u00e9mocratie capable de se d\u00e9fendre), qui \u00e9tait au c\u0153ur de la Loi fondamentale de 1949.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Mais si d\u00e8s les premiers jours de d\u00e9cembre, la nouvelle coalition est apparue plus \u00ab&#160;g\u00e9opolitique&#160;\u00bb que la pr\u00e9c\u00e9dente, la politique sociale ou \u00e9conomique n\u2019a pas pour autant cess\u00e9 d\u2019occuper le gouvernement. Malgr\u00e9 la mont\u00e9e des p\u00e9rils en politique \u00e9trang\u00e8re, la politique int\u00e9rieure est rest\u00e9e une pr\u00e9occupation centrale dans ces cents premiers jours.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Il n&rsquo;y a pas en Allemagne de \u00ab&#160;&nbsp;domaine r\u00e9serv\u00e9&#160;\u00bb de la politique \u00e9trang\u00e8re et de d\u00e9fense et, dans la crise actuelle qui est \u00e0 la fois financi\u00e8re, g\u00e9opolitique et \u00e9conomique, les trois ministres comp\u00e9tents \u2013&nbsp;qui sont aussi les leaders de leurs partis \u2013 sont tous trois mis \u00e0 contribution.<\/li><\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"has-drop-cap\">Le dicton allemand <em>Aller Anfang ist schwer <\/em>(chaque d\u00e9but est difficile) r\u00e9sume particuli\u00e8rement bien les trois premiers mois du gouvernement Scholz. Les d\u00e9buts de la coalition en feu tricolore (SPD, B\u00fcndnis 90\/Die Gr\u00fcnen, FDP) ont sans doute \u00e9t\u00e9 les plus p\u00e9rilleux de l\u2019histoire de la r\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne depuis la r\u00e9unification, dans un contexte de guerre de haute intensit\u00e9 sur le sol europ\u00e9en, de recrudescence pand\u00e9mique et de changement climatique.&nbsp;<\/p>\n\n\n\n<p>L\u2019accord de coalition n\u00e9goci\u00e9 et conclu en novembre dernier, dont nous avions <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/25\/doctrine-de-la-nouvelle-ere-allemande\/\">traduit et comment\u00e9<\/a> de larges extraits, montrait d\u00e9j\u00e0 une conscience de ces trois grands d\u00e9fis. La lutte contre le changement climatique, la sortie de la pand\u00e9mie et la fermet\u00e9 face aux r\u00e9gimes autocratiques y figuraient en effet en bonne place.&nbsp;<\/p>\n\n\n\n<p>Si d\u00e8s les premiers jours de d\u00e9cembre, la nouvelle coalition est apparue plus \u00ab&#160;g\u00e9opolitique&#160;\u00bb que la pr\u00e9c\u00e9dente, la politique sociale ou \u00e9conomique n\u2019a pas pour autant cess\u00e9 d\u2019occuper le gouvernement. Dans ces domaines, plusieurs mesures symboliques du programme ont \u00e9t\u00e9 mises en place, et les ministres de cette coalition in\u00e9dite au plan f\u00e9d\u00e9ral, ont pris leurs marques au pouvoir avec l\u2019annonce de grands plans, et ont d\u00fb confronter, parfois durement, leurs principes et positions ant\u00e9rieures \u00e0 la r\u00e9alit\u00e9 de la gestion de leurs portefeuilles respectifs. Mais ces cent jours ont \u00e9t\u00e9 d\u00e8s le d\u00e9but profond\u00e9ment marqu\u00e9s par la guerre aux fronti\u00e8res de l\u2019Union. L\u2019invasion russe de l\u2019Ukraine le 24 f\u00e9vrier a d\u00e9finitivement rebattu les cartes et referm\u00e9 la p\u00e9riode de gr\u00e2ce d\u2019un gouvernement allemand parvenu en acc\u00e9l\u00e9r\u00e9 \u00e0 \u00ab&#160;&nbsp;l\u2019\u00e2ge de raison&#160;\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1 \u2014 La premi\u00e8re exp\u00e9rience du pouvoir et la lutte contre la pand\u00e9mie<\/h2>\n\n\n\n<p>La pand\u00e9mie avait d\u00e9j\u00e0 durablement boulevers\u00e9 la tradition des comptes publics allemands \u00e0 l\u2019\u00e9quilibre qu\u2019incarnait la doctrine de la \u00ab&#160;&nbsp;<em>Schwarze Null<\/em>&#160;\u00bb.&nbsp; Le vote d\u2019un budget correctionnel (<em>Nachtragshaushalt<\/em>) de 60 milliards d\u2019euros le 16 d\u00e9cembre, soit huit jours apr\u00e8s l\u2019entr\u00e9e en fonction du gouvernement, port\u00e9 par le nouveau ministre des finances lib\u00e9ral Christian Lindner, a remis en question les pr\u00e9ceptes financiers de rigueur pr\u00f4n\u00e9s par le FDP&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-1-134154' title='&lt;a href=&quot;https:\/\/www.tagesschau.de\/inland\/innenpolitik\/lindner-nachtragshaushalt-103.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Nachtragshaushalt&amp;#160;: Lindners Sinneswande&lt;\/a&gt;'><sup>1<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>De son c\u00f4t\u00e9, le nouveau ministre de la sant\u00e9 \u2013&nbsp;et m\u00e9decin \u00e9pid\u00e9miologiste de profession \u2013 Karl Lauterbach (SPD), devenu c\u00e9l\u00e8bre pour ses critiques des politiques sanitaires de son pr\u00e9d\u00e9cesseur Jens Spahn, a d\u00fb lutter avec les L\u00e4nder dans un contexte \u00e9pid\u00e9mique instable d\u00fb \u00e0 la vague de Covid-19 du variant Omicron. Fin d\u00e9cembre, l\u2019objectif d\u2019atteindre 80&#160;% de la population vaccin\u00e9e le 7 janvier avait \u00e9t\u00e9 repouss\u00e9 \u00e0 la fin du mois&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-2-134154' title='&lt;a href=&quot;https:\/\/www.tagesschau.de\/inland\/bundesregierung-impfquote-101.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Corona-Pandemie&amp;#160;: Bundesregierung verschiebt Impfziel&lt;\/a&gt;, Tagesschau, 26 d\u00e9cembre 2021'><sup>2<\/sup><\/a><\/span><\/span>. Le 14 mars 2022, 76,4&#160;% de la population a re\u00e7u au moins une dose, 75,7&#160;% deux doses, et 57,8&#160;% a re\u00e7u un rappel. Lothar Wieler, le directeur du Robert-Koch-Institut (RKI), l\u2019institut de sant\u00e9 publique allemand, est entr\u00e9 en janvier en conflit avec les ministres-pr\u00e9sidents en raccourcissant de sa propre initiative le d\u00e9lai de gu\u00e9rison. \u00c0 la suite de cette petite crise de communication, Karl Lauterbach reprend la main personnellement sur ces dossiers.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2 \u2014 Des r\u00e9formes phares du programme de gouvernement pour la justice sociale<\/h2>\n\n\n\n<p>Malgr\u00e9 la mont\u00e9e des p\u00e9rils en politique \u00e9trang\u00e8re, la politique int\u00e9rieure est rest\u00e9e une pr\u00e9occupation centrale dans ces cents premiers jours. En mati\u00e8re sociale, la hausse du salaire minimum de 9 \u00e0 12 euros d\u00e8s le d\u00e9but du mandat, la principale promesse de campagne du candidat Scholz et du parti social-d\u00e9mocrate, a \u00e9t\u00e9 finalis\u00e9e en f\u00e9vrier, non sans provoquer une r\u00e9action de certains secteurs de l\u2019\u00e9conomie dont les conventions collectives sont rendues en partie caduques par la hausse de salaire. La justice est \u00e9galement un des domaines o\u00f9 des progr\u00e8s notables ont \u00e9t\u00e9 r\u00e9alis\u00e9s. Le ministre de la justice lib\u00e9ral Marco Buschmann a par exemple initi\u00e9 la suppression de l\u2019article 219-a du code p\u00e9nal qui criminalisait la publicit\u00e9 pour l\u2019avortement.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si d\u00e8s les premiers jours de d\u00e9cembre, la nouvelle coalition est apparue plus \u00ab&#160;g\u00e9opolitique&#160;\u00bb que la pr\u00e9c\u00e9dente, la politique sociale ou \u00e9conomique n\u2019a pas pour autant cess\u00e9 d\u2019occuper le gouvernement.<\/p><cite>pierre mennerat<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ayant pris les r\u00eanes d\u2019un super-minist\u00e8re de l\u2019environnement et de l\u2019\u00e9conomie, le co-dirigeant des Verts Robert Habeck a pr\u00e9sent\u00e9 le 11 janvier un plan ambitieux pour acc\u00e9l\u00e9rer la transition \u00e9nerg\u00e9tique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-3-134154' title='&lt;a href=&quot;https:\/\/www.bmwi.de\/Redaktion\/DE\/Reden\/2022\/20220111-habeck-rede-eroeffnungsbilanz-klimaschutz.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;BMWK &amp;#8211; Er\u00f6ffnungsbilanz Klimaschutz&lt;\/a&gt;, Bundesministerium f\u00fcr Wirtschaft und Klimaschutz, 11 janvier 2022'><sup>3<\/sup><\/a><\/span><\/span>. Celui-ci pr\u00e9sente les moyens concrets d\u2019intensifier l\u2019utilisation des \u00e9nergies renouvelables, pour atteindre 2&#160;% du territoire consacr\u00e9s \u00e0 l\u2019\u00e9olien et au solaire. Le 7 mars, Christian Lindner a annonc\u00e9 d\u00e9bloquer 200 milliards d\u2019euros pour la transition \u00e9nerg\u00e9tique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3 \u2014 Volont\u00e9 de r\u00e9formes europ\u00e9ennes et pr\u00e9mices de la crise ukrainienne<\/h2>\n\n\n\n<p>La premi\u00e8re semaine en fonction du gouvernement \u00e0 partir du 8 d\u00e9cembre a \u00e9t\u00e9 marqu\u00e9e par un carrousel diplomatique intense, en direction de Paris, de Bruxelles et de Varsovie. Ce format dit du<em> triangle de Weimar<\/em> entre la France, l\u2019Allemagne et la Pologne, dont la revitalisation \u00e9tait annonc\u00e9e par le contrat de coalition, a \u00e9t\u00e9 r\u00e9activ\u00e9 le 1er mars pour une rencontre trilat\u00e9rale entre les ministres des affaires \u00e9trang\u00e8res&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-4-134154' title='&lt;a href=&quot;https:\/\/www.zdf.de\/nachrichten\/politik\/baerbock-polen-frankreich-russland-ukraine-krieg-100.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Baerbock in Polen&amp;#160;: Krieg schwei\u00dft den Westen zusammen&lt;\/a&gt;, ZDF Heute, 1er mars 2022'><sup>4<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>Sur le terrain des affaires europ\u00e9ennes, la pr\u00e9sidence fran\u00e7aise du conseil de l\u2019Union europ\u00e9enne force le nouveau gouvernement allemand \u00e0 prendre position <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/02\/22\/que-faire-des-regles-budgetaires-europeennes\/\">sur le th\u00e8me des r\u00e8gles du pacte de stabilit\u00e9 et de croissance<\/a>, qui doivent \u00e0 terme \u00eatre r\u00e9tablies selon Berlin. Christian Lindner s\u2019est ainsi pr\u00e9sent\u00e9 \u00e0 son premier conseil des ministres \u00e0 Bruxelles le 18 f\u00e9vrier comme un \u00ab&#160;gentil faucon&#160;\u00bb (<em>friendly hawk<\/em>)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-5-134154' title='&lt;a href=&quot;https:\/\/twitter.com\/BloombergTV\/status\/1483447347644354571&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/twitter.com\/BloombergTV\/status\/1483447347644354571&lt;\/a&gt;, 18 f\u00e9vrier 2022'><sup>5<\/sup><\/a><\/span><\/span>, et a nomm\u00e9 conseiller sp\u00e9cial \u00e0 ses c\u00f4t\u00e9s le professeur d\u2019\u00e9conomie de Freiburg Lars P. Feld, r\u00e9put\u00e9 pour sa d\u00e9fense de la rigueur budg\u00e9taire&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-6-134154' title='&lt;a href=&quot;https:\/\/www.bundesfinanzministerium.de\/Content\/DE\/Pressemitteilungen\/Finanzpolitik\/2022\/02\/2022-02-14-lars-feld-persoenlicher-beauftragter-bundesfinanzminister.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Bundesfinanzministerium &amp;#8211; Christian Lindner bestellt Lars Feld zum Pers\u00f6nlichen Beauftragten des Bundesministers der Finanzen f\u00fcr die gesamtwirtschaftliche Entwicklung&lt;\/a&gt;, 14 f\u00e9vrier 2022'><sup>6<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>Apr\u00e8s avoir rendu sa premi\u00e8re visite au pr\u00e9sident Macron \u00e0 Paris pour honorer l\u2019amiti\u00e9 franco-allemande, Olaf Scholz s\u2019est ensuite rendu \u00e0 Washington les 6 et 7 f\u00e9vrier, o\u00f9 il est notamment observ\u00e9 qu\u2019il ne se prononce pas sur Nord Stream 2 sp\u00e9cifiquement, se contentant d\u2019affirmer qu\u2019aucune sanction n\u2019est d\u00e9finitivement exclue. \u00c0 la suite du pr\u00e9sident de la r\u00e9publique, le chancelier se rend \u00e0 Moscou le 14 f\u00e9vrier. \u00c9galement re\u00e7u \u00e0 la table d\u00e9mesur\u00e9e du pr\u00e9sident russe, il n\u2019obtient pas beaucoup plus que le visiteur pr\u00e9c\u00e9dent. La guerre \u00e9clate v\u00e9ritablement huit jours plus tard lorsque le pr\u00e9sident Poutine, apr\u00e8s un conseil de d\u00e9fense, reconna\u00eet les r\u00e9publiques du Donbass.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4 \u2014 Guerre en Europe et grand pivot d\u2019Olaf Scholz&#160;: \u00ab&#160;Germany has joined the fight&#160;\u00bb<\/h2>\n\n\n\n<p>Le 22 f\u00e9vrier, apr\u00e8s la reconnaissance par Vladimir Poutine de l\u2019ind\u00e9pendance des deux r\u00e9publiques s\u00e9paratistes du Donbass, Olaf Scholz prend la premi\u00e8re grande d\u00e9cision de politique internationale de son mandat, en suspendant jusqu\u2019\u00e0 nouvel ordre l\u2019entr\u00e9e en service du pipeline baltique <em>Nord Stream 2<\/em>. Apr\u00e8s avoir d\u00e9clar\u00e9 que le syst\u00e8me de communication bancaire Swift ne serait pas parmi les sanctions massives d\u00e9cid\u00e9es contre les piliers de l\u2019\u00e9conomie et du r\u00e9gime russe, l\u2019Allemagne, progressivement isol\u00e9e sur la question au sein du camp occidental, consent \u00e0 en exclure plusieurs grandes banques russes, sans toutefois bloquer les \u00e9tablissements par lesquels transitent les paiements pour des livraisons d\u2019hydrocarbures&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-7-134154' title='&lt;a href=&quot;https:\/\/www.br.de\/nachrichten\/deutschland-welt\/russland-sanktionen-deutschland-fuer-gezielte-swift-beschraenkung,SyZHp1r&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Russland-Sanktionen&amp;#160;: Deutschland f\u00fcr gezielte Swift-Beschr\u00e4nkung&lt;\/a&gt;, Bayerischer Rundfunk, 26 f\u00e9vrier 2022'><sup>7<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>Le 24 au soir, alors que les arm\u00e9es russes envahissent l\u2019Ukraine et marchent sur Kiev, Olaf Scholz r\u00e9alise sa premi\u00e8re allocution t\u00e9l\u00e9vis\u00e9e en direct au peuple allemand, un format dont les chefs du gouvernement pr\u00e9c\u00e9dents avaient toujours us\u00e9 avec beaucoup de parcimonie. \u00c0 l\u2019exception de ses v\u0153ux du nouvel an, Angela Merkel ne s\u2019\u00e9tait adress\u00e9e \u00e0 ses concitoyens qu\u2019au d\u00e9but de la pand\u00e9mie de Covid-19 au printemps 2020.&nbsp;<\/p>\n\n\n\n<p>L\u2019Allemagne op\u00e8re par la suite un retournement encore plus important de sa doctrine de politique \u00e9trang\u00e8re en acceptant dans un premier temps que des pays tiers <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/10\/conversation-avec-kaja-kallas-premiere-ministre-estonienne\/\">comme l\u2019Estonie<\/a> livrent des armes l\u00e9tales dans une zone de conflit, avant d\u2019annoncer qu\u2019elle livrera des armes elle-m\u00eame. Le 26 f\u00e9vrier au soir, deux jours apr\u00e8s le d\u00e9but de l\u2019invasion, le chancelier d\u00e9clare&#160;: \u00ab&#160;L&rsquo;attaque russe marque un changement d&rsquo;\u00e9poque. Il est de notre devoir de soutenir l&rsquo;Ukraine de toutes nos forces pour la d\u00e9fense contre l&rsquo;arm\u00e9e d&rsquo;invasion de Poutine. Nous livrons donc 1 000 missiles antichars et 500 missiles stingers \u00e0 nos amis en Ukraine.&#160;\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La premi\u00e8re semaine en fonction du gouvernement \u00e0 partir du 8 d\u00e9cembre a \u00e9t\u00e9 marqu\u00e9e par un carrousel diplomatique intense, en direction de Paris, de Bruxelles et de Varsovie.<\/p><cite>pierre mennerat<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le d\u00e9bat au Bundestag le 27 f\u00e9vrier 2022, et les discours prononc\u00e9s par le chancelier et sa ministre des affaires \u00e9trang\u00e8res, ont constitu\u00e9 un v\u00e9ritable <a href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/28\/le-jour-ou-la-politique-etrangere-allemande-a-change\/\">renouveau de la doctrine politique allemande<\/a>. Au m\u00eame moment, une foule de 100 000 personnes \u2013 loin des 20 000 personnes initialement attendues \u2013 remplit le <em>Tiergarten <\/em>entre la porte de Brandebourg et le quartier gouvernemental. Le ministre des finances annonce lors de la session du Bundestag une augmentation massive des budgets militaires allemands, la ministre des affaires \u00e9trang\u00e8res parle d\u2019une nouvelle politique \u00e9trang\u00e8re pour une nouvelle \u00e9poque.&nbsp;<\/p>\n\n\n\n<p>Dans sa d\u00e9claration gouvernementale, le chancelier Scholz appelle \u00e0 un effort international pour mettre fin \u00e0 la guerre d&rsquo;agression de la Russie contre l&rsquo;Ukraine. \u00ab&#160;&nbsp;Nous ne nous reposerons pas tant que la paix ne sera pas assur\u00e9e en Europe.&#160;\u00bb Olaf Scholz pr\u00e9sente \u00e0 cet effet un plan en cinq points. Premi\u00e8rement, \u00e0 court terme, il s\u2019agit d\u2019aider l\u2019Ukraine \u00e0 se d\u00e9fendre, y compris en lui fournissant des armes&#160;; deuxi\u00e8mement, de pousser la Russie \u00e0 la paix par des sanctions \u00e9conomiques&#160;; troisi\u00e8mement, d\u2019\u00e9viter un \u00e9largissement du conflit en renfor\u00e7ant la contribution allemande au front oriental de l\u2019OTAN&#160;; quatri\u00e8mement de renforcer durablement la d\u00e9fense allemande, \u00e0 travers un fonds sp\u00e9cial pour la Bundeswehr et cinqui\u00e8mement de repenser pour le long terme les fondamentaux de la politique \u00e9trang\u00e8re allemande.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22655671_000006-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22655671_000006-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22655671_000006-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22655671_000006-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22655671_000006-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 AP Photo\/Markus Schreiber<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Le soir m\u00eame, l\u2019Union europ\u00e9enne annonce qu\u2019elle va elle-m\u00eame acheter et fournir des armements \u00e0 l\u2019Ukraine, une d\u00e9cision qui n\u2019aurait pas \u00e9t\u00e9 possible sans le pivot allemand.&nbsp;<\/p>\n\n\n\n<p>La soci\u00e9t\u00e9 allemande semble pour le moment unie derri\u00e8re cette politique de fermet\u00e9 en faveur de l\u2019Ukraine et contre la Russie&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-8-134154' title='&lt;a href=&quot;http:\/\/ARD-DeutschlandTrend: Mehrheit unterst\u00fctzt deutschen Ukraine-Kurs&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;ARD-DeutschlandTrend&amp;#160;: Mehrheit unterst\u00fctzt deutschen Ukraine-Kurs&lt;\/a&gt;, Tagesschau, 3 mars 2022'><sup>8<\/sup><\/a><\/span><\/span>. Selon Infratest Dimap, le 3 mars, 65&#160;% des Allemands approuvent la mise en place du budget sp\u00e9cial de 100 milliards pour la Bundeswehr et 61&#160;% d\u2019entre eux approuvent les livraisons de mat\u00e9riel de guerre l\u00e9tal \u00e0 l\u2019Ukraine. L\u2019acceptation des mesures de r\u00e9torsion envers la Russie \u00e9taient \u00e9galement \u00e9lev\u00e9es, y compris au vu des risques de p\u00e9nuries et de hausses des prix.<\/p>\n\n\n\n<p>En acceptant le r\u00e9armement et en soutenant ses alli\u00e9s orientaux, l\u2019opinion publique allemande prend en quelque sorte conscience du prix \u00e0 payer pour la libert\u00e9 et la d\u00e9mocratie, apr\u00e8s des ann\u00e9es de refoulement&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-9-134154' title='Franke, Ulrike,&amp;nbsp; &lt;a href=&quot;https:\/\/warontherocks.com\/2021\/05\/a-millennial-considers-the-new-german-problem-after-30-years-of-peace\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;A Millennial Considers the New German Problem After 30 Years of Peace&lt;\/a&gt;, War on the Rocks, 19 mai 2021'><sup>9<\/sup><\/a><\/span><\/span>. La doctrine du \u00ab&#160;&nbsp;changement par le commerce&#160;\u00bb (<em>Wandel durch Handel<\/em>) dominait la politique \u00e9trang\u00e8re allemande depuis la r\u00e9unification&#160;: en \u00e9changeant des biens, l\u2019\u00e9conomie allemande devait aussi v\u00e9hiculer une conception multilat\u00e9rale et pacifique de l\u2019ordre mondial. Cette vision progressiste avait \u00e9t\u00e9 d\u00e9j\u00e0 brutalement contest\u00e9e sous le mandat (2017-2021) du pr\u00e9sident des \u00c9tats-Unis Donald J. Trump, qui avait adopt\u00e9 vis-\u00e0-vis de l\u2019Allemagne une posture accusatrice lui reprochant de ne pas payer pour sa d\u00e9fense.&nbsp;<\/p>\n\n\n\n<p>La dimension proprement allemande du tournant g\u00e9opolitique actuel peut \u00eatre mieux comprise en faisant appel au concept de \u00ab&#160;&nbsp;<em>wehrhafte Demokratie<\/em>&#160;\u00bb (d\u00e9mocratie capable de se d\u00e9fendre), qui \u00e9tait au c\u0153ur de la Loi fondamentale de 1949. Ce dernier a conduit notamment les services de renseignement int\u00e9rieurs de la RFA \u00e0 s\u2019appeler \u00ab&#160;&nbsp;<em>Verfassungsschutz<\/em>&#160;\u00bb (d\u00e9fense de la constitution), le gouvernement f\u00e9d\u00e9ral \u00e0 interdire des partis comme le SRP n\u00e9onazi en 1952 ou le KPD en 1956, ou \u00e0 promulguer en 1972 un d\u00e9cret excluant les individus jug\u00e9s radicaux et ennemis de la constitution du service public. L\u2019objectif de cette doctrine est d\u2019abord de ne pas laisser se r\u00e9p\u00e9ter le cours des \u00e9v\u00e9nements des ann\u00e9es 1929-1933 qui avaient conduit la constitution allemande \u00e0 \u00eatre vid\u00e9e de son sens avec un glissement progressif vers la dictature. Cette doctrine de la d\u00e9mocratie capable de se d\u00e9fendre est un des piliers de \u00ab&#160;l\u2019ordre fondamental lib\u00e9ral et d\u00e9mocratique&#160;\u00bb (<em>Freiheitlich-demokratische Grundordnung<\/em>) et a donc une vocation essentiellement int\u00e9rieure&#160;: d\u00e9fendre l&rsquo;ordre public constitutionnel, consid\u00e9r\u00e9 comme le garant des libert\u00e9s. Le pivot g\u00e9opolitique de Berlin fait indirectement appel \u00e0 cet \u00e9l\u00e9ment central de la doctrine constitutionnelle allemande&#160;: la d\u00e9fense de la d\u00e9mocratie et de l\u2019ordre politique lib\u00e9ral passe d\u00e9sormais aussi par sa d\u00e9fense \u00e0 l\u2019\u00e9tranger.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le pivot g\u00e9opolitique de Berlin fait indirectement appel \u00e0 cet \u00e9l\u00e9ment central de la doctrine constitutionnelle allemande&#160;: la d\u00e9fense de la d\u00e9mocratie et de l\u2019ordre politique lib\u00e9ral passe d\u00e9sormais aussi par sa d\u00e9fense \u00e0 l\u2019\u00e9tranger.&nbsp;<\/p><cite>pierre mennerat<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Les modalit\u00e9s de ce r\u00e9armement seront donc l\u2019objet d\u2019un rapport de forces politique, entre un gouvernement d\u00e9termin\u00e9 et des bases partisanes plus partag\u00e9es sur l\u2019usage de la force arm\u00e9e. Un r\u00e9tablissement du service militaire, suspendu en 2011, reste peu probable \u00e0 ce stade. Cependant, le 14 mars, la ministre f\u00e9d\u00e9rale de la D\u00e9fense Christine Lambrecht (SPD) met un terme \u00e0 l\u2019incertitude concernant le remplacement de la flotte d\u2019avions de combat Tornado, en annon\u00e7ant le choix de 35 appareils F-35 du constructeur am\u00e9ricain Lockheed Martin capable de porter des bombes nucl\u00e9aires am\u00e9ricaines et de 15 Eurofighters Typhoon adapt\u00e9s pour la guerre \u00e9lectronique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-10-134154' title='&lt;a href=&quot;https:\/\/www.zeit.de\/zustimmung?url=https%3A%2F%2Fwww.zeit.de%2Fpolitik%2Fdeutschland%2F2022-03%2Fbundeswehr-f-35-jets-militaer&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Milit\u00e4r&amp;#160;: F-35-Tarnkappenjets sollen Tornados der Bundeswehr ersetzen&lt;\/a&gt;, Zeit Online, 14 mars 2022'><sup>10<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5 \u2014 De nouveaux \u00e9quilibres gouvernementaux et partisans<\/h2>\n\n\n\n<p>Apr\u00e8s avoir b\u00e9n\u00e9fici\u00e9 d\u2019un bref \u00e9tat de gr\u00e2ce dans les sondages, les sociaux-d\u00e9mocrates du nouveau chancelier ont connu un l\u00e9ger recul, \u00e9changeant plusieurs fois la premi\u00e8re position avec l\u2019Union CDU\/CSU, avec qui les sociaux-d\u00e9mocrates restent au coude-\u00e0-coude. Les chr\u00e9tiens-d\u00e9mocrates ont conclu provisoirement leur crise de direction en \u00e9lisant \u00e0 leur t\u00eate le lib\u00e9ral-conservateur Friedrich Merz le 22 janvier&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-11-134154' title='&lt;a href=&quot;Merz mit 95,3 Prozent offiziell zum CDU-Chef gew\u00e4hlt&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Parteien&amp;#160;: Merz mit 95,3 Prozent offiziell zum CDU-Chef gew\u00e4hlt&lt;\/a&gt;, Zeit Online, 22 janvier 2022'><sup>11<\/sup><\/a><\/span><\/span> et reprennent des couleurs dans les sondages. Friedrich Merz a ensuite \u00e9galement enlev\u00e9 \u00e0 Ralph Brinkhaus la t\u00eate du groupe parlementaire et est donc devenu le visage de l\u2019opposition au gouvernement au Bundestag. Dans la guerre ukrainienne, il se cantonne n\u00e9anmoins \u00e0 un soutien des sanctions et de la politique de fermet\u00e9 du gouvernement. Ainsi, malgr\u00e9 la fin de la p\u00e9riode de gr\u00e2ce dans l\u2019opinion, l\u2019invasion ukrainienne et le pivot g\u00e9opolitique du gouvernement Scholz a entra\u00een\u00e9 une hausse de popularit\u00e9 personnelle significative pour le chancelier et ses principaux ministres.&nbsp;<\/p>\n\n\n\n<p>De son c\u00f4t\u00e9, \u00e0 l\u2019occasion de la guerre en Ukraine, Olaf Scholz a r\u00e9ussi \u00e0 prendre le dessus sur les membres les plus ouverts aux arguments de la Russie au sein de son propre parti, notamment le pr\u00e9sident du groupe parlementaire social-d\u00e9mocrate Rolf M\u00fctzenich, la ministre-pr\u00e9sidente du Land de Mecklenbourg-Pom\u00e9ranie Occidentale, et l\u2019ancien chancelier Gerhard Schr\u00f6der. Ce dernier n\u2019a cependant pas d\u00e9missionn\u00e9 de ses postes aux conseils d\u2019administration de diff\u00e9rentes entreprises proches du Kremlin et a tent\u00e9 de son propre gr\u00e9 de jouer un r\u00f4le de m\u00e9diateur aupr\u00e8s de Vladimir Poutine&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-12-134154' title='&lt;a href=&quot;https:\/\/www.spiegel.de\/ausland\/wladimir-putin-und-gerhard-schroeder-kreml-hat-keine-informationen-zu-treffen-a-90a0919a-94e5-40b8-956c-56f4add8a384&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Wladimir Putin und Gerhard Schr\u00f6der&amp;#160;: Kreml hat \u00bbkeine Informationen\u00ab&amp;#160;zu Treffen&lt;\/a&gt;, Der Spiegel, 11 mars 2022'><sup>12<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>Contrairement \u00e0 une repr\u00e9sentation souvent pr\u00e9sente en France et \u00e0 l\u2019\u00e9tranger, les Gr\u00fcnen, qui avaient alert\u00e9 pendant la campagne sur la d\u00e9pendance au gaz russe, font preuve d\u2019une grande fermet\u00e9 depuis le d\u00e9but de la crise. Les ministres Annalena Baerbock et Robert Habeck, s\u2019ils n\u2019occupent plus formellement la direction du parti, en sont encore les dirigeants de fait. Cependant la d\u00e9cision du chancelier Scholz d\u2019augmenter significativement les budgets militaires, prise selon la presse en concertation avec le seul ministre des finances Lindner, a fait grincer des dents au sein du parti \u00e9cologiste, sans faire cependant \u00e9clater de v\u00e9ritable crise politique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-13-134154' title='&lt;a href=&quot;https:\/\/www.tagesschau.de\/inland\/innenpolitik\/gruene-krieg-101.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Aufr\u00fcstung und Waffen&amp;#160;: Warum der Protest bei den Gr\u00fcnen ausbleibt&lt;\/a&gt;, Tagesschau, 3 mars 2022'><sup>13<\/sup><\/a><\/span><\/span>.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Malgr\u00e9 la fin de la p\u00e9riode de gr\u00e2ce dans l\u2019opinion, l\u2019invasion ukrainienne et le pivot g\u00e9opolitique du gouvernement Scholz a entra\u00een\u00e9 une hausse de popularit\u00e9 personnelle significative pour le chancelier et ses principaux ministres.&nbsp;<\/p><cite>pierre mennerat<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Les lib\u00e9raux-d\u00e9mocrates doivent eux aussi r\u00e9viser leurs positions concernant la d\u00e9pense publique. Confront\u00e9 \u00e0 la r\u00e9alit\u00e9 de la gestion de la crise \u00e9pid\u00e9mique, puis militaire, Christian Lindner s\u2019est prononc\u00e9 pour des arbitrages entre les minist\u00e8res&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-14-134154' title='&lt;a href=&quot;https:\/\/www.spiegel.de\/wirtschaft\/soziales\/schuldenbremse-und-sondervermoegen-bundeswehr-christian-lindner-will-im-haushalt-noch-staerker-priorisieren-a-7448fe3d-2bb4-483f-b411-a6c81b02ff7e&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Christian Lindner will im Haushalt noch st\u00e4rker priorisieren&lt;\/a&gt;, Der Spiegel, 2 mars 202'><sup>14<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>La crise clarifie ainsi les r\u00f4les au sein du gouvernement f\u00e9d\u00e9ral allemand, dans une forme de&nbsp; \u00ab&#160;&nbsp;t\u00e9trarchie&#160;\u00bb qui se r\u00e9partit les r\u00f4les dans la gestion du conflit. Christian Lindner, Annalena Baerbock, Robert Habeck et bien s\u00fbr Olaf Scholz semblent bien agir de concert. Le d\u00e9bat au Bundestag qui a suivi le discours d\u2019Olaf Scholz illustre un point qui peut appara\u00eetre \u00e9trange \u00e0 un observateur fran\u00e7ais ou am\u00e9ricain&#160;: dans le syst\u00e8me gouvernemental allemand, le chancelier a une \u00ab&#160;&nbsp;<em>Richtlinienkompetenz<\/em>&#160;\u00bb \u2013&nbsp;il fixe les lignes directrices \u2013 mais les ministres sont tr\u00e8s importants dans la mise en \u0153uvre et la d\u00e9termination pr\u00e9cise de ces lignes dans le d\u00e9tail. Il n&rsquo;y a pas ainsi de \u00ab&#160;&nbsp;domaine r\u00e9serv\u00e9&#160;\u00bb de la politique \u00e9trang\u00e8re et de d\u00e9fense et, dans la crise actuelle qui est \u00e0 la fois financi\u00e8re, g\u00e9opolitique et \u00e9conomique, les trois ministres comp\u00e9tents \u2013&nbsp;qui sont aussi les leaders de leurs partis \u2013 sont tous trois mis \u00e0 contribution.<\/p>\n\n\n\n<p>Ce partage officieux du pouvoir est un ph\u00e9nom\u00e8ne r\u00e9current de la vie politique allemande. Au d\u00e9but de la d\u00e9cennie 2010 une sorte de \u00ab&#160;&nbsp;dyarchie&#160;\u00bb s&rsquo;\u00e9tait \u00e9tablie entre Angela Merkel et son tr\u00e8s puissant ministre des finances Wolfgang Sch\u00e4uble dans le contexte de la crise de l&rsquo;Euro, jusqu\u2019\u00e0 son d\u00e9part du gouvernement en 2017. Une dualit\u00e9 fonctionnelle avait \u00e9galement vue le jour entre le chancelier Adenauer et son tr\u00e8s populaire ministre de l\u2019\u00e9conomie Erhard \u00e0 l&rsquo;\u00e9poque ou la R\u00e9publique f\u00e9d\u00e9rale avait comme priorit\u00e9 de reconstruire la prosp\u00e9rit\u00e9 au temps du miracle \u00e9conomique, puis une dualit\u00e9 Schmidt-Genscher \u2013&nbsp;qui devint une dualit\u00e9 Kohl-Genscher \u00e0 partir de 1982 \u2013 lorsque la nouvelle guerre froide et la r\u00e9unification devinrent les t\u00e2ches de l&rsquo;heure. Pour la premi\u00e8re fois cependant \u00e9merge un groupe de quatre ministres qui se partagent le premier plan, qui sont \u00e9galement les leaders des trois partis dans la coalition. Cependant ces quatre chefs de partis occupent \u00e9galement des postes essentiels dans la gestion de la crise actuelle \u2013 outre la direction du gouvernement \u2013 les finances, les affaires \u00e9trang\u00e8res et l\u2019\u00e9conomie. Mais la stabilit\u00e9 de ce groupe de quatre ministres puissants n\u2019est cependant pas garantie, et la formation d\u2019un duo complice entre Olaf Scholz et Christian Lindner sur certains dossiers pourrait \u00e0 terme irriter les Verts s\u2019ils se sentent exclus des grandes d\u00e9cisions&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-134154' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#easy-footnote-bottom-15-134154' title='&lt;a href=&quot;https:\/\/plus.tagesspiegel.de\/politik\/krach-in-der-ampel-423730.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Krach in der Ampel&amp;#160;: Das Duo Scholz-Lindner br\u00fcskiert die Gr\u00fcnen&lt;\/a&gt;, Tagesspiegel, 15 mars 2022'><sup>15<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pivot g\u00e9opolitique de Berlin fait appel \u00e0 un \u00e9l\u00e9ment central de la doctrine constitutionnelle allemande&#160;&#160;: d\u00e9sormais, la d\u00e9fense de la d\u00e9mocratie et de l\u2019ordre politique lib\u00e9ral passe aussi par sa d\u00e9fense \u00e0 l\u2019\u00e9tranger. Cinq points pour comprendre comment l\u2019Allemagne a chang\u00e9 au cours des derni\u00e8res semaines.<\/p>\n","protected":false},"author":1782,"featured_media":134158,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":17,"footnotes":""},"categories":[1731],"tags":[],"staff":[1691],"editorial_format":[4849],"serie":[],"audience":[],"geo":[536],"class_list":["post-134154","post","type-post","status-publish","format-standard","hentry","category-politique","staff-pierre-mennerat","editorial_format-etudes","geo-centres"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":134158,"excerpt":"Le pivot g\u00e9opolitique de Berlin fait appel \u00e0 un \u00e9l\u00e9ment central de la doctrine constitutionnelle allemande : d\u00e9sormais, la d\u00e9fense de la d\u00e9mocratie et de l\u2019ordre politique lib\u00e9ral passe aussi par sa d\u00e9fense \u00e0 l\u2019\u00e9tranger. Cinq points pour comprendre comment l\u2019Allemagne a chang\u00e9 au cours des derni\u00e8res semaines.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le pivot g\u00e9opolitique de Berlin fait appel \u00e0 un \u00e9l\u00e9ment central de la doctrine constitutionnelle allemande&#160;: d\u00e9sormais, la d\u00e9fense de la d\u00e9mocratie et de l\u2019ordre politique lib\u00e9ral passe aussi par sa d\u00e9fense \u00e0 l\u2019\u00e9tranger. Cinq points pour comprendre comment l\u2019Allemagne a chang\u00e9 au cours des derni\u00e8res semaines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-16T11:47:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-16T17:26:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/100joursreseaux.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"clementf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/gc-centjours.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"clementf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/\",\"name\":\"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg\",\"datePublished\":\"2022-03-16T11:47:27+00:00\",\"dateModified\":\"2022-03-16T17:26:41+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"German Chancellor Olaf Scholz stands behind a window with the reflection of the German flag as he waits for the arrival of Jordan's King Abdullah II for talks at the chancellery in Berlin, Germany, Tuesday, March 15, 2022. (AP Photo\/Markus Schreiber)\/MSC105\/22074366147807\/\/2203151115\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84\",\"name\":\"clementf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g\",\"caption\":\"clementf\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/","og_locale":"fr_FR","og_type":"article","og_title":"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne | Le Grand Continent","og_description":"Le pivot g\u00e9opolitique de Berlin fait appel \u00e0 un \u00e9l\u00e9ment central de la doctrine constitutionnelle allemande&#160;: d\u00e9sormais, la d\u00e9fense de la d\u00e9mocratie et de l\u2019ordre politique lib\u00e9ral passe aussi par sa d\u00e9fense \u00e0 l\u2019\u00e9tranger. Cinq points pour comprendre comment l\u2019Allemagne a chang\u00e9 au cours des derni\u00e8res semaines.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/","og_site_name":"Le Grand Continent","article_published_time":"2022-03-16T11:47:27+00:00","article_modified_time":"2022-03-16T17:26:41+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/100joursreseaux.jpg","type":"image\/jpeg"}],"author":"clementf","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/gc-centjours.jpg","twitter_misc":{"\u00c9crit par":"clementf","Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/","name":"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg","datePublished":"2022-03-16T11:47:27+00:00","dateModified":"2022-03-16T17:26:41+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg","width":2560,"height":1706,"caption":"German Chancellor Olaf Scholz stands behind a window with the reflection of the German flag as he waits for the arrival of Jordan's King Abdullah II for talks at the chancellery in Berlin, Germany, Tuesday, March 15, 2022. (AP Photo\/Markus Schreiber)\/MSC105\/22074366147807\/\/2203151115"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/03\/16\/cinq-points-pour-comprendre-le-pivot-geopolitique-de-scholz-en-allemagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Cinq points pour comprendre le pivot g\u00e9opolitique de Scholz en Allemagne"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84","name":"clementf","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g","caption":"clementf"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1691,"name":"Pierre Mennerat","slug":"pierre-mennerat","description":"<span style=\"font-weight: 400\">Pierre Mennerat est germaniste agr\u00e9g\u00e9 d\u2019allemand \u00e0 l\u2019ENS-Ulm. Titulaire d\u2019un dipl\u00f4me en histoire contemporaine et litt\u00e9rature germanophone de la Sorbonne, il y est d\u00e9sormais doctorant en histoire contemporaine de l\u2019Allemagne. Ses travaux portent sur la diplomatie de l\u2019Allemagne f\u00e9d\u00e9rale face \u00e0 l\u2019apartheir entre 1983 et 1989 et sur les droits de l\u2019homme en R\u00e9publique f\u00e9d\u00e9rale. <\/span>","first_name":"Pierre ","last_name":"Mennerat","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/01\/JHOJd33h_400x400.jpeg","width":400,"height":400,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg","width":2560,"height":1706,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/03\/SIPA_AP22661192_000006-scaled.jpg","width":2560,"height":1706,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/134154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1782"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=134154"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/134154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/134158"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=134154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=134154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=134154"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=134154"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=134154"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=134154"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=134154"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=134154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}