{"id":13175,"date":"2019-03-03T23:37:42","date_gmt":"2019-03-03T22:37:42","guid":{"rendered":"https:\/\/lldl.eu\/?p=13175"},"modified":"2019-04-27T15:30:12","modified_gmt":"2019-04-27T13:30:12","slug":"le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/","title":{"rendered":"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba"},"content":{"rendered":"\n<p><em>La Havane. <\/em>La Constitution cubaine de 1976 est entr\u00e9e dans les annales de l&rsquo;\u00eele des Cara\u00efbes. Lors du r\u00e9f\u00e9rendum du 24 f\u00e9vrier, 6,8 millions de Cubains ont ratifi\u00e9 la nouvelle Constitution, ce qui repr\u00e9sente 86,85&#160;% du nombre total des citoyens \u00e2g\u00e9s de plus de 16 ans inscrits sur les listes \u00e9lectorales. Environ 706 000 personnes ont vot\u00e9 pour le \u201cNon\u201d, soit 9&#160;% du total des votes exprim\u00e9s&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-13175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#easy-footnote-bottom-1-13175' title='&lt;a href=&quot;http:\/\/www.granma.cu\/reforma-constitucional\/2019-02-25\/cuba-dijo-si-por-la-nueva-constitucion-25-02-2019-16-02-47&quot;&gt;Cuba dijo s\u00ed a la nueva Constituci\u00f3n&lt;\/a&gt;. Granma, 25 f\u00e9vrier 2019'><sup>1<\/sup><\/a><\/span><\/span>. Bien que Cuba nous ait habitu\u00e9s \u00e0 la grandiloquence de ses chiffres dans les processus \u00e9lectoraux, ce vote s&rsquo;est d\u00e9roul\u00e9 dans un contexte de changement \u00e9conomique et g\u00e9n\u00e9rationnel qui a eu un impact certain sur le r\u00e9sultat final.<\/p>\n\n\n\n<p>Le texte constitutionnel vise \u00e0 devenir un acte plus formel d&rsquo;application et de protection de la loi, mais il n&rsquo;est pas exempt de lacunes avec de simples mentions de droits sans avancer dans leurs garanties. Deux mois se sont \u00e9coul\u00e9s entre l&rsquo;approbation nominale de l&rsquo;Assembl\u00e9e nationale en d\u00e9cembre 2018, lors de la deuxi\u00e8me session ordinaire, et la tenue du r\u00e9f\u00e9rendum. Durant cette p\u00e9riode, en utilisant les moyens de communication traditionnels et, de mani\u00e8re in\u00e9dite, les r\u00e9seaux sociaux et autres espaces num\u00e9riques officiels, le gouvernement cubain a men\u00e9 une campagne pour le \u201cOui\u201d, soutenue par les conqu\u00eates historiques de la R\u00e9volution et la d\u00e9fense de la souverainet\u00e9 et de la nation (#YoVotoSi, #S\u00edPorLaRevolucion, #SomosContinuidad). La grande controverse sur les r\u00e9seaux sociaux, \u00e0 laquelle ont fait \u00e9cho de nombreux m\u00e9dias et organisations d&rsquo;opposition, ainsi que la presse internationale en g\u00e9n\u00e9ral&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-13175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#easy-footnote-bottom-2-13175' title='&lt;a href=&quot;https:\/\/www.bbc.com\/mundo\/noticias-47341053&quot;&gt;Referendo Constitucional en Cuba&amp;#160;: 5 puntos que explican la pol\u00e9mica por la Constituci\u00f3n que se vot\u00f3 este domingo&lt;\/a&gt;. BBC, 26 f\u00e9vrier 2019.'><sup>2<\/sup><\/a><\/span><\/span>, \u00e9tait aussi in\u00e9dite, affirmant que l&rsquo;ouverture num\u00e9rique du pays a g\u00e9n\u00e9r\u00e9 pour la premi\u00e8re fois que des milliers de Cubains aient utilis\u00e9 les r\u00e9seaux sociaux pour exprimer leur m\u00e9contentement face au texte (#YoVotoNo, #NoAprueboElReferendo, #Ni1M\u00e1s) et avec l&rsquo;impossibilit\u00e9 d&rsquo;exercer son vote de l&rsquo;ext\u00e9rieur.<\/p>\n\n\n\n<p>Quel est l&rsquo;impact du texte final sur la politique nationale et la citoyennet\u00e9 cubaine&#160;? Dans le domaine social, la Constitution ne mentionne pas la soci\u00e9t\u00e9 civile, la pauvret\u00e9 ou les in\u00e9galit\u00e9s, ni l&rsquo;\u00e9galit\u00e9 des chances entre les hommes et les femmes. En ce qui concerne le mariage pour tous, elle conditionne le droit \u00e0 un r\u00e9f\u00e9rendum sur le Code de la famille dans deux ans et \u00e9limine d\u00e9finitivement la possibilit\u00e9 d&rsquo;adoption pour les couples homosexuels&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-13175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#easy-footnote-bottom-3-13175' title='&lt;a href=&quot;http:\/\/media.cubadebate.cu\/wp-content\/uploads\/2019\/01\/Constitucion-Cuba-2019.pdf&quot;&gt;Constituci\u00f3n de la Rep\u00fablica de Cuba&lt;\/a&gt;.'><sup>3<\/sup><\/a><\/span><\/span>. Sur le plan politique, la cr\u00e9ation d&rsquo;une Cour des garanties constitutionnelles ou d&rsquo;un organe similaire, la reconnaissance du droit \u00e0 l&rsquo;investissement pour les nationaux, les droits des Cubains vivant \u00e0 l&rsquo;\u00e9tranger, les libert\u00e9s politiques et l&rsquo;\u00e9lection directe du Pr\u00e9sident de la R\u00e9publique, entre autres, ont \u00e9t\u00e9 supprim\u00e9s du texte&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-13175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#easy-footnote-bottom-4-13175' title='DOMINGUEZ DELGADO Jessica, &lt;a href=&quot;https:\/\/eltoque.com\/cuanto-cambio-en-realidad-la-constitucion-que-sera-votada-en-cuba\/&quot;&gt;\u00bfCu\u00e1nto cambi\u00f3 del proyecto a la constituci\u00f3n que ser\u00e1 votada el 24 de febrero&lt;\/a&gt;&amp;#160;?, El Toque, 15 janvier 2019'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Un \u00e9l\u00e9ment positif est l&rsquo;\u00e9l\u00e9vation au rang constitutionnel de la question de la violence de genre, ainsi que la pond\u00e9ration de la municipalit\u00e9 en tant qu'\u00a0\u00bbunit\u00e9 politico-administrative primaire et fondamentale de l&rsquo;organisation nationale&#160;\u00bb (article 168). D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, le choix des modifications entre le projet de Constitution et le texte final soumis au r\u00e9f\u00e9rendum ne r\u00e9pondait pas aux crit\u00e8res de majorit\u00e9, mais \u00e9tait laiss\u00e9 \u00e0 la discr\u00e9tion des membres de la commission de r\u00e9daction. Ce type de proc\u00e9dure ternit et remet en cause l&rsquo;importance que le pays attache \u00e0 la participation citoyenne dans la prise de d\u00e9cision.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Perspectives <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>La nouvelle Constitution \u00e9largit et am\u00e9liore la formulation de certains droits, mais leur r\u00e9affirmation d\u00e9pend de futures lois. Apparemment, le r\u00e9f\u00e9rendum sera plus assid\u00fbment utilis\u00e9comme un m\u00e9canisme de participation. Cependant, du point de vue de la th\u00e9orie politique, cela ne devrait m\u00eame pas \u00eatre le terme utilis\u00e9, mais plut\u00f4t celui de pl\u00e9biscite pour d\u00e9signer les actes promus par l&rsquo;ex\u00e9cutif ou le l\u00e9gislatif.<\/li><li>Avec l&rsquo;extension de 300 points Wifi \u00e0 travers le pays et l&rsquo;insertion progressive de la population dans le cyberespace, la population entre dans une \u00e8re num\u00e9rique \u00ab&#160;plus d\u00e9mocratique&#160;\u00bb, qui va diversifier l&rsquo;acc\u00e8s \u00e0 d&rsquo;autres sources d&rsquo;information non officielles. Reste \u00e0 \u00e9valuer l&rsquo;impact de ces ressources sur la pression citoyenne pour la r\u00e9affirmation des droits et une plus grande transparence institutionnelle.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p> Le 24 f\u00e9vrier 2019, un r\u00e9f\u00e9rendum populaire s&rsquo;est tenu pour voter en faveur de la nouvelle Constitution cubaine. La journ\u00e9e a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e de deux mois de propagande officielle intense en faveur du \u201cOui\u201d et avec tr\u00e8s peu d&rsquo;espaces formels de discussion qui permettraient une analyse plus approfondie des implications juridiques et des droits de la nouvelle Constitution. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[1664],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525],"class_list":["post-13175","post","type-post","status-publish","format-standard","hentry","category-politique","staff-lianne-guerra-rondon","editorial_format-actu-breves","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":" Le 24 f\u00e9vrier 2019, un r\u00e9f\u00e9rendum populaire s'est tenu pour voter en faveur de la nouvelle Constitution cubaine. La journ\u00e9e a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e de deux mois de propagande officielle intense en faveur du \u201cOui\u201d et avec tr\u00e8s peu d'espaces formels de discussion qui permettraient une analyse plus approfondie des implications juridiques et des droits de la nouvelle Constitution. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le 24 f\u00e9vrier 2019, un r\u00e9f\u00e9rendum populaire s&#039;est tenu pour voter en faveur de la nouvelle Constitution cubaine. La journ\u00e9e a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e de deux mois de propagande officielle intense en faveur du \u201cOui\u201d et avec tr\u00e8s peu d&#039;espaces formels de discussion qui permettraient une analyse plus approfondie des implications juridiques et des droits de la nouvelle Constitution.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-03T22:37:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-27T13:30:12+00:00\" \/>\n<meta name=\"author\" content=\"alevals\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"alevals\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/\",\"name\":\"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2019-03-03T22:37:42+00:00\",\"dateModified\":\"2019-04-27T13:30:12+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/65e95442ccc8faeb99165aa95bcea06e\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/65e95442ccc8faeb99165aa95bcea06e\",\"name\":\"alevals\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/94b13c11b37d5487c1720b83c90d23d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/94b13c11b37d5487c1720b83c90d23d4?s=96&d=mm&r=g\",\"caption\":\"alevals\"},\"description\":\"My french info\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/","og_locale":"fr_FR","og_type":"article","og_title":"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba | Le Grand Continent","og_description":"Le 24 f\u00e9vrier 2019, un r\u00e9f\u00e9rendum populaire s'est tenu pour voter en faveur de la nouvelle Constitution cubaine. La journ\u00e9e a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e de deux mois de propagande officielle intense en faveur du \u201cOui\u201d et avec tr\u00e8s peu d'espaces formels de discussion qui permettraient une analyse plus approfondie des implications juridiques et des droits de la nouvelle Constitution.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/","og_site_name":"Le Grand Continent","article_published_time":"2019-03-03T22:37:42+00:00","article_modified_time":"2019-04-27T13:30:12+00:00","author":"alevals","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"alevals","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/","name":"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2019-03-03T22:37:42+00:00","dateModified":"2019-04-27T13:30:12+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/65e95442ccc8faeb99165aa95bcea06e"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/03\/le-peuple-cubain-oublie-dans-la-campagne-ouipourcuba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le peuple cubain oubli\u00e9 dans la campagne #OuipourCuba"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/65e95442ccc8faeb99165aa95bcea06e","name":"alevals","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/94b13c11b37d5487c1720b83c90d23d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94b13c11b37d5487c1720b83c90d23d4?s=96&d=mm&r=g","caption":"alevals"},"description":"My french info"}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1664,"name":"Lianne Guerra Rond\u00f3n","slug":"lianne-guerra-rondon","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/13175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=13175"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/13175\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=13175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=13175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=13175"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=13175"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=13175"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=13175"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=13175"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=13175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}