{"id":131402,"date":"2022-09-03T06:52:00","date_gmt":"2022-09-03T04:52:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=131402"},"modified":"2022-09-03T09:48:04","modified_gmt":"2022-09-03T07:48:04","slug":"lempire-et-lordre-mondial-selon-jiang-shigong","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/","title":{"rendered":"L&#8217;empire et l&rsquo;ordre mondial selon Jiang Shigong"},"content":{"rendered":"\n<p class=\"intro\">N\u00e9 en 1967, professeur de droit \u00e0 l&rsquo;Universit\u00e9 de P\u00e9kin, Jiang Shigong est un \u00e9minent apologiste du pouvoir \u00e9tatique en Chine. Son long et important essai de 2018 d\u00e9finit et d\u00e9fend la pens\u00e9e de Xi Jinping (\u00ab&#160;Philosophie et histoire&#160;: Interpr\u00e9ter \u00ab&#160;l&rsquo;\u00e8re Xi Jinping&#160;\u00bb \u00e0 travers le rapport de Xi au XIXe Congr\u00e8s national du PCC&#160;\u00bb) sera prochainement traduit <em>in extenso <\/em>et comment\u00e9. Nous soutenons que les ambitieux arguments th\u00e9oriques de Jiang visent non seulement \u00e0 donner de la substance \u00e0 la propagande abondante de la pens\u00e9e de Xi Jinping, mais aussi \u00e0 servir de r\u00e9ponse muscl\u00e9e et critique au pluralisme de fait qui s&rsquo;est d\u00e9velopp\u00e9 dans le monde de la pens\u00e9e chinoise depuis le d\u00e9but de l&rsquo;essor de la Chine.<\/p>\n\n\n\n<p class=\"intro\">Les arguments de Jiang ne convaincront probablement que peu de personnes en dehors de la Chine, mais son texte est r\u00e9fl\u00e9chi et rigoureux dans ses tentatives d&rsquo;expliquer pourquoi le \u00ab&#160;socialisme \u00e0 caract\u00e9ristiques chinoises&#160;\u00bb n&rsquo;est pas, selon lui, un slogan vide, mais plut\u00f4t une description de l&rsquo;\u00e9conomie politique chinoise qui trace actuellement la voie vers la domination mondiale, \u00e9tant donn\u00e9 l&rsquo;\u00e9chec de la d\u00e9mocratie lib\u00e9rale am\u00e9ricaine et du communisme sovi\u00e9tique.<\/p>\n\n\n\n<p class=\"intro\">Le texte traduit ici s\u2019inscrit dans la continuit\u00e9 de certains essais pr\u00e9c\u00e9dents de Jiang en ce qu&rsquo;il sugg\u00e8re qu&rsquo;un empire mondial chinois est visible \u00e0 l&rsquo;horizon. L&rsquo;argument fondamental est assez simple&#160;: les empires ont toujours \u00e9t\u00e9 les \u00e9l\u00e9ments constitutifs des ordres politiques r\u00e9gionaux, m\u00eame avant que la mont\u00e9e de l&rsquo;imp\u00e9rialisme ne rende possible la construction d&#8217;empires mondiaux. La mont\u00e9e des id\u00e9es de souverainet\u00e9 et la formation des \u00c9tats-nations au cours de la p\u00e9riode moderne ont apport\u00e9 de nouvelles facettes \u00e0 la construction et \u00e0 l&rsquo;administration de l&#8217;empire, et a fait perdre de vue \u00e0 beaucoup son importance actuelle. Mais les empires n&rsquo;ont pas disparu, ils ont seulement chang\u00e9 de forme et de fonction. L&rsquo;essai de Jiang s&rsquo;\u00e9tend largement dans le temps et l&rsquo;espace, et semble, \u00e0 partir de l\u00e0, tenter de construire une typologie des empires. Nous pensons qu&rsquo;il s&rsquo;agit surtout de remplissage, ce qui explique par ailleurs la nature quelque peu r\u00e9p\u00e9titive du texte. L&rsquo;affirmation brute de Jiang est que l&#8217;empire &#8211; et en particulier l&#8217;empire mondial, structur\u00e9 autour des march\u00e9s, des monnaies et de la politique int\u00e9rieure des superpuissances d\u00e9guis\u00e9e en pratique juridique universelle &#8211; est un \u00e9tat in\u00e9luctable du monde contemporain. Et c&rsquo;est au tour de la Chine de diriger cet empire, \u00e9tant donn\u00e9 l&rsquo;\u00e9tat actuel du pays et du monde. Selon les mots de Jiang&#160;:<\/p>\n\n\n\n<p class=\"intro\"><em>\u00ab&#160;[L&rsquo;\u00e9tat actuel de l&#8217;empire mondial] est confront\u00e9 \u00e0 trois grands probl\u00e8mes insolubles&#160;: l&rsquo;in\u00e9galit\u00e9 toujours croissante cr\u00e9\u00e9e par l&rsquo;\u00e9conomie lib\u00e9rale&#160;; l&rsquo;\u00e9chec de l&rsquo;\u00c9tat, le d\u00e9clin politique et la gouvernance inefficace caus\u00e9s par le lib\u00e9ralisme politique&#160;; et la d\u00e9cadence et le nihilisme cr\u00e9\u00e9s par le lib\u00e9ralisme culturel. Face \u00e0 ces difficult\u00e9s, m\u00eame les \u00c9tats-Unis se sont retir\u00e9s en termes de strat\u00e9gie militaire mondiale, ce qui signifie que l&#8217;empire mondial 1.0 est actuellement confront\u00e9 \u00e0 une grande crise, et que les r\u00e9voltes, la r\u00e9sistance et la r\u00e9volution de l&rsquo;int\u00e9rieur de l&#8217;empire sont en train de d\u00e9faire le syst\u00e8me.&#160;\u00bb<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"jiang-shigong-la-logique-interne-des-entites-politiques-surdimensionnees-empire-et-ordre-mondial\">Jiang Shigong, \u00ab&#160;La logique interne des entit\u00e9s politiques surdimensionn\u00e9es&#160;: Empire et ordre mondial&#160;\u00bb<\/h2>\n\n\n\n<p class=\"intro\">\u5f3a\u4e16\u529f, \u201c\u8d85\u5927\u578b\u653f\u6cbb\u5b9e\u4f53\u7684\u5185\u5728\u903b\u8f91\uff1a\u2019\u5e1d\u56fd\u2019\u4e0e\u4e16\u754c\u79e9\u5e8f,\u201d publi\u00e9 \u00e0 l&rsquo;origine dans \u6587\u5316\u7eb5\u6a2a, 2019.4, et disponible en ligne ici&#160;: <a href=\"http:\/\/www.aisixiang.com\/data\/115799.html\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.aisixiang.com\/data\/115799.html<\/a>.<\/p>\n\n\n\n<p>Une question importante aujourd\u2019hui dans le domaine de la pens\u00e9e politique est l&rsquo;\u00e9norme \u00e9cart dans le discours dominant entre l'\u00a0\u00bbexpression&#160;\u00bb th\u00e9orique d&rsquo;une nation souveraine et la pratique politique universelle des empires. Cet \u00e9cart entre la th\u00e9orie et la pratique nous am\u00e8ne \u00e0 r\u00e9fl\u00e9chir au syst\u00e8me conceptuel de l'\u00a0\u00bb\u00c9tat-nation&#160;\u00bb, puis \u00e0 utiliser le concept d'\u00a0\u00bbempire&#160;\u00bb pour parvenir \u00e0 une nouvelle compr\u00e9hension de l&rsquo;histoire et de la vie politique contemporaine.<\/p>\n\n\n\n<p>Contrairement au concept d'\u00a0\u00bbempire&#160;\u00bb utilis\u00e9 dans le discours id\u00e9ologique traditionnel, je l\u2019utilise, dans cet essai, comme un concept sociologique descriptif pour caract\u00e9riser de tr\u00e8s grands syst\u00e8mes politiques qui ont exist\u00e9 universellement \u00e0 travers l&rsquo;histoire. Ces syst\u00e8mes poss\u00e8dent une stabilit\u00e9 interne complexe et d\u00e9pendant d\u2019une pluralit\u00e9 d\u2019acteurs, ainsi que d\u2019une volont\u00e9 philosophique, intellectuelle et politique d&rsquo;\u00e9tablir une sorte d&rsquo;universalisme, ou en d&rsquo;autres termes, d\u2019une envie d&rsquo;universaliser leur propre forme et d&rsquo;occuper un espace encore plus grand. En ce sens, l'\u00a0\u00bbempire&#160;\u00bb est une forme d\u2019organisation historique par laquelle l&rsquo;humanit\u00e9 a cherch\u00e9 \u00e0 g\u00e9rer l&rsquo;universalisme et la particularit\u00e9, ainsi qu&rsquo;une force motrice du d\u00e9veloppement et du changement.<\/p>\n\n\n\n<p>En effet, la construction d&rsquo;un empire et la concurrence entre les empires sont ce qui a pouss\u00e9 l&rsquo;humanit\u00e9 \u00e0 s&rsquo;\u00e9loigner des civilisations locales et dispers\u00e9es pour se diriger vers la civilisation mondiale d&rsquo;aujourd&rsquo;hui, dans un contexte de mondialisation. L&rsquo;histoire du monde est \u00e0 la fois une histoire d&#8217;empires en comp\u00e9tition pour l&rsquo;h\u00e9g\u00e9monie et une histoire de l&rsquo;\u00e9volution des formes d&#8217;empire. \u00c0 l&rsquo;heure actuelle, le monde se trouve \u00e0 un moment historique crucial dans le d\u00e9veloppement et l&rsquo;\u00e9volution de \u00ab&#160;l&#8217;empire mondial&#160;\u00bb. Ce n&rsquo;est qu&rsquo;en partant de la perspective de l&#8217;empire, et en comprenant les diff\u00e9rentes formes que prennent les empires au fil de l&rsquo;histoire, que nous pourrons transcender l&rsquo;id\u00e9ologie de l&rsquo;\u00c9tat-nation souverain et comprendre le r\u00f4le que joue la Chine d&rsquo;aujourd&rsquo;hui dans l&rsquo;\u00e9volution historique de l&#8217;empire mondial, et ainsi tracer une voie pour l&rsquo;avenir de la Chine.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"le-paradoxe-du-discours-souverain-et-de-la-pratique-imperiale\">Le paradoxe du discours \u00ab&#160;souverain&#160;\u00bb et de la \u00ab&#160;pratique&#160;\u00bb imp\u00e9riale<\/h2>\n\n\n\n<p>L&rsquo;id\u00e9e de souverainet\u00e9 est au c\u0153ur de la th\u00e9orie politique contemporaine. Dans la vaste g\u00e9n\u00e9alogie de la pens\u00e9e politique occidentale, tous les mouvements intellectuels de l&rsquo;histoire de la pens\u00e9e moderne, de la Renaissance \u00e0 la R\u00e9forme, de la r\u00e9volution scientifique aux Lumi\u00e8res, ont fait progresser l\u2019\u00e9dification et l\u2019approfondissement de la th\u00e9orie moderne de la souverainet\u00e9, et les concepts issus des sciences sociales qui ont particip\u00e9 \u00e0 la construction de la th\u00e9orie de l&rsquo;\u00c9tat-nation souverain constituent, aujourd&rsquo;hui encore, nos cat\u00e9gories acad\u00e9miques et \u00e9pist\u00e9mologiques de base.<\/p>\n\n\n\n<p>Depuis la fin de l&rsquo;\u00e9poque Qing, le monde intellectuel chinois a \u00e9galement connu une transformation intellectuelle profonde, par laquelle il a commenc\u00e9 \u00e0 construire et \u00e0 imaginer l&rsquo;ordre politique mondial sur la base de la pens\u00e9e politique occidentale moderne et contemporaine. La vision id\u00e9ale de cet ordre mondial est ce que nous appelons le \u00ab&#160;syst\u00e8me westphalien&#160;\u00bb, dans lequel toutes les \u00ab&#160;nations civilis\u00e9es&#160;\u00bb participent \u00e0 la construction de l&rsquo;ordre mondial sur un pied d&rsquo;\u00e9galit\u00e9 en tant qu&rsquo;\u00c9tats souverains. La Soci\u00e9t\u00e9 des Nations, issue de la Premi\u00e8re Guerre mondiale, et les Nations unies, issues de la Deuxi\u00e8me Guerre mondiale, ont souvent \u00e9t\u00e9 consid\u00e9r\u00e9es comme les mod\u00e8les de cet ordre mondial. Dans ce cadre, chaque fois que nous r\u00e9fl\u00e9chissons sur l&rsquo;ordre politique, nous commen\u00e7ons in\u00e9vitablement par des id\u00e9es telles que les \u00c9tats-nations souverains et la soci\u00e9t\u00e9 internationale, les \u00ab&#160;pr\u00e9occupations int\u00e9rieures&#160;\u00bb et les \u00ab&#160;pays \u00e9trangers&#160;\u00bb, qui cr\u00e9ent le nationalisme et l&rsquo;internationalisme comme id\u00e9ologies politiques fondamentales.<\/p>\n\n\n\n<p class=\"comment\">Il n&rsquo;y a pas si longtemps, la Nouvelle Gauche chinoise, dont la plupart, comme Jiang, sont des \u00e9tatistes convaincus, faisait de la souverainet\u00e9 l&rsquo;un de ses principes directeurs (pour un exemple parmi d&rsquo;autres, voir Wang Hui, \u00ab&#160;The Economy of a Rising China and its Contradictions&#160;\u00bb). Bien entendu, Jiang ne d\u00e9nonce pas la souverainet\u00e9, m\u00eame s&rsquo;il sugg\u00e8re, avec un clin d&rsquo;\u0153il, que le discours de l&rsquo;\u00c9tat-nation est un tour de passe-passe. Mais il n&rsquo;aborde pas non plus l&rsquo;apparente contradiction entre l&#8217;empire et la souverainet\u00e9 nationale, et il est difficile de savoir o\u00f9 se situe son argument dans le r\u00e9seau contemporain de la propagande politique et du r\u00eave chinois. Comme le dit ici l&rsquo;auteur anonyme du blog \u00ab&#160;The Credible Target&#160;\u00bb&#160;: \u00ab&#160;La prose de Jiang est un peu acad\u00e9mique, et impr\u00e9cise&#160;; elle n\u00e9cessite un peu de colmatage entre les lignes. C&rsquo;est en partie parce que l\u2019affirmation &lsquo;Rempla\u00e7ons l&#8217;empire am\u00e9ricain par un empire chinois qui ressemble \u00e0 ceci&rsquo; pourrait attirer une attention inutile.&#160;\u00bb Peut-\u00eatre pourrions-nous lire la th\u00e9orie de Jiang sur l&#8217;empire comme un ballon d&rsquo;essai&#160;?<\/p>\n\n\n\n<p>Pourtant, si nous regardons les choses en face, cet ordre international qui existe dans l&rsquo;abstrait, sur le papier, est-il v\u00e9ritablement l\u2019ordre international que nous trouvons \u00e0 notre \u00e9poque&#160;? L&rsquo;ordre international est-il vraiment construit par des \u00c9tats-nations souverains \u00e9gaux&#160;? Si nous revenons au v\u00e9ritable domaine de la pratique politique internationale, combien des quelques 200 pays reconnus comme des \u00c9tats-nations souverains aujourd&rsquo;hui poss\u00e8dent v\u00e9ritablement une souverainet\u00e9 compl\u00e8te&#160;? La souverainet\u00e9 de combien d&rsquo;\u00c9tats s&rsquo;est transform\u00e9e en une puissante influence \u00ab&#160;imp\u00e9riale&#160;\u00bb&#160;? Et combien d&rsquo;\u00c9tats ne sont que des \u00ab&#160;d\u00e9pendances&#160;\u00bb, des \u00ab&#160;zones frontali\u00e8res imp\u00e9riales&#160;\u00bb ou des \u00ab&#160;provinces&#160;\u00bb de ces empires&#160;?<\/p>\n\n\n\n<p>En termes de normes juridiques, et dans l\u2019esprit de nombreuses personnes, l&rsquo;ordre mondial est soutenu par les lois internationales, qui sont \u00e0 leur tour d\u00e9termin\u00e9es par les \u00c9tats-nations souverains. Mais dans la pratique politique, l&rsquo;ordre mondial a toujours fonctionn\u00e9 selon la logique imp\u00e9riale. Certains pays, comme l&rsquo;Allemagne et le Japon de l&rsquo;apr\u00e8s-guerre, n&rsquo;ont pas \u00e9t\u00e9 construits comme des \u00c9tats-nations pleinement souverains, m\u00eame au sens juridique du terme, parce que leurs constitutions n&rsquo;\u00e9taient pas fond\u00e9es sur des principes de souverainet\u00e9, mais plut\u00f4t sur des principes de paix internationale et de droit international.&nbsp; L&rsquo;origine de cette cat\u00e9gorie d&rsquo; \u00ab&#160;\u00c9tat-nation \u00e0 demi souverain&#160;\u00bb r\u00e9side dans le statut de perdants de l&rsquo;Allemagne et du Japon dans la comp\u00e9tition h\u00e9g\u00e9monique des empires. Il existe en outre d&rsquo;autres pays qui, tout en poss\u00e9dant une souverainet\u00e9 compl\u00e8te et ind\u00e9pendante au sens juridique, ont vu, dans la pratique, leur souverainet\u00e9 absorb\u00e9e par un syst\u00e8me imp\u00e9rial plus vaste. Certains de ces syst\u00e8mes imp\u00e9riaux supra-souverains ont \u00e9t\u00e9 construits sur la base du droit international, comme le Commonwealth, l&rsquo;Alliance du Nord ou l&rsquo;Union europ\u00e9enne.<\/p>\n\n\n\n<p>Et certains pays, tout en \u00e9tant pleinement souverains, peuvent \u00e9galement passer outre le droit international avec leur droit national, ou \u00e9tendre leur droit national \u00e0 d&rsquo;autres pays souverains, comme c&rsquo;est le cas des \u00c9tats-Unis lorsqu&rsquo;ils combattent la corruption \u00e0 l&rsquo;\u00e9tranger avec leur \u00ab&#160;juridiction \u00e0 long bras&#160;\u00bb et leurs sanctions \u00e9conomiques, sans parler des \u00ab&#160;r\u00e9volutions de couleur&#160;\u00bb qu&rsquo;ils ont ouvertement sanctionn\u00e9es et organis\u00e9es. En fait, les discussions sur des concepts tels que \u00ab&#160;l&rsquo;h\u00e9g\u00e9monie&#160;\u00bb, le \u00ab&#160;Tiers-Monde&#160;\u00bb, les \u00ab&#160;relations Nord-Sud&#160;\u00bb, la \u00ab&#160;multipolarit\u00e9&#160;\u00bb et le \u00ab&#160;nouvel ordre politique et \u00e9conomique international&#160;\u00bb dans le domaine des relations internationales rel\u00e8vent toutes de questions d&#8217;empire.<\/p>\n\n\n\n<p>De ce point de vue, l&rsquo;histoire de l&rsquo;humanit\u00e9 est certainement l&rsquo;histoire de la comp\u00e9tition pour l&rsquo;h\u00e9g\u00e9monie imp\u00e9riale, l&rsquo;histoire d&rsquo;une comp\u00e9tition acharn\u00e9e entre les empires qui a progressivement propuls\u00e9 la forme des empires de leur nature locale originelle vers la tendance actuelle aux empires mondiaux, et finalement vers un seul empire mondial. La mondialisation d&rsquo;aujourd&rsquo;hui est \u00e0 la fois le produit de la concurrence imp\u00e9riale et une forme particuli\u00e8re d&#8217;empire.<\/p>\n\n\n\n<p>Lorsque nous examinons l&rsquo;histoire de l&rsquo;humanit\u00e9, l&#8217;empire a toujours \u00e9t\u00e9 le principal acteur en termes politiques, tandis que l&rsquo;\u00c9tat-nation souverain est une chose nouvelle, un produit de la modernit\u00e9. De plus, les activit\u00e9s politiques des \u00c9tats-nations souverains sont souvent garanties par l&rsquo;ordre imp\u00e9rial, et nous pourrions dire que l&rsquo;ordre des \u00c9tats-nations souverains est une expression particuli\u00e8re de l&rsquo;ordre imp\u00e9rial. Si nous mettons de c\u00f4t\u00e9 les notions de concurrence imp\u00e9riale et de construction du nouvel ordre imp\u00e9rial, nous ne pouvons m\u00eame pas comprendre le concept d&rsquo;\u00c9tat-nation souverain. C&rsquo;est pourquoi nous devons r\u00e9examiner l&rsquo;histoire du point de vue de l&#8217;empire, et repenser la construction des \u00c9tats-nations souverains du point de vue de la construction de l&rsquo;ordre imp\u00e9rial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"l-age-axial-dans-la-civilisation-humaine-la-formation-d-empires-civilisationnels-regionaux\">L&rsquo;\u00e2ge axial dans la civilisation humaine&#160;: La formation d&#8217;empires civilisationnels r\u00e9gionaux<\/h2>\n\n\n\n<p>L&#8217;empire est avant tout un concept intellectuel universel qui s&rsquo;\u00e9tend au monde entier, et ensuite une forme de pratique politique qui cherche \u00e0 imposer une certaine harmonie dans le monde. Il y a toujours eu une grande tension interne entre l&rsquo;id\u00e9e et la pratique&#160;: les concepts imp\u00e9riaux sont universels, mais la pratique imp\u00e9riale est souvent confin\u00e9e \u00e0 un temps et un espace particuliers. Cette tension explique la mont\u00e9e en puissance puis la chute des empires, le remplacement d\u2019un empire par un autre.<\/p>\n\n\n\n<p>Les origines de la civilisation humaine sont dispers\u00e9es autour du globe, dans des r\u00e9gions qui r\u00e9pondaient le mieux aux besoins des premiers hommes. Les r\u00e9gions montagneuses ne convenaient pas \u00e0 la survie de l&rsquo;homme, et la vie sous les tropiques \u00e9tait trop facile, ce qui sapait la force du d\u00e9veloppement de la civilisation. Ce sont donc les r\u00e9gions temp\u00e9r\u00e9es qui ont appris aux gens \u00e0 maintenir la vie par un travail continu et l&rsquo;innovation. Pour cette raison, la civilisation humaine s&rsquo;est r\u00e9pandue dans les vastes r\u00e9gions temp\u00e9r\u00e9es de la plan\u00e8te.<\/p>\n\n\n\n<p>Ces diff\u00e9rentes civilisations ont continu\u00e9 \u00e0 progresser et ont fini par d\u00e9passer leurs fronti\u00e8res g\u00e9ographiques originelles, ce qui a donn\u00e9 lieu \u00e0 des \u00e9changes, \u00e0 de la concurrence et m\u00eame \u00e0 des luttes entre les civilisations pour leur survie. L&rsquo;histoire du d\u00e9veloppement de la civilisation humaine a continuellement suivi ce processus d&rsquo;\u00e9volution de petites communaut\u00e9s locales vers des groupes toujours plus grands.&nbsp; Dans ce processus, les diff\u00e9rentes civilisations ont constamment appris les unes des autres et se sont m\u00e9lang\u00e9es, mais il s&rsquo;agissait en m\u00eame temps d&rsquo;un processus de conflit et de conqu\u00eate, de d\u00e9fi et de r\u00e9ponse, et d&rsquo;annexion.<\/p>\n\n\n\n<p>Si nous prenons les \u00ab&#160;pays homog\u00e8nes&#160;\u00bb et les \u00ab&#160;pays pluriels&#160;\u00bb comme deux types id\u00e9aux d&rsquo;ordre politique dans l&rsquo;\u00e9volution de l&rsquo;histoire de la civilisation, alors l&rsquo;histoire de l&rsquo;humanit\u00e9 est le processus d\u2019interaction constante et dialectique entre l'\u00a0\u00bb\u00c9tat&#160;\u00bb et l'\u00a0\u00bbempire&#160;\u00bb, ce qui signifie que nous trouvons aussi bien la formation d&#8217;empires pluriels par la conqu\u00eate militaire d&rsquo;une nation homog\u00e8ne par une autre, que des formations imp\u00e9riales devenues des \u00c9tats-nations homog\u00e8nes par un long processus d&rsquo;assimilation et d&rsquo;int\u00e9gration d&rsquo;un ordre imp\u00e9rial pluriel, apr\u00e8s quoi cet \u00c9tat homog\u00e8ne s&rsquo;engagera sur la voie de la construction d&rsquo;un nouvel empire.<\/p>\n\n\n\n<p>Pour cette raison, les distinctions entre \u00c9tat-nation et empire dans la pratique politique r\u00e9elle ont toujours \u00e9t\u00e9 relatives, dynamiques et continues. En ce sens, l&#8217;empire n&rsquo;est pas seulement un nom utilis\u00e9 pour d\u00e9crire un ordre pluriel dans la pratique, mais il a aussi toujours fonctionn\u00e9 comme un verbe d\u00e9crivant un processus dynamique d'\u00a0\u00bbunification&#160;\u00bb.<\/p>\n\n\n\n<p>Du point de vue de l'\u00a0\u00bbempire&#160;\u00bb, la premi\u00e8re \u00e9tape de l&rsquo;histoire de la civilisation humaine a \u00e9t\u00e9 le processus par lequel les civilisations de toute la plan\u00e8te ont \u00e9volu\u00e9 par l&rsquo;interaction dialectique des deux formes politiques que sont l&rsquo;\u00c9tat et l&#8217;empire, pour finalement s&rsquo;unir pour former des empires locaux aux fronti\u00e8res g\u00e9ographiques stables. La conscience imp\u00e9riale universaliste a m\u00fbri pr\u00e9cis\u00e9ment dans ces empires g\u00e9ographiquement \u00e9tendus, assez complets et stables. Ce que nous appelons \u00ab&#160;l&rsquo;\u00e2ge axial&#160;\u00bb de l&rsquo;histoire humaine a \u00e9t\u00e9 caract\u00e9ris\u00e9 par une telle conscience imp\u00e9riale&#160;: l&#8217;empire n&rsquo;\u00e9tait plus une simple question de conqu\u00eate \u00e9conomique ou de construction politique, mais devenait un ordre civilisationnel universel. Nous pouvons appeler cette forme d&#8217;empire, avec son espace g\u00e9ographique relativement stable et son homog\u00e9n\u00e9it\u00e9 civilisationnelle relativement continue, &#160;\u00bb l&#8217;empire civilisationnel r\u00e9gional. \u00ab&#160;<\/p>\n\n\n\n<p>Pour prendre l&rsquo;exemple de la Chine, au d\u00e9but de la civilisation, des communaut\u00e9s sont apparues et se sont d\u00e9velopp\u00e9es jusqu&rsquo;\u00e0 devenir comme des \u00ab&#160;\u00e9toiles dans le ciel&#160;\u00bb, et apr\u00e8s \u00eatres pass\u00e9es par des interactions et des int\u00e9grations sans fin, elles se sont finalement r\u00e9unies pour former des tribus ou des f\u00e9d\u00e9rations tribales distinctes, que nous pourrions appeler des empires locaux. Gr\u00e2ce \u00e0 une comp\u00e9tition constante, ces empires locaux instables sont finalement devenus l&#8217;empire r\u00e9gional des Xia, Shang et Zhou, les neuf \u00e9tats install\u00e9s de fa\u00e7on stable dans les plaines centrales. Cet empire Xia-Shang-Zhou n&rsquo;est devenu un syst\u00e8me politique, rituel et civilisationnel stable qu&rsquo;apr\u00e8s que la pens\u00e9e confuc\u00e9enne lui ait donn\u00e9 une expression philosophique universelle. Les constructions imp\u00e9riales ult\u00e9rieures des p\u00e9riodes Qin-Han, Sui-Tang et Ming-Qing ont \u00e9t\u00e9 des renouvellements civilisationnels de ce mod\u00e8le fondamental.<\/p>\n\n\n\n<p class=\"comment\">Il s&rsquo;agit d&rsquo;une r\u00e9f\u00e9rence au livre de l&rsquo;arch\u00e9ologue chinois Su Bingqi \u82cf\u79c9\u7426, Stars Filling the Sky&#160;: Su Bingqi on Primitive China \u6ee1\u5929\u661f\u6597&#160;: \u82cf\u79c9\u7426\u8bba\u8fdc\u53e4\u4e2d\u56fd, qui a \u00e9t\u00e9 cit\u00e9 par Zhao Tingyang \u8d75\u6c40\u9633 dans ses arguments concernant l&rsquo;ordre mondial chinois. Voir&#160;: <a href=\"http:\/\/www.xinhuanet.com\/local\/2017-01\/02\/c_129428651.htm.\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.xinhuanet.com\/local\/2017-01\/02\/c_129428651.htm<\/a>.<\/p>\n\n\n\n<p>Halford Mackinder (1861-1947), sp\u00e9cialiste de g\u00e9opolitique, \u00e9tait parfaitement conscient des fondements g\u00e9ographiques et civilisationnels des empires r\u00e9gionaux. D&rsquo;un point de vue macrospatial, il a divis\u00e9 l&rsquo;ensemble du continent eurasien en un noyau central, [historiquement repr\u00e9sent\u00e9 par l&#8217;empire russe] caract\u00e9ris\u00e9 par des prairies et des p\u00e2turages, et des zones p\u00e9riph\u00e9riques, caract\u00e9ris\u00e9es par des rivi\u00e8res, des plaines et l&rsquo;agriculture.<\/p>\n\n\n\n<p class=\"comment\">Halford Mackinder \u00e9tait un g\u00e9ographe britannique qui introduisit sa \u00ab&#160;th\u00e9orie du Heartland&#160;\u00bb dans un article intitul\u00e9 \u00ab&#160;The Geographical Pivot of History&#160;\u00bb, pr\u00e9sent\u00e9 \u00e0 la Royal Geographical Association en 1904. Sa th\u00e9orie divise le monde en trois r\u00e9gions&#160;: l&rsquo;\u00eele-monde, les \u00eeles p\u00e9riph\u00e9riques et les \u00eeles offshore. L&rsquo;\u00eele-monde comprend l&rsquo;Europe, l&rsquo;Asie et l&rsquo;Afrique, et domine donc en termes de population et de ressources. Les \u00eeles au large des c\u00f4tes comprennent le Japon et la Grande-Bretagne. Les \u00eeles p\u00e9riph\u00e9riques comprenaient les Am\u00e9riques et l&rsquo;Australie. Mackinder a soulign\u00e9 l&rsquo;importance de l&rsquo;Europe de l&rsquo;Est, une r\u00e9gion qui offrait une passerelle vers le contr\u00f4le du c\u0153ur du Heartland, en partie pour avertir la Grande-Bretagne que sa d\u00e9pendance historique \u00e0 la puissance maritime pouvait avoir des limites. Voir <a href=\"https:\/\/www.worldatlas.com\/articles\/what-is-the-heartland-theory.html\">https:\/\/www.worldatlas.com\/articles\/what-is-the-heartland-theory.html<\/a>. Jiang Shigong semble ici adapter les th\u00e9ories de Mackinder aux besoins de sa d\u00e9monstration.<\/p>\n\n\n\n<p>Dans les r\u00e9gions centrales, le mode de vie nomade et arri\u00e9r\u00e9 \u00e9tait la principale forme de civilisation, tandis que les r\u00e9gions p\u00e9riph\u00e9riques \u00e9taient divis\u00e9es en quatre zones civilisationnelles relativement avanc\u00e9es, o\u00f9 l&rsquo;agriculture et le commerce pr\u00e9dominaient&#160;: les r\u00e9gions de la civilisation confuc\u00e9enne chinoise, de la civilisation hindoue d&rsquo;Asie du Sud, de la civilisation arabo-islamique et de la civilisation chr\u00e9tienne europ\u00e9enne. Nous pouvons consid\u00e9rer ces cinq civilisations r\u00e9gionales eurasiennes comme cinq empires r\u00e9gionaux relativement stables. Ces empires ont fond\u00e9 leur coh\u00e9rence sur les \u00e9l\u00e9ments naturels de leur environnement g\u00e9ographique ainsi que sur certains \u00e9l\u00e9ments spirituels de nature philosophique ou th\u00e9ocratique. Sur une tr\u00e8s longue p\u00e9riode de l&rsquo;histoire, alors que des incarnations sp\u00e9cifiques d&#8217;empires locaux se sont \u00e9lev\u00e9es et ont chut\u00e9, ces cinq empires civilisationnels r\u00e9gionaux ont atteint une stabilit\u00e9 relative dans leur r\u00e9gion. Aujourd&rsquo;hui encore, des milliers d&rsquo;ann\u00e9es apr\u00e8s leur fondation, ces cinq empires civilisationnels r\u00e9gionaux continuent de maintenir une stabilit\u00e9 relative en termes d&rsquo;espace g\u00e9ographique et de caract\u00e9ristiques, ce qui t\u00e9moigne de la t\u00e9nacit\u00e9 dont font preuve les empires civilisationnels r\u00e9gionaux.<\/p>\n\n\n\n<p class=\"comment\">Pour ceux qui sont int\u00e9ress\u00e9s par d&rsquo;autres commentaires ou par le contexte de Jiang et\/ou des id\u00e9es chinoises sur l&#8217;empire, voir \u00ab&#160;Credible Target&#160;\u00bb qui propose une analyse ainsi qu&rsquo;une traduction partielle&#160;; ainsi qu&rsquo;un article \u00e0 para\u00eetre de Leigh Jenco et Jonathan Chappell dans The Journal of Asian Studies, \u00ab&#160;Imperialism in Chinese Eyes&#160;: Nations, Empires, and State-Building&#160;\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"la-montee-des-empires-coloniaux-mondiaux-la-concurrence-mondiale-entre-les-empires-continentaux-et-les-empires-maritimes\">La mont\u00e9e des empires coloniaux mondiaux&#160;: La concurrence mondiale entre les empires continentaux et les empires maritimes<\/h2>\n\n\n\n<p>Dans la premi\u00e8re phase de l&rsquo;histoire des empires, les cinq empires civilisationnels r\u00e9gionaux \u00e9taient tous situ\u00e9s sur la masse continentale eurasienne, et tous \u00e9taient des empires continentaux. Du point de vue de la localisation respective des cinq empires, les quatre empires p\u00e9riph\u00e9riques poss\u00e9daient, par rapport \u00e0 l\u2019empire des steppes, d\u2019importants avantages civilisationnels, tandis que ce dernier, situ\u00e9 dans les r\u00e9gions montagneuses, \u00e9tait moins avanc\u00e9 car plus associ\u00e9 au nomadisme. Mais cet empire poss\u00e9dait \u00e9galement certains avantages strat\u00e9giques sur le plan g\u00e9ographique, et constituait toujours une menace pour les quatre grands empires civilisationnels p\u00e9riph\u00e9riques. C&rsquo;\u00e9tait particuli\u00e8rement le cas pour la civilisation chr\u00e9tienne occidentale, qui \u00e9tait continuellement mise sous pression par la civilisation islamique orientale et par la civilisation des steppes.<\/p>\n\n\n\n<p>La raison pour laquelle l&#8217;empire islamique pouvait constituer une menace pour l&#8217;empire chr\u00e9tien n&rsquo;\u00e9tait pas seulement due \u00e0 sa sup\u00e9riorit\u00e9 en termes religieux et militaires, mais aussi, et surtout, au fait qu&rsquo;il monopolisait le commerce maritime avec la civilisation hindoue et la civilisation chinoise \u00e0 l&rsquo;est, ce qui lui assurait de grandes quantit\u00e9s de ressources et de richesses. C&rsquo;est dans ce contexte de concurrence que l&rsquo;Empire chr\u00e9tien a finalement \u00e9t\u00e9 contraint de s&#8217;embarquer sur l&rsquo;oc\u00e9an Atlantique, pour tenter de localiser une route maritime qui lui ouvrirait les \u00e9changes et le commerce avec l&rsquo;Empire chinois \u00e0 l&rsquo;est. Christophe Colomb cherchait une Route de la Soie maritime pour remplacer la voie terrestre, qui avait \u00e9t\u00e9 d\u00e9truite par l&rsquo;Empire des steppes, ce qui remettrait en cause le monopole de la civilisation islamique sur le commerce avec l&rsquo;Orient.<\/p>\n\n\n\n<p>Lorsque l&rsquo;Empire chr\u00e9tien est contraint de prendre le large, c&rsquo;est la premi\u00e8re page de l&rsquo;histoire des empires du monde qui se tourne. D&rsquo;une part, l&#8217;empire chr\u00e9tien a \u00ab&#160;d\u00e9couvert&#160;\u00bb&nbsp; et conquis l&rsquo;Am\u00e9rique, ainsi que des territoires et des civilisations jusqu&rsquo;alors inconnus, comme l&rsquo;Afrique australe et m\u00eame l&rsquo;Oc\u00e9anie, s&#8217;emparant au passage de ressources jusqu&rsquo;alors inconnues. D&rsquo;autre part, ces grandes d\u00e9couvertes g\u00e9ographiques ont conduit \u00e0 l&rsquo;\u00e9mergence d'\u00a0\u00bbempires coloniaux mondiaux&#160;\u00bb comme nouvelle forme d&#8217;empire, ce qui signifie que l&#8217;empire chr\u00e9tien autrefois uni a commenc\u00e9 \u00e0 se diviser en nouveaux empires coloniaux fond\u00e9s sur des \u00c9tats-nations souverains nouvellement form\u00e9s.<\/p>\n\n\n\n<p>La concurrence entre ces empires coloniaux a conduit la civilisation chr\u00e9tienne \u00e0 \u00eatre la premi\u00e8re \u00e0 effectuer la transition vers la civilisation moderne, ce qui a conf\u00e9r\u00e9 aux empires coloniaux occidentaux une sup\u00e9riorit\u00e9 \u00e9crasante sur les empires civilisationnels traditionnels de l&rsquo;Est. Par la suite, l&rsquo;histoire du monde est entr\u00e9e dans la phase de domination imp\u00e9riale occidentale. Les grandes d\u00e9couvertes g\u00e9ographiques ont conduit la civilisation chr\u00e9tienne occidentale \u00e0 s&rsquo;inspirer des civilisations orientales et \u00e0 absorber non seulement les pratiques avanc\u00e9es de l&rsquo;astronomie, des math\u00e9matiques, de la g\u00e9ographie, de la navigation et de la construction navale orientales, mais aussi \u00e0 \u00eatre influenc\u00e9e par l&rsquo;humanisme et le rationalisme de la civilisation chinoise. Pourtant, la d\u00e9couverte de peuples et de civilisations diff\u00e9rents durant le processus de mondialisation a affaibli la vision singuli\u00e8re du monde que l&rsquo;on trouve dans la Bible chr\u00e9tienne. Cela a conduit \u00e0 la mont\u00e9e de la rationalit\u00e9, de l&rsquo;humanisme et de la science en Occident, et donc \u00e0 la d\u00e9sint\u00e9gration de l&#8217;empire chr\u00e9tien traditionnel.<\/p>\n\n\n\n<p>L&rsquo;\u00e8re des d\u00e9couvertes a entra\u00een\u00e9 une concurrence interne au sein de l&#8217;empire chr\u00e9tien, chaque royaume ou nation luttant contre l&rsquo;autre. Cette concurrence interne a \u00e9galement stimul\u00e9 le processus global de rationalisation de la civilisation occidentale, chaque royaume cherchant \u00e0 mettre l&#8217;empire chr\u00e9tien derri\u00e8re lui et \u00e0 entreprendre la transition vers un \u00c9tat-nation souverain moderne. Ce processus a abouti \u00e0 la cr\u00e9ation d&rsquo;un nouveau mod\u00e8le politique, compris en termes de th\u00e9orie politique occidentale moderne comme un mod\u00e8le fond\u00e9 sur le citoyen individuel et ses droits, avec un contrat social liant les droits des citoyens \u00e0 la construction d&rsquo;un \u00c9tat-nation souverain homog\u00e8ne. Le m\u00eame processus a abouti \u00e0 l&rsquo;ordre westphalien qui r\u00e9git les relations entre les diff\u00e9rents \u00c9tats-nations souverains.<\/p>\n\n\n\n<p>De l\u00e0 est n\u00e9e la comparaison, dans la th\u00e9orie politique, entre les \u00c9tats-nations souverains et les empires en tant que formes politiques, selon laquelle les anciens empires r\u00e9gionaux (comme l&#8217;empire chinois, l&#8217;empire indien, l&#8217;empire ottoman, l&#8217;empire russe, etc.) ont \u00e9t\u00e9 consid\u00e9r\u00e9s comme repr\u00e9sentant une forme politique traditionnelle d\u00e9pass\u00e9e, tandis que seuls les \u00c9tats-nations souverains europ\u00e9ens repr\u00e9sentaient la forme politique moderne de l&rsquo;avenir.<\/p>\n\n\n\n<p>Mais, les nouveaux \u00c9tats-nations souverains europ\u00e9ens, en s\u2019engageant dans la colonisation outre-mer et en construisant leurs empires coloniaux, ont \u00e9galement construit un nouveau syst\u00e8me imp\u00e9rial. Contrairement aux empires traditionnels des civilisations r\u00e9gionales, qui administraient les territoires nouvellement conquis comme faisant partie de leur empire, les empires coloniaux ont cr\u00e9\u00e9 un nouveau mod\u00e8le imp\u00e9rial colonial dans lequel les \u00c9tats-nations souverains \u00e9taient distingu\u00e9s des colonies, et des distinctions de statut s&rsquo;appliquaient \u00e0 chacun. La colonie ne faisait partie de l&#8217;empire que dans la mesure o\u00f9 elle servait de fournisseuse de ressources naturelles et o\u00f9 elle \u00e9tait source de profits pour l&rsquo;\u00c9tat-nation souverain. L&rsquo;\u00c9tat-nation au c\u0153ur de l&#8217;empire pratiquait une politique r\u00e9publicaine, tandis que dans la p\u00e9riph\u00e9rie coloniale de l&#8217;empire, la politique \u00e9tait ouvertement autoritaire&#160;; ce sont les deux visages de l&#8217;empire colonial. Par cons\u00e9quent, la concurrence entre les empires europ\u00e9ens n&rsquo;\u00e9tait pas seulement une lutte pour le territoire europ\u00e9en, mais surtout une lutte pour obtenir ou redistribuer des colonies d&rsquo;outre-mer.<\/p>\n\n\n\n<p>Du trait\u00e9 de Westphalie au trait\u00e9 d&rsquo;Utrecht, le syst\u00e8me de droit international entre les \u00c9tats-nations souverains modernes est en fait le produit de la concurrence &#8211; et de la r\u00e9alisation d&rsquo;\u00e9quilibres temporaires &#8211; entre les empires coloniaux, qui reposaient tous, dans une large mesure, sur la concurrence pour l&rsquo;obtention et la redistribution des colonies.<\/p>\n\n\n\n<p>Si nous demandons \u00ab&#160;comment les empires europ\u00e9ens en sont venus \u00e0 dominer le monde&#160;\u00bb, une partie importante de la r\u00e9ponse se trouve dans le syst\u00e8me moderne d&rsquo;\u00c9tat-nation au c\u0153ur de ces civilisations imp\u00e9riales. C&rsquo;est pr\u00e9cis\u00e9ment la d\u00e9cision des diff\u00e9rents peuples europ\u00e9ens d&rsquo;abandonner la forme de l&#8217;empire traditionnel de la civilisation chr\u00e9tienne, ainsi que les contraintes que la religion et la morale avaient autrefois repr\u00e9sent\u00e9es, pour se concentrer sur la libert\u00e9 individuelle et sur la construction du syst\u00e8me moderne d&rsquo;\u00c9tat-nation, qui a cr\u00e9\u00e9 dans ces pays un nouveau style de vie ainsi que de grandes forces \u00e9conomiques, politiques et culturelles, qui \u00e0 leur tour ont continuellement fond\u00e9 des colonies dans le monde entier, cr\u00e9ant ainsi une nouvelle forme d&#8217;empire.<\/p>\n\n\n\n<p>On pourrait dire que les \u00c9tats-nations occidentaux ont construit de nouveaux empires en m\u00eame temps qu&rsquo;ils ont abandonn\u00e9 les anciens, et que ces nouveaux empires contenaient non seulement des colonies, mais aussi un syst\u00e8me de droit international. La forme imp\u00e9riale enti\u00e8rement nouvelle combinait donc le droit colonial, le droit national et le droit international, une forme composite \u00e0 deux visages, d\u2019un c\u00f4t\u00e9 les \u00c9tats-nations, de l\u2019autre les colonies. La condition pr\u00e9alable \u00e0 la construction du syst\u00e8me westphalien d&rsquo;\u00c9tats-nations souverains a toujours \u00e9t\u00e9 le syst\u00e8me colonial mondialis\u00e9. Seuls les \u00c9tats qui avaient obtenu le pouvoir par la lutte pour les empires coloniaux avaient le droit d&rsquo;entrer dans le syst\u00e8me des \u00c9tats-nations souverains. Ce n&rsquo;est que parce que les puissances europ\u00e9ennes pouvaient d\u00e9velopper \u00e0 volont\u00e9 des empires coloniaux dans les \u00ab&#160;nouveaux territoires&#160;\u00bb rendus disponibles par les d\u00e9couvertes que le fragile \u00e9quilibre des pouvoirs du syst\u00e8me westphalien pouvait \u00eatre maintenu. Pourtant, \u00e0 la fin du XIXe si\u00e8cle, avec la fin de la p\u00e9riode des grandes d\u00e9couvertes, la lutte entre les puissances coloniales europ\u00e9ennes pour l&rsquo;h\u00e9g\u00e9monie mondiale a conduit \u00e0 l&rsquo;\u00e9clatement de la Premi\u00e8re Guerre mondiale, qui a acc\u00e9l\u00e9r\u00e9 la fin du syst\u00e8me imp\u00e9rial colonial, ainsi que la d\u00e9sint\u00e9gration du syst\u00e8me westphalien eurocentr\u00e9.<\/p>\n\n\n\n<p>Si nous comparons l&#8217;empire civilisationnel r\u00e9gional traditionnel \u00e0 l&#8217;empire colonial mondial moderne, nous d\u00e9couvrons d&rsquo;\u00e9normes diff\u00e9rences en termes de forme.<\/p>\n\n\n\n<p>Tout d&rsquo;abord, si les empires r\u00e9gionaux de civilisation ont connu l\u2019\u00e9mergence puis la chute, des expansions et des contractions, ils ont plus ou moins maintenu une pr\u00e9sence r\u00e9gionale stable&#160;; en revanche, les tentacules des empires coloniaux nouvellement apparus ont largement d\u00e9pass\u00e9 l&rsquo;espace g\u00e9ographique de l&rsquo;Europe et se sont \u00e9tendus \u00e0 tous les continents du monde. Leur puissance ne trouvait rien qui puisse leur r\u00e9sister dans les Am\u00e9riques, en Afrique, en Oc\u00e9anie ou m\u00eame dans l&rsquo;Asie ancienne, donnant naissance \u00e0 un empire mondial en termes d&rsquo;espace g\u00e9ographique.<\/p>\n\n\n\n<p>Deuxi\u00e8mement, lorsque les empires civilisationnels r\u00e9gionaux en conqu\u00e9raient d&rsquo;autres, ils cherchaient souvent \u00e0 d\u00e9velopper la civilisation, en cr\u00e9ant l'\u00a0\u00bbunit\u00e9&#160;\u00bb et la \u00ab&#160;paix&#160;\u00bb dans la r\u00e9gion&#160;; en comparaison, les empires coloniaux mondiaux ont, d\u00e8s le d\u00e9part, fait du commerce et de l&rsquo;\u00e9change leur objectif principal, et par cons\u00e9quent, les r\u00e9gions qu&rsquo;ils ont conquises n&rsquo;\u00e9taient pas des territoires \u00e0 gouverner, mais plut\u00f4t des colonies destin\u00e9es \u00e0 fournir des mati\u00e8res premi\u00e8res, des esclaves et des march\u00e9s d&rsquo;exportation \u00e0 la m\u00e8re patrie. C&rsquo;est pourquoi les colonies et le syst\u00e8me d&rsquo;esclavage constituaient les deux caract\u00e9ristiques fondamentales des empires coloniaux. En fait, l&rsquo;une des raisons importantes pour lesquelles l&#8217;empire chr\u00e9tien pouvait facilement se transformer en empire colonial \u00e9tait que, d\u00e8s l&rsquo;\u00e9poque des empires grec et romain, les \u00e9changes et le commerce avaient donn\u00e9 naissance \u00e0 un syst\u00e8me d&rsquo;esclavage durable.<\/p>\n\n\n\n<p>Troisi\u00e8mement, les empires civilisationnels r\u00e9gionaux ont d\u00e9velopp\u00e9 des syst\u00e8mes de gouvernance qui \u00e9taient raisonnablement uniformes \u00e0 l&rsquo;int\u00e9rieur, et ont utilis\u00e9 des syst\u00e8mes de gouvernance diff\u00e9rents uniquement dans les zones locales \u00e0 la p\u00e9riph\u00e9rie&#160;; en revanche, les empires coloniaux mondiaux ont d\u00e8s le d\u00e9part consid\u00e9r\u00e9 les colonies comme de simples sources de profit \u00e9conomique, ce qui a conduit au syst\u00e8me imp\u00e9rialiste moderne dans lequel il y a une s\u00e9paration stricte entre l&rsquo;\u00c9tat-nation souverain central et les colonies p\u00e9riph\u00e9riques. En termes de r\u00e9gimes constitutionnels, les \u00c9tats-nations souverains europ\u00e9ens et les empires colonis\u00e9s existaient dans deux mondes juridiques compl\u00e8tement diff\u00e9rents.<\/p>\n\n\n\n<p>Quatri\u00e8mement, les caract\u00e9ristiques particuli\u00e8res des empires civilisationnels r\u00e9gionaux favorisaient l&rsquo;harmonie ethnique au sein de la r\u00e9gion et de la civilisation, de sorte que m\u00eame s&rsquo;il y avait des probl\u00e8mes ethniques dans ce type d&#8217;empires civilisationnels, l&rsquo;ethnicit\u00e9 ne devenait pas un obstacle \u00e0 la construction des empires&#160;; en revanche, si les empires coloniaux mondiaux ont men\u00e9 leur expansion au nom de la civilisation (contre la barbarie) &#8211; parce que les empires coloniaux ont, d\u00e8s le d\u00e9part, maintenu des divisions strictes entre l&rsquo;\u00c9tat-nation m\u00e9tropolitain et la colonie p\u00e9riph\u00e9rique, ainsi que des diff\u00e9rences correspondantes dans le statut de citoyennet\u00e9 &#8211; les normes civilisationnelles des empires coloniaux ont toujours contenu des \u00e9l\u00e9ments de racisme. Pour cette raison, les empires coloniaux non seulement n&rsquo;ont pas pu promouvoir l&rsquo;harmonie raciale, mais ont au contraire engendr\u00e9 une haine raciale et des massacres sans pr\u00e9c\u00e9dent. L&rsquo;h\u00e9ritage cr\u00e9\u00e9 par les empires coloniaux reste \u00e0 ce jour difficile \u00e0 \u00e9radiquer.<\/p>\n\n\n\n<p>L&rsquo;essor des empires coloniaux europ\u00e9ens a sans aucun doute \u00e9t\u00e9 la deuxi\u00e8me transformation de l&rsquo;histoire de l&#8217;empire dans l&rsquo;humanit\u00e9, et ce processus a \u00e9t\u00e9 d\u00e8s le d\u00e9part li\u00e9 aux d\u00e9couvertes maritimes, ce qui signifie que les premiers pays \u00e0 prendre la mer ont \u00e9galement \u00e9t\u00e9 les premiers \u00e0 \u00e9tablir des colonies d&rsquo;outre-mer et \u00e0 construire des empires coloniaux. Par cons\u00e9quent, l&rsquo;histoire de l\u2019\u00e9mergence et de la chute des empires coloniaux europ\u00e9ens a pris la forme de l&rsquo;histoire de la conqu\u00eate des mers, de la ma\u00eetrise de la navigation, de l&rsquo;\u00e9tablissement de colonies et de la concurrence pour les colonies. L&rsquo;Espagne et le Portugal ont ouvert la voie en d\u00e9veloppant les explorations maritimes et en \u00e9tablissant des empires coloniaux outre-mer, et ces pays se sont appuy\u00e9s sur l&rsquo;orthodoxie de l&#8217;empire europ\u00e9en pour \u00e9tablir la l\u00e9gitimit\u00e9 des empires coloniaux mondiaux construits dans ces territoires nouvellement d\u00e9couverts.<\/p>\n\n\n\n<p>Lorsque la vague suivante de puissances, repr\u00e9sent\u00e9e par la Hollande, l&rsquo;Angleterre et la France, a commenc\u00e9 \u00e0 se disputer les colonies, elle s&rsquo;est heurt\u00e9e \u00e0 la contestation de sa l\u00e9gitimit\u00e9 par l&#8217;empire europ\u00e9en. En fait, la R\u00e9forme promue par la Hollande, l&rsquo;Angleterre et la France \u00e9tait en r\u00e9alit\u00e9 dirig\u00e9e contre l&rsquo;Espagne, le Portugal et le contexte europ\u00e9en m\u00e9di\u00e9val qui les soutenait. Cette situation a donn\u00e9 lieu \u00e0 une scission de l&#8217;empire chr\u00e9tien entre le groupe catholique traditionnel et le nouveau groupe protestant, qui a fini par l&#8217;emporter.<\/p>\n\n\n\n<p>En raison des diff\u00e9rences entre les conditions continentales et maritimes, les pays europ\u00e9ens, dans le processus de comp\u00e9tition pour l&rsquo;h\u00e9g\u00e9monie dans leur construction d&#8217;empires coloniaux, ont progressivement d\u00e9velopp\u00e9 deux types de gouvernance \u00e9tatique et coloniale&#160;: l&#8217;empire maritime et l&#8217;empire continental. Les pays protestants comme la Hollande et l&rsquo;Angleterre ont d\u00e9velopp\u00e9 des empires maritimes fond\u00e9s sur le commerce mondial.&nbsp; Sur le plan int\u00e9rieur, ils pratiquaient le r\u00e9publicanisme et, en termes de gouvernance coloniale, ils faisaient tout leur possible pour pratiquer le libre-\u00e9change et le commerce dans des conditions de souverainet\u00e9. En revanche, les premiers colonisateurs, comme le Portugal et l&rsquo;Espagne, ainsi que les arrivants plus tardifs comme la France, l&rsquo;Allemagne et la Russie, ont surtout h\u00e9rit\u00e9 du style de gouvernement continental-imp\u00e9rial associ\u00e9 aux empires grec et romain et \u00e0 l&#8217;empire chr\u00e9tien. Chez eux, ils pratiquaient l&rsquo;autocratie, et en termes de gouvernance coloniale, ils pratiquaient une forme autocratique de pillage.<\/p>\n\n\n\n<p>Cela nous indique que les dichotomies id\u00e9ologiques de la pens\u00e9e europ\u00e9enne moderne entre r\u00e9publicanisme et autocratie, commerce et territoire, libert\u00e9 et despotisme, trouvent en fait leur origine dans les dichotomies des types de gouvernance employ\u00e9s par les empires maritimes et continentaux. Ces deux types de gouvernance diff\u00e9rents, n\u00e9s des diff\u00e9rents probl\u00e8mes rencontr\u00e9s par les empires continentaux et maritimes, ont profond\u00e9ment influenc\u00e9 la situation mondiale pendant la guerre froide et m\u00eame apr\u00e8s.<\/p>\n\n\n\n<p>L&rsquo;essor des empires coloniaux a acc\u00e9l\u00e9r\u00e9 la concurrence entre les empires, et l&rsquo;intensification des conflits imp\u00e9riaux a \u00e9galement acc\u00e9l\u00e9r\u00e9 l&rsquo;arriv\u00e9e des r\u00e9volutions modernes en mati\u00e8re de technologie et de pens\u00e9e, entra\u00eenant ainsi le passage de la tradition \u00e0 la modernit\u00e9.&nbsp; Dans une certaine mesure, cette comp\u00e9tition coloniale qui se jouait sur la sc\u00e8ne mondiale \u00e9tait une comp\u00e9tition entre les empires coloniaux europ\u00e9ens, mais en m\u00eame temps, avec la diffusion de la culture europ\u00e9enne moderne dans le monde entier, d&rsquo;autres empires traditionnels ont \u00e9t\u00e9 incit\u00e9s \u00e0 \u00e9tudier l&rsquo;Occident, et au fur et \u00e0 mesure de leurs propres r\u00e9formes, ils ont \u00e9galement particip\u00e9 \u00e0 la comp\u00e9tition.<\/p>\n\n\n\n<p>C&rsquo;est dans ce contexte que les empires allemand et tsariste ont commenc\u00e9 \u00e0 d\u00e9velopper leurs empires coloniaux et se sont trouv\u00e9s pris dans la lutte mondiale.&nbsp; De m\u00eame, le Japon, situ\u00e9 en marge de l&#8217;empire chinois, a \u00e9t\u00e9 le premier \u00e0 \u00ab&#160;quitter l&rsquo;Asie pour l&rsquo;Europe&#160;\u00bb et \u00e0 embrasser le monde maritime, se constituant en puissance coloniale et entrant dans la comp\u00e9tition mondiale.&nbsp; Les deux Guerres mondiales ont \u00e9t\u00e9 le th\u00e9\u00e2tre d&rsquo;une lutte sanglante entre tous les empires coloniaux mondiaux pour construire ce qu&rsquo;ils appelaient un \u00ab&#160;empire mondial h\u00e9g\u00e9monique unique&#160;\u00bb.<\/p>\n\n\n\n<p class=\"comment\">Jiang fait ici r\u00e9f\u00e9rence \u00e0 un \u00e9ditorial publi\u00e9 en 1885 dans le journal japonais Jiji shimpo, et probablement \u00e9crit par Fukuzawa Yukichi, qui sugg\u00e9rait que le Japon devait \u00ab&#160;quitter l&rsquo;Asie&#160;\u00bb \u8131\u4e9a et rejoindre le monde occidental.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"empire-mondial-1-0-de-l-angleterre-aux-etats-unis\">\u00ab&#160;Empire mondial&#160;\u00bb 1.0&#160;: De l&rsquo;Angleterre aux \u00c9tats-Unis<\/h2>\n\n\n\n<p>Au tournant du XX\u00e8me si\u00e8cle, suite \u00e0 une comp\u00e9tition toujours plus intense entre les empires, la forme de l&#8217;empire a encore chang\u00e9. Tout d&rsquo;abord, dans la comp\u00e9tition entre les nombreux empires mondiaux, est apparu un \u00ab&#160;empire mondial&#160;\u00bb, avec des colonies partout sur la plan\u00e8te, capable de diriger le commerce et les \u00e9changes mondiaux ainsi que de r\u00e9guler l&rsquo;\u00e9quilibre des forces entre les nombreux empires europ\u00e9ens. Il s&rsquo;agit de l&#8217;empire britannique de l&rsquo;\u00e8re westphalienne, sur lequel \u00ab&#160;le soleil ne s&rsquo;est jamais couch\u00e9&#160;\u00bb. En outre, le mod\u00e8le de gouvernance imp\u00e9riale au sein de cet empire mondial a constamment \u00e9volu\u00e9&#160;; ne se satisfaisant plus du simple pillage colonial, les empires mondiaux se sont plut\u00f4t attach\u00e9s \u00e0 contr\u00f4ler le pouls des \u00e9conomies coloniales en dominant la science, la technologie et la finance.<\/p>\n\n\n\n<p>Or, c&rsquo;est pr\u00e9cis\u00e9ment ce nouveau mod\u00e8le de gouvernance imp\u00e9riale qui a conduit les empires \u00e0 accorder \u00e0 leurs colonies des niveaux toujours plus \u00e9lev\u00e9s d&rsquo;autonomie et de souverainet\u00e9, cr\u00e9ant ainsi une tendance \u00e0 l&rsquo;int\u00e9gration coloniale avec les m\u00e8res patries. C&rsquo;est dans ce contexte que le Commonwealth britannique s&rsquo;est d\u00e9velopp\u00e9. L&rsquo;\u00e9mergence de ce nouveau type de gouvernance imp\u00e9riale a provoqu\u00e9 de nombreux d\u00e9bats entre les colonies et les empires concernant les \u00ab&#160;anciens empires&#160;\u00bb contre les \u00ab&#160;nouveaux&#160;\u00bb, les \u00ab&#160;empires coloniaux&#160;\u00bb contre les \u00ab&#160;empires libres&#160;\u00bb et le \u00ab&#160;colonialisme&#160;\u00bb contre l'\u00a0\u00bbimp\u00e9rialisme&#160;\u00bb.<\/p>\n\n\n\n<p>Tout comme dans la critique politique de l'\u00a0\u00bbimp\u00e9rialisme&#160;\u00bb par Hobson et L\u00e9nine, les empires coloniaux traditionnels en sont venus \u00e0 \u00eatre qualifi\u00e9s de \u00ab&#160;colonialistes&#160;\u00bb, tandis que la notion d'\u00a0\u00bbimp\u00e9rialisme&#160;\u00bb a fini par \u00eatre utilis\u00e9e uniquement pour d\u00e9signer la nouvelle forme d&#8217;empire mondial de la Grande-Bretagne, ce que nous pourrions appeler le colonialisme sans colonies.&nbsp; L&rsquo;\u00e9mergence de cette nouvelle forme d&#8217;empire signifiait que l&rsquo;expansion imp\u00e9riale ne reposerait plus sur l&rsquo;occupation de territoires, mais plut\u00f4t sur la domination scientifique et technologique, le contr\u00f4le financier et le droit international. Ceci est d&rsquo;autant plus vrai que le droit international n&rsquo;est plus le droit international partag\u00e9 de l&rsquo;\u00e9poque imp\u00e9riale, mais des lois priv\u00e9es qui ont p\u00e9n\u00e9tr\u00e9 dans les territoires des affaires, commerciales et financi\u00e8res, de tous les pays. En ce sens, un \u00c9tat-nation souverain pouvait \u00e9riger un \u00ab&#160;empire mondial&#160;\u00bb simplement par le contr\u00f4le mondial de la science et de la technologie, de la monnaie et du commerce. C&rsquo;est le mod\u00e8le d&#8217;empire mondial construit par l&rsquo;Angleterre et les \u00c9tats-Unis.<\/p>\n\n\n\n<p>Les deux guerres mondiales ont fait entrer la construction de l&#8217;empire mondial dans une nouvelle phase historique. Nous les appelons \u00ab&#160;Guerres mondiales&#160;\u00bb non seulement parce que les puissances du monde entier y ont \u00e9t\u00e9 impliqu\u00e9es, mais aussi parce que de nombreux empires coloniaux mondiaux \u00e9taient aux prises avec la construction de l'\u00a0\u00bbempire mondial&#160;\u00bb. En fait, les deux camps de la guerre froide qui se sont d\u00e9velopp\u00e9s apr\u00e8s la Seconde Guerre mondiale refl\u00e9taient la concurrence entre deux mod\u00e8les d'\u00a0\u00bbempire mondial&#160;\u00bb&#160;: l&rsquo;un \u00e9tait le mod\u00e8le am\u00e9ricain, qui avait h\u00e9rit\u00e9 du nouveau mod\u00e8le \u00ab&#160;imp\u00e9rialiste&#160;\u00bb d\u00e9velopp\u00e9 par l&#8217;empire britannique \u00e0 la fin de la p\u00e9riode&#160;; l&rsquo;autre \u00e9tait le mod\u00e8le sovi\u00e9tique, une alliance politique stable qui reposait sur une croyance commune dans le communisme et dans le leadership du Parti communiste parmi les r\u00e9publiques alli\u00e9es. En termes id\u00e9ologiques, ces deux types d&#8217;empire mondial \u00e9taient appel\u00e9s \u00ab&#160;lib\u00e9ralisme\/imp\u00e9rialisme&#160;\u00bb et \u00ab&#160;communisme&#160;\u00bb, ce qui, en termes de valeurs, se traduisait par \u00ab&#160;libert\u00e9&#160;\u00bb contre \u00ab&#160;\u00e9galit\u00e9&#160;\u00bb, mais en termes de tradition imp\u00e9riale, ils refl\u00e9taient toujours la distinction entre les empires maritimes et continentaux, l&#8217;empire maritime exer\u00e7ant son contr\u00f4le par le commerce et les \u00e9changes, et l&#8217;empire continental par la moralit\u00e9 communautaire.<\/p>\n\n\n\n<p>Nous avons limit\u00e9 notre compr\u00e9hension de l&rsquo;id\u00e9e d'\u00a0\u00bbempire&#160;\u00bb, soit \u00e0 ce que nous imaginons que l&#8217;empire r\u00e9gional civilisationnel classique aurait pu \u00eatre, soit \u00e0 notre critique des empires coloniaux mondiaux modernes, y compris l&rsquo;\u00e9mergence de la nouvelle forme d'\u00a0\u00bbempire mondial&#160;\u00bb, et pour cette raison, nous avons accord\u00e9 peu d&rsquo;attention \u00e0 la nature particuli\u00e8re de cette forme imp\u00e9riale.&nbsp; L&#8217;empire sovi\u00e9tique a souvent \u00e9t\u00e9 critiqu\u00e9 comme un empire traditionnel, avide de territoire et d&rsquo;h\u00e9g\u00e9monie, ce qui a entra\u00een\u00e9 l\u2019ignorance des diff\u00e9rences entre le mod\u00e8le sovi\u00e9tique et les id\u00e9es traditionnelles d&#8217;empire, notamment les fortes croyances en la r\u00e9volution et la lib\u00e9ration contenues dans l&rsquo;id\u00e9ologie communiste, ce qui a conduit au d\u00e9sir d&rsquo;\u00e9tablir un seul empire, mondial.<\/p>\n\n\n\n<p class=\"comment\">Une question importante dans le domaine de la pens\u00e9e politique aujourd&rsquo;hui est l&rsquo;\u00e9norme \u00e9cart dans le discours dominant entre l'\u00a0\u00bbexpression&#160;\u00bb th\u00e9orique d&rsquo;une nation souveraine et la pratique politique universelle des empires. Cet \u00e9cart entre la th\u00e9orie et la pratique nous am\u00e8ne \u00e0 r\u00e9fl\u00e9chir au syst\u00e8me conceptuel de l'\u00a0\u00bb\u00c9tat-nation&#160;\u00bb, puis \u00e0 utiliser le concept d'\u00a0\u00bbempire&#160;\u00bb pour parvenir \u00e0 une nouvelle compr\u00e9hension de l&rsquo;histoire et de la vie politique contemporaine.<\/p>\n\n\n\n<p>Et parce que l&#8217;empire mondial construit par les Britanniques et les Am\u00e9ricains reposait sur une monnaie et un syst\u00e8me commercial, ainsi que sur un syst\u00e8me de trait\u00e9s internationaux, les gens ont souvent ignor\u00e9 la nouveaut\u00e9 de cette forme imp\u00e9riale. Il \u00e9tait facile de le voir comme un empire dans lequel des \u00c9tats-nations souverains, sur un pied d&rsquo;\u00e9galit\u00e9, sont entr\u00e9s dans le syst\u00e8me international \u00e0 la suite des mouvements de lib\u00e9ration nationale qui se sont produits avec l&rsquo;\u00e9clipse des anciens empires coloniaux. Nous ne voyons les Nations unies que comme repr\u00e9sentatives de ce syst\u00e8me international d&rsquo;\u00c9tats-nations \u00e9gaux, et ignorons le fait que les Nations unies elles-m\u00eames \u00e9taient un r\u00e9sultat de la construction de l&#8217;empire mondial, un site de lutte dans la construction des empires mondiaux. \u00c0 la fin de la guerre froide, l&rsquo;abandon par les \u00c9tats-Unis des Nations unies et leur adh\u00e9sion \u00e0 l&rsquo;unilat\u00e9ralisme d\u00e9montrent pleinement que la construction de l'\u00a0\u00bbempire mondial&#160;\u00bb dirig\u00e9 par les \u00c9tats-Unis est achev\u00e9e&#160;; dans le monde d&rsquo;aujourd&rsquo;hui, la Chine et la Russie se situent dans le syst\u00e8me de l'\u00a0\u00bbempire mondial&#160;\u00bb dirig\u00e9 par les \u00c9tats-Unis. La raison pour laquelle les sanctions \u00e9conomiques des \u00c9tats-Unis, fond\u00e9es sur le droit national, peuvent obtenir les r\u00e9sultats qu&rsquo;elles obtiennent, c&rsquo;est que le monde a \u00e9t\u00e9 organis\u00e9 de mani\u00e8re \u00e0 r\u00e9pondre aux besoins de cet unique \u00ab&#160;empire mondial&#160;\u00bb.<\/p>\n\n\n\n<p>C&rsquo;est pourquoi, au lieu de comprendre la fin de la guerre froide comme la \u00ab&#160;fin de l&rsquo;histoire&#160;\u00bb d&rsquo;un point de vue id\u00e9ologique, il est plus juste de la voir sous l&rsquo;angle de \u00ab&#160;l&#8217;empire mondial&#160;\u00bb. La \u00ab&#160;mondialisation&#160;\u00bb dirig\u00e9e par les Am\u00e9ricains dans l&rsquo;\u00e8re de l&rsquo;apr\u00e8s-guerre froide, que ce soit en termes d&rsquo;id\u00e9es ou de strat\u00e9gie militaire, favorise l'\u00a0\u00bbimp\u00e9rialisation&#160;\u00bb am\u00e9ricaine et la construction d&rsquo;un seul empire mondial.&nbsp; Dans le contexte occidental, on a souvent appel\u00e9 cela le \u00ab&#160;nouvel Empire romain&#160;\u00bb.<\/p>\n\n\n\n<p>D\u00e9sormais, aucun pays ne pourra exister en dehors de ce syst\u00e8me de commerce mondial avec sa libert\u00e9, son \u00e9tat de droit et sa d\u00e9mocratie. Chaque pays, qu&rsquo;il le veuille ou non, sera n\u00e9cessairement impliqu\u00e9 dans la construction de cet empire mondial.&nbsp; L&rsquo;historien chinois Tong Tekong \u5510\u5fb7\u521a (1920-2009) parlait souvent des \u00ab&#160;trois gorges de l&rsquo;histoire \u5386\u53f2\u4e09\u5ce1&#160;\u00bb, ce qui, par essence, renvoie \u00e9galement au processus de \u00ab&#160;fin de l&rsquo;histoire&#160;\u00bb et d'\u00a0\u00bbempire mondial&#160;\u00bb.&nbsp; Nous pourrions dire que la mondialisation que nous vivons aujourd&rsquo;hui est l'\u00a0\u00bbempire mondial unique&#160;\u00bb 1.0, le mod\u00e8le d&#8217;empire mondial \u00e9tabli par l&rsquo;Angleterre et les \u00c9tats-Unis. \u00c0 l&rsquo;avenir, chaque pays devra chercher son propre mod\u00e8le de d\u00e9veloppement au sein de cet ordre imp\u00e9rial mondial de libert\u00e9, d&rsquo;\u00c9tat de droit et de d\u00e9mocratie.<\/p>\n\n\n\n<p class=\"comment\">Tong Tekong (1920-2009) \u00e9tait un historien sino-am\u00e9ricain ayant enseign\u00e9 \u00e0 l&rsquo;universit\u00e9 Columbia et \u00e0 la City University of New York. Ses \u00ab&#160;trois gorges&#160;\u00bb font r\u00e9f\u00e9rence aux \u00e9poques f\u00e9odale, imp\u00e9riale et d\u00e9mocratique de la Chine, ainsi qu&rsquo;aux transitions entre ces \u00e9poques.<\/p>\n\n\n\n<p>\u00c0 l&rsquo;heure actuelle, l&rsquo;Am\u00e9rique subit une forte pression pour maintenir son empire mondial, notamment en raison de la r\u00e9sistance russe et de la concurrence chinoise. Mais nous devons reconna\u00eetre que cette comp\u00e9tition est une comp\u00e9tition qui se d\u00e9roule au sein du syst\u00e8me de l&#8217;empire mondial, une lutte pour s&#8217;emparer du leadership \u00e9conomique et politique apr\u00e8s la r\u00e9alisation de \u00ab&#160;l&#8217;empire mondial&#160;\u00bb.&nbsp; En fait, nous pouvons la comprendre comme une lutte pour devenir le c\u0153ur de l&#8217;empire mondial. Cette lutte pourrait conduire \u00e0 l&rsquo;effondrement et \u00e0 la d\u00e9sint\u00e9gration du syst\u00e8me imp\u00e9rial mondial, ou \u00e0 un changement de qui d\u00e9tient le pouvoir ultime dans l&#8217;empire mondial, ou m\u00eame \u00e0 la reconstruction du syst\u00e8me de l&#8217;empire mondial, mais ce qui ne se produira absolument pas, c&rsquo;est un retour \u00e0 la p\u00e9riode historique marqu\u00e9e par l&rsquo;existence d&#8217;empires civilisationnels r\u00e9gionaux.<\/p>\n\n\n\n<p><em>[Le monde se transforme. Avec notre s\u00e9rie \u00ab Doctrines de la Chine de Xi Jinping \u00bb, nous esquissons une tentative de comprendre les dynamiques profondes qui animent les penseurs chinois contemporains en les lisant, en les traduisant. Si vous trouvez notre travail utile et pensez qu\u2019il m\u00e9rite d\u2019\u00eatre soutenu, vous pouvez vous abonner&nbsp;<a href=\"https:\/\/legrandcontinent.eu\/fr\/user-dashboard\/register\/\">ici<\/a>.]<\/em><\/p>\n\n\n\n<p>M\u00eame si Huntington consid\u00e9rait la situation mondiale de l&rsquo;apr\u00e8s-guerre froide comme un \u00ab&#160;choc des civilisations&#160;\u00bb, et m\u00eame si ces conflits de civilisations recoupent dans une certaine mesure la r\u00e9partition g\u00e9ographique des empires civilisationnels r\u00e9gionaux, nous ne pouvons absolument pas confondre les deux. Ce que Huntington appelle un \u00ab&#160;choc des civilisations&#160;\u00bb n&rsquo;est en fait qu&rsquo;une r\u00e9volte contre l&#8217;empire mondial de l&rsquo;int\u00e9rieur, qui se d\u00e9veloppera n\u00e9cessairement dans le cadre du syst\u00e8me de l&rsquo;actuel \u00ab&#160;empire mondial&#160;\u00bb, tout comme elle doit n\u00e9cessairement se d\u00e9velopper dans le cadre du r\u00e9cit philosophique universaliste de la \u00ab&#160;fin de l&rsquo;histoire&#160;\u00bb de la technologie, du commerce et des \u00e9changes, de la libert\u00e9 et de l&rsquo;\u00c9tat de droit.&nbsp; Pour cette raison, le monde futur ne peut progresser et se reconstruire que sur cette base, qui ne peut \u00eatre compl\u00e8tement boulevers\u00e9e, \u00e0 moins que le monde entier ne retourne \u00e0 l&#8217;empire mondial construit par le fondamentalisme islamique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"conclusion\"><strong>Conclusion<\/strong><\/h2>\n\n\n\n<p>Depuis le vingti\u00e8me si\u00e8cle, le destin in\u00e9vitable de l&rsquo;humanit\u00e9 est d&rsquo;entrer dans l&#8217;empire mondial. Peu importe que nous y voyions une source de \u00ab&#160;paix \u00e9ternelle&#160;\u00bb ou que nous maintenions nos attentes communistes, et peu importe que nous critiquions et\/ou d\u00e9plorions l&rsquo;h\u00e9g\u00e9monie technologique, \u00e9conomique et politique, nous ne pouvons \u00e9chapper \u00e0 l&rsquo;arriv\u00e9e de l&rsquo;\u00e2ge de l&#8217;empire mondial. Si nous disons que les origines de l&#8217;empire mondial peuvent \u00eatre attribu\u00e9es \u00e0 la concurrence entre des empires civilisationnels r\u00e9gionaux, alors l&#8217;empire mondial 1.0 d&rsquo;aujourd&rsquo;hui est le mod\u00e8le d&#8217;empire mondial fa\u00e7onn\u00e9 par la civilisation chr\u00e9tienne occidentale.&nbsp;<\/p>\n\n\n\n<p>Ce mod\u00e8le est confront\u00e9 \u00e0 trois grands probl\u00e8mes insolubles&#160;: l&rsquo;in\u00e9galit\u00e9 toujours croissante cr\u00e9\u00e9e par l&rsquo;\u00e9conomie lib\u00e9rale&#160;; l&rsquo;\u00e9chec de l&rsquo;\u00c9tat, le d\u00e9clin politique et la gouvernance inefficace caus\u00e9s par le lib\u00e9ralisme politique&#160;; et la d\u00e9cadence et le nihilisme cr\u00e9\u00e9s par le lib\u00e9ralisme culturel.&nbsp; Face \u00e0 ces difficult\u00e9s, m\u00eame les \u00c9tats-Unis se sont retir\u00e9s en termes de strat\u00e9gie militaire mondiale, ce qui signifie que l&#8217;empire mondial 1.0 est actuellement confront\u00e9 \u00e0 une grande crise, et que les r\u00e9voltes, la r\u00e9sistance et la r\u00e9volution au sein de l&#8217;empire sont en train de d\u00e9faire le syst\u00e8me.&nbsp;<\/p>\n\n\n\n<p>La mont\u00e9e de l&#8217;empire mondial a compl\u00e8tement chang\u00e9 les distinctions politiques et id\u00e9ologiques traditionnelles entre la gauche et la droite, traditionnellement bas\u00e9es sur la politique int\u00e9rieure, comme on peut le voir clairement dans les \u00e9lections comp\u00e9titives aux \u00c9tats-Unis et en Europe. L&rsquo;aile droite, qui d\u00e9fendait traditionnellement les march\u00e9s libres, s&rsquo;est orient\u00e9e vers le populisme, tandis que l&rsquo;aile gauche a chang\u00e9 de discours et d\u00e9fend d\u00e9sormais les int\u00e9r\u00eats particuliers de la mondialisation. Ce renversement id\u00e9ologique refl\u00e8te parfaitement la crise \u00e0 laquelle est confront\u00e9 l&#8217;empire mondial aujourd&rsquo;hui, dans la mesure o\u00f9 il n&rsquo;existe aucun programme politique capable de r\u00e9soudre les trois grands probl\u00e8mes auxquels l&#8217;empire mondial est confront\u00e9.&nbsp;<\/p>\n\n\n\n<p>Nous pourrions conclure que nous vivons \u00e0 une \u00e9poque de chaos, de conflits et de changements massifs dans laquelle l&#8217;empire mondial 1.0 est en d\u00e9clin et tend \u00e0 s&rsquo;effondrer, tandis que nous sommes encore incapables d&rsquo;imaginer l&#8217;empire mondial 2.0. Pourtant, nous devons reconna\u00eetre que le changement de la forme de l&#8217;empire est un long processus historique. Les quelques milliers d&rsquo;ann\u00e9es de l&rsquo;histoire de l&rsquo;humanit\u00e9 n&rsquo;ont connu que trois grands changements de forme imp\u00e9riale, et chacun de ces changements a \u00e9t\u00e9 accompagn\u00e9 de grands conflits et de chaos. En m\u00eame temps, nous ne pouvons nier que ces \u00e9poques de transition historique ont \u00e9galement cr\u00e9\u00e9 l&rsquo;opportunit\u00e9 pour chaque civilisation de construire un empire mondial 2.0. La civilisation qui est capable d&rsquo;apporter de v\u00e9ritables solutions aux trois grands probl\u00e8mes auxquels est confront\u00e9 l&#8217;empire mondial 1.0 fournira \u00e9galement le plan de l&#8217;empire mondial 2.0.&nbsp; En tant que grande puissance mondiale qui doit regarder au-del\u00e0 de ses propres fronti\u00e8res, la Chine doit r\u00e9fl\u00e9chir \u00e0 son propre avenir, car sa mission importante ne consiste pas seulement \u00e0 faire revivre sa culture traditionnelle. La Chine doit \u00e9galement absorber patiemment les comp\u00e9tences et les r\u00e9alisations de l&rsquo;humanit\u00e9 dans son ensemble, et notamment celles employ\u00e9es par la civilisation occidentale pour construire l&#8217;empire mondial. Ce n&rsquo;est que sur cette base que nous pourrons consid\u00e9rer la reconstruction de la civilisation chinoise et la reconstruction de l&rsquo;ordre mondial comme un tout qui se renforce mutuellement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/doctrines-de-xi\/\" \/>Doctrines de la Chine de Xi<\/a> |\u00a0\u00c9pisode 2<\/p>\n<p>Les empires n&rsquo;ont pas disparu, ils ont seulement chang\u00e9 de forme et de fonction. Pour Jiang Shigong, la Chine est in\u00e9luctablement en train d&rsquo;entrer dans une nouvelle phase&#160;&#160;: l&#8217;empire mondial 2.0.<\/p>\n","protected":false},"author":10,"featured_media":131502,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":39,"footnotes":""},"categories":[3097],"tags":[],"staff":[3098],"editorial_format":[4943],"serie":[],"audience":[],"geo":[531],"class_list":["post-131402","post","type-post","status-publish","format-standard","hentry","category-doctrines-de-xi","staff-david-ownby","editorial_format-discours","geo-chine"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":131502,"excerpt":"<a href=https:\/\/legrandcontinent.eu\/fr\/themes\/doctrines-de-xi\/>Doctrines de la Chine de Xi<\/a> |\u00a0\u00c9pisode 2\r\n\r\nLes empires n'ont pas disparu, ils ont seulement chang\u00e9 de forme et de fonction. Pour Jiang Shigong, la Chine est in\u00e9luctablement en train d'entrer dans une nouvelle phase : l'empire mondial 2.0.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;empire et l&#039;ordre mondial selon Jiang Shigong | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;empire et l&#039;ordre mondial selon Jiang Shigong | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Doctrines de la Chine de Xi |\u00a0\u00c9pisode 2  Les empires n&#039;ont pas disparu, ils ont seulement chang\u00e9 de forme et de fonction. Pour Jiang Shigong, la Chine est in\u00e9luctablement en train d&#039;entrer dans une nouvelle phase&#160;: l&#039;empire mondial 2.0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-03T04:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-03T07:48:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/gc-jiang-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"39 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/\",\"name\":\"L'empire et l'ordre mondial selon Jiang Shigong | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg\",\"datePublished\":\"2022-09-03T04:52:00+00:00\",\"dateModified\":\"2022-09-03T07:48:04+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg\",\"width\":2560,\"height\":2025,\"caption\":\"(210930) -- BEIJING, Sept. 30, 2021 (Xinhua) -- Xi Jinping straightens the red ribbons on flower baskets during a ceremony offering floral tribute to fallen national heroes on Tian'anmen Square in Beijing, capital of China, Sept. 30, 2021. Xi Jinping and other leaders of the Communist Party of China and the state attended the ceremony on Thursday morning on Tian'anmen Square in central Beijing. The event was held to mark China's Martyrs' Day, a day ahead of the National Day. The other leaders included Li Keqiang, Li Zhanshu, Wang Yang, Wang Huning, Zhao Leji, Han Zheng and Wang Qishan. (Xinhua\/Li Xiang) - Li Xiang -\/\/CHINENOUVELLE_XxjpbeE007385_20210930_PEPFN0A001\/2109301637\/Credit:CHINE NOUVELLE\/SIPA\/2109301637\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;empire et l&rsquo;ordre mondial selon Jiang Shigong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'empire et l'ordre mondial selon Jiang Shigong | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/","og_locale":"fr_FR","og_type":"article","og_title":"L'empire et l'ordre mondial selon Jiang Shigong | Le Grand Continent","og_description":"Doctrines de la Chine de Xi |\u00a0\u00c9pisode 2  Les empires n'ont pas disparu, ils ont seulement chang\u00e9 de forme et de fonction. Pour Jiang Shigong, la Chine est in\u00e9luctablement en train d'entrer dans une nouvelle phase&#160;: l'empire mondial 2.0.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/","og_site_name":"Le Grand Continent","article_published_time":"2022-09-03T04:52:00+00:00","article_modified_time":"2022-09-03T07:48:04+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/gc-jiang-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"39 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/","name":"L'empire et l'ordre mondial selon Jiang Shigong | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg","datePublished":"2022-09-03T04:52:00+00:00","dateModified":"2022-09-03T07:48:04+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg","width":2560,"height":2025,"caption":"(210930) -- BEIJING, Sept. 30, 2021 (Xinhua) -- Xi Jinping straightens the red ribbons on flower baskets during a ceremony offering floral tribute to fallen national heroes on Tian'anmen Square in Beijing, capital of China, Sept. 30, 2021. Xi Jinping and other leaders of the Communist Party of China and the state attended the ceremony on Thursday morning on Tian'anmen Square in central Beijing. The event was held to mark China's Martyrs' Day, a day ahead of the National Day. The other leaders included Li Keqiang, Li Zhanshu, Wang Yang, Wang Huning, Zhao Leji, Han Zheng and Wang Qishan. (Xinhua\/Li Xiang) - Li Xiang -\/\/CHINENOUVELLE_XxjpbeE007385_20210930_PEPFN0A001\/2109301637\/Credit:CHINE NOUVELLE\/SIPA\/2109301637"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/09\/03\/lempire-et-lordre-mondial-selon-jiang-shigong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;empire et l&rsquo;ordre mondial selon Jiang Shigong"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3097,"name":"Doctrines de la Chine de Xi Jinping","slug":"doctrines-de-xi"}],"lgc_author":{"id":3098,"name":"David Ownby","slug":"david-ownby","description":"David Ownby est sinologue, professeur \u00e0 l\u2019Universit\u00e9 de Montr\u00e9al. Il a dispens\u00e9 une s\u00e9rie de cours au Coll\u00e8ge de France, et est directeur de Voices from the Chinese Century, ainsi que de son site Reading the China Dream qui traduit des auteurs chinois importants dans le d\u00e9bat intellectuel. Il \u00e9dite la s\u00e9rie \u00ab <a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/doctrines-de-xi\/\">Doctrines de la Chine de Xi Jinping<\/a> \u00bb sur Le Grand Continent.","first_name":"David ","last_name":"Ownby ","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/01\/52144281584_121c0c1809_k-680x1020-1.jpeg","width":680,"height":680,"alt":"Directeur de Reading the China Dream"}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg","width":2560,"height":2025,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_01040917_000003-scaled.jpg","width":2560,"height":2025,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/131402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=131402"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/131402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/131502"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=131402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=131402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=131402"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=131402"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=131402"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=131402"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=131402"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=131402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}