{"id":130452,"date":"2022-02-04T17:20:30","date_gmt":"2022-02-04T16:20:30","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=130452"},"modified":"2022-02-07T15:49:38","modified_gmt":"2022-02-07T14:49:38","slug":"les-spectres-de-la-defense-europeenne-se-raniment","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/","title":{"rendered":"Les spectres de la d\u00e9fense europ\u00e9enne se raniment"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Comment jeter les bases d&rsquo;une industrie de d\u00e9fense dans un pays qui vient de perdre une guerre mondiale qu\u2019il se trouve avoir lui-m\u00eame d\u00e9clench\u00e9e&#160;? C\u2019est la question qui s\u2019est pr\u00e9sent\u00e9e \u00e0 Franz Josef Strauss lorsque le gouvernement allemand de l\u2019apr\u00e8s-guerre a fait le choix du r\u00e9armement au milieu des ann\u00e9es 1950. Les d\u00e9cisions prises par le ministre de la d\u00e9fense de l&rsquo;\u00e9poque alimentent encore la schizophr\u00e9nie qui d\u00e9finit aujourd\u2019hui la politique d\u2019exportation allemande. Ils affectent \u00e9galement la coop\u00e9ration europ\u00e9enne en mati\u00e8re de s\u00e9curit\u00e9 apr\u00e8s le Brexit, alors m\u00eame que la nouvelle coalition gouvernementale entre aux affaires \u00e0 Berlin et esp\u00e8re \u00e9toffer l&rsquo;id\u00e9e d&rsquo;une <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/25\/doctrine-de-la-nouvelle-ere-allemande\/\">\u00ab&#160;&nbsp;souverainet\u00e9 strat\u00e9gique&#160;\u00bb<\/a> europ\u00e9enne.<\/p>\n\n\n\n<p>De l&rsquo;autre c\u00f4t\u00e9 du Rhin, Emmanuel Macron a fait de l&rsquo;Europe un marqueur constant de son identit\u00e9 politique prot\u00e9iforme dans la perspective de l&rsquo;\u00e9lection pr\u00e9sidentielle de 2022. La coop\u00e9ration franco-allemande actuelle et future appara\u00eet donc essentielle pour cr\u00e9dibiliser ses efforts dans un environnement fran\u00e7ais marqu\u00e9 par des r\u00e9surgences nationalistes et un paysage international qui a vu l&rsquo;\u00e9mergence d&rsquo;un pacte de d\u00e9fense opposant les \u00c9tats-Unis, le Royaume-Uni et l&rsquo;Australie (AUKUS) \u00e0 la Chine dans la r\u00e9gion indo-pacifique. Beaucoup d\u00e9pendra du degr\u00e9 jusqu\u2019auquel Paris et Berlin consid\u00e8reront que leurs int\u00e9r\u00eats politiques communs l&#8217;emportent sur leurs diff\u00e9rences strat\u00e9giques nationales.<\/p>\n\n\n\n<p>Car les deux pays devront composer avec un h\u00e9ritage qui ne joue pas en leur faveur \u2013 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/26\/le-passe-impense-pour-un-recit-critique-europeen\/\">m\u00eame si la nature anhistorique des d\u00e9bats actuels sur la construction d&rsquo;une Europe \u00ab&#160;g\u00e9opolitique&#160;\u00bb semble masquer cette dimension<\/a>. Lorsque les d\u00e9cideurs politiques daignent faire un rare clin d&rsquo;\u0153il \u00e0 l&rsquo;histoire, ils se contentent g\u00e9n\u00e9ralement d&rsquo;une allusion fatigu\u00e9e \u00e0 l&rsquo;\u00e9chec de la Communaut\u00e9 europ\u00e9enne de d\u00e9fense en 1954 \u2013 quand ils ne se trompent pas dans la date&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-1-130452' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.lemonde.fr\/international\/article\/2021\/09\/11\/guy-verhofstadt-faute-d-une-coordination-suffisante-l-europe-dans-sa-forme-actuelle-ne-survivra-pas-au-xxie-siecle_6094336_3210.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Guy Verhofstadt&amp;nbsp;&amp;#160;: &amp;lsquo;Faute d\u2019une coordination suffisante, l\u2019Europe, dans sa forme actuelle, ne survivra pas au XXIe&amp;nbsp;si\u00e8cle&amp;rsquo;&lt;\/a&gt;\u00ab&amp;#160;, &lt;em&gt;Le Monde&lt;\/em&gt;, 11 septembre 2021.'><sup>1<\/sup><\/a><\/span><\/span>. L&rsquo;histoire a bien retenu l&rsquo;\u00e9chec de l&rsquo;id\u00e9e de Jean Monnet qui laissa Romain Gary dans un \u00e9tat de constante schizophr\u00e9nie&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-2-130452' title='Voir la contribution d&amp;rsquo;Olivier de France dans &lt;a href=&quot;https:\/\/css.ethz.ch\/content\/dam\/ethz\/special-interest\/gess\/cis\/center-for-securities-studies\/resources\/docs\/EUISS-After%20the%20EU%20Global%20Strategy.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;ce memo de l&amp;rsquo;ISS&lt;\/a&gt;'><sup>2<\/sup><\/a><\/span><\/span>. \u00c0 Bonn, sous la houlette de Franz Josef Strauss, des \u00e9v\u00e9nements moins connus conspiraient \u00e0 l&rsquo;\u00e9poque pour cr\u00e9er un cas tout aussi durable de schizophr\u00e9nie allemande. Ces deux spectres se cachent toujours au fond des tiroirs strat\u00e9giques du continent et continuent de saper certains de ses meilleurs efforts de coop\u00e9ration.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Deux spectres se cachent toujours au fond des tiroirs strat\u00e9giques du continent et continuent de saper certains de ses meilleurs efforts de coop\u00e9ration.<\/p><cite>Olivier de France et John Helferich<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ces derni\u00e8res ann\u00e9es, le consensus franco-allemand sur le r\u00f4le de l\u2019Union a \u00e9volu\u00e9 de mani\u00e8re inhabituelle pour d\u00e9passer des tabous \u00e9conomiques et militaires&#160;: le budget europ\u00e9en est aujourd&rsquo;hui utilis\u00e9 pour \u00e9mettre une dette commune et pour financer la recherche en mati\u00e8re de d\u00e9fense. La conjonction des \u00e9lections fran\u00e7aises et de la nouvelle coalition allemande ranimera-t-elle ces spectres enfouis dans le grenier de l&rsquo;Europe&#160;?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"l-allemagne-geopolitique\"><strong>L\u2019Allemagne g\u00e9opolitique<\/strong><\/h2>\n\n\n\n<p>Lorsque Franz Josef Strauss arrive \u00e0 la t\u00eate du minist\u00e8re allemand de la d\u00e9fense en 1956, \u00ab&#160;g\u00e9opolitique&#160;\u00bb est un mot interdit dans les cercles diplomatiques europ\u00e9ens. Son pays, paria politique sur le continent, est encore dans l\u2019ombre des proc\u00e8s de Nuremberg. L&rsquo;impulsion initiale en faveur de la normalisation de la position de l&rsquo;Allemagne en Europe viendra donc de Washington, dans le contexte de la guerre froide et du conflit en Cor\u00e9e, non sans une forte r\u00e9sistance de Paris et de Londres.<\/p>\n\n\n\n<p>Avec la b\u00e9n\u00e9diction des \u00c9tats-Unis, Bonn se rallie progressivement au camp de l\u2019Ouest, reconstitue ses forces arm\u00e9es et entre dans l&rsquo;OTAN en 1955. Konrad Adenauer soutient le r\u00e9armement&#160;: il y voit un moyen de r\u00e9tablir la capacit\u00e9 d&rsquo;autod\u00e9termination de la jeune R\u00e9publique f\u00e9d\u00e9rale. Mais dans l&rsquo;ensemble, Adenauer est favorable \u00e0 la cr\u00e9ation de la Communaut\u00e9 europ\u00e9enne de d\u00e9fense, dont l&rsquo;\u00e9chec sera plus tard qualifi\u00e9 de \u00ab&#160;plus grand revers&#160;\u00bb pour l&rsquo;Allemagne dans l&rsquo;apr\u00e8s-guerre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-3-130452' title='Voir &lt;a href=&quot;https:\/\/www.youtube.com\/watch?v=90EVIH4KZsc&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;l&amp;rsquo;entretien t\u00e9l\u00e9vis\u00e9&lt;\/a&gt; de G\u00fcnter Gaus \u00e0 Konrad Adenauer de 1965.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>L\u2019autorisation de r\u00e9armement national donne l&rsquo;occasion de reb\u00e2tir une industrie de la d\u00e9fense allemande, bien que de mani\u00e8re restreinte. Fait remarquable, l&rsquo;un des premiers clients importants de l&rsquo;Allemagne est Isra\u00ebl&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-4-130452' title='&lt;a href=&quot;https:\/\/www.bpb.de\/apuz\/199900\/zur-geschichte-der-ruestungskooperation&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.bpb.de\/apuz\/199900\/zur-geschichte-der-ruestungskooperation&lt;\/a&gt;'><sup>4<\/sup><\/a><\/span><\/span>. Le nouvel \u00c9tat cherche alors d\u00e9sesp\u00e9r\u00e9ment \u00e0 acqu\u00e9rir les moyens de se d\u00e9fendre, et Bonn lui fournit. La politique de r\u00e9conciliation d&rsquo;Adenauer&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-5-130452' title='&lt;a href=&quot;https:\/\/www.bits.de\/public\/articles\/cast06-02.htm&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.bits.de\/public\/articles\/cast06-02.htm&lt;\/a&gt;'><sup>5<\/sup><\/a><\/span><\/span> permet d&rsquo;envoyer des quantit\u00e9s substantielles de biens \u00e0 double usage et de mat\u00e9riel d\u00e9saffect\u00e9 \u00e0 Tel-Aviv, soigneusement mises \u00e0 l\u2019abri des regards. L&rsquo;exportation d&rsquo;\u00e9quipements militaires dans de telles conditions n&rsquo;est toutefois pas viable sans un cadre juridique appropri\u00e9.<\/p>\n\n\n\n<p>Dans la mesure o\u00f9 le corpus juridique d&rsquo;une nation peut \u00eatre consid\u00e9r\u00e9 comme une codification de sa politique, \u00e9difier un tel corpus n&rsquo;a jamais \u00e9t\u00e9 facile. D&rsquo;une part, un r\u00e9gime d&rsquo;exportation permissif pourrait permettre de cr\u00e9er des emplois dans un pays d\u00e9chir\u00e9 par la guerre, de construire une industrie de d\u00e9fense florissante et d&rsquo;aider l&rsquo;Allemagne \u00e0 retrouver son statut d&rsquo;\u00c9tat ind\u00e9pendant. D&rsquo;autre part, la loi peut difficilement fermer les yeux sur le sentiment public et le pacifisme g\u00e9n\u00e9ralis\u00e9. Une r\u00e9sistance farouche au r\u00e9armement se manifeste au Bundestag et dans l&rsquo;opinion publique allemande, qui craint une r\u00e9surgence du militarisme allemand.<\/p>\n\n\n\n<p>Pour r\u00e9soudre la quadrature du cercle, Strauss doit sortir des sentiers battus \u2013 en l&rsquo;occurrence&#160;: de la constitution de son pays. L&rsquo;article 26 (2) de la Loi fondamentale stipule que seul le gouvernement peut autoriser les exportations d&rsquo;armes, mais que tous les d\u00e9tails doivent \u00eatre r\u00e9glement\u00e9s par un texte de loi f\u00e9d\u00e9ral. S\u2019\u00e9cartant la lettre de ce texte, Strauss d\u00e9cide de cr\u00e9er non pas une mais deux lois f\u00e9d\u00e9rales, qui suivent des logiques oppos\u00e9es.<\/p>\n\n\n\n<p>La Loi sur le contr\u00f4le des armes de guerre, vot\u00e9e en 1961, adopte une vision restrictive des exportations d&rsquo;armes. Selon ses directives d&rsquo;application, \u00ab&#160;l&rsquo;exportation \u201cd&rsquo;armes de guerre\u201d ne fait pas l&rsquo;objet d&rsquo;une licence, \u00e0 moins que des int\u00e9r\u00eats particuliers de politique \u00e9trang\u00e8re ou de s\u00e9curit\u00e9 ne plaident en faveur d&rsquo;une licence dans un cas individuel&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-6-130452' title='Url du texte en vigueur&amp;#160;: &lt;a href=&quot;https:\/\/www.auswaertiges-amt.de\/en\/aussenpolitik\/themen\/aussenwirtschaft\/-\/231416#content_1&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.auswaertiges-amt.de\/en\/aussenpolitik\/themen\/aussenwirtschaft\/-\/231416#content_1&lt;\/a&gt;'><sup>6<\/sup><\/a><\/span><\/span>. La loi sur le commerce ext\u00e9rieur et les paiements, qui suivra quelques mois plus tard, dispose que le commerce ext\u00e9rieur des \u00ab&#160;autres armements&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-7-130452' title='Url&amp;#160;: &lt;a href=&quot;https:\/\/www.gesetze-im-internet.de\/englisch_awg\/englisch_awg.html#p0106&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.gesetze-im-internet.de\/englisch_awg\/englisch_awg.html#p0106&lt;\/a&gt;'><sup>7<\/sup><\/a><\/span><\/span> n&rsquo;est soumis \u00e0 aucune restriction, sauf si des int\u00e9r\u00eats essentiels de politique de s\u00e9curit\u00e9 s&rsquo;y opposent. Aussi arbitraire soit-elle, la distinction \u00e9tablie entre \u00ab&#160;armes de guerre&#160;\u00bb et \u00ab&#160;autres armements&#160;\u00bb cr\u00e9e une ambigu\u00eft\u00e9 constructive tout juste suffisante pour r\u00e9pondre aux besoins politiques et industriels de l&rsquo;\u00e9poque. Au cours des deux d\u00e9cennies suivantes, le r\u00e9gime de contr\u00f4le des exportations, associ\u00e9 \u00e0 une politique industrielle coh\u00e9rente et \u00e0 une campagne de privatisation pr\u00e9coce, font de l&rsquo;Allemagne l&rsquo;un des plus grands pays exportateurs d&rsquo;armes au monde&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-8-130452' title='Brzoska, Michael. \u201cThe Erosion of Restraint in West German Arms Transfer Policy.\u201d&amp;nbsp;&lt;em&gt;Journal of Peace Research&lt;\/em&gt;, vol. 26, no. 2, May 1989, pp. 165\u2013177, doi&amp;#160;:&lt;a href=&quot;https:\/\/doi.org\/10.1177\/0022343389026002005&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;10.1177\/0022343389026002005&lt;\/a&gt;.'><sup>8<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Aussi arbitraire soit-elle, la distinction \u00e9tablie entre \u00ab&#160;armes de guerre&#160;\u00bb et \u00ab&#160;autres armements&#160;\u00bb cr\u00e9e une ambigu\u00eft\u00e9 constructive tout juste suffisante pour r\u00e9pondre aux besoins politiques et industriels de l&rsquo;\u00e9poque.<\/p><cite>Olivier de France et John Helferich<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"contourner-la-constitution\"><strong>Contourner la Constitution<\/strong><\/h2>\n\n\n\n<p>Elle a \u00e9galement cr\u00e9\u00e9 un paradoxe qui a, depuis, poursuivi la politique allemande et europ\u00e9enne en la mati\u00e8re&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-9-130452' title='Voir Ian Davis, &lt;em&gt;The Regulation of Arms and Dual-Use Exports. Germany, Sweden and the UK&lt;\/em&gt;, publication du SIPRI, Oxford University Press, 2002. Url&amp;#160;: &lt;a href=&quot;https:\/\/www.sipri.org\/sites\/default\/files\/files\/books\/SIPRI02Davis.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.sipri.org\/sites\/default\/files\/files\/books\/SIPRI02Davis.pdf&lt;\/a&gt;'><sup>9<\/sup><\/a><\/span><\/span>. En Allemagne, les militants pacifistes se sont plaints que la distinction arbitraire entre les \u00ab&#160;armes de guerre&#160;\u00bb et les \u00ab&#160;autres armements&#160;\u00bb obscurcissait la l\u00e9galit\u00e9 des d\u00e9cisions d&rsquo;exportation&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-10-130452' title='&lt;a href=&quot;https:\/\/www.dw.com\/en\/german-arms-exports-strict-rules-dicey-deals\/a-16095538&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.dw.com\/en\/german-arms-exports-strict-rules-dicey-deals\/a-16095538&lt;\/a&gt;'><sup>10<\/sup><\/a><\/span><\/span>. Il a notamment \u00e9t\u00e9 avanc\u00e9 que les armes pouvaient \u00eatre d\u00e9sassembl\u00e9es et export\u00e9es en pi\u00e8ces d\u00e9tach\u00e9es afin de modifier leur statut d&rsquo;autorisation. De l\u2019autre c\u00f4t\u00e9, l&rsquo;industrie allemande s&rsquo;indigne souvent de la nature incoh\u00e9rente et impr\u00e9visible des pratiques d&rsquo;exportation qui en r\u00e9sultent.<\/p>\n\n\n\n<p>En termes politiques, cependant, le syst\u00e8me de double r\u00e9glementation a fourni aux d\u00e9cideurs un bouclier rh\u00e9torique contre les critiques \u00e9manant de ces diff\u00e9rents groupes. En permettant aux responsables politiques de mettre opportun\u00e9ment l&rsquo;accent sur la loi la plus restrictive ou la plus permissive, en fonction de l&rsquo;origine de la contestation, elle a noy\u00e9 dans l&rsquo;opacit\u00e9 le d\u00e9bat sur le r\u00f4le de l&rsquo;Allemagne comme acteur de la s\u00e9curit\u00e9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-11-130452' title='Ulrike Franke, \u00ab&amp;#160;A Millennial Considers The New German Problem After 30 Years Of Peace&amp;#160;\u00bb, &lt;em&gt;War On The Rocks&lt;\/em&gt;, 19 mai 2021. Url&amp;#160;: &lt;a href=&quot;https:\/\/warontherocks.com\/2021\/05\/a-millennial-considers-the-new-german-problem-after-30-years-of-peace\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/warontherocks.com\/2021\/05\/a-millennial-considers-the-new-german-problem-after-30-years-of-peace\/&lt;\/a&gt;'><sup>11<\/sup><\/a><\/span><\/span>. Aujourd&rsquo;hui, on oublie souvent que le syst\u00e8me opaque de contr\u00f4le des exportations a largement contribu\u00e9 \u00e0 maintenir \u00e0 l\u2019\u00e9tat pathologique le d\u00e9bat sur la politique de d\u00e9fense dans le discours public allemand.<\/p>\n\n\n\n<p>Sur la sc\u00e8ne internationale, cependant, l&rsquo;h\u00e9ritage de Strauss a contribu\u00e9 \u00e0 la r\u00e9putation de l&rsquo;Allemagne comme un acteur restrictif en termes de politique d\u2019exportation d&rsquo;armes et lui a permis de jouir d&rsquo;une position morale privil\u00e9gi\u00e9e. Le pays applique des contr\u00f4les stricts sur les exportations d&rsquo;armes l\u00e9g\u00e8res et de technologies li\u00e9es aux armes nucl\u00e9aires. C&rsquo;est \u00e9galement l&rsquo;un des rares pays \u00e0 effectuer des contr\u00f4les apr\u00e8s exp\u00e9dition sur place&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-12-130452' title='Dr Andrea Edoardo Varisco&amp;nbsp;,&amp;nbsp;Kolja Brockmann&amp;nbsp;et&amp;nbsp;Lucile Robin, \u00ab&amp;#160;Post-shipment Control Measures&amp;#160;: European Approaches to On-site Inspections of Exported Military Materiel&amp;#160;\u00bb, &lt;em&gt;SIPRI&lt;\/em&gt;, d\u00e9cembre 2020. Url&amp;#160;: &lt;a href=&quot;https:\/\/www.sipri.org\/sites\/default\/files\/2020-12\/bp_2012_post-shipment_controls.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.sipri.org\/sites\/default\/files\/2020-12\/bp_2012_post-shipment_controls.pdf&lt;\/a&gt;'><sup>12<\/sup><\/a><\/span><\/span>, et il a souvent demand\u00e9 \u00e0 ses partenaires de cesser les exportations vers des \u00c9tats ciblant des civils ou encourageant les conflits.&nbsp;<\/p>\n\n\n\n<p>Dans le m\u00eame temps, on trouve des armes allemandes dans toutes les grandes zones de guerre. La plus grande entreprise de d\u00e9fense allemande, Rheinmetall, fait du commerce dans le monde entier et approvisionne des \u00c9tats comme la Libye en munitions \u00e0 partir de filiales \u00e0 l&rsquo;\u00e9tranger&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-13-130452' title='&lt;a href=&quot;https:\/\/www.ardmediathek.de\/video\/dokthema\/bomben-fuer-die-welt-wie-deutschland-an-kriegen-und-krisen-verdient\/br-fernsehen\/Y3JpZDovL2JyLmRlL3ZpZGVvLzVhMzk2NWVlLTgzMGUtNDMzNy05NTMwLWI5OWFkODc1MjE2OQ\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Lien vid\u00e9o&lt;\/a&gt;.'><sup>13<\/sup><\/a><\/span><\/span>. Malgr\u00e9 des analyses juridiques montrant que de telles activit\u00e9s extraterritoriales pourraient \u00eatre sanctionn\u00e9es, les gouvernements successifs n&rsquo;ont pas \u00e9t\u00e9 incit\u00e9s \u00e0 agir&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-14-130452' title='John N. T. Helferich, &lt;a href=&quot;https:\/\/www.tectum-elibrary.de\/10.5771\/9783828876187\/arms-export-controls-under-siege-of-globalisation?hitid=00&amp;amp;search-click&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Arms Export Controls under Siege of Globalisation&lt;\/a&gt;, Tectum, Baden-Baden, 2020, &lt;a href=&quot;https:\/\/doi.org\/10.5771\/9783828876187&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;doi.org\/10.5771\/9783828876187&lt;\/a&gt;'><sup>14<\/sup><\/a><\/span><\/span>. L&rsquo;exp\u00e9rience des deux guerres mondiales peut peut-\u00eatre contribuer \u00e0 expliquer l&rsquo;aversion pour toute application extraterritoriale du droit allemand. Pourtant, l&rsquo;\u00c9tat a \u00e9galement b\u00e9n\u00e9fici\u00e9 de la r\u00e9ussite du groupe Rheinmetall. Les fonds de pension allemands ont investi dans l&rsquo;entreprise, et son savoir-faire technologique a permis au gouvernement de jouer un r\u00f4le de premier plan dans des projets de coop\u00e9ration.<\/p>\n\n\n\n<p>N\u00e9anmoins, le d\u00e9calage entre les principes normatifs et la pratique politique r\u00e9elle est patent&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-15-130452' title='Hendrik Platte et Dirk Leuffen, \u00ab&amp;#160;German Arms Exports&amp;#160;: Between Normative Aspirations and Political Reality&amp;#160;\u00bb, &lt;em&gt;German Politics&lt;\/em&gt;&amp;#160;; 25 (2016), 4. &amp;#8211; S. 561-580 http:\/\/dx.doi.org\/10.1080\/09644008.2016.118465. Url&amp;#160;: &lt;a href=&quot;https:\/\/d-nb.info\/1162059451\/34&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/d-nb.info\/1162059451\/34&lt;\/a&gt;'><sup>15<\/sup><\/a><\/span><\/span>. Depuis 2015, seule une poign\u00e9e d&rsquo;inspections apr\u00e8s exp\u00e9dition ont \u00e9t\u00e9 effectu\u00e9es. Comme elles sont difficiles \u00e0 mener efficacement, elles ne sont pas pertinentes en termes de politique \u00e9trang\u00e8re et de s\u00e9curit\u00e9. En g\u00e9n\u00e9ral, la d\u00e9cision d&rsquo;arr\u00eater les exportations est moins guid\u00e9e par un ensemble de principes coh\u00e9rents de politique \u00e9trang\u00e8re que par des pouss\u00e9es spontan\u00e9es de malaise public. Il convient de noter, par exemple, que l&rsquo;Allemagne n&rsquo;a cess\u00e9 ses exportations vers l&rsquo;Arabie saoudite qu&rsquo;en 2018, apr\u00e8s le meurtre de Jamal Khashoggi. Avant cet \u00e9v\u00e9nement, toutes les indications de bombardements cibl\u00e9s contre des civils au Y\u00e9men, qui avaient incit\u00e9 des \u00c9tats comme les Pays-Bas \u00e0 arr\u00eater les livraisons d\u00e8s 2016, ont \u00e9t\u00e9 ignor\u00e9es. En somme, les gouvernements allemands depuis Strauss ont adopt\u00e9 une approche qui oscille de mani\u00e8re relativement impr\u00e9visible entre la qu\u00eate de r\u00e9demption morale et la poursuite implicite de la politique de puissance&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-16-130452' title='Dominik Wullers, \u00ab&amp;#160;Germany, Wilsonianism, And The Return Of RealPolitik&amp;#160;\u00bb, &lt;em&gt;War On The Rocks&lt;\/em&gt;, 18 mars 2020.'><sup>16<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En somme, les gouvernements allemands depuis Strauss ont adopt\u00e9 une approche qui oscille de mani\u00e8re relativement impr\u00e9visible entre la qu\u00eate de r\u00e9demption morale et la poursuite implicite de la politique de puissance.<\/p><cite>Olivier de France et John Helferich<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"spectres-de-strauss\"><strong>Spectres de Strauss<\/strong><\/h2>\n\n\n\n<p>Sur la sc\u00e8ne europ\u00e9enne, la politique d&rsquo;exportation conflictuelle de l&rsquo;Allemagne entra\u00eene de fr\u00e9quents malentendus avec ses alli\u00e9s les plus proches. L&rsquo;arr\u00eat des exportations vers l&rsquo;Arabie saoudite, par exemple, a creus\u00e9 un foss\u00e9 le long du Rhin et au milieu de l&rsquo;Europe entre la France et l&rsquo;Allemagne, bien que les deux pays soient signataires des m\u00eames trait\u00e9s internationaux. La France, pour sa part, a fait peu d&rsquo;efforts pour condamner l&rsquo;agression saoudienne, mais a interrompu l&rsquo;exportation de technologies pouvant \u00eatre utilis\u00e9es directement au Y\u00e9men. Cependant, dans la mesure o\u00f9 les fabricants fran\u00e7ais d\u00e9pendaient des livraisons de composants en provenance d&rsquo;Allemagne, ils ont souvent \u00e9t\u00e9 incapables de remplir leurs contrats.<\/p>\n\n\n\n<p>En r\u00e9ponse, l&rsquo;ambassadrice de France en Allemagne a d\u00e9clar\u00e9 en 2019 qu&rsquo;il n&rsquo;\u00e9tait plus tenable de faire d\u00e9pendre les grands contrats d&rsquo;exportation de livraisons ayant re\u00e7u un blanc seing allemand&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-17-130452' title='Url du communiqu\u00e9&amp;#160;: &lt;a href=&quot;https:\/\/www.baks.bund.de\/de\/arbeitspapiere\/2019\/vom-german-free-zum-gegenseitigen-vertrauen&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.baks.bund.de\/de\/arbeitspapiere\/2019\/vom-german-free-zum-gegenseitigen-vertrauen&lt;\/a&gt;'><sup>17<\/sup><\/a><\/span><\/span>. L&rsquo;impr\u00e9visibilit\u00e9 qui en r\u00e9sulte a une incidence sur la capacit\u00e9 du couple franco-allemand \u00e0 entreprendre une collaboration majeure en mati\u00e8re d&rsquo;armement sur le long terme, et donc sur la p\u00e9rennit\u00e9 de tels projets&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-18-130452' title='Beth Oppenheim, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/foreignpolicy.com\/2019\/09\/18\/europe-is-at-war-over-arms-exports\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Europe Is at War Over Arms Exports&lt;\/a&gt;\u00ab&amp;#160;, &lt;em&gt;Foreign Policy&lt;\/em&gt;, 18 septembre 2019.'><sup>18<\/sup><\/a><\/span><\/span>. En raison de la place centrale qu&rsquo;occupent Paris et Berlin dans le projet europ\u00e9en, cela a un effet d&rsquo;entra\u00eenement sur l&rsquo;objectif m\u00eame de la construction d&rsquo;une autonomie strat\u00e9gique sur le continent.<\/p>\n\n\n\n<p>Pour faire montre de leur engagement, les deux pays ont r\u00e9cemment renouvel\u00e9 leur partenariat dans le cadre du trait\u00e9 d&rsquo;Aix-la-Chapelle, qui a officiellement r\u00e9align\u00e9 les principes d&rsquo;exportation pour les projets communs. Une r\u00e8gle dite<em> de minimis<\/em> a \u00e9t\u00e9 convenue entre les deux pays, qui stipule que les d\u00e9cisions d&rsquo;exportation ne peuvent \u00eatre interrompues si la part des composants du partenaire est inf\u00e9rieure \u00e0 20&#160;%. L&rsquo;application des r\u00e8gles <em>de minimis<\/em> est toutefois une pratique courante dans les projets de coop\u00e9ration depuis longtemps. En outre, elle ne s&rsquo;appliquera pas aux projets de grande envergure tels que le syst\u00e8me de combat a\u00e9rien du futur (SCAF), dans lequel la part des composants du partenaire sera bien sup\u00e9rieure \u00e0 20&#160;%&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-19-130452' title='Voir \u00e0 ce sujet&amp;#160;: &lt;a href=&quot;https:\/\/www.janes.com\/defence-news\/news-detail\/fcasscaf-partner-nations-agree-ngws-development&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.janes.com\/defence-news\/news-detail\/fcasscaf-partner-nations-agree-ngws-development&lt;\/a&gt;'><sup>19<\/sup><\/a><\/span><\/span>. Il est n\u00e9anmoins significatif que le gouvernement allemand ait finalement \u00e9t\u00e9 pr\u00eat \u00e0 accepter officiellement cette r\u00e8gle. Il \u00e9tait auparavant r\u00e9ticent \u00e0 le faire parce qu&rsquo;il craignait les critiques du public selon lesquelles les projets internationaux \u00e9taient un moyen de contourner le r\u00e9gime national de contr\u00f4le des exportations.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;histoire a l&rsquo;habitude de contrecarrer les meilleures intentions des gouvernements, lorsqu&rsquo;ils oublient que les maux d&rsquo;aujourd&rsquo;hui sont \u00e9galement le fruit des spectres des hivers pass\u00e9s<\/p><cite>Olivier de France et John Helferich<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Au lendemain des \u00e9lections au Bundestag, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/25\/doctrine-de-la-nouvelle-ere-allemande\/\">le nouveau trait\u00e9 de coalition<\/a> propose \u00ab&#160;la poursuite du d\u00e9veloppement d&rsquo;un \u00c9tat europ\u00e9en f\u00e9d\u00e9ral&#160;\u00bb&#160;: cela inclut davantage de votes \u00e0 la majorit\u00e9 qualifi\u00e9e au Conseil europ\u00e9en, un ministre de la d\u00e9fense de l&rsquo;Union et des listes transnationales pour les \u00e9lections au Parlement europ\u00e9en. Parall\u00e8lement, il recommande \u00e9galement des r\u00e9glementations europ\u00e9ennes plus contraignantes en mati\u00e8re d&rsquo;exportation d&rsquo;armes, en plus d&rsquo;une \u00ab&#160;loi nationale sur le contr\u00f4le des exportations d&rsquo;armes&#160;\u00bb qui, ensemble, devraient cr\u00e9er un r\u00e9gime plus transparent. Malgr\u00e9 l&rsquo;importance de ces r\u00e9formes politiques attendues depuis longtemps&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-130452' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#easy-footnote-bottom-20-130452' title='Sophia Besch, Beth Oppenheim, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.cer.eu\/sites\/default\/files\/pbrief_arms_export_9.9.19.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Up In Arms&amp;#160;: Warring Over Europe&amp;rsquo;s Arms Export Regime&lt;\/a&gt;\u00ab&amp;#160;, Policy Brief, &lt;em&gt;CER&lt;\/em&gt;, 10 sept. 2019.'><sup>20<\/sup><\/a><\/span><\/span>, il y a peu d&rsquo;espoir qu&rsquo;un minist\u00e8re de la d\u00e9fense dirig\u00e9 par les sociaux-d\u00e9mocrates suscite un d\u00e9bat plus authentique. Les questions li\u00e9es \u00e0 la coop\u00e9ration en mati\u00e8re de d\u00e9fense en Europe sont une fois de plus d\u00e9guis\u00e9es en probl\u00e8mes r\u00e9glementaires, alors qu&rsquo;elles sont de nature politique et historique.<\/p>\n\n\n\n<p>Dans ce domaine, les d\u00e9bats internes en France et en Allemagne demeurent moins perm\u00e9ables aux pressions ext\u00e9rieures que leurs partenaires aiment \u00e0 le croire. Toutefois, si Paris et Berlin veulent aborder la nouvelle concurrence strat\u00e9gique mondiale dans une perspective r\u00e9solument europ\u00e9enne, Olaf Scholz et son homologue fran\u00e7ais doivent ranimer les spectres qui se cachent encore dans le placard commun franco-allemand. Sinon, ils risquent simplement de perp\u00e9tuer la longue histoire des plan\u00e8tes mal align\u00e9es qui a contrari\u00e9 les efforts d&rsquo;Emmanuel Macron et d&rsquo;Angela Merkel. Une histoire qui a retenu la le\u00e7on de l&rsquo;\u00e9chec de la Communaut\u00e9 europ\u00e9enne de d\u00e9fense, invariable \u00e9pouvantail brandi pour expliquer les probl\u00e8mes structurels qui entravent la coop\u00e9ration europ\u00e9enne en mati\u00e8re de s\u00e9curit\u00e9. L&rsquo;h\u00e9ritage de Franz Josef Strauss a \u00e9t\u00e9 trait\u00e9 avec plus de bienveillance. Pourtant, ces deux \u00e9pisodes jettent une ombre sur les efforts de coop\u00e9ration actuels en Europe, que la nature centr\u00e9e sur le d\u00e9bat actuel n&rsquo;a gu\u00e8re contribu\u00e9 \u00e0 lever. Il ne s&rsquo;agit pas d&rsquo;une pr\u00e9occupation purement acad\u00e9mique&#160;: l&rsquo;histoire a l&rsquo;habitude de contrecarrer les meilleures intentions des gouvernements, lorsqu&rsquo;ils oublient que les maux d&rsquo;aujourd&rsquo;hui sont \u00e9galement le fruit des spectres des hivers pass\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En France et en Allemagne, l&rsquo;\u00e9chec de la CED et le \u00ab&#160;&#160;choix de Strauss&#160;&#160;\u00bb ont structur\u00e9 les politiques de d\u00e9fense europ\u00e9ennes. En 2022, la menace russe aux fronti\u00e8res de l&rsquo;Ukraine oblige les Europ\u00e9ens \u00e0 un r\u00e9veil, et pourrait les pousser \u00e0 ranimer les spectres des hivers pass\u00e9s.<\/p>\n","protected":false},"author":10,"featured_media":130453,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":14,"footnotes":""},"categories":[1732],"tags":[],"staff":[3079,3078],"editorial_format":[4944],"serie":[],"audience":[],"geo":[1917],"class_list":["post-130452","post","type-post","status-publish","format-standard","hentry","category-guerre","staff-john-helferich","staff-olivier-de-france","editorial_format-actu-longues","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":130453,"excerpt":"En France et en Allemagne, l'\u00e9chec de la CED et le \u00ab choix de Strauss \u00bb ont structur\u00e9 les politiques de d\u00e9fense europ\u00e9ennes. En 2022, la menace russe aux fronti\u00e8res de l'Ukraine oblige les Europ\u00e9ens \u00e0 un r\u00e9veil, et pourrait les pousser \u00e0 ranimer les spectres des hivers pass\u00e9s.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les spectres de la d\u00e9fense europ\u00e9enne se raniment | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les spectres de la d\u00e9fense europ\u00e9enne se raniment | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"En France et en Allemagne, l&#039;\u00e9chec de la CED et le \u00ab&#160;choix de Strauss&#160;\u00bb ont structur\u00e9 les politiques de d\u00e9fense europ\u00e9ennes. En 2022, la menace russe aux fronti\u00e8res de l&#039;Ukraine oblige les Europ\u00e9ens \u00e0 un r\u00e9veil, et pourrait les pousser \u00e0 ranimer les spectres des hivers pass\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-04T16:20:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-07T14:49:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/gc-oliv-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/gc-oliv-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/\",\"name\":\"Les spectres de la d\u00e9fense europ\u00e9enne se raniment | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg\",\"datePublished\":\"2022-02-04T16:20:30+00:00\",\"dateModified\":\"2022-02-07T14:49:38+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"A Ukrainian serviceman walks in a trench at a frontline position in the Donetsk region, eastern Ukraine, Monday, Jan. 31, 2022. The United States and Russia are squaring off at the U.N. Security Council over Ukraine, with Washington calling Moscow's actions a threat to international peace and security, while a Kremlin envoy ridiculed Monday's meeting as a \\\"PR stunt.\\\"(AP Photo\/Vadim Ghirda)\/XVG101\/22031520680080\/\/2202010205\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les spectres de la d\u00e9fense europ\u00e9enne se raniment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les spectres de la d\u00e9fense europ\u00e9enne se raniment | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/","og_locale":"fr_FR","og_type":"article","og_title":"Les spectres de la d\u00e9fense europ\u00e9enne se raniment | Le Grand Continent","og_description":"En France et en Allemagne, l'\u00e9chec de la CED et le \u00ab&#160;choix de Strauss&#160;\u00bb ont structur\u00e9 les politiques de d\u00e9fense europ\u00e9ennes. En 2022, la menace russe aux fronti\u00e8res de l'Ukraine oblige les Europ\u00e9ens \u00e0 un r\u00e9veil, et pourrait les pousser \u00e0 ranimer les spectres des hivers pass\u00e9s.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/","og_site_name":"Le Grand Continent","article_published_time":"2022-02-04T16:20:30+00:00","article_modified_time":"2022-02-07T14:49:38+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/gc-oliv-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/gc-oliv-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/","url":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/","name":"Les spectres de la d\u00e9fense europ\u00e9enne se raniment | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg","datePublished":"2022-02-04T16:20:30+00:00","dateModified":"2022-02-07T14:49:38+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg","width":2560,"height":1707,"caption":"A Ukrainian serviceman walks in a trench at a frontline position in the Donetsk region, eastern Ukraine, Monday, Jan. 31, 2022. The United States and Russia are squaring off at the U.N. Security Council over Ukraine, with Washington calling Moscow's actions a threat to international peace and security, while a Kremlin envoy ridiculed Monday's meeting as a \"PR stunt.\"(AP Photo\/Vadim Ghirda)\/XVG101\/22031520680080\/\/2202010205"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2022\/02\/04\/les-spectres-de-la-defense-europeenne-se-raniment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Les spectres de la d\u00e9fense europ\u00e9enne se raniment"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1732,"name":"Guerre","slug":"guerre"}],"lgc_author":{"id":3079,"name":"John Helferich","slug":"john-helferich","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/02\/SIPA_AP22647339_000001-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/130452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=130452"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/130452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/130453"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=130452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=130452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=130452"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=130452"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=130452"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=130452"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=130452"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=130452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}