{"id":127020,"date":"2021-12-16T22:20:00","date_gmt":"2021-12-16T21:20:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=127020"},"modified":"2021-12-23T12:34:47","modified_gmt":"2021-12-23T11:34:47","slug":"premier-ministre","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/","title":{"rendered":"Premier ministre"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"introduction\"><strong>Introduction<\/strong><\/h2>\n\n\n\n<p>Dans un des tout premiers commentaires sur la Ve R\u00e9publique, le politologue Maurice Duverger soulevait un probl\u00e8me qui fait \u00e9trangement \u00e9cho soixante ans plus tard&#160;:<\/p>\n\n\n\n<p>\u00ab&#160;Le Premier ministre existe-t-il&#160;? Ce n\u2019est pas s\u00fbr. [&#8230;] Le Premier ministre devrait \u00eatre d\u2019abord l\u2019organisateur des \u201cpublics relations\u201d entre l\u2019ex\u00e9cutif et le Parlement. Exposer aux chambres la politique du gouvernement, d\u00e9fendre devant elle ses projets, r\u00e9pondre aux questions de politique g\u00e9n\u00e9rale&#160;; d\u00e9sarmer ses adversaires, rallier et convaincre les h\u00e9sitants, galvaniser les partisans&#160;; tenir sur les points essentiels, c\u00e9der \u00e0 l\u2019occasion sur les points secondaires et d\u00e9finir les compromis n\u00e9cessaires [&#8230;]. Le Premier ministre devrait \u00eatre, d\u2019autre part, le leader de la majorit\u00e9 parlementaire, son chef reconnu, respect\u00e9, ob\u00e9i. Il ne l\u2019est point. [&#8230;] Il n\u2019est point non plus un chef de gouvernement, respect\u00e9 de tous les ministres, il n\u2019a d\u2019autorit\u00e9 que sur tr\u00e8s peu d\u2019entre eux [&#8230;]. La plupart, pour toutes les questions importantes, cherchent \u00e0 \u00e9tablir un contact direct avec le Pr\u00e9sident de la R\u00e9publique. Ils pr\u00e9f\u00e8rent s\u2019adresser \u00e0 Dieu plut\u00f4t qu\u2019\u00e0 St Pierre [&#8230;]. On n\u2019h\u00e9site, cependant, \u00e0 accabler M. Michel Debr\u00e9. Il n\u2019est pas l\u2019homme de son r\u00f4le, certes. Mais le r\u00f4le est-il tenable&#160;? Un autre jouerait-il mieux&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-1-127020' title='Maurice Duverger, \u00ab&amp;#160;Monsieur Debr\u00e9 existe-t-il&amp;#160;?&amp;#160;\u00bb, La NEF, juillet-ao\u00fbt 1959.'><sup>1<\/sup><\/a><\/span><\/span>&#160;?&#160;\u00bb<\/p>\n\n\n\n<p>L\u2019histoire a depuis tranch\u00e9&#160;: de Pierre Messmer, dont \u00ab&#160;l\u2019insignifiance [aurait] d\u00e9pouill\u00e9 de ses derniers restes d\u2019existence politique le poste de Premier ministre&#160;\u00bb selon L\u2019Express (14 ao\u00fbt 1972), \u00e0 Jean Castex dont les interventions publiques sont la ris\u00e9e de tous les r\u00e9seaux sociaux, peu d\u2019acteurs politiques ont endoss\u00e9 ce r\u00f4le politique avec succ\u00e8s. Et ceux qui semblaient y parvenir, comme derni\u00e8rement \u00c9douard Philippe, ont vite \u00e9t\u00e9 remerci\u00e9s par le Pr\u00e9sident de la R\u00e9publique. La crise g\u00e9n\u00e9r\u00e9e par la pand\u00e9mie du COVID\u201019 en 2020 ne fait \u00e0 cet \u00e9gard que mettre en lumi\u00e8re un probl\u00e8me aussi ancien que central dans la vie politique fran\u00e7aise, celui de la dyarchie du pouvoir ex\u00e9cutif.<\/p>\n\n\n\n<p>Beaucoup l\u2019ignorent en effet mais la Constitution fran\u00e7aise n\u2019\u00e9tablit pas de hi\u00e9rarchie claire entre le Pr\u00e9sident et le Premier ministre. Si elle confie au Pr\u00e9sident un certain nombre de pouvoirs, c\u2019est avant tout pour arbitrer et non pour gouverner. Il n\u2019y a que dans les r\u00e9gimes pr\u00e9sidentiels, tr\u00e8s minoritaires, que les Pr\u00e9sidents gouvernent. Ces derniers n\u2019ont alors pas de Premier ministre. Dans les autres r\u00e9gimes d\u00e9mocratiques, c\u2019est le Parlement ou plus souvent le chef du gouvernement \u2013 \u00ab&#160;Premier ministre&#160;\u00bb en Grande Bretagne, \u00ab&#160;Chancelier&#160;\u00bb en Allemagne, \u00ab&#160;Pr\u00e9sident du Conseil&#160;\u00bb en Italie, etc. \u2013 qui dirige la politique de la nation. Conform\u00e9ment \u00e0 cette tradition, l\u2019article 21 de la Constitution de 1958 confie au Premier ministre le soin de diriger le gouvernement. Situ\u00e9 au sommet de l\u2019\u00c9tat, au point d\u2019intersection de tous les espaces sociaux, il doit ainsi \u00ab&#160;faire fonctionner le gouvernement, les relations avec le Parlement, les administrations, recevoir les syndicats, les repr\u00e9sentants des collectivit\u00e9s locales, les personnalit\u00e9s de l\u2019outre-mer, les dirigeants \u00e9trangers&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-2-127020' title='Raymond Barre, dans Rapha\u00eblle Bacqu\u00e9, L\u2019Enfer de Matignon, Paris, Albin Michel, 2008, p. 195.'><sup>2<\/sup><\/a><\/span><\/span>&#160;\u00bb. Cependant, en vertu d\u2019une r\u00e8gle coutumi\u00e8re \u00e9tablie tr\u00e8s t\u00f4t pour r\u00e9gler le probl\u00e8me de la dyarchie, le Premier ministre doit en m\u00eame temps s\u2019effacer devant le Pr\u00e9sident. La singularit\u00e9 du Premier ministre fran\u00e7ais est l\u00e0, dans cette contradiction majeure entre ses fonctions constitutionnelles et le r\u00f4le qu\u2019il doit performer pour rendre sensible \u00e0 tous sa position subordonn\u00e9e vis-\u00e0-vis du Pr\u00e9sident&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-3-127020' title='Sur la notion de r\u00f4le en science politique, voir Jacques Lagroye, \u00ab&amp;#160;On ne subit pas son r\u00f4le&amp;#160;\u00bb, Politix, no 38, 1997, p. 7\u201017&amp;#160;; et Christian Le Bart, Les Maires. Sociologie d\u2019un r\u00f4le, Lille, Presses Universitaires du Septentrion, 2003. Ce d\u00e9calage entre la position centrale qu\u2019occupe objectivement le Premier ministre dans le champ du pouvoir et le r\u00f4le subordonn\u00e9 qu\u2019il doit performer pour donner \u00e0 voir la pr\u00e9\u00e9minence pr\u00e9sidentielle en fait \u00e0 cet \u00e9gard une \u00e9tude de cas tr\u00e8s pertinente pour \u00e9clairer la notion de r\u00f4le telle qu\u2019elle a \u00e9t\u00e9 retravaill\u00e9e par Jacques Lagroye, l\u2019un des fondateurs de la sociologie des institutions en France.'><sup>3<\/sup><\/a><\/span><\/span>. Vu sous cet angle, le Premier ministre n\u2019appara\u00eet d\u00e8s lors pas si insignifiant que cela, bien au contraire, il s\u2019analyse, pour reprendre les mots d\u2019Olivier Duhamel, comme la v\u00e9ritable \u00ab&#160;cl\u00e9 de vo\u00fbte&#160;\u00bb du r\u00e9gime.&nbsp;<\/p>\n\n\n\n<p>R\u00f4le pivot dont d\u00e9pend pour partie la pr\u00e9\u00e9minence du Pr\u00e9sident, le Premier ministre est en effet particuli\u00e8rement heuristique pour \u00e9clairer le fonctionnement de la Ve R\u00e9publique. Pour la science politique, l\u2019enjeu n\u2019est pas nul. Car si elle a su d\u00e9velopper une approche originale des institutions politiques, elle ne les appr\u00e9hende le plus souvent que de mani\u00e8re isol\u00e9e&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-4-127020' title='&amp;nbsp;Sur cette approche, voir&amp;#160;: Jacques Lagroye, Michel Offerl\u00e9 (dir.), Sociologie de l\u2019institution, Paris, Belin, 2011&amp;#160;; et Delphine Dulong, Sociologie des institutions politiques, Paris, La D\u00e9couverte, 2012'><sup>4<\/sup><\/a><\/span><\/span>. La connaissance qui en r\u00e9sulte sur le r\u00e9gime politique est par cons\u00e9quent segment\u00e9e et n\u00e9glige par trop les relations interinstitutionnelles. Or, comme on le verra, c\u2019est par et dans ses relations avec les autres institutions politiques que se construit le Premier ministre.<\/p>\n\n\n\n<p>Il ne s\u2019agit toutefois pas seulement de revenir \u00e0 nouveau frais sur la pr\u00e9sidentialisation du r\u00e9gime en se pla\u00e7ant du c\u00f4t\u00e9 des \u00ab&#160;perdants&#160;\u00bb. Le Premier ministre est aussi int\u00e9ressant \u00e0 \u00e9tudier en raison de la faible codification juridique du poste. La Constitution, en effet, ne lui consacre que deux articles contre quinze pour le Pr\u00e9sident. Elle pr\u00e9voit en outre un partage flou des t\u00e2ches entre Matignon et l\u2019\u00c9lys\u00e9e qui a trois cons\u00e9quences importantes&#160;: la division du travail au sein du pouvoir ex\u00e9cutif, partant les d\u00e9finitions des r\u00f4les respectifs du Premier ministre et du Pr\u00e9sident, sont largement interd\u00e9pendantes&#160;; cette d\u00e9limitation repose moins sur le droit que sur la pratique des acteurs&#160;; elle est donc potentiellement variable d\u2019une configuration politique \u00e0 une autre. En d\u2019autres termes, ceux de Maurice Duverger, \u00ab&#160;si le Pr\u00e9sident de la R\u00e9publique gouverne, le Premier ministre est r\u00e9duit \u00e0 l\u2019impuissance&#160;; si le Premier ministre gouverne, le Pr\u00e9sident de la R\u00e9publique s\u2019efface&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-5-127020' title='Maurice Duverger, \u00ab&amp;#160;Monsieur Debr\u00e9 existe-t-il&amp;#160;?&amp;#160;\u00bb, art. cit\u00e9.'><sup>5<\/sup><\/a><\/span><\/span>&#160;\u00bb.<\/p>\n\n\n\n<p>Au flou qui entoure la d\u00e9finition de l\u2019institution et la condamne \u00e0 l\u2019impressionnisme \u2013 d\u2019ailleurs revendiqu\u00e9 par un Premier ministre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-6-127020' title='&amp;nbsp;\u00ab&amp;#160;\u00c0 Matignon on peint impressionniste, \u00e0 l\u2019\u00c9lys\u00e9e, on a besoin de ligne claire&amp;#160;\u00bb (\u00c9douard Philippe, Gilles Boyer, Impression et lignes claires, Paris, JC Latt\u00e8s, 2021, p. 363).'><sup>6<\/sup><\/a><\/span><\/span> \u2013 s\u2019ajoute la faible objectivation juridique du travail gouvernemental. Le Premier ministre peut certes s\u2019appuyer sur un stock de connaissances stabilis\u00e9es pour coordonner l\u2019action du gouvernement. Il peut compter sur le Secr\u00e9tariat g\u00e9n\u00e9ral du gouvernement qui est en quelque sorte la m\u00e9moire du gouvernement&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-7-127020' title='Celui-ci suppl\u00e9e en tout cas \u00e0 la doctrine juridique. Ainsi, \u00e0 d\u00e9faut de r\u00e8glement int\u00e9rieur, le Secr\u00e9tariat g\u00e9n\u00e9ral du gouvernement a \u00e9labor\u00e9 en 1985 un \u00ab&amp;#160;dossier du travail du gouvernement&amp;#160;\u00bb qui comporte une s\u00e9rie de fiches sur son fonctionnement concret. Mais ce document, qui n\u2019a jamais \u00e9t\u00e9 valid\u00e9 en Conseil des ministres, n\u2019est pas r\u00e9guli\u00e8rement mis \u00e0 jour. Sur cette institution, voir&amp;#160;: Jean-Michel Eymeri-Douzans, Michel Mangenot, \u00ab&amp;#160;Rouage ou centre de l\u2019\u00c9tat&amp;#160;? Gen\u00e8se et institutionnalisation du SGG&amp;#160;\u00bb, Revue fran\u00e7aise d\u2019administration publique, no 171, 2019, p. 603\u2010627'><sup>7<\/sup><\/a><\/span><\/span>&#160;; il peut s\u2019appuyer sur les r\u00e8gles du protocole ou certaines routines institutionnelles qui se sont mises en place avec le temps \u2013 le Conseil des ministres le mercredi, la division du travail entre chef de cabinet et directeur de cabinet, etc. Mais l\u2019organisation du travail gouvernemental n\u2019est pas plus fig\u00e9e dans le marbre du droit que le r\u00f4le de Premier ministre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-8-127020' title='Par exemple, entre 1961 et 1986, le nombre de comit\u00e9s interminist\u00e9riels permanents n\u2019a pas cess\u00e9 de changer d\u2019une ann\u00e9e sur l\u2019autre \u00e0 quatre exceptions pr\u00e8s. Sur cette faible routinisation du travail gouvernemental, voir Jacques Fournier, Le Travail gouvernemental, Paris, Presses de la FNSP, 1987.'><sup>8<\/sup><\/a><\/span><\/span>. Il n\u2019y a pas de r\u00e8glement int\u00e9rieur des travaux du gouvernement comme celui qui avait \u00e9t\u00e9 adopt\u00e9 en 1947. Le nombre de minist\u00e8res n\u2019est pas pr\u00e9d\u00e9termin\u00e9 puisque la d\u00e9cision rel\u00e8ve du pouvoir r\u00e9glementaire, tout comme les attributions des minist\u00e8res&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-9-127020' title='Marc-Antoine Granger, \u00ab&amp;#160;Les d\u00e9crets portant attributions des membres du Gouvernement&amp;#160;\u00bb, Revue fran\u00e7aise de droit constitutionnel, no 94, 2013, p. 335\u2010355.'><sup>9<\/sup><\/a><\/span><\/span> \u2013 lesquelles sont d\u2019autant plus floues et impr\u00e9cises qu\u2019elles sont de potentielles sources de conflits&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-10-127020' title='Dans son rapport de 1985 \u00ab&amp;#160;Structures gouvernementales et organisation administrative&amp;#160;\u00bb, le Conseil d\u2019\u00c9tat critique en effet le flou et l\u2019impr\u00e9cision des formules souvent utilis\u00e9es dans les d\u00e9crets d\u2019attribution et de d\u00e9l\u00e9gation des minist\u00e8res, ainsi que la pratique courante du renvoi \u00e0 des textes ant\u00e9rieurs qui oblige \u00e0 remonter parfois fort loin dans la cha\u00eene des d\u00e9crets pour trouver celui qui d\u00e9finit concr\u00e8tement les comp\u00e9tences du ministre.'><sup>10<\/sup><\/a><\/span><\/span>. Et si la composition des cabinets minist\u00e9riels est davantage encadr\u00e9e par le droit&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-11-127020' title='Fr\u00e9d\u00e9ric Edel, \u00ab&amp;#160;Les r\u00e9formes de l\u2019encadrement juridique des cabinets minist\u00e9riels en France&amp;#160;: quelle am\u00e9lioration de la transparence et de la probit\u00e9&amp;#160;?&amp;#160;\u00bb, \u00c9thique publique, vol. 20, no 1, 2018.'><sup>11<\/sup><\/a><\/span><\/span>, celle du cabinet du Premier ministre lui \u00e9chappe. Par cons\u00e9quent, l\u2019organisation du travail gouvernemental repose sur la personne m\u00eame du chef de gouvernement qui en d\u00e9cide librement dans les limites que lui imposent le Pr\u00e9sident et les contraintes partisanes.<\/p>\n\n\n\n<p>On comprend dans ces conditions qu\u2019on ait pu penser que \u00ab&#160;le sujet se pr\u00eate mal aux d\u00e9veloppements th\u00e9oriques&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-12-127020' title='Jacques Fournier, Le Travail gouvernemental, op. cit., p. 13.'><sup>12<\/sup><\/a><\/span><\/span>&#160;\u00bb. Ce d\u00e9faut d\u2019objectivation juridique explique certes le peu d\u2019\u00e9tudes consacr\u00e9es \u00e0 cette institution en droit&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-13-127020' title='Sauf exception (voir Alain Claisse, Le Premier ministre de la Ve R\u00e9publique, Paris, LGDJ, 1972), les travaux juridiques existants d\u00e9crivent de mani\u00e8re formelle les services, proc\u00e9dures et outils de l\u2019action gouvernementale&amp;#160;; ils n\u2019\u00e9clairent pas le r\u00f4le politique du Premier ministre.'><sup>13<\/sup><\/a><\/span><\/span>. En revanche, il n\u2019explique pas l\u2019indiff\u00e9rence des sciences humaines et sociales&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-14-127020' title='Il faut mettre \u00e0 part les historiens qui ont largement aliment\u00e9 la connaissance sur le sujet \u2013 et la mienne en particulier \u2013 mais sous la forme de monographies qui, si elles sont passionnantes, ne cherchent pas \u00e0 comprendre comment s\u2019est construit le r\u00f4le. Voir la bibliographie en fin d\u2019ouvrage.'><sup>14<\/sup><\/a><\/span><\/span>. Car si on sait pourquoi la subordination du Premier ministre au Pr\u00e9sident est devenue une prescription majeure de ce r\u00f4le politique, on ne sait pas comment. Or la question se pose d\u2019autant plus que la conformation \u00e0 cette prescription de r\u00f4le place les Premiers ministres en situation de double bind et du m\u00eame coup dans une grande ins\u00e9curit\u00e9&#160;: leur autorit\u00e9 sur le gouvernement et la majorit\u00e9 ne peut s\u2019affirmer que dans les limites du respect de la pr\u00e9\u00e9minence pr\u00e9sidentielle.&nbsp;<\/p>\n\n\n\n<p>Ces injonctions contradictoires soul\u00e8vent par ailleurs d\u2019autres questions. Comment fait-on pour performer ce type de r\u00f4le&#160;? Quelles dispositions faut-il pour tenir ensemble ces attentes contradictoires&#160;? La r\u00e9ponse \u00e0 ces questions n\u2019a rien d\u2019\u00e9vident au regard du groupe h\u00e9t\u00e9roclite que composent ceux qui ont successivement endoss\u00e9 le r\u00f4le de Premier ministre. Certains sont issus d\u2019une famille bourgeoise, d\u2019autres de milieux modestes. Certains sont de droite, d\u2019autres de gauche, et d\u2019autres encore sont sans attaches partisanes. Ils n\u2019ont pas tous le m\u00eame type d\u2019exp\u00e9rience professionnelle&#160;: les uns sont hauts fonctionnaires, les autres des professionnels de la politique. Surtout, ils ne sont pas toujours de \u00ab&#160;fid\u00e8les&#160;\u00bb compagnons de route du Pr\u00e9sident.<\/p>\n\n\n\n<p>Malgr\u00e9 toutes ces diff\u00e9rences, la mani\u00e8re dont ils rendent sensible aux autres leur position converge sur des points essentiels. Except\u00e9 les p\u00e9riodes de cohabitation, tous affichent leur subordination au Pr\u00e9sident, m\u00eame quand ils sont fortement dot\u00e9s en capitaux (comme Michel Rocard). Avec bien s\u00fbr plus ou moins de succ\u00e8s, ils s\u2019efforcent d\u2019assurer l\u2019unit\u00e9 du gouvernement, m\u00eame quand il s\u2019agit d\u2019un gouvernement de coalition (comme pour Lionel Jospin). Ils m\u00e8nent la bataille contre l\u2019opposition au Parlement et les campagnes \u00e9lectorales, m\u00eame lorsqu\u2019ils n\u2019ont aucune exp\u00e9rience du militantisme politique (Georges Pompidou, Raymond Barre, Dominique de Villepin). Enfin, ils font tous sauf exception un usage limit\u00e9 des armes juridiques qu\u2019ils poss\u00e8dent pour discipliner les parlementaires. Il y a donc bien eu \u00ab&#160;un processus de structuration relativement durable d\u2019un collectif autour de comportements routiniers et de conceptions partag\u00e9es&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-15-127020' title='&amp;nbsp;Julien Fretel, Militants catholiques en politique. La nouvelle UDF, th\u00e8se de doctorat, Universit\u00e9 Paris 1, 2004.'><sup>15<\/sup><\/a><\/span><\/span>&#160;\u00bb. Comment l\u2019expliquer&#160;? Comment se fait-il qu\u2019un r\u00f4le aussi peu codifi\u00e9 et coh\u00e9rent ait pu s\u2019institutionnaliser au point de s\u2019imposer \u00e0 des acteurs aux dispositions variables et parfois mal ajust\u00e9es&#160;?<\/p>\n\n\n\n<p>Plusieurs postulats et partis pris \u00e9pist\u00e9mologiques ont guid\u00e9 la recherche qui a pr\u00e9sid\u00e9 aux r\u00e9ponses que l\u2019on apporte \u00e0 ces diff\u00e9rentes questions dans les pages qui suivent. Le premier d\u00e9coule des constats pr\u00e9c\u00e9dents. Si le droit fait d\u00e9faut, cela signifie que le r\u00f4le s\u2019est construit avant tout en actes, plus pr\u00e9cis\u00e9ment dans la relation du Premier ministre avec les autres acteurs de la vie la politique dont il est la cheville ouvri\u00e8re. C\u2019est ce que d\u00e9montrent les quatre parties qui composent ce livre. La premi\u00e8re \u00e9claire le dispositif (pour reprendre la notion de Michel Foucault) que les Pr\u00e9sidents ont mis en place pour discipliner leurs Premiers ministres. La deuxi\u00e8me d\u00e9place la focale vers le gouvernement et montre comment le Premier ministre est devenu, selon les mots de Matthieu Caron, un primus inter pares \u00e0 d\u00e9faut de pouvoir en revendiquer le leadership politique. Dans la troisi\u00e8me partie, c\u2019est le travail de mobilisation de la majorit\u00e9 qui est mis au jour ainsi que sa principale cons\u00e9quence, la politisation du r\u00f4le. Enfin, la derni\u00e8re partie a pour principal objectif d\u2019interroger ce que le r\u00f4le fait aux acteurs, et traite simultan\u00e9ment du contr\u00f4le social qu\u2019exercent les journalistes sur la conduite des Premiers ministres.<\/p>\n\n\n\n<p>Cette approche relationnelle n\u2019est pas sans danger. Dans un monde aussi agonistique qu\u2019est le champ politique, elle conduit \u00e0 hypertrophier les enjeux de pouvoir au d\u00e9triment des conditions les plus prosa\u00efques du travail gouvernemental&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-16-127020' title='Didier Demazi\u00e8re, Patrick Le Lidec, \u00ab&amp;#160;Analyser le travail politique&amp;#160;\u00bb, introduction \u00e0 Les Mondes du travail politique. Les \u00e9lus et leurs entourages, Rennes, PUR, 2014, p. 11\u201034.'><sup>16<\/sup><\/a><\/span><\/span> et des repr\u00e9sentations subjectives des acteurs. Ce faisant, elle expose au travers commun des r\u00e9cits journalistiques et autobiographiques, celui de l\u2019illusion h\u00e9ro\u00efque de l\u2019acteur rationnel d\u00e9cidant seul. Bien s\u00fbr, ici plus qu\u2019ailleurs les acteurs anticipent, calculent et d\u00e9ploient des strat\u00e9gies. Mais ils ne le font pas dans un univers vide de contraintes et n\u2019en ma\u00eetrisent jamais enti\u00e8rement les cons\u00e9quences.<\/p>\n\n\n\n<p>C\u2019est l\u00e0 un autre postulat sur lequel repose l\u2019analyse qui suit. Elle porte une attention soutenue aux ressources et contraintes qui p\u00e8sent sur la conduite des Premiers ministres, \u00e0 l\u2019instar des entourages qui influent \u00e0 la fois sur la perception que les Premiers ministres ont des probl\u00e8mes ainsi que sur la d\u00e9finition des solutions. L\u2019analyse part aussi du principe que les jeux de pouvoir dans lesquels ils sont pris n\u2019interdisent pas d\u2019interroger les valeurs au nom desquelles ils se battent. Car quoi qu\u2019on en dise, un Premier ministre socialiste n\u2019est pas interchangeable avec un Premier ministre de droite&#160;: ils peuvent parfois partager des priorit\u00e9s en mati\u00e8re d\u2019action publique, ils n\u2019ont cependant pas exactement la m\u00eame conception de l\u2019ordre gouvernemental ni le m\u00eame rapport \u00e0 leur majorit\u00e9 parlementaire. Ce parti pris en entra\u00eene un autre&#160;: la socialisation des acteurs est ici envisag\u00e9e comme un \u00e9l\u00e9ment cl\u00e9 du rapport au poste, ce qui n\u2019emp\u00eache pas ce rapport d\u2019\u00e9voluer par un effet de socialisation propre \u00e0 l\u2019institution gouvernementale qu\u2019on aura l\u2019occasion de montrer.<\/p>\n\n\n\n<p>Prendre au s\u00e9rieux toutes ces variables dans l\u2019analyse ne signifie pas pour autant que l\u2019on verse dans une sociologie d\u00e9terministe. La sociologie qui inspire ce livre s\u2019efforce au contraire de tenir \u00e0 \u00e9gale distance l\u2019id\u00e9e que les acteurs sont de purs strat\u00e8ges et son antith\u00e8se, l\u2019id\u00e9e qu\u2019ils sont agis. Conform\u00e9ment au postulat qui fonde la sociologie des institutions en France, selon lequel la relation entre \u00ab&#160;l\u2019acteur et le syst\u00e8me&#160;\u00bb est de type dialectique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-17-127020' title='Cf. Peter Berger, Thomas Luckmann, La Construction sociale de la r\u00e9alit\u00e9, Paris, M\u00e9ridiens Klincksieck, 1986&amp;#160;; Jacques Lagroye, Michel Offerl\u00e9 (dir.), Sociologie de l\u2019institution, op. cit.&amp;#160;; Delphine Dulong, Sociologie des institutions politiques, op. cit.'><sup>17<\/sup><\/a><\/span><\/span>, elle s\u2019efforce de comprendre \u00e0 quelles conditions le r\u00f4le s\u2019impose aux acteurs mais aussi dans quelle mesure chacun d\u2019eux prend part \u00e0 sa construction et \u00e0 son institutionnalisation.<\/p>\n\n\n\n<p>La sociologie qui inspire ce livre est en outre attentive \u00e0 la temporalit\u00e9 des processus \u00e9tudi\u00e9s. Si le temps long est son horizon, elle ne n\u00e9glige pas les diff\u00e9rentes configurations politiques dans lesquelles les Premiers ministres s\u2019inscrivent, ne serait-ce que parce que ces configurations informent en grande partie leurs pr\u00e9f\u00e9rences. Le fait de disposer ou non, en tant que Premier ministre, d\u2019une majorit\u00e9 confortable, solide et coh\u00e9rente \u00e0 l\u2019Assembl\u00e9e nationale n\u2019est pas anodin&#160;: cela conditionne sa marge de libert\u00e9. Par ailleurs, dans un champ pour partie r\u00e9gi par les \u00e9lections, le calendrier \u00e9lectoral p\u00e8se tr\u00e8s fortement sur les anticipations des acteurs et donc sur leur d\u00e9cision, leur conduite et bien s\u00fbr sur le destin des Premiers ministres. Enfin, s\u2019il faut \u00eatre attentif aux questions de temporalit\u00e9 ici c\u2019est que le stock de connaissances sur le r\u00f4le et, de mani\u00e8re plus g\u00e9n\u00e9rale, sur les r\u00e8gles tacites du r\u00e9gime politique ne sont pas les m\u00eames en 1959 et en 2021. Autrement dit, ce n\u2019est pas la m\u00eame chose d\u2019endosser le r\u00f4le aujourd\u2019hui et dans les ann\u00e9es 1970. Non seulement le r\u00f4le du Premier ministre et celui du Pr\u00e9sident ont \u00e9volu\u00e9 mais l\u2019espace du possible et du pensable n\u2019est pas identique&#160;: des \u00ab&#160;pr\u00e9c\u00e9dents&#160;\u00bb ont \u00e9t\u00e9 peu \u00e0 peu \u00e9tablis comme autant d\u2019\u0153ill\u00e8res qui orientent le sens pratique des acteurs.&nbsp;<\/p>\n\n\n\n<p>Un dernier choix reste \u00e0 pr\u00e9ciser. Tout au long de la recherche s\u2019est pos\u00e9e la question des modalit\u00e9s de sa restitution. Pour des raisons qui tiennent aussi bien \u00e0 l\u2019ampleur du terrain d\u2019\u00e9tude qu\u2019au caract\u00e8re parcellaire des sources&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-18-127020' title='Voir la note m\u00e9thodologique en fin d\u2019ouvrage.'><sup>18<\/sup><\/a><\/span><\/span> ou encore \u00e0 la lisibilit\u00e9 du propos&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-19-127020' title='Par exemple, pour permettre au lecteur de d\u00e9couvrir les biographies de tous les Premiers ministres sans que cela ne soit trop fastidieux, celles-ci sont expos\u00e9es de mani\u00e8re s\u00e9par\u00e9e, lorsque cela servait le mieux l\u2019analyse.'><sup>19<\/sup><\/a><\/span><\/span>, nous avons opt\u00e9 pour un expos\u00e9 hybride, m\u00ealant \u00e9chelle temporelle courte sur des \u00e9tudes de cas et \u00e9chelle temporelle longue portant sur tout ou partie du groupe. Dans chaque partie, l\u2019analyse s\u2019arr\u00eate ainsi plus particuli\u00e8rement sur un ou plusieurs cas, ce qui pourrait donner l\u2019impression au lecteur \u00e9pris d\u2019histoire d\u2019un expos\u00e9 impressionniste, \u00e0 l\u2019image du r\u00f4le \u00e9tudi\u00e9. On voudrait donc tout d\u2019abord rappeler ici que le propos du livre n\u2019est pas de restituer l\u2019histoire des Premiers ministres sous la Ve R\u00e9publique mais de comprendre comment s\u2019est construit puis objectiv\u00e9 le r\u00f4le&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-20-127020' title='&amp;nbsp;Cet expos\u00e9 casuistique refl\u00e8te \u00e0 cet \u00e9gard le rapport singulier que les sciences sociales entretiennent avec l\u2019histoire. Pour celles-ci, l\u2019histoire n\u2019est pas une fin en soi mais un outil au service d\u2019une probl\u00e9matique particuli\u00e8re. Sur ce point, voir&amp;#160;: Pierre Bourdieu, \u00ab&amp;#160;Esprit d\u2019\u00c9tat. Gen\u00e8se et structure du champ bureaucratique&amp;#160;\u00bb, Actes de la recherche en sciences sociales, no 96\u201097, 1993, p. 49\u201062&amp;#160;; et Delphine Dulong, \u00ab&amp;#160;Le Premier ministre en actes et en coulisses. L\u2019histoire comme outil et objet d\u2019analyse sociologique des institutions politiques&amp;#160;\u00bb, dans Michel Offerl\u00e9, Henry Rousso (dir.), La Fabrique interdisciplinaire. Histoire et science politique, Rennes, PUR, 2008, p. 47\u201058.'><sup>20<\/sup><\/a><\/span><\/span>. On voudrait ensuite pr\u00e9ciser que le choix des cas d\u00e9velopp\u00e9s dans tel ou tel chapitre n\u2019a rien d\u2019arbitraire. Le cas du gouvernement Michel Debr\u00e9 est syst\u00e9matiquement convoqu\u00e9 pour expliquer l\u2019intention originelle des constituants. Si l\u2019on d\u00e9veloppe celui de Georges Pompidou dans la premi\u00e8re partie, c\u2019est entre autres parce qu\u2019il est un moment cl\u00e9 dans la bascule des rapports entre Pr\u00e9sident et Premier ministre. Creuser le cas du premier gouvernement socialiste Pierre Mauroy dans la partie suivante est pertinent pour mesurer l\u2019institutionnalisation du r\u00f4le. Il ne l\u2019est pas en revanche pour d\u00e9montrer la politisation qu\u2019engendre in\u00e9vitablement le dialogue avec la majorit\u00e9 parlementaire et la bataille contre l\u2019opposition. Sur ce point, Raymond Barre est bien plus d\u00e9monstratif dans la mesure o\u00f9 il n\u2019a aucune exp\u00e9rience partisane ou \u00e9lective lorsqu\u2019il devient Premier ministre. En r\u00e9sum\u00e9, le choix des cas d\u00e9velopp\u00e9s s\u2019est fait sur le fondement de leurs propri\u00e9t\u00e9s d\u00e9monstratives et\/ou repr\u00e9sentatives du groupe (ou d\u2019un sous-groupe), \u00e0 chaque fois explicit\u00e9es en d\u00e9but d\u2019analyse.<\/p>\n\n\n\n<p>Par ailleurs, lorsque cela \u00e9tait possible, i.e. d\u00e8s lors que nous dispositions d\u2019\u00e9l\u00e9ments de comparaison suffisants, nous avons proc\u00e9d\u00e9 \u00e0 une analyse g\u00e9n\u00e9rale, parfois objectiv\u00e9e par des statistiques descriptives. Au total, tous les Premiers ministres de la Ve R\u00e9publique, de 1959 \u00e0 2021, sont trait\u00e9s dans ce livre. Certains sont plus minutieusement analys\u00e9s que d\u2019autres mais c\u2019est bien normal&#160;: entre Bernard Cazeneuve, qui est rest\u00e9 moins d\u2019un an pour achever le quinquennat de Fran\u00e7ois Hollande, et Georges Pompidou ou Fran\u00e7ois Fillon, qui sont respectivement rest\u00e9s six et cinq ans, l\u2019importance accord\u00e9e ne pouvait \u00eatre la m\u00eame. \u00c9dith Cresson, qui est la seule femme du groupe et celle qui est rest\u00e9e le moins longtemps, m\u00e9ritait qu\u2019on s\u2019arr\u00eate sur son cas \u00e0 plus d\u2019un titre. Jacques Chirac \u00e9galement d\u00e8s lors qu\u2019il est l\u2019un des rares Premiers ministres \u00e0 avoir d\u00e9missionn\u00e9 de son plein gr\u00e9, \u00e0 avoir endoss\u00e9 le r\u00f4le \u00e0 deux reprises (dont une fois en p\u00e9riode de cohabitation) et \u00e0 avoir conquis l\u2019\u00c9lys\u00e9e. Ces choix ne refl\u00e8tent \u00e9videmment pas la valeur que l\u2019on accorde aux personnes mais l\u2019int\u00e9r\u00eat heuristique de leur exp\u00e9rience&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-21-127020' title='Certains documents sur lesquels s\u2019appuie l\u2019analyse ne sont pas reproduits dans le texte faute de place. On pourra cependant les trouver sur le site du CESSP.'><sup>21<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"chapitre-5\"><strong>Chapitre 5<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"les-socialistes-et-la-force-des-institutions\"><strong>Les socialistes et \u00ab&#160;la force des institutions&#160;\u00bb<\/strong><\/h2>\n\n\n\n<p>Ind\u00e9pendamment des multiples contraintes qu\u2019ils rencontrent dans l\u2019exercice de leur fonction, les Premiers ministres sont in\u00e9galement dispos\u00e9s \u00e0 devenir \u00ab&#160;chef du gouvernement&#160;\u00bb. Comment pr\u00e9tendre avoir une autorit\u00e9 politique sur les ministres quand on a, comme certains, moins de capital politique qu\u2019eux&#160;? Comment acquiert-on ce sens de l\u2019\u00c9tat si fondamental \u00e0 l\u2019exercice du pouvoir ex\u00e9cutif quand on n\u2019est pas \u00e9narque et qu\u2019on m\u00e9conna\u00eet totalement l\u2019ordre gouvernemental&#160;? Comment revendiquer enfin le titre de chef aupr\u00e8s de ses \u00ab&#160;camarades&#160;\u00bb quand on a un ethos militant et un rapport collectif aux activit\u00e9s politiques&#160;?<\/p>\n\n\n\n<p>Le cas de Pierre Mauroy permet de r\u00e9pondre \u00e0 ces questions tout en \u00e9clairant un moment cl\u00e9 de l\u2019institutionnalisation du r\u00f4le. En effet, l\u2019alternance de 1981 promeut au gouvernement des \u00e9lites \u00ab&#160;roses&#160;\u00bb vierges de tout exercice du pouvoir ex\u00e9cutif. Beaucoup ont une exp\u00e9rience du pouvoir local, aucun n\u2019a \u00e9t\u00e9 ministre. Les viviers dans lesquels les membres du gouvernement puisent leurs collaborateurs ne sont pas non plus les m\u00eames que dans les gouvernements pr\u00e9c\u00e9dents&#160;: la part des hauts fonctionnaires, qui ma\u00eetrisent les rouages de l\u2019administration, recule face aux enseignants du sup\u00e9rieur ou du secondaire plus souvent form\u00e9s aux \u00e9tudes litt\u00e9raires que juridiques&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-22-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-22-127020' title='Pour plus de d\u00e9tails sur les propri\u00e9t\u00e9s sociales des ministres socialistes entre 1981 et 1985, voir&amp;#160;: Brigitte Ga\u00efti, \u00ab&amp;#160;\u201cPolitique d\u2019abord\u201d&amp;#160;: le chemin de la r\u00e9ussite minist\u00e9rielle dans la France contemporaine&amp;#160;\u00bb, dans Pierre Birnbaum (dir.), Les \u00c9lites socialistes au pouvoir (1981\u20101985), Paris, PUF, 1985, p. 53\u201086.'><sup>22<\/sup><\/a><\/span><\/span>. Ces \u00e9lites roses, par ailleurs, sont bien plus impr\u00e9gn\u00e9es des logiques partisanes que ne l\u2019\u00e9taient avant eux leurs homologues giscardiens et gaullistes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-23-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-23-127020' title='&amp;nbsp;Fran\u00e7oise Dreyfus, \u00ab&amp;#160;Les cabinets minist\u00e9riels&amp;#160;: du politique \u00e0 la gestion administrative&amp;#160;\u00bb, dans Pierre Birnbaum (dir.), Les \u00c9lites socialistes au pouvoir, op. cit, p. 87\u2010104. Sur le personnel des cabinets socialistes, voir&amp;#160;: Pierre Mathiot, Fr\u00e9d\u00e9ric Sawicki, \u00ab&amp;#160;Les membres des cabinets minist\u00e9riels socialistes en France (1981\u20101993)&amp;#160;: recrutement et reconversion. 1) Caract\u00e9ristiques sociales et fili\u00e8res de recrutement&amp;#160;\u00bb, Revue fran\u00e7aise de science politique, vol. 49, no 1, p. 3\u201030.'><sup>23<\/sup><\/a><\/span><\/span>. Elles ont une vision plus collective de la vie politique doubl\u00e9e d\u2019un rapport m\u00e9fiant pour ne pas dire hostile \u00e0 l\u2019appareil d\u2019\u00c9tat centralisateur \u2013 comme en attestent les lois de d\u00e9centralisation de 1982 et 1983.<\/p>\n\n\n\n<p>En somme, rien ne les dispose \u00e0 se conformer \u00e0 un ordre institutionnel qu\u2019elles veulent au contraire transformer. Et pourtant, d\u00e8s 1985 Pierre Birnbaum constate&#160;:<\/p>\n\n\n\n<p>\u00ab&#160;les ministres, qu\u2019ils soient socialistes ou communistes, se comportent, \u00e0 l\u2019image du Pr\u00e9sident de la R\u00e9publique lui-m\u00eame, en fonction des pr\u00e9rogatives qui leur sont conf\u00e9r\u00e9es par un \u00c9tat tout puissant dot\u00e9 d\u2019un r\u00e9gime semi-pr\u00e9sidentiel&#160;; les membres des cabinets minist\u00e9riels les plus engag\u00e9s politiquement paraissent eux aussi se conformer au service public et pr\u00e9f\u00e9rer recourir \u00e0 des arguments techniques plut\u00f4t qu\u2019\u00e0 des consid\u00e9rations strictement politiques [&#8230;] n\u2019est-ce pas en d\u00e9finitive souligner la force des institutions&#160;?&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-24-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-24-127020' title='Voir&amp;#160;: Pierre Birnbaum (dir.), Les \u00c9lites socialistes au pouvoir, op. cit., p. 309.'><sup>24<\/sup><\/a><\/span><\/span>&#160;\u00bb<\/p>\n\n\n\n<p>Reste \u00e0 comprendre \u00e0 quoi tient cette \u00ab&#160;force des institutions&#160;\u00bb. Comme on va le voir au travers de l\u2019exp\u00e9rience des premiers gouvernements socialistes, cette force est avant tout le produit d\u2019une socialisation informelle&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-25-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-25-127020' title='Sur ce type de socialisation propre aux activit\u00e9s politiques, voir&amp;#160;: Lucie Bargel, Jeunes socialistes et jeunes UMP. Lieux et processus de socialisation politique, Paris, Dalloz, 2009.'><sup>25<\/sup><\/a><\/span><\/span> qui op\u00e8re par des interactions plus ou moins insignifiantes dans le quotidien du travail gouvernemental et, comme le dit Pierre Mauroy, \u00ab&#160;sous la pression du commandement&#160;\u00bb, via certains membres de l\u2019entourage. Cette socialisation n\u2019a rien d\u2019un long fleuve tranquille. Elle est plut\u00f4t chaotique et non lin\u00e9aire car l\u2019apprentissage de l\u2019ordre gouvernemental proc\u00e8de par t\u00e2tonnements, \u00e0 coups d\u2019\u00e9preuves et de sanctions positives ou n\u00e9gatives&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-26-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-26-127020' title='Cela n\u2019est toutefois pas propre \u00e0 l\u2019ordre gouvernemental. Voir&amp;#160;: Martin Baloge, \u00ab&amp;#160;Le d\u00e9put\u00e9 d\u00e9butant. Apprentissage et assimilation de l\u2019ethos parlementaire au Bundestag&amp;#160;\u00bb, Politix, no 113, 2016, p. 201\u2010222.'><sup>26<\/sup><\/a><\/span><\/span>. Elle demeure par ailleurs sous la d\u00e9pendance de la socialisation primaire de chaque Premier ministre et varie selon leur contexte d\u2019action. Elle n\u2019emp\u00eache pas, enfin, les socialistes de marquer durablement l\u2019ordre gouvernemental.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"pierre-mauroy-et-la-pression-du-commandement\"><strong>Pierre Mauroy et \u00ab&#160;la pression du commandement&#160;\u00bb<\/strong><\/h3>\n\n\n\n<p>\u00c9tudier le cas du gouvernement Mauroy c\u2019est porter l\u2019\u00e9clairage sur ce que signifie tr\u00e8s concr\u00e8tement apprendre \u00ab&#160;sur le tas&#160;\u00bb l\u2019exercice du pouvoir ex\u00e9cutif. Bien s\u00fbr, Mauroy n\u2019est pas un \u00ab&#160;bleu&#160;\u00bb en politique. Il est loin d\u2019\u00eatre d\u00e9pourvu de capitaux. Cet alli\u00e9 de poids du Pr\u00e9sident, qui a soutenu la motion Rocard contre celle de Mitterrand au congr\u00e8s de Metz en 1979, dirige l\u2019une des f\u00e9d\u00e9rations les plus puissantes du Parti socialiste (la f\u00e9d\u00e9ration du Nord) et anime son propre courant. Cependant, \u00e0 l\u2019instar de Georges Pompidou, rien dans sa trajectoire ne l\u2019a vraiment pr\u00e9par\u00e9 \u00e0 diriger le gouvernement&#160;: ni ses origines sociales modestes (son grand-p\u00e8re \u00e9tait bucheron et son p\u00e8re instituteur), ni ses \u00e9tudes (le conduisant \u00e0 int\u00e9grer le corps des professeurs de l\u2019enseignement technique du secondaire), ni m\u00eame sa carri\u00e8re \u00ab&#160;d\u2019apparatchik&#160;\u00bb qui pourtant l\u2019am\u00e8ne \u00e0 diriger un syndicat enseignant (de 1955 \u00e0 1959), puis \u00e0 devenir secr\u00e9taire g\u00e9n\u00e9ral adjoint de la SFIO (1966) et secr\u00e9taire national \u00e0 la coordination du Parti socialiste (1971\u20101979). Si ces exp\u00e9riences militantes font de lui le \u00ab&#160;num\u00e9ro 2&#160;\u00bb du PS, elles ne font pas de lui le num\u00e9ro 1 du gouvernement&#160;: d\u2019une part son exp\u00e9rience du pouvoir ex\u00e9cutif est limit\u00e9e au pouvoir local&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-27-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-27-127020' title='&amp;nbsp;&amp;nbsp;En tant que maire de Lille (depuis 1973) et Pr\u00e9sident du conseil r\u00e9gional du Nord-Pas-de-Calais (depuis 1974). Mauroy souligne lui-m\u00eame cette \u00ab&amp;#160;impr\u00e9paration&amp;#160;\u00bb dans ses m\u00e9moires&amp;#160;: \u00ab&amp;#160;Ma mairie de Lille m\u2019avait beaucoup appris, rien de comparable cependant \u00e0 cette agression permanente, cette pr\u00e9cipitation et les nombreuses d\u00e9cisions \u00e0 prendre. Pas davantage la direction du Parti socialiste avec Fran\u00e7ois Mitterrand&amp;#160;! \u00c0 Matignon on ressent rapidement la chape des contraintes et des pres\u2010 sions&amp;#160;\u00bb (P. Mauroy, Vous mettrez du bleu au ciel, op. cit, p. 179).'><sup>27<\/sup><\/a><\/span><\/span>, d\u2019autre part l\u2019ethos militant qu\u2019il s\u2019est forg\u00e9 durant toutes ces ann\u00e9es le pousse \u00e0 avoir un rapport au poste tr\u00e8s diff\u00e9rent de celui de ses pr\u00e9d\u00e9cesseurs et en particulier de celui qui l\u2019a con\u00e7u et endoss\u00e9 le premier, Michel Debr\u00e9. Cependant, sa volont\u00e9 de gouverner autrement se heurte d\u2019embl\u00e9e \u00e0 l\u2019ordinaire routinis\u00e9 du travail gouvernemental. Porter l\u2019\u00e9clairage sur ce premier gouvernement socialiste, c\u2019est de fait aussi mettre en lumi\u00e8re l\u2019importance dans les processus d\u2019institutionnalisation de ce que Michel Rocard appelle \u00ab&#160;la technique d\u2019organisation du syst\u00e8me&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-28-127020' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#easy-footnote-bottom-28-127020' title='Michel Rocard, Si la gauche savait, op. cit., p. 277.'><sup>28<\/sup><\/a><\/span><\/span>&#160;\u00bb \u2013 i.e. les r\u00e8gles proc\u00e9durales et la temporalit\u00e9 qu\u2019elles imposent aux acteurs. Celles-ci ne p\u00e8sent toutefois qu\u2019au travers des rappels \u00e0 l\u2019ordre incessants de certains collaborateurs du Premier ministre qui, avec l\u2019aide des \u00e9lections interm\u00e9diaires, v\u00e9cues comme des sanctions, jouent un r\u00f4le majeur dans la socialisation de Pierre Mauroy \u00e0 l\u2019ordre gouvernemental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00f4le de Premier ministre en France est une construction sociologique et historique. Si le couple Pr\u00e9sident-Premier ministre est con\u00e7u par la Constitution comme une dyarchie, c&rsquo;est la pratique, plus que le droit, qui a fa\u00e7onn\u00e9 la fonction. Nous publions les bonnes feuilles de l&rsquo;ouvrage, paru aux \u00e9ditions du CNRS. <\/p>\n","protected":false},"author":1782,"featured_media":127025,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-reviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":24,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1731],"tags":[],"staff":[3061],"editorial_format":[4868],"serie":[],"audience":[],"geo":[],"class_list":["post-127020","post","type-post","status-publish","format-standard","hentry","category-politique","staff-delphine-dulong","editorial_format-comptes-rendus"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":127025,"excerpt":"Le r\u00f4le de Premier ministre en France est une construction sociologique et historique. Si le couple Pr\u00e9sident-Premier ministre est con\u00e7u par la Constitution comme une dyarchie, c'est la pratique, plus que le droit, qui a fa\u00e7onn\u00e9 la fonction. Nous publions les bonnes feuilles de l'ouvrage, paru aux \u00e9ditions du CNRS. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Premier ministre | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premier ministre | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le r\u00f4le de Premier ministre en France est une construction sociologique et historique. Si le couple Pr\u00e9sident-Premier ministre est con\u00e7u par la Constitution comme une dyarchie, c&#039;est la pratique, plus que le droit, qui a fa\u00e7onn\u00e9 la fonction. Nous publions les bonnes feuilles de l&#039;ouvrage, paru aux \u00e9ditions du CNRS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-16T21:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-23T11:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/dulong.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"clementf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/dulong.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"clementf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/\",\"name\":\"Premier ministre | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg\",\"datePublished\":\"2021-12-16T21:20:00+00:00\",\"dateModified\":\"2021-12-23T11:34:47+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg\",\"width\":400,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premier ministre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84\",\"name\":\"clementf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g\",\"caption\":\"clementf\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premier ministre | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/","og_locale":"fr_FR","og_type":"article","og_title":"Premier ministre | Le Grand Continent","og_description":"Le r\u00f4le de Premier ministre en France est une construction sociologique et historique. Si le couple Pr\u00e9sident-Premier ministre est con\u00e7u par la Constitution comme une dyarchie, c'est la pratique, plus que le droit, qui a fa\u00e7onn\u00e9 la fonction. Nous publions les bonnes feuilles de l'ouvrage, paru aux \u00e9ditions du CNRS.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/","og_site_name":"Le Grand Continent","article_published_time":"2021-12-16T21:20:00+00:00","article_modified_time":"2021-12-23T11:34:47+00:00","og_image":[{"width":1200,"height":693,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/dulong.jpg","type":"image\/jpeg"}],"author":"clementf","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/dulong.jpg","twitter_misc":{"\u00c9crit par":"clementf","Dur\u00e9e de lecture estim\u00e9e":"24 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/","url":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/","name":"Premier ministre | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg","datePublished":"2021-12-16T21:20:00+00:00","dateModified":"2021-12-23T11:34:47+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg","width":400,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/12\/16\/premier-ministre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Premier ministre"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84","name":"clementf","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g","caption":"clementf"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":3061,"name":"Delphine Dulong","slug":"delphine-dulong","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg","width":400,"height":614,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/12\/Premier-ministre.jpg","width":400,"height":614,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/127020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1782"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=127020"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/127020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/127025"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=127020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=127020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=127020"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=127020"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=127020"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=127020"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=127020"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=127020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}