{"id":125470,"date":"2021-11-18T22:24:03","date_gmt":"2021-11-18T21:24:03","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=125470"},"modified":"2021-11-18T22:31:02","modified_gmt":"2021-11-18T21:31:02","slug":"resultats-des-elections-locales-et-regionales-danoises","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/","title":{"rendered":"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises"},"content":{"rendered":"\n<p>Mardi 16 novembre, les citoyens danois ont \u00e9lu leurs repr\u00e9sentants pour 98 conseils municipaux et 5 conseils r\u00e9gionaux. Bilan en cinq points.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Malgr\u00e9 un l\u00e9ger recul, les sociaux-d\u00e9mocrates (S&amp;D) de la Premi\u00e8re ministre Mette Fredriksen ont conserv\u00e9 leur position de premier parti, remportant 28,5&#160;% des voix devant le parti lib\u00e9ral-conservateur Venstre (RE) qui a obtenu 21,2&#160;% des voix.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Trois des cinq pr\u00e9sidents de conseils r\u00e9gionaux seront des sociaux-d\u00e9mocrates, tandis que les deux autres seront issus de Venstre. Venstre a notamment remport\u00e9 la pr\u00e9sidence du conseil r\u00e9gional du nord du Danemark face aux sociaux-d\u00e9mocrates.<br><\/li><li>Au niveau municipal, 44 maires seront issus des sociaux-d\u00e9mocrates, et 36 de Venstre. Dans l&rsquo;ensemble, il y a eu peu de changements depuis la pr\u00e9c\u00e9dente \u00e9lection, qui s&rsquo;\u00e9tait tenue en 2017. Les sociaux-d\u00e9mocrates ont perdu trois postes de maire, tandis que le Parti populaire conservateur (PPE) a obtenu la troisi\u00e8me place, augmentant son nombre de maires de 8 \u00e0 12.<br><\/li><li>Frederiksberg, une municipalit\u00e9 d&rsquo;un peu plus de 100 000 habitants enclav\u00e9e dans Copenhague, aura un maire social-d\u00e9mocrate apr\u00e8s 112 ans de direction conservatrice ininterrompue. Le Parti populaire conservateur a remport\u00e9 plus de 40&#160;% des voix dans cette riche municipalit\u00e9, mais une coalition dirig\u00e9e par les sociaux-d\u00e9mocrates a r\u00e9ussi \u00e0 emporter la majorit\u00e9. Les sociaux-d\u00e9mocrates ont \u00e9galement conserv\u00e9 la mairie de Copenhague, malgr\u00e9 une perte de dix points et la victoire dans la capitale de l&rsquo;Alliance rouge-verte (GUE\/NGL).<br><\/li><li>Le chef du Parti du peuple danois (ID), Kristian Thulesen Dahl, a annonc\u00e9 sa d\u00e9mission apr\u00e8s les mauvais r\u00e9sultats du parti aux \u00e9lections. La part de voix du parti est pass\u00e9e de 8,75&#160;% lors des derni\u00e8res \u00e9lections \u00e0 4,08&#160;% ce mardi, faisant perdre au parti 130 de ses 221 si\u00e8ges de conseillers municipaux. Dans le m\u00eame temps, le parti d&rsquo;extr\u00eame droite Nouvelle Droite, form\u00e9 en 2015, a remport\u00e9 63 nouveaux si\u00e8ges dans les conseils municipaux, alors qu&rsquo;il n&rsquo;avait obtenu qu&rsquo;un seul si\u00e8ge lors de ses premi\u00e8res \u00e9lections locales en 2017.<\/li><\/ul>\n\n\n\n<p><em>Nota bene.<\/em> Ces \u00e9lections r\u00e9gionales \u00e9taient les derni\u00e8res de l&rsquo;ann\u00e9e 2021. Le prochain scrutin r\u00e9gional aura lieu en Finlande le 23 janvier.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mardi 16 novembre, les citoyens danois ont \u00e9lu leurs repr\u00e9sentants pour 98 conseils municipaux et 5 conseils r\u00e9gionaux. Bilan en cinq points.<\/p>\n","protected":false},"author":98,"featured_media":125471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":2,"footnotes":""},"categories":[2980],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[547],"class_list":["post-125470","post","type-post","status-publish","format-standard","hentry","category-elections","editorial_format-actu-breves","geo-nordiques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":125471,"excerpt":"Mardi 16 novembre, les citoyens danois ont \u00e9lu leurs repr\u00e9sentants pour 98 conseils municipaux et 5 conseils r\u00e9gionaux. Bilan en cinq points.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Mardi 16 novembre, les citoyens danois ont \u00e9lu leurs repr\u00e9sentants pour 98 conseils municipaux et 5 conseils r\u00e9gionaux. Bilan en cinq points.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-18T21:24:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T21:31:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1261\" \/>\n\t<meta property=\"og:image:height\" content=\"707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fran\u00e7ois Hublet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fran\u00e7ois Hublet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/\",\"name\":\"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png\",\"datePublished\":\"2021-11-18T21:24:03+00:00\",\"dateModified\":\"2021-11-18T21:31:02+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/8a178114687bc8266b68dcf6a19160b2\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png\",\"width\":1261,\"height\":707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/8a178114687bc8266b68dcf6a19160b2\",\"name\":\"Fran\u00e7ois Hublet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cc38f005f1fe04d1524b8746ee1817ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cc38f005f1fe04d1524b8746ee1817ed?s=96&d=mm&r=g\",\"caption\":\"Fran\u00e7ois Hublet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises | Le Grand Continent","og_description":"Mardi 16 novembre, les citoyens danois ont \u00e9lu leurs repr\u00e9sentants pour 98 conseils municipaux et 5 conseils r\u00e9gionaux. Bilan en cinq points.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/","og_site_name":"Le Grand Continent","article_published_time":"2021-11-18T21:24:03+00:00","article_modified_time":"2021-11-18T21:31:02+00:00","og_image":[{"width":1261,"height":707,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png","type":"image\/png"}],"author":"Fran\u00e7ois Hublet","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png","twitter_misc":{"\u00c9crit par":"Fran\u00e7ois Hublet","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/","url":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/","name":"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png","datePublished":"2021-11-18T21:24:03+00:00","dateModified":"2021-11-18T21:31:02+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/8a178114687bc8266b68dcf6a19160b2"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png","width":1261,"height":707},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/18\/resultats-des-elections-locales-et-regionales-danoises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sultats des \u00e9lections locales et r\u00e9gionales danoises"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/8a178114687bc8266b68dcf6a19160b2","name":"Fran\u00e7ois Hublet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cc38f005f1fe04d1524b8746ee1817ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc38f005f1fe04d1524b8746ee1817ed?s=96&d=mm&r=g","caption":"Fran\u00e7ois Hublet"}}]}},"lgc_categories":[{"id":2980,"name":"\u00c9lections","slug":"elections"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/11\/Bildschirmfoto-vom-2021-11-18-22-19-26.png","width":1261,"height":707,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/125470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/98"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=125470"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/125470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/125471"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=125470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=125470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=125470"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=125470"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=125470"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=125470"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=125470"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=125470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}