{"id":12497,"date":"2018-12-15T10:22:39","date_gmt":"2018-12-15T09:22:39","guid":{"rendered":"https:\/\/legrandcontinent.eu\/?p=12497"},"modified":"2019-04-04T21:28:05","modified_gmt":"2019-04-04T20:28:05","slug":"le-brexit-au-dela-de-la-question-europeenne","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/","title":{"rendered":"Le Brexit, au-del\u00e0 de la question europ\u00e9enne"},"content":{"rendered":"\n<p><em>La question de l\u2019immigration \u00e9tait l\u2019un des grands th\u00e8mes de la campagne r\u00e9f\u00e9rendaire du Brexit et la motivation premi\u00e8re des partisans d\u2019une sortie de l\u2019Union europ\u00e9enne. Aujourd\u2019hui, apr\u00e8s deux ans de n\u00e9gociations, la migration nette en provenance de l\u2019UE a chut\u00e9, ce qui pourrait \u00e0 terme entra\u00eener une p\u00e9nurie de main d&rsquo;oeuvre dans plusieurs secteurs des services publics et de l&rsquo;\u00e9conomie. De plus, les \u00e9tudes r\u00e9centes donnent les cons\u00e9quences \u00e9conomiques d\u2019une sortie du pays de l\u2019Union comme n\u00e9gatives. Les Britanniques, qui semblent avoir chang\u00e9 d\u2019id\u00e9e sur le Brexit, sont-ils en passe de r\u00e9aliser, deux ans et demi apr\u00e8s le r\u00e9f\u00e9rendum, que ce n\u2019\u00e9tait pas la question europ\u00e9enne qui \u00e9tait au c\u0153ur de leur vote en juin 2016&#160;?<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p style=\"text-align:right\"><em>Par Vera Marchand<\/em><\/p>\n\n\n\n<p>Le vote en faveur du Brexit a produit l\u2019effet d\u2019un s\u00e9isme tant pour le Royaume-Uni, qui traverse sa crise politique la plus importante depuis la Seconde Guerre mondiale, que pour l\u2019Union europ\u00e9enne. Le 23 juin 2016, le <em>Leave<\/em> l\u2019emportait \u00e0 52&#160;% des voix, avec une majorit\u00e9 d\u2019Anglais et de Gallois votant pour sortir de l\u2019Union europ\u00e9enne tandis qu\u2019une majorit\u00e9 d\u2019Irlandais du Nord et d&rsquo;\u00c9cossais choisissaient, \u00e0 l\u2019inverse, de rester en son sein. Les rapports et les \u00e9tudes publi\u00e9s apr\u00e8s le vote ont soulign\u00e9 l\u2019\u00e9mergence de profonds clivages, \u00e0 la fois territoriaux et g\u00e9n\u00e9rationnels, r\u00e9v\u00e9lateurs d\u2019une fracture nationale qui allait bien au-del\u00e0 de la question de l\u2019appartenance \u00e0 l\u2019Union europ\u00e9enne.<\/p>\n\n\n\n<p>Comme l\u2019a r\u00e9cemment soulign\u00e9 <em>UK in a Changing Europe<\/em>, un think tank bas\u00e9 \u00e0 Londres et qui \u00e9tudie les relations entre le Royaume-Uni et l\u2019Europe, l\u2019accord n\u00e9goci\u00e9 avec Bruxelles &#8211; sans parler d\u2019un <em>no deal<\/em> -, marquera l\u2019arr\u00eat de la libert\u00e9 de circulation, et avec elle la diminution du PIB national. Selon Matt Bevington, l\u2019approche migratoire pr\u00f4n\u00e9e par Theresa May rel\u00e8ve du <em>cherry picking<\/em> et repose sur un raisonnement intrins\u00e8quement d\u00e9faillant&#160;: de fait, si la Grande-Bretagne veut privil\u00e9gier les immigr\u00e9s les plus qualifi\u00e9s (<em>\u2018high-skilled\u2019 workers<\/em>), elle doit pouvoir compter sur ce pouvoir d\u2019attractivit\u00e9 m\u00eame qu\u2019elle semble perdre depuis le vote sur le Brexit. La migration nette en provenance de l\u2019Union europ\u00e9enne a chut\u00e9 de plus de 50&#160;% depuis le 23 juin 2016, passant de 190 000 \u00e0 90 000. Les chiffres concernant les immigr\u00e9s en provenance d\u2019Europe de l\u2019Est vont dans le m\u00eame sens&#160;: depuis le Brexit, ils ont diminu\u00e9 d\u2019environ 50&#160;%, passant de 84 000 \u00e0 45 000.<sup><a id=\"ref1\" href=\"#fn1\">1<\/a><\/sup> Mais selon un rapport publi\u00e9 en octobre par le <em>National Institute of Economic and Social Research<\/em> et la <em>Birckbeck University<\/em>, fond\u00e9 sur 12 groupes repr\u00e9sentatifs de 105 participants dans une aire g\u00e9ographique o\u00f9 le <em>Leave<\/em> l\u2019a emport\u00e9, les employeurs reconnaissent un besoin \u00e9gal de travailleurs qualifi\u00e9s et de travailleurs peu qualifi\u00e9s.<sup><a id=\"ref2\" href=\"#fn2\">2<\/a><\/sup> <\/p>\n\n\n\n<p>Les r\u00e9percussions du Brexit se font tout particuli\u00e8rement sentir au niveau du National Health Service (NHS), le syst\u00e8me de sant\u00e9 publique britannique, dans la mesure o\u00f9 son personnel m\u00e9dical est en grande partie issu de l\u2019immigration. C\u2019est notamment le cas \u00e0 Londres, dans le sud-est du pays ou en Irlande du Nord. Les chiffres publi\u00e9s par la <em>Health Foundation<\/em> r\u00e9v\u00e8lent une baisse actuelle de 87&#160;% du nombre d\u2019infirmi\u00e8res en provenance de l\u2019Union europ\u00e9enne&#160;: de 6 400 en 2016-2017, elles sont pass\u00e9es \u00e0 800 en 2017-2018, laissant les h\u00f4pitaux britanniques dans le plus grand d\u00e9sarroi.<sup><a id=\"ref3\" href=\"#fn3\">3<\/a><\/sup> <\/p>\n\n\n\n<p>L\u2019ancien Premier Ministre David Cameron avait affirm\u00e9 vouloir restreindre la libert\u00e9 de circulation en fixant des limites \u00e0 l\u2019immigration. Ainsi, en f\u00e9vrier 2016, quelques mois avant le vote sur le Brexit, Cameron tenta de n\u00e9gocier un nouveau statut pour la Grande-Bretagne. Mais il ne parvint pas \u00e0 satisfaire, sur la question migratoire, l\u2019aile la plus eurosceptique de son parti. Ces <em>hard<\/em> <em>brexiteers<\/em> lui reprochaient de ne pas avoir su n\u00e9gocier la fin des allocations destin\u00e9es aux immigr\u00e9s europ\u00e9ens issus de l\u2019\u00e9largissement de 2004 et 2007. Cameron n\u2019avait en effet r\u00e9ussi \u00e0 obtenir de Bruxelles qu\u2019un \u201c<em>emergency brake<\/em>\u201d obligeant, en cas de <em>Remain<\/em>, les immigr\u00e9s europ\u00e9ens \u00e0 attendre quatre ans avant d\u2019avoir acc\u00e8s aux allocations de l\u2019\u00e9tat social britannique.<\/p>\n\n\n\n<p>Ce qui avait alors \u00e9t\u00e9 tr\u00e8s peu soulign\u00e9, c\u2019est que les allocations vers\u00e9es aux \u00e9trangers ne repr\u00e9sentaient que 2,2&#160;% du total des allocations en 2015.<sup><a id=\"ref4\" href=\"#fn4\">4<\/a><\/sup> Les tablo\u00efds eurosceptiques \u2013 il n\u2019est que de songer aux images de migrants publi\u00e9es pendant la campagne \u2013 ont contribu\u00e9 \u00e0 orienter les esprits, confondant la question des allocations avec celle de la crise des r\u00e9fugi\u00e9s. C\u2019est ainsi qu\u2019en avril 2016, le tablo\u00efd <em>Daily Express<\/em>,<em> <\/em>reprenant la m\u00eame image d\u2019une foule de migrants que celle choisie par UKIP en y ajoutant une photographie d\u2019\u00e9l\u00e8ves de lyc\u00e9e, sous-titrait&#160;: \u201c<em>Le flux de migrants pourrait faire perdre \u00e0 des milliers d\u2019\u00e9l\u00e8ves leur place \u00e0 l\u2019\u00e9cole primaire<\/em>\u201d.<\/p>\n\n\n\n<p>Ce ph\u00e9nom\u00e8ne n\u2019est pas nouveau. En effet, plusieurs \u00e9tudes publi\u00e9es en Grande-Bretagne au lendemain du vote se concentr\u00e8rent sur la couverture m\u00e9diatique de la question europ\u00e9enne durant la campagne, et mirent l\u2019accent sur le r\u00f4le crucial jou\u00e9 dans celle-ci par la th\u00e9matique de l\u2019immigration.<sup><a id=\"ref5\" href=\"#fn5\">5<\/a><\/sup> Le <em>Migration Observatory<\/em> de l\u2019Universit\u00e9 d\u2019Oxford publia un rapport tr\u00e8s d\u00e9taill\u00e9 sur la couverture de la question migratoire par les m\u00e9dias, \u00e9valuant en particulier l\u2019impact, apr\u00e8s 2013, du d\u00e9bat public suscit\u00e9 autour de l\u2019acc\u00e8s au march\u00e9 du travail britannique des immigr\u00e9s en provenance d\u2019Europe de l\u2019Est, ainsi que ceux, plus r\u00e9cents, de 2006 \u00e0 2015, qui accompagn\u00e8rent l\u2019\u00e9closion de la crise des r\u00e9fugi\u00e9s au sein l\u2019Union europ\u00e9enne. Selon les conclusions de ce rapport, ces effets cumul\u00e9s pourraient avoir influenc\u00e9 le choix du Brexit. Mike Berry, professeur \u00e0 la Cardiff University School, semble confirmer l\u2019id\u00e9e d\u2019une (sur)exposition m\u00e9diatique, sur le court et le long terme, de la question migratoire&#160;: \u00ab&#160;<em>Bien que de nombreux commentaires se concentrent sur l\u2019impact de la campagne, l\u2019effet le plus puissant produit par les m\u00e9dias est li\u00e9 \u00e0 des processus de long-terme, exposant les \u00e9lecteurs \u00e0 des messages r\u00e9p\u00e9t\u00e9s. Il est fondamental de consid\u00e9rer que la question europ\u00e9enne \u2013 particuli\u00e8rement l\u2019enjeu migratoire \u2013 a fait l\u2019objet d\u2019une couverture m\u00e9diatique sur plusieurs ann\u00e9es<\/em>.&#160;\u00bb<sup><a id=\"ref6\" href=\"#fn6\">6<\/a><\/sup> <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1019\" src=\"https:\/\/i1.wp.com\/legrandcontinent.eu\/wp-content\/uploads\/2018\/12\/IMG_5687.jpg?fit=1000%2C995&amp;ssl=1\" alt=\"\" class=\"wp-image-12527\" srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/IMG_5687.jpg 1024w, https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/IMG_5687-125x124.jpg 125w, https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/IMG_5687-330x328.jpg 330w, https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/IMG_5687-86x86.jpg 86w, https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/IMG_5687-182x182.jpg 182w, https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/IMG_5687-690x687.jpg 690w, https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/IMG_5687-990x985.jpg 990w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Les Britanniques, d\u00e8s lors, se sont-ils r\u00e9ellement prononc\u00e9s sur le sujet du r\u00e9f\u00e9rendum (la sortie de l\u2019UE), ou ont-ils en r\u00e9alit\u00e9 vot\u00e9 sur d\u2019autres th\u00e8mes&#160;? Selon un sondage publi\u00e9 par YouGov, \u00e0 la question \u00ab&#160;Pensez-vous que la Grande-Bretagne a eu tort ou raison de voter pour sortir de l\u2019Union europ\u00e9enne&#160;?&#160;\u00bb, 53&#160;% des interview\u00e9s pensent d\u00e9sormais qu\u2019elle a eu tort.<sup><a id=\"ref7\" href=\"#fn7\">7<\/a><\/sup> Cette \u00e9volution de l\u2019opinion publique est li\u00e9e \u00e0 l\u2019impasse politique dans laquelle se d\u00e9bat actuellement le pouvoir ex\u00e9cutif, mais elle est aussi en partie due \u00e0 la publications d\u2019\u00e9tudes r\u00e9centes sur les cons\u00e9quences \u00e9conomiques d\u2019une sortie de l\u2019Union europ\u00e9enne. En effet, selon le <em>National Institute of Economic and Social Research<\/em>, l\u2019accord induira une r\u00e9duction du PIB de 3&#160;%. Les donn\u00e9es publi\u00e9es sur les cons\u00e9quences d\u2019une sortie sans parachute sont encore plus d\u00e9solantes. Qu\u2019il s\u2019agisse de la difficult\u00e9 du processus de n\u00e9gociation ou de la publication de la part du gouvernement et de la Banque d\u2019Angleterre de pr\u00e9visions \u00e9conomiques n\u00e9gatives pour l\u2019apr\u00e8s-Brexit, les Britanniques semblent avoir mesur\u00e9 \u00e0 quel point la sortie de l\u2019Union nuirait aux m\u00e9nages. Et ce en d\u00e9pit de toutes les assurances fournies par les <em>brexiteers <\/em>avant, pendant et apr\u00e8s le r\u00e9f\u00e9rendum.<\/p>\n\n\n\n<p>Le paradoxe britannique en mati\u00e8re d\u2019immigration &#8211; voter pour reprendre le contr\u00f4le sur les fronti\u00e8res tout en le perdant sur certains secteurs cl\u00e9s de l\u2019\u00e9conomie &#8211; pourrait bien \u00eatre la r\u00e9ponse \u00e0 des probl\u00e8mes nationaux, li\u00e9s notamment \u00e0 la crise \u00e9conomique et \u00e0 ses effets sur la population britannique, comme dans le reste de l\u2019Union europ\u00e9enne. Une l\u00e9gislation europ\u00e9enne davantage concentr\u00e9e sur la gestion de l\u2019immigration ill\u00e9gale que sur l\u2019int\u00e9gration des migrants, le manque d\u2019harmonisation du droit en mati\u00e8re d\u2019accueil et le non-respect par certains pays du principe de solidarit\u00e9 ont g\u00e9n\u00e9r\u00e9 une panique dans l\u2019opinion qui pourrait \u00eatre l\u2019un des facteurs du sentiment de rejet britannique. Selon Enrico Letta et S\u00e9bastien Maillard, dans un livre publi\u00e9 en septembre 2017 sur le sujet de la construction europ\u00e9enne, \u00ab&#160;Pour la crise des migrants, l\u2019Europe a manqu\u00e9 d\u2019une bo\u00eete \u00e0 outils, d\u2019un choix politique fond\u00e9 sur nos capacit\u00e9s, nos crit\u00e8res d\u2019accueil et nos r\u00e8gles de relocalisation.&#160;\u00bb<\/p>\n\n\n\n<p>Les Britanniques, par leur question clivante &#8211; \u00ab&#160;voulez-vous rester ou voulez-vous sortir&#160;?&#160;\u00bb \u2013 ont voulu prendre acte d\u2019un dysfonctionnement de l\u2019Europe. M\u00eame si l\u2019accord conclu avec l\u2019Union europ\u00e9enne le 25 novembre dernier \u00e9tait accept\u00e9 par Westminster &#8211; accord que Nigel Farage, <em>brexiteer<\/em> de la premi\u00e8re heure, a qualifi\u00e9 de \u00ab&#160;jeu, set et match&#160;\u00bb pour l\u2019Union europ\u00e9enne -, les causes v\u00e9ritables du rejet sont peut-\u00eatre davantage \u00e0 rechercher au niveau national, dans la r\u00e9surgence d\u2019un sentiment anti-immigration caract\u00e9ristique, composante essentielle de cette mont\u00e9e du souverainisme qui menace en profondeur les d\u00e9mocraties occidentales. Et ce, quelle que soit la d\u00e9cision de Westminster sur le projet d\u2019accord conclu avec Bruxelles.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>NOTES<\/p>\n\n\n\n<p><sup id=\"fn1\">1. http:\/\/ukandeu.ac.uk\/we-can-pick-and-choose-migrants-but-they-may-not-want-to-move-here\/ <a title=\"Jump back to footnote 1 in the text.\" href=\"#ref1\">\u21a9<\/a><\/sup><\/p>\n<\/p><sup id=\"fn2\">2. \u201cPost-Brexit Immigration Policy&#160;: Reconciling Public Perceptions with Economic Evidence\u201d, National Institute of Economic and Social Research, 11 oct 2018 <a title=\"Jump back to footnote 2 in the text.\" href=\"#ref2\">\u21a9<\/a><\/sup><\/p>\n<\/p><sup id=\"fn3\">3. \u00ab&#160;Large drop in the number of new nurses coming from the EU to work in the UK&#160;\u00bb, The Health Foundation, 2018 <a title=\"Jump back to footnote 3 in the text.\" href=\"#ref3\">\u21a9<\/a><\/sup><\/p>\n<\/p><sup id=\"fn4\">4. \u00ab&#160;How many EU migrants claim benefits in the UK&#160;?&#160;\u00bb, UK in a Changing Europe <a title=\"Jump back to footnote 4 in the text.\" href=\"#ref4\">\u21a9<\/a><\/sup><\/p>\n<\/p><sup id=\"fn5\">5. EU Referendum Analysis, Loughborough University, 2016&#160;; A decade of immigration in the British press, The Migration Observatory, 2016 <a title=\"Jump back to footnote 5 in the text.\" href=\"#ref5\">\u21a9<\/a><\/sup><\/p>\n<\/p><sup id=\"fn6\">6. Mike Berry, Understanding the role of the mass media in the EU referendum, EU Referendum Analysis, Loughborough University, 2016 <a title=\"Jump back to footnote 6 in the text.\" href=\"#ref6\">\u21a9<\/a><\/sup><\/p>\n<\/p><sup id=\"fn7\">7. In hindsight, do you think Britain was right or wrong to vote to leave the EU&#160;?, Natcen Social Research, 27 novembre 2018 <a title=\"Jump back to footnote 7 in the text.\" href=\"#ref7\">\u21a9<\/a><\/sup>\n<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>La question de l\u2019immigration \u00e9tait l\u2019un des grands th\u00e8mes de la campagne r\u00e9f\u00e9rendaire du Brexit et la motivation premi\u00e8re des partisans d\u2019une sortie de l\u2019Union europ\u00e9enne. Aujourd\u2019hui, apr\u00e8s deux ans de n\u00e9gociations, la migration nette en provenance de l\u2019UE a chut\u00e9, ce qui pourrait \u00e0 terme entra\u00eener une p\u00e9nurie de main d&rsquo;oeuvre dans plusieurs secteurs [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12525,"comment_status":"closed","ping_status":"open","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[],"class_list":["post-12497","post","type-post","status-publish","format-standard","hentry","category-uncategorised","editorial_format-actu-breves"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":12525,"excerpt":"La question de l\u2019immigration \u00e9tait l\u2019un des grands th\u00e8mes de la campagne r\u00e9f\u00e9rendaire du Brexit et la motivation premi\u00e8re des partisans d\u2019une sortie de l\u2019Union europ\u00e9enne. Aujourd\u2019hui, apr\u00e8s deux ans de n\u00e9gociations, la migration nette en provenance de l\u2019UE a chut\u00e9, ce qui pourrait \u00e0 terme entra\u00eener une p\u00e9nurie de main d&rsquo;oeuvre dans plusieurs secteurs [&hellip;]","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Brexit, au-del\u00e0 de la question europ\u00e9enne | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Brexit, au-del\u00e0 de la question europ\u00e9enne | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La question de l\u2019immigration \u00e9tait l\u2019un des grands th\u00e8mes de la campagne r\u00e9f\u00e9rendaire du Brexit et la motivation premi\u00e8re des partisans d\u2019une sortie de l\u2019Union europ\u00e9enne. Aujourd\u2019hui, apr\u00e8s deux ans de n\u00e9gociations, la migration nette en provenance de l\u2019UE a chut\u00e9, ce qui pourrait \u00e0 terme entra\u00eener une p\u00e9nurie de main d&rsquo;oeuvre dans plusieurs secteurs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-15T09:22:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-04T20:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gegeurope\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gegeurope\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/\",\"name\":\"Le Brexit, au-del\u00e0 de la question europ\u00e9enne | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png\",\"datePublished\":\"2018-12-15T09:22:39+00:00\",\"dateModified\":\"2019-04-04T20:28:05+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png\",\"width\":1600,\"height\":568},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Brexit, au-del\u00e0 de la question europ\u00e9enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\",\"name\":\"gegeurope\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"caption\":\"gegeurope\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Brexit, au-del\u00e0 de la question europ\u00e9enne | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Brexit, au-del\u00e0 de la question europ\u00e9enne | Le Grand Continent","og_description":"La question de l\u2019immigration \u00e9tait l\u2019un des grands th\u00e8mes de la campagne r\u00e9f\u00e9rendaire du Brexit et la motivation premi\u00e8re des partisans d\u2019une sortie de l\u2019Union europ\u00e9enne. Aujourd\u2019hui, apr\u00e8s deux ans de n\u00e9gociations, la migration nette en provenance de l\u2019UE a chut\u00e9, ce qui pourrait \u00e0 terme entra\u00eener une p\u00e9nurie de main d&rsquo;oeuvre dans plusieurs secteurs [&hellip;]","og_url":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/","og_site_name":"Le Grand Continent","article_published_time":"2018-12-15T09:22:39+00:00","article_modified_time":"2019-04-04T20:28:05+00:00","og_image":[{"width":1600,"height":568,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png","type":"image\/png"}],"author":"gegeurope","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gegeurope","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/","url":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/","name":"Le Brexit, au-del\u00e0 de la question europ\u00e9enne | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png","datePublished":"2018-12-15T09:22:39+00:00","dateModified":"2019-04-04T20:28:05+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png","width":1600,"height":568},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/12\/15\/le-brexit-au-dela-de-la-question-europeenne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Brexit, au-del\u00e0 de la question europ\u00e9enne"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44","name":"gegeurope","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","caption":"gegeurope"}}]}},"lgc_categories":[{"id":1,"name":"Uncategorised","slug":"uncategorised"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/12\/express-2014.png","width":1600,"height":568,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/12497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=12497"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/12497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/12525"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=12497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=12497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=12497"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=12497"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=12497"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=12497"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=12497"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=12497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}