{"id":123045,"date":"2021-10-13T18:00:00","date_gmt":"2021-10-13T16:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=123045"},"modified":"2021-10-13T11:43:54","modified_gmt":"2021-10-13T09:43:54","slug":"nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/","title":{"rendered":"\u00ab&#160;Nous voulons changer la donne politique&#160;\u00bb, une conversation avec Natalie Bennett"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Au d\u00e9but du mois de mai 2021, des \u00e9lections ont eu lieu dans une grande partie du Royaume-Uni&#160;: des \u00e9lections locales en Angleterre, des <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/05\/09\/resultats-des-elections-au-parlement-ecossais\/\">\u00e9lections parlementaires en \u00c9cosse<\/a> et des <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/05\/10\/resultats-des-elections-au-parlement-gallois\/\">\u00e9lections locales et parlementaires au Pays de Galles<\/a>. Quelles sont les principales tendances des r\u00e9sultats&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Ce que les r\u00e9sultats montrent avant tout, c&rsquo;est que les plaques tectoniques se d\u00e9placent, tant sur le plan g\u00e9ographique que d\u00e9mographique. Les \u00e9lections sont pr\u00e9sent\u00e9es comme d\u00e9sastreuses pour les travaillistes et de bon augure pour les <em>Tories<\/em> [conservateurs], mais ce n&rsquo;est pas si simple. Le <em>Labour<\/em> perd des voix dans le nord de l&rsquo;Angleterre et dans les villes c\u00f4ti\u00e8res pauvres, et les <em>Tories<\/em> les r\u00e9cup\u00e8rent. Mais les <em>Tories<\/em> perdent des voix dans les r\u00e9gions les plus riches du Royaume-Uni, en particulier dans le sud et le sud-ouest de l&rsquo;Angleterre. Pendant ce temps, les travaillistes ont obtenu de bons r\u00e9sultats au Pays de Galles et le <em>Scottish National Party<\/em> (SNP) est presque totalement dominant en \u00c9cosse, malgr\u00e9 un syst\u00e8me \u00e9lectoral \u00e9quitable et proportionnel. Il n&rsquo;a manqu\u00e9 qu&rsquo;un seul si\u00e8ge au SNP pour obtenir la majorit\u00e9 au Parlement \u00e9cossais et, avec les Verts pro-ind\u00e9pendance, il d\u00e9tient la majorit\u00e9 du pouvoir. C&rsquo;est une v\u00e9ritable fracture de la politique britannique&#160;: les travaillistes sont forts au Pays de Galles, le SNP domine avec le soutien des Verts en \u00c9cosse, et l&rsquo;Angleterre est divis\u00e9e, le clivage nord-sud \u00e9tant d\u00e8s lors renvers\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les Verts ont \u00e9galement progress\u00e9 dans toute l&rsquo;Angleterre, au nord comme au sud.<\/strong><\/h3>\n\n\n\n<p>Les Verts ont fait une tr\u00e8s bonne \u00e9lection, obtenant 99 si\u00e8ges suppl\u00e9mentaires. Nombre d&rsquo;entre eux sont des si\u00e8ges de conseils de comt\u00e9s importants et les Verts ont \u00e9galement obtenu un si\u00e8ge suppl\u00e9mentaire \u00e0 l&rsquo;Assembl\u00e9e de Londres. Les Verts sont arriv\u00e9s troisi\u00e8me \u00e0 l&rsquo;\u00e9lection du maire de Londres &#8211; avec deux fois plus de voix que les lib\u00e9raux-d\u00e9mocrates &#8211; et ont termin\u00e9 deuxi\u00e8me dans la course \u00e0 la mairie de Bristol. C&rsquo;est un \u00e9norme pas en avant. \u00c0 Bristol, il y a d\u00e9sormais 24 conseillers verts, \u00e0 \u00e9galit\u00e9 avec les travaillistes. C&rsquo;est le plus grand groupe de conseillers verts jamais constitu\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les \u00e9lections locales de 2018 et 2019, ainsi que la derni\u00e8re \u00e9lection europ\u00e9enne, ont \u00e9t\u00e9 \u00e9galement tr\u00e8s r\u00e9ussies pour les Verts. Qu&rsquo;est-ce que cela indique, et d&rsquo;o\u00f9 vient ce soutien&#160;?<\/strong><\/h3>\n\n\n\n<p>Tout d&rsquo;abord, cela d\u00e9montre qu&rsquo;il existe une base d&rsquo;environ 11 ou 12&#160;% d&rsquo;\u00e9lecteurs qui soutiennent le Parti vert. Dans n&rsquo;importe quel syst\u00e8me proportionnel, cela donnerait un r\u00e9sultat tout \u00e0 fait honorable. Lors de ces derni\u00e8res \u00e9lections locales, le professeur John Curtis, un commentateur tr\u00e8s respect\u00e9, a calcul\u00e9 que nous avions obtenu environ 11&#160;% des voix. Deuxi\u00e8mement, cela montre que le parti a atteint un nouveau niveau de professionnalisme et d&rsquo;organisation. En 2019, nous avons plus que doubl\u00e9 notre nombre de conseillers en une seule \u00e9lection. Cette fois-ci, les Verts ont r\u00e9alis\u00e9 un gain de 99 conseillers et un gain net de 93 conseillers. Nous avons maintenant les comp\u00e9tences, le professionnalisme et l&rsquo;organisation pour gagner presque tous les si\u00e8ges que nous ciblons. Ce qui est frappant, c&rsquo;est que les gains sont presque \u00e9galement r\u00e9partis entre les conservateurs et les travaillistes. Ils refl\u00e8tent toutes les tendances, du conseil de comt\u00e9 de Mid-Suffolk, qui est une r\u00e9gion agricole rurale, \u00e0 Bristol, qui est une ville tr\u00e8s jeune et \u00e9duqu\u00e9e. Il y a maintenant des conseillers de comt\u00e9 de partout&#160;: de Cornwall \u00e0 Cumbria et de Northumberland \u00e0 East Sussex. Nous avons maintenant cinq conseillers \u00e0 Burnley, l&rsquo;un des si\u00e8ges du \u00ab&#160;mur rouge&#160;\u00bb du Grand Manchester, o\u00f9 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/brexit-party-ou-litalianisation-de-la-politique-britannique\/\">le parti UKIP<\/a> \u00e9tait particuli\u00e8rement fort il y a quelques ann\u00e9es. Les Verts \u00e9taient le plus grand des petits partis, mais nous pouvons maintenant pr\u00e9tendre \u00e0 devenir l\u2019un des grands partis.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les Verts \u00e9taient le plus grand des petits partis, mais nous pouvons maintenant pr\u00e9tendre \u00e0 devenir l&rsquo;un des grands partis.<\/p><cite>NATALIE BENNETT<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle importance ont eu le climat et les questions \u00e9cologiques classiques dans le r\u00e9sultat&#160;? La vision plus large du parti a-t-elle jou\u00e9 un r\u00f4le plus important&#160;?<\/strong><\/h3>\n\n\n\n<p>Il y a trois \u00e9l\u00e9ments et l&rsquo;importance de chacun varie selon les endroits. Premi\u00e8rement, il y a une cohorte croissante de personnes qui votent uniquement pour des questions de climat et de biodiversit\u00e9. \u00c0 Bristol, l&rsquo;un de nos nouveaux conseillers municipaux est un jeune de 18 ans qui a \u00e9t\u00e9 l&rsquo;un des principaux organisateurs de l&rsquo;\u00e9norme marche pour le climat, forte de 10 000 personnes, \u00e0 laquelle Greta Thunberg a particip\u00e9 en 2019. Les questions climatiques aident \u00e0 construire ce soutien de base. Deuxi\u00e8mement, nous constatons \u00e9galement que les conseillers Verts se sont montr\u00e9s efficaces. Les Verts ont des conseillers dans le Mid-Suffolk depuis un certain temps et ils ont construit leur r\u00e9putation en prenant l&rsquo;avenir de l&rsquo;agriculture au s\u00e9rieux et en travaillant pour les petites entreprises agricoles et les autres entreprises ind\u00e9pendantes. Troisi\u00e8mement, le profond m\u00e9contentement \u00e0 l&rsquo;\u00e9gard du gouvernement local au Royaume-Uni est une opportunit\u00e9 pour la politique verte. \u00c0 Sheffield, nous avons pris la municipalit\u00e9 sans majorit\u00e9 absolue. Il s&rsquo;agissait d&rsquo;un bastion travailliste, mais il y a eu une \u00e9norme dispute sur l&rsquo;abattage des arbres de rue dans la ville. De nombreux \u00e9lecteurs \u00e9taient m\u00e9contents de ce qui avait \u00e9t\u00e9 per\u00e7u comme un conseil sans voix dissonantes avec une domination massive des travaillistes pendant des d\u00e9cennies. Beaucoup de gens veulent simplement quelque chose de diff\u00e9rent et les Verts ont r\u00e9ussi \u00e0 canaliser cela.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dans quelle mesure les autres partis d\u00e9veloppent-ils leur propre \u00ab&#160;politique verte&#160;\u00bb en r\u00e9ponse aux pr\u00e9occupations du public&#160;?<\/strong><\/h3>\n\n\n\n<p>C&rsquo;est vraiment notable, notamment chez les conservateurs. Depuis 2019 environ, ils parlent vert. Et je mets un grand ast\u00e9risque \u00e0 c\u00f4t\u00e9 du mot \u00ab&#160;parle&#160;\u00bb parce que ce n&rsquo;est pas la m\u00eame chose qu&rsquo;agir vert ou qu&rsquo;avoir des politiques publiques efficaces en la mati\u00e8re. Le gouvernement britannique a r\u00e9cemment essay\u00e9 de consacrer 2 milliards de livres \u00e0 l\u2019efficience \u00e9nerg\u00e9tique des foyers dans le cadre de la reprise \u00e9conomique apr\u00e8s la crise du Covid-19. Le plan \u00e9tait un g\u00e2chis et ils ont d\u00e9pens\u00e9 une infime partie de l&rsquo;argent avant de le rejeter \u00e0 nouveau. Le gouvernement parle donc d&rsquo;\u00e9cologie mais ne tient pas ses promesses. Pendant ce temps, les lib\u00e9raux d\u00e9mocrates ont toujours parl\u00e9 d&rsquo;\u00e9cologie, mais plus personne ne les \u00e9coute &#8211; ils n&rsquo;ont pas d&rsquo;histoire &#8211; et les travaillistes parlent d&rsquo;un <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/09\/28\/laurence-tubiana\/\">nouveau pacte vert<\/a> mais soutiennent ensuite l&rsquo;expansion des a\u00e9roports et les nouvelles routes. Ils ne comprennent tout simplement pas la transformation qui doit avoir lieu. Les gens cherchent donc de nouvelles r\u00e9ponses. Ce mouvement se d\u00e9veloppe depuis longtemps mais, \u00e0 la suite de la pand\u00e9mie, on comprend bien que le syst\u00e8me actuel est d\u00e9faillant et qu&rsquo;il doit et va changer.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le gouvernement parle d&rsquo;\u00e9cologie mais ne tient pas ses promesses.<\/p><cite>NATALIE BENNETT<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quels sont les probl\u00e8mes \u00e9cologiques fondamentaux, autres que le climat, qui sont les plus urgents sur le plan politique au Royaume-Uni&#160;?<\/strong><\/h3>\n\n\n\n<p>Certaines personnes &#8211; en particulier les jeunes &#8211; sont particuli\u00e8rement passionn\u00e9es et pr\u00e9occup\u00e9es par la crise climatique. Mais les gens parlent surtout de la pollution de l&rsquo;air et de ses cons\u00e9quences sur la sant\u00e9. Des campagnes efficaces se d\u00e9veloppent autour de la pollution de l&rsquo;eau &#8211; li\u00e9e \u00e0 la contamination des rivi\u00e8res et des mers par les eaux us\u00e9es et les d\u00e9chets, ainsi qu&rsquo;au ruissellement agricole. Pour des raisons sanitaires et environnementales, la qualit\u00e9 des aliments et la fa\u00e7on dont ils sont produits suscitent de r\u00e9elles inqui\u00e9tudes. Ce sont donc les choses du quotidien, li\u00e9es \u00e0 la vie des citoyens, qui retiennent l&rsquo;attention.<\/p>\n\n\n\n<p>La Grande-Bretagne est l&rsquo;un des pays o\u00f9 la nature est la plus d\u00e9grad\u00e9e de la plan\u00e8te. Un rapport a class\u00e9 le Royaume-Uni au 279e rang mondial des pires pays pour la nature. La campagne est une grande source de fiert\u00e9 pour les Britanniques, mais les gens commencent \u00e0 reconna\u00eetre qu&rsquo;elle est incroyablement appauvrie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous avez mentionn\u00e9 que les plaques tectoniques de la politique britannique \u00e9taient en train de bouger. Quelle est l&rsquo;importance du Brexit dans ce mouvement&#160;?<\/strong><\/h3>\n\n\n\n<p>Le Brexit a contribu\u00e9 \u00e0 diviser les nations du Royaume-Uni. Il faut commencer par l&rsquo;\u00c9cosse, l&rsquo;Irlande du Nord et, dans une moindre mesure, le Pays de Galles. D\u00e8s avant le Brexit, l&rsquo;\u00c9cosse a organis\u00e9 un r\u00e9f\u00e9rendum d&rsquo;ind\u00e9pendance en 2014 qui n&rsquo;a pas \u00e9t\u00e9 adopt\u00e9, mais le Brexit a \u00e9norm\u00e9ment acc\u00e9l\u00e9r\u00e9 la pouss\u00e9e vers l&rsquo;ind\u00e9pendance. La volont\u00e9 de faire partie de l&rsquo;Union est un \u00e9l\u00e9ment important du d\u00e9bat. En Irlande du Nord, la fronti\u00e8re \u00ab&#160;au milieu de la mer d&rsquo;Irlande&#160;\u00bb pose d&rsquo;importantes difficult\u00e9s et les conflits violents en Irlande du Nord augmentent de mani\u00e8re inqui\u00e9tante. Au sein de la communaut\u00e9 unioniste, beaucoup ont le sentiment que le Brexit les a jet\u00e9s dans la tourmente et que la r\u00e9unification de l&rsquo;Irlande se rapproche. C&rsquo;est une situation instable et, malheureusement, tr\u00e8s pr\u00e9occupante.<\/p>\n\n\n\n<p>En Angleterre, nous assistons \u00e9galement \u00e0 un r\u00e9alignement, la culture devenant au moins aussi importante que l&rsquo;\u00e9conomie. L&rsquo;ancienne r\u00e8gle selon laquelle les travaillistes sont synonymes de classe ouvri\u00e8re et les conservateurs de classe moyenne et sup\u00e9rieure n\u2019a plus aucun sens. Le Brexit n&rsquo;en est pas la cause, mais il a encourag\u00e9 cette transformation. Les Tories veulent garder les \u00e9lecteurs qu&rsquo;ils ont gagn\u00e9s gr\u00e2ce au Brexit et, de plus en plus, ils font de la surench\u00e8re en disant aux si\u00e8ges travaillistes traditionnels&#160;: &#160;\u00bb Votez pour nous et nous vous donnerons de l&rsquo;argent. &#160;\u00bb C&rsquo;est une forme de politique extr\u00eamement client\u00e9liste et transactionnelle, et cela leur a permis de remporter l&rsquo;\u00e9lection partielle de Hartlepool.<\/p>\n\n\n\n<p>Les conservateurs dirigent la politique britannique dans l\u2019optique de rester longtemps au pouvoir.<\/p>\n\n\n\n<p>Ils sont au pouvoir depuis 11 ans et ils ne sont pas pr\u00eats \u00e0 y renoncer. En 2019, 44&#160;% des votants (24&#160;% de la population) ont vot\u00e9 pour les conservateurs et ils d\u00e9tiennent 100&#160;% du pouvoir. Avant la prochaine \u00e9lection, ils vont encore d\u00e9couper les circonscriptions \u00e9lectorales (<em>gerrymandering<\/em>) et ils ont \u00e9galement annonc\u00e9 l&rsquo;introduction de l&rsquo;identification des \u00e9lecteurs. C&rsquo;est une importation directe des tactiques de suppression des \u00e9lecteurs des \u00c9tats-Unis.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qu&rsquo;en est-il de la vision des Verts sur l&rsquo;avenir du Royaume-Uni lui-m\u00eame&#160;?<\/strong><\/h3>\n\n\n\n<p>L&rsquo;autod\u00e9termination est notre position philosophique. Les Verts \u00e9cossais sont devenus un parti ind\u00e9pendant en 1990 et la d\u00e9cision prise \u00e0 l&rsquo;\u00e9poque \u00e9tait que, sur les questions purement \u00e9cossaises, nous nous inspirerions des Verts \u00e9cossais. Les Verts du reste du Royaume-Uni n&rsquo;ont pas de position sur l&rsquo;ind\u00e9pendance de l&rsquo;Ecosse. C&rsquo;est \u00e0 l&rsquo;Ecosse et aux Verts \u00e9cossais de d\u00e9cider ce qu&rsquo;ils veulent faire, et nous les soutiendrons. Notre parti vert gallois a \u00e9galement chang\u00e9 r\u00e9cemment sa position pour devenir plus fortement pro-ind\u00e9pendance. S&rsquo;il devait y avoir un r\u00e9f\u00e9rendum au Pays de Galles, ils feraient campagne pour l&rsquo;ind\u00e9pendance galloise.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les Verts du reste du Royaume-Uni n&rsquo;ont pas de position sur l&rsquo;ind\u00e9pendance de l&rsquo;\u00c9cosse. C&rsquo;est \u00e0 l&rsquo;\u00c9cosse et aux Verts \u00e9cossais de d\u00e9cider de ce qu&rsquo;ils veulent faire, et nous les soutiendrons.<\/p><cite>NATALIE BENNETT<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le Brexit a maintenant eu lieu et la Grande-Bretagne est sortie de l&rsquo;Union. En tant que parti pro-Remain, quelle est la vision des Verts sur la future relation de la Grande-Bretagne avec l&rsquo;Union&#160;?<\/strong><\/h3>\n\n\n\n<p>Nous cherchons \u00e0 \u00e9viter autant de dommages que possible. Cela signifie faire de notre mieux pour d\u00e9fendre le programme Erasmus+ et l&rsquo;importance de r\u00e9tablir les relations traditionnelles de jumelage entre les villes, par le biais des \u00e9coles par exemple. Ces liens ont \u00e9t\u00e9 bris\u00e9s au niveau de Westminster, nous allons donc essayer de les reconstruire par la base. Au Parlement, nous essayons de prot\u00e9ger le secteur des services&#160;: tout le monde, des musiciens aux comptables, se bat maintenant pour op\u00e9rer au sein de l&rsquo;Union. La pand\u00e9mie a masqu\u00e9 ces probl\u00e8mes, mais ils vont devenir de plus en plus visibles avec l&rsquo;ouverture des fronti\u00e8res. Du point de vue des droits des citoyens, de nombreuses personnes se retrouvent bloqu\u00e9es. En tant que Verts, nous luttons contre le feu et essayons de minimiser les d\u00e9g\u00e2ts. \u00c0 cet \u00e9gard, je suis heureuse de dire que nous faisons toujours partie du Parti vert europ\u00e9en et, d&rsquo;une certaine mani\u00e8re, les liens sont plus forts aujourd&rsquo;hui qu&rsquo;ils ne l&rsquo;ont jamais \u00e9t\u00e9.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Il y a un d\u00e9bat en cours en Europe \u00e0 propos du positionnement europ\u00e9en entre les \u00c9tats-Unis et la Chine. Comment voyez-vous la place de la Grande-Bretagne dans le monde apr\u00e8s le Brexit&#160;?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Nous parlerons de la Grande-Bretagne en tant qu&rsquo;\u00c9tat europ\u00e9en et nous nous concentrerons sur nos liens avec nos voisins, notamment en ce qui concerne les relations personnelles et humaines. Si l&rsquo;on consid\u00e8re les acteurs g\u00e9opolitiques, du point de vue des Verts, l&rsquo;Europe est la plus proche des valeurs que nous souhaitons pour le Royaume-Uni&#160;: la d\u00e9fense des droits de l&rsquo;homme, de l&rsquo;\u00c9tat de droit, la protection des personnes vuln\u00e9rables et la promotion des droits sociaux sont autant de valeurs essentielles \u00e0 nos yeux. La vision verte du Royaume-Uni est celle d&rsquo;un pays qui fonctionne de la m\u00eame mani\u00e8re que les pays scandinaves dans le monde, \u00e0 la fois en termes de contribution \u00e0 l&rsquo;aide au d\u00e9veloppement international et de promotion de la paix, par exemple par le biais des Nations unies. Je l&rsquo;appelle parfois \u00ab&#160;Super Norv\u00e8ge&#160;\u00bb. La Norv\u00e8ge a une influence tr\u00e8s positive dans le monde, et le Royaume-Uni, compte tenu de sa taille, pourrait potentiellement en faire encore plus.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La Grande-Bretagne a une difficult\u00e9 historique particuli\u00e8re avec la Chine qui d\u00e9coule de la p\u00e9riode coloniale.<\/strong><\/h3>\n\n\n\n<p>La Grande-Bretagne est signataire avec la Chine de la D\u00e9claration commune, qui est cens\u00e9e prot\u00e9ger les droits des habitants de Hong Kong. L&rsquo;un des rares domaines o\u00f9 le gouvernement m\u00e9rite un certain cr\u00e9dit est sa position relativement ferme dans la d\u00e9fense des droits des habitants de Hong Kong. Le traitement des Ou\u00efghours par l&rsquo;\u00c9tat chinois est \u00e9galement tr\u00e8s inqui\u00e9tant \u00e0 l&rsquo;\u00e9chelle internationale. Le monde ne peut vraiment pas, une fois de plus, rester sans rien faire et permettre qu&rsquo;un peuple soit trait\u00e9 de cette mani\u00e8re.<\/p>\n\n\n\n<p>Les relations entre la Grande-Bretagne et la Chine traversent une phase particuli\u00e8rement complexes et rel\u00e8vent du jeu d\u2019\u00e9quilibrisme. L&rsquo;ancien Premier ministre David Cameron \u00e9tait d\u00e9sireux de nouer des liens \u00e9conomiques \u00e9troits avec la Chine mais, au cours des deux derni\u00e8res ann\u00e9es, l&rsquo;extr\u00eame droite du parti conservateur s&rsquo;est montr\u00e9e de plus en plus pr\u00e9occup\u00e9e par la Chine sur le plan militaire. Le gouvernement a \u00e9t\u00e9 pouss\u00e9 dans une direction beaucoup moins pro-chinoise et vient d&rsquo;adopter le projet de loi sur la s\u00e9curit\u00e9 nationale et l&rsquo;investissement, \u00e9galement connu sous le nom de projet de loi Huawei, adoptant une approche beaucoup moins enthousiaste concernant l&rsquo;argent \u00e9tranger, quelle qu&rsquo;en soit la source, par rapport \u00e0 ce qui \u00e9tait en vigueur jusqu&rsquo;\u00e0 pr\u00e9sent.<\/p>\n\n\n\n<p>D\u00e9fendre les droits de l&rsquo;homme et la d\u00e9mocratie dans le monde signifie parfois que l&rsquo;on se retrouve sur une plateforme avec des personnes avec lesquelles on ne partage pas grand-chose. En particulier parce que les droits de l&rsquo;homme et l&rsquo;\u00c9tat de droit sont des principes que, traditionnellement, les gens utilisent comme une arme pour battre leurs rivaux, tout en ignorant tranquillement ce que font leurs alli\u00e9s. L&rsquo;exemple \u00e9vident est l&rsquo;Arabie Saoudite. La Grande-Bretagne continue de lui vendre des quantit\u00e9s massives d&rsquo;armes, malgr\u00e9 ses terribles violations des droits de l&rsquo;homme, tant en Arabie saoudite que pendant la guerre au Y\u00e9men. Le d\u00e9bat sur la Chine est donc aussi une v\u00e9ritable occasion de souligner que les droits de l&rsquo;homme et l&rsquo;\u00c9tat de droit sont des normes internationales. S&rsquo;ils \u00e9taient appliqu\u00e9s de mani\u00e8re \u00e9gale dans le monde entier, ce serait le fondement d&rsquo;un autre type de monde.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le d\u00e9bat sur la Chine est une v\u00e9ritable occasion de souligner que les droits de l&rsquo;homme et l&rsquo;\u00c9tat de droit sont des normes internationales.<\/p><cite>NATALIE BENNETT<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelles sont les priorit\u00e9s des Verts pour les deux ou trois prochaines ann\u00e9es&#160;?<\/strong><\/h3>\n\n\n\n<p>Nous pensons d\u00e9sormais clairement \u00e0 tous les niveaux de la politique. L&rsquo;\u00c9cosse est une \u00e9chelle totalement diff\u00e9rente parce que les Verts \u00e9cossais auront une grande partie du pouvoir et pourront, comme ils l&rsquo;ont fait avec le dernier parlement \u00e9cossais en place, mettre en \u0153uvre des parties importantes de leur programme politique. Si l&rsquo;on regarde plus largement le Royaume-Uni, les Verts sont maintenant le troisi\u00e8me parti le plus populaire en Angleterre. Nous voulons construire sur cette base et \u00e9lire plus de membres du Parlement \u00e0 Westminster. Nous pouvons changer la donne politique.<\/p>\n\n\n\n<p>Les partis travailliste et conservateur sont tr\u00e8s instables, et si vous regardez ce qui se passe en Allemagne &#8211; qui a un syst\u00e8me \u00e9lectoral diff\u00e9rent &#8211; les Verts allemands ont acquis une place similaire \u00e0 celle du parti travailliste. Notre objectif \u00e0 long terme est de devenir l&rsquo;un des deux plus grands partis du Royaume-Uni. Dans un monde id\u00e9al, les contradictions de notre gouvernement d&rsquo;extr\u00eame-droite actuel finiront par s&rsquo;effondrer et ils s&rsquo;\u00e9craseront. Peut-\u00eatre pourrions-nous nous retrouver avec le Parti travailliste et les Verts au sommet de la politique britannique&#160;?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le syst\u00e8me uninominal \u00e0 un tour jette une ombre sur la croissance r\u00e9guli\u00e8re des Verts au Royaume-Uni. En 1989, le parti vert a obtenu pr\u00e8s de 15&#160;% des voix mais le syst\u00e8me \u00e9lectoral a entrav\u00e9 sa progression pendant des d\u00e9cennies. Comment le parti a-t-il pu continuer \u00e0 cro\u00eetre dans l&rsquo;ombre&#160;?<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Nous faisons campagne pour que le Royaume-Uni devienne une d\u00e9mocratie, car il ne l&rsquo;est pas actuellement. Mais les Verts d\u00e9montrent \u00e9galement que nous ne devons pas attendre la repr\u00e9sentation proportionnelle. En raison de notre syst\u00e8me \u00e9lectoral, les Verts britanniques &#8211; en Angleterre, en particulier &#8211; savent ce que c&rsquo;est que d&rsquo;avoir besoin de 45&#160;% des voix pour gagner un si\u00e8ge. Certains conseillers municipaux obtiennent 60 \u00e0 70&#160;% des voix. Nous savons donc ce que c&rsquo;est que de gagner et nous avons les comp\u00e9tences n\u00e9cessaires pour obtenir des parts de voix tr\u00e8s \u00e9lev\u00e9es. C&rsquo;est quelque chose que nous pouvons partager avec nos amis europ\u00e9ens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon Natalie Bennett, qui a dirig\u00e9 le parti en Angleterre et au Pays de Galles, le statut des Verts au Royaume-Uni en tant que force politique importante dans le paysage politique ne fait plus d\u00e9bat. Mais dans une p\u00e9riode o\u00f9 les lignes de division politique sont en train d&rsquo;\u00eatre redessin\u00e9es, et o\u00f9 les anciennes loyaut\u00e9s envers les partis semblent en suspens, comment les Verts peuvent-ils s\u2019am\u00e9nager un espace politique propre et continuer \u00e0 gagner du terrain&#160;&#160;? <\/p>\n","protected":false},"author":1782,"featured_media":123213,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":13,"footnotes":""},"categories":[3019],"tags":[],"staff":[1971,2966],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-123045","post","type-post","status-publish","format-standard","hentry","category-verts-en-europe","staff-edouard-gaudot","staff-jamie-kendrick","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":123213,"excerpt":"Selon Natalie Bennett, qui a dirig\u00e9 le parti en Angleterre et au Pays de Galles, le statut des Verts au Royaume-Uni en tant que force politique importante dans le paysage politique ne fait plus d\u00e9bat. Mais dans une p\u00e9riode o\u00f9 les lignes de division politique sont en train d'\u00eatre redessin\u00e9es, et o\u00f9 les anciennes loyaut\u00e9s envers les partis semblent en suspens, comment les Verts peuvent-ils s\u2019am\u00e9nager un espace politique propre et continuer \u00e0 gagner du terrain ? ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00ab Nous voulons changer la donne politique \u00bb, une conversation avec Natalie Bennett | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab Nous voulons changer la donne politique \u00bb, une conversation avec Natalie Bennett | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Selon Natalie Bennett, qui a dirig\u00e9 le parti en Angleterre et au Pays de Galles, le statut des Verts au Royaume-Uni en tant que force politique importante dans le paysage politique ne fait plus d\u00e9bat. Mais dans une p\u00e9riode o\u00f9 les lignes de division politique sont en train d&#039;\u00eatre redessin\u00e9es, et o\u00f9 les anciennes loyaut\u00e9s envers les partis semblent en suspens, comment les Verts peuvent-ils s\u2019am\u00e9nager un espace politique propre et continuer \u00e0 gagner du terrain&#160;?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/gc-bennett-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"clementf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/gc-bennett-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"clementf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/\",\"name\":\"\u00ab Nous voulons changer la donne politique \u00bb, une conversation avec Natalie Bennett | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg\",\"datePublished\":\"2021-10-13T16:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg\",\"width\":1523,\"height\":2560,\"caption\":\"Mandatory Credit: Photo by LNP\/REX Shutterstock (4743592c) Natalie Bennett, Leader of the Green Party of England and Wales, campaigns in Islington, London, with local Green candidate Caroline Russell. Green Party general election campaigning, Islington, London, Britain - 03 May 2015 \/Rex_Green_Party_general_election_campaigning_Isling_4743592C\/\/1505032223\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Nous voulons changer la donne politique&#160;\u00bb, une conversation avec Natalie Bennett\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84\",\"name\":\"clementf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g\",\"caption\":\"clementf\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab Nous voulons changer la donne politique \u00bb, une conversation avec Natalie Bennett | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab Nous voulons changer la donne politique \u00bb, une conversation avec Natalie Bennett | Le Grand Continent","og_description":"Selon Natalie Bennett, qui a dirig\u00e9 le parti en Angleterre et au Pays de Galles, le statut des Verts au Royaume-Uni en tant que force politique importante dans le paysage politique ne fait plus d\u00e9bat. Mais dans une p\u00e9riode o\u00f9 les lignes de division politique sont en train d'\u00eatre redessin\u00e9es, et o\u00f9 les anciennes loyaut\u00e9s envers les partis semblent en suspens, comment les Verts peuvent-ils s\u2019am\u00e9nager un espace politique propre et continuer \u00e0 gagner du terrain&#160;?","og_url":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/","og_site_name":"Le Grand Continent","article_published_time":"2021-10-13T16:00:00+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/gc-bennett-scaled.jpg","type":"image\/jpeg"}],"author":"clementf","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/gc-bennett-scaled.jpg","twitter_misc":{"\u00c9crit par":"clementf","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/","url":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/","name":"\u00ab Nous voulons changer la donne politique \u00bb, une conversation avec Natalie Bennett | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg","datePublished":"2021-10-13T16:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg","width":1523,"height":2560,"caption":"Mandatory Credit: Photo by LNP\/REX Shutterstock (4743592c) Natalie Bennett, Leader of the Green Party of England and Wales, campaigns in Islington, London, with local Green candidate Caroline Russell. Green Party general election campaigning, Islington, London, Britain - 03 May 2015 \/Rex_Green_Party_general_election_campaigning_Isling_4743592C\/\/1505032223"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/13\/nous-voulons-changer-la-donne-politique-une-conversation-avec-natalie-bennett\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Nous voulons changer la donne politique&#160;\u00bb, une conversation avec Natalie Bennett"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/b22879caf2a074c0786f019573977c84","name":"clementf","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41f278c3339276cfdaa0b30a33819066?s=96&d=mm&r=g","caption":"clementf"}}]}},"lgc_categories":[{"id":3019,"name":"Verts en Europe","slug":"verts-en-europe"}],"lgc_author":{"id":1971,"name":"\u00c9douard Gaudot","slug":"edouard-gaudot","description":"\u00c9douard Gaudot est consultant en Affaires europ\u00e9ennes, ancien conseiller politique du groupe Verts\/ALE au Parlement europ\u00e9en","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/09\/gc-gaudot.png","width":292,"height":284,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg","width":1523,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/10\/SIPA_REX40374206_000012-scaled-e1634115747471.jpg","width":1523,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/123045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1782"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=123045"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/123045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/123213"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=123045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=123045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=123045"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=123045"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=123045"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=123045"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=123045"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=123045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}