{"id":105323,"date":"2021-04-08T09:59:35","date_gmt":"2021-04-08T07:59:35","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=105323"},"modified":"2021-04-08T11:04:06","modified_gmt":"2021-04-08T09:04:06","slug":"crise-au-myanmar-new-delhi-face-au-dilemme-birman","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/","title":{"rendered":"Crise au Myanmar&#160;: New Delhi face au dilemme birman"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>Apr\u00e8s un \u00e9t\u00e9 2020 o\u00f9 la fronti\u00e8re himalayenne partag\u00e9e avec la Chine au nord-ouest du pays <a href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/24\/frontiere-sino-indienne\/\">fut au c\u0153ur de l\u2019actualit\u00e9<\/a>, ce sont les fronti\u00e8res orientales de l\u2019Inde qui retiennent l\u2019attention en ce d\u00e9but de printemps 2021.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>D\u2019abord parce que le Premier ministre indien, Narendra Modi, a entam\u00e9 le 26&nbsp;&nbsp;une visite au Bangladesh \u00e0 l\u2019occasion du 50e anniversaire du lancement du mouvement de lib\u00e9ration nationale dans ce qui \u00e9tait encore le Pakistan oriental et au succ\u00e8s duquel l\u2019Inde apporta un concours d\u00e9cisif fin 1971. Une visite qui co\u00efncide avec les campagnes \u00e9lectorales qui d\u00e9roulent dans deux \u00c9tats de l\u2019Union indienne frontaliers du Bangladesh&nbsp;&#160;: le Bengale occidental et l\u2019Assam. Dans le premier cas, le Bharatiya Janata Party esp\u00e8re arriver au pouvoir dans un \u00c9tat qui n\u2019a plus \u00e9t\u00e9 gouvern\u00e9 par le parti dominant au niveau national depuis 1977 lorsque les communistes indiens sont arriv\u00e9s au pouvoir \u00e0 Calcutta. Ils y sont rest\u00e9s jusqu\u2019en 2011 avant de c\u00e9der la place \u00e0 l\u2019actuelle ministre en chef, Mamata Banerjee du Trinamool Congress Party, un parti r\u00e9gional. En Assam, le BJP, qui a conquis l\u2019\u00c9tat en 2016, compte bien \u00eatre reconduit aux affaires. Dans les deux cas, les sentiments envers la minorit\u00e9 musulmane, dont les rangs ont \u00e9t\u00e9 grossis au fil du temps par un afflux de migrants bangladais, est un facteur de polarisation \u00e9lectorale. L\u2019adoption par New Delhi de la loi sur la citoyennet\u00e9 qui a ouvert la voie \u00e0 la naturalisation de migrants bangladais non-musulmans pourrait aussi jouer sur le choix du vote.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>La situation au Myanmar (Birmanie), qui jusqu\u2019en 1937 \u00e9tait une province de l\u2019Inde britannique, est un autre objet de pr\u00e9occupation avec un d\u00e9but d\u2019exode de Birmans fuyant la r\u00e9pression brutale men\u00e9e par l\u2019arm\u00e9e depuis le coup d\u2019\u00c9tat du 1<sup>er<\/sup>&nbsp;f\u00e9vrier.&nbsp;&nbsp;L\u2019Inde n\u2019a pas adh\u00e9r\u00e9 \u00e0 la convention de Gen\u00e8ve de 1951, ni au protocole de 1967, relatifs au droit d\u2019asile, et ne dispose pas davantage d\u2019un cadre l\u00e9gal national de protection des r\u00e9fugi\u00e9s. Toutefois, New Delhi a eu par le pass\u00e9 une attitude plut\u00f4t lib\u00e9rale \u00e0 l\u2019\u00e9gard des populations r\u00e9fugi\u00e9es, respectant le principe de non refoulement, notamment pour les Tib\u00e9tains. Dans le cas des musulmans Rohingyas fuyant les pers\u00e9cutions au Myanmar, le gouvernement des nationalistes hindous ne fut cependant pas m\u00e9content que, malgr\u00e9 1640 km de fronti\u00e8re commune, ce soit le Bangladesh qui ait \u00e0 g\u00e9rer l\u2019installation de quelque 800 000 d\u2019entre eux sur son territoire. On estime \u00e0 40000 le nombre de Rohingyas pr\u00e9sents sur le sol indien dont 6 500 \u00e0 Jammu (nord-ouest de l\u2019Inde). Leur appartenance confessionnelle ne jouent pas en leur faveur dans une p\u00e9riode o\u00f9 les musulmans peuvent \u00eatre per\u00e7us comme un risque s\u00e9curitaire. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>D\u00e9but mars, 200 de ces Rohingyas ont \u00e9t\u00e9 arr\u00eat\u00e9s \u00e0 Jammu en vue d\u2019une d\u00e9portation qu\u2019il restera difficile \u00e0 mettre en \u0153uvre. Le nouvel afflux de Birmans li\u00e9 au coup de force des militaires de Naypyidaw est de nature diff\u00e9rente.&nbsp;&nbsp;Plus de 1000 Birmans, dont des membres des forces de s\u00e9curit\u00e9 refusant d\u2019avoir \u00e0 ouvrir le feu sur les manifestants, ont d\u00e9j\u00e0 fui dans l\u2019Etat indien voisin du Mizoram en franchissant la rivi\u00e8re Tiau qui court sur une partie des 400 km de fronti\u00e8re commune. Le ministre en chef du Mizoram, Zoramthanga, pr\u00e9sident du Mizo National Front, a adress\u00e9 une lettre le 18 mars au Premier ministre indien demandant l\u2019octroi de l\u2019asile \u00e0 ces r\u00e9fugi\u00e9s politiques. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>R\u00e9pondant manifestement \u00e0 une consigne du minist\u00e8re de l\u2019Int\u00e9rieur, le gouvernement du Manipur, autre \u00c9tat de l\u2019Union indienne frontalier du Myanmar, a \u00e9mis une circulaire le 26 mars se pronon\u00e7ant contre l\u2019accueil et l\u2019ouverture de camps pouvant accueillir des r\u00e9fugi\u00e9s birmans, avant finalement d\u2019annoncer son annulation trois jours plus tard et s\u2019engager \u00e0 prendre des mesures humanitaires. Les Chins du Myanmar partagent une parent\u00e9 avec les ethnies Mizo (Mizoram) et Kuki (Manipur). D\u00e9j\u00e0 en 1988, lors de la sanglante r\u00e9pression des militaires birmans contre le mouvement pour l\u2019instauration de la d\u00e9mocratie, plusieurs Chins, ainsi que d\u2019autres r\u00e9fugi\u00e9s, avaient fui au Mizoram et au Manipur o\u00f9 ils furent accueillis avec le soutien tacite des autorit\u00e9s de New Delhi.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>La situation au Myanmar plonge New Delhi dans l\u2019embarras.&nbsp;Car, si le minist\u00e8re des Affaires \u00e9trang\u00e8res a bien exprim\u00e9 sa profonde inqui\u00e9tude et le souhait de voir la d\u00e9mocratie restaur\u00e9e,&nbsp;&nbsp;les autorit\u00e9s du pays sont traditionnellement oppos\u00e9es aux sanctions internationales et r\u00e9ticentes \u00e0 prendre position sur des \u00e9v\u00e9nements int\u00e9rieurs dans un pays tiers, notamment lorsque cela a trait aux droits de l\u2019homme avec la question du Cachemire en filigrane. Le 27 mars, l\u2019Inde, en la personne de son attach\u00e9 militaire, fut un des huit pays \u00e9trangers \u00e0 \u00eatre repr\u00e9sent\u00e9 au d\u00e9fil\u00e9 militaire c\u00e9l\u00e9brant les forces arm\u00e9es birmanes, le jour m\u00eame d\u2019une r\u00e9pression particuli\u00e8rement sanglante.&nbsp;New Delhi ne souhaite surtout pas plonger un peu plus le Myanmar dans les bras de la Chine apr\u00e8s s\u2019\u00eatre employ\u00e9 ces derni\u00e8res ann\u00e9es \u00e0 offrir aux dirigeants birmans une alternative \u00e0 une sur-d\u00e9pendance envers P\u00e9kin.&nbsp;&nbsp;Ainsi l\u2019Inde a d\u00e9velopp\u00e9 avec son voisin oriental une coop\u00e9ration militaire (un protocole d\u2019accord en mati\u00e8re de d\u00e9fense fut sign\u00e9 en 2019), vendu de l\u2019armement et conduit des exercices conjoints, tout en s\u2019engageant \u00e0 financer des projets de d\u00e9veloppement d\u2019infrastructure. Le Myanmar a une ind\u00e9niable importance strat\u00e9gique pour New Delhi, non seulement parce que, historiquement la poreuse fronti\u00e8re commune a \u00e9t\u00e9 travers\u00e9e par des mouvements insurrectionnels tribaux, mais aussi parce que le Myanmar est le point d\u2019acc\u00e8s terrestre \u00e0 l\u2019Asie du sud-est, une aire g\u00e9ographique remise \u00e0 l\u2019honneur avec la \u00ab&#160;&nbsp;Act East Policy&nbsp;&#160;\u00bb annonc\u00e9e par le gouvernement Modi en 2014, relance de la \u00ab&#160;&nbsp;Look East Policy&#160;\u00bb des ann\u00e9es 1990.&nbsp;&nbsp;Il sera int\u00e9ressant de voir comment New Delhi jongle entre imp\u00e9ratifs strat\u00e9giques li\u00e9s \u00e0 la volont\u00e9 de contrer la Chine et devoir d\u2019assistance humanitaire.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La situation au Myanmar plonge New Delhi dans l\u2019embarras.\u00a0Car, si le minist\u00e8re des Affaires \u00e9trang\u00e8res a bien exprim\u00e9 sa profonde inqui\u00e9tude et le souhait de voir la d\u00e9mocratie restaur\u00e9e,\u00a0les autorit\u00e9s du pays sont traditionnellement oppos\u00e9es aux sanctions internationales et r\u00e9ticentes \u00e0 prendre position sur des \u00e9v\u00e9nements int\u00e9rieurs dans un pays tiers, notamment lorsque cela a trait aux droits de l\u2019homme avec la question du Cachemire en filigrane. Comment les autorit\u00e9s indiennes s&rsquo;accommoderont-elles d&rsquo;une situation toujours plus instable chez leur voisin oriental&#160;&#160;?<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"footnotes":""},"categories":[1731],"tags":[],"staff":[1643],"editorial_format":[4942],"serie":[],"audience":[],"geo":[531],"class_list":["post-105323","post","type-post","status-publish","format-standard","hentry","category-politique","staff-gilles-boquerat","editorial_format-actu-breves","geo-chine"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"La situation au Myanmar plonge New Delhi dans l\u2019embarras.\u00a0Car, si le minist\u00e8re des Affaires \u00e9trang\u00e8res a bien exprim\u00e9 sa profonde inqui\u00e9tude et le souhait de voir la d\u00e9mocratie restaur\u00e9e,\u00a0les autorit\u00e9s du pays sont traditionnellement oppos\u00e9es aux sanctions internationales et r\u00e9ticentes \u00e0 prendre position sur des \u00e9v\u00e9nements int\u00e9rieurs dans un pays tiers, notamment lorsque cela a trait aux droits de l\u2019homme avec la question du Cachemire en filigrane. Comment les autorit\u00e9s indiennes s'accommoderont-elles d'une situation toujours plus instable chez leur voisin oriental ?","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crise au Myanmar : New Delhi face au dilemme birman | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crise au Myanmar : New Delhi face au dilemme birman | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La situation au Myanmar plonge New Delhi dans l\u2019embarras.\u00a0Car, si le minist\u00e8re des Affaires \u00e9trang\u00e8res a bien exprim\u00e9 sa profonde inqui\u00e9tude et le souhait de voir la d\u00e9mocratie restaur\u00e9e,\u00a0les autorit\u00e9s du pays sont traditionnellement oppos\u00e9es aux sanctions internationales et r\u00e9ticentes \u00e0 prendre position sur des \u00e9v\u00e9nements int\u00e9rieurs dans un pays tiers, notamment lorsque cela a trait aux droits de l\u2019homme avec la question du Cachemire en filigrane. Comment les autorit\u00e9s indiennes s&#039;accommoderont-elles d&#039;une situation toujours plus instable chez leur voisin oriental&#160;?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-08T07:59:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-08T09:04:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/04\/gc-myanmar-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/04\/gc-myanmar-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/\",\"name\":\"Crise au Myanmar : New Delhi face au dilemme birman | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2021-04-08T07:59:35+00:00\",\"dateModified\":\"2021-04-08T09:04:06+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crise au Myanmar&#160;: New Delhi face au dilemme birman\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crise au Myanmar : New Delhi face au dilemme birman | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/","og_locale":"fr_FR","og_type":"article","og_title":"Crise au Myanmar : New Delhi face au dilemme birman | Le Grand Continent","og_description":"La situation au Myanmar plonge New Delhi dans l\u2019embarras.\u00a0Car, si le minist\u00e8re des Affaires \u00e9trang\u00e8res a bien exprim\u00e9 sa profonde inqui\u00e9tude et le souhait de voir la d\u00e9mocratie restaur\u00e9e,\u00a0les autorit\u00e9s du pays sont traditionnellement oppos\u00e9es aux sanctions internationales et r\u00e9ticentes \u00e0 prendre position sur des \u00e9v\u00e9nements int\u00e9rieurs dans un pays tiers, notamment lorsque cela a trait aux droits de l\u2019homme avec la question du Cachemire en filigrane. Comment les autorit\u00e9s indiennes s'accommoderont-elles d'une situation toujours plus instable chez leur voisin oriental&#160;?","og_url":"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/","og_site_name":"Le Grand Continent","article_published_time":"2021-04-08T07:59:35+00:00","article_modified_time":"2021-04-08T09:04:06+00:00","og_image":[{"width":2560,"height":1479,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/04\/gc-myanmar-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/04\/gc-myanmar-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/","url":"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/","name":"Crise au Myanmar : New Delhi face au dilemme birman | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2021-04-08T07:59:35+00:00","dateModified":"2021-04-08T09:04:06+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/04\/08\/crise-au-myanmar-new-delhi-face-au-dilemme-birman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Crise au Myanmar&#160;: New Delhi face au dilemme birman"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1643,"name":"Gilles Boqu\u00e9rat","slug":"gilles-boquerat","description":"Gilles Boqu\u00e9rat est chercheur associ\u00e9 \u00e0 la Fondation pour la recherche strat\u00e9gique.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/09\/gc-Boquerat.png","width":466,"height":445,"alt":""}},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/105323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=105323"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/105323\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=105323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=105323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=105323"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=105323"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=105323"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=105323"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=105323"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=105323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}