{"id":103341,"date":"2021-03-18T17:49:36","date_gmt":"2021-03-18T16:49:36","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=103341"},"modified":"2021-03-18T17:49:46","modified_gmt":"2021-03-18T16:49:46","slug":"quand-la-pologne-redecouvre-la-geopolitique","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/","title":{"rendered":"Quand la Pologne red\u00e9couvre la g\u00e9opolitique"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Depuis l&rsquo;effondrement de la R\u00e9publique des Deux Nations (RDN) \u00e0 la fin du XVIIIe si\u00e8cle, l\u2019Occident ne pense plus le territoire polonais en termes d\u2019ind\u00e9pendance strat\u00e9gique. Contrairement aux empires turc, allemand ou russe, cette puissante alliance polono-lituanienne &#8211; dont le projet civilisationnel et politique distinct a pendant plusieurs si\u00e8cles jou\u00e9 un r\u00f4le fondamental dans le jeu d&rsquo;\u00e9quilibre en Europe &#8211; a disparu de la r\u00e9flexion g\u00e9opolitique occidentale.<\/p>\n\n\n\n<p>Un tel oubli n\u2019a jamais eu lieu en Russie, pour laquelle les terres plates de la RDN \u00e9taient tout ce qui la s\u00e9parait de l\u2019Occident et les arm\u00e9es des puissantes monarchies europ\u00e9ennes. Affaiblie par des conflits internes, la RDN a \u00e9t\u00e9 partag\u00e9e \u00e0 la fin du XVIIIe si\u00e8cle entre la Russie, l&rsquo;Autriche et la Prusse. L&rsquo;id\u00e9e politique fondant la RDN a \u00e9t\u00e9 reprise dans l\u2019entre-deux-guerres par J\u00f3zef Pi\u0142sudski, dirigeant et homme d\u2019\u00e9tat polonais, qui a lanc\u00e9 le projet d\u2019une f\u00e9d\u00e9ration cens\u00e9e int\u00e9grer les pays situ\u00e9s dans l&rsquo;isthme mer Baltique-mer Noire (IMBMN), ainsi que d\u2019autres terres situ\u00e9es entre celui-ci et la mer Adriatique o\u00f9 le trait\u00e9 de Versailles a d\u00e9voil\u00e9 de nouvelles structures \u00e9tatiques slaves. La reprise en 1939 des hostilit\u00e9s d&rsquo;une guerre mondiale inachev\u00e9e vingt ans plus t\u00f4t n\u2019a pas permis aux successeurs de Pi\u0142sudski, d\u00e9c\u00e9d\u00e9 en 1939, de poursuivre son plan, d\u00e9nomm\u00e9 la F\u00e9d\u00e9ration entre Mers ou de l\u2019<em>Intermarium<\/em>.<\/p>\n\n\n\n<p>La mal\u00e9diction de la Pologne, de m\u00eame que d&rsquo;autres pays situ\u00e9s dans la r\u00e9gion de l\u2019IMBMN, r\u00e9side dans leur emprise \u00e9ternelle entre le marteau russe et l&rsquo;enclume allemande. La Russie, enferm\u00e9e dans la g\u00e9ographie impitoyable du nord de l&rsquo;Eurasie et craignant constamment d&rsquo;\u00eatre envahie \u00e0 travers ses plaines sans fin, a su faire sienne un effet levier pour inculquer dans la mentalit\u00e9 occidentale la conviction de son caract\u00e8re indispensable au parach\u00e8vement de la stabilit\u00e9 politique en Europe. L\u2019Allemagne, n\u2019ayant que rarement pris le risque de rivaliser les puissances maritimes Anglo-Saxonnes, s\u2019\u00e9tait concentr\u00e9e sur l\u2019expansion continentale &#8211; poursuivie de mani\u00e8re centrifuge et surtout aux d\u00e9pens des pays d&rsquo;Europe Orientale. Il a donc fallu attendre la mont\u00e9e en puissance d\u2019une marine qui a eu int\u00e9r\u00eat \u00e0 changer ce paradigme pour que les nations de l\u2019IMBMN puissent regagner la capacit\u00e9 &#8211; quoique limit\u00e9e &#8211; \u00e0 se pr\u00e9valoir de leur bien le plus pr\u00e9cieux&#160;: l\u2019importance g\u00e9opolitique colossale de leur emplacement.<\/p>\n\n\n\n<p>Ce n\u2019est qu\u2019\u00e0 la fin de la guerre froide qu\u2019une puissance, en l\u2019occurence am\u00e9ricaine, red\u00e9couvre l\u2019importance de l\u2019IMBMN et s\u2019en serve pour bloquer la force terrestre dominante qu&rsquo;\u00e9tait devenue l\u2019URSS. La strat\u00e9gie de Washington apr\u00e8s la deuxi\u00e8me guerre mondiale donnait priorit\u00e9, \u00e0 bon escient, \u00e0 la prise de contr\u00f4le am\u00e9ricaine sur la frange maritime eurasiatique. D\u00e9nomm\u00e9e \u00ab&#160;Rimland&#160;\u00bb d&rsquo;apr\u00e8s son conceptualiste et strat\u00e8ge Nicholas Spykman, celle-ci comprenait la quasi-totalit\u00e9 de l\u2019Europe, y compris la plupart de l\u2019IMBMN. La chute de l\u2019URSS a pourtant marqu\u00e9 le retour en gr\u00e2ce d\u2019une autre id\u00e9e, formul\u00e9e par Halford Mackinder dans sa fameuse d\u00e9claration&#160;: \u00ab&#160;qui contr\u00f4le l&rsquo;Europe de l&rsquo;Est contr\u00f4le l&rsquo;Heartland&#160;; qui contr\u00f4le l&rsquo;Heartland contr\u00f4le l&rsquo;\u00cele Monde&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La strat\u00e9gie de Washington apr\u00e8s la Deuxi\u00e8me guerre mondiale a donn\u00e9 la priorit\u00e9, \u00e0 bon escient, \u00e0 la prise de contr\u00f4le am\u00e9ricaine sur la frange maritime eurasiatique.<\/p><cite>Maciej Bukowski<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La d\u00e9sint\u00e9gration du Bloc de l\u2019Est a rendu possible l\u2019implantation politique des \u00c9tats-Unis au sein de l\u2019IMBMN, en d\u00e9pit de la Russie. L&rsquo;av\u00e8nement de la Pax Americana, qui a suivi l\u2019\u00e9croulement de l\u2019URSS, a red\u00e9fini les politiques \u00e9trang\u00e8res des ex-membres du Pacte de Varsovie. Auparavant dict\u00e9es directement par Moscou, elles \u00e9taient maintenant d\u00e9termin\u00e9es indirectement par Washington &#8211; dont les pays qui ont retrouv\u00e9 leur ind\u00e9pendance dans l\u2019IMBMN d\u00e9pendent au demeurant toujours pour satisfaire leurs besoins de s\u00e9curit\u00e9. Apr\u00e8s l&rsquo;\u00e9largissement de l&rsquo;OTAN en 1999, la zone d&rsquo;Europe centrale et orientale est devenue et reste, malgr\u00e9 l\u2019opposition russe, couverte par les garanties militaires am\u00e9ricaines en tant que socle central de l&rsquo;architecture s\u00e9curitaire r\u00e9gionale pour la majorit\u00e9 des pays de l\u2019IMBMN.<\/p>\n\n\n\n<p>La conviction de la capacit\u00e9 des \u00c9tats-Unis en la projection de sa puissance militaire en Eurasie a permis aux pays de l\u2019IMBMN de consacrer les 30 derni\u00e8res ann\u00e9es \u00e0 la connexion aux march\u00e9s mondiaux, ainsi qu&rsquo;\u00e0 la poursuite de l&rsquo;int\u00e9gration europ\u00e9enne. En Pologne, ces processus ne s\u2019inscrivaient gu\u00e8re dans un projet politique pr\u00e9d\u00e9finis et coh\u00e9rent, mais r\u00e9sultaient du constat que l\u2019atteinte de certains objectifs \u00e9conomiques et politiques identifi\u00e9s est indispensable pour que le pays puisse commencer \u00e0 rattraper le temps perdu sous le l\u2019\u00e8re communiste. Ces objectifs, incarn\u00e9s dans le souhait de s\u2019approcher de l\u2019occident \u00e0 travers de l&rsquo;adh\u00e9rence \u00e0 l\u2019OTAN et l\u2019UE, r\u00e9sultaient avant tout de la conviction de l\u2019incompatibilit\u00e9 des int\u00e9r\u00eats g\u00e9opolitiques de la Pologne avec ceux de la Russie. Quant \u00e0 l\u2019Allemagne, le succ\u00e8s remarquable de l\u2019int\u00e9gration de la RDA \u00e0 la RFA a att\u00e9nu\u00e9 chez les Polonais les inqui\u00e9tudes suscit\u00e9es par le plan d\u2019int\u00e9gration au projet europ\u00e9en. Il reste aujourd\u2019hui peu de cet enthousiasme des ann\u00e9es 1990, qui a c\u00e9d\u00e9 la place \u00e0 une prise de conscience envers le d\u00e9calage flagrant entre les int\u00e9r\u00eats g\u00e9opolitiques allemands et polonais. Aucun exemple r\u00e9cent ne para\u00eet plus pertinent que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/04\/nord-stream-2-administration-biden\/\">l\u2019affaire Nord Stream 2<\/a>.<\/p>\n\n\n\n<p>La d\u00e9pendance polonaise aux \u00c9tats-Unis, form\u00e9e dans les ann\u00e9es 1990, s\u2019est traduite en une alliance durable m\u00eame si d\u00e9s\u00e9quilibr\u00e9e. Dans la conception am\u00e9ricaine, la Pologne est cens\u00e9e jouer le r\u00f4le du premier bouclier contre la dimension militaire russe dans les zones g\u00e9ographiques limitrophes de l\u2019IMBMN. Il en r\u00e9sulte que la Pologne d\u00e9ploie les principales forces terrestres de la r\u00e9gion, et qu\u2019elle soit pr\u00e9munie contre les outils de la nouvelle g\u00e9n\u00e9ration de guerre hybride d\u00e9j\u00e0 en cours. Dans ce contexte, il faut souligner que l\u2019IMBMN est la zone de projection de forces la plus importante pour la Russie. Moscou est conscient que la question de son maintien en tant que puissance majeure en Europe et en Eurasie se r\u00e9soudra l\u00e0. Tandis que les \u00c9tats-Unis et l&rsquo;OTAN ont pass\u00e9 la derni\u00e8re d\u00e9cennie \u00e0 rattraper l\u2019art de la guerre asym\u00e9trique popularis\u00e9e par les actions russes, la Russie a perfectionn\u00e9 les syst\u00e8mes anti-acc\u00e8s A2AD et a restaur\u00e9 ses capacit\u00e9s en guerre sym\u00e9trique (la r\u00e9forme militaire de Serdyukov).<\/p>\n\n\n\n<p>Le mur anti-acc\u00e8s russe qui va du nord de la Baltique et tout au long du flanc oriental de l&rsquo;OTAN, de l&rsquo;Ukraine, de la Crim\u00e9e, de la mer Noire, du d\u00e9troit de Turquie et jusqu&rsquo;\u00e0 l&rsquo;est de la M\u00e9diterran\u00e9e rend difficile pour la puissance navale am\u00e9ricaine de projeter efficacement ses forces dans la r\u00e9gion en cas d\u2019escalade de conflit entre un membre de l\u2019OTAN et la Russie. Il sera par exemple probablement impossible pour la flotte am\u00e9ricaine d\u2019entrer dans la Baltique par le d\u00e9troit du Danemark. Les capacit\u00e9s am\u00e9ricaines \u00e0 venir en aide \u00e0 la Pologne et\/ou aux pays baltes d\u00e9pendront alors, le cas \u00e9ch\u00e9ant, d\u2019un accord avec l\u2019Allemagne permettant \u00e0 l\u2019US Army de traverser son territoire. En absence d\u2019un tel accord, il sera difficile pour les brigades lourdes am\u00e9ricaines d&rsquo;atteindre la Pologne&#160;; sans atteindre la Pologne, il sera impossible d\u2019aider les \u00c9tats baltes, dont la couverture par les syst\u00e8mes A2AD russes neutralise les voies a\u00e9riennes et maritimes de l\u2019OTAN. Cela signifie que l&rsquo;ind\u00e9pendance des \u00c9tats baltes d\u00e9pend notamment de la position, tant g\u00e9ographique que politique, de la Pologne. Celle-ci reste alors in\u00e9vitablement le point de mire du flanc oriental de l&rsquo;OTAN.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il reste peu aujourd&rsquo;hui de l&rsquo;enthousiaste des ann\u00e9es 1990, qui a c\u00e9d\u00e9 la place \u00e0 une prise de conscience envers le d\u00e9calage flagrant entre les int\u00e9r\u00eats g\u00e9opolitiques allemands et polonais. Aucun exemple r\u00e9cent ne para\u00eet plus pertinent que l&rsquo;affaire Nord Stream\u00a02.<\/p><cite>Maciej Bukowski<\/cite><\/blockquote><\/figure>\n\n\n\n<p>\u00c0 cette situation d\u00e9j\u00e0 complexe s\u2019ajoute la question de l&rsquo;oblast de Kaliningrad, t\u00eate de pont russe dans une zone op\u00e9rationnelle cl\u00e9 pour d&rsquo;\u00e9ventuels affrontements entre la Russie et l&rsquo;OTAN, et qui poserait pour cette derni\u00e8re des probl\u00e8mes majeurs en cas d\u2019un conflit d\u2019envergure avec Moscou. La bulle A2AD, d\u00e9ploy\u00e9e au moyen des syst\u00e8mes Kalibr et S-300\/400\/500, menacent les lignes de communication maritimes, a\u00e9riennes et terrestres de l\u2019OTAN et bloque l&rsquo;acc\u00e8s aux pays baltes par l&rsquo;isthme Suwa\u0142ki, un passage \u00e9troit d\u2019importance strat\u00e9gique sur la fronti\u00e8re polono-lituanienne et coinc\u00e9 entre les territoires russes et bi\u00e9lorusse. On ne peut non plus manquer de mentionner ici l\u2019impact qu\u2019aura l\u2019extension r\u00e9cente du trait\u00e9 \u00ab&#160;New START&#160;\u00bb limitant les arsenaux nucl\u00e9aires am\u00e9ricain et russe, qui a failli inclure les armes nucl\u00e9aires non strat\u00e9giques du type qui est d\u00e9ploy\u00e9 \u00e0 Kaliningrad.<\/p>\n\n\n\n<p>Le paysage g\u00e9opolitique et g\u00e9ostrat\u00e9gique r\u00e9gional complique davantage encore l\u2019incertitude autour de la question b\u00e9larusse. L\u2019enchev\u00eatrement des int\u00e9r\u00eats occidentaux, russes et chinois en Bi\u00e9lorussie &#8211; qui a suivi la prise de conscience de ce que le r\u00e9gime de Loukachenko est peut-\u00eatre en voie de disparition &#8211; pr\u00e9dit que l&rsquo;avenir du pays ne sera pas dict\u00e9 par son peuple. Pour la Russie, la Bi\u00e9lorussie est ce que Hong Kong ou Taiwan est \u00e0 la Chine, et bien plus, elle \u00e9loigne la fronti\u00e8re russe de l&rsquo;OTAN.&nbsp;La Chine, \u00e0 son tour, comprenant les cons\u00e9quences de l&rsquo;importance de la position g\u00e9opolitique de la Bi\u00e9lorussie, fait preuve d&rsquo;une politique de plus en plus affirm\u00e9e dans la r\u00e9gion. Ses dirigeants y voient une porte d&rsquo;entr\u00e9e \u00e0 l&rsquo;Europe occidentale pour la branche nord de la nouvelle route de la soie, et pr\u00e9f\u00e9reraient donc que Minsk soit au moins partiellement ind\u00e9pendant de Moscou. Tous les doutes \u00e9ventuels quant \u00e0 l&rsquo;int\u00e9r\u00eat de la Chine d\u2019avoir son mot \u00e0 dire dans l&rsquo;\u00e9volution de la situation bi\u00e9lorusse ont \u00e9t\u00e9 dissip\u00e9s lorsque celle-ci a re\u00e7u en d\u00e9cembre dernier un pr\u00eat chinois de 500 millions de dollars US. La Pologne, dont le terminal de transbordement ferroviaire \u00e0 Ma\u0142aszewicze re\u00e7oit d\u00e9j\u00e0 des trains en provenance de la Chine et traversant la Bi\u00e9lorussie, a tout int\u00e9r\u00eat \u00e0 d\u00e9velopper ses propres moyens pour influencer le jeu de pouvoirs \u00e0 Minsk. \u00c0 cet \u00e9gard, il n&rsquo;est pas sans importance que les terres b\u00e9larussiennes aient autrefois fait partie de la RDN. L&rsquo;\u00e9troitesse des liens sociaux et culturels entre les Polonais et les Bi\u00e9lorusses c\u00e8de la place seulement aux relations historiquement et culturellement plus serr\u00e9es que ces derniers cultivent avec le peuple russe.&nbsp;<\/p>\n\n\n\n<p>Le remaniement g\u00e9opolitique en cours, entre autres traduit par l\u2019attention presque enti\u00e8re des \u00c9tats-Unis sur la Chine et les clins d\u2019\u0153il que l\u2019Occident fait \u00e0 la Russie &#8211; notamment par les suggestions du Pr\u00e9sident Macron qu\u2019un d\u00e9gel dans les relations avec Moscou est n\u00e9cessaire &#8211; a raviv\u00e9 l\u2019opinion en Pologne que les pays de l\u2019Union europ\u00e9enne ne viendraient pas au secours de leurs alli\u00e9s en cas d\u2019un conflit majeur. Ce discours, popularis\u00e9 par le th\u00e9oricien Dr Jacek Bartosiak, contient l\u2019id\u00e9e que l\u2019\u00c9tat polonais n\u2019a qu\u2019un seul int\u00e9r\u00eat strat\u00e9gique inali\u00e9nable&#160;: garder la Russie en dehors du jeu europ\u00e9en d\u2019\u00e9quilibre.<\/p>\n\n\n\n<p>La r\u00e9\u00e9mergence de la <em>realpolitik<\/em> comme l\u2019outil principal sous-entendant la formation des rapports de pouvoir sur la sc\u00e8ne internationale a valid\u00e9 les appels \u00e0 ce que la Pologne augmente ses capacit\u00e9s militaires. L\u2019id\u00e9e dominante est d\u00e9sormais que celles-ci lui seront n\u00e9cessaires non seulement pour renforcer sa politique s\u00e9curitaire men\u00e9e en tandem avec les \u00c9tats-Unis, mais aussi pour d\u00e9velopper ses propres moyens afin de revendiquer le r\u00f4le du leader r\u00e9gional dans l\u2019IMBMN. Autrement dit, c\u2019est la prise de conscience des exigences g\u00e9opolitiques de la r\u00e9gion qui a pouss\u00e9 la Pologne \u00e0 augmenter ses d\u00e9penses d\u2019armement, plut\u00f4t que Donald Trump. Cela ne signifie pas pour autant que la Pologne esp\u00e8re achever l\u2019autosuffisance militaire et devenir ind\u00e9pendante du parapluie am\u00e9ricain&#160;; au contraire, la conviction naissante chez les dirigeants et intellectuels polonais est que l\u2019emplacement de leur pays au c\u0153ur de l\u2019IMBMN leur conf\u00e8re une marge de n\u00e9gociation, auparavant n\u00e9glig\u00e9e, dont la Varsovie devrait se servir pour tirer plus de b\u00e9n\u00e9fices de son alliance avec Washington. La Pologne a aujourd\u2019hui autant besoin des \u00c9tats-Unis que ceux-ci de la Pologne&#160;: face au cocktail de facteurs affaiblissant la pr\u00e9sence am\u00e9ricaine en Europe \u2013 la n\u00e9cessit\u00e9 de se concentrer sur l\u2019Asie, le Brexit ou l&rsquo;appel de la France \u00e0 d\u00e9velopper l\u2019autonomie strat\u00e9gique europ\u00e9enne n\u2019en \u00e9tant que trois exemples \u2013 les am\u00e9ricains ont plus que jamais int\u00e9r\u00eat \u00e0 soutenir les initiatives qui pourraient permettre de pr\u00e9server leur influence sur l&rsquo;\u00e9quilibre des forces en Europe. Notons \u00e9galement que l\u2019appel allemand au renouvellement de la relation transatlantique avec un r\u00f4le de premier plan pour les \u00c9tats-Unis, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/11\/21\/reponse-akk-macron\/\">\u00e9mis strat\u00e9giquement par Annegret Kramp-Karrenbauer en octobre dernier<\/a>, reste \u00e0 ce jour sans r\u00e9ponse de la part de l&rsquo;administration Biden.<\/p>\n\n\n\n<p>Dans cette optique, il ne surprend donc gu\u00e8re que le nouveau secr\u00e9taire d&rsquo;\u00c9tat am\u00e9ricain Antony Blinken ait d\u00e9j\u00e0 annonc\u00e9 \u2013 alors que les orientations de la politique \u00e9trang\u00e8re de l&rsquo;\u00e9quipe Biden sont encore en train d\u2019\u00eatre form\u00e9es \u2013 que Washington maintiendra son soutien accord\u00e9 \u00e0 l&rsquo;Initiative des Trois Mers (ITM) par l\u2019administration am\u00e9ricaine pr\u00e9c\u00e9dente. L\u2019ITM est le projet d&rsquo;int\u00e9gration de la r\u00e9gion de l\u2019IMBMN le plus prometteur, dont l\u2019aboutissement permettrait aux \u00c9tats-Unis de contrebalancer l&rsquo;influence allemande sur le continent \u00e0 travers une entit\u00e9 form\u00e9e des \u00c9tats-membres de l\u2019Union et soutenue par cette derni\u00e8re. Son succ\u00e8s garantirait \u00e0 Washington une place \u00e0 la table o\u00f9 Berlin, Paris, Bruxelles, Moscou et de plus en plus P\u00e9kin sont en comp\u00e9tition pour le pouvoir dans l\u2019IMBMN. La Pologne constituerait l\u2019axe principal de l\u2019ITM, donnant un coup d&rsquo;int\u00e9gration qui se propagerait au sud et sud-est du continent. Les investissement importants actuellement en cours pour d\u00e9velopper les connexions routi\u00e8res et ferroviaires nord-sud, ou la distribution du gaz am\u00e9ricain \u00e0 l&rsquo;Ukraine \u00e0 partir du port de gaz polonais c\u00f4tier \u00e0 \u015awinouj\u015bcie, doivent \u00eatre lues en ce sens.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>C&rsquo;est la prise de conscience des exigences g\u00e9opolitiques de la r\u00e9gion qui a pouss\u00e9 la Pologne \u00e0 augmenter ses d\u00e9penses d&rsquo;armement \u2013 plut\u00f4t que Donald Trump.<\/p><cite>Maciej Bukowski<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le projet de l\u2019ITM est \u00e9galement, voire surtout, pens\u00e9 comme une tentative de couvrir le d\u00e9ficit d&rsquo;investissement dans les 12 pays de l\u2019UE qui en font partie. Celui-ci est \u00e0 l\u2019heure actuelle estim\u00e9 \u00e0 plus de 500 milliards USD&#160;; il n&rsquo;est donc pas \u00e9tonnant que la premi\u00e8re \u00e9chelle dans la r\u00e9alisation de l\u2019ITM r\u00e9side dans le d\u00e9veloppement d\u2019un fond d\u2019investissement d\u00e9di\u00e9 au financement des projets d&rsquo;infrastructures, pouvant approfondir l&rsquo;int\u00e9gration r\u00e9gionale. N\u2019oublions qu\u2019il s\u2019agit d\u2019une r\u00e9gion comptant 110 millions d&rsquo;habitants, un PIB de pr\u00e8s de 1 500 milliards de dollars et un taux de croissance actuellement pr\u00e9vu entre 2,4 et 3&#160;% jusqu&rsquo;en 2030. Son potentiel \u00e9conomique \u00e9tant \u00e9vident, il ne surprit donc gu\u00e8re que m\u00eame les entreprises chinoises sont d\u00e9sormais nombreuses \u00e0 participer aux appels d&rsquo;offres publics pour la construction de routes ou de chemins de fer.<\/p>\n\n\n\n<p>Si l\u2019ITM r\u00e9ussit \u00e0 gagner du poids, elle commencera in\u00e9vitablement \u00e0 valoriser son potentiel militaire. D\u2019autres formats de coop\u00e9ration r\u00e9gionale sont en attendant mis en place pour renforcer la coop\u00e9ration militaire entre les pays constituant le flanc oriental de l&rsquo;OTAN &#8211; le plus r\u00e9cent \u00e9tant le Triangle de Lublin (TDL), initiative visant \u00e0 renforcer la coop\u00e9ration dans les domaines politique, militaire et \u00e9conomique entre la Lituanie, la Pologne et l&rsquo;Ukraine. Sign\u00e9 symboliquement dans la ville o\u00f9 fut conclue en 1569 l&rsquo;union polono-lituanienne donnant naissance \u00e0 la RDN, la d\u00e9claration trilat\u00e9rale du Triangle souligne que son objectif est de rapprocher l&rsquo;Ukraine de l\u2019UE et de l\u2019OTAN, mais aussi \u00ab&#160;d&rsquo;autres formats r\u00e9gionaux&#160;\u00bb. Tandis que les autres initiatives r\u00e9gionales au succ\u00e8s variable telles que l\u2019Initiative Centre-Europ\u00e9enne,<strong> <\/strong>le Groupe de Visegr\u00e1d ou les Neuf de Bucarest excluent g\u00e9n\u00e9ralement la coop\u00e9ration militaire du champ de leurs objectifs, le TDL s\u2019appuie sur le succ\u00e8s relatif de la Brigade lituanienne-polonaise-ukrainienne, devenue op\u00e9rationnelle peu apr\u00e8s l&rsquo;annexion de la Crim\u00e9e par la Russie.&nbsp;<\/p>\n\n\n\n<p>C&rsquo;est un secret de polichinelle que la force motrice derri\u00e8re cette entreprise est la perception du besoin de renforcer la d\u00e9fense contre les tendances r\u00e9visionnistes de Moscou. Alors qu\u2019apr\u00e8s 1991, les relations entre les trois pays ont \u00e9t\u00e9 variables, parfois tendues, la Lituanie et la Pologne partagent des objectifs communs en ce qui concerne le soutien des aspirations europ\u00e9ennes de l&rsquo;Ukraine. Suite \u00e0 l&rsquo;agression arm\u00e9e de la Russie contre l&rsquo;Ukraine d\u00e9but 2014, Vilnius et Varsovie ont d\u00e9ploy\u00e9 de grands efforts pour internationaliser le conflit russo-ukrainien et rassurer Kiev de leur soutien. Pendant longtemps, la Lituanie a \u00e9t\u00e9 le seul pays \u00e0 fournir officiellement \u00e0 l&rsquo;Ukraine des armes offensives l\u00e9tales, et la Pologne figurait parmi les principaux donateurs d&rsquo;aide militaire \u00e0 l&rsquo;Ukraine. Le premier test est peut-\u00eatre maintenant venu, \u00e0 l\u2019heure de reprise des hostilit\u00e9s \u00e0 Donbass, o\u00f9 le bombardement de positions des s\u00e9paratistes pro-russes par des drones turcs (contr\u00f4l\u00e9s \u00e0 grande distance) signale potentiellement l\u2019escalade du conflit. \u00c0 l&rsquo;avenir, le TDL pourrait peut-\u00eatre servir de point de d\u00e9part du d\u00e9veloppement de la coop\u00e9ration militaire entre les pays de l&rsquo;IDM.<\/p>\n\n\n\n<p>Il est \u00e0 noter que la renaissance de la conscience g\u00e9opolitique polonaise a \u00e9t\u00e9 remarqu\u00e9e en Russie.\u00a0<a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/06\/le-monde-vu-du-kremlin\/\">L&rsquo;agence de presse russe Regnum<\/a>, l&rsquo;un des principaux centres de propagande du r\u00e9gime de Poutine, a r\u00e9cemment d\u00e9battu de la question de la rivalit\u00e9 polono-russe pour l&rsquo;influence en Europe centrale, en particulier dans les \u00c9tats \u00ab&#160;tampons&#160;\u00bb s\u00e9parant les deux pays qui sont la Belarus et l&rsquo;Ukraine. Ledit d\u00e9bat a fait ressentir la conviction chez les penseurs d&rsquo;\u00c9tat russe, m\u00eal\u00e9e d&rsquo;\u00e9tonnement, que la Pologne tente actuellement de se servir de la complexit\u00e9 de ses relations avec la Russie pour atteindre des objectifs politiques dans les pays voisins. Selon Modest Kolerov, r\u00e9dacteur en chef de Regnum, le nouvel \u00ab&#160;imp\u00e9rialisme polonais&#160;\u00bb, arm\u00e9 de l&rsquo;outil de la politique historique, de l\u2019id\u00e9e f\u00e9d\u00e9raliste de Pi\u0142sudski et de la doctrine de Giedroyc-Miroszewski &#8211; selon laquelle la Pologne n&rsquo;a pas \u00e0 int\u00e9grer les zones frontali\u00e8res mais qu&rsquo;il lui suffira de les contr\u00f4ler et d&rsquo;en faire des protectorats &#8211; est un adversaire s\u00e9rieux pour la Russie, auquel celle-ci n&rsquo;a pas de r\u00e9ponse. Sergei Markov, l&rsquo;\u00e9minence grise dans les milieux de la pens\u00e9e strat\u00e9gique russe, a m\u00eame lanc\u00e9 un appel adress\u00e9 aux \u00e9lites polonaises dans lequel il parle de la n\u00e9cessit\u00e9 de restaurer un dialogue approfondi entre les deux pays.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Suite \u00e0 l&rsquo;agression arm\u00e9e de la Russie contre l&rsquo;Ukraine d\u00e9but 2014, Vilnius et Varsovie ont d\u00e9ploy\u00e9 de grands efforts pour internationaliser le conflit russo-ukrainien et rassurer Kiev de leur soutien. Pendant longtemps, la Lituanie a \u00e9t\u00e9 le seul pays \u00e0 fournir officiellement \u00e0 l&rsquo;Ukraine des armes offensives l\u00e9tales, et la Pologne figurait parmi les principaux donateurs d&rsquo;aide militaire \u00e0 l&rsquo;Ukraine.<\/p><cite>Maciej Bukowski<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Toutes les consid\u00e9rations pr\u00e9c\u00e9dentes ne peuvent \u00eatre conclues sans pr\u00e9ciser que le ph\u00e9nom\u00e8ne d\u00e9crit est distinct de l&rsquo;\u00e9volution du paysage politique interne de la Pologne. Alors que celle-ci se brouille r\u00e9guli\u00e8rement depuis plusieurs ann\u00e9es avec les institutions de l\u2019Union au sujet de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/12\/02\/valeurs-traites\/\">ses initiatives l\u00e9gislatives jug\u00e9es controvers\u00e9es<\/a>, les diff\u00e9rences sur les questions soci\u00e9tales ou culturelles au c\u0153ur de ces querelles n&rsquo;auront pas d&rsquo;impact sur la structuration des alliances fond\u00e9es sur des forces mesur\u00e9es et des int\u00e9r\u00eats concrets. L\u2019\u00e9veil g\u00e9opolitique de la Pologne, r\u00e9sultant du constat que le monde est \u00e0 nouveau plong\u00e9 dans la comp\u00e9tition entre factions, o\u00f9 la durabilit\u00e9 des alliances se mesure par la force objectivement appr\u00e9ci\u00e9e, se poursuivra sous les gouvernements polonais suivants quel que soit leur orientation politique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment la Pologne voit-elle le monde&#160;&#160;? Dans cette perspective inform\u00e9e, Maciej Bukowski revient sur les raisons, essentiellement endog\u00e8nes, qui ont pouss\u00e9 la Pologne \u00e0 red\u00e9couvrir une <em>realpolitik<\/em> fond\u00e9e sur un mythe fondateur crucial&#160;&#160;: le n\u0153ud strat\u00e9gique de l&rsquo;isthme mer Baltique-mer Noire. Une position qu&rsquo;il faut prendre en compte dans la g\u00e9opolitique interne de l&rsquo;Union.<\/p>\n","protected":false},"author":10,"featured_media":103353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":14,"footnotes":""},"categories":[1732],"tags":[],"staff":[2871],"editorial_format":[4944],"serie":[],"audience":[],"geo":[536],"class_list":["post-103341","post","type-post","status-publish","format-standard","hentry","category-guerre","staff-maciej-bukowski","editorial_format-actu-longues","geo-centres"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":103353,"excerpt":"Comment la Pologne voit-elle le monde ? Dans cette perspective inform\u00e9e, Maciej Bukowski revient sur les raisons, essentiellement endog\u00e8nes, qui ont pouss\u00e9 la Pologne \u00e0 red\u00e9couvrir une <em>realpolitik<\/em> fond\u00e9e sur un mythe fondateur crucial : le n\u0153ud strat\u00e9gique de l'isthme mer Baltique-mer Noire. Une position qu'il faut prendre en compte dans la g\u00e9opolitique interne de l'Union.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quand la Pologne red\u00e9couvre la g\u00e9opolitique | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand la Pologne red\u00e9couvre la g\u00e9opolitique | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Comment la Pologne voit-elle le monde&#160;? Dans cette perspective inform\u00e9e, Maciej Bukowski revient sur les raisons, essentiellement endog\u00e8nes, qui ont pouss\u00e9 la Pologne \u00e0 red\u00e9couvrir une realpolitik fond\u00e9e sur un mythe fondateur crucial&#160;: le n\u0153ud strat\u00e9gique de l&#039;isthme mer Baltique-mer Noire. Une position qu&#039;il faut prendre en compte dans la g\u00e9opolitique interne de l&#039;Union.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-18T16:49:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-18T16:49:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-poland-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-poland-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/\",\"name\":\"Quand la Pologne red\u00e9couvre la g\u00e9opolitique | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg\",\"datePublished\":\"2021-03-18T16:49:36+00:00\",\"dateModified\":\"2021-03-18T16:49:46+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand la Pologne red\u00e9couvre la g\u00e9opolitique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand la Pologne red\u00e9couvre la g\u00e9opolitique | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/","og_locale":"fr_FR","og_type":"article","og_title":"Quand la Pologne red\u00e9couvre la g\u00e9opolitique | Le Grand Continent","og_description":"Comment la Pologne voit-elle le monde&#160;? Dans cette perspective inform\u00e9e, Maciej Bukowski revient sur les raisons, essentiellement endog\u00e8nes, qui ont pouss\u00e9 la Pologne \u00e0 red\u00e9couvrir une realpolitik fond\u00e9e sur un mythe fondateur crucial&#160;: le n\u0153ud strat\u00e9gique de l'isthme mer Baltique-mer Noire. Une position qu'il faut prendre en compte dans la g\u00e9opolitique interne de l'Union.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/","og_site_name":"Le Grand Continent","article_published_time":"2021-03-18T16:49:36+00:00","article_modified_time":"2021-03-18T16:49:46+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-poland-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-poland-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/","url":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/","name":"Quand la Pologne red\u00e9couvre la g\u00e9opolitique | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg","datePublished":"2021-03-18T16:49:36+00:00","dateModified":"2021-03-18T16:49:46+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/quand-la-pologne-redecouvre-la-geopolitique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Quand la Pologne red\u00e9couvre la g\u00e9opolitique"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1732,"name":"Guerre","slug":"guerre"}],"lgc_author":{"id":2871,"name":"Maciej Filip Bukowski","slug":"maciej-bukowski","description":"Doctorant en sciences politiques \u00e0 l'Universit\u00e9 Jagellonne, dipl\u00f4m\u00e9 de l'\u00c9cole de droit de la Sorbonne et de la Cornell Law School. Auparavant juriste international, actuellement expert senior aupr\u00e8s du Minist\u00e8re du Climat et de l'Environnement en Pologne. Les opinions exprim\u00e9es dans ce texte n'engagent que l'auteur et ne peuvent en aucun cas \u00eatre attribu\u00e9es aux institutions auxquelles l'auteur est affili\u00e9.","first_name":"Maciej Filip","last_name":"Bukowski","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/Maciej-F.-Bukowski.png","width":800,"height":800,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/24012970968_e2a8b1009c_o-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/103341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=103341"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/103341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/103353"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=103341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=103341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=103341"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=103341"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=103341"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=103341"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=103341"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=103341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}