{"id":103225,"date":"2021-03-18T09:01:38","date_gmt":"2021-03-18T08:01:38","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=103225"},"modified":"2021-03-20T19:05:30","modified_gmt":"2021-03-20T18:05:30","slug":"la-commune-de-paris-1871","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/","title":{"rendered":"La Commune de Paris, 1871&#160;: \u00e9v\u00e9nement local, \u00e9v\u00e9nement global"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Proposer une nouvelle enqu\u00eate sur un \u00e9v\u00e9nement comme la Commune de Paris peut sembler une gageure. Rarement un \u00e9pisode r\u00e9volutionnaire, court qui plus est (72 jours) a en effet \u00e9t\u00e9 aussi abondamment scrut\u00e9 et \u00e9tudi\u00e9. La bibliographie r\u00e9unie en 2006 par Robert le Quillec propose pr\u00e8s de 600 pages et 5000 entr\u00e9es&#160;: romans, m\u00e9moires, r\u00e9flexions philosophiques, ou travaux de recherches. Un effort de recherche par ailleurs tr\u00e8s internationalis\u00e9, puisqu\u2019il appartient aux domaines acad\u00e9miques fran\u00e7ais, am\u00e9ricains, anglais, russes, espagnols, allemands, chinois\u2026&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-103225' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#easy-footnote-bottom-1-103225' title='Robert Le Quillec, &lt;em&gt;Bibliographie critique de la Commune de Paris&lt;\/em&gt;, Paris, la boutique de l\u2019histoire, 2006.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Les interrogations suscit\u00e9es par la Commune, pourtant, ne se sont jamais taries. Elles ont m\u00eame \u00e9t\u00e9 renouvel\u00e9es ces derni\u00e8res ann\u00e9es avec la r\u00e9actualisation de la r\u00e9f\u00e9rence \u00e0 l\u2019\u00e9v\u00e8nement dans <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/02\/14\/le-savant-et-le-mouvement\/\">de nombreuses luttes sociales et politiques, en France et dans le monde<\/a>. Quelles investigations peuvent donc encore \u00eatre propos\u00e9es&#160;?<\/p>\n\n\n\n<p>Peut-\u00eatre faut-il avant de les aborder rappeler bri\u00e8vement ce qu\u2019a \u00e9t\u00e9 la Commune de Paris.<strong>&nbsp;<\/strong>Troisi\u00e8me r\u00e9volution du 19<sup>e<\/sup> si\u00e8cle fran\u00e7ais (quatri\u00e8me si on inclut la R\u00e9volution fran\u00e7aise), elle fait irruption \u00e0 l\u2019issue d\u2019un lent \u00ab&#160;glissement&#160;\u00bb (J. Rougerie). Elle prend place dans le cadre d\u2019une guerre franco-prussienne, d\u2019un changement de r\u00e9gime r\u00e9publicain (le 4 septembre 1870), de l\u2019exp\u00e9rience douloureuse d\u2019un si\u00e8ge militaire. Apr\u00e8s la d\u00e9faite contre la Prusse est \u00e9lue une chambre \u00e0 majorit\u00e9 monarchiste qui multiplie les vexations contre la capitale, qui est alors une ville tr\u00e8s ouvri\u00e8re et r\u00e9publicaine. La tentative de reprise par le gouvernement d\u2018Adolphe Thiers de canons de la garde nationale, \u00e0 Montmartre, entra\u00eene un mouvement insurrectionnel le 18 mars qui aboutit \u00e0 la proclamation officielle de la Commune de Paris le 28 mars.<\/p>\n\n\n\n<p>On conna\u00eet bien le groupe de 79 \u00e9lus qui si\u00e8ge \u00e0 l\u2019h\u00f4tel de ville, les R. Rigault, J. Vall\u00e8s, F. Jourde, E. Varlin, et qui proclame la \u00ab&#160;R\u00e9volution victorieuse&#160;\u00bb, le 29 mars. Ce groupe se caract\u00e9rise, c\u2019est une premi\u00e8re au 19<sup>e<\/sup> si\u00e8cle, par son fort contingent d\u2019ouvriers qualifi\u00e9s (33, soit 41&#160;% du total). Les mesures prises au cours des 57 s\u00e9ances de la Commune ont \u00e9galement \u00e9t\u00e9 \u00e9tudi\u00e9es&#160;: s\u00e9paration de l\u2019\u00c9glise et de l\u2019\u00c9tat, \u00e9cole rendue la\u00efque, gratuite et obligatoire, interdiction du travail de nuit aux boulangers, interdiction des retenues sur salaire dans les ateliers et administrations\u2026 Cela en fait une exp\u00e9rience politique originale.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les mesures prises au cours des 57 s\u00e9ances de la Commune ont \u00e9galement \u00e9t\u00e9 \u00e9tudi\u00e9es&#160;: s\u00e9paration de l\u2019\u00c9glise et de l\u2019\u00c9tat, \u00e9cole rendue la\u00efque, gratuite et obligatoire, interdiction du travail de nuit aux boulangers, interdiction des retenues sur salaire dans les ateliers et administrations\u2026 Cela en fait une exp\u00e9rience politique originale.<\/p><cite>Quentin Deluermoz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ces mesures sont le fruit de d\u00e9bats entre des positions politiques plurielles qui rappellent la richesse des r\u00e9publicanismes et socialismes du 19<sup>e<\/sup> si\u00e8cle&#160;: blanquistes, internationaux, proudhoniens, jacobins, radicaux&#8230; Globalement toutefois, le r\u00e9f\u00e9rent commun, \u00e0 l\u2019H\u00f4tel de ville et sur le terrain est davantage la \u00ab&#160;R\u00e9publique d\u00e9mocratique et sociale&#160;\u00bb, qui s\u2019\u00e9tait affirm\u00e9e lors de la pr\u00e9c\u00e9dente r\u00e9volution, en 1848. Selon celle-ci, il n\u2019est pas possible de changer la forme politique (la R\u00e9publique) sans modifier l\u2019organisation sociale et \u00e9conomique, par le moyen de l\u2019Association. Le but est, dans le langage du temps \u00ab&#160;l\u2019affranchissement des servitudes&#160;\u00bb.<\/p>\n\n\n\n<p>Cependant la plupart des travaux constatent la faible dur\u00e9e de la Commune, et le peu de r\u00e9alisations effectives de ces projets. La Commune est souvent d\u00e9crite comme un brouillon. Et ce qui marque dans la Commune est sa fin, la Semaine sanglante (21-28 mai 1871), marqu\u00e9e par les incendies des grands b\u00e2timents de la ville d\u2019un c\u00f4t\u00e9 (H\u00f4tel de ville, Palais des Tuileries), le massacre des insurg\u00e9s de l\u2019autre (entre 8 000 et 20 000 morts)<\/p>\n\n\n\n<p>Tel est l\u2019\u00e9v\u00e8nement, \u00e0 la fois clair et intrigant, qu\u2019est cette derni\u00e8re r\u00e9volution du 19<sup>e<\/sup> si\u00e8cle fran\u00e7ais. Puis toutes les grilles d\u2019analyse du ph\u00e9nom\u00e8ne r\u00e9volutionnaire du XXe si\u00e8cle (marxiste, anarchiste, lib\u00e9rale, r\u00e9publicaine) lui ont \u00e9t\u00e9 appliqu\u00e9es pour essayer de comprendre sa signification, jusqu\u2019\u00e0 ce que les travaux de R. Tombs et J. Rougerie dans les ann\u00e9es 1980-2000 le r\u00e9inscrivent dans un 19<sup>e<\/sup> si\u00e8cle qu\u2019il s\u2019agissait de red\u00e9couvrir, et laissent \u00e0 nouveau le questionnement.&nbsp;<\/p>\n\n\n\n<p>Ces derni\u00e8res ann\u00e9es, de nombreuses publications de qualit\u00e9, synth\u00e9tiques ou inventives, sont parues (L. Godineau, M. C\u00e9sar, M. Cordillot, M. Audin, R. Meyssan, E. Fournier, J-F. Dupeyron, L. Bantigny\u2026) Le pari de mon ouvrage, <em>Commune(s) 1870-1871&#160;: une travers\u00e9e des mondes au 19<sup>e<\/sup> si\u00e8cle<\/em> est le suivant&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-103225' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#easy-footnote-bottom-2-103225' title='Ce texte s\u2019appuie sur cet ouvrage paru au Seuil en octobre 2020. Il reprend aussi pour partie une contribution au num\u00e9ro hors s\u00e9rie du magazine &lt;em&gt;L\u2019histoire &lt;\/em&gt;&amp;#160;; \u00ab&amp;#160;La Commune, le Grand r\u00eave de la d\u00e9mocratie directe&amp;#160;\u00bb (janvier 2021)'><sup>2<\/sup><\/a><\/span><\/span>&#160;: plut\u00f4t que de chercher \u00e0 inscrire la Commune dans un \u00ab&#160;grand r\u00e9cit&#160;\u00bb d\u00e9j\u00e0 l\u00e0, l\u2019id\u00e9e est d\u2019essayer de tirer les fils spatiaux et temporels dans lesquels elle s\u2019ins\u00e8re ou qu\u2019elle a g\u00e9n\u00e9r\u00e9 afin de mieux comprendre sa port\u00e9e et sa signification. Lui laisser la parole, en quelque sorte.<\/p>\n\n\n\n<p>La d\u00e9marche s\u2019inscrit dans la logique de mes pr\u00e9c\u00e9dents travaux d\u2019histoire sociale et culturelle du 19<sup>e<\/sup> si\u00e8cle, centr\u00e9s sur l\u2019\u00e9tude des relations sociales et des perceptions des acteurs et actrices. Cependant, l\u2019\u00e9nigme pos\u00e9e par la Commune a pouss\u00e9 \u00e0 mener plus loin le jeu d\u2019\u00e9chelle, la pratique de l\u2019interdisciplinarit\u00e9 ou l\u2019interrogation sur l\u2019incorporation possible des ordres sociaux. Dans ce but, deux d\u00e9placements y sont notamment propos\u00e9s&#160;: d\u2019une part, proposer une analyse de terrain \u00ab&#160;au ras du sol&#160;\u00bb, \u00e0 hauteur d\u2019homme et de femmes, pour observer sous un angle plus ethnographique ce qui se passe pendant la Commune.&nbsp; D\u2019autre part, sortir la Commune de son seul cadre fran\u00e7ais et la replacer dans une trame d\u2019exp\u00e9riences plus large, transnationales, imp\u00e9riales, voire globales afin de comprendre sa r\u00e9sonance. Les deux sont pens\u00e9s dans leur interaction, mais le pr\u00e9sent texte pr\u00e9sente cette derni\u00e8re dimension.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L\u2019\u00e9nigme pos\u00e9e par la Commune a pouss\u00e9 \u00e0 mener plus loin le jeu d\u2019\u00e9chelle, la pratique de l\u2019interdisciplinarit\u00e9 ou l\u2019interrogation sur l\u2019incorporation possible des ordres sociaux.<\/p><cite>Quentin Deluermoz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cette derni\u00e8re attention n\u2019allait pourtant pas de soi. Contrairement \u00e0 la R\u00e9volution fran\u00e7aise, aux r\u00e9volutions de 1830 ou au printemps des peuples de 1848, la Commune de Paris, ne s\u2019inscrit pas <em>a priori<\/em> dans une vague r\u00e9volutionnaire transnationale. Il existe certes des \u00ab&#160;Communes&#160;\u00bb, dite de province et parfois d\u00e9clar\u00e9es avant la parisienne. Mais seule l\u2019ex-capitale fait l\u2019exp\u00e9rience d\u2019une forme d\u2019autogouvernement de plusieurs semaines. Aussi, la question ets l\u00e9gitime&#160;: quelle est l\u2019ampleur la Commune&#160;? Cette incertitude est accentu\u00e9e par l\u2019historiographie&#160;: Longtemps la dimension internationale de ce que K. Marx consid\u00e9rait d\u00e8s avril 1871 comme un \u00ab&#160;point de d\u00e9part d\u2019importance dans l\u2019histoire du monde&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-103225' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#easy-footnote-bottom-3-103225' title='Lettre au Dr Kugelmann, 17 avril 1871, &lt;em&gt;cit in &lt;\/em&gt;Gareth Stedman Jones, &lt;em&gt;Karl Marx, Greatness and Illusion, &lt;\/em&gt;London, Allen Lane, 2016, p. 505'><sup>3<\/sup><\/a><\/span><\/span> est all\u00e9e de soi. Cet horizon semblait d\u2019autant plus \u00e9vident que la lecture marxiste, ou d\u2019inspiration marxiste, faisait de la Commune un moment de transition entre les r\u00e9volutions \u00ab&#160;romantiques&#160;\u00bb du XIXe si\u00e8cle, et les r\u00e9volutions \u00ab&#160;modernes&#160;\u00bb \u00e0 venir dans le monde \u2013 particuli\u00e8rement apr\u00e8s la r\u00e9volution russe de 1917. Avec le reflux des analyses marxistes, la critique des approches en termes de \u00ab&#160;diffusion&#160;\u00bb et l\u2019\u00e9tude intensifi\u00e9e de l\u2019exp\u00e9rience communale, cette lecture s\u2019est modifi\u00e9e&#160;: la \u00ab&#160;R\u00e9publique de Paris&#160;\u00bb, alors, a sembl\u00e9 moins brouillonne, mais aussi plus singuli\u00e8re, et plus parisienne. Cependant la question reste pos\u00e9e de savoir comment comprendre l\u2019impact de ces quelques mois \u00e0 une telle \u00e9chelle&#160;? Faut-il supposer comme cela a pu \u00eatre dit qu\u2019il tient essentiellement \u00e0 surinvestissement post\u00e9rieur, notamment des r\u00e9gimes socialistes du XXe si\u00e8cle&#160;? Les approches connect\u00e9es et compar\u00e9es apportent des \u00e9l\u00e9ments de r\u00e9ponse. L\u2019exercice n\u2019a alors rien d\u2019une mode (il est assez peu pratiqu\u00e9 concr\u00e8tement), et n\u2019a rien non plus d\u2019\u00e9vident. Le dispositif d\u2019enqu\u00eate pr\u00e9cis est d\u00e9crit dans l\u2019ouvrage. Mais il permet bien de renouveler les interpr\u00e9tations<\/p>\n\n\n\n<p>Cette perspective, d\u2019abord, ram\u00e8ne la Commune dans la continuit\u00e9 de la guerre de 1870. Le conflit franco-prussien de 1870 est un moment important dans la nationalisation des soci\u00e9t\u00e9s bellig\u00e9rantes. Mais il est aussi l\u2019occasion d\u2019un vaste mouvement de volontariat transnational, particuli\u00e8rement apr\u00e8s le 4 septembre. La cause fran\u00e7aise devient alors cause r\u00e9publicaine, et en particulier celle de la \u00ab&#160;R\u00e9publique universelle&#160;\u00bb. Rapidement, des milliers de volontaires internationaux viennent combattre en France au nom de la libert\u00e9 des peuples. La majorit\u00e9 sont Italiens, mais s\u2019y trouvent aussi des Polonais, des Espagnols, des Belges, des Irlandais, des Grecs, des \u00c9tats-uniens ou des Uruguayens. Ces hommes, rarement des femmes, ont souvent particip\u00e9 aux grands combats politiques de l\u2019\u00e9poque&#160;: luttes de lib\u00e9rations italiennes de 1848 et 1860, conflits polonais de 1830 et 1848, \u00ab&#160;glorieuse r\u00e9volution&#160;\u00bb espagnole de 1868, guerre civile am\u00e9ricaine de 1861-1865, fenianisme des ann\u00e9es 1850-1860\u2026 Or, non sans tension ni rejets, le mouvement se poursuit avec la proclamation de la Commune en mars. Plusieurs figures c\u00e9l\u00e8bres participent \u00e0 l\u2019aventure parisienne. Ainsi de Gustave Cluseret ou encore de Jaroslaw Dombrowski. N\u00e9 en 1837, ce fils d&rsquo;un riche propri\u00e9taire polonais, form\u00e9 \u00e0 l&rsquo;\u00e9cole militaire de Saint-P\u00e9tersbourg, prend fait et cause pour l\u2019insurrection polonaise de 1863. Arr\u00eat\u00e9, il s\u2019enfuit, fr\u00e9quente les milieux socialistes allemands, puis se rend \u00e0 Paris o\u00f9 il se rapproche de l&rsquo;A.I.T. Il part \u00e0 Lyon pendant le si\u00e8ge de 1870, puis revient en mars offrir ses services \u00e0 la Commune \u00e0 Paris. Il est \u00e9lu chef de la 12e l\u00e9gion, avant d\u2019\u00eatre nomm\u00e9 commandant en chef de la place de Paris. Les trajectoires sont cependant vari\u00e9es. Beaucoup des combattant \u00ab&#160;\u00e9trangers&#160;\u00bb sont des r\u00e9fugi\u00e9s politiques d\u00e9j\u00e0 sur place. Certains sont aussi moins connus, comme Lucien Combatz. Cet officier de ligne t\u00e9l\u00e9graphique a pourtant particip\u00e9 aux guerres d\u2019Italie dans les ann\u00e9es 1850, \u00e0 la l\u00e9gion garibaldienne au Tyrol en 1866, au corps garibaldien en Cr\u00e8te et dirig\u00e9 les volontaires aragonais dans la Siera de Ronda. Pr\u00e9sent \u00e0 Paris depuis la guerre franco-prussienne, il est nomm\u00e9 directeur des t\u00e9l\u00e9graphes sous la Commune. Loin d\u2019\u00eatre majoritaire dans la masse des combattants parisiens, ces combattants sont n\u00e9anmoins tr\u00e8s visibles en raison de leur r\u00e9putation et de leur accession fr\u00e9quente \u00e0 des postes de commandement. Les \u00e9trangers en vue ne sont pas non plus uniquement combattants. L\u00e9o Frankel, un orf\u00e8vre hongrois adh\u00e9rent \u00e0 l\u2019Internationale est l\u2019un des membres de la Commission du travail et de l\u2019\u00e9change. Son int\u00e9gration est publiquement justifi\u00e9e, \u00ab&#160;consid\u00e9rant que le drapeau de la Commune est celui de la R\u00e9publique universelle, que toute cit\u00e9 a le droit de donner le titre de citoyen aux \u00e9trangers qui la servent (\u2026)&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-103225' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#easy-footnote-bottom-4-103225' title='&lt;em&gt;Journal officiel&lt;\/em&gt;, 31 mars 1871.'><sup>4<\/sup><\/a><\/span><\/span>. Ces hommes incarnent ainsi dans la Paris insurg\u00e9 le lien entre la Commune et la \u00ab&#160;R\u00e9publique Universelle&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Rapidement, des milliers de volontaires internationaux viennent combattre en France au nom de la libert\u00e9 des peuples. La majorit\u00e9 sont Italiens, mais s\u2019y trouvent aussi des Polonais, des Espagnols, des Belges, des Irlandais, des Grecs, des \u00c9tats-uniens ou des Uruguayens.<\/p><cite>Quentin Deluermoz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>D\u2019autres relais assurent de telles connexions et l\u2019Association internationale des Travailleurs bien s\u00fbr ne saurait \u00eatre oubli\u00e9e. Depuis sa cr\u00e9ation en 1864, elle est tout \u00e0 la fois une organisation syndicale, une association politique internationale et un lieu de r\u00e9flexion et d\u2019\u00e9changes autour de th\u00e8mes tels que la libert\u00e9 des peuples ou la d\u00e9fense des prol\u00e9taires&#8230; Comme nous l\u2019avons dit, les historiens ont battu en br\u00e8che l\u2019id\u00e9e que la Commune a \u00e9t\u00e9 organis\u00e9e par l\u2019AIT. Ses membres parisiens ont tout aussi bien agi comme ouvrier qualifi\u00e9, citoyen, membre d\u2019autres organisations ou \u00e9lu d\u2019arrondissement). De plus, la d\u00e9fense du conseil g\u00e9n\u00e9ral \u00e0 Londres est timide au d\u00e9part. Elle finit n\u00e9anmoins par se faire entendre. Et l\u2019\u00e9cho est plus net parmi les sections nationales. Des manifestations de soutien sont organis\u00e9es en avril \u00e0 Londres, Gen\u00e8ve, Bruxelles ou Hambourg. Elles se m\u00ealent souvent \u00e0 d\u2019autres groupes plus ou moins li\u00e9s. Les r\u00e9publicains anglais organisent des meetings de soutien \u00e0 Londres (\u00ab&#160;Long live the Universal Republic&#160;!&#160;\u00bb). Les motifs sont \u00e0 la fois crois\u00e9s et vari\u00e9s&#160;: en Roumanie, les lib\u00e9raux c\u00e9l\u00e8brent la lutte contre l\u2019envahisseur et la tyrannie, sans percevoir la port\u00e9e socialiste de la r\u00e9volte parisienne. Ailleurs, jusqu\u2019aux \u00c9tats-Unis, elle alimente les luttes ouvri\u00e8res contre les politiques patronales. Beaucoup de ces manifestations, pas toutes en raison du si\u00e8ge, sont suivies par les instances de la Commune. Elles sont notamment recens\u00e9es au sein d\u2019une rubrique \u00ab&#160;nouvelles \u00e9trang\u00e8res&#160;\u00bb du <em>Journal officiel de la R\u00e9publique fran\u00e7aise<\/em> (qui a pris pour un jour le nom de <em>Journal officiel de la Commune<\/em>.) La Commune se voit ainsi arrim\u00e9e aux luttes sociales et politiques des ann\u00e9es 1850-1870.<\/p>\n\n\n\n<p>Serait-ce tout&#160;? L\u2019\u00e9vocation des autres Communes a peut-\u00eatre \u00e9t\u00e9 un peu rapide, surtout si l\u2019on comprend la France d\u2019alors pour ce qu\u2019elle, un \u00c9tat-nation imp\u00e9rial. Les exp\u00e9riences des Communes de Lyon, Marseille ou du Creusot, ne sauraient \u00eatre n\u00e9glig\u00e9es. Mais un mouvement r\u00e9publicain et radical s\u2019est aussi d\u00e9clench\u00e9 \u00e0 Alger et dans les principales villes de la colonie. Il s\u2019auto-d\u00e9signe comme \u00ab&#160;Commune&#160;\u00bb, en r\u00e9f\u00e9rence \u00e0 1792-1793. Or avec la proclamation de la Commune parisienne, les radicaux d\u2019Alger envoient une adresse de f\u00e9licitations et d\u2019adh\u00e9sion \u00e0 la Commune. L\u2019une des figures du mouvement alg\u00e9rois, Alexandre Lambert, se voit m\u00eame promu d\u00e9l\u00e9gu\u00e9 de l\u2019Alg\u00e9rie aupr\u00e8s de la Commune, avant de devenir \u00ab&#160;chef de bureau au minist\u00e8re de l\u2019int\u00e9rieur (presse)&#160;\u00bb. Le mouvement communaliste n\u2019\u00e9chappe pas au fait colonial. Il le fait d\u2019autant moins que la mobilisation r\u00e9publicaine des villes alg\u00e9riennes, tr\u00e8s \u00ab&#160;coloniste&#160;\u00bb, acc\u00e9l\u00e8re parall\u00e8lement le d\u00e9veloppement d\u2019une des plus importantes r\u00e9voltes alg\u00e9riennes du si\u00e8cle, l\u2019insurrection kabyle, qui rassembla jusqu\u2019\u00e0 800 000 hommes. La r\u00e9volte communale est ainsi li\u00e9e par effet de domino aux contestations des colonis\u00e9s. En d\u2019autres endroits de la plan\u00e8te d\u2019ailleurs, la nouvelle du d\u00e9clenchement de la Commune est utilis\u00e9e par les populations pour contester une domination fran\u00e7aise d\u00e9j\u00e0 fragilis\u00e9e par la guerre. La dynamique historique europ\u00e9enne se voit confront\u00e9e \u00e0 d\u2019autres dynamiques, extra-europ\u00e9ennes. L\u2019information alimente des troubles, suscite espoir ou inqui\u00e9tude parmi les autres puissances, au point que la r\u00e9solution de l\u2019\u00e9v\u00e8nement parisien devient aussi un enjeu g\u00e9opolitique extra-europ\u00e9en.<\/p>\n\n\n\n<p>Car la Commune ne passe pas inaper\u00e7ue. D\u00e8s mars 1871, c\u2019est le dernier point, la r\u00e9volte parisienne est sans doute l\u2019un des \u00e9v\u00e8nements les plus m\u00e9diatis\u00e9s de l\u2019\u00e9poque. Qu\u2019une nouvelle r\u00e9volution et guerre civile ait lieu \u00e0 Paris, capitale de la modernit\u00e9 et des r\u00e9volutions, et ce apr\u00e8s le conflit franco-prussien ne peut que susciter l\u2019attention. Le d\u00e9but des ann\u00e9es 1870 est de plus marqu\u00e9 par de profondes transformations m\u00e9diatiques&#160;: les flux d\u2019informations sont facilit\u00e9s par le d\u00e9veloppement des bateaux \u00e0 vapeur, et plus encore par la mise en place en 1866 du c\u00e2ble atlantique qui leur permet de passer d\u2019un continent \u00e0 l\u2019autre en quelques heures et non en plusieurs jours. De grandes agences de presse comme Reuters, Wolff, Havas, compilent, \u00e9changent et font circuler les nouvelles. L\u2019examen des t\u00e9l\u00e9grammes Reuters montre que sur l\u2019ensemble des informations qui circulent sur le r\u00e9seau \u00e0 propos de la semaine du 18 mars 1871, l\u2019\u00e9crasante majorit\u00e9 concerne l\u2019insurrection parisienne &#8211; alors que de nombreux \u00ab&#160;faits&#160;\u00bb signifiants se d\u00e9roulent bien entendu \u00e0 l\u2019\u00e9chelle de la plan\u00e8te. Objet d\u2019un incessant flux de mots, la Commune est suivie par les journaux europ\u00e9ens, dans toute l\u2019aire d\u2019influence britannique (Canada, Inde, Australie), et dans tout l\u2019espace atlantique (Br\u00e9sil, Mexique, \u00c9tats-Unis). Les attentions r\u00e9gionales certes varient. Mais elles peuvent \u00eatre tr\u00e8s soutenues, comme au Mexique o\u00f9 le devenir parisien est suivi au jour le jour par l\u2019ensemble de la presse ou aux \u00c9tats-Unis o\u00f9 selon l\u2019historien Samuel Bernstein \u00ab&#160;aucun th\u00e8me \u00e9conomique ou politique [\u2026] \u00e0 l\u2019exception de la corruption gouvernementale, n\u2019a re\u00e7u plus de gros titres dans la presse am\u00e9ricaine des ann\u00e9es 1870 que la Commune de Paris&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-103225' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#easy-footnote-bottom-5-103225' title='Samuel Bernstein, \u00ab&amp;#160;The Impact of the Paris Commune in the United States&amp;#160;\u00bb&lt;em&gt;, The Massachusetts Review&lt;\/em&gt;, Vol. 12, No. 3 (Summer, 1971), 436, p.60.'><sup>5<\/sup><\/a><\/span><\/span>&#160;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La Commune est arrim\u00e9e aux luttes sociales et politiques des ann\u00e9es 1850-1870.<\/p><cite>Quentin Deluermoz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La Commune g\u00e9n\u00e8re donc une constellation de r\u00e9sonances et contre-r\u00e9sonances \u00e0 grande \u00e9chelle dont les acteurs et actrices parisiens ont partiellement conscience et qui joue en retour dans la repr\u00e9sentation de leur action. Sa fin sanglante, marqu\u00e9e par les incendies de la ville, l\u2019assassinat des otages et le massacre terrible des insurg\u00e9s provoque une torsion &#8211; et comme souvent pour des \u00e9v\u00e8nements marquants, une red\u00e9finition <em>a posteriori<\/em>. Juste apr\u00e8s les faits, les r\u00e9actions sont majoritairement de rejet. La condamnation diplomatique est unanime, en Grande-Bretagne ou encore au Br\u00e9sil, o\u00f9 la chambre affirme son \u00ab&#160;sentiment d\u2019horreur que lui inspire l\u2019anarchie qui a r\u00e9ussi la d\u00e9truire la plus belle partie de la grande capitale de Paris [. Elle] se f\u00e9licite de la victoire de la cause de la civilisation et des principes du christianisme&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-103225' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#easy-footnote-bottom-6-103225' title='CAD, CP, Br\u00e9sil, courrier du 2 juillet'><sup>6<\/sup><\/a><\/span><\/span>&#160;\u00bb. Un sentiment sur lequel s\u2019appuient les autorit\u00e9s fran\u00e7aises pour se poser en rempart contre les menaces r\u00e9volutionnaires nouvelles qui semblent se profiler. M\u00eame r\u00e9probation au sein de la presse, o\u00f9 le volant des appr\u00e9ciations se simplifie apr\u00e8s la semaine sanglante, jusque dans certains titres radicaux ou socialiste qui ne veulent pas \u00eatre associ\u00e9s \u00e0 cette image de violence.&nbsp; \u00ab&#160;Ce n\u2019est pas le fusil seulement qu\u2019ils manient, tonne <em>l\u2019Ind\u00e9pendance belge,<\/em> c\u2019est la torche incendiaire.&#160;\u00bb Les terribles p\u00e9troleuses, et avec elles tout un cort\u00e8ge de criminels, de fous, de d\u00e9g\u00e9n\u00e9r\u00e9s et autre \u00ab&#160;rouges&#160;\u00bb hantent les portraits de l\u2019insurrection. \u00c0 peine termin\u00e9e, un certain nombre d\u2019id\u00e9es types lui sont alors durablement accol\u00e9es, comme la violence ou l\u2019id\u00e9e d\u2019un mouvement qui serait dirig\u00e9 par l\u2019Association internationale des travailleurs, une id\u00e9e qui sera reprise ensuite selon une toute autre orientation (non celle du complot mais celle de l\u2019avant-garde), par la lecture marxiste-l\u00e9niniste.<\/p>\n\n\n\n<p>Mais la Commune devient en m\u00eame temps, et sans doute est-ce li\u00e9 \u00e0 cette audience, l\u2019incarnation du martyr des luttes sociales et un haut lieu de m\u00e9moire r\u00e9volutionnaire. Les lectures les plus connues, et les plus marquantes, sont celles de K. Marx et de M. Bakounine. Le premier fait para\u00eetre d\u00e8s juin 1871, au nom de l\u2019AIT, <em>La guerre civile en France<\/em>, dont circulent rapidement des versions en anglais, allemand, fran\u00e7ais et espagnol. Le second propose une interpr\u00e9tation anarchiste qui voit dans la r\u00e9volte parisienne \u00ab&#160;la n\u00e9gation audacieuse, bien prononc\u00e9e de l\u2019\u00c9tat&#160;\u00bb. Les historiens ont point\u00e9 de longue date les apparentes incongruit\u00e9s de ces textes (Marx d\u00e9fendant une forme de f\u00e9d\u00e9ralisme r\u00e9publicain, Bakounine les jacobins). Cependant les analyses s\u2019ajustent vite et dessinent deux lectures&#160;: <em>grosso modo<\/em>, les marxistes inscrivent la Commune dans une lign\u00e9e de r\u00e9volutions, comme une \u00e9tape dont la le\u00e7on doit \u00eatre tir\u00e9e, tandis que les anarchistes la situent davantage dans une constante lutte des exploit\u00e9s contre les exploiteurs, suivant une conception plus germinale de la r\u00e9volution. Ensemble, ils s\u00e9dimentent en tous cas l\u2019id\u00e9e d\u2019une Commune qui serait un temps fort de la lutte des classes, une autre id\u00e9e appel\u00e9e \u00e0 durer qui se solidifie peu \u00e0 peu au sein des nouvelles organisations politiques et syndicales.<\/p>\n\n\n\n<p>Mais ce ne sont pas l\u00e0 les seules lectures et appropriations. Les ann\u00e9es 1860 sont en effet marqu\u00e9es par ce que les historiens appellent un \u00ab&#160;radicalisme global&#160;\u00bb, fait de f\u00e9d\u00e9ralisme, de r\u00e9publicanisme, d\u2019associationnisme, de socialisme, ainsi que de multiples combats socio-politiques. La r\u00e9f\u00e9rence \u00e0 la Commune est ainsi reprise lors de la r\u00e9volution cantonale espagnole de 1873&#160;: elle contribue, avec d\u2019autres morceaux de pass\u00e9s comme la r\u00e9volution de 1868, \u00e0 rendre vivant l\u2019esprit f\u00e9d\u00e9raliste espagnol. Il en est de m\u00eame des r\u00e9appropriations italiennes&#160;: la chute de la Commune alimente une hausse du nombre d\u2019adh\u00e9rent de l\u2019AIT et tout un courant de socialisme libertaire. Puis la r\u00e9f\u00e9rence circule \u00e0 plus grande \u00e9chelle, suivant le flux des exil\u00e9s parisiens, celui de ces combattants ou des informations. En Argentine, au Br\u00e9sil, au Chili, en Bolivie se cr\u00e9ent ainsi dans les ann\u00e9es 1870 des journaux appel\u00e9 <em>el Comuna. <\/em>Le lien \u00e0 l\u2019aventure parisienne est explicite&#160;: \u00ab&#160;aussi longtemps qu\u2019il y aura un homme ou une femme vivante, explique <em>El Comuna mexicana<\/em>, la Commune continuera \u00e0 exister, parce que les grands principes sont immortels (\u2026). La Commune est vivante en France comme au Mexique, aux \u00c9tats-Unis comme en Allemagne, en Chine ou en Arabie&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-103225' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#easy-footnote-bottom-7-103225' title='&lt;em&gt;El Comuna&lt;\/em&gt;, 28 juin 1874, &lt;em&gt;cit in&lt;\/em&gt; B. Bosteels, \u00ab&amp;#160;The Mexican Commune&amp;#160;\u00bb, &lt;em&gt;op.cit.&lt;\/em&gt;'><sup>7<\/sup><\/a><\/span><\/span>.&#160;\u00bb Aux \u00c9tats-Unis, d\u2019autres appropriations sont observable au sein de la culture radicale naissante des ann\u00e9es 1870. \u00c0 chaque fois, la r\u00e9f\u00e9rence \u00e0 la Commune de Paris apporte ainsi un surcro\u00eet de force et d\u2019internationalit\u00e9 aux luttes en cours, tandis que ces usages l\u2019ins\u00e8rent progressivement dans l\u2019histoire domestique. S\u2019observe ainsi, en m\u00eame temps que l\u2019\u00e9v\u00e8nement lui-m\u00eame, une sorte de co-construction de l\u2019id\u00e9e communale, qui en \u00e9largit la port\u00e9e et l\u2019enjeu.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ensemble, Marx et Bakounine s\u00e9dimentent l\u2019id\u00e9e d\u2019une Commune qui serait un temps fort de la lutte des classes, une autre id\u00e9e appel\u00e9e \u00e0 durer qui se solidifie peu \u00e0 peu au sein des nouvelles organisations politiques et syndicales.<\/p><cite>Quentin Deluermoz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Encore une fois, l\u2019arrachement propre au mouvement r\u00e9volutionnaire parisien, multiforme, h\u00e9t\u00e9rog\u00e8ne, inachev\u00e9, ne saurait \u00eatre n\u00e9glig\u00e9. Et l\u2019enjeu du livre consiste \u00e0 croiser ces niveaux d\u2019analyse. Mais parce qu\u2019elle a lieu \u00e0 Paris, dans la seconde puissance imp\u00e9riale du temps, dans un pays porteur d\u2019un fort imaginaire en mati\u00e8re de culture et de r\u00e9volution, la Commune ne pouvait non plus \u00eatre uniquement parisienne. Pour p\u00e9n\u00e9trer l\u2019\u00e9cheveau complexe des interrelations et des significations du temps, il faut ainsi abandonner les lectures en terme de diffusion, et se pencher sur les liens complexes entre ces diff\u00e9rentes sc\u00e8nes. Au final, la lutte parisienne aboutit \u00e0 la construction, dans Paris et hors de Paris, d\u2019une nouvelle cat\u00e9gorie historique, la \u00ab&#160;Commune&#160;\u00bb. C\u2019est l\u00e0 une trace de la cr\u00e9ativit\u00e9 dont les mouvements r\u00e9volutionnaires peuvent \u00eatre porteurs. Par la suite, l\u2019interpr\u00e9tation marxiste de la fin du si\u00e8cle et les relectures d\u2019Engels puis de L\u00e9nine introduisent ensuite, on le sait, une autre torsion dans la m\u00e9moire et la d\u00e9finition de la Commune. Elle va porter la r\u00e9f\u00e9rence sur d\u2019autres espaces, notamment asiatiques et africains, selon des usages toujours aussi vari\u00e9s. L\u2019id\u00e9e communale se charge de plus de sens, tant\u00f4t convergents, tant\u00f4t conflictuels, mouvants, resurgissants. Une fascinante travers\u00e9e des temps qui m\u00e8ne jusqu\u2019\u00e0 aujourd\u2019hui, o\u00f9 elle refait surface, ce n\u2019est sans doute pas un hasard, dans des pays aussi divers que la France, l\u2019Espagne, le Mexique ou les \u00c9tats-Unis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soul\u00e8vement parisien ou R\u00e9publique universelle&#160;&#160;? Que peut-on encore dire des \u00e9chelles de la Commune, \u00e9v\u00e9nement local hors du commun et pourtant imm\u00e9diatement discut\u00e9 et comment\u00e9 dans le monde entier&#160;&#160;? En ce jour anniversaire du d\u00e9but de l&rsquo;insurrection, qui aboutira dix jours plus tard \u00e0 la proclamation de la Commune de Paris, Quentin Deluermoz nous invite \u00e0 r\u00e9inscrire ces 72 jours dans une \u00ab&#160;&#160;fascinante travers\u00e9e des temps&#160;&#160;\u00bb \u2013 de 1871 \u00e0 aujourd&rsquo;hui.<\/p>\n","protected":false},"author":10,"featured_media":103231,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":16,"footnotes":""},"categories":[2024],"tags":[],"staff":[2867],"editorial_format":[4944],"serie":[],"audience":[],"geo":[2163],"class_list":["post-103225","post","type-post","status-publish","format-standard","hentry","category-histoire","staff-quentin-deluermoz","editorial_format-actu-longues","geo-monde"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":103231,"excerpt":"Soul\u00e8vement parisien ou R\u00e9publique universelle ? Que peut-on encore dire des \u00e9chelles de la Commune, \u00e9v\u00e9nement local hors du commun et pourtant imm\u00e9diatement discut\u00e9 et comment\u00e9 dans le monde entier ? En ce jour anniversaire du d\u00e9but de l'insurrection, qui aboutira dix jours plus tard \u00e0 la proclamation de la Commune de Paris, Quentin Deluermoz nous invite \u00e0 r\u00e9inscrire ces 72 jours dans une \u00ab fascinante travers\u00e9e des temps \u00bb \u2013 de 1871 \u00e0 aujourd'hui.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Commune de Paris, 1871 : \u00e9v\u00e9nement local, \u00e9v\u00e9nement global | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Commune de Paris, 1871 : \u00e9v\u00e9nement local, \u00e9v\u00e9nement global | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Soul\u00e8vement parisien ou R\u00e9publique universelle&#160;? Que peut-on encore dire des \u00e9chelles de la Commune, \u00e9v\u00e9nement local hors du commun et pourtant imm\u00e9diatement discut\u00e9 et comment\u00e9 dans le monde entier&#160;? En ce jour anniversaire du d\u00e9but de l&#039;insurrection, qui aboutira dix jours plus tard \u00e0 la proclamation de la Commune de Paris, Quentin Deluermoz nous invite \u00e0 r\u00e9inscrire ces 72 jours dans une \u00ab&#160;fascinante travers\u00e9e des temps&#160;\u00bb \u2013 de 1871 \u00e0 aujourd&#039;hui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-18T08:01:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-20T18:05:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-commune-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-commune-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/\",\"name\":\"La Commune de Paris, 1871 : \u00e9v\u00e9nement local, \u00e9v\u00e9nement global | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg\",\"datePublished\":\"2021-03-18T08:01:38+00:00\",\"dateModified\":\"2021-03-20T18:05:30+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg\",\"width\":1200,\"height\":815},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Commune de Paris, 1871&#160;: \u00e9v\u00e9nement local, \u00e9v\u00e9nement global\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Commune de Paris, 1871 : \u00e9v\u00e9nement local, \u00e9v\u00e9nement global | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/","og_locale":"fr_FR","og_type":"article","og_title":"La Commune de Paris, 1871 : \u00e9v\u00e9nement local, \u00e9v\u00e9nement global | Le Grand Continent","og_description":"Soul\u00e8vement parisien ou R\u00e9publique universelle&#160;? Que peut-on encore dire des \u00e9chelles de la Commune, \u00e9v\u00e9nement local hors du commun et pourtant imm\u00e9diatement discut\u00e9 et comment\u00e9 dans le monde entier&#160;? En ce jour anniversaire du d\u00e9but de l'insurrection, qui aboutira dix jours plus tard \u00e0 la proclamation de la Commune de Paris, Quentin Deluermoz nous invite \u00e0 r\u00e9inscrire ces 72 jours dans une \u00ab&#160;fascinante travers\u00e9e des temps&#160;\u00bb \u2013 de 1871 \u00e0 aujourd'hui.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/","og_site_name":"Le Grand Continent","article_published_time":"2021-03-18T08:01:38+00:00","article_modified_time":"2021-03-20T18:05:30+00:00","og_image":[{"width":2560,"height":1436,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-commune-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/gc-commune-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/","url":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/","name":"La Commune de Paris, 1871 : \u00e9v\u00e9nement local, \u00e9v\u00e9nement global | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg","datePublished":"2021-03-18T08:01:38+00:00","dateModified":"2021-03-20T18:05:30+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg","width":1200,"height":815},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2021\/03\/18\/la-commune-de-paris-1871\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"La Commune de Paris, 1871&#160;: \u00e9v\u00e9nement local, \u00e9v\u00e9nement global"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":2024,"name":"Histoire","slug":"histoire"}],"lgc_author":{"id":2867,"name":"Quentin Deluermoz","slug":"quentin-deluermoz","description":"Historien, Universit\u00e9 de Paris","first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg","width":1200,"height":815,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2021\/03\/standard_compressed_Barricade_Voltaire_Lenoir_Commune_Paris_1871.jpg","width":1200,"height":815,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/103225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=103225"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/103225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/103231"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=103225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=103225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=103225"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=103225"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=103225"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=103225"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=103225"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=103225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}