{"id":10299,"date":"2018-11-25T22:00:17","date_gmt":"2018-11-25T21:00:17","guid":{"rendered":"https:\/\/lldl.eu\/?p=10299"},"modified":"2019-09-21T23:22:54","modified_gmt":"2019-09-21T21:22:54","slug":"quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/","title":{"rendered":"Forces et faiblesses de l&rsquo;expansion turque en Afrique"},"content":{"rendered":"\n<p><em>Ankara<\/em>. En d\u00e9cembre 2017, le Soudan annon\u00e7ait qu\u2019il c\u00e9dait pour 99 ans \u00e0 la Turquie la quasi-totalit\u00e9 de la ville portuaire de Suakin, sur la Mer rouge, ancienne porte d\u2019entr\u00e9e sur l\u2019Afrique de l\u2019Est pendant la p\u00e9riode ottomane. En f\u00e9vrier, Recep Tayyip Erdo\u011fan visitait la C\u00f4te d\u2019Ivoire, le Ghana, le Nig\u00e9ria et la Guin\u00e9e. En octobre, Istanbul accueillait le second Forum \u00e9conomique et commercial turco-africain, auxquels 43 pays africains participaient. Enfin, au d\u00e9but du mois de novembre, le pr\u00e9sident du Conseil pr\u00e9sidentiel libyen, Fayez Sarraj, \u00e9tait \u00e0 Istanbul pour discuter de la participation turque dans la reconstruction du pays, et pour la signature d\u2019un accord de sant\u00e9 entre les deux \u00c9tats (<strong>1<\/strong>).<\/p>\n\n\n\n<p>Derri\u00e8re ces faits, se dessinent les r\u00e9sultats d\u2019une strat\u00e9gie turque datant de 1998, lorsque sous la pr\u00e9sidence Demirel, le gouvernement lan\u00e7a le \u00ab&#160;Plan d\u2019Action pour l\u2019Afrique&#160;\u00bb, destin\u00e9 \u00e0 augmenter le nombre d\u2019ambassades sur le continent, \u00e0 am\u00e9liorer les consultations politiques avec les pays sub-sahariens et celles avec les organisations internationales, et \u00e0 promouvoir une aide humanitaire turque en Afrique (<strong>2<\/strong>). Si les premi\u00e8res ann\u00e9es de mise en place de ce plan ont \u00e9t\u00e9 tr\u00e8s compliqu\u00e9es, notamment du fait de la crise \u00e9conomique de 2000-2001, l\u2019AKP s\u2019est empar\u00e9 du sujet pour le relancer de plus belle, d\u00e9clarant l\u2019ann\u00e9e 2005 comme l\u2019ann\u00e9e de l\u2019Afrique, multipliant les sommets \u00e9conomiques ou politiques, jusqu\u2019\u00e0 \u00eatre nomm\u00e9 en 2008 \u00ab&#160;partenaire strat\u00e9gique&#160;\u00bb par l\u2019Union Africaine.<\/p>\n\n\n\n<p>D\u2019un point de vue \u00e9conomique, la strat\u00e9gie turque peut \u00eatre consid\u00e9r\u00e9e comme r\u00e9ussie. Depuis 2003, les volumes d\u2019\u00e9changes bilat\u00e9raux entre la Turquie et les pays africains ont quadrupl\u00e9s, passant de cinq milliards de dollars d\u2019\u00e9changes \u00e0 pr\u00e8s de 20 en 2017 (<strong>3<\/strong>). L\u2019approche turque dans le d\u00e9veloppement des nations africaines, qui se concentre sur des domaines \u00e0 faible valeur \u00e9conomique ajout\u00e9e, comme l\u2019agriculture, semble avoir conquis les dirigeants africains. Les autorit\u00e9s turques peuvent ainsi se targuer d\u2019aider efficacement les populations locales, au contraire d\u2019autres nations ne cherchant qu\u2019\u00e0 exploiter les ressources mini\u00e8res (<strong>4<\/strong>).<\/p>\n\n\n\n<p>La strat\u00e9gie turque s\u2019est aussi concentr\u00e9e sur les domaines humanitaires et \u00e9ducatifs. En Somalie, alors que la Turkish Airlines fut la premi\u00e8re compagnie \u00e0 ouvrir une connexion directe avec Mogadiscio, le gouvernement turc envoie r\u00e9guli\u00e8rement des tonnes d\u2019aides alimentaires, tandis que les compagnies du BTP proches du pouvoir d\u2019Ankara se sont vu confier la r\u00e9alisation d\u2019h\u00f4pitaux et d\u00e9sormais d\u2019a\u00e9roports (<strong>5<\/strong>). En mati\u00e8re \u00e9ducative, le mouvement Hizmet, dirig\u00e9 par le religieux Fethullah G\u00fclen, a jou\u00e9 un r\u00f4le important dans l&rsquo;introduction et la promotion de la Turquie en Afrique australe et subsaharienne. Hizmet a \u00e9tabli des centaines d&rsquo;\u00e9coles, de centres culturels et d&rsquo;installations religieuses qui ont fait leurs preuves, et a \u00e9tabli des relations solides avec les \u00e9lites \u00e9conomiques et politiques locales.<\/p>\n\n\n\n<p>Alors que le mouvement \u00e9tait devenu le visage de la Turquie dans de nombreux pays africains, la crise ouverte entre Erdo\u011fan et G\u00fclen apr\u00e8s la tentative de coup d\u2019\u00c9tat en juillet 2016, pose la question du futur de la coop\u00e9ration turco-africaine. En Afrique subsaharienne, l&rsquo;AKP cherche d\u00e9sormais \u00e0 supplanter la pr\u00e9sence de Hizmet et \u00e0 r\u00e9introduire la Turquie du point de vue gouvernemental. Mais avec son statut de \u00ab&#160;nouvel arrivant&#160;\u00bb, Ankara fait face \u00e0 une concurrence accrue, surtout qu\u2019elle ne dispose pas des cr\u00e9dits dont peut disposer la Chine ou encore la Russie, deux autres \u00ab&#160;nouveaux arrivants&#160;\u00bb.<\/p>\n\n\n\n<p>Plus encore, alors que l\u2019opposition entre Turquie et Arabie Saoudite a atteint depuis 2017 son paroxysme, chaque camp fourbit ses armes dans la corne de l\u2019Afrique, essayant de conforter ses positions. Alors que les Turcs \u00e9difiaient une base militaire \u00e0 Mogadiscio, partout sur la c\u00f4te africaine les \u00c9miratis d\u00e9veloppaient leurs relations, se faisant confier les travaux de r\u00e9fection du port de Berbera au Somaliland, et signant un accord avec les autorit\u00e9s de Puntland. En Erythr\u00e9e, sous l\u2019influence des \u00c9miratis, les \u00c9gyptiens d\u00e9ployaient des troupes en r\u00e9action \u00e0 la cession du port de Suakin aux Turcs (<strong>6<\/strong>). Dans le reste du continent, la rupture des relations entre l\u2019Arabie Saoudite et le Qatar poussaient la Mauritanie, le Niger, le Tchad et le S\u00e9n\u00e9gal \u00e0 faire de m\u00eame&#160;; tandis qu\u2019au contraire, la Sierra Leone et le Ghana choisissaient le camp oppos\u00e9.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Perspectives&#160;:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>La strat\u00e9gie de d\u00e9veloppement turque en Afrique est d\u00e9sormais fragilis\u00e9e par l\u2019influence de l\u2019Arabie Saoudite, de l\u2019\u00c9gypte et de leurs alli\u00e9s. Si la \u00ab&#160;diplomatie humanitaire&#160;\u00bb turque a permis au pays de gagner un capital sympathie, les \u00c9miratis ont, directement ou indirectement, construit \u00e0 l\u2019\u00e9chelle du continent une opposition politique contre le r\u00e9gime qatari.<\/li><li>Avec la cession du port de Suakin, la Turquie a obtenu d\u2019une part l\u2019acc\u00e8s \u00e0 la mer Rouge, et donc aux march\u00e9s asiatiques, en contournant l\u2019obstacle du canal de Suez&#160;; mais \u00e9galement un point d\u2019acc\u00e8s ind\u00e9pendant pour les p\u00e8lerins turcs en route pour le Hajj.<\/li><li>D\u00e9sormais, la question est de savoir si la Turquie pourra tirer son \u00e9pingle du jeu face au durcissement de ses relations avec les pays du Golfe, et face \u00e0 la Chine, qui a investi massivement sur toute la c\u00f4te Est.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sources<\/strong>&#160;:\n\n<\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li>ALHARATHY Safa,<a href=\"https:\/\/www.libyaobserver.ly\/inbrief\/libya-and-turkey-sign-cooperation-agreement-health-sector\"> Libya and Turkey sign cooperation agreement in health sector<\/a>, The Libya Observer, 11 novembre 2018.<\/li><li>Zuhal Demirci and Fatih Hafiz Mehmet,<a href=\"https:\/\/www.aa.com.tr\/en\/africa\/turkey-in-intense-cooperation-with-africa-\/1059565\"> Turkey in intense cooperation with Africa<\/a>, Anadolu Ajansi, 2 f\u00e9vrier 2018.<\/li><li>BACCHI Eleonora,<a href=\"https:\/\/ovipot.hypotheses.org\/13639\"> A timeline of the Turkish Africa policy<\/a>, OVIPOT, 28 juillet 2015.<\/li><li><a href=\"https:\/\/www.dw.com\/en\/turkeys-erdogan-seeks-more-influence-in-africa\/a-42788010\">Turkey&rsquo;s Erdogan seeks more influence in Africa<\/a>, Deutsche Welle, 2 mars 2018.<\/li><li>\u00d6ZKHAN Mehmet,<a href=\"http:\/\/turkishpolicy.com\/Files\/ArticlePDF\/turkeys-rising-role-in-africa-winter-2010-en.pdf\"> Turkey \u0301s rising role in Africa<\/a>, Turkish Policy Quarterly, volume 9, num\u00e9ro. 4.<\/li><li>PRUNIER G\u00e9rard, <a href=\"https:\/\/orientxxi.info\/magazine\/comment-les-divergences-dans-le-golfe-sont-exportees-en-afrique,2765\">Les pays du Golfe et la Turquie s\u2019affrontent en Afrique<\/a>, Orient XXI, 22 novembre 2018.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le d\u00e9but des ann\u00e9es 2000, la politique \u00e9trang\u00e8re turque a fait de l\u2019Afrique une des priorit\u00e9s de sa strat\u00e9gie d\u2019influence. De la Libye \u00e0 la Somalie, le pays avance ses pions et ouvre un nouveau front dans le conflit qui l\u2019oppose aux pays du Golfe.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[1674],"editorial_format":[4942],"serie":[],"audience":[],"geo":[522,543],"class_list":["post-10299","post","type-post","status-publish","format-standard","hentry","category-politique","staff-matthieu-caillaud","editorial_format-actu-breves","geo-afriques-subsahariennes","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Depuis le d\u00e9but des ann\u00e9es 2000, la politique \u00e9trang\u00e8re turque a fait de l\u2019Afrique une des priorit\u00e9s de sa strat\u00e9gie d\u2019influence. De la Libye \u00e0 la Somalie, le pays avance ses pions et ouvre un nouveau front dans le conflit qui l\u2019oppose aux pays du Golfe.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Forces et faiblesses de l&#039;expansion turque en Afrique | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forces et faiblesses de l&#039;expansion turque en Afrique | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Depuis le d\u00e9but des ann\u00e9es 2000, la politique \u00e9trang\u00e8re turque a fait de l\u2019Afrique une des priorit\u00e9s de sa strat\u00e9gie d\u2019influence. De la Libye \u00e0 la Somalie, le pays avance ses pions et ouvre un nouveau front dans le conflit qui l\u2019oppose aux pays du Golfe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-25T21:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-21T21:22:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/\",\"name\":\"Forces et faiblesses de l'expansion turque en Afrique | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2018-11-25T21:00:17+00:00\",\"dateModified\":\"2019-09-21T21:22:54+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forces et faiblesses de l&rsquo;expansion turque en Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Forces et faiblesses de l'expansion turque en Afrique | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Forces et faiblesses de l'expansion turque en Afrique | Le Grand Continent","og_description":"Depuis le d\u00e9but des ann\u00e9es 2000, la politique \u00e9trang\u00e8re turque a fait de l\u2019Afrique une des priorit\u00e9s de sa strat\u00e9gie d\u2019influence. De la Libye \u00e0 la Somalie, le pays avance ses pions et ouvre un nouveau front dans le conflit qui l\u2019oppose aux pays du Golfe.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/","og_site_name":"Le Grand Continent","article_published_time":"2018-11-25T21:00:17+00:00","article_modified_time":"2019-09-21T21:22:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/","url":"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/","name":"Forces et faiblesses de l'expansion turque en Afrique | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2018-11-25T21:00:17+00:00","dateModified":"2019-09-21T21:22:54+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/25\/quel-avenir-pour-la-politique-etrangere-de-la-turquie-en-afrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Forces et faiblesses de l&rsquo;expansion turque en Afrique"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":""}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1674,"name":"Matthieu Caillaud","slug":"matthieu-caillaud","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/10299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=10299"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/10299\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=10299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=10299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=10299"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=10299"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=10299"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=10299"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=10299"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=10299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}