{"id":776,"count":1,"description":"Periodista espa\u00f1ol, autor de <em>Espa\u00f1a: el pacto y la furia<\/em> (Arpa, 2024). ","link":"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/","name":"Enric Juliana","slug":"enric-juliana","taxonomy":"staff","meta":[],"acf":{"name_title":"","first_name":"Enric","last_name":"Juliana","key_figure_template":"","cardinal_type":[],"picture":30914,"job_role":"Director adjunto de La Vanguardia","lgc_editorial_staff":false,"full_description":"","side_image":null,"side_text_1":"","side_text_2":"","page_content":"","linkedin_url":"","twitter_url":"","articles_authored":null,"articles_interviewed":null,"articles_speech_author":null,"books_authored":null,"events_authored":null,"videos_authored":null,"posts_related":null,"events_related":null,"elections_related":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enric Juliana - archivos - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enric Juliana - archivos - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Periodista espa\u00f1ol, autor de Espa\u00f1a: el pacto y la furia (Arpa, 2024).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/\",\"name\":\"Enric Juliana - archivos - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enric Juliana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enric Juliana - archivos - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/","og_locale":"es_ES","og_type":"article","og_title":"Enric Juliana - archivos - El Grand Continent","og_description":"Periodista espa\u00f1ol, autor de Espa\u00f1a: el pacto y la furia (Arpa, 2024).","og_url":"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/","og_site_name":"El Grand Continent","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/","url":"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/","name":"Enric Juliana - archivos - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/p\/enric-juliana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Enric Juliana"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"first_name":"Enric","last_name":"Juliana","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/03\/unnamed.jpeg","width":389,"height":371,"alt":""},"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff\/776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/taxonomies\/staff"}],"wp:post_type":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts?staff=776"},{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/sunday?staff=776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}